{"id":232,"count":4,"description":"salute-neurologi","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/","name":"Neurologi","slug":"neurologi","taxonomy":"product_cat","parent":163,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Neurologi Archivi - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neurologi Archivi - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"salute-neurologi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/\",\"name\":\"Neurologi Archivi - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salute\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Neurologi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neurologi Archivi - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/","og_locale":"it_IT","og_type":"article","og_title":"Neurologi Archivi - UIL Polizia","og_description":"salute-neurologi","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/","og_site_name":"UIL Polizia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/","name":"Neurologi Archivi - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/neurologi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Salute","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/categorie\/salute\/"},{"@type":"ListItem","position":3,"name":"Neurologi"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat\/163"}],"wp:post_type":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product?product_cat=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}