{"id":98400,"date":"2026-05-08T18:03:25","date_gmt":"2026-05-08T16:03:25","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=98400"},"modified":"2026-05-11T15:36:23","modified_gmt":"2026-05-11T13:36:23","slug":"hotel-gangi","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/","title":{"rendered":"Hotel Gangi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"98400\" class=\"elementor elementor-98400\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f97c7a e-flex e-con-boxed e-con e-parent\" data-id=\"8f97c7a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3381c77 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3381c77\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dd5f93 elementor-widget elementor-widget-image\" data-id=\"8dd5f93\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"259\" height=\"36\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-Hotel-Gangi.png\" class=\"attachment-large size-large wp-image-98403\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-300a3a9 e-flex e-con-boxed e-con e-parent\" data-id=\"300a3a9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad3039d e-con-full e-flex e-con e-child\" data-id=\"ad3039d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5e79f7b e-con-full e-flex e-con e-child\" data-id=\"5e79f7b\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f89f714 e-con-full e-flex e-con e-child\" data-id=\"f89f714\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29cb7ad elementor-widget elementor-widget-heading\" data-id=\"29cb7ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">HOTEL A PIAZZA ARMERINA\n\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5973b16 elementor-widget elementor-widget-text-editor\" data-id=\"5973b16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 1955, Hotel Gangi rappresenta un\u2019icona di ospitalit\u00e0 nel cuore di Piazza Armerina.\u00a0<\/p><p>La struttura, completamente ristrutturata, \u00e8 la scelta ideale per viaggi d\u2019affari e soggiorni di piacere grazie alla sua posizione centrale e strategica.\u00a0<\/p><p>L\u2019hotel riflette una tradizione familiare che ha radici profonde: iniziata negli anni \u201950, quando Piazza Armerina divenne una meta turistica di riferimento grazie alla scoperta della Villa Romana del Casale e alle prime edizioni del suggestivo Palio dei Normanni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0541f5c e-con-full e-flex e-con e-child\" data-id=\"0541f5c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:&quot;98417&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/doppia-standard-03hotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98418&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/img1hotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98407&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/singola-04hotel-gangi.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50d7ad5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"50d7ad5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94b484b e-con-full e-flex e-con e-child\" data-id=\"94b484b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dcfef55 e-con-full e-flex e-con e-child\" data-id=\"dcfef55\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-17269fe e-con-full e-flex e-con e-child\" data-id=\"17269fe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5773f elementor-widget elementor-widget-text-editor\" data-id=\"3f5773f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gli ospiti possono gustare una ricchissima colazione a buffet servita in un\u2019accogliente saletta. La proposta spazia da croissant, pane e affettati a marmellate, miele, frutta fresca, yogurt e dolci artigianali come torte e crostate. Non mancano caff\u00e8, cappuccino o t\u00e8 caldo.<\/p><p>L\u2019hotel offre inoltre connessione Wi-Fi gratuita in tutta la struttura, ascensore e bar per garantire un soggiorno completo e confortevole.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69c7127 e-con-full e-flex e-con e-child\" data-id=\"69c7127\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-75a22bd e-con-full e-flex e-con e-child\" data-id=\"75a22bd\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3cd071d e-con-full e-flex e-con e-child\" data-id=\"3cd071d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18e9796 elementor-widget elementor-widget-heading\" data-id=\"18e9796\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Le camere:<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a55cd39 elementor-widget elementor-widget-text-editor\" data-id=\"a55cd39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019Hotel Gangi dispone di 15 camere recentemente rinnovate, tra cui una progettata per accogliere persone con disabilit\u00e0.\u00a0<\/p><p>Le opzioni includono Matrimoniale Classic e Superior, Tripla Classic e Singola Standard, con tariffe a partire da \u20ac50 a notte.\u00a0<\/p><p>Tutte le camere sono dotate di comfort moderni: TV satellitare, telefono, frigobar, cassaforte, bagno privato con asciugacapelli e aria climatizzata regolabile.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-889ca9f e-con-full e-flex e-con e-child\" data-id=\"889ca9f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fa172c elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6fa172c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hotelgangi.eu\/#camere\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a3ad1d e-con-full e-flex e-con e-child\" data-id=\"1a3ad1d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:&quot;98439&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/doppia-disabilihotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98440&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/doppia-superior-03hotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98441&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/tripla-classichotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98442&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/singolahotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98443&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/doppia-standardhotel-gangi.jpg&quot;},{&quot;id&quot;:&quot;98444&quot;,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/doppia-disabili-01hotel-gangi.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74db39e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"74db39e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-333419e e-flex e-con-boxed e-con e-parent\" data-id=\"333419e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e90a43c e-con-full e-flex e-con e-child\" data-id=\"e90a43c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-131e05b elementor-widget elementor-widget-text-editor\" data-id=\"131e05b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAgevolazioni riservate agli associati\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7efec7 e-flex e-con-boxed e-con e-parent\" data-id=\"d7efec7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dde042e e-con-full e-flex e-con e-child\" data-id=\"dde042e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f87173e e-con-full e-flex e-con e-child\" data-id=\"f87173e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ea92fb e-con-full e-flex e-con e-child\" data-id=\"3ea92fb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7bfbd elementor-widget elementor-widget-image\" data-id=\"5d7bfbd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"259\" height=\"36\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-Hotel-Gangi.png\" class=\"attachment-large size-large wp-image-98403\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6efd442 e-con-full e-flex e-con e-child\" data-id=\"6efd442\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cdeb7f elementor-widget elementor-widget-text-editor\" data-id=\"2cdeb7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Viale Gen. Ciancio, 68 &#8211; 94015 Piazza Armerina (EN)<br \/>Tel: <a href=\"tel:+390935680333\" target=\"_blank\" rel=\"noopener\">+39 0935 680 333<\/a><br \/>Cell: <a href=\"tel:+393388769097\" target=\"_blank\" rel=\"noopener\">+39 338 876 9097<\/a><br \/>Mail: <a href=\"mailto:hotelgangi@aruba.it\" target=\"_blank\" rel=\"noopener\">hotelgangi@aruba.it<\/a><br \/>Sito: <a href=\"https:\/\/www.hotelgangi.eu\/\" target=\"_blank\" rel=\"noopener\">www.hotelgangi.eu<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb6ba61 e-con-full e-flex e-con e-child\" data-id=\"cb6ba61\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78af576 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"78af576\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/booking.com\/hotel\/it\/gangi-piazza-armerina.it.html\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prenota ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b10c13f e-con-full e-flex e-con e-child\" data-id=\"b10c13f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c8c253 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"9c8c253\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-272\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"98400\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-272\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:500px;\"> <span id=\"gmw-resize-map-toggle-272\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-272\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-272\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"272\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8286b42 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"8286b42\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52ef2dd elementor-widget elementor-widget-text-editor\" data-id=\"52ef2dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDal 1955, Hotel Gangi rappresenta un\u2019icona di ospitalit\u00e0 nel cuore di Piazza Armerina. La struttura, completamente ristrutturata, \u00e8 la scelta ideale per viaggi d\u2019affari e soggiorni di piacere grazie alla sua posizione centrale e strategica. L\u2019hotel riflette una tradizione familiare che ha radici profonde: iniziata negli anni \u201950, quando Piazza Armerina divenne una meta turistica di riferimento grazie alla scoperta della Villa Romana del Casale e alle prime edizioni del suggestivo Palio dei Normanni.\n\nL\u2019Hotel Gangi dispone di 15 camere recentemente rinnovate, tra cui una progettata per accogliere persone con disabilit\u00e0. Le opzioni includono Matrimoniale Classic e Superior, Tripla Classic e Singola Standard, con tariffe a partire da \u20ac50 a notte. Tutte le camere sono dotate di comfort moderni: TV satellitare, telefono, frigobar, cassaforte, bagno privato con asciugacapelli e aria climatizzata regolabile.\n\nGli ospiti possono gustare una ricchissima colazione a buffet servita in un\u2019accogliente saletta. La proposta spazia da croissant, pane e affettati a marmellate, miele, frutta fresca, yogurt e dolci artigianali come torte e crostate. Non mancano caff\u00e8, cappuccino o t\u00e8 caldo.\n\nL\u2019hotel offre inoltre connessione Wi-Fi gratuita in tutta la struttura, ascensore e bar per garantire un soggiorno completo e confortevole.\n\nHotel Gangi, Piazza Armerina, ospitalit\u00e0, soggiorni, viaggi d&#8217;affari, vacanze, posizione centrale, ristrutturato, tradizione familiare, anni &#8217;50, Villa Romana del Casale, Palio dei Normanni, camere rinnovate, disabilit\u00e0, Matrimoniale Classic, Matrimoniale Superior, Tripla Classic, Singola Standard, comfort moderni, TV satellitare, frigobar, cassaforte, bagno privato, aria climatizzata, colazione a buffet, dolci artigianali, Wi-Fi gratuito, ascensore, bar, albergo, alberghi, hotel, albergo con parcheggio, alberghi con parcheggio, hotel con parcheggio, hotel accessibile, albergo accessibile, stanza albergo per disabili, hotel per disabili, camere accessibili per disabili, camere hotel accessibili, camere albergo accessibili per disabili, camera hotel accessibile, camera accessibile per disabili, camera albergo accessibile per disabili, \u00a0Piazza Armerina,\nHotel Gangi Piazza Armerina, Piazza Armerina Piazza Armerina, ospitalit\u00e0 Piazza Armerina, soggiorni Piazza Armerina, viaggi d&#8217;affari Piazza Armerina, vacanze Piazza Armerina, posizione centrale Piazza Armerina, ristrutturato Piazza Armerina, tradizione familiare Piazza Armerina, anni &#8217;50 Piazza Armerina, Villa Romana del Casale Piazza Armerina, Palio dei Normanni Piazza Armerina, camere rinnovate Piazza Armerina, disabilit\u00e0 Piazza Armerina, Matrimoniale Classic Piazza Armerina, Matrimoniale Superior Piazza Armerina, Tripla Classic Piazza Armerina, Singola Standard Piazza Armerina, comfort moderni Piazza Armerina, TV satellitare Piazza Armerina, frigobar Piazza Armerina, cassaforte Piazza Armerina, bagno privato Piazza Armerina, aria climatizzata Piazza Armerina, colazione a buffet Piazza Armerina, dolci artigianali Piazza Armerina, Wi-Fi gratuito Piazza Armerina, ascensore Piazza Armerina, bar Piazza Armerina, albergo Piazza Armerina, alberghi Piazza Armerina, hotel Piazza Armerina, albergo con parcheggio Piazza Armerina, alberghi con parcheggio Piazza Armerina, hotel con parcheggio Piazza Armerina, hotel accessibile Piazza Armerina, albergo accessibile Piazza Armerina, stanza albergo per disabili Piazza Armerina, hotel per disabili Piazza Armerina, camere accessibili per disabili Piazza Armerina, camere hotel accessibili Piazza Armerina, camere albergo accessibili per disabili Piazza Armerina, camera hotel accessibile Piazza Armerina, camera accessibile per disabili Piazza Armerina, camera albergo accessibile per disabili Piazza Armerina, \u00a0\nHotel Gangi a Piazza Armerina, Piazza Armerina a Piazza Armerina, ospitalit\u00e0 a Piazza Armerina, soggiorni a Piazza Armerina, viaggi d&#8217;affari a Piazza Armerina, vacanze a Piazza Armerina, posizione centrale a Piazza Armerina, ristrutturato a Piazza Armerina, tradizione familiare a Piazza Armerina, anni &#8217;50 a Piazza Armerina, Villa Romana del Casale a Piazza Armerina, Palio dei Normanni a Piazza Armerina, camere rinnovate a Piazza Armerina, disabilit\u00e0 a Piazza Armerina, Matrimoniale Classic a Piazza Armerina, Matrimoniale Superior a Piazza Armerina, Tripla Classic a Piazza Armerina, Singola Standard a Piazza Armerina, comfort moderni a Piazza Armerina, TV satellitare a Piazza Armerina, frigobar a Piazza Armerina, cassaforte a Piazza Armerina, bagno privato a Piazza Armerina, aria climatizzata a Piazza Armerina, colazione a buffet a Piazza Armerina, dolci artigianali a Piazza Armerina, Wi-Fi gratuito a Piazza Armerina, ascensore a Piazza Armerina, bar a Piazza Armerina, albergo a Piazza Armerina, alberghi a Piazza Armerina, hotel a Piazza Armerina, albergo con parcheggio a Piazza Armerina, alberghi con parcheggio a Piazza Armerina, hotel con parcheggio a Piazza Armerina, hotel accessibile a Piazza Armerina, albergo accessibile a Piazza Armerina, stanza albergo per disabili a Piazza Armerina, hotel per disabili a Piazza Armerina, camere accessibili per disabili a Piazza Armerina, camere hotel accessibili a Piazza Armerina, camere albergo accessibili per disabili a Piazza Armerina, camera hotel accessibile a Piazza Armerina, camera accessibile per disabili a Piazza Armerina, camera albergo accessibile per disabili a Piazza Armerina, \u00a0\nHotel Gangi Sicilia, Piazza Armerina Sicilia, ospitalit\u00e0 Sicilia, soggiorni Sicilia, viaggi d&#8217;affari Sicilia, vacanze Sicilia, posizione centrale Sicilia, ristrutturato Sicilia, tradizione familiare Sicilia, anni &#8217;50 Sicilia, Villa Romana del Casale Sicilia, Palio dei Normanni Sicilia, camere rinnovate Sicilia, disabilit\u00e0 Sicilia, Matrimoniale Classic Sicilia, Matrimoniale Superior Sicilia, Tripla Classic Sicilia, Singola Standard Sicilia, comfort moderni Sicilia, TV satellitare Sicilia, frigobar Sicilia, cassaforte Sicilia, bagno privato Sicilia, aria climatizzata Sicilia, colazione a buffet Sicilia, dolci artigianali Sicilia, Wi-Fi gratuito Sicilia, ascensore Sicilia, bar Sicilia, albergo Sicilia, alberghi Sicilia, hotel Sicilia, albergo con parcheggio Sicilia, alberghi con parcheggio Sicilia, hotel con parcheggio Sicilia, hotel accessibile Sicilia, albergo accessibile Sicilia, stanza albergo per disabili Sicilia, hotel per disabili Sicilia, camere accessibili per disabili Sicilia, camere hotel accessibili Sicilia, camere albergo accessibili per disabili Sicilia, camera hotel accessibile Sicilia, camera accessibile per disabili Sicilia, camera albergo accessibile per disabili Sicilia, \u00a0\nHotel Gangi in Sicilia, Piazza Armerina in Sicilia, ospitalit\u00e0 in Sicilia, soggiorni in Sicilia, viaggi d&#8217;affari in Sicilia, vacanze in Sicilia, posizione centrale in Sicilia, ristrutturato in Sicilia, tradizione familiare in Sicilia, anni &#8217;50 in Sicilia, Villa Romana del Casale in Sicilia, Palio dei Normanni in Sicilia, camere rinnovate in Sicilia, disabilit\u00e0 in Sicilia, Matrimoniale Classic in Sicilia, Matrimoniale Superior in Sicilia, Tripla Classic in Sicilia, Singola Standard in Sicilia, comfort moderni in Sicilia, TV satellitare in Sicilia, frigobar in Sicilia, cassaforte in Sicilia, bagno privato in Sicilia, aria climatizzata in Sicilia, colazione a buffet in Sicilia, dolci artigianali in Sicilia, Wi-Fi gratuito in Sicilia, ascensore in Sicilia, bar in Sicilia, albergo in Sicilia, alberghi in Sicilia, hotel in Sicilia, albergo con parcheggio in Sicilia, alberghi con parcheggio in Sicilia, hotel con parcheggio in Sicilia, hotel accessibile in Sicilia, albergo accessibile in Sicilia, stanza albergo per disabili in Sicilia, hotel per disabili in Sicilia, camere accessibili per disabili in Sicilia, camere hotel accessibili in Sicilia, camere albergo accessibili per disabili in Sicilia, camera hotel accessibile in Sicilia, camera accessibile per disabili in Sicilia, camera albergo accessibile per disabili in Sicilia, \u00a0\n\n\n\n\n\n\n\n\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e66c32 e-con-full e-flex e-con e-child\" data-id=\"5e66c32\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Dal 1955, Hotel Gangi rappresenta un\u2019icona di ospitalit\u00e0 nel cuore di Piazza Armerina. La struttura, completamente ristrutturata, \u00e8 la scelta ideale per viaggi d\u2019affari e soggiorni di piacere grazie alla sua posizione centrale e strategica. L\u2019hotel riflette una tradizione familiare che ha radici profonde: iniziata negli anni \u201950, quando Piazza Armerina divenne una meta turistica di riferimento grazie alla scoperta della Villa Romana del Casale e alle prime edizioni del suggestivo Palio dei Normanni.<\/p>\n<p>L\u2019Hotel Gangi dispone di 15 camere recentemente rinnovate, tra cui una progettata per accogliere persone con disabilit\u00e0. Le opzioni includono Matrimoniale Classic e Superior, Tripla Classic e Singola Standard, con tariffe a partire da \u20ac50 a notte. Tutte le camere sono dotate di comfort moderni: TV satellitare, telefono, frigobar, cassaforte, bagno privato con asciugacapelli e aria climatizzata regolabile.<\/p>\n<p>Gli ospiti possono gustare una ricchissima colazione a buffet servita in un\u2019accogliente saletta. La proposta spazia da croissant, pane e affettati a marmellate, miele, frutta fresca, yogurt e dolci artigianali come torte e crostate. Non mancano caff\u00e8, cappuccino o t\u00e8 caldo.<\/p>\n<p>L\u2019hotel offre inoltre connessione Wi-Fi gratuita in tutta la struttura, ascensore e bar per garantire un soggiorno completo e confortevole.<\/p>\n<p>Hotel Gangi, Piazza Armerina, ospitalit\u00e0, soggiorni, viaggi d&#8217;affari, vacanze, posizione centrale, ristrutturato, tradizione familiare, anni &#8217;50, Villa Romana del Casale, Palio dei Normanni, camere rinnovate, disabilit\u00e0, Matrimoniale Classic, Matrimoniale Superior, Tripla Classic, Singola Standard, comfort moderni, TV satellitare, frigobar, cassaforte, bagno privato, aria climatizzata, colazione a buffet, dolci artigianali, Wi-Fi gratuito, ascensore, bar, albergo, alberghi, hotel, albergo con parcheggio, alberghi con parcheggio, hotel con parcheggio, hotel accessibile, albergo accessibile, stanza albergo per disabili, hotel per disabili, camere accessibili per disabili, camere hotel accessibili, camere albergo accessibili per disabili, camera hotel accessibile, camera accessibile per disabili, camera albergo accessibile per disabili, \u00a0Piazza Armerina,<br \/>\nHotel Gangi Piazza Armerina, Piazza Armerina Piazza Armerina, ospitalit\u00e0 Piazza Armerina, soggiorni Piazza Armerina, viaggi d&#8217;affari Piazza Armerina, vacanze Piazza Armerina, posizione centrale Piazza Armerina, ristrutturato Piazza Armerina, tradizione familiare Piazza Armerina, anni &#8217;50 Piazza Armerina, Villa Romana del Casale Piazza Armerina, Palio dei Normanni Piazza Armerina, camere rinnovate Piazza Armerina, disabilit\u00e0 Piazza Armerina, Matrimoniale Classic Piazza Armerina, Matrimoniale Superior Piazza Armerina, Tripla Classic Piazza Armerina, Singola Standard Piazza Armerina, comfort moderni Piazza Armerina, TV satellitare Piazza Armerina, frigobar Piazza Armerina, cassaforte Piazza Armerina, bagno privato Piazza Armerina, aria climatizzata Piazza Armerina, colazione a buffet Piazza Armerina, dolci artigianali Piazza Armerina, Wi-Fi gratuito Piazza Armerina, ascensore Piazza Armerina, bar Piazza Armerina, albergo Piazza Armerina, alberghi Piazza Armerina, hotel Piazza Armerina, albergo con parcheggio Piazza Armerina, alberghi con parcheggio Piazza Armerina, hotel con parcheggio Piazza Armerina, hotel accessibile Piazza Armerina, albergo accessibile Piazza Armerina, stanza albergo per disabili Piazza Armerina, hotel per disabili Piazza Armerina, camere accessibili per disabili Piazza Armerina, camere hotel accessibili Piazza Armerina, camere albergo accessibili per disabili Piazza Armerina, camera hotel accessibile Piazza Armerina, camera accessibile per disabili Piazza Armerina, camera albergo accessibile per disabili Piazza Armerina,<br \/>\nHotel Gangi a Piazza Armerina, Piazza Armerina a Piazza Armerina, ospitalit\u00e0 a Piazza Armerina, soggiorni a Piazza Armerina, viaggi d&#8217;affari a Piazza Armerina, vacanze a Piazza Armerina, posizione centrale a Piazza Armerina, ristrutturato a Piazza Armerina, tradizione familiare a Piazza Armerina, anni &#8217;50 a Piazza Armerina, Villa Romana del Casale a Piazza Armerina, Palio dei Normanni a Piazza Armerina, camere rinnovate a Piazza Armerina, disabilit\u00e0 a Piazza Armerina, Matrimoniale Classic a Piazza Armerina, Matrimoniale Superior a Piazza Armerina, Tripla Classic a Piazza Armerina, Singola Standard a Piazza Armerina, comfort moderni a Piazza Armerina, TV satellitare a Piazza Armerina, frigobar a Piazza Armerina, cassaforte a Piazza Armerina, bagno privato a Piazza Armerina, aria climatizzata a Piazza Armerina, colazione a buffet a Piazza Armerina, dolci artigianali a Piazza Armerina, Wi-Fi gratuito a Piazza Armerina, ascensore a Piazza Armerina, bar a Piazza Armerina, albergo a Piazza Armerina, alberghi a Piazza Armerina, hotel a Piazza Armerina, albergo con parcheggio a Piazza Armerina, alberghi con parcheggio a Piazza Armerina, hotel con parcheggio a Piazza Armerina, hotel accessibile a Piazza Armerina, albergo accessibile a Piazza Armerina, stanza albergo per disabili a Piazza Armerina, hotel per disabili a Piazza Armerina, camere accessibili per disabili a Piazza Armerina, camere hotel accessibili a Piazza Armerina, camere albergo accessibili per disabili a Piazza Armerina, camera hotel accessibile a Piazza Armerina, camera accessibile per disabili a Piazza Armerina, camera albergo accessibile per disabili a Piazza Armerina,<br \/>\nHotel Gangi Sicilia, Piazza Armerina Sicilia, ospitalit\u00e0 Sicilia, soggiorni Sicilia, viaggi d&#8217;affari Sicilia, vacanze Sicilia, posizione centrale Sicilia, ristrutturato Sicilia, tradizione familiare Sicilia, anni &#8217;50 Sicilia, Villa Romana del Casale Sicilia, Palio dei Normanni Sicilia, camere rinnovate Sicilia, disabilit\u00e0 Sicilia, Matrimoniale Classic Sicilia, Matrimoniale Superior Sicilia, Tripla Classic Sicilia, Singola Standard Sicilia, comfort moderni Sicilia, TV satellitare Sicilia, frigobar Sicilia, cassaforte Sicilia, bagno privato Sicilia, aria climatizzata Sicilia, colazione a buffet Sicilia, dolci artigianali Sicilia, Wi-Fi gratuito Sicilia, ascensore Sicilia, bar Sicilia, albergo Sicilia, alberghi Sicilia, hotel Sicilia, albergo con parcheggio Sicilia, alberghi con parcheggio Sicilia, hotel con parcheggio Sicilia, hotel accessibile Sicilia, albergo accessibile Sicilia, stanza albergo per disabili Sicilia, hotel per disabili Sicilia, camere accessibili per disabili Sicilia, camere hotel accessibili Sicilia, camere albergo accessibili per disabili Sicilia, camera hotel accessibile Sicilia, camera accessibile per disabili Sicilia, camera albergo accessibile per disabili Sicilia,<br \/>\nHotel Gangi in Sicilia, Piazza Armerina in Sicilia, ospitalit\u00e0 in Sicilia, soggiorni in Sicilia, viaggi d&#8217;affari in Sicilia, vacanze in Sicilia, posizione centrale in Sicilia, ristrutturato in Sicilia, tradizione familiare in Sicilia, anni &#8217;50 in Sicilia, Villa Romana del Casale in Sicilia, Palio dei Normanni in Sicilia, camere rinnovate in Sicilia, disabilit\u00e0 in Sicilia, Matrimoniale Classic in Sicilia, Matrimoniale Superior in Sicilia, Tripla Classic in Sicilia, Singola Standard in Sicilia, comfort moderni in Sicilia, TV satellitare in Sicilia, frigobar in Sicilia, cassaforte in Sicilia, bagno privato in Sicilia, aria climatizzata in Sicilia, colazione a buffet in Sicilia, dolci artigianali in Sicilia, Wi-Fi gratuito in Sicilia, ascensore in Sicilia, bar in Sicilia, albergo in Sicilia, alberghi in Sicilia, hotel in Sicilia, albergo con parcheggio in Sicilia, alberghi con parcheggio in Sicilia, hotel con parcheggio in Sicilia, hotel accessibile in Sicilia, albergo accessibile in Sicilia, stanza albergo per disabili in Sicilia, hotel per disabili in Sicilia, camere accessibili per disabili in Sicilia, camere hotel accessibili in Sicilia, camere albergo accessibili per disabili in Sicilia, camera hotel accessibile in Sicilia, camera accessibile per disabili in Sicilia, camera albergo accessibile per disabili in Sicilia,<\/p>\n<\/div>\n","protected":false},"featured_media":98401,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[338,330],"product_tag":[3094,21137,3092,21139,16929,21120,21133,21136,21132,2979,21145,21146,21144,21141,21143,21142,21123,21131,16471,21128,5155,21134,21130,479,21138,16920,21115,17276,21124,21125,20256,21122,18835,21117,21118,21127,2627,21140,21119,21126,21129,1039,21116,21121,21135],"class_list":{"0":"post-98400","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hotel","7":"product_cat-turismo-e-viaggi","8":"product_tag-alberghi","9":"product_tag-alberghi-con-parcheggio","10":"product_tag-albergo","11":"product_tag-albergo-accessibile","12":"product_tag-albergo-con-parcheggio","13":"product_tag-anni-50","14":"product_tag-aria-climatizzata","15":"product_tag-ascensore","16":"product_tag-bagno-privato","17":"product_tag-bar","18":"product_tag-camera-accessibile-per-disabili","19":"product_tag-camera-albergo-accessibile-per-disabili","20":"product_tag-camera-hotel-accessibile","21":"product_tag-camere-accessibili-per-disabili","22":"product_tag-camere-albergo-accessibili-per-disabili","23":"product_tag-camere-hotel-accessibili","24":"product_tag-camere-rinnovate","25":"product_tag-cassaforte","26":"product_tag-colazione-a-buffet","27":"product_tag-comfort-moderni","28":"product_tag-disabilita","29":"product_tag-dolci-artigianali","30":"product_tag-frigobar","31":"product_tag-hotel","32":"product_tag-hotel-accessibile","33":"product_tag-hotel-con-parcheggio","34":"product_tag-hotel-gangi","35":"product_tag-hotel-per-disabili","36":"product_tag-matrimoniale-classic","37":"product_tag-matrimoniale-superior","38":"product_tag-ospitalita","39":"product_tag-palio-dei-normanni","40":"product_tag-piazza-armerina","41":"product_tag-posizione-centrale","42":"product_tag-ristrutturato","43":"product_tag-singola-standard","44":"product_tag-soggiorni","45":"product_tag-stanza-albergo-per-disabili","46":"product_tag-tradizione-familiare","47":"product_tag-tripla-classic","48":"product_tag-tv-satellitare","49":"product_tag-vacanze","50":"product_tag-viaggi-daffari","51":"product_tag-villa-romana-del-casale","52":"product_tag-wi-fi-gratuito","54":"first","55":"instock","56":"shipping-taxable","57":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hotel Gangi - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Gangi - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dal 1955, Hotel Gangi rappresenta un\u2019icona di ospitalit\u00e0 nel cuore di Piazza Armerina. La struttura, completamente ristrutturata, \u00e8 la scelta ideale per viaggi d\u2019affari e soggiorni di piacere grazie alla sua posizione centrale e strategica. L\u2019hotel riflette una tradizione familiare che ha radici profonde: iniziata negli anni \u201950, quando Piazza Armerina divenne una meta turistica di riferimento grazie alla scoperta della Villa Romana del Casale e alle prime edizioni del suggestivo Palio dei Normanni.  L\u2019Hotel Gangi dispone di 15 camere recentemente rinnovate, tra cui una progettata per accogliere persone con disabilit\u00e0. Le opzioni includono Matrimoniale Classic e Superior, Tripla Classic e Singola Standard, con tariffe a partire da \u20ac50 a notte. Tutte le camere sono dotate di comfort moderni: TV satellitare, telefono, frigobar, cassaforte, bagno privato con asciugacapelli e aria climatizzata regolabile.  Gli ospiti possono gustare una ricchissima colazione a buffet servita in un\u2019accogliente saletta. La proposta spazia da croissant, pane e affettati a marmellate, miele, frutta fresca, yogurt e dolci artigianali come torte e crostate. Non mancano caff\u00e8, cappuccino o t\u00e8 caldo.  L\u2019hotel offre inoltre connessione Wi-Fi gratuita in tutta la struttura, ascensore e bar per garantire un soggiorno completo e confortevole.  Hotel Gangi, Piazza Armerina, ospitalit\u00e0, soggiorni, viaggi d&#039;affari, vacanze, posizione centrale, ristrutturato, tradizione familiare, anni &#039;50, Villa Romana del Casale, Palio dei Normanni, camere rinnovate, disabilit\u00e0, Matrimoniale Classic, Matrimoniale Superior, Tripla Classic, Singola Standard, comfort moderni, TV satellitare, frigobar, cassaforte, bagno privato, aria climatizzata, colazione a buffet, dolci artigianali, Wi-Fi gratuito, ascensore, bar, albergo, alberghi, hotel, albergo con parcheggio, alberghi con parcheggio, hotel con parcheggio, hotel accessibile, albergo accessibile, stanza albergo per disabili, hotel per disabili, camere accessibili per disabili, camere hotel accessibili, camere albergo accessibili per disabili, camera hotel accessibile, camera accessibile per disabili, camera albergo accessibile per disabili, \u00a0Piazza Armerina, Hotel Gangi Piazza Armerina, Piazza Armerina Piazza Armerina, ospitalit\u00e0 Piazza Armerina, soggiorni Piazza Armerina, viaggi d&#039;affari Piazza Armerina, vacanze Piazza Armerina, posizione centrale Piazza Armerina, ristrutturato Piazza Armerina, tradizione familiare Piazza Armerina, anni &#039;50 Piazza Armerina, Villa Romana del Casale Piazza Armerina, Palio dei Normanni Piazza Armerina, camere rinnovate Piazza Armerina, disabilit\u00e0 Piazza Armerina, Matrimoniale Classic Piazza Armerina, Matrimoniale Superior Piazza Armerina, Tripla Classic Piazza Armerina, Singola Standard Piazza Armerina, comfort moderni Piazza Armerina, TV satellitare Piazza Armerina, frigobar Piazza Armerina, cassaforte Piazza Armerina, bagno privato Piazza Armerina, aria climatizzata Piazza Armerina, colazione a buffet Piazza Armerina, dolci artigianali Piazza Armerina, Wi-Fi gratuito Piazza Armerina, ascensore Piazza Armerina, bar Piazza Armerina, albergo Piazza Armerina, alberghi Piazza Armerina, hotel Piazza Armerina, albergo con parcheggio Piazza Armerina, alberghi con parcheggio Piazza Armerina, hotel con parcheggio Piazza Armerina, hotel accessibile Piazza Armerina, albergo accessibile Piazza Armerina, stanza albergo per disabili Piazza Armerina, hotel per disabili Piazza Armerina, camere accessibili per disabili Piazza Armerina, camere hotel accessibili Piazza Armerina, camere albergo accessibili per disabili Piazza Armerina, camera hotel accessibile Piazza Armerina, camera accessibile per disabili Piazza Armerina, camera albergo accessibile per disabili Piazza Armerina, Hotel Gangi a Piazza Armerina, Piazza Armerina a Piazza Armerina, ospitalit\u00e0 a Piazza Armerina, soggiorni a Piazza Armerina, viaggi d&#039;affari a Piazza Armerina, vacanze a Piazza Armerina, posizione centrale a Piazza Armerina, ristrutturato a Piazza Armerina, tradizione familiare a Piazza Armerina, anni &#039;50 a Piazza Armerina, Villa Romana del Casale a Piazza Armerina, Palio dei Normanni a Piazza Armerina, camere rinnovate a Piazza Armerina, disabilit\u00e0 a Piazza Armerina, Matrimoniale Classic a Piazza Armerina, Matrimoniale Superior a Piazza Armerina, Tripla Classic a Piazza Armerina, Singola Standard a Piazza Armerina, comfort moderni a Piazza Armerina, TV satellitare a Piazza Armerina, frigobar a Piazza Armerina, cassaforte a Piazza Armerina, bagno privato a Piazza Armerina, aria climatizzata a Piazza Armerina, colazione a buffet a Piazza Armerina, dolci artigianali a Piazza Armerina, Wi-Fi gratuito a Piazza Armerina, ascensore a Piazza Armerina, bar a Piazza Armerina, albergo a Piazza Armerina, alberghi a Piazza Armerina, hotel a Piazza Armerina, albergo con parcheggio a Piazza Armerina, alberghi con parcheggio a Piazza Armerina, hotel con parcheggio a Piazza Armerina, hotel accessibile a Piazza Armerina, albergo accessibile a Piazza Armerina, stanza albergo per disabili a Piazza Armerina, hotel per disabili a Piazza Armerina, camere accessibili per disabili a Piazza Armerina, camere hotel accessibili a Piazza Armerina, camere albergo accessibili per disabili a Piazza Armerina, camera hotel accessibile a Piazza Armerina, camera accessibile per disabili a Piazza Armerina, camera albergo accessibile per disabili a Piazza Armerina, Hotel Gangi Sicilia, Piazza Armerina Sicilia, ospitalit\u00e0 Sicilia, soggiorni Sicilia, viaggi d&#039;affari Sicilia, vacanze Sicilia, posizione centrale Sicilia, ristrutturato Sicilia, tradizione familiare Sicilia, anni &#039;50 Sicilia, Villa Romana del Casale Sicilia, Palio dei Normanni Sicilia, camere rinnovate Sicilia, disabilit\u00e0 Sicilia, Matrimoniale Classic Sicilia, Matrimoniale Superior Sicilia, Tripla Classic Sicilia, Singola Standard Sicilia, comfort moderni Sicilia, TV satellitare Sicilia, frigobar Sicilia, cassaforte Sicilia, bagno privato Sicilia, aria climatizzata Sicilia, colazione a buffet Sicilia, dolci artigianali Sicilia, Wi-Fi gratuito Sicilia, ascensore Sicilia, bar Sicilia, albergo Sicilia, alberghi Sicilia, hotel Sicilia, albergo con parcheggio Sicilia, alberghi con parcheggio Sicilia, hotel con parcheggio Sicilia, hotel accessibile Sicilia, albergo accessibile Sicilia, stanza albergo per disabili Sicilia, hotel per disabili Sicilia, camere accessibili per disabili Sicilia, camere hotel accessibili Sicilia, camere albergo accessibili per disabili Sicilia, camera hotel accessibile Sicilia, camera accessibile per disabili Sicilia, camera albergo accessibile per disabili Sicilia, Hotel Gangi in Sicilia, Piazza Armerina in Sicilia, ospitalit\u00e0 in Sicilia, soggiorni in Sicilia, viaggi d&#039;affari in Sicilia, vacanze in Sicilia, posizione centrale in Sicilia, ristrutturato in Sicilia, tradizione familiare in Sicilia, anni &#039;50 in Sicilia, Villa Romana del Casale in Sicilia, Palio dei Normanni in Sicilia, camere rinnovate in Sicilia, disabilit\u00e0 in Sicilia, Matrimoniale Classic in Sicilia, Matrimoniale Superior in Sicilia, Tripla Classic in Sicilia, Singola Standard in Sicilia, comfort moderni in Sicilia, TV satellitare in Sicilia, frigobar in Sicilia, cassaforte in Sicilia, bagno privato in Sicilia, aria climatizzata in Sicilia, colazione a buffet in Sicilia, dolci artigianali in Sicilia, Wi-Fi gratuito in Sicilia, ascensore in Sicilia, bar in Sicilia, albergo in Sicilia, alberghi in Sicilia, hotel in Sicilia, albergo con parcheggio in Sicilia, alberghi con parcheggio in Sicilia, hotel con parcheggio in Sicilia, hotel accessibile in Sicilia, albergo accessibile in Sicilia, stanza albergo per disabili in Sicilia, hotel per disabili in Sicilia, camere accessibili per disabili in Sicilia, camere hotel accessibili in Sicilia, camere albergo accessibili per disabili in Sicilia, camera hotel accessibile in Sicilia, camera accessibile per disabili in Sicilia, camera albergo accessibile per disabili in Sicilia,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T13:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/\",\"name\":\"Hotel Gangi - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png\",\"datePublished\":\"2026-05-08T16:03:25+00:00\",\"dateModified\":\"2026-05-11T13:36:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hotel Gangi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Gangi - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/","og_locale":"it_IT","og_type":"article","og_title":"Hotel Gangi - UIL Polizia","og_description":"Dal 1955, Hotel Gangi rappresenta un\u2019icona di ospitalit\u00e0 nel cuore di Piazza Armerina. La struttura, completamente ristrutturata, \u00e8 la scelta ideale per viaggi d\u2019affari e soggiorni di piacere grazie alla sua posizione centrale e strategica. L\u2019hotel riflette una tradizione familiare che ha radici profonde: iniziata negli anni \u201950, quando Piazza Armerina divenne una meta turistica di riferimento grazie alla scoperta della Villa Romana del Casale e alle prime edizioni del suggestivo Palio dei Normanni.  L\u2019Hotel Gangi dispone di 15 camere recentemente rinnovate, tra cui una progettata per accogliere persone con disabilit\u00e0. Le opzioni includono Matrimoniale Classic e Superior, Tripla Classic e Singola Standard, con tariffe a partire da \u20ac50 a notte. Tutte le camere sono dotate di comfort moderni: TV satellitare, telefono, frigobar, cassaforte, bagno privato con asciugacapelli e aria climatizzata regolabile.  Gli ospiti possono gustare una ricchissima colazione a buffet servita in un\u2019accogliente saletta. La proposta spazia da croissant, pane e affettati a marmellate, miele, frutta fresca, yogurt e dolci artigianali come torte e crostate. Non mancano caff\u00e8, cappuccino o t\u00e8 caldo.  L\u2019hotel offre inoltre connessione Wi-Fi gratuita in tutta la struttura, ascensore e bar per garantire un soggiorno completo e confortevole.  Hotel Gangi, Piazza Armerina, ospitalit\u00e0, soggiorni, viaggi d'affari, vacanze, posizione centrale, ristrutturato, tradizione familiare, anni '50, Villa Romana del Casale, Palio dei Normanni, camere rinnovate, disabilit\u00e0, Matrimoniale Classic, Matrimoniale Superior, Tripla Classic, Singola Standard, comfort moderni, TV satellitare, frigobar, cassaforte, bagno privato, aria climatizzata, colazione a buffet, dolci artigianali, Wi-Fi gratuito, ascensore, bar, albergo, alberghi, hotel, albergo con parcheggio, alberghi con parcheggio, hotel con parcheggio, hotel accessibile, albergo accessibile, stanza albergo per disabili, hotel per disabili, camere accessibili per disabili, camere hotel accessibili, camere albergo accessibili per disabili, camera hotel accessibile, camera accessibile per disabili, camera albergo accessibile per disabili, \u00a0Piazza Armerina, Hotel Gangi Piazza Armerina, Piazza Armerina Piazza Armerina, ospitalit\u00e0 Piazza Armerina, soggiorni Piazza Armerina, viaggi d'affari Piazza Armerina, vacanze Piazza Armerina, posizione centrale Piazza Armerina, ristrutturato Piazza Armerina, tradizione familiare Piazza Armerina, anni '50 Piazza Armerina, Villa Romana del Casale Piazza Armerina, Palio dei Normanni Piazza Armerina, camere rinnovate Piazza Armerina, disabilit\u00e0 Piazza Armerina, Matrimoniale Classic Piazza Armerina, Matrimoniale Superior Piazza Armerina, Tripla Classic Piazza Armerina, Singola Standard Piazza Armerina, comfort moderni Piazza Armerina, TV satellitare Piazza Armerina, frigobar Piazza Armerina, cassaforte Piazza Armerina, bagno privato Piazza Armerina, aria climatizzata Piazza Armerina, colazione a buffet Piazza Armerina, dolci artigianali Piazza Armerina, Wi-Fi gratuito Piazza Armerina, ascensore Piazza Armerina, bar Piazza Armerina, albergo Piazza Armerina, alberghi Piazza Armerina, hotel Piazza Armerina, albergo con parcheggio Piazza Armerina, alberghi con parcheggio Piazza Armerina, hotel con parcheggio Piazza Armerina, hotel accessibile Piazza Armerina, albergo accessibile Piazza Armerina, stanza albergo per disabili Piazza Armerina, hotel per disabili Piazza Armerina, camere accessibili per disabili Piazza Armerina, camere hotel accessibili Piazza Armerina, camere albergo accessibili per disabili Piazza Armerina, camera hotel accessibile Piazza Armerina, camera accessibile per disabili Piazza Armerina, camera albergo accessibile per disabili Piazza Armerina, Hotel Gangi a Piazza Armerina, Piazza Armerina a Piazza Armerina, ospitalit\u00e0 a Piazza Armerina, soggiorni a Piazza Armerina, viaggi d'affari a Piazza Armerina, vacanze a Piazza Armerina, posizione centrale a Piazza Armerina, ristrutturato a Piazza Armerina, tradizione familiare a Piazza Armerina, anni '50 a Piazza Armerina, Villa Romana del Casale a Piazza Armerina, Palio dei Normanni a Piazza Armerina, camere rinnovate a Piazza Armerina, disabilit\u00e0 a Piazza Armerina, Matrimoniale Classic a Piazza Armerina, Matrimoniale Superior a Piazza Armerina, Tripla Classic a Piazza Armerina, Singola Standard a Piazza Armerina, comfort moderni a Piazza Armerina, TV satellitare a Piazza Armerina, frigobar a Piazza Armerina, cassaforte a Piazza Armerina, bagno privato a Piazza Armerina, aria climatizzata a Piazza Armerina, colazione a buffet a Piazza Armerina, dolci artigianali a Piazza Armerina, Wi-Fi gratuito a Piazza Armerina, ascensore a Piazza Armerina, bar a Piazza Armerina, albergo a Piazza Armerina, alberghi a Piazza Armerina, hotel a Piazza Armerina, albergo con parcheggio a Piazza Armerina, alberghi con parcheggio a Piazza Armerina, hotel con parcheggio a Piazza Armerina, hotel accessibile a Piazza Armerina, albergo accessibile a Piazza Armerina, stanza albergo per disabili a Piazza Armerina, hotel per disabili a Piazza Armerina, camere accessibili per disabili a Piazza Armerina, camere hotel accessibili a Piazza Armerina, camere albergo accessibili per disabili a Piazza Armerina, camera hotel accessibile a Piazza Armerina, camera accessibile per disabili a Piazza Armerina, camera albergo accessibile per disabili a Piazza Armerina, Hotel Gangi Sicilia, Piazza Armerina Sicilia, ospitalit\u00e0 Sicilia, soggiorni Sicilia, viaggi d'affari Sicilia, vacanze Sicilia, posizione centrale Sicilia, ristrutturato Sicilia, tradizione familiare Sicilia, anni '50 Sicilia, Villa Romana del Casale Sicilia, Palio dei Normanni Sicilia, camere rinnovate Sicilia, disabilit\u00e0 Sicilia, Matrimoniale Classic Sicilia, Matrimoniale Superior Sicilia, Tripla Classic Sicilia, Singola Standard Sicilia, comfort moderni Sicilia, TV satellitare Sicilia, frigobar Sicilia, cassaforte Sicilia, bagno privato Sicilia, aria climatizzata Sicilia, colazione a buffet Sicilia, dolci artigianali Sicilia, Wi-Fi gratuito Sicilia, ascensore Sicilia, bar Sicilia, albergo Sicilia, alberghi Sicilia, hotel Sicilia, albergo con parcheggio Sicilia, alberghi con parcheggio Sicilia, hotel con parcheggio Sicilia, hotel accessibile Sicilia, albergo accessibile Sicilia, stanza albergo per disabili Sicilia, hotel per disabili Sicilia, camere accessibili per disabili Sicilia, camere hotel accessibili Sicilia, camere albergo accessibili per disabili Sicilia, camera hotel accessibile Sicilia, camera accessibile per disabili Sicilia, camera albergo accessibile per disabili Sicilia, Hotel Gangi in Sicilia, Piazza Armerina in Sicilia, ospitalit\u00e0 in Sicilia, soggiorni in Sicilia, viaggi d'affari in Sicilia, vacanze in Sicilia, posizione centrale in Sicilia, ristrutturato in Sicilia, tradizione familiare in Sicilia, anni '50 in Sicilia, Villa Romana del Casale in Sicilia, Palio dei Normanni in Sicilia, camere rinnovate in Sicilia, disabilit\u00e0 in Sicilia, Matrimoniale Classic in Sicilia, Matrimoniale Superior in Sicilia, Tripla Classic in Sicilia, Singola Standard in Sicilia, comfort moderni in Sicilia, TV satellitare in Sicilia, frigobar in Sicilia, cassaforte in Sicilia, bagno privato in Sicilia, aria climatizzata in Sicilia, colazione a buffet in Sicilia, dolci artigianali in Sicilia, Wi-Fi gratuito in Sicilia, ascensore in Sicilia, bar in Sicilia, albergo in Sicilia, alberghi in Sicilia, hotel in Sicilia, albergo con parcheggio in Sicilia, alberghi con parcheggio in Sicilia, hotel con parcheggio in Sicilia, hotel accessibile in Sicilia, albergo accessibile in Sicilia, stanza albergo per disabili in Sicilia, hotel per disabili in Sicilia, camere accessibili per disabili in Sicilia, camere hotel accessibili in Sicilia, camere albergo accessibili per disabili in Sicilia, camera hotel accessibile in Sicilia, camera accessibile per disabili in Sicilia, camera albergo accessibile per disabili in Sicilia,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/","og_site_name":"UIL Polizia","article_modified_time":"2026-05-11T13:36:23+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/","name":"Hotel Gangi - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png","datePublished":"2026-05-08T16:03:25+00:00","dateModified":"2026-05-11T13:36:23+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/logo-siti-hotel-gangi.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/hotel-gangi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Hotel Gangi"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/98400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=98400"}],"version-history":[{"count":7,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/98400\/revisions"}],"predecessor-version":[{"id":98529,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/98400\/revisions\/98529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/98401"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=98400"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=98400"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=98400"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=98400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}