{"id":92908,"date":"2026-03-23T17:28:45","date_gmt":"2026-03-23T16:28:45","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=92908"},"modified":"2026-03-24T18:07:48","modified_gmt":"2026-03-24T17:07:48","slug":"dr-lorenzo-degiovanni-fisioterapista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/","title":{"rendered":"Dr. Lorenzo Degiovanni &#8211; Fisioterapista"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"92908\" class=\"elementor elementor-92908\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7713df1d e-flex e-con-boxed e-con e-parent\" data-id=\"7713df1d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c9dc534 elementor-widget elementor-widget-text-editor\" data-id=\"3c9dc534\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDr. Lorenzo Degiovanni\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c894b3f elementor-widget elementor-widget-text-editor\" data-id=\"2c894b3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fisioterapista<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4d526 e-flex e-con-boxed e-con e-parent\" data-id=\"b4d526\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3dc65336 e-con-full e-flex e-con e-child\" data-id=\"3dc65336\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4fdd033e e-con-full e-flex e-con e-child\" data-id=\"4fdd033e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e522399 elementor-widget elementor-widget-text-editor\" data-id=\"e522399\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73eda159 elementor-widget elementor-widget-text-editor\" data-id=\"73eda159\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fisioterapista specializzato in riabilitazione sportiva e muscolo-scheletrica, laureato presso l\u2019Universit\u00e0 degli Studi di Torino. Integro terapia manuale, esercizio terapeutico personalizzato e ricondizionamento del gesto atletico per favorire un recupero efficace e duraturo. Appassionato di sport ed allenamenti credo nel movimento come strumento di salute, performance e crescita personale.<\/p><p>Attualmente sto frequentando il master in osteopatia presso EOM Italia, per ampliare ulteriormente le mie competenze e offrire un approccio sempre pi\u00f9 completo alla persona.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-378599ab e-con-full e-flex e-con e-child\" data-id=\"378599ab\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:92919,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/01-scaled.jpg&quot;},{&quot;id&quot;:92913,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/06-scaled.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:4000,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1a8edb e-flex e-con-boxed e-con e-parent\" data-id=\"b1a8edb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-235f6da elementor-widget elementor-widget-text-editor\" data-id=\"235f6da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aree di Intervento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe55c8b e-grid e-con-full e-con e-child\" data-id=\"fe55c8b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e159f4f elementor-view-stacked elementor-shape-rounded elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"e159f4f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-running\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 96c26.51 0 48-21.49 48-48S298.51 0 272 0s-48 21.49-48 48 21.49 48 48 48zM113.69 317.47l-14.8 34.52H32c-17.67 0-32 14.33-32 32s14.33 32 32 32h77.45c19.25 0 36.58-11.44 44.11-29.09l8.79-20.52-10.67-6.3c-17.32-10.23-30.06-25.37-37.99-42.61zM384 223.99h-44.03l-26.06-53.25c-12.5-25.55-35.45-44.23-61.78-50.94l-71.08-21.14c-28.3-6.8-57.77-.55-80.84 17.14l-39.67 30.41c-14.03 10.75-16.69 30.83-5.92 44.86s30.84 16.66 44.86 5.92l39.69-30.41c7.67-5.89 17.44-8 25.27-6.14l14.7 4.37-37.46 87.39c-12.62 29.48-1.31 64.01 26.3 80.31l84.98 50.17-27.47 87.73c-5.28 16.86 4.11 34.81 20.97 40.09 3.19 1 6.41 1.48 9.58 1.48 13.61 0 26.23-8.77 30.52-22.45l31.64-101.06c5.91-20.77-2.89-43.08-21.64-54.39l-61.24-36.14 31.31-78.28 20.27 41.43c8 16.34 24.92 26.89 43.11 26.89H384c17.67 0 32-14.33 32-32s-14.33-31.99-32-31.99z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFisioterapia\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPercorsi mirati dopo interventi ortopedici (legamenti, protesi, menischi) per un ritorno sicuro alla quotidianit\u00e0.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8325af4 elementor-view-stacked elementor-shape-rounded elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"8325af4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-running\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 96c26.51 0 48-21.49 48-48S298.51 0 272 0s-48 21.49-48 48 21.49 48 48 48zM113.69 317.47l-14.8 34.52H32c-17.67 0-32 14.33-32 32s14.33 32 32 32h77.45c19.25 0 36.58-11.44 44.11-29.09l8.79-20.52-10.67-6.3c-17.32-10.23-30.06-25.37-37.99-42.61zM384 223.99h-44.03l-26.06-53.25c-12.5-25.55-35.45-44.23-61.78-50.94l-71.08-21.14c-28.3-6.8-57.77-.55-80.84 17.14l-39.67 30.41c-14.03 10.75-16.69 30.83-5.92 44.86s30.84 16.66 44.86 5.92l39.69-30.41c7.67-5.89 17.44-8 25.27-6.14l14.7 4.37-37.46 87.39c-12.62 29.48-1.31 64.01 26.3 80.31l84.98 50.17-27.47 87.73c-5.28 16.86 4.11 34.81 20.97 40.09 3.19 1 6.41 1.48 9.58 1.48 13.61 0 26.23-8.77 30.52-22.45l31.64-101.06c5.91-20.77-2.89-43.08-21.64-54.39l-61.24-36.14 31.31-78.28 20.27 41.43c8 16.34 24.92 26.89 43.11 26.89H384c17.67 0 32-14.33 32-32s-14.33-31.99-32-31.99z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRiabilitazione Sportiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProgrammi specifici per atleti: dalla fase acuta dell'infortunio fino al ritorno in campo e al miglioramento della performance.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efc9a44 elementor-view-stacked elementor-shape-rounded elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"efc9a44\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-running\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 96c26.51 0 48-21.49 48-48S298.51 0 272 0s-48 21.49-48 48 21.49 48 48 48zM113.69 317.47l-14.8 34.52H32c-17.67 0-32 14.33-32 32s14.33 32 32 32h77.45c19.25 0 36.58-11.44 44.11-29.09l8.79-20.52-10.67-6.3c-17.32-10.23-30.06-25.37-37.99-42.61zM384 223.99h-44.03l-26.06-53.25c-12.5-25.55-35.45-44.23-61.78-50.94l-71.08-21.14c-28.3-6.8-57.77-.55-80.84 17.14l-39.67 30.41c-14.03 10.75-16.69 30.83-5.92 44.86s30.84 16.66 44.86 5.92l39.69-30.41c7.67-5.89 17.44-8 25.27-6.14l14.7 4.37-37.46 87.39c-12.62 29.48-1.31 64.01 26.3 80.31l84.98 50.17-27.47 87.73c-5.28 16.86 4.11 34.81 20.97 40.09 3.19 1 6.41 1.48 9.58 1.48 13.61 0 26.23-8.77 30.52-22.45l31.64-101.06c5.91-20.77-2.89-43.08-21.64-54.39l-61.24-36.14 31.31-78.28 20.27 41.43c8 16.34 24.92 26.89 43.11 26.89H384c17.67 0 32-14.33 32-32s-14.33-31.99-32-31.99z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGinnastica Posturale\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tStrategie moderne per il trattamento di mal di schiena, cervicalgia e dolori persistenti legati alla postura.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c99cd elementor-view-stacked elementor-shape-rounded elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"e4c99cd\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-running\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M272 96c26.51 0 48-21.49 48-48S298.51 0 272 0s-48 21.49-48 48 21.49 48 48 48zM113.69 317.47l-14.8 34.52H32c-17.67 0-32 14.33-32 32s14.33 32 32 32h77.45c19.25 0 36.58-11.44 44.11-29.09l8.79-20.52-10.67-6.3c-17.32-10.23-30.06-25.37-37.99-42.61zM384 223.99h-44.03l-26.06-53.25c-12.5-25.55-35.45-44.23-61.78-50.94l-71.08-21.14c-28.3-6.8-57.77-.55-80.84 17.14l-39.67 30.41c-14.03 10.75-16.69 30.83-5.92 44.86s30.84 16.66 44.86 5.92l39.69-30.41c7.67-5.89 17.44-8 25.27-6.14l14.7 4.37-37.46 87.39c-12.62 29.48-1.31 64.01 26.3 80.31l84.98 50.17-27.47 87.73c-5.28 16.86 4.11 34.81 20.97 40.09 3.19 1 6.41 1.48 9.58 1.48 13.61 0 26.23-8.77 30.52-22.45l31.64-101.06c5.91-20.77-2.89-43.08-21.64-54.39l-61.24-36.14 31.31-78.28 20.27 41.43c8 16.34 24.92 26.89 43.11 26.89H384c17.67 0 32-14.33 32-32s-14.33-31.99-32-31.99z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTeleriabilitazione (Online)\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tConsulenze e programmi di esercizi a distanza, monitorati costantemente per garantire risultati ovunque tu sia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69fd8c3f e-flex e-con-boxed e-con e-parent\" data-id=\"69fd8c3f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1383522f elementor-widget elementor-widget-text-editor\" data-id=\"1383522f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9f3b8f e-flex e-con-boxed e-con e-parent\" data-id=\"f9f3b8f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-35f7d65 e-con-full e-flex e-con e-child\" data-id=\"35f7d65\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dba7fa2 e-con-full e-flex e-con e-child\" data-id=\"dba7fa2\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2999207a e-con-full e-flex e-con e-child\" data-id=\"2999207a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8644dd elementor-widget elementor-widget-text-editor\" data-id=\"a8644dd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti e orari\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359dea11 elementor-widget elementor-widget-icon-box\" data-id=\"359dea11\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDr. Lorenzo Degiovanni\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFisioterapista\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f052ccc e-con-full e-flex e-con e-child\" data-id=\"4f052ccc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-235235df elementor-widget elementor-widget-text-editor\" data-id=\"235235df\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Tel.<\/strong> <a href=\"tel:+393534944116\" target=\"_blank\" rel=\"noopener\">353 4944116<\/a>\u202c<br \/><span style=\"color: #006d9e;\"><strong><a style=\"color: #006d9e;\" href=\"https:\/\/degiovannifisioterapia.com\/\" target=\"_blank\" rel=\"noopener\">degiovannifisioterapia.com<\/a><\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30b8f773 elementor-shape-circle e-grid-align-left e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"30b8f773\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-00cad6d\" href=\"https:\/\/www.instagram.com\/lorenzodegiovanni_physio\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-843b30d\" href=\"https:\/\/www.linkedin.com\/in\/lorenzo-degiovanni-3b584b204\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c097863 e-con-full e-flex e-con e-child\" data-id=\"4c097863\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bd55a5 elementor-widget elementor-widget-text-editor\" data-id=\"5bd55a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-134\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-134\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:400px;\"> <span id=\"gmw-resize-map-toggle-134\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-134\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-134\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"134\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1df4c63e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"1df4c63e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a295976 elementor-widget elementor-widget-text-editor\" data-id=\"6a295976\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>fisioterapia, fisioterapie, fisioterapista, fisioterapisti, riabilitazione, riabilitazioni, riabilitazione sportiva, riabilitazioni sportive, riabilitazione muscolo scheletrica, riabilitazioni muscolo scheletriche, terapia manuale, terapie manuali, esercizio terapeutico, esercizi terapeutici, ricondizionamento atletico, recupero funzionale, recuperi funzionali, recupero infortunio, recupero infortuni, prevenzione infortuni, prevenzione, performance sportiva, performance sportive, allenamento, allenamenti, movimento e salute, fisioterapia ortopedica, riabilitazione ortopedica, riabilitazione post intervento, riabilitazione post interventi, riabilitazione legamenti, riabilitazione protesi, riabilitazione menisco, riabilitazione menischi, ginnastica posturale, esercizi posturali, postura corretta, mal di schiena, cervicalgia, dolore cervicale, dolori muscolari, dolori articolari, dolore cronico, dolori persistenti, teleriabilitazione, fisioterapia online, riabilitazione online, consulenza fisioterapica online, programmi di esercizi personalizzati, programmi riabilitativi, esercizi a distanza, preparazione atletica, preparazione atletica personalizzata, schede running, allenamento running, corsa, maratona, 10 km, ritorno allo sport, ritorno in campo, miglioramento performance, benessere fisico, crescita personale, osteopatia, approccio integrato, trattamento personalizzato<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fisioterapista specializzato in riabilitazione sportiva e muscolo-scheletrica, laureato presso l\u2019Universit\u00e0 degli Studi di Torino. Integro terapia manuale, esercizio terapeutico personalizzato e ricondizionamento del gesto atletico per favorire un recupero efficace e duraturo. Appassionato di sport ed allenamenti credo nel movimento come strumento di salute, performance e crescita personale.<\/p>\n<p>Attualmente sto frequentando il master in osteopatia presso EOM Italia, per ampliare ulteriormente le mie competenze e offrire un approccio sempre pi\u00f9 completo alla persona.<\/p>\n<p>Aree di<br \/>\nIntervento<br \/>\nFisioterapia<br \/>\nPercorsi mirati dopo interventi ortopedici (legamenti, protesi, menischi) per un ritorno sicuro alla quotidianit\u00e0.<\/p>\n<p>Riabilitazione Sportiva<br \/>\nProgrammi specifici per atleti: dalla fase acuta dell&#8217;infortunio fino al ritorno in campo e al miglioramento della performance.<\/p>\n<p>Ginnastica Posturale<br \/>\nStrategie moderne per il trattamento di mal di schiena, cervicalgia e dolori persistenti legati alla postura.<\/p>\n<p>Teleriabilitazione Online<br \/>\nConsulenze e programmi di esercizi a distanza, monitorati costantemente per garantire risultati ovunque tu sia.<\/p>\n<p>Preparazione Atletica e Schede Running<br \/>\nDai primi 10 km alla maratona<\/p>\n<p>RIABILITAZIONE SPORTIVA \u2022 TERAPIA MANUALE \u2022 GINNASTICA POSTURALE \u2022 TELERIABILITAZIONE \u2022 PREVENZIONE<\/p>\n<p>fisioterapia, fisioterapie, fisioterapista, fisioterapisti, riabilitazione, riabilitazioni, riabilitazione sportiva, riabilitazioni sportive, riabilitazione muscolo scheletrica, riabilitazioni muscolo scheletriche, terapia manuale, terapie manuali, esercizio terapeutico, esercizi terapeutici, ricondizionamento atletico, recupero funzionale, recuperi funzionali, recupero infortunio, recupero infortuni, prevenzione infortuni, prevenzione, performance sportiva, performance sportive, allenamento, allenamenti, movimento e salute, fisioterapia ortopedica, riabilitazione ortopedica, riabilitazione post intervento, riabilitazione post interventi, riabilitazione legamenti, riabilitazione protesi, riabilitazione menisco, riabilitazione menischi, ginnastica posturale, esercizi posturali, postura corretta, mal di schiena, cervicalgia, dolore cervicale, dolori muscolari, dolori articolari, dolore cronico, dolori persistenti, teleriabilitazione, fisioterapia online, riabilitazione online, consulenza fisioterapica online, programmi di esercizi personalizzati, programmi riabilitativi, esercizi a distanza, preparazione atletica, preparazione atletica personalizzata, schede running, allenamento running, corsa, maratona, 10 km, ritorno allo sport, ritorno in campo, miglioramento performance, benessere fisico, crescita personale, osteopatia, approccio integrato, trattamento personalizzato<\/p>\n","protected":false},"featured_media":92909,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,163],"product_tag":[19198,4092,1519,19195,13709,1727,673,19189,19196,3032,4812,4404,4184,2394,19185,19192,5630,11894,1400,447,19187,1667,19168,365,448,1840,2214,19197,16141,19178,384,18321,19177,19184,4323,19193,2821,19176,19190,19191,18361,1484,19175,19174,387,19180,19183,19182,19171,19188,3660,19179,3661,19181,1554,19169,19172,19170,19173,19199,19200,19194,19186,1551,1722,18360],"class_list":{"0":"post-92908","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-salute","8":"product_tag-10-km","9":"product_tag-allenamenti","10":"product_tag-allenamento","11":"product_tag-allenamento-running","12":"product_tag-approccio-integrato","13":"product_tag-benessere-fisico","14":"product_tag-cervicalgia","15":"product_tag-consulenza-fisioterapica-online","16":"product_tag-corsa","17":"product_tag-crescita-personale","18":"product_tag-dolore-cervicale","19":"product_tag-dolore-cronico","20":"product_tag-dolori-articolari","21":"product_tag-dolori-muscolari","22":"product_tag-dolori-persistenti","23":"product_tag-esercizi-a-distanza","24":"product_tag-esercizi-posturali","25":"product_tag-esercizi-terapeutici","26":"product_tag-esercizio-terapeutico","27":"product_tag-fisioterapia","28":"product_tag-fisioterapia-online","29":"product_tag-fisioterapia-ortopedica","30":"product_tag-fisioterapie","31":"product_tag-fisioterapista","32":"product_tag-fisioterapisti","33":"product_tag-ginnastica-posturale","34":"product_tag-mal-di-schiena","35":"product_tag-maratona","36":"product_tag-miglioramento-performance","37":"product_tag-movimento-e-salute","38":"product_tag-osteopatia","39":"product_tag-performance-sportiva","40":"product_tag-performance-sportive","41":"product_tag-postura-corretta","42":"product_tag-preparazione-atletica","43":"product_tag-preparazione-atletica-personalizzata","44":"product_tag-prevenzione","45":"product_tag-prevenzione-infortuni","46":"product_tag-programmi-di-esercizi-personalizzati","47":"product_tag-programmi-riabilitativi","48":"product_tag-recuperi-funzionali","49":"product_tag-recupero-funzionale","50":"product_tag-recupero-infortuni","51":"product_tag-recupero-infortunio","52":"product_tag-riabilitazione","53":"product_tag-riabilitazione-legamenti","54":"product_tag-riabilitazione-menischi","55":"product_tag-riabilitazione-menisco","56":"product_tag-riabilitazione-muscolo-scheletrica","57":"product_tag-riabilitazione-online","58":"product_tag-riabilitazione-ortopedica","59":"product_tag-riabilitazione-post-interventi","60":"product_tag-riabilitazione-post-intervento","61":"product_tag-riabilitazione-protesi","62":"product_tag-riabilitazione-sportiva","63":"product_tag-riabilitazioni","64":"product_tag-riabilitazioni-muscolo-scheletriche","65":"product_tag-riabilitazioni-sportive","66":"product_tag-ricondizionamento-atletico","67":"product_tag-ritorno-allo-sport","68":"product_tag-ritorno-in-campo","69":"product_tag-schede-running","70":"product_tag-teleriabilitazione","71":"product_tag-terapia-manuale","72":"product_tag-terapie-manuali","73":"product_tag-trattamento-personalizzato","75":"first","76":"instock","77":"shipping-taxable","78":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dr. Lorenzo Degiovanni - Fisioterapista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Lorenzo Degiovanni - Fisioterapista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Fisioterapista specializzato in riabilitazione sportiva e muscolo-scheletrica, laureato presso l\u2019Universit\u00e0 degli Studi di Torino. Integro terapia manuale, esercizio terapeutico personalizzato e ricondizionamento del gesto atletico per favorire un recupero efficace e duraturo. Appassionato di sport ed allenamenti credo nel movimento come strumento di salute, performance e crescita personale. Attualmente sto frequentando il master in osteopatia presso EOM Italia, per ampliare ulteriormente le mie competenze e offrire un approccio sempre pi\u00f9 completo alla persona. Aree di Intervento Fisioterapia Percorsi mirati dopo interventi ortopedici (legamenti, protesi, menischi) per un ritorno sicuro alla quotidianit\u00e0. Riabilitazione Sportiva Programmi specifici per atleti: dalla fase acuta dell&#039;infortunio fino al ritorno in campo e al miglioramento della performance. Ginnastica Posturale Strategie moderne per il trattamento di mal di schiena, cervicalgia e dolori persistenti legati alla postura. Teleriabilitazione Online Consulenze e programmi di esercizi a distanza, monitorati costantemente per garantire risultati ovunque tu sia. Preparazione Atletica e Schede Running Dai primi 10 km alla maratona RIABILITAZIONE SPORTIVA \u2022 TERAPIA MANUALE \u2022 GINNASTICA POSTURALE \u2022 TELERIABILITAZIONE \u2022 PREVENZIONE  fisioterapia, fisioterapie, fisioterapista, fisioterapisti, riabilitazione, riabilitazioni, riabilitazione sportiva, riabilitazioni sportive, riabilitazione muscolo scheletrica, riabilitazioni muscolo scheletriche, terapia manuale, terapie manuali, esercizio terapeutico, esercizi terapeutici, ricondizionamento atletico, recupero funzionale, recuperi funzionali, recupero infortunio, recupero infortuni, prevenzione infortuni, prevenzione, performance sportiva, performance sportive, allenamento, allenamenti, movimento e salute, fisioterapia ortopedica, riabilitazione ortopedica, riabilitazione post intervento, riabilitazione post interventi, riabilitazione legamenti, riabilitazione protesi, riabilitazione menisco, riabilitazione menischi, ginnastica posturale, esercizi posturali, postura corretta, mal di schiena, cervicalgia, dolore cervicale, dolori muscolari, dolori articolari, dolore cronico, dolori persistenti, teleriabilitazione, fisioterapia online, riabilitazione online, consulenza fisioterapica online, programmi di esercizi personalizzati, programmi riabilitativi, esercizi a distanza, preparazione atletica, preparazione atletica personalizzata, schede running, allenamento running, corsa, maratona, 10 km, ritorno allo sport, ritorno in campo, miglioramento performance, benessere fisico, crescita personale, osteopatia, approccio integrato, trattamento personalizzato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T17:07:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/\",\"name\":\"Dr. Lorenzo Degiovanni - Fisioterapista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg\",\"datePublished\":\"2026-03-23T16:28:45+00:00\",\"dateModified\":\"2026-03-24T17:07:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr. Lorenzo Degiovanni &#8211; Fisioterapista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Lorenzo Degiovanni - Fisioterapista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/","og_locale":"it_IT","og_type":"article","og_title":"Dr. Lorenzo Degiovanni - Fisioterapista - UIL Polizia","og_description":"Fisioterapista specializzato in riabilitazione sportiva e muscolo-scheletrica, laureato presso l\u2019Universit\u00e0 degli Studi di Torino. Integro terapia manuale, esercizio terapeutico personalizzato e ricondizionamento del gesto atletico per favorire un recupero efficace e duraturo. Appassionato di sport ed allenamenti credo nel movimento come strumento di salute, performance e crescita personale. Attualmente sto frequentando il master in osteopatia presso EOM Italia, per ampliare ulteriormente le mie competenze e offrire un approccio sempre pi\u00f9 completo alla persona. Aree di Intervento Fisioterapia Percorsi mirati dopo interventi ortopedici (legamenti, protesi, menischi) per un ritorno sicuro alla quotidianit\u00e0. Riabilitazione Sportiva Programmi specifici per atleti: dalla fase acuta dell'infortunio fino al ritorno in campo e al miglioramento della performance. Ginnastica Posturale Strategie moderne per il trattamento di mal di schiena, cervicalgia e dolori persistenti legati alla postura. Teleriabilitazione Online Consulenze e programmi di esercizi a distanza, monitorati costantemente per garantire risultati ovunque tu sia. Preparazione Atletica e Schede Running Dai primi 10 km alla maratona RIABILITAZIONE SPORTIVA \u2022 TERAPIA MANUALE \u2022 GINNASTICA POSTURALE \u2022 TELERIABILITAZIONE \u2022 PREVENZIONE  fisioterapia, fisioterapie, fisioterapista, fisioterapisti, riabilitazione, riabilitazioni, riabilitazione sportiva, riabilitazioni sportive, riabilitazione muscolo scheletrica, riabilitazioni muscolo scheletriche, terapia manuale, terapie manuali, esercizio terapeutico, esercizi terapeutici, ricondizionamento atletico, recupero funzionale, recuperi funzionali, recupero infortunio, recupero infortuni, prevenzione infortuni, prevenzione, performance sportiva, performance sportive, allenamento, allenamenti, movimento e salute, fisioterapia ortopedica, riabilitazione ortopedica, riabilitazione post intervento, riabilitazione post interventi, riabilitazione legamenti, riabilitazione protesi, riabilitazione menisco, riabilitazione menischi, ginnastica posturale, esercizi posturali, postura corretta, mal di schiena, cervicalgia, dolore cervicale, dolori muscolari, dolori articolari, dolore cronico, dolori persistenti, teleriabilitazione, fisioterapia online, riabilitazione online, consulenza fisioterapica online, programmi di esercizi personalizzati, programmi riabilitativi, esercizi a distanza, preparazione atletica, preparazione atletica personalizzata, schede running, allenamento running, corsa, maratona, 10 km, ritorno allo sport, ritorno in campo, miglioramento performance, benessere fisico, crescita personale, osteopatia, approccio integrato, trattamento personalizzato","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/","og_site_name":"UIL Polizia","article_modified_time":"2026-03-24T17:07:48+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/","name":"Dr. Lorenzo Degiovanni - Fisioterapista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg","datePublished":"2026-03-23T16:28:45+00:00","dateModified":"2026-03-24T17:07:48+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/03\/Logo-Dr-Degiovanni-Lorenzo.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-lorenzo-degiovanni-fisioterapista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dr. Lorenzo Degiovanni &#8211; Fisioterapista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/92908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=92908"}],"version-history":[{"count":16,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/92908\/revisions"}],"predecessor-version":[{"id":92939,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/92908\/revisions\/92939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/92909"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=92908"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=92908"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=92908"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=92908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}