{"id":87472,"date":"2026-01-28T22:50:21","date_gmt":"2026-01-28T21:50:21","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=87472"},"modified":"2026-01-29T12:33:50","modified_gmt":"2026-01-29T11:33:50","slug":"dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/","title":{"rendered":"Dott.ssa Gabriella Montanari &#8211; Psicologa clinica e forense, Criminologa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"87472\" class=\"elementor elementor-87472\">\n\t\t\t\t<div class=\"elementor-element elementor-element-262c4721 e-con-full e-flex e-con e-parent\" data-id=\"262c4721\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf3e23c elementor-widget elementor-widget-icon-box\" data-id=\"7bf3e23c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDott.ssa Gabriella Montanari\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPsicologa clinica e forense, Criminologa\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73b2af70 e-flex e-con-boxed e-con e-parent\" data-id=\"73b2af70\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e921bae e-con-full e-flex e-con e-child\" data-id=\"e921bae\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-39c25164 e-con-full e-flex e-con e-child\" data-id=\"39c25164\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-690ddf0a e-con-full e-flex e-con e-child\" data-id=\"690ddf0a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ebc7bcc elementor-widget elementor-widget-text-editor\" data-id=\"7ebc7bcc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>presentazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c776240 elementor-widget elementor-widget-text-editor\" data-id=\"c776240\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Sono la dott.ssa <\/span><span class=\"s2\"><b>Gabriella Montanari<\/b><\/span><span class=\"s1\">, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476).&nbsp;<\/span><\/p><p class=\"p1\"><span class=\"s1\">Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in <\/span><span class=\"s2\"><b>psicologia giuridica e criminologia<\/b><\/span><span class=\"s1\">, <\/span><span class=\"s2\"><b>criminologia penitenziaria<\/b><\/span><span class=\"s1\"> e <\/span><span class=\"s2\"><b>psicologia dell\u2019emergenza<\/b><\/span><span class=\"s1\">. Sono certificata come <\/span><span class=\"s2\"><b>Esperto in Psicologia delle Dipendenze<\/b><\/span><span class=\"s1\"> a livello internazionale. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La mia esperienza include <\/span><span class=\"s2\"><b>attivit\u00e0 clinica e psicodiagnostica privata<\/b><\/span><span class=\"s1\">, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come <\/span><span class=\"s2\"><b>consulente tecnico di parte (CTP)<\/b><\/span><span class=\"s1\"> in ambito civile e penale e un impegno costante nel volontariato, sia con <\/span><span class=\"s2\"><b>Croce Rossa Italiana<\/b><\/span><span class=\"s1\"> (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come <\/span><span class=\"s2\"><b>Progetto Itaca<\/b><\/span><span class=\"s1\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3eb3682d e-con-full e-flex e-con e-child\" data-id=\"3eb3682d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-261aad9b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"261aad9b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffa970c e-con-full e-flex e-con e-child\" data-id=\"ffa970c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-439fb085 e-con-full e-flex e-con e-child\" data-id=\"439fb085\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b1c824a elementor-widget elementor-widget-text-editor\" data-id=\"4b1c824a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Mi occupo di <\/span><span class=\"s2\"><b>et\u00e0 evolutiva e adulti<\/b><\/span><span class=\"s1\">, con particolare attenzione alle <\/span><span class=\"s2\"><b>dipendenze patologiche<\/b><\/span><span class=\"s1\"> (da sostanze, comportamentali, dipendenza affettiva), alle <\/span><span class=\"s2\"><b>difficolt\u00e0 emotive e relazionali<\/b><\/span><span class=\"s1\">\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle <\/span><span class=\"s2\"><b>problematiche\u00a0 legate ai comportamenti alimentari.<\/b><\/span><span class=\"s1\"> Offro percorsi di <\/span><span class=\"s2\"><b>sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi <\/b><\/span><span class=\"s1\">(parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia).<\/span><\/p><p class=\"p1\"><span class=\"s1\">Grazie alla mia formazione transculturale e alla conoscenza fluente di <\/span><span class=\"s2\"><b>francese e inglese<\/b><\/span><span class=\"s1\">, offro anche<\/span><span class=\"s2\"><b> colloqui di accoglienza e sostegno psicologico a cittadini stranieri,<\/b><\/span><span class=\"s1\"> con un approccio aperto e inclusivo.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Accolgo le persone con <\/span><span class=\"s2\"><b>empatia, ascolto attento e competenze scientifiche<\/b><\/span><span class=\"s1\">, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della <\/span><span class=\"s2\"><b>parola e dell&#8217;espressione artistica in generale\u00a0<\/b><\/span><span class=\"s1\">come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Il mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Quando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le <\/span><span class=\"s2\"><b>sedute in presenza<\/b><\/span><span class=\"s1\"> possono essere svolte in <\/span><span class=\"s2\"><b>spiaggia e in laguna<\/b><\/span><span class=\"s1\">, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0<\/span><\/p><p class=\"p1\"><span class=\"s1\">Se cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a240c8b e-con-full e-flex e-con e-child\" data-id=\"a240c8b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5d79c8f8 e-con-full e-flex e-con e-child\" data-id=\"5d79c8f8\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7350db48 e-con-full e-flex e-con e-child\" data-id=\"7350db48\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-483291ea elementor-widget elementor-widget-text-editor\" data-id=\"483291ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tServizi psicologici offerti:\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ee71875 elementor-widget__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5ee71875\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supporto psicologico per stress lavoro-correlato e prevenzione del burnout<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gestione di ansia, rabbia e disregolazione emotiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Attacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dipendenze patologiche (sostanze, comportamentali, affettive)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Elaborazione di eventi critici o traumatici<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sostegno nelle fasi di cambiamento professionale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supporto relazionale, di coppia e familiare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Valutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3002dea2 e-flex e-con-boxed e-con e-child\" data-id=\"3002dea2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7939adaf e-con-full e-flex e-con e-child\" data-id=\"7939adaf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee53ab0 elementor-widget elementor-widget-text-editor\" data-id=\"ee53ab0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bambini e adolescenti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3118d5 elementor-widget__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4f3118d5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ansia, paure e difficolt\u00e0 emotive<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Problemi comportamentali e scolastici, bullismo e cyberbullismo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Difficolt\u00e0 relazionali e ritiro sociale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Autolesionismo e disregolazione emotiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supporto nei contesti familiari complessi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bc123f4 e-flex e-con-boxed e-con e-parent\" data-id=\"1bc123f4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6309ec1a elementor-widget elementor-widget-text-editor\" data-id=\"6309ec1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-632f7f1b e-flex e-con-boxed e-con e-parent\" data-id=\"632f7f1b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-57b9e412 e-con-full e-flex e-con e-child\" data-id=\"57b9e412\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d09ff3b e-con-full e-flex e-con e-child\" data-id=\"1d09ff3b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:87493,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/foto-studio-3dottssa-gabriella-montanari.jpg&quot;},{&quot;id&quot;:87494,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/foto-studio-1dottssa-gabriella-montanari.jpg&quot;},{&quot;id&quot;:87495,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/20260124_111213dottssa-gabriella-montanari-scaled-1.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e40338d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5e40338d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1d3c4f e-con-full e-flex e-con e-child\" data-id=\"a1d3c4f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-209a7d65 e-con-full e-flex e-con e-child\" data-id=\"209a7d65\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2149248c elementor-widget elementor-widget-text-editor\" data-id=\"2149248c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti e orari\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78e9ad0f elementor-widget elementor-widget-icon-box\" data-id=\"78e9ad0f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDott.ssa Gabriella Montanari\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34e2e024 e-con-full e-flex e-con e-child\" data-id=\"34e2e024\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53a456ed elementor-widget elementor-widget-text-editor\" data-id=\"53a456ed\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><strong>Effettuo anche sedute da remoto<\/strong><\/em><\/p>\n<p>Viale dei Fiori, 29 &#8211; 48123 Ravenna<br>Cell:<a href=\"tel:+393393391518238\" target=\"_blank\" rel=\"noopener\">&nbsp;339 1518238<\/a><br>Mail: <a href=\"mailto:montanarigab@gmail.com\" target=\"_blank\" rel=\"noopener\">montanarigab@gmail.com<\/a><br>PEC: <a href=\"mailto:montanarigabriella@psypec.it\" target=\"_blank\" rel=\"noopener\">montanarigabriella@psypec.it<\/a><\/p>\n<p><em>Ricevo solo previo appuntamento<\/em><br>Luned\u00ec-venerd\u00ec: 8.30 &#8211; 19.30<br>Sabato mattina<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d182dfa e-con-full e-flex e-con e-child\" data-id=\"2d182dfa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60e5a283 elementor-widget elementor-widget-text-editor\" data-id=\"60e5a283\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-159\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-159\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-159\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-159\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-159\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"159\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2403195f elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2403195f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f85f96b\" data-id=\"1f85f96b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-457155e7 elementor-widget elementor-widget-text-editor\" data-id=\"457155e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3621ed8f elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3621ed8f\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-208a4c5f\" data-id=\"208a4c5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e5f30c8 elementor-widget elementor-widget-text-editor\" data-id=\"7e5f30c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-416\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"87472\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-416\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-416\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-416\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-416\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"416\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-611177d6 elementor-widget elementor-widget-text-editor\" data-id=\"611177d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-111\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-111\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-111\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-111\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-111\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"111\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-61d5e718 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"61d5e718\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d24d69b elementor-widget elementor-widget-text-editor\" data-id=\"6d24d69b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSono la dott.ssa Gabriella Montanari, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476). Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in psicologia giuridica e criminologia, criminologia penitenziaria e psicologia dell\u2019emergenza. Sono certificata come Esperto in Psicologia delle Dipendenze a livello internazionale. \nLa mia esperienza include attivit\u00e0 clinica e psicodiagnostica privata, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come consulente tecnico di parte (CTP) in ambito civile e penale e un impegno costante nel volontariato, sia con Croce Rossa Italiana (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come Progetto Itaca.\nMi occupo di et\u00e0 evolutiva e adulti, con particolare attenzione alle dipendenze patologiche (da sostanze, comportamentali, dipendenza affettiva), alle difficolt\u00e0 emotive e relazionali\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle problematiche\u00a0 legate ai comportamenti alimentari. Offro percorsi di sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi (parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia).\nGrazie alla mia formazione transculturale e alla conoscenza fluente di francese e inglese, offro anche colloqui di accoglienza e sostegno psicologico a cittadini stranieri, con un approccio aperto e inclusivo.\nAccolgo le persone con empatia, ascolto attento e competenze scientifiche, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della parola e dell&#8217;espressione artistica in generale\u00a0come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica.\nIl mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari.\nQuando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le sedute in presenza possono essere svolte in spiaggia e in laguna, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0\nSe cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.\n\nServizi psicologici offerti:\n\nSupporto psicologico per stress lavoro-correlato e prevenzione del burnout\nGestione di ansia, rabbia e disregolazione emotiva\nAttacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0\nDipendenze patologiche (sostanze, comportamentali, affettive)\nElaborazione di eventi critici o traumatici\nSostegno nelle fasi di cambiamento professionale\nSupporto relazionale, di coppia e familiare\nValutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale\n\nBambini e adolescenti\nAnsia, paure e difficolt\u00e0 emotive\nProblemi comportamentali e scolastici, bullismo e cyberbullismo\nDifficolt\u00e0 relazionali e ritiro sociale\nAutolesionismo e disregolazione emotiva\nSupporto nei contesti familiari complessi\n\n\nPsicologo, psicologi, psicologa, psicologhe, supporto psicologico, sostegno psicologico, percorso psicologico, psicologa clinica, psicologa forense, psicologia giuridica, criminologia, criminologia penitenziaria, psicologia dell&#8217;emergenza, psicologia delle dipendenze, dipendenze patologiche, supporto psicologico, ansia, stress, gestione emozioni, rabbia, stress lavoro-correlato, burnout, attacchi di panico, umore, comportamenti alimentari, ossessioni, compulsioni, personalit\u00e0, consultazioni tecniche, assistenza giuridica, supporto famigliare, sostegno coppie, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, ritiro sociale, autolesionismo, elaborazione traumi, lutti, dipendenze affettive, parent training, competenze genitoriali, abbandono scolastico, bullismo, cyberbullismo, salute mentale, supporto adolescenti, consulenze tecniche forensi, colloqui transculturali, sostegno stranieri, approccio inclusivo, psicoterapia in natura, supporto professionale effettuato in spiaggia, Ravenna, Sedute psicologiche online, psicologo online, psicologi online, percorso psicologico online, colloqui psicologo online, psicologa online, psicologi online, sostegno psicologico online,\n\nPsicologo Ravenna, psicologi Ravenna, psicologa Ravenna, psicologhe Ravenna, supporto psicologico Ravenna, sostegno psicologico Ravenna, percorso psicologico Ravenna, psicologa clinica Ravenna, psicologa forense Ravenna, psicologia giuridica Ravenna, criminologia Ravenna, criminologia penitenziaria Ravenna, psicologia dell&#8217;emergenza Ravenna, psicologia delle dipendenze Ravenna, dipendenze patologiche Ravenna, supporto psicologico Ravenna, ansia Ravenna, stress Ravenna, gestione emozioni Ravenna, rabbia Ravenna, stress lavoro-correlato Ravenna, burnout Ravenna, attacchi di panico Ravenna, umore Ravenna, comportamenti alimentari Ravenna, ossessioni Ravenna, compulsioni Ravenna, personalit\u00e0 Ravenna, consultazioni tecniche Ravenna, assistenza giuridica Ravenna, supporto famigliare Ravenna, sostegno coppie Ravenna, difficolt\u00e0 emotive Ravenna, difficolt\u00e0 relazionali Ravenna, ritiro sociale Ravenna, autolesionismo Ravenna, elaborazione traumi Ravenna, lutti Ravenna, dipendenze affettive Ravenna, parent training Ravenna, competenze genitoriali Ravenna, abbandono scolastico Ravenna, bullismo Ravenna, cyberbullismo Ravenna, salute mentale Ravenna, supporto adolescenti Ravenna, consulenze tecniche forensi Ravenna, colloqui transculturali Ravenna, sostegno stranieri Ravenna, approccio inclusivo Ravenna, psicoterapia in natura Ravenna, supporto professionale effettuato in spiaggia Ravenna, \n\nPsicologo a Ravenna, psicologi a Ravenna, psicologa a Ravenna, psicologhe a Ravenna, supporto psicologico a Ravenna, sostegno psicologico a Ravenna, percorso psicologico a Ravenna, psicologa clinica a Ravenna, psicologa forense a Ravenna, psicologia giuridica a Ravenna, criminologia a Ravenna, criminologia penitenziaria a Ravenna, psicologia dell&#8217;emergenza a Ravenna, psicologia delle dipendenze a Ravenna, dipendenze patologiche a Ravenna, supporto psicologico a Ravenna, ansia a Ravenna, stress a Ravenna, gestione emozioni a Ravenna, rabbia a Ravenna, stress lavoro-correlato a Ravenna, burnout a Ravenna, attacchi di panico a Ravenna, umore a Ravenna, comportamenti alimentari a Ravenna, ossessioni a Ravenna, compulsioni a Ravenna, personalit\u00e0 a Ravenna, consultazioni tecniche a Ravenna, assistenza giuridica a Ravenna, supporto famigliare a Ravenna, sostegno coppie a Ravenna, difficolt\u00e0 emotive a Ravenna, difficolt\u00e0 relazionali a Ravenna, ritiro sociale a Ravenna, autolesionismo a Ravenna, elaborazione traumi a Ravenna, lutti a Ravenna, dipendenze affettive a Ravenna, parent training a Ravenna, competenze genitoriali a Ravenna, abbandono scolastico a Ravenna, bullismo a Ravenna, cyberbullismo a Ravenna, salute mentale a Ravenna, supporto adolescenti a Ravenna, consulenze tecniche forensi a Ravenna, colloqui transculturali a Ravenna, sostegno stranieri a Ravenna, approccio inclusivo a Ravenna, psicoterapia in natura a Ravenna, supporto professionale effettuato in spiaggia a Ravenna, \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ddf4daf e-con-full e-flex e-con e-parent\" data-id=\"1ddf4daf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27cb5cf5 elementor-widget elementor-widget-icon-box\" data-id=\"27cb5cf5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDott.ssa Gabriella Montanari\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPsicologa clinica e forense, Criminologa\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-539f5b6d e-flex e-con-boxed e-con e-parent\" data-id=\"539f5b6d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3bcb25fc e-con-full e-flex e-con e-child\" data-id=\"3bcb25fc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-403256b8 e-con-full e-flex e-con e-child\" data-id=\"403256b8\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-38933775 e-con-full e-flex e-con e-child\" data-id=\"38933775\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e6f453c elementor-widget elementor-widget-text-editor\" data-id=\"6e6f453c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>presentazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4605c1d6 elementor-widget elementor-widget-text-editor\" data-id=\"4605c1d6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Sono la dott.ssa <\/span><span class=\"s2\"><b>Gabriella Montanari<\/b><\/span><span class=\"s1\">, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476).&nbsp;<\/span><\/p><p class=\"p1\"><span class=\"s1\">Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in <\/span><span class=\"s2\"><b>psicologia giuridica e criminologia<\/b><\/span><span class=\"s1\">, <\/span><span class=\"s2\"><b>criminologia penitenziaria<\/b><\/span><span class=\"s1\"> e <\/span><span class=\"s2\"><b>psicologia dell\u2019emergenza<\/b><\/span><span class=\"s1\">. Sono certificata come <\/span><span class=\"s2\"><b>Esperto in Psicologia delle Dipendenze<\/b><\/span><span class=\"s1\"> a livello internazionale. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La mia esperienza include <\/span><span class=\"s2\"><b>attivit\u00e0 clinica e psicodiagnostica privata<\/b><\/span><span class=\"s1\">, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come <\/span><span class=\"s2\"><b>consulente tecnico di parte (CTP)<\/b><\/span><span class=\"s1\"> in ambito civile e penale e un impegno costante nel volontariato, sia con <\/span><span class=\"s2\"><b>Croce Rossa Italiana<\/b><\/span><span class=\"s1\"> (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come <\/span><span class=\"s2\"><b>Progetto Itaca<\/b><\/span><span class=\"s1\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d801333 e-con-full e-flex e-con e-child\" data-id=\"5d801333\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16f4bf2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16f4bf2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a6f1e10 e-con-full e-flex e-con e-child\" data-id=\"3a6f1e10\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4dfec1a3 e-con-full e-flex e-con e-child\" data-id=\"4dfec1a3\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79d1f58 elementor-widget elementor-widget-text-editor\" data-id=\"79d1f58\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Mi occupo di <\/span><span class=\"s2\"><b>et\u00e0 evolutiva e adulti<\/b><\/span><span class=\"s1\">, con particolare attenzione alle <\/span><span class=\"s2\"><b>dipendenze patologiche<\/b><\/span><span class=\"s1\"> (da sostanze, comportamentali, dipendenza affettiva), alle <\/span><span class=\"s2\"><b>difficolt\u00e0 emotive e relazionali<\/b><\/span><span class=\"s1\">\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle <\/span><span class=\"s2\"><b>problematiche\u00a0 legate ai comportamenti alimentari.<\/b><\/span><span class=\"s1\"> Offro percorsi di <\/span><span class=\"s2\"><b>sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi <\/b><\/span><span class=\"s1\">(parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia).<\/span><\/p><p class=\"p1\"><span class=\"s1\">Grazie alla mia formazione transculturale e alla conoscenza fluente di <\/span><span class=\"s2\"><b>francese e inglese<\/b><\/span><span class=\"s1\">, offro anche<\/span><span class=\"s2\"><b> colloqui di accoglienza e sostegno psicologico a cittadini stranieri,<\/b><\/span><span class=\"s1\"> con un approccio aperto e inclusivo.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Accolgo le persone con <\/span><span class=\"s2\"><b>empatia, ascolto attento e competenze scientifiche<\/b><\/span><span class=\"s1\">, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della <\/span><span class=\"s2\"><b>parola e dell&#8217;espressione artistica in generale\u00a0<\/b><\/span><span class=\"s1\">come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Il mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Quando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le <\/span><span class=\"s2\"><b>sedute in presenza<\/b><\/span><span class=\"s1\"> possono essere svolte in <\/span><span class=\"s2\"><b>spiaggia e in laguna<\/b><\/span><span class=\"s1\">, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0<\/span><\/p><p class=\"p1\"><span class=\"s1\">Se cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7aea6e65 e-con-full e-flex e-con e-child\" data-id=\"7aea6e65\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-376e5571 e-con-full e-flex e-con e-child\" data-id=\"376e5571\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d65decc e-con-full e-flex e-con e-child\" data-id=\"3d65decc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-716078bf elementor-widget elementor-widget-text-editor\" data-id=\"716078bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tServizi psicologici offerti:\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-373ff5ad elementor-widget__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"373ff5ad\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supporto psicologico per stress lavoro-correlato e prevenzione del burnout<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gestione di ansia, rabbia e disregolazione emotiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Attacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dipendenze patologiche (sostanze, comportamentali, affettive)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Elaborazione di eventi critici o traumatici<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sostegno nelle fasi di cambiamento professionale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supporto relazionale, di coppia e familiare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Valutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-186f7806 e-flex e-con-boxed e-con e-child\" data-id=\"186f7806\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2ae6d016 e-con-full e-flex e-con e-child\" data-id=\"2ae6d016\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4e1912 elementor-widget elementor-widget-text-editor\" data-id=\"7d4e1912\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bambini e adolescenti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-256c1aee elementor-widget__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"256c1aee\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ansia, paure e difficolt\u00e0 emotive<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Problemi comportamentali e scolastici, bullismo e cyberbullismo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Difficolt\u00e0 relazionali e ritiro sociale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Autolesionismo e disregolazione emotiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supporto nei contesti familiari complessi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d26bbd1 e-flex e-con-boxed e-con e-parent\" data-id=\"7d26bbd1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-389721dd elementor-widget elementor-widget-text-editor\" data-id=\"389721dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a8eb629 e-flex e-con-boxed e-con e-parent\" data-id=\"6a8eb629\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65ccdd1c e-con-full e-flex e-con e-child\" data-id=\"65ccdd1c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-66608202 e-con-full e-flex e-con e-child\" data-id=\"66608202\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:87493,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/foto-studio-3dottssa-gabriella-montanari.jpg&quot;},{&quot;id&quot;:87494,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/foto-studio-1dottssa-gabriella-montanari.jpg&quot;},{&quot;id&quot;:87495,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/20260124_111213dottssa-gabriella-montanari-scaled-1.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b0e013d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4b0e013d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7032bd91 e-con-full e-flex e-con e-child\" data-id=\"7032bd91\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-637ade6b e-con-full e-flex e-con e-child\" data-id=\"637ade6b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7be1f2ec elementor-widget elementor-widget-text-editor\" data-id=\"7be1f2ec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti e orari\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737c3fe elementor-widget elementor-widget-icon-box\" data-id=\"737c3fe\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDott.ssa Gabriella Montanari\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f7f1f85 e-con-full e-flex e-con e-child\" data-id=\"7f7f1f85\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31ea9aaf elementor-widget elementor-widget-text-editor\" data-id=\"31ea9aaf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><strong>Effettuo anche sedute da remoto<\/strong><\/em><\/p><p>Viale dei Fiori, 29 &#8211; 48123 Ravenna<br \/>Cell: <a href=\"tel:+393393391518238\" target=\"_blank\" rel=\"noopener\">339 3391518238<\/a><br \/>Mail: <a href=\"mailto:montanarigab@gmail.com\" target=\"_blank\" rel=\"noopener\">montanarigab@gmail.com<\/a><br \/>PEC: <a href=\"mailto:montanarigabriella@psypec.it\" target=\"_blank\" rel=\"noopener\">montanarigabriella@psypec.it<\/a><\/p><p><em>Ricevo solo previo appuntamento<\/em><br \/>Luned\u00ec-venerd\u00ec: 8.30 &#8211; 19.30<br \/>Sabato mattina<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-710bae4e e-con-full e-flex e-con e-child\" data-id=\"710bae4e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c9acf3f elementor-widget elementor-widget-text-editor\" data-id=\"6c9acf3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-211\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-211\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-211\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-211\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-211\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"211\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b323ab6 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b323ab6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3483c504\" data-id=\"3483c504\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d9b54c5 elementor-widget elementor-widget-text-editor\" data-id=\"5d9b54c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6846def8 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"6846def8\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25dffa5a\" data-id=\"25dffa5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5388cb6a elementor-widget elementor-widget-text-editor\" data-id=\"5388cb6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-141\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"87472\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-141\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-141\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-141\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-141\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"141\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a7cc2fe elementor-widget elementor-widget-text-editor\" data-id=\"3a7cc2fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-482\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-482\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-482\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-482\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-482\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"482\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-5186448f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"5186448f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55bc6790 elementor-widget elementor-widget-text-editor\" data-id=\"55bc6790\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSono la dott.ssa Gabriella Montanari, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476). Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in psicologia giuridica e criminologia, criminologia penitenziaria e psicologia dell\u2019emergenza. Sono certificata come Esperto in Psicologia delle Dipendenze a livello internazionale. \nLa mia esperienza include attivit\u00e0 clinica e psicodiagnostica privata, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come consulente tecnico di parte (CTP) in ambito civile e penale e un impegno costante nel volontariato, sia con Croce Rossa Italiana (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come Progetto Itaca.\nMi occupo di et\u00e0 evolutiva e adulti, con particolare attenzione alle dipendenze patologiche (da sostanze, comportamentali, dipendenza affettiva), alle difficolt\u00e0 emotive e relazionali\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle problematiche\u00a0 legate ai comportamenti alimentari. Offro percorsi di sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi (parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia).\nGrazie alla mia formazione transculturale e alla conoscenza fluente di francese e inglese, offro anche colloqui di accoglienza e sostegno psicologico a cittadini stranieri, con un approccio aperto e inclusivo.\nAccolgo le persone con empatia, ascolto attento e competenze scientifiche, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della parola e dell&#8217;espressione artistica in generale\u00a0come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica.\nIl mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari.\nQuando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le sedute in presenza possono essere svolte in spiaggia e in laguna, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0\nSe cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.\n\nServizi psicologici offerti:\n\nSupporto psicologico per stress lavoro-correlato e prevenzione del burnout\nGestione di ansia, rabbia e disregolazione emotiva\nAttacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0\nDipendenze patologiche (sostanze, comportamentali, affettive)\nElaborazione di eventi critici o traumatici\nSostegno nelle fasi di cambiamento professionale\nSupporto relazionale, di coppia e familiare\nValutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale\n\nBambini e adolescenti\nAnsia, paure e difficolt\u00e0 emotive\nProblemi comportamentali e scolastici, bullismo e cyberbullismo\nDifficolt\u00e0 relazionali e ritiro sociale\nAutolesionismo e disregolazione emotiva\nSupporto nei contesti familiari complessi\n\n\nPsicologo, psicologi, psicologa, psicologhe, supporto psicologico, sostegno psicologico, percorso psicologico, psicologa clinica, psicologa forense, psicologia giuridica, criminologia, criminologia penitenziaria, psicologia dell&#8217;emergenza, psicologia delle dipendenze, dipendenze patologiche, supporto psicologico, ansia, stress, gestione emozioni, rabbia, stress lavoro-correlato, burnout, attacchi di panico, umore, comportamenti alimentari, ossessioni, compulsioni, personalit\u00e0, consultazioni tecniche, assistenza giuridica, supporto famigliare, sostegno coppie, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, ritiro sociale, autolesionismo, elaborazione traumi, lutti, dipendenze affettive, parent training, competenze genitoriali, abbandono scolastico, bullismo, cyberbullismo, salute mentale, supporto adolescenti, consulenze tecniche forensi, colloqui transculturali, sostegno stranieri, approccio inclusivo, psicoterapia in natura, supporto professionale effettuato in spiaggia, Ravenna, Sedute psicologiche online, psicologo online, psicologi online, percorso psicologico online, colloqui psicologo online, psicologa online, psicologi online, sostegno psicologico online,\n\nPsicologo Ravenna, psicologi Ravenna, psicologa Ravenna, psicologhe Ravenna, supporto psicologico Ravenna, sostegno psicologico Ravenna, percorso psicologico Ravenna, psicologa clinica Ravenna, psicologa forense Ravenna, psicologia giuridica Ravenna, criminologia Ravenna, criminologia penitenziaria Ravenna, psicologia dell&#8217;emergenza Ravenna, psicologia delle dipendenze Ravenna, dipendenze patologiche Ravenna, supporto psicologico Ravenna, ansia Ravenna, stress Ravenna, gestione emozioni Ravenna, rabbia Ravenna, stress lavoro-correlato Ravenna, burnout Ravenna, attacchi di panico Ravenna, umore Ravenna, comportamenti alimentari Ravenna, ossessioni Ravenna, compulsioni Ravenna, personalit\u00e0 Ravenna, consultazioni tecniche Ravenna, assistenza giuridica Ravenna, supporto famigliare Ravenna, sostegno coppie Ravenna, difficolt\u00e0 emotive Ravenna, difficolt\u00e0 relazionali Ravenna, ritiro sociale Ravenna, autolesionismo Ravenna, elaborazione traumi Ravenna, lutti Ravenna, dipendenze affettive Ravenna, parent training Ravenna, competenze genitoriali Ravenna, abbandono scolastico Ravenna, bullismo Ravenna, cyberbullismo Ravenna, salute mentale Ravenna, supporto adolescenti Ravenna, consulenze tecniche forensi Ravenna, colloqui transculturali Ravenna, sostegno stranieri Ravenna, approccio inclusivo Ravenna, psicoterapia in natura Ravenna, supporto professionale effettuato in spiaggia Ravenna, \n\nPsicologo a Ravenna, psicologi a Ravenna, psicologa a Ravenna, psicologhe a Ravenna, supporto psicologico a Ravenna, sostegno psicologico a Ravenna, percorso psicologico a Ravenna, psicologa clinica a Ravenna, psicologa forense a Ravenna, psicologia giuridica a Ravenna, criminologia a Ravenna, criminologia penitenziaria a Ravenna, psicologia dell&#8217;emergenza a Ravenna, psicologia delle dipendenze a Ravenna, dipendenze patologiche a Ravenna, supporto psicologico a Ravenna, ansia a Ravenna, stress a Ravenna, gestione emozioni a Ravenna, rabbia a Ravenna, stress lavoro-correlato a Ravenna, burnout a Ravenna, attacchi di panico a Ravenna, umore a Ravenna, comportamenti alimentari a Ravenna, ossessioni a Ravenna, compulsioni a Ravenna, personalit\u00e0 a Ravenna, consultazioni tecniche a Ravenna, assistenza giuridica a Ravenna, supporto famigliare a Ravenna, sostegno coppie a Ravenna, difficolt\u00e0 emotive a Ravenna, difficolt\u00e0 relazionali a Ravenna, ritiro sociale a Ravenna, autolesionismo a Ravenna, elaborazione traumi a Ravenna, lutti a Ravenna, dipendenze affettive a Ravenna, parent training a Ravenna, competenze genitoriali a Ravenna, abbandono scolastico a Ravenna, bullismo a Ravenna, cyberbullismo a Ravenna, salute mentale a Ravenna, supporto adolescenti a Ravenna, consulenze tecniche forensi a Ravenna, colloqui transculturali a Ravenna, sostegno stranieri a Ravenna, approccio inclusivo a Ravenna, psicoterapia in natura a Ravenna, supporto professionale effettuato in spiaggia a Ravenna, \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display:none\">\n<p>Sono la dott.ssa Gabriella Montanari, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476). Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in psicologia giuridica e criminologia, criminologia penitenziaria e psicologia dell\u2019emergenza. Sono certificata come Esperto in Psicologia delle Dipendenze a livello internazionale.<br \/>\nLa mia esperienza include attivit\u00e0 clinica e psicodiagnostica privata, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come consulente tecnico di parte (CTP) in ambito civile e penale e un impegno costante nel volontariato, sia con Croce Rossa Italiana (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come Progetto Itaca.<br \/>\nMi occupo di et\u00e0 evolutiva e adulti, con particolare attenzione alle dipendenze patologiche (da sostanze, comportamentali, dipendenza affettiva), alle difficolt\u00e0 emotive e relazionali\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle problematiche\u00a0 legate ai comportamenti alimentari. Offro percorsi di sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi (parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia).<br \/>\nGrazie alla mia formazione transculturale e alla conoscenza fluente di francese e inglese, offro anche colloqui di accoglienza e sostegno psicologico a cittadini stranieri, con un approccio aperto e inclusivo.<br \/>\nAccolgo le persone con empatia, ascolto attento e competenze scientifiche, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della parola e dell&#8217;espressione artistica in generale\u00a0come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica.<br \/>\nIl mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari.<br \/>\nQuando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le sedute in presenza possono essere svolte in spiaggia e in laguna, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0<br \/>\nSe cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.<\/p>\n<p>Servizi psicologici offerti:<\/p>\n<p>Supporto psicologico per stress lavoro-correlato e prevenzione del burnout<br \/>\nGestione di ansia, rabbia e disregolazione emotiva<br \/>\nAttacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0<br \/>\nDipendenze patologiche (sostanze, comportamentali, affettive)<br \/>\nElaborazione di eventi critici o traumatici<br \/>\nSostegno nelle fasi di cambiamento professionale<br \/>\nSupporto relazionale, di coppia e familiare<br \/>\nValutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale<\/p>\n<p>Bambini e adolescenti<br \/>\nAnsia, paure e difficolt\u00e0 emotive<br \/>\nProblemi comportamentali e scolastici, bullismo e cyberbullismo<br \/>\nDifficolt\u00e0 relazionali e ritiro sociale<br \/>\nAutolesionismo e disregolazione emotiva<br \/>\nSupporto nei contesti familiari complessi<\/p>\n<p>Psicologo, psicologi, psicologa, psicologhe, supporto psicologico, sostegno psicologico, percorso psicologico, psicologa clinica, psicologa forense, psicologia giuridica, criminologia, criminologia penitenziaria, psicologia dell&#8217;emergenza, psicologia delle dipendenze, dipendenze patologiche, supporto psicologico, ansia, stress, gestione emozioni, rabbia, stress lavoro-correlato, burnout, attacchi di panico, umore, comportamenti alimentari, ossessioni, compulsioni, personalit\u00e0, consultazioni tecniche, assistenza giuridica, supporto famigliare, sostegno coppie, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, ritiro sociale, autolesionismo, elaborazione traumi, lutti, dipendenze affettive, parent training, competenze genitoriali, abbandono scolastico, bullismo, cyberbullismo, salute mentale, supporto adolescenti, consulenze tecniche forensi, colloqui transculturali, sostegno stranieri, approccio inclusivo, psicoterapia in natura, supporto professionale effettuato in spiaggia, Ravenna, Sedute psicologiche online, psicologo online, psicologi online, percorso psicologico online, colloqui psicologo online, psicologa online, psicologi online, sostegno psicologico online,<\/p>\n<p>Psicologo Ravenna, psicologi Ravenna, psicologa Ravenna, psicologhe Ravenna, supporto psicologico Ravenna, sostegno psicologico Ravenna, percorso psicologico Ravenna, psicologa clinica Ravenna, psicologa forense Ravenna, psicologia giuridica Ravenna, criminologia Ravenna, criminologia penitenziaria Ravenna, psicologia dell&#8217;emergenza Ravenna, psicologia delle dipendenze Ravenna, dipendenze patologiche Ravenna, supporto psicologico Ravenna, ansia Ravenna, stress Ravenna, gestione emozioni Ravenna, rabbia Ravenna, stress lavoro-correlato Ravenna, burnout Ravenna, attacchi di panico Ravenna, umore Ravenna, comportamenti alimentari Ravenna, ossessioni Ravenna, compulsioni Ravenna, personalit\u00e0 Ravenna, consultazioni tecniche Ravenna, assistenza giuridica Ravenna, supporto famigliare Ravenna, sostegno coppie Ravenna, difficolt\u00e0 emotive Ravenna, difficolt\u00e0 relazionali Ravenna, ritiro sociale Ravenna, autolesionismo Ravenna, elaborazione traumi Ravenna, lutti Ravenna, dipendenze affettive Ravenna, parent training Ravenna, competenze genitoriali Ravenna, abbandono scolastico Ravenna, bullismo Ravenna, cyberbullismo Ravenna, salute mentale Ravenna, supporto adolescenti Ravenna, consulenze tecniche forensi Ravenna, colloqui transculturali Ravenna, sostegno stranieri Ravenna, approccio inclusivo Ravenna, psicoterapia in natura Ravenna, supporto professionale effettuato in spiaggia Ravenna, <\/p>\n<p>Psicologo a Ravenna, psicologi a Ravenna, psicologa a Ravenna, psicologhe a Ravenna, supporto psicologico a Ravenna, sostegno psicologico a Ravenna, percorso psicologico a Ravenna, psicologa clinica a Ravenna, psicologa forense a Ravenna, psicologia giuridica a Ravenna, criminologia a Ravenna, criminologia penitenziaria a Ravenna, psicologia dell&#8217;emergenza a Ravenna, psicologia delle dipendenze a Ravenna, dipendenze patologiche a Ravenna, supporto psicologico a Ravenna, ansia a Ravenna, stress a Ravenna, gestione emozioni a Ravenna, rabbia a Ravenna, stress lavoro-correlato a Ravenna, burnout a Ravenna, attacchi di panico a Ravenna, umore a Ravenna, comportamenti alimentari a Ravenna, ossessioni a Ravenna, compulsioni a Ravenna, personalit\u00e0 a Ravenna, consultazioni tecniche a Ravenna, assistenza giuridica a Ravenna, supporto famigliare a Ravenna, sostegno coppie a Ravenna, difficolt\u00e0 emotive a Ravenna, difficolt\u00e0 relazionali a Ravenna, ritiro sociale a Ravenna, autolesionismo a Ravenna, elaborazione traumi a Ravenna, lutti a Ravenna, dipendenze affettive a Ravenna, parent training a Ravenna, competenze genitoriali a Ravenna, abbandono scolastico a Ravenna, bullismo a Ravenna, cyberbullismo a Ravenna, salute mentale a Ravenna, supporto adolescenti a Ravenna, consulenze tecniche forensi a Ravenna, colloqui transculturali a Ravenna, sostegno stranieri a Ravenna, approccio inclusivo a Ravenna, psicoterapia in natura a Ravenna, supporto professionale effettuato in spiaggia a Ravenna, <\/p>\n<\/div>\n","protected":false},"featured_media":87525,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,163],"product_tag":[3394,1585,16968,16961,1560,4513,2713,14754,16971,16966,16964,16957,16958,16965,16960,1929,16953,3845,5852,2705,3179,3178,10083,15414,2581,3814,3120,5847,14136,16959,353,658,16952,12018,1136,460,12020,16954,16955,3855,516,13263,16969,6666,601,3392,1362,13264,16963,1499,15424,16967,1675,16956,14793,16962,16970,1123,13624],"class_list":{"0":"post-87472","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-salute","8":"product_tag-abbandono-scolastico","9":"product_tag-ansia","10":"product_tag-approccio-inclusivo","11":"product_tag-assistenza-giuridica","12":"product_tag-attacchi-di-panico","13":"product_tag-autolesionismo","14":"product_tag-bullismo","15":"product_tag-burnout","16":"product_tag-colloqui-psicologo-online","17":"product_tag-colloqui-transculturali","18":"product_tag-competenze-genitoriali","19":"product_tag-comportamenti-alimentari","20":"product_tag-compulsioni","21":"product_tag-consulenze-tecniche-forensi","22":"product_tag-consultazioni-tecniche","23":"product_tag-criminologia","24":"product_tag-criminologia-penitenziaria","25":"product_tag-cyberbullismo","26":"product_tag-difficolta-emotive","27":"product_tag-difficolta-relazionali","28":"product_tag-dipendenze-affettive","29":"product_tag-dipendenze-patologiche","30":"product_tag-elaborazione-traumi","31":"product_tag-gestione-emozioni","32":"product_tag-lutti","33":"product_tag-ossessioni","34":"product_tag-parent-training","35":"product_tag-percorso-psicologico","36":"product_tag-percorso-psicologico-online","37":"product_tag-personalita","38":"product_tag-psicologa","39":"product_tag-psicologa-clinica","40":"product_tag-psicologa-forense","41":"product_tag-psicologa-online","42":"product_tag-psicologhe","43":"product_tag-psicologi","44":"product_tag-psicologi-online","45":"product_tag-psicologia-dellemergenza","46":"product_tag-psicologia-delle-dipendenze","47":"product_tag-psicologia-giuridica","48":"product_tag-psicologo","49":"product_tag-psicologo-online","50":"product_tag-psicoterapia-in-natura","51":"product_tag-rabbia","52":"product_tag-ravenna","53":"product_tag-ritiro-sociale","54":"product_tag-salute-mentale","55":"product_tag-sedute-psicologiche-online","56":"product_tag-sostegno-coppie","57":"product_tag-sostegno-psicologico","58":"product_tag-sostegno-psicologico-online","59":"product_tag-sostegno-stranieri","60":"product_tag-stress","61":"product_tag-stress-lavoro-correlato","62":"product_tag-supporto-adolescenti","63":"product_tag-supporto-famigliare","64":"product_tag-supporto-professionale-effettuato-in-spiaggia","65":"product_tag-supporto-psicologico","66":"product_tag-umore","68":"first","69":"instock","70":"shipping-taxable","71":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Gabriella Montanari - Psicologa clinica e forense, Criminologa - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Gabriella Montanari - Psicologa clinica e forense, Criminologa - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono la dott.ssa Gabriella Montanari, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476). Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in psicologia giuridica e criminologia, criminologia penitenziaria e psicologia dell\u2019emergenza. Sono certificata come Esperto in Psicologia delle Dipendenze a livello internazionale.  La mia esperienza include attivit\u00e0 clinica e psicodiagnostica privata, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come consulente tecnico di parte (CTP) in ambito civile e penale e un impegno costante nel volontariato, sia con Croce Rossa Italiana (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come Progetto Itaca. Mi occupo di et\u00e0 evolutiva e adulti, con particolare attenzione alle dipendenze patologiche (da sostanze, comportamentali, dipendenza affettiva), alle difficolt\u00e0 emotive e relazionali\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle problematiche\u00a0 legate ai comportamenti alimentari. Offro percorsi di sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi (parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia). Grazie alla mia formazione transculturale e alla conoscenza fluente di francese e inglese, offro anche colloqui di accoglienza e sostegno psicologico a cittadini stranieri, con un approccio aperto e inclusivo. Accolgo le persone con empatia, ascolto attento e competenze scientifiche, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della parola e dell&#039;espressione artistica in generale\u00a0come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica. Il mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari. Quando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le sedute in presenza possono essere svolte in spiaggia e in laguna, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0 Se cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.  Servizi psicologici offerti:  Supporto psicologico per stress lavoro-correlato e prevenzione del burnout Gestione di ansia, rabbia e disregolazione emotiva Attacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0 Dipendenze patologiche (sostanze, comportamentali, affettive) Elaborazione di eventi critici o traumatici Sostegno nelle fasi di cambiamento professionale Supporto relazionale, di coppia e familiare Valutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale  Bambini e adolescenti Ansia, paure e difficolt\u00e0 emotive Problemi comportamentali e scolastici, bullismo e cyberbullismo Difficolt\u00e0 relazionali e ritiro sociale Autolesionismo e disregolazione emotiva Supporto nei contesti familiari complessi   Psicologo, psicologi, psicologa, psicologhe, supporto psicologico, sostegno psicologico, percorso psicologico, psicologa clinica, psicologa forense, psicologia giuridica, criminologia, criminologia penitenziaria, psicologia dell&#039;emergenza, psicologia delle dipendenze, dipendenze patologiche, supporto psicologico, ansia, stress, gestione emozioni, rabbia, stress lavoro-correlato, burnout, attacchi di panico, umore, comportamenti alimentari, ossessioni, compulsioni, personalit\u00e0, consultazioni tecniche, assistenza giuridica, supporto famigliare, sostegno coppie, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, ritiro sociale, autolesionismo, elaborazione traumi, lutti, dipendenze affettive, parent training, competenze genitoriali, abbandono scolastico, bullismo, cyberbullismo, salute mentale, supporto adolescenti, consulenze tecniche forensi, colloqui transculturali, sostegno stranieri, approccio inclusivo, psicoterapia in natura, supporto professionale effettuato in spiaggia, Ravenna, Sedute psicologiche online, psicologo online, psicologi online, percorso psicologico online, colloqui psicologo online, psicologa online, psicologi online, sostegno psicologico online,  Psicologo Ravenna, psicologi Ravenna, psicologa Ravenna, psicologhe Ravenna, supporto psicologico Ravenna, sostegno psicologico Ravenna, percorso psicologico Ravenna, psicologa clinica Ravenna, psicologa forense Ravenna, psicologia giuridica Ravenna, criminologia Ravenna, criminologia penitenziaria Ravenna, psicologia dell&#039;emergenza Ravenna, psicologia delle dipendenze Ravenna, dipendenze patologiche Ravenna, supporto psicologico Ravenna, ansia Ravenna, stress Ravenna, gestione emozioni Ravenna, rabbia Ravenna, stress lavoro-correlato Ravenna, burnout Ravenna, attacchi di panico Ravenna, umore Ravenna, comportamenti alimentari Ravenna, ossessioni Ravenna, compulsioni Ravenna, personalit\u00e0 Ravenna, consultazioni tecniche Ravenna, assistenza giuridica Ravenna, supporto famigliare Ravenna, sostegno coppie Ravenna, difficolt\u00e0 emotive Ravenna, difficolt\u00e0 relazionali Ravenna, ritiro sociale Ravenna, autolesionismo Ravenna, elaborazione traumi Ravenna, lutti Ravenna, dipendenze affettive Ravenna, parent training Ravenna, competenze genitoriali Ravenna, abbandono scolastico Ravenna, bullismo Ravenna, cyberbullismo Ravenna, salute mentale Ravenna, supporto adolescenti Ravenna, consulenze tecniche forensi Ravenna, colloqui transculturali Ravenna, sostegno stranieri Ravenna, approccio inclusivo Ravenna, psicoterapia in natura Ravenna, supporto professionale effettuato in spiaggia Ravenna,   Psicologo a Ravenna, psicologi a Ravenna, psicologa a Ravenna, psicologhe a Ravenna, supporto psicologico a Ravenna, sostegno psicologico a Ravenna, percorso psicologico a Ravenna, psicologa clinica a Ravenna, psicologa forense a Ravenna, psicologia giuridica a Ravenna, criminologia a Ravenna, criminologia penitenziaria a Ravenna, psicologia dell&#039;emergenza a Ravenna, psicologia delle dipendenze a Ravenna, dipendenze patologiche a Ravenna, supporto psicologico a Ravenna, ansia a Ravenna, stress a Ravenna, gestione emozioni a Ravenna, rabbia a Ravenna, stress lavoro-correlato a Ravenna, burnout a Ravenna, attacchi di panico a Ravenna, umore a Ravenna, comportamenti alimentari a Ravenna, ossessioni a Ravenna, compulsioni a Ravenna, personalit\u00e0 a Ravenna, consultazioni tecniche a Ravenna, assistenza giuridica a Ravenna, supporto famigliare a Ravenna, sostegno coppie a Ravenna, difficolt\u00e0 emotive a Ravenna, difficolt\u00e0 relazionali a Ravenna, ritiro sociale a Ravenna, autolesionismo a Ravenna, elaborazione traumi a Ravenna, lutti a Ravenna, dipendenze affettive a Ravenna, parent training a Ravenna, competenze genitoriali a Ravenna, abbandono scolastico a Ravenna, bullismo a Ravenna, cyberbullismo a Ravenna, salute mentale a Ravenna, supporto adolescenti a Ravenna, consulenze tecniche forensi a Ravenna, colloqui transculturali a Ravenna, sostegno stranieri a Ravenna, approccio inclusivo a Ravenna, psicoterapia in natura a Ravenna, supporto professionale effettuato in spiaggia a Ravenna,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T11:33:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/\",\"name\":\"Dott.ssa Gabriella Montanari - Psicologa clinica e forense, Criminologa - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png\",\"datePublished\":\"2026-01-28T21:50:21+00:00\",\"dateModified\":\"2026-01-29T11:33:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Gabriella Montanari &#8211; Psicologa clinica e forense, Criminologa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Gabriella Montanari - Psicologa clinica e forense, Criminologa - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Gabriella Montanari - Psicologa clinica e forense, Criminologa - UIL Polizia","og_description":"Sono la dott.ssa Gabriella Montanari, psicologa clinica e forense, iscritta all\u2019Albo dell\u2019Emilia-Romagna (sez.A n\u00b012476). Ho conseguito la laurea magistrale in Psicologia seguita da numerosi corsi di alta formazione in psicologia giuridica e criminologia, criminologia penitenziaria e psicologia dell\u2019emergenza. Sono certificata come Esperto in Psicologia delle Dipendenze a livello internazionale.  La mia esperienza include attivit\u00e0 clinica e psicodiagnostica privata, collaborazioni con Universit\u00e0 e servizi pubblici per le dipendenze, incarichi come consulente tecnico di parte (CTP) in ambito civile e penale e un impegno costante nel volontariato, sia con Croce Rossa Italiana (SEP- Servizio Psicosociale) sia con associazioni dedicate alla salute mentale come Progetto Itaca. Mi occupo di et\u00e0 evolutiva e adulti, con particolare attenzione alle dipendenze patologiche (da sostanze, comportamentali, dipendenza affettiva), alle difficolt\u00e0 emotive e relazionali\u00a0(gestione delle emozioni, della rabbia e dello stress, ritiro sociale e difficolt\u00e0 relazionali, abbandono scolastico) e alle problematiche\u00a0 legate ai comportamenti alimentari. Offro percorsi di sostegno psicologico per adolescenti, famiglie e coppie nei momenti di particolare crisi (parent training, competenze genitoriali, orientamento scolastico e professionale, elaborazione di lutti e traumi, abbandoni sentimentali, autolesionismo, maltrattamenti in famiglia). Grazie alla mia formazione transculturale e alla conoscenza fluente di francese e inglese, offro anche colloqui di accoglienza e sostegno psicologico a cittadini stranieri, con un approccio aperto e inclusivo. Accolgo le persone con empatia, ascolto attento e competenze scientifiche, accompagnandole in percorsi di comprensione, cura e cambiamento dei disagi interiori. Credo nel valore della parola e dell'espressione artistica in generale\u00a0come strumento terapeutico, integrando la mia passione per la scrittura\/poesia\/fotografia e la ricerca con la pratica clinica. Il mio obiettivo \u00e8 creare uno spazio sicuro in cui adulti, adolescenti e famiglie possano sentirsi accolti, compresi e supportati nel percorso verso la crescita, il benessere psicologico e relazionale e la resilienza, valorizzando le risorse personali e familiari. Quando il meteo lo permette, nei mesi autunnali fino a primavera inoltrata, le sedute in presenza possono essere svolte in spiaggia e in laguna, davanti al mare, circondati dalla pineta e avvolti nel silenzio.\u00a0 Se cerchi un sostegno psicologico competente e attento alla tua storia, sar\u00f2 felice di affiancarti nel tuo cammino.  Servizi psicologici offerti:  Supporto psicologico per stress lavoro-correlato e prevenzione del burnout Gestione di ansia, rabbia e disregolazione emotiva Attacchi di panico, umore, comportamenti alimentari, ossessioni e compulsioni, personalit\u00e0 Dipendenze patologiche (sostanze, comportamentali, affettive) Elaborazione di eventi critici o traumatici Sostegno nelle fasi di cambiamento professionale Supporto relazionale, di coppia e familiare Valutazioni psicodiagnostiche in ambito clinico e forense, consulenze tecniche in ambito civile e penale  Bambini e adolescenti Ansia, paure e difficolt\u00e0 emotive Problemi comportamentali e scolastici, bullismo e cyberbullismo Difficolt\u00e0 relazionali e ritiro sociale Autolesionismo e disregolazione emotiva Supporto nei contesti familiari complessi   Psicologo, psicologi, psicologa, psicologhe, supporto psicologico, sostegno psicologico, percorso psicologico, psicologa clinica, psicologa forense, psicologia giuridica, criminologia, criminologia penitenziaria, psicologia dell'emergenza, psicologia delle dipendenze, dipendenze patologiche, supporto psicologico, ansia, stress, gestione emozioni, rabbia, stress lavoro-correlato, burnout, attacchi di panico, umore, comportamenti alimentari, ossessioni, compulsioni, personalit\u00e0, consultazioni tecniche, assistenza giuridica, supporto famigliare, sostegno coppie, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, ritiro sociale, autolesionismo, elaborazione traumi, lutti, dipendenze affettive, parent training, competenze genitoriali, abbandono scolastico, bullismo, cyberbullismo, salute mentale, supporto adolescenti, consulenze tecniche forensi, colloqui transculturali, sostegno stranieri, approccio inclusivo, psicoterapia in natura, supporto professionale effettuato in spiaggia, Ravenna, Sedute psicologiche online, psicologo online, psicologi online, percorso psicologico online, colloqui psicologo online, psicologa online, psicologi online, sostegno psicologico online,  Psicologo Ravenna, psicologi Ravenna, psicologa Ravenna, psicologhe Ravenna, supporto psicologico Ravenna, sostegno psicologico Ravenna, percorso psicologico Ravenna, psicologa clinica Ravenna, psicologa forense Ravenna, psicologia giuridica Ravenna, criminologia Ravenna, criminologia penitenziaria Ravenna, psicologia dell'emergenza Ravenna, psicologia delle dipendenze Ravenna, dipendenze patologiche Ravenna, supporto psicologico Ravenna, ansia Ravenna, stress Ravenna, gestione emozioni Ravenna, rabbia Ravenna, stress lavoro-correlato Ravenna, burnout Ravenna, attacchi di panico Ravenna, umore Ravenna, comportamenti alimentari Ravenna, ossessioni Ravenna, compulsioni Ravenna, personalit\u00e0 Ravenna, consultazioni tecniche Ravenna, assistenza giuridica Ravenna, supporto famigliare Ravenna, sostegno coppie Ravenna, difficolt\u00e0 emotive Ravenna, difficolt\u00e0 relazionali Ravenna, ritiro sociale Ravenna, autolesionismo Ravenna, elaborazione traumi Ravenna, lutti Ravenna, dipendenze affettive Ravenna, parent training Ravenna, competenze genitoriali Ravenna, abbandono scolastico Ravenna, bullismo Ravenna, cyberbullismo Ravenna, salute mentale Ravenna, supporto adolescenti Ravenna, consulenze tecniche forensi Ravenna, colloqui transculturali Ravenna, sostegno stranieri Ravenna, approccio inclusivo Ravenna, psicoterapia in natura Ravenna, supporto professionale effettuato in spiaggia Ravenna,   Psicologo a Ravenna, psicologi a Ravenna, psicologa a Ravenna, psicologhe a Ravenna, supporto psicologico a Ravenna, sostegno psicologico a Ravenna, percorso psicologico a Ravenna, psicologa clinica a Ravenna, psicologa forense a Ravenna, psicologia giuridica a Ravenna, criminologia a Ravenna, criminologia penitenziaria a Ravenna, psicologia dell'emergenza a Ravenna, psicologia delle dipendenze a Ravenna, dipendenze patologiche a Ravenna, supporto psicologico a Ravenna, ansia a Ravenna, stress a Ravenna, gestione emozioni a Ravenna, rabbia a Ravenna, stress lavoro-correlato a Ravenna, burnout a Ravenna, attacchi di panico a Ravenna, umore a Ravenna, comportamenti alimentari a Ravenna, ossessioni a Ravenna, compulsioni a Ravenna, personalit\u00e0 a Ravenna, consultazioni tecniche a Ravenna, assistenza giuridica a Ravenna, supporto famigliare a Ravenna, sostegno coppie a Ravenna, difficolt\u00e0 emotive a Ravenna, difficolt\u00e0 relazionali a Ravenna, ritiro sociale a Ravenna, autolesionismo a Ravenna, elaborazione traumi a Ravenna, lutti a Ravenna, dipendenze affettive a Ravenna, parent training a Ravenna, competenze genitoriali a Ravenna, abbandono scolastico a Ravenna, bullismo a Ravenna, cyberbullismo a Ravenna, salute mentale a Ravenna, supporto adolescenti a Ravenna, consulenze tecniche forensi a Ravenna, colloqui transculturali a Ravenna, sostegno stranieri a Ravenna, approccio inclusivo a Ravenna, psicoterapia in natura a Ravenna, supporto professionale effettuato in spiaggia a Ravenna,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/","og_site_name":"UIL Polizia","article_modified_time":"2026-01-29T11:33:50+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/","name":"Dott.ssa Gabriella Montanari - Psicologa clinica e forense, Criminologa - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png","datePublished":"2026-01-28T21:50:21+00:00","dateModified":"2026-01-29T11:33:50+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-siti-dottoressa-gabriella-montanari.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gabriella-montanari-psicologa-clinica-e-forense-criminologa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Gabriella Montanari &#8211; Psicologa clinica e forense, Criminologa"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/87472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=87472"}],"version-history":[{"count":14,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/87472\/revisions"}],"predecessor-version":[{"id":87634,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/87472\/revisions\/87634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/87525"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=87472"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=87472"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=87472"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=87472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}