{"id":86818,"date":"2026-01-26T11:18:01","date_gmt":"2026-01-26T10:18:01","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=86818"},"modified":"2026-01-26T11:19:09","modified_gmt":"2026-01-26T10:19:09","slug":"dott-ssa-lucia-boniotti-psicologa","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/","title":{"rendered":"Dott.ssa Lucia Boniotti &#8211; Psicologa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"86818\" class=\"elementor elementor-86818\">\n\t\t\t\t<div class=\"elementor-element elementor-element-477f518 e-flex e-con-boxed e-con e-parent\" data-id=\"477f518\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5d2dfe elementor-widget elementor-widget-text-editor\" data-id=\"3d5d2dfe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDott.ssa Lucia Boniotti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32654a3e elementor-widget elementor-widget-text-editor\" data-id=\"32654a3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Psicologa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5bb04b49 e-flex e-con-boxed e-con e-parent\" data-id=\"5bb04b49\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-235f4e7e e-con-full e-flex e-con e-child\" data-id=\"235f4e7e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-576a0016 e-con-full e-flex e-con e-child\" data-id=\"576a0016\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10e7e300 elementor-widget elementor-widget-text-editor\" data-id=\"10e7e300\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c0103f4 elementor-widget elementor-widget-text-editor\" data-id=\"3c0103f4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono Lucia Boniotti, psicologa clinica in costante formazione e in specializzazione in psicoterapia con un approccio psicocorporeo. Credo fermamente nell&#8217;importanza di un approccio olistico al benessere, che tenga conto della connessione profonda tra mente e corpo.<\/p><p>Il mio obiettivo \u00e8 accompagnare le persone nel loro percorso di crescita personale, aiutandole a superare le difficolt\u00e0 e a riscoprire il proprio potenziale. Lavoro per creare uno spazio sicuro e accogliente in cui le persone possano esplorare le proprie emozioni e i propri vissuti.<\/p><p>Sono convinta che il benessere psicologico sia un diritto fondamentale e mi impegno a offrire un supporto professionale e personalizzato, basato sulla fiducia e sul rispetto reciproco.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8fb2c0 e-con-full e-flex e-con e-child\" data-id=\"c8fb2c0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52f9a2f e-flex e-con-boxed e-con e-parent\" data-id=\"52f9a2f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5573c452 elementor-widget elementor-widget-text-editor\" data-id=\"5573c452\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6113ddf5 e-flex e-con-boxed e-con e-parent\" data-id=\"6113ddf5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-335b7e16 e-con-full e-flex e-con e-child\" data-id=\"335b7e16\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-119d68bb e-con-full e-flex e-con e-child\" data-id=\"119d68bb\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:86823,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/fe33ec25-1c68-49ae-856d-873cc338418e_large.jpg&quot;},{&quot;id&quot;:86824,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/c87c6fc9-22d5-4288-ac04-cf8ff54628af_large.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:4000,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d2ca2eb e-con-full e-flex e-con e-child\" data-id=\"2d2ca2eb\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-799540fd e-con-full e-flex e-con e-child\" data-id=\"799540fd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56dc0396 elementor-widget elementor-widget-text-editor\" data-id=\"56dc0396\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti e orari\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b631bbb elementor-widget elementor-widget-icon-box\" data-id=\"7b631bbb\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDott.ssa Lucia Boniotti\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPsicologa\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70c7b22b e-con-full e-flex e-con e-child\" data-id=\"70c7b22b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c530896 elementor-widget elementor-widget-text-editor\" data-id=\"6c530896\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Corsica, 263 &#8211; 25125 Brescia<\/p><p><strong>Tel.<\/strong> <a href=\"tel:+393349441589\">334 9441589<\/a><br \/><strong>Mail:<\/strong> <a href=\"mailto:luciaboniotti@yahoo.it\">luciaboniotti@yahoo.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6e9ad9 elementor-shape-circle e-grid-align-left e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"5e6e9ad9\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-72e21cb\" href=\"https:\/\/www.miodottore.it\/lucia-boniotti\/psicologo-clinico\/brescia\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" viewBox=\"0 0 441.2 418.5\"><path d=\"M1.3,190.2l26.4-80.3,138.7,32.3L178.7,0h85.2l10.5,129c-65,21.5-127.8,53.3-176.2,102.4L1.3,190.9v-.7Z\"><\/path><path d=\"M314.8,418.9h-.7l-68.8-80.4c5.1-12.2,12.4-23.5,20.5-34,13.9-18,30.9-34.7,50.2-46.8l67.2,111.1-68.4,50.1h0Z\"><\/path><path d=\"M414.9,110.3l26.2,81.3c-127.1,24.2-238.8,110.8-295,226.9l-94.9-60.4c-.3-.6,2.5-5.5,3-6.5,70-129.5,206.1-222.3,352.5-240.6,1.1,0,7.7-1,8.1-.7h.1Z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46855d09 elementor-widget elementor-widget-text-editor\" data-id=\"46855d09\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-410\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-410\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:400px;\"> <span id=\"gmw-resize-map-toggle-410\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-410\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-410\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"410\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23e27e73 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"23e27e73\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61deb99 elementor-widget elementor-widget-text-editor\" data-id=\"61deb99\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tpsicologa, psicologhe, psicologa clinica, psicologhe cliniche, psicoterapia, psicoterapie, psicoterapeuta, psicoterapeuti, approccio psicocorporeo, benessere olistico, mente, corpo, crescita personale, emozioni, vissuti, dolore, dolori, depressione, depressioni, crisi, paura, paure, autostima, stress, disturbo mentale, disturbi mentali, ansia, attacco di panico, attacchi di panico, somatizzazione, somatizzazioni, difficolt\u00e0 relazionali, ansia da prestazione, problemi relazionali, rabbia, disturbi relazionali, sconforto, angoscia, disturbo d&#8217;ansia generalizzato, fobia, fobie, dipendenza affettiva, dipendenze affettive, disturbi psicosomatici, psicologia del femminile, confusione mentale, disadattamento, negativismo, break-down adolescenziale, complesso, complessi, stato di agitazione, stati di agitazione, disturbi emotivi, cefalea, cefalee, claustrofobia, esaurimento nervoso, esaurimenti nervosi, agorafobia\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sono Lucia Boniotti, psicologa clinica in costante formazione e in specializzazione in psicoterapia con un approccio psicocorporeo. Credo fermamente nell&#8217;importanza di un approccio olistico al benessere, che tenga conto della connessione profonda tra mente e corpo.<br \/>\nIl mio obiettivo \u00e8 accompagnare le persone nel loro percorso di crescita personale, aiutandole a superare le difficolt\u00e0 e a riscoprire il proprio potenziale. Lavoro per creare uno spazio sicuro e accogliente in cui le persone possano esplorare le proprie emozioni e i propri vissuti.<br \/>\nSono convinta che il benessere psicologico sia un diritto fondamentale e mi impegno a offrire un supporto professionale e personalizzato, basato sulla fiducia e sul rispetto reciproco.<\/p>\n<p>Patologie trattate<br \/>\nDolore<br \/>\nDepressione<br \/>\nCrisi<br \/>\nPaura<br \/>\nAutostima<br \/>\nStress<br \/>\nDisturbo mentale<br \/>\nAnsia<br \/>\nAttacco di panico<br \/>\nSomatizzazione<br \/>\nDifficolt\u00e0 relazionali<br \/>\nAnsia da prestazione<br \/>\nProblemi relazionali<br \/>\nRabbia<br \/>\nDisturbi relazionali<br \/>\nSconforto<br \/>\nAngoscia<br \/>\nDisturbo d&#8217;ansia generalizzato<br \/>\nFobia<br \/>\nFobie<br \/>\nDipendenza affettiva<br \/>\nDisturbi psicosomatici<br \/>\nPsicologia del femminile<br \/>\nConfusione mentale<br \/>\nDisadattamento<br \/>\nNegativismo<br \/>\nBreak-down adolescenziale<br \/>\nComplesso<br \/>\nStato di agitazione<br \/>\nDisturbi emotivi<br \/>\nCefalea<br \/>\nClaustrofobia<br \/>\nEsaurimento nervoso<br \/>\nAgorafobia<\/p>\n<p>psicologa, psicologhe, psicologa clinica, psicologhe cliniche, psicoterapia, psicoterapie, psicoterapeuta, psicoterapeuti, approccio psicocorporeo, benessere olistico, mente, corpo, crescita personale, emozioni, vissuti, dolore, dolori, depressione, depressioni, crisi, paura, paure, autostima, stress, disturbo mentale, disturbi mentali, ansia, attacco di panico, attacchi di panico, somatizzazione, somatizzazioni, difficolt\u00e0 relazionali, ansia da prestazione, problemi relazionali, rabbia, disturbi relazionali, sconforto, angoscia, disturbo d&#8217;ansia generalizzato, fobia, fobie, dipendenza affettiva, dipendenze affettive, disturbi psicosomatici, psicologia del femminile, confusione mentale, disadattamento, negativismo, break-down adolescenziale, complesso, complessi, stato di agitazione, stati di agitazione, disturbi emotivi, cefalea, cefalee, claustrofobia, esaurimento nervoso, esaurimenti nervosi, agorafobia<\/p>\n","protected":false},"featured_media":86819,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,163],"product_tag":[16727,14531,1585,14469,16716,1560,7602,2632,13369,15190,674,3931,16725,16723,16722,16720,1544,3032,12247,1587,16439,2705,4571,3179,14532,14498,16719,2746,14529,11929,16718,5995,3070,2712,16726,14467,5495,1559,2153,16721,12128,15771,3211,353,658,1136,16715,10235,354,511,818,9776,6666,14530,5192,2710,16724,14533,1675,16717],"class_list":{"0":"post-86818","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-salute","8":"product_tag-agorafobia","9":"product_tag-angoscia","10":"product_tag-ansia","11":"product_tag-ansia-da-prestazione","12":"product_tag-approccio-psicocorporeo","13":"product_tag-attacchi-di-panico","14":"product_tag-attacco-di-panico","15":"product_tag-autostima","16":"product_tag-benessere-olistico","17":"product_tag-break-down-adolescenziale","18":"product_tag-cefalea","19":"product_tag-cefalee","20":"product_tag-claustrofobia","21":"product_tag-complessi","22":"product_tag-complesso","23":"product_tag-confusione-mentale","24":"product_tag-corpo","25":"product_tag-crescita-personale","26":"product_tag-crisi","27":"product_tag-depressione","28":"product_tag-depressioni","29":"product_tag-difficolta-relazionali","30":"product_tag-dipendenza-affettiva","31":"product_tag-dipendenze-affettive","32":"product_tag-disadattamento","33":"product_tag-disturbi-emotivi","34":"product_tag-disturbi-mentali","35":"product_tag-disturbi-psicosomatici","36":"product_tag-disturbi-relazionali","37":"product_tag-disturbo-dansia-generalizzato","38":"product_tag-disturbo-mentale","39":"product_tag-dolore","40":"product_tag-dolori","41":"product_tag-emozioni","42":"product_tag-esaurimenti-nervosi","43":"product_tag-esaurimento-nervoso","44":"product_tag-fobia","45":"product_tag-fobie","46":"product_tag-mente","47":"product_tag-negativismo","48":"product_tag-paura","49":"product_tag-paure","50":"product_tag-problemi-relazionali","51":"product_tag-psicologa","52":"product_tag-psicologa-clinica","53":"product_tag-psicologhe","54":"product_tag-psicologhe-cliniche","55":"product_tag-psicologia-del-femminile","56":"product_tag-psicoterapeuta","57":"product_tag-psicoterapeuti","58":"product_tag-psicoterapia","59":"product_tag-psicoterapie","60":"product_tag-rabbia","61":"product_tag-sconforto","62":"product_tag-somatizzazione","63":"product_tag-somatizzazioni","64":"product_tag-stati-di-agitazione","65":"product_tag-stato-di-agitazione","66":"product_tag-stress","67":"product_tag-vissuti","69":"first","70":"instock","71":"shipping-taxable","72":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Lucia Boniotti - Psicologa - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Lucia Boniotti - Psicologa - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono Lucia Boniotti, psicologa clinica in costante formazione e in specializzazione in psicoterapia con un approccio psicocorporeo. Credo fermamente nell&#039;importanza di un approccio olistico al benessere, che tenga conto della connessione profonda tra mente e corpo. Il mio obiettivo \u00e8 accompagnare le persone nel loro percorso di crescita personale, aiutandole a superare le difficolt\u00e0 e a riscoprire il proprio potenziale. Lavoro per creare uno spazio sicuro e accogliente in cui le persone possano esplorare le proprie emozioni e i propri vissuti. Sono convinta che il benessere psicologico sia un diritto fondamentale e mi impegno a offrire un supporto professionale e personalizzato, basato sulla fiducia e sul rispetto reciproco.  Patologie trattate Dolore Depressione Crisi Paura Autostima Stress Disturbo mentale Ansia Attacco di panico Somatizzazione Difficolt\u00e0 relazionali Ansia da prestazione Problemi relazionali Rabbia Disturbi relazionali Sconforto Angoscia Disturbo d&#039;ansia generalizzato Fobia Fobie Dipendenza affettiva Disturbi psicosomatici Psicologia del femminile Confusione mentale Disadattamento Negativismo Break-down adolescenziale Complesso Stato di agitazione Disturbi emotivi Cefalea Claustrofobia Esaurimento nervoso Agorafobia    psicologa, psicologhe, psicologa clinica, psicologhe cliniche, psicoterapia, psicoterapie, psicoterapeuta, psicoterapeuti, approccio psicocorporeo, benessere olistico, mente, corpo, crescita personale, emozioni, vissuti, dolore, dolori, depressione, depressioni, crisi, paura, paure, autostima, stress, disturbo mentale, disturbi mentali, ansia, attacco di panico, attacchi di panico, somatizzazione, somatizzazioni, difficolt\u00e0 relazionali, ansia da prestazione, problemi relazionali, rabbia, disturbi relazionali, sconforto, angoscia, disturbo d&#039;ansia generalizzato, fobia, fobie, dipendenza affettiva, dipendenze affettive, disturbi psicosomatici, psicologia del femminile, confusione mentale, disadattamento, negativismo, break-down adolescenziale, complesso, complessi, stato di agitazione, stati di agitazione, disturbi emotivi, cefalea, cefalee, claustrofobia, esaurimento nervoso, esaurimenti nervosi, agorafobia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T10:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/\",\"name\":\"Dott.ssa Lucia Boniotti - Psicologa - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg\",\"datePublished\":\"2026-01-26T10:18:01+00:00\",\"dateModified\":\"2026-01-26T10:19:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Lucia Boniotti &#8211; Psicologa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Lucia Boniotti - Psicologa - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Lucia Boniotti - Psicologa - UIL Polizia","og_description":"Sono Lucia Boniotti, psicologa clinica in costante formazione e in specializzazione in psicoterapia con un approccio psicocorporeo. Credo fermamente nell'importanza di un approccio olistico al benessere, che tenga conto della connessione profonda tra mente e corpo. Il mio obiettivo \u00e8 accompagnare le persone nel loro percorso di crescita personale, aiutandole a superare le difficolt\u00e0 e a riscoprire il proprio potenziale. Lavoro per creare uno spazio sicuro e accogliente in cui le persone possano esplorare le proprie emozioni e i propri vissuti. Sono convinta che il benessere psicologico sia un diritto fondamentale e mi impegno a offrire un supporto professionale e personalizzato, basato sulla fiducia e sul rispetto reciproco.  Patologie trattate Dolore Depressione Crisi Paura Autostima Stress Disturbo mentale Ansia Attacco di panico Somatizzazione Difficolt\u00e0 relazionali Ansia da prestazione Problemi relazionali Rabbia Disturbi relazionali Sconforto Angoscia Disturbo d'ansia generalizzato Fobia Fobie Dipendenza affettiva Disturbi psicosomatici Psicologia del femminile Confusione mentale Disadattamento Negativismo Break-down adolescenziale Complesso Stato di agitazione Disturbi emotivi Cefalea Claustrofobia Esaurimento nervoso Agorafobia    psicologa, psicologhe, psicologa clinica, psicologhe cliniche, psicoterapia, psicoterapie, psicoterapeuta, psicoterapeuti, approccio psicocorporeo, benessere olistico, mente, corpo, crescita personale, emozioni, vissuti, dolore, dolori, depressione, depressioni, crisi, paura, paure, autostima, stress, disturbo mentale, disturbi mentali, ansia, attacco di panico, attacchi di panico, somatizzazione, somatizzazioni, difficolt\u00e0 relazionali, ansia da prestazione, problemi relazionali, rabbia, disturbi relazionali, sconforto, angoscia, disturbo d'ansia generalizzato, fobia, fobie, dipendenza affettiva, dipendenze affettive, disturbi psicosomatici, psicologia del femminile, confusione mentale, disadattamento, negativismo, break-down adolescenziale, complesso, complessi, stato di agitazione, stati di agitazione, disturbi emotivi, cefalea, cefalee, claustrofobia, esaurimento nervoso, esaurimenti nervosi, agorafobia","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/","og_site_name":"UIL Polizia","article_modified_time":"2026-01-26T10:19:09+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/","name":"Dott.ssa Lucia Boniotti - Psicologa - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg","datePublished":"2026-01-26T10:18:01+00:00","dateModified":"2026-01-26T10:19:09+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-Drssa-Boniotti-Lucia.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-lucia-boniotti-psicologa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Lucia Boniotti &#8211; Psicologa"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/86818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=86818"}],"version-history":[{"count":7,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/86818\/revisions"}],"predecessor-version":[{"id":86836,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/86818\/revisions\/86836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/86819"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=86818"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=86818"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=86818"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=86818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}