{"id":86545,"date":"2026-01-23T09:48:35","date_gmt":"2026-01-23T08:48:35","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=86545"},"modified":"2026-01-23T10:39:21","modified_gmt":"2026-01-23T09:39:21","slug":"pin-viaggi","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/","title":{"rendered":"Pin Viaggi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"86545\" class=\"elementor elementor-86545\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d55c404 e-con-full e-flex e-con e-parent\" data-id=\"4d55c404\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d251cf0 e-con-full e-flex e-con e-child\" data-id=\"d251cf0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-666d565a elementor-widget elementor-widget-image\" data-id=\"666d565a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"319\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-PINVIAGGI-vettoriale-1024x319.png\" class=\"attachment-large size-large wp-image-86551\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-PINVIAGGI-vettoriale-980x305.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-PINVIAGGI-vettoriale-480x149.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18789cdf e-con-full e-flex e-con e-child\" data-id=\"18789cdf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52f693c5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52f693c5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a326d07 e-con-full e-flex e-con e-parent\" data-id=\"4a326d07\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c9ae5cf elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"3c9ae5cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agenzia viaggi \u2022 tour operator \u2022 personal travel designer\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-707c579 elementor-hidden-desktop elementor-widget elementor-widget-text-editor\" data-id=\"707c579\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agenzia viaggi<br \/>tour operator<br \/>personal travel designer<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5dbda6b2 e-flex e-con-boxed e-con e-parent\" data-id=\"5dbda6b2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77f24789 e-con-full e-flex e-con e-child\" data-id=\"77f24789\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e50513a e-con-full e-flex e-con e-child\" data-id=\"e50513a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-22ebb714 e-con-full e-flex e-con e-child\" data-id=\"22ebb714\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68f1f217 elementor-widget elementor-widget-text-editor\" data-id=\"68f1f217\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Presentazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70cacd99 e-con-full e-flex e-con e-child\" data-id=\"70cacd99\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ce85dc elementor-widget elementor-widget-text-editor\" data-id=\"12ce85dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Pin viaggi \u00e8 un piccolo tour operator delle Marche che fa parte della associazione Inside Marche per fare incoming e valorizzare la nostra regione. I nostri principali clienti sono le associazioni culturali della terza et\u00e0 ed organizziamo per loro viaggi di gruppo sia in Italia che all\u2019Estero.\u00a0<\/p><p>Allo stesso tempo ci occupiamo anche di viaggi individuali in tutto il mondo. La caratteristica che ci contraddistingue \u00e8 la personalizzazione del viaggio per incontrare alla perfezione le richieste dei nostri clienti. Commercializziamo anche la \u201cDimora Guidi Tordini\u201d, una eccellenza nei B&amp;B del borgo di Grottammare.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29522006 e-con-full e-flex e-con e-child\" data-id=\"29522006\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4bb7765f e-con-full e-flex e-con e-child\" data-id=\"4bb7765f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57139cf elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"57139cf\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/san-benedetto-02pin-viaggi-600x400.jpg\" alt=\"San Benedetto del Tronto\" \/><figcaption class=\"elementor-image-carousel-caption\">San Benedetto del Tronto<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/portosangiorgio-01pin-viaggi-600x400.jpg\" alt=\"Porto San Giorgio\" \/><figcaption class=\"elementor-image-carousel-caption\">Porto San Giorgio<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/offida-pin-viaggi1-600x401.jpg\" alt=\"Offida\" \/><figcaption class=\"elementor-image-carousel-caption\">Offida<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/ascoli-piceno-02pin-viaggi-600x401.jpg\" alt=\"Ascoli Piceno\" \/><figcaption class=\"elementor-image-carousel-caption\">Ascoli Piceno<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/GROTTAMMARE-IL-BORGOpin-viaggi-600x401.png\" alt=\"Borgo di Grottammare\" \/><figcaption class=\"elementor-image-carousel-caption\">Borgo di Grottammare<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-295ad85c e-con-full e-flex e-con e-parent\" data-id=\"295ad85c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ea8c1c8 e-con-full e-flex e-con e-child\" data-id=\"3ea8c1c8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b455638 elementor-widget elementor-widget-text-editor\" data-id=\"5b455638\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-136b97e e-flex e-con-boxed e-con e-parent\" data-id=\"136b97e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3144990c e-con-full e-flex e-con e-child\" data-id=\"3144990c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-136bdbd0 e-con-full e-flex e-con e-child\" data-id=\"136bdbd0\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b3952ce elementor-widget elementor-widget-image\" data-id=\"7b3952ce\" data-element_type=\"widget\" id=\"contatti\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"319\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-PINVIAGGI-vettoriale-1024x319.png\" class=\"attachment-large size-large wp-image-86551\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-PINVIAGGI-vettoriale-980x305.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo-PINVIAGGI-vettoriale-480x149.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe81d1c elementor-widget elementor-widget-text-editor\" data-id=\"2fe81d1c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via L. Da Vinci, 50 \u2013 63824 Altidona (FM)<br \/>Tel. Maria Guidi: <a href=\"tel:+393429141322\" target=\"_blank\" rel=\"noopener\">342 9141322 <\/a><br \/>Mail: <a href=\"mailto:info@pinviaggi.com\" target=\"_blank\" rel=\"noopener\">info@pinviaggi.com<\/a><br \/>Sito web: <a href=\"https:\/\/www.pinviaggi.com\" target=\"_blank\" rel=\"noopener\">www.pinviaggi.com<\/a><\/p><p>Luned\u00ec \u2013 Venerd\u00ec: 8:00 &#8211; 13:00 \/ 15:00 &#8211; 18:00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e86d00c elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"e86d00c\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-b8e16d5\" href=\"https:\/\/www.facebook.com\/pinviaggi\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f05914e\" href=\"https:\/\/www.instagram.com\/pin_viaggi\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54d55661 e-con-full e-flex e-con e-child\" data-id=\"54d55661\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61456c40 elementor-widget elementor-widget-text-editor\" data-id=\"61456c40\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-359\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-359\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-359\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-359\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-359\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"359\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5403386 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"5403386\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2ad920 elementor-widget elementor-widget-text-editor\" data-id=\"7d2ad920\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa Pin viaggi \u00e8 un piccolo tour operator delle Marche che fa parte della associazione Inside Marche per fare incoming e valorizzare la nostra regione. I nostri principali clienti sono le associazioni culturali della terza et\u00e0 ed organizziamo per loro viaggi di gruppo sia in Italia che all\u2019Estero. Allo stesso tempo ci occupiamo anche di viaggi individuali in tutto il mondo. La caratteristica che ci contraddistingue \u00e8 la personalizzazione del viaggio per incontrare alla perfezione le richieste dei nostri clienti. Commercializziamo anche la \u201cDimora Guidi Tordini\u201d, una eccellenza nei B&#038;B del borgo di Grottammare.\nServizi offerti :\u00a0Agenzia viaggi &#8211; tour operator &#8211; personal travel designer.\n\nPin viaggi, tour operator Marche, Inside Marche, incoming Marche, agenzia viaggi, agenzie viaggi, viaggi terza et\u00e0, associazioni culturali, viaggi di gruppo Italia, viaggi di gruppo estero, viaggi individuali mondo, personalizzazione viaggi, Dimora Guidi Tordini, B&#038;B Grottammare, agenzia viaggi, personal travel designer, Marina di Altidona,\nPin viaggi Marina di Altidona, tour operator Marina di Altidona,  agenzia viaggi Marina di Altidona, agenzie viaggi Marina di Altidona, viaggi terza et\u00e0 Marina di Altidona, associazioni culturali Marina di Altidona, viaggi di gruppo Italia Marina di Altidona, viaggi di gruppo estero Marina di Altidona, viaggi individuali mondo Marina di Altidona, personalizzazione viaggi Marina di Altidona, Dimora Guidi Tordini Marina di Altidona, B&#038;B Marina di Altidona, agenzia viaggi Marina di Altidona, personal travel designer Marina di Altidona, \nPin viaggi a Marina di Altidona, tour operator a Marina di Altidona,  agenzia viaggi a Marina di Altidona, agenzie viaggi a Marina di Altidona, viaggi terza et\u00e0 a Marina di Altidona, associazioni culturali a Marina di Altidona, viaggi di gruppo Italia a Marina di Altidona, viaggi di gruppo estero a Marina di Altidona, viaggi individuali mondo a Marina di Altidona, personalizzazione viaggi a Marina di Altidona, Dimora Guidi Tordini a Marina di Altidona, B&#038;B a Marina di Altidona, agenzia viaggi a Marina di Altidona, personal travel designer a Marina di Altidona, \nPin viaggi Fermo, tour operator Fermo,  agenzia viaggi Fermo, agenzie viaggi Fermo, viaggi terza et\u00e0 Fermo, associazioni culturali Fermo, viaggi di gruppo Italia Fermo, viaggi di gruppo estero Fermo, viaggi individuali mondo Fermo, personalizzazione viaggi Fermo, Dimora Guidi Tordini Fermo, B&#038;B Fermo, agenzia viaggi Fermo, personal travel designer Fermo, \nPin viaggi a Fermo, tour operator a Fermo,  agenzia viaggi a Fermo, agenzie viaggi a Fermo, viaggi terza et\u00e0 a Fermo, associazioni culturali a Fermo, viaggi di gruppo Italia a Fermo, viaggi di gruppo estero a Fermo, viaggi individuali mondo a Fermo, personalizzazione viaggi a Fermo, Dimora Guidi Tordini a Fermo, B&#038;B a Fermo, agenzia viaggi a Fermo, personal travel designer a Fermo, \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4c414e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4c414e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67fc3453\" data-id=\"67fc3453\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4262428d elementor-widget elementor-widget-text-editor\" data-id=\"4262428d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50d16baf elementor-widget elementor-widget-text-editor\" data-id=\"50d16baf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1066131d elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"1066131d\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-2136453\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-bbe8529\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-a831d86\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29bf3e8d\" data-id=\"29bf3e8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31beaba8 elementor-widget elementor-widget-text-editor\" data-id=\"31beaba8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-530\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"86545\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-530\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-530\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-530\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-530\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"530\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11c5be04 elementor-widget elementor-widget-text-editor\" data-id=\"11c5be04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-520\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-520\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-520\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-520\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-520\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"520\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display:none\">\n<p>La Pin viaggi \u00e8 un piccolo tour operator delle Marche che fa parte della associazione Inside Marche per fare incoming e valorizzare la nostra regione. I nostri principali clienti sono le associazioni culturali della terza et\u00e0 ed organizziamo per loro viaggi di gruppo sia in Italia che all\u2019Estero. Allo stesso tempo ci occupiamo anche di viaggi individuali in tutto il mondo. La caratteristica che ci contraddistingue \u00e8 la personalizzazione del viaggio per incontrare alla perfezione le richieste dei nostri clienti. Commercializziamo anche la \u201cDimora Guidi Tordini\u201d, una eccellenza nei B&#038;B del borgo di Grottammare.<br \/>\nServizi offerti :\u00a0Agenzia viaggi &#8211; tour operator &#8211; personal travel designer.<\/p>\n<p>Pin viaggi, tour operator Marche, Inside Marche, incoming Marche, agenzia viaggi, agenzie viaggi, viaggi terza et\u00e0, associazioni culturali, viaggi di gruppo Italia, viaggi di gruppo estero, viaggi individuali mondo, personalizzazione viaggi, Dimora Guidi Tordini, B&#038;B Grottammare, agenzia viaggi, personal travel designer, Marina di Altidona,<br \/>\nPin viaggi Marina di Altidona, tour operator Marina di Altidona,  agenzia viaggi Marina di Altidona, agenzie viaggi Marina di Altidona, viaggi terza et\u00e0 Marina di Altidona, associazioni culturali Marina di Altidona, viaggi di gruppo Italia Marina di Altidona, viaggi di gruppo estero Marina di Altidona, viaggi individuali mondo Marina di Altidona, personalizzazione viaggi Marina di Altidona, Dimora Guidi Tordini Marina di Altidona, B&#038;B Marina di Altidona, agenzia viaggi Marina di Altidona, personal travel designer Marina di Altidona,<br \/>\nPin viaggi a Marina di Altidona, tour operator a Marina di Altidona,  agenzia viaggi a Marina di Altidona, agenzie viaggi a Marina di Altidona, viaggi terza et\u00e0 a Marina di Altidona, associazioni culturali a Marina di Altidona, viaggi di gruppo Italia a Marina di Altidona, viaggi di gruppo estero a Marina di Altidona, viaggi individuali mondo a Marina di Altidona, personalizzazione viaggi a Marina di Altidona, Dimora Guidi Tordini a Marina di Altidona, B&#038;B a Marina di Altidona, agenzia viaggi a Marina di Altidona, personal travel designer a Marina di Altidona,<br \/>\nPin viaggi Fermo, tour operator Fermo,  agenzia viaggi Fermo, agenzie viaggi Fermo, viaggi terza et\u00e0 Fermo, associazioni culturali Fermo, viaggi di gruppo Italia Fermo, viaggi di gruppo estero Fermo, viaggi individuali mondo Fermo, personalizzazione viaggi Fermo, Dimora Guidi Tordini Fermo, B&#038;B Fermo, agenzia viaggi Fermo, personal travel designer Fermo,<br \/>\nPin viaggi a Fermo, tour operator a Fermo,  agenzia viaggi a Fermo, agenzie viaggi a Fermo, viaggi terza et\u00e0 a Fermo, associazioni culturali a Fermo, viaggi di gruppo Italia a Fermo, viaggi di gruppo estero a Fermo, viaggi individuali mondo a Fermo, personalizzazione viaggi a Fermo, Dimora Guidi Tordini a Fermo, B&#038;B a Fermo, agenzia viaggi a Fermo, personal travel designer a Fermo, <\/p>\n<\/div>\n","protected":false},"featured_media":86562,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[331,2325,330],"product_tag":[2761,8745,16579,16585,16584,16577,16576,16587,16586,16583,16574,16575,16581,16580,16582,16578],"class_list":{"0":"post-86545","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agenzie-di-viaggi","7":"product_cat-tour-operator","8":"product_cat-turismo-e-viaggi","9":"product_tag-agenzia-viaggi","10":"product_tag-agenzie-viaggi","11":"product_tag-associazioni-culturali","12":"product_tag-bb-grottammare","13":"product_tag-dimora-guidi-tordini","14":"product_tag-incoming-marche","15":"product_tag-inside-marche","16":"product_tag-marina-di-altidona","17":"product_tag-personal-travel-designer","18":"product_tag-personalizzazione-viaggi","19":"product_tag-pin-viaggi","20":"product_tag-tour-operator-marche","21":"product_tag-viaggi-di-gruppo-estero","22":"product_tag-viaggi-di-gruppo-italia","23":"product_tag-viaggi-individuali-mondo","24":"product_tag-viaggi-terza-eta","26":"first","27":"instock","28":"shipping-taxable","29":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pin Viaggi - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pin Viaggi - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"La Pin viaggi \u00e8 un piccolo tour operator delle Marche che fa parte della associazione Inside Marche per fare incoming e valorizzare la nostra regione. I nostri principali clienti sono le associazioni culturali della terza et\u00e0 ed organizziamo per loro viaggi di gruppo sia in Italia che all\u2019Estero. Allo stesso tempo ci occupiamo anche di viaggi individuali in tutto il mondo. La caratteristica che ci contraddistingue \u00e8 la personalizzazione del viaggio per incontrare alla perfezione le richieste dei nostri clienti. Commercializziamo anche la \u201cDimora Guidi Tordini\u201d, una eccellenza nei B&amp;B del borgo di Grottammare. Servizi offerti :\u00a0Agenzia viaggi - tour operator - personal travel designer.  Pin viaggi, tour operator Marche, Inside Marche, incoming Marche, agenzia viaggi, agenzie viaggi, viaggi terza et\u00e0, associazioni culturali, viaggi di gruppo Italia, viaggi di gruppo estero, viaggi individuali mondo, personalizzazione viaggi, Dimora Guidi Tordini, B&amp;B Grottammare, agenzia viaggi, personal travel designer, Marina di Altidona, Pin viaggi Marina di Altidona, tour operator Marina di Altidona, agenzia viaggi Marina di Altidona, agenzie viaggi Marina di Altidona, viaggi terza et\u00e0 Marina di Altidona, associazioni culturali Marina di Altidona, viaggi di gruppo Italia Marina di Altidona, viaggi di gruppo estero Marina di Altidona, viaggi individuali mondo Marina di Altidona, personalizzazione viaggi Marina di Altidona, Dimora Guidi Tordini Marina di Altidona, B&amp;B Marina di Altidona, agenzia viaggi Marina di Altidona, personal travel designer Marina di Altidona,  Pin viaggi a Marina di Altidona, tour operator a Marina di Altidona, agenzia viaggi a Marina di Altidona, agenzie viaggi a Marina di Altidona, viaggi terza et\u00e0 a Marina di Altidona, associazioni culturali a Marina di Altidona, viaggi di gruppo Italia a Marina di Altidona, viaggi di gruppo estero a Marina di Altidona, viaggi individuali mondo a Marina di Altidona, personalizzazione viaggi a Marina di Altidona, Dimora Guidi Tordini a Marina di Altidona, B&amp;B a Marina di Altidona, agenzia viaggi a Marina di Altidona, personal travel designer a Marina di Altidona,  Pin viaggi Fermo, tour operator Fermo, agenzia viaggi Fermo, agenzie viaggi Fermo, viaggi terza et\u00e0 Fermo, associazioni culturali Fermo, viaggi di gruppo Italia Fermo, viaggi di gruppo estero Fermo, viaggi individuali mondo Fermo, personalizzazione viaggi Fermo, Dimora Guidi Tordini Fermo, B&amp;B Fermo, agenzia viaggi Fermo, personal travel designer Fermo,  Pin viaggi a Fermo, tour operator a Fermo, agenzia viaggi a Fermo, agenzie viaggi a Fermo, viaggi terza et\u00e0 a Fermo, associazioni culturali a Fermo, viaggi di gruppo Italia a Fermo, viaggi di gruppo estero a Fermo, viaggi individuali mondo a Fermo, personalizzazione viaggi a Fermo, Dimora Guidi Tordini a Fermo, B&amp;B a Fermo, agenzia viaggi a Fermo, personal travel designer a Fermo,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T09:39:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/\",\"name\":\"Pin Viaggi - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png\",\"datePublished\":\"2026-01-23T08:48:35+00:00\",\"dateModified\":\"2026-01-23T09:39:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pin Viaggi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pin Viaggi - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/","og_locale":"it_IT","og_type":"article","og_title":"Pin Viaggi - UIL Polizia","og_description":"La Pin viaggi \u00e8 un piccolo tour operator delle Marche che fa parte della associazione Inside Marche per fare incoming e valorizzare la nostra regione. I nostri principali clienti sono le associazioni culturali della terza et\u00e0 ed organizziamo per loro viaggi di gruppo sia in Italia che all\u2019Estero. Allo stesso tempo ci occupiamo anche di viaggi individuali in tutto il mondo. La caratteristica che ci contraddistingue \u00e8 la personalizzazione del viaggio per incontrare alla perfezione le richieste dei nostri clienti. Commercializziamo anche la \u201cDimora Guidi Tordini\u201d, una eccellenza nei B&B del borgo di Grottammare. Servizi offerti :\u00a0Agenzia viaggi - tour operator - personal travel designer.  Pin viaggi, tour operator Marche, Inside Marche, incoming Marche, agenzia viaggi, agenzie viaggi, viaggi terza et\u00e0, associazioni culturali, viaggi di gruppo Italia, viaggi di gruppo estero, viaggi individuali mondo, personalizzazione viaggi, Dimora Guidi Tordini, B&B Grottammare, agenzia viaggi, personal travel designer, Marina di Altidona, Pin viaggi Marina di Altidona, tour operator Marina di Altidona, agenzia viaggi Marina di Altidona, agenzie viaggi Marina di Altidona, viaggi terza et\u00e0 Marina di Altidona, associazioni culturali Marina di Altidona, viaggi di gruppo Italia Marina di Altidona, viaggi di gruppo estero Marina di Altidona, viaggi individuali mondo Marina di Altidona, personalizzazione viaggi Marina di Altidona, Dimora Guidi Tordini Marina di Altidona, B&B Marina di Altidona, agenzia viaggi Marina di Altidona, personal travel designer Marina di Altidona,  Pin viaggi a Marina di Altidona, tour operator a Marina di Altidona, agenzia viaggi a Marina di Altidona, agenzie viaggi a Marina di Altidona, viaggi terza et\u00e0 a Marina di Altidona, associazioni culturali a Marina di Altidona, viaggi di gruppo Italia a Marina di Altidona, viaggi di gruppo estero a Marina di Altidona, viaggi individuali mondo a Marina di Altidona, personalizzazione viaggi a Marina di Altidona, Dimora Guidi Tordini a Marina di Altidona, B&B a Marina di Altidona, agenzia viaggi a Marina di Altidona, personal travel designer a Marina di Altidona,  Pin viaggi Fermo, tour operator Fermo, agenzia viaggi Fermo, agenzie viaggi Fermo, viaggi terza et\u00e0 Fermo, associazioni culturali Fermo, viaggi di gruppo Italia Fermo, viaggi di gruppo estero Fermo, viaggi individuali mondo Fermo, personalizzazione viaggi Fermo, Dimora Guidi Tordini Fermo, B&B Fermo, agenzia viaggi Fermo, personal travel designer Fermo,  Pin viaggi a Fermo, tour operator a Fermo, agenzia viaggi a Fermo, agenzie viaggi a Fermo, viaggi terza et\u00e0 a Fermo, associazioni culturali a Fermo, viaggi di gruppo Italia a Fermo, viaggi di gruppo estero a Fermo, viaggi individuali mondo a Fermo, personalizzazione viaggi a Fermo, Dimora Guidi Tordini a Fermo, B&B a Fermo, agenzia viaggi a Fermo, personal travel designer a Fermo,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/","og_site_name":"UIL Polizia","article_modified_time":"2026-01-23T09:39:21+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/","name":"Pin Viaggi - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png","datePublished":"2026-01-23T08:48:35+00:00","dateModified":"2026-01-23T09:39:21+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/Logo-siti-pin-viaggi.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/pin-viaggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Pin Viaggi"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/86545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=86545"}],"version-history":[{"count":13,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/86545\/revisions"}],"predecessor-version":[{"id":86591,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/86545\/revisions\/86591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/86562"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=86545"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=86545"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=86545"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=86545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}