{"id":85534,"date":"2026-01-14T15:33:24","date_gmt":"2026-01-14T14:33:24","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=85534"},"modified":"2026-01-15T09:47:56","modified_gmt":"2026-01-15T08:47:56","slug":"dott-andrea-bartolomucci-psicologo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/","title":{"rendered":"Dott. Andrea Bartolomucci &#8211; Psicologo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"85534\" class=\"elementor elementor-85534\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82b60f1 e-flex e-con-boxed e-con e-parent\" data-id=\"82b60f1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa73e46 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"fa73e46\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"858\" height=\"858\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-1.png\" class=\"attachment-full size-full wp-image-85525\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-1.png 858w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/LOGO-1-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 858px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1df50a elementor-widget elementor-widget-text-editor\" data-id=\"f1df50a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. Andrea Bartolomucci<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40ca0e6 elementor-widget elementor-widget-text-editor\" data-id=\"40ca0e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>psicologo clinico ad orientamento psicodinamico<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9b01d3 e-flex e-con-boxed e-con e-parent\" data-id=\"f9b01d3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-359027d e-con-full e-flex e-con e-child\" data-id=\"359027d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af9cd0c elementor-widget elementor-widget-text-editor\" data-id=\"af9cd0c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi sono<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-506f3d9 elementor-widget elementor-widget-text-editor\" data-id=\"506f3d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono il dott. Andrea Bartolomucci, psicologo clinico ad orientamento psicodinamico, iscritto all\u2019Albo A dell\u2019Ordine degli Psicologi dell\u2019Emilia-Romagna (n. 11007).<\/p><p>Svolgo attivit\u00e0 clinica con adolescenti e adulti, con particolare attenzione alle difficolt\u00e0 emotive, relazionali e ai momenti di stress legati alle fasi di vita e al contesto lavorativo.<\/p><p>Presso il Centro MAPP realizzo interventi di supporto psicologico e progetti di sostegno e riabilitazione nell\u2019ambito dell\u2019apprendimento.<\/p><p>Conduco inoltre attivit\u00e0 di supervisione e formazione per docenti ed educatori e collaboro stabilmente con famiglie e genitori, offrendo un supporto strutturato nella gestione delle complessit\u00e0 legate alla crescita e allo sviluppo in et\u00e0 evolutiva.<\/p><p>Il mio lavoro \u00e8 orientato a fornire spazi di ascolto professionali, riservati e concreti, finalizzati alla comprensione delle difficolt\u00e0 e al rafforzamento delle risorse personali.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f4ad10 elementor-widget elementor-widget-text-editor\" data-id=\"7f4ad10\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Servizi Offerti:<\/strong><br \/>\u2713 Supporto psicologico<br \/>\u2713 Supporto all\u2019apprendimento<br \/>\u2713 Supporto genitoriale<br \/>\u2713 Orientamento scolastico, universitario e professionale<br \/>\u2713 Valutazioni Psicodiagnostiche<br \/>\u2713 Formazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2bf637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2bf637\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac28957\" data-id=\"ac28957\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6db7cac elementor-widget elementor-widget-text-editor\" data-id=\"6db7cac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ba33cfe elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"ba33cfe\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8f7b442 e-con-full e-flex e-con e-child\" data-id=\"8f7b442\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:85528,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_133909-min-scaled.jpg&quot;},{&quot;id&quot;:85530,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_134620-min-scaled.jpg&quot;},{&quot;id&quot;:85527,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_133542-min-scaled.jpg&quot;},{&quot;id&quot;:85526,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_133256-min-scaled.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2000,&quot;background_slideshow_transition_duration&quot;:200,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11800c4 elementor-widget elementor-widget-spacer\" data-id=\"11800c4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-964eaa1 e-con-full e-flex e-con e-child\" data-id=\"964eaa1\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-aa1a665 e-con-full e-flex e-con e-child\" data-id=\"aa1a665\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5efda2c elementor-widget elementor-widget-text-editor\" data-id=\"5efda2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e7874 elementor-widget elementor-widget-text-editor\" data-id=\"51e7874\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. Andrea Bartolomucci<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-281a5e4 elementor-widget elementor-widget-text-editor\" data-id=\"281a5e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro MAPP \u2013 Mente, Apprendimento, Pensiero, Parole<br \/>Sito in strada Aurelio Saffi, 11 &#8211; 43121 Parma<\/p><p><strong>Tel:<\/strong> <a href=\"http:\/\/tel.+390521522332\">0521 522332<\/a><br \/><strong>Mail:<\/strong> <a href=\"mailto:info@centromapp.com\">info@centromapp.com<\/a><\/p><p><b>Lun &#8211; Ven: <\/b>8:00 &#8211; 20:00\u00a0 |\u00a0 \u00a0<strong>Sab:<\/strong> 8:00 &#8211; 18:00<br \/>Gli orari sono indicativi e flessibili, da concordare in base alle esigenze.<br \/>\u00c8 possibile svolgere colloqui anche in modalit\u00e0 online, previa valutazione del caso specifico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3e71b elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"8d3e71b\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-5bc3046\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=390521522332&#038;text&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-7725969\" href=\"https:\/\/www.linkedin.com\/company\/centromapp\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fab97e elementor-widget elementor-widget-text-editor\" data-id=\"8fab97e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-258\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"85534\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-258\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:250px;\"> <span id=\"gmw-resize-map-toggle-258\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-258\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-258\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"258\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b514c31 elementor-hidden-desktop elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"b514c31\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ac3a929 e-flex e-con-boxed e-con e-child\" data-id=\"ac3a929\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:85528,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_133909-min-scaled.jpg&quot;},{&quot;id&quot;:85530,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_134620-min-scaled.jpg&quot;},{&quot;id&quot;:85527,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_133542-min-scaled.jpg&quot;},{&quot;id&quot;:85526,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/img-andrea-bartolomucci1215_133256-min-scaled.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2000,&quot;background_slideshow_transition_duration&quot;:200,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da6dad8 elementor-widget elementor-widget-spacer\" data-id=\"da6dad8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5840da e-flex e-con-boxed e-con e-child\" data-id=\"e5840da\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e548995 elementor-widget elementor-widget-text-editor\" data-id=\"e548995\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56a3dd3 elementor-widget elementor-widget-text-editor\" data-id=\"56a3dd3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. Andrea Bartolomucci<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbfa22f elementor-widget elementor-widget-text-editor\" data-id=\"cbfa22f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro MAPP \u2013 Mente, Apprendimento, Pensiero, Parole<br \/>Sito in strada Aurelio Saffi, 11 &#8211; 43121 Parma<\/p><p><strong>Tel:<\/strong> <a href=\"http:\/\/tel.+390521522332\">0521 522332<\/a><br \/><strong>Mail:<\/strong> <a href=\"mailto:info@centromapp.com\">info@centromapp.com<\/a><\/p><p><b>Lun &#8211; Ven: <\/b>8:00 &#8211; 20:00\u00a0 |\u00a0 \u00a0<strong>Sab:<\/strong> 8:00 &#8211; 18:00<br \/>Gli orari sono indicativi e flessibili, da concordare in base alle esigenze.<br \/>\u00c8 possibile svolgere colloqui anche in modalit\u00e0 online, previa valutazione del caso specifico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70a0c1d elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"70a0c1d\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-5bc3046\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=390521522332&#038;text&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-7725969\" href=\"https:\/\/www.linkedin.com\/company\/centromapp\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d20c837 e-con-full e-flex e-con e-child\" data-id=\"d20c837\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-478d4ff elementor-widget elementor-widget-text-editor\" data-id=\"478d4ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-508\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"85534\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-508\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:250px;\"> <span id=\"gmw-resize-map-toggle-508\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-508\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-508\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"508\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0919b1 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"e0919b1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a25df1 elementor-widget elementor-widget-text-editor\" data-id=\"8a25df1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&lt;div style= &#8220;display: none&#8221;&gt;<\/p><p>Sono il dott. Andrea Bartolomucci, psicologo clinico ad orientamento psicodinamico, iscritto all\u2019Albo A dell\u2019Ordine degli Psicologi dell\u2019Emilia-Romagna (n. 11007).<br \/>Svolgo attivit\u00e0 clinica con adolescenti e adulti, con particolare attenzione alle difficolt\u00e0 emotive, relazionali e ai momenti di stress legati alle fasi di vita e al contesto lavorativo.<br \/>Presso il Centro MAPP realizzo interventi di supporto psicologico e progetti di sostegno e riabilitazione nell\u2019ambito dell\u2019apprendimento.<br \/>Conduco inoltre attivit\u00e0 di supervisione e formazione per docenti ed educatori e collaboro stabilmente con famiglie e genitori, offrendo un supporto strutturato nella gestione delle complessit\u00e0 legate alla crescita e allo sviluppo in et\u00e0 evolutiva.<br \/>Il mio lavoro \u00e8 orientato a fornire spazi di ascolto professionali, riservati e concreti, finalizzati alla comprensione delle difficolt\u00e0 e al rafforzamento delle risorse personali.<br \/>Servizi Offerti:<br \/>\u2713 Supporto psicologico<br \/>\u2713 Supporto all\u2019apprendimento<br \/>\u2713 Supporto genitoriale<br \/>\u2713 Orientamento scolastico, universitario e professionale<br \/>\u2713 Valutazioni Psicodiagnostiche<br \/>\u2713 Formazione<\/p><p>\u00a0<\/p><p>psicologo clinico, orientamento psicodinamico, supporto psicologico, psicologo per adolescenti, psicologo per adulti, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, gestione dello stress, stress lavorativo, sostegno all&#8217;apprendimento, riabilitazione dell&#8217;apprendimento, supervisione per docenti, formazione per educatori, supporto genitoriale, sostegno alla genitorialit\u00e0, consulenza per genitori, et\u00e0 evolutiva, ascolto professionale, risorse personali, orientamento scolastico, orientamento universitario, orientamento professionale, valutazioni psicodiagnostiche, psicodiagnostica, formazione professionale, benessere psicologico, crescita personale, psicologo, psicologi, psicologia, supporto emotivo<\/p><p><br \/>psicologo clinico a Parma, orientamento psicodinamico a Parma, supporto psicologico a Parma, psicologo per adolescenti a Parma, psicologo per adulti a Parma, difficolt\u00e0 emotive a Parma, difficolt\u00e0 relazionali a Parma, gestione dello stress a Parma, stress lavorativo a Parma, sostegno all&#8217;apprendimento a Parma, riabilitazione dell&#8217;apprendimento a Parma, supervisione per docenti a Parma, formazione per educatori a Parma, supporto genitoriale a Parma, sostegno alla genitorialit\u00e0 a Parma, consulenza per genitori a Parma, et\u00e0 evolutiva a Parma, ascolto professionale a Parma, risorse personali a Parma, orientamento scolastico a Parma, orientamento universitario a Parma, orientamento professionale a Parma, valutazioni psicodiagnostiche a Parma, psicodiagnostica a Parma, formazione professionale a Parma, benessere psicologico a Parma, crescita personale a Parma, psicologo a Parma, psicologi a Parma, psicologia a Parma, supporto emotivo a Parma<\/p><p><br \/>&lt;\/div&gt;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Sono il dott. Andrea Bartolomucci, psicologo clinico ad orientamento psicodinamico, iscritto all\u2019Albo A dell\u2019Ordine degli Psicologi dell\u2019Emilia-Romagna (n. 11007).<br \/>\nSvolgo attivit\u00e0 clinica con adolescenti e adulti, con particolare attenzione alle difficolt\u00e0 emotive, relazionali e ai momenti di stress legati alle fasi di vita e al contesto lavorativo.<br \/>\nPresso il Centro MAPP realizzo interventi di supporto psicologico e progetti di sostegno e riabilitazione nell\u2019ambito dell\u2019apprendimento.<br \/>\nConduco inoltre attivit\u00e0 di supervisione e formazione per docenti ed educatori e collaboro stabilmente con famiglie e genitori, offrendo un supporto strutturato nella gestione delle complessit\u00e0 legate alla crescita e allo sviluppo in et\u00e0 evolutiva.<br \/>\nIl mio lavoro \u00e8 orientato a fornire spazi di ascolto professionali, riservati e concreti, finalizzati alla comprensione delle difficolt\u00e0 e al rafforzamento delle risorse personali.<br \/>\nServizi Offerti:<br \/>\n\u2713 Supporto psicologico<br \/>\n\u2713 Supporto all\u2019apprendimento<br \/>\n\u2713 Supporto genitoriale<br \/>\n\u2713 Orientamento scolastico, universitario e professionale<br \/>\n\u2713 Valutazioni Psicodiagnostiche<br \/>\n\u2713 Formazione<\/p>\n<p>psicologo clinico, orientamento psicodinamico, supporto psicologico, psicologo per adolescenti, psicologo per adulti, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, gestione dello stress, stress lavorativo, sostegno all&#8217;apprendimento, riabilitazione dell&#8217;apprendimento, supervisione per docenti, formazione per educatori, supporto genitoriale, sostegno alla genitorialit\u00e0, consulenza per genitori, et\u00e0 evolutiva, ascolto professionale, risorse personali, orientamento scolastico, orientamento universitario, orientamento professionale, valutazioni psicodiagnostiche, psicodiagnostica, formazione professionale, benessere psicologico, crescita personale, psicologo, psicologi, psicologia, supporto emotivo<\/p>\n<p>psicologo clinico a Parma, orientamento psicodinamico a Parma, supporto psicologico a Parma, psicologo per adolescenti a Parma, psicologo per adulti a Parma, difficolt\u00e0 emotive a Parma, difficolt\u00e0 relazionali a Parma, gestione dello stress a Parma, stress lavorativo a Parma, sostegno all&#8217;apprendimento a Parma, riabilitazione dell&#8217;apprendimento a Parma, supervisione per docenti a Parma, formazione per educatori a Parma, supporto genitoriale a Parma, sostegno alla genitorialit\u00e0 a Parma, consulenza per genitori a Parma, et\u00e0 evolutiva a Parma, ascolto professionale a Parma, risorse personali a Parma, orientamento scolastico a Parma, orientamento universitario a Parma, orientamento professionale a Parma, valutazioni psicodiagnostiche a Parma, psicodiagnostica a Parma, formazione professionale a Parma, benessere psicologico a Parma, crescita personale a Parma, psicologo a Parma, psicologi a Parma, psicologia a Parma, supporto emotivo a Parma<\/p>\n<\/div>\n","protected":false},"featured_media":85567,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,163],"product_tag":[6892,3430,3381,3032,5852,2705,1981,16191,1896,3034,4395,16187,3909,8586,9782,460,993,516,850,10069,10066,16189,13356,16188,3391,5195,16190,6321,3241,1123,2750],"class_list":{"0":"post-85534","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-salute","8":"product_tag-ascolto-professionale","9":"product_tag-benessere-psicologico","10":"product_tag-consulenza-per-genitori","11":"product_tag-crescita-personale","12":"product_tag-difficolta-emotive","13":"product_tag-difficolta-relazionali","14":"product_tag-eta-evolutiva","15":"product_tag-formazione-per-educatori","16":"product_tag-formazione-professionale","17":"product_tag-gestione-dello-stress","18":"product_tag-orientamento-professionale","19":"product_tag-orientamento-psicodinamico","20":"product_tag-orientamento-scolastico","21":"product_tag-orientamento-universitario","22":"product_tag-psicodiagnostica","23":"product_tag-psicologi","24":"product_tag-psicologia","25":"product_tag-psicologo","26":"product_tag-psicologo-clinico","27":"product_tag-psicologo-per-adolescenti","28":"product_tag-psicologo-per-adulti","29":"product_tag-riabilitazione-dellapprendimento","30":"product_tag-risorse-personali","31":"product_tag-sostegno-allapprendimento","32":"product_tag-sostegno-alla-genitorialita","33":"product_tag-stress-lavorativo","34":"product_tag-supervisione-per-docenti","35":"product_tag-supporto-emotivo","36":"product_tag-supporto-genitoriale","37":"product_tag-supporto-psicologico","38":"product_tag-valutazioni-psicodiagnostiche","40":"first","41":"instock","42":"shipping-taxable","43":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Andrea Bartolomucci - Psicologo - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Andrea Bartolomucci - Psicologo - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono il dott. Andrea Bartolomucci, psicologo clinico ad orientamento psicodinamico, iscritto all\u2019Albo A dell\u2019Ordine degli Psicologi dell\u2019Emilia-Romagna (n. 11007). Svolgo attivit\u00e0 clinica con adolescenti e adulti, con particolare attenzione alle difficolt\u00e0 emotive, relazionali e ai momenti di stress legati alle fasi di vita e al contesto lavorativo. Presso il Centro MAPP realizzo interventi di supporto psicologico e progetti di sostegno e riabilitazione nell\u2019ambito dell\u2019apprendimento. Conduco inoltre attivit\u00e0 di supervisione e formazione per docenti ed educatori e collaboro stabilmente con famiglie e genitori, offrendo un supporto strutturato nella gestione delle complessit\u00e0 legate alla crescita e allo sviluppo in et\u00e0 evolutiva. Il mio lavoro \u00e8 orientato a fornire spazi di ascolto professionali, riservati e concreti, finalizzati alla comprensione delle difficolt\u00e0 e al rafforzamento delle risorse personali. Servizi Offerti: \u2713 Supporto psicologico \u2713 Supporto all\u2019apprendimento \u2713 Supporto genitoriale \u2713 Orientamento scolastico, universitario e professionale \u2713 Valutazioni Psicodiagnostiche \u2713 Formazione    psicologo clinico, orientamento psicodinamico, supporto psicologico, psicologo per adolescenti, psicologo per adulti, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, gestione dello stress, stress lavorativo, sostegno all&#039;apprendimento, riabilitazione dell&#039;apprendimento, supervisione per docenti, formazione per educatori, supporto genitoriale, sostegno alla genitorialit\u00e0, consulenza per genitori, et\u00e0 evolutiva, ascolto professionale, risorse personali, orientamento scolastico, orientamento universitario, orientamento professionale, valutazioni psicodiagnostiche, psicodiagnostica, formazione professionale, benessere psicologico, crescita personale, psicologo, psicologi, psicologia, supporto emotivo   psicologo clinico a Parma, orientamento psicodinamico a Parma, supporto psicologico a Parma, psicologo per adolescenti a Parma, psicologo per adulti a Parma, difficolt\u00e0 emotive a Parma, difficolt\u00e0 relazionali a Parma, gestione dello stress a Parma, stress lavorativo a Parma, sostegno all&#039;apprendimento a Parma, riabilitazione dell&#039;apprendimento a Parma, supervisione per docenti a Parma, formazione per educatori a Parma, supporto genitoriale a Parma, sostegno alla genitorialit\u00e0 a Parma, consulenza per genitori a Parma, et\u00e0 evolutiva a Parma, ascolto professionale a Parma, risorse personali a Parma, orientamento scolastico a Parma, orientamento universitario a Parma, orientamento professionale a Parma, valutazioni psicodiagnostiche a Parma, psicodiagnostica a Parma, formazione professionale a Parma, benessere psicologico a Parma, crescita personale a Parma, psicologo a Parma, psicologi a Parma, psicologia a Parma, supporto emotivo a Parma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T08:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/\",\"name\":\"Dott. Andrea Bartolomucci - Psicologo - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg\",\"datePublished\":\"2026-01-14T14:33:24+00:00\",\"dateModified\":\"2026-01-15T08:47:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Andrea Bartolomucci &#8211; Psicologo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Andrea Bartolomucci - Psicologo - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Andrea Bartolomucci - Psicologo - UIL Polizia","og_description":"Sono il dott. Andrea Bartolomucci, psicologo clinico ad orientamento psicodinamico, iscritto all\u2019Albo A dell\u2019Ordine degli Psicologi dell\u2019Emilia-Romagna (n. 11007). Svolgo attivit\u00e0 clinica con adolescenti e adulti, con particolare attenzione alle difficolt\u00e0 emotive, relazionali e ai momenti di stress legati alle fasi di vita e al contesto lavorativo. Presso il Centro MAPP realizzo interventi di supporto psicologico e progetti di sostegno e riabilitazione nell\u2019ambito dell\u2019apprendimento. Conduco inoltre attivit\u00e0 di supervisione e formazione per docenti ed educatori e collaboro stabilmente con famiglie e genitori, offrendo un supporto strutturato nella gestione delle complessit\u00e0 legate alla crescita e allo sviluppo in et\u00e0 evolutiva. Il mio lavoro \u00e8 orientato a fornire spazi di ascolto professionali, riservati e concreti, finalizzati alla comprensione delle difficolt\u00e0 e al rafforzamento delle risorse personali. Servizi Offerti: \u2713 Supporto psicologico \u2713 Supporto all\u2019apprendimento \u2713 Supporto genitoriale \u2713 Orientamento scolastico, universitario e professionale \u2713 Valutazioni Psicodiagnostiche \u2713 Formazione    psicologo clinico, orientamento psicodinamico, supporto psicologico, psicologo per adolescenti, psicologo per adulti, difficolt\u00e0 emotive, difficolt\u00e0 relazionali, gestione dello stress, stress lavorativo, sostegno all'apprendimento, riabilitazione dell'apprendimento, supervisione per docenti, formazione per educatori, supporto genitoriale, sostegno alla genitorialit\u00e0, consulenza per genitori, et\u00e0 evolutiva, ascolto professionale, risorse personali, orientamento scolastico, orientamento universitario, orientamento professionale, valutazioni psicodiagnostiche, psicodiagnostica, formazione professionale, benessere psicologico, crescita personale, psicologo, psicologi, psicologia, supporto emotivo   psicologo clinico a Parma, orientamento psicodinamico a Parma, supporto psicologico a Parma, psicologo per adolescenti a Parma, psicologo per adulti a Parma, difficolt\u00e0 emotive a Parma, difficolt\u00e0 relazionali a Parma, gestione dello stress a Parma, stress lavorativo a Parma, sostegno all'apprendimento a Parma, riabilitazione dell'apprendimento a Parma, supervisione per docenti a Parma, formazione per educatori a Parma, supporto genitoriale a Parma, sostegno alla genitorialit\u00e0 a Parma, consulenza per genitori a Parma, et\u00e0 evolutiva a Parma, ascolto professionale a Parma, risorse personali a Parma, orientamento scolastico a Parma, orientamento universitario a Parma, orientamento professionale a Parma, valutazioni psicodiagnostiche a Parma, psicodiagnostica a Parma, formazione professionale a Parma, benessere psicologico a Parma, crescita personale a Parma, psicologo a Parma, psicologi a Parma, psicologia a Parma, supporto emotivo a Parma","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/","og_site_name":"UIL Polizia","article_modified_time":"2026-01-15T08:47:56+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/","name":"Dott. Andrea Bartolomucci - Psicologo - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg","datePublished":"2026-01-14T14:33:24+00:00","dateModified":"2026-01-15T08:47:56+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/01\/logo_Andrea-Bartolomucci.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bartolomucci-psicologo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Andrea Bartolomucci &#8211; Psicologo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/85534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=85534"}],"version-history":[{"count":26,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/85534\/revisions"}],"predecessor-version":[{"id":85592,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/85534\/revisions\/85592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/85567"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=85534"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=85534"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=85534"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=85534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}