{"id":81059,"date":"2025-11-11T16:17:53","date_gmt":"2025-11-11T15:17:53","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=81059"},"modified":"2025-11-11T17:20:38","modified_gmt":"2025-11-11T16:20:38","slug":"dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/","title":{"rendered":"Dott. Domenico Berardi &#8211; Psicologo, Psicoterapeuta, Ipnologo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"81059\" class=\"elementor elementor-81059\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54adf826 e-flex e-con-boxed e-con e-parent\" data-id=\"54adf826\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77c53542 elementor-widget elementor-widget-image-box\" data-id=\"77c53542\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Dott. Domenico Berardi <\/div><p class=\"elementor-image-box-description\">Psicologo \u2022 Psicoterapeuta \u2022 Ipnologo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d0e2c95 e-flex e-con-boxed e-con e-parent\" data-id=\"2d0e2c95\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-524d029e e-con-full e-flex e-con e-child\" data-id=\"524d029e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-642717e9 e-con-full e-flex e-con e-child\" data-id=\"642717e9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1518c71c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1518c71c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6357bad3 e-con-full e-flex e-con e-child\" data-id=\"6357bad3\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-277eb565 elementor-widget elementor-widget-text-editor\" data-id=\"277eb565\" data-element_type=\"widget\" id=\"chisono\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Presentazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-481ac3b0 elementor-widget elementor-widget-text-editor\" data-id=\"481ac3b0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono uno <b>Psicologo clinico<\/b>, <b>Psicoterapeuta<\/b> specializzato in Psicoterapie Brevi ad Approccio Strategico e <b>Ipnologo<\/b>, iscritto all\u2019Albo dell\u2019Ordine degli Psicologi della Regione Lazio\u00a0con il n. 19917.<\/p><p>Mi occupo delle varie forme di disagio psicologico, utilizzando varie tecniche d\u2019intervento, tra cui la\u00a0<b>Psicoterapia Breve Strategica<\/b>, l\u2019<b>Ipnosi clinica<\/b>, la <b>PNL<\/b>, la <b>Mindfulness<\/b>, l\u2019<b>Acceptance<\/b> and <b>Commitment Theraphy\u00a0<\/b>(ACT).<\/p><p>Condivido e utilizzo anche i principi e le tecniche di sviluppo della consapevolezza di\u00a0<b>Eckhart Tolle<\/b>.<\/p><p>Il mio campo d\u2019intervento riguarda principalmente i\u00a0<b>problemi relazionali<\/b>, di\u00a0<b>autostima<\/b>, di\u00a0<b>ansia<\/b>, di\u00a0<b>depressione<\/b>, di\u00a0<b>comunicazione<\/b>\u00a0disfunzionale, l\u2019elaborazione dei\u00a0<b>traumi<\/b>\u00a0e del\u00a0<b>lutto<\/b>.<\/p><p>Ho conseguito anche un\u00a0<b>Master in\u00a0Sessuologia clinica<\/b>\u00a0per trattare i problemi relativi alla sfera sessuale e un\u00a0<b>Master in\u00a0Psicologia e trattamento delle Dipendenze<\/b>\u00a0(in particolare affettive, sessuali e da Internet).<\/p><p>Mi occupo principalmente di adulti e giovani adulti, coppie e famiglie.<\/p><p>Svolgo la mia attivit\u00e0 come volontario presso l\u2019Associazione no-profit\u00a0<b>\u201cGenitori con la patente\u00ae \u2013 APS\u201d<\/b>, la quale applica dei\u00a0costi particolarmente sostenibili\u00a0per consentire l\u2019accesso ai servizi psicologici anche alle persone economicamente pi\u00f9 svantaggiate.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ae576fd e-con-full e-flex e-con e-child\" data-id=\"3ae576fd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6848663f e-con-full e-flex e-con e-child\" data-id=\"6848663f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-636199c7 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"636199c7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dottdomenicoberardipsicologo.com\/attestati\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">La mia formazione<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13083534 e-con-full e-flex e-con e-child\" data-id=\"13083534\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1031ec8b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1031ec8b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dottdomenicoberardipsicologo.com\/wp-content\/uploads\/2025\/04\/CV-Domenico-Berardi.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curriculum Vitae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c0e33f7 e-con-full e-flex e-con e-child\" data-id=\"1c0e33f7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5487a61e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5487a61e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.dottdomenicoberardipsicologo.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">visita il sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-633f0cf4 e-flex e-con-boxed e-con e-parent\" data-id=\"633f0cf4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4abd5401 e-con-full e-flex e-con e-child\" data-id=\"4abd5401\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73e7301e elementor-widget elementor-widget-text-editor\" data-id=\"73e7301e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PER GLI ASSOCIATI<br><b>sconto di \u20ac 5,00 sulle tariffe&nbsp; praticate dall\u2019Associazione &#8220;Genitori con la patente &#8211; APS&#8221;<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53263f0e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"53263f0e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/genitoriconlapatente.it\/costi-sostenibili\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCOPRI DI PI\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e9042f4 e-flex e-con-boxed e-con e-parent\" data-id=\"4e9042f4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-32926c5f e-con-full e-flex e-con e-child\" data-id=\"32926c5f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3da935a2 e-con-full e-flex e-con e-child\" data-id=\"3da935a2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62f81f25 elementor-widget elementor-widget-text-editor\" data-id=\"62f81f25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-302\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-302\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:400px;\"> <span id=\"gmw-resize-map-toggle-302\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-302\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-302\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"302\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a4d3278 e-con-full e-flex e-con e-child\" data-id=\"1a4d3278\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7626689b e-con-full e-flex e-con e-child\" data-id=\"7626689b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64dc7ca0 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"64dc7ca0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tsedi &#038; contatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-129e4509 elementor-widget elementor-widget-image-box\" data-id=\"129e4509\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Dott. Domenico Berardi <\/div><p class=\"elementor-image-box-description\">Psicologo \u2022 Psicoterapeuta \u2022 Ipnologo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e87aec4 e-con-full e-flex e-con e-child\" data-id=\"2e87aec4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33e9e236 elementor-widget elementor-widget-text-editor\" data-id=\"33e9e236\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><b>Si effettuano anche colloqui online<\/b><\/i><\/p><p>Via Don Tonino Bello, 20 \u2013 00132 Roma<br \/>Tel: <a href=\"tel:+393319751814\" target=\"_blank\" rel=\"noopener\">+39 331 9751814<\/a><br \/>Mail: <a href=\"mailto:berardi.domenico@libero.it\" target=\"_blank\" rel=\"noopener\">berardi.domenico@libero.it<\/a><br \/>Sito:\u00a0<a href=\"https:\/\/www.dottdomenicoberardipsicologo.com\" target=\"_blank\" rel=\"noopener\">www.dottdomenicoberardipsicologo.com<\/a><br \/>Sito: <a href=\"https:\/\/www.sessoamico.org\" target=\"_blank\" rel=\"noopener\">www.sessoamico.org<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1b0f7f elementor-shape-circle e-grid-align-left e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"c1b0f7f\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-animation-grow elementor-repeater-item-108f2f9\" href=\"https:\/\/wa.me\/393319751814\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-eb6bd87\" href=\"https:\/\/www.facebook.com\/DomenicoBerardiPsicologo\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-d08f678\" href=\"https:\/\/www.instagram.com\/domenico_berardi_psicologo\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-7d42dec\" href=\"https:\/\/www.linkedin.com\/in\/domenico-berardi-94458b32\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1992be85 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1992be85\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7bbe0106\" data-id=\"7bbe0106\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-113082ab elementor-widget elementor-widget-text-editor\" data-id=\"113082ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f1dfc1a elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"1f1dfc1a\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44b96f16\" data-id=\"44b96f16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43f7ba45 elementor-widget elementor-widget-text-editor\" data-id=\"43f7ba45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-253\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"81059\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-253\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-253\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-253\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-253\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"253\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a1a654 elementor-widget elementor-widget-text-editor\" data-id=\"8a1a654\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-375\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-375\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-375\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-375\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-375\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"375\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Psicologo clinico, Psicoterapeuta e Ipnologo<br \/>\nSono uno Psicologo clinico, Psicoterapeuta specializzato in Psicoterapie Brevi ad Approccio Strategico e Ipnologo, iscritto all\u2019Albo dell\u2019Ordine degli Psicologi della Regione Lazio\u00a0con il n. 19917.<br \/>\nMi occupo delle varie forme di disagio psicologico, utilizzando varie tecniche d\u2019intervento, tra cui la\u00a0Psicoterapia Breve Strategica, l\u2019Ipnosi clinica, la PNL, la Mindfulness, l\u2019Acceptance and Commitment Theraphy\u00a0(ACT). Condivido e utilizzo anche i principi e le tecniche di sviluppo della consapevolezza di\u00a0Eckhart Tolle.<br \/>\nIl mio campo d\u2019intervento riguarda principalmente i\u00a0problemi relazionali, di\u00a0autostima, di\u00a0ansia, di\u00a0depressione, di\u00a0comunicazione\u00a0disfunzionale, l\u2019elaborazione dei\u00a0traumi\u00a0e del\u00a0lutto. Ho conseguito anche un\u00a0Master in\u00a0Sessuologia clinica\u00a0per trattare i problemi relativi alla sfera sessuale e un\u00a0Master in\u00a0Psicologia e trattamento delle Dipendenze\u00a0(in particolare affettive, sessuali e da Internet).<br \/>\nMi occupo principalmente di adulti e giovani adulti, coppie e famiglie.<br \/>\nSvolgo la mia attivit\u00e0 come volontario presso l\u2019Associazione no-profit\u00a0\u201cGenitori con la patente\u00ae \u2013 APS\u201d, la quale applica dei\u00a0costi particolarmente sostenibili\u00a0per consentire l\u2019accesso ai servizi psicologici anche alle persone economicamente pi\u00f9 svantaggiate.<br \/>\nLa mia formazione<br \/>\nScarica il mio Curriculum VitaeDott. Domenico Berard<br \/>\nPsicologo, psicologi, psicologia, psicoterapia, psicoterapeuti, Psicoterapeuta, Ipnologo, ipnologi, sostegno psicologico, supporto psicologico, percorso psicologico, Psicologo clinico, Psicoterapeuta, Psicoterapie Brevi, Approccio Strategico, Ipnologo, Ordine Psicologi Lazio, disagio psicologico, Psicoterapia Breve Strategica, Ipnosi clinica, PNL, Mindfulness, Acceptance and Commitment Therapy, ACT, Eckhart Tolle, problemi relazionali, autostima, ansia, depressione, comunicazione disfunzionale, elaborazione traumi, elaborazione lutto, Master in Sessuologia clinica, problemi sfera sessuale, Master in Psicologia e trattamento Dipendenze, dipendenze affettive, dipendenze sessuali, dipendenze Internet, adulti, giovani adulti, coppie, famiglie, Associazione no-profit, Genitori con la patente APS, servizi psicologici sostenibili, Roma,<br \/>\nPsicologo Roma, psicologi Roma, psicologia Roma, psicoterapia Roma, psicoterapeuti Roma, Psicoterapeuta Roma, Ipnologo Roma, ipnologi Roma, sostegno psicologico Roma, supporto psicologico Roma, percorso psicologico Roma, Psicologo clinico Roma, Psicoterapeuta Roma, Psicoterapie Brevi Roma, Approccio Strategico Roma, Ipnologo Roma, Ordine Psicologi Lazio Roma, disagio psicologico Roma, Psicoterapia Breve Strategica Roma, Ipnosi clinica Roma, PNL Roma, Mindfulness Roma, Acceptance and Commitment Therapy Roma, ACT Roma, Eckhart Tolle Roma, problemi relazionali Roma, autostima Roma, ansia Roma, depressione Roma, comunicazione disfunzionale Roma, elaborazione traumi Roma, elaborazione lutto Roma, Master in Sessuologia clinica Roma, problemi sfera sessuale Roma, Master in Psicologia e trattamento Dipendenze Roma, dipendenze affettive Roma, dipendenze sessuali Roma, dipendenze Internet Roma, adulti Roma, giovani adulti Roma, coppie Roma, famiglie Roma, Associazione no-profit Roma, Genitori con la patente APS Roma, servizi psicologici sostenibili Roma,<br \/>\nPsicologo a Roma, psicologi a Roma, psicologia a Roma, psicoterapia a Roma, psicoterapeuti a Roma, Psicoterapeuta a Roma, Ipnologo a Roma, ipnologi a Roma, sostegno psicologico a Roma, supporto psicologico a Roma, percorso psicologico a Roma, Psicologo clinico a Roma, Psicoterapeuta a Roma, Psicoterapie Brevi a Roma, Approccio Strategico a Roma, Ipnologo a Roma, Ordine Psicologi Lazio a Roma, disagio psicologico a Roma, Psicoterapia Breve Strategica a Roma, Ipnosi clinica a Roma, PNL a Roma, Mindfulness a Roma, Acceptance and Commitment Therapy a Roma, ACT a Roma, Eckhart Tolle a Roma, problemi relazionali a Roma, autostima a Roma, ansia a Roma, depressione a Roma, comunicazione disfunzionale a Roma, elaborazione traumi a Roma, elaborazione lutto a Roma, Master in Sessuologia clinica a Roma, problemi sfera sessuale a Roma, Master in Psicologia e trattamento Dipendenze a Roma, dipendenze affettive a Roma, dipendenze sessuali a Roma, dipendenze Internet a Roma, adulti a Roma, giovani adulti a Roma, coppie a Roma, famiglie a Roma, Associazione no-profit a Roma, Genitori con la patente APS a Roma, servizi psicologici sostenibili a Roma,<\/div>\n","protected":false},"featured_media":81060,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[215,256,258,163],"product_tag":[14610,14611,1044,1585,14606,14619,2632,14613,4900,1587,3179,14618,14617,6036,14612,5517,10083,3189,14620,13619,14604,807,4413,14616,14614,2509,14607,5847,14609,3211,14615,460,993,516,850,354,511,818,14608,14605,508,14621,1499,1123],"class_list":{"0":"post-81059","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ipnologo","7":"product_cat-psicologi","8":"product_cat-psicoterapeuti","9":"product_cat-salute","10":"product_tag-acceptance-and-commitment-therapy","11":"product_tag-act","12":"product_tag-adulti","13":"product_tag-ansia","14":"product_tag-approccio-strategico","15":"product_tag-associazione-no-profit","16":"product_tag-autostima","17":"product_tag-comunicazione-disfunzionale","18":"product_tag-coppie","19":"product_tag-depressione","20":"product_tag-dipendenze-affettive","21":"product_tag-dipendenze-internet","22":"product_tag-dipendenze-sessuali","23":"product_tag-disagio-psicologico","24":"product_tag-eckhart-tolle","25":"product_tag-elaborazione-lutto","26":"product_tag-elaborazione-traumi","27":"product_tag-famiglie","28":"product_tag-genitori-con-la-patente-aps","29":"product_tag-giovani-adulti","30":"product_tag-ipnologi","31":"product_tag-ipnologo","32":"product_tag-ipnosi-clinica","33":"product_tag-master-in-psicologia-e-trattamento-dipendenze","34":"product_tag-master-in-sessuologia-clinica","35":"product_tag-mindfulness","36":"product_tag-ordine-psicologi-lazio","37":"product_tag-percorso-psicologico","38":"product_tag-pnl","39":"product_tag-problemi-relazionali","40":"product_tag-problemi-sfera-sessuale","41":"product_tag-psicologi","42":"product_tag-psicologia","43":"product_tag-psicologo","44":"product_tag-psicologo-clinico","45":"product_tag-psicoterapeuta","46":"product_tag-psicoterapeuti","47":"product_tag-psicoterapia","48":"product_tag-psicoterapia-breve-strategica","49":"product_tag-psicoterapie-brevi","50":"product_tag-roma","51":"product_tag-servizi-psicologici-sostenibili","52":"product_tag-sostegno-psicologico","53":"product_tag-supporto-psicologico","55":"first","56":"instock","57":"shipping-taxable","58":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Domenico Berardi - Psicologo, Psicoterapeuta, Ipnologo - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Domenico Berardi - Psicologo, Psicoterapeuta, Ipnologo - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Psicologo clinico, Psicoterapeuta e Ipnologo Sono uno Psicologo clinico, Psicoterapeuta specializzato in Psicoterapie Brevi ad Approccio Strategico e Ipnologo, iscritto all\u2019Albo dell\u2019Ordine degli Psicologi della Regione Lazio\u00a0con il n. 19917. Mi occupo delle varie forme di disagio psicologico, utilizzando varie tecniche d\u2019intervento, tra cui la\u00a0Psicoterapia Breve Strategica, l\u2019Ipnosi clinica, la PNL, la Mindfulness, l\u2019Acceptance and Commitment Theraphy\u00a0(ACT). Condivido e utilizzo anche i principi e le tecniche di sviluppo della consapevolezza di\u00a0Eckhart Tolle. Il mio campo d\u2019intervento riguarda principalmente i\u00a0problemi relazionali, di\u00a0autostima, di\u00a0ansia, di\u00a0depressione, di\u00a0comunicazione\u00a0disfunzionale, l\u2019elaborazione dei\u00a0traumi\u00a0e del\u00a0lutto. Ho conseguito anche un\u00a0Master in\u00a0Sessuologia clinica\u00a0per trattare i problemi relativi alla sfera sessuale e un\u00a0Master in\u00a0Psicologia e trattamento delle Dipendenze\u00a0(in particolare affettive, sessuali e da Internet). Mi occupo principalmente di adulti e giovani adulti, coppie e famiglie. Svolgo la mia attivit\u00e0 come volontario presso l\u2019Associazione no-profit\u00a0\u201cGenitori con la patente\u00ae \u2013 APS\u201d, la quale applica dei\u00a0costi particolarmente sostenibili\u00a0per consentire l\u2019accesso ai servizi psicologici anche alle persone economicamente pi\u00f9 svantaggiate. La mia formazione Scarica il mio Curriculum VitaeDott. Domenico Berard Psicologo, psicologi, psicologia, psicoterapia, psicoterapeuti, Psicoterapeuta, Ipnologo, ipnologi, sostegno psicologico, supporto psicologico, percorso psicologico, Psicologo clinico, Psicoterapeuta, Psicoterapie Brevi, Approccio Strategico, Ipnologo, Ordine Psicologi Lazio, disagio psicologico, Psicoterapia Breve Strategica, Ipnosi clinica, PNL, Mindfulness, Acceptance and Commitment Therapy, ACT, Eckhart Tolle, problemi relazionali, autostima, ansia, depressione, comunicazione disfunzionale, elaborazione traumi, elaborazione lutto, Master in Sessuologia clinica, problemi sfera sessuale, Master in Psicologia e trattamento Dipendenze, dipendenze affettive, dipendenze sessuali, dipendenze Internet, adulti, giovani adulti, coppie, famiglie, Associazione no-profit, Genitori con la patente APS, servizi psicologici sostenibili, Roma, Psicologo Roma, psicologi Roma, psicologia Roma, psicoterapia Roma, psicoterapeuti Roma, Psicoterapeuta Roma, Ipnologo Roma, ipnologi Roma, sostegno psicologico Roma, supporto psicologico Roma, percorso psicologico Roma, Psicologo clinico Roma, Psicoterapeuta Roma, Psicoterapie Brevi Roma, Approccio Strategico Roma, Ipnologo Roma, Ordine Psicologi Lazio Roma, disagio psicologico Roma, Psicoterapia Breve Strategica Roma, Ipnosi clinica Roma, PNL Roma, Mindfulness Roma, Acceptance and Commitment Therapy Roma, ACT Roma, Eckhart Tolle Roma, problemi relazionali Roma, autostima Roma, ansia Roma, depressione Roma, comunicazione disfunzionale Roma, elaborazione traumi Roma, elaborazione lutto Roma, Master in Sessuologia clinica Roma, problemi sfera sessuale Roma, Master in Psicologia e trattamento Dipendenze Roma, dipendenze affettive Roma, dipendenze sessuali Roma, dipendenze Internet Roma, adulti Roma, giovani adulti Roma, coppie Roma, famiglie Roma, Associazione no-profit Roma, Genitori con la patente APS Roma, servizi psicologici sostenibili Roma, Psicologo a Roma, psicologi a Roma, psicologia a Roma, psicoterapia a Roma, psicoterapeuti a Roma, Psicoterapeuta a Roma, Ipnologo a Roma, ipnologi a Roma, sostegno psicologico a Roma, supporto psicologico a Roma, percorso psicologico a Roma, Psicologo clinico a Roma, Psicoterapeuta a Roma, Psicoterapie Brevi a Roma, Approccio Strategico a Roma, Ipnologo a Roma, Ordine Psicologi Lazio a Roma, disagio psicologico a Roma, Psicoterapia Breve Strategica a Roma, Ipnosi clinica a Roma, PNL a Roma, Mindfulness a Roma, Acceptance and Commitment Therapy a Roma, ACT a Roma, Eckhart Tolle a Roma, problemi relazionali a Roma, autostima a Roma, ansia a Roma, depressione a Roma, comunicazione disfunzionale a Roma, elaborazione traumi a Roma, elaborazione lutto a Roma, Master in Sessuologia clinica a Roma, problemi sfera sessuale a Roma, Master in Psicologia e trattamento Dipendenze a Roma, dipendenze affettive a Roma, dipendenze sessuali a Roma, dipendenze Internet a Roma, adulti a Roma, giovani adulti a Roma, coppie a Roma, famiglie a Roma, Associazione no-profit a Roma, Genitori con la patente APS a Roma, servizi psicologici sostenibili a Roma,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T16:20:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/\",\"name\":\"Dott. Domenico Berardi - Psicologo, Psicoterapeuta, Ipnologo - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png\",\"datePublished\":\"2025-11-11T15:17:53+00:00\",\"dateModified\":\"2025-11-11T16:20:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Domenico Berardi &#8211; Psicologo, Psicoterapeuta, Ipnologo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Domenico Berardi - Psicologo, Psicoterapeuta, Ipnologo - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Domenico Berardi - Psicologo, Psicoterapeuta, Ipnologo - UIL Polizia","og_description":"Psicologo clinico, Psicoterapeuta e Ipnologo Sono uno Psicologo clinico, Psicoterapeuta specializzato in Psicoterapie Brevi ad Approccio Strategico e Ipnologo, iscritto all\u2019Albo dell\u2019Ordine degli Psicologi della Regione Lazio\u00a0con il n. 19917. Mi occupo delle varie forme di disagio psicologico, utilizzando varie tecniche d\u2019intervento, tra cui la\u00a0Psicoterapia Breve Strategica, l\u2019Ipnosi clinica, la PNL, la Mindfulness, l\u2019Acceptance and Commitment Theraphy\u00a0(ACT). Condivido e utilizzo anche i principi e le tecniche di sviluppo della consapevolezza di\u00a0Eckhart Tolle. Il mio campo d\u2019intervento riguarda principalmente i\u00a0problemi relazionali, di\u00a0autostima, di\u00a0ansia, di\u00a0depressione, di\u00a0comunicazione\u00a0disfunzionale, l\u2019elaborazione dei\u00a0traumi\u00a0e del\u00a0lutto. Ho conseguito anche un\u00a0Master in\u00a0Sessuologia clinica\u00a0per trattare i problemi relativi alla sfera sessuale e un\u00a0Master in\u00a0Psicologia e trattamento delle Dipendenze\u00a0(in particolare affettive, sessuali e da Internet). Mi occupo principalmente di adulti e giovani adulti, coppie e famiglie. Svolgo la mia attivit\u00e0 come volontario presso l\u2019Associazione no-profit\u00a0\u201cGenitori con la patente\u00ae \u2013 APS\u201d, la quale applica dei\u00a0costi particolarmente sostenibili\u00a0per consentire l\u2019accesso ai servizi psicologici anche alle persone economicamente pi\u00f9 svantaggiate. La mia formazione Scarica il mio Curriculum VitaeDott. Domenico Berard Psicologo, psicologi, psicologia, psicoterapia, psicoterapeuti, Psicoterapeuta, Ipnologo, ipnologi, sostegno psicologico, supporto psicologico, percorso psicologico, Psicologo clinico, Psicoterapeuta, Psicoterapie Brevi, Approccio Strategico, Ipnologo, Ordine Psicologi Lazio, disagio psicologico, Psicoterapia Breve Strategica, Ipnosi clinica, PNL, Mindfulness, Acceptance and Commitment Therapy, ACT, Eckhart Tolle, problemi relazionali, autostima, ansia, depressione, comunicazione disfunzionale, elaborazione traumi, elaborazione lutto, Master in Sessuologia clinica, problemi sfera sessuale, Master in Psicologia e trattamento Dipendenze, dipendenze affettive, dipendenze sessuali, dipendenze Internet, adulti, giovani adulti, coppie, famiglie, Associazione no-profit, Genitori con la patente APS, servizi psicologici sostenibili, Roma, Psicologo Roma, psicologi Roma, psicologia Roma, psicoterapia Roma, psicoterapeuti Roma, Psicoterapeuta Roma, Ipnologo Roma, ipnologi Roma, sostegno psicologico Roma, supporto psicologico Roma, percorso psicologico Roma, Psicologo clinico Roma, Psicoterapeuta Roma, Psicoterapie Brevi Roma, Approccio Strategico Roma, Ipnologo Roma, Ordine Psicologi Lazio Roma, disagio psicologico Roma, Psicoterapia Breve Strategica Roma, Ipnosi clinica Roma, PNL Roma, Mindfulness Roma, Acceptance and Commitment Therapy Roma, ACT Roma, Eckhart Tolle Roma, problemi relazionali Roma, autostima Roma, ansia Roma, depressione Roma, comunicazione disfunzionale Roma, elaborazione traumi Roma, elaborazione lutto Roma, Master in Sessuologia clinica Roma, problemi sfera sessuale Roma, Master in Psicologia e trattamento Dipendenze Roma, dipendenze affettive Roma, dipendenze sessuali Roma, dipendenze Internet Roma, adulti Roma, giovani adulti Roma, coppie Roma, famiglie Roma, Associazione no-profit Roma, Genitori con la patente APS Roma, servizi psicologici sostenibili Roma, Psicologo a Roma, psicologi a Roma, psicologia a Roma, psicoterapia a Roma, psicoterapeuti a Roma, Psicoterapeuta a Roma, Ipnologo a Roma, ipnologi a Roma, sostegno psicologico a Roma, supporto psicologico a Roma, percorso psicologico a Roma, Psicologo clinico a Roma, Psicoterapeuta a Roma, Psicoterapie Brevi a Roma, Approccio Strategico a Roma, Ipnologo a Roma, Ordine Psicologi Lazio a Roma, disagio psicologico a Roma, Psicoterapia Breve Strategica a Roma, Ipnosi clinica a Roma, PNL a Roma, Mindfulness a Roma, Acceptance and Commitment Therapy a Roma, ACT a Roma, Eckhart Tolle a Roma, problemi relazionali a Roma, autostima a Roma, ansia a Roma, depressione a Roma, comunicazione disfunzionale a Roma, elaborazione traumi a Roma, elaborazione lutto a Roma, Master in Sessuologia clinica a Roma, problemi sfera sessuale a Roma, Master in Psicologia e trattamento Dipendenze a Roma, dipendenze affettive a Roma, dipendenze sessuali a Roma, dipendenze Internet a Roma, adulti a Roma, giovani adulti a Roma, coppie a Roma, famiglie a Roma, Associazione no-profit a Roma, Genitori con la patente APS a Roma, servizi psicologici sostenibili a Roma,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/","og_site_name":"UIL Polizia","article_modified_time":"2025-11-11T16:20:38+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/","name":"Dott. Domenico Berardi - Psicologo, Psicoterapeuta, Ipnologo - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png","datePublished":"2025-11-11T15:17:53+00:00","dateModified":"2025-11-11T16:20:38+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/11\/Logo-siti-dott-berardi-genitori-con-la-patente.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-domenico-berardi-psicologo-psicoterapeuta-ipnologo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Domenico Berardi &#8211; Psicologo, Psicoterapeuta, Ipnologo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/81059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=81059"}],"version-history":[{"count":4,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/81059\/revisions"}],"predecessor-version":[{"id":81096,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/81059\/revisions\/81096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/81060"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=81059"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=81059"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=81059"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=81059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}