{"id":78685,"date":"2025-10-22T10:59:15","date_gmt":"2025-10-22T08:59:15","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=78685"},"modified":"2025-10-22T12:03:44","modified_gmt":"2025-10-22T10:03:44","slug":"rp-di-rondelli-paolo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/","title":{"rendered":"RP di Rondelli Paolo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"78685\" class=\"elementor elementor-78685\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-481488b2 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"481488b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-322f70df\" data-id=\"322f70df\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21abe358 elementor-widget elementor-widget-image\" data-id=\"21abe358\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"908\" height=\"472\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/LOGO-PAOLO-RONDELLI-senza-sfondo-2-1.png\" class=\"attachment-full size-full wp-image-78753\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/LOGO-PAOLO-RONDELLI-senza-sfondo-2-1.png 908w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/LOGO-PAOLO-RONDELLI-senza-sfondo-2-1-480x250.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 908px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a0dbf6c\" data-id=\"a0dbf6c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e93fd86 elementor-widget elementor-widget-spacer\" data-id=\"2e93fd86\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-480baab0 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"480baab0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef0247d e-con-full e-flex e-con e-child\" data-id=\"ef0247d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19a951b9 elementor-widget elementor-widget-text-editor\" data-id=\"19a951b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-665bf45c elementor-widget elementor-widget-text-editor\" data-id=\"665bf45c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSoluzioni personalizzate e su misura per impianti fotovoltaici, impianti di allarme e videosorveglianza e impianti elettrici civili e industriali\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50687832 elementor-widget elementor-widget-text-editor\" data-id=\"50687832\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo un&#8217;azienda leader nel settore degli impianti fotovoltaici, elettrici civili e industriali, sistemi di allarme, videosorveglianza e domotica. Con oltre 10 anni di esperienza alle spalle, la nostra azienda ha saputo crescere e innovarsi costantemente, diventando un punto di riferimento per l&#8217;Alto Chiascio, Gualdo Tadino, Nocera Umbra e oltre.<\/p><p>R.P. Impianti \u00e8 nata dal sogno di Paolo Rondelli, un artigiano e imprenditore che, sin da giovane, ha voluto guadagnarsi da vivere grazie alle proprie capacit\u00e0 e offrire opportunit\u00e0 di lavoro a chi lo circondava. Partendo da zero, con solo un furgoncino bianco pieno di attrezzi, Paolo ha costruito un&#8217;impresa solida che oggi conta 20 dipendenti.<\/p><p>Ogni giorno lavoriamo con passione e dedizione per garantire la massima qualit\u00e0 nei nostri servizi. Che si tratti di grandi appalti nazionali o di piccoli interventi locali, il nostro obiettivo \u00e8 sempre lo stesso: soddisfare le esigenze dei nostri clienti con soluzioni innovative e personalizzate.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-224e4463 e-flex e-con-boxed e-con e-child\" data-id=\"224e4463\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:78768,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/82924064_566016997314811_6544391855331606528_n.jpg&quot;},{&quot;id&quot;:78769,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.54.31-4.jpeg&quot;},{&quot;id&quot;:78770,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.56.43-1.jpeg&quot;},{&quot;id&quot;:78771,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.54.31-1.jpeg&quot;},{&quot;id&quot;:78772,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/96215213_628451021071408_8772924589928873984_n.jpg&quot;},{&quot;id&quot;:78773,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.54.30-1.jpeg&quot;},{&quot;id&quot;:78774,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/106998688_664148990834944_1602979799463587514_n.jpg&quot;},{&quot;id&quot;:78775,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/126314735_761936297722879_8475041277274761603_n.jpg&quot;},{&quot;id&quot;:78776,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/107893754_669391850310658_7588440889234689972_n.jpg&quot;},{&quot;id&quot;:78777,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/84717171_566016967314814_1291793890528985088_n.jpg&quot;},{&quot;id&quot;:78778,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/106732286_664148937501616_8072561650186142695_n.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2000,&quot;background_slideshow_transition_duration&quot;:200,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22e21157 elementor-widget elementor-widget-spacer\" data-id=\"22e21157\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-732845f2 e-flex e-con-boxed e-con e-child\" data-id=\"732845f2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64a54f41 elementor-widget elementor-widget-text-editor\" data-id=\"64a54f41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tServizi che offriamo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e453bfa elementor-widget elementor-widget-text-editor\" data-id=\"4e453bfa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Passa all&#8217;energia solare. Il Futuro \u00e8 adesso!<\/strong><br \/>Richiedi un preventivo gratuito per un impianto fotovoltaico con batteria d&#8217;accumulo, la soluzione economicamente ed ecologicamente pi\u00f9 vantaggiosa per autoprodurre energia elettrica.<\/p><p><strong>Impianti di allarme e videosorveglianza<\/strong><br \/>Offriamo impianti di allarme e videosorveglianza di ultima generazione, progettati per garantire la sicurezza totale di case e aziende. <br \/>Utilizziamo tecnologie avanzate per fornire soluzioni affidabili e su misura, che proteggono i tuoi beni e offrono tranquillit\u00e0.<\/p><p><strong>Impianti elettrici civili e industriali<\/strong><br \/>Siamo specializzati nella progettazione e installazione di impianti elettrici civili e industriali. <br \/>Offriamo soluzioni personalizzate per abitazioni private e strutture aziendali, garantendo sicurezza, efficienza e conformit\u00e0 alle normative vigenti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc0d4b5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6dc0d4b5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.rp-impianti.com\/contatti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contattaci ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56343c70 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"56343c70\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f025064 e-con-full e-flex e-con e-child\" data-id=\"3f025064\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1c2343 elementor-widget elementor-widget-text-editor\" data-id=\"5e1c2343\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37fa3cbe elementor-widget elementor-widget-text-editor\" data-id=\"37fa3cbe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSoluzioni personalizzate e su misura per impianti fotovoltaici, impianti di allarme e videosorveglianza e impianti elettrici civili e industriali\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef9ea9 elementor-widget elementor-widget-text-editor\" data-id=\"aef9ea9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo un&#8217;azienda leader nel settore degli impianti fotovoltaici, elettrici civili e industriali, sistemi di allarme, videosorveglianza e domotica. Con oltre 10 anni di esperienza alle spalle, la nostra azienda ha saputo crescere e innovarsi costantemente, diventando un punto di riferimento per l&#8217;Alto Chiascio, Gualdo Tadino, Nocera Umbra e oltre.<\/p><p>R.P. Impianti \u00e8 nata dal sogno di Paolo Rondelli, un artigiano e imprenditore che, sin da giovane, ha voluto guadagnarsi da vivere grazie alle proprie capacit\u00e0 e offrire opportunit\u00e0 di lavoro a chi lo circondava. Partendo da zero, con solo un furgoncino bianco pieno di attrezzi, Paolo ha costruito un&#8217;impresa solida che oggi conta 20 dipendenti.<\/p><p>Ogni giorno lavoriamo con passione e dedizione per garantire la massima qualit\u00e0 nei nostri servizi. Che si tratti di grandi appalti nazionali o di piccoli interventi locali, il nostro obiettivo \u00e8 sempre lo stesso: soddisfare le esigenze dei nostri clienti con soluzioni innovative e personalizzate.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f6fca2e e-con-full e-flex e-con e-child\" data-id=\"5f6fca2e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:78768,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/82924064_566016997314811_6544391855331606528_n.jpg&quot;},{&quot;id&quot;:78769,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.54.31-4.jpeg&quot;},{&quot;id&quot;:78770,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.56.43-1.jpeg&quot;},{&quot;id&quot;:78771,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.54.31-1.jpeg&quot;},{&quot;id&quot;:78772,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/96215213_628451021071408_8772924589928873984_n.jpg&quot;},{&quot;id&quot;:78773,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/WhatsApp-Image-2023-02-08-at-21.54.30-1.jpeg&quot;},{&quot;id&quot;:78774,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/106998688_664148990834944_1602979799463587514_n.jpg&quot;},{&quot;id&quot;:78775,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/126314735_761936297722879_8475041277274761603_n.jpg&quot;},{&quot;id&quot;:78776,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/107893754_669391850310658_7588440889234689972_n.jpg&quot;},{&quot;id&quot;:78777,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/84717171_566016967314814_1291793890528985088_n.jpg&quot;},{&quot;id&quot;:78778,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/106732286_664148937501616_8072561650186142695_n.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2000,&quot;background_slideshow_transition_duration&quot;:200,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-188393dd elementor-widget elementor-widget-spacer\" data-id=\"188393dd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bc936ea e-con-full e-flex e-con e-child\" data-id=\"4bc936ea\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3437401f elementor-widget elementor-widget-text-editor\" data-id=\"3437401f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tServizi che offriamo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68dc32f3 elementor-widget elementor-widget-text-editor\" data-id=\"68dc32f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Passa all&#8217;energia solare. Il Futuro \u00e8 adesso!<\/strong><br \/>Richiedi un preventivo gratuito per un impianto fotovoltaico con batteria d&#8217;accumulo, la soluzione economicamente ed ecologicamente pi\u00f9 vantaggiosa per autoprodurre energia elettrica.<\/p><p><strong>Impianti di allarme e videosorveglianza<\/strong><br \/>Offriamo impianti di allarme e videosorveglianza di ultima generazione, progettati per garantire la sicurezza totale di case e aziende. <br \/>Utilizziamo tecnologie avanzate per fornire soluzioni affidabili e su misura, che proteggono i tuoi beni e offrono tranquillit\u00e0.<\/p><p><strong>Impianti elettrici civili e industriali<\/strong><br \/>Siamo specializzati nella progettazione e installazione di impianti elettrici civili e industriali. <br \/>Offriamo soluzioni personalizzate per abitazioni private e strutture aziendali, garantendo sicurezza, efficienza e conformit\u00e0 alle normative vigenti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c566b97 elementor-widget elementor-widget-button\" data-id=\"4c566b97\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.rp-impianti.com\/contatti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contattaci ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-331b6a64 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"331b6a64\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62833138 e-flex e-con-boxed e-con e-child\" data-id=\"62833138\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18872de1 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"18872de1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate <br \/>agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5ddd55 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2b5ddd55\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b581922 elementor-widget elementor-widget-text-editor\" data-id=\"1b581922\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66730285 elementor-widget elementor-widget-text-editor\" data-id=\"66730285\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>RP DI RONDELLI PAOLO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55334530 elementor-widget elementor-widget-text-editor\" data-id=\"55334530\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Flaminia Nord KM 191 &#8211; 06023 Gualdo Tardino (PG)<br \/><strong>Tel: <\/strong><a href=\"tel:+390756101510\">0756101510<\/a><strong><br \/>Cell: <\/strong><a href=\"tel:+393336157717\">3336157717<\/a> &#8211; <a href=\"tel:+393205719704\">3205719704<\/a><br \/><strong>Mail: <\/strong><a href=\"mailto:info@rp-impianti.com\">info@rp-impianti.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49b3bc4e elementor-widget elementor-widget-text-editor\" data-id=\"49b3bc4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.rp-impianti.com\/\">www.rp-impianti.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5527aff3 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"5527aff3\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-c6b0c59\" href=\"https:\/\/www.facebook.com\/impiantielettri?mibextid=wwXIfr&#038;rdid=ohru1UnISRUL2Oqh&#038;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F1GhzTksN8L%2F%3Fmibextid%3DwwXIfr#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-610e95e\" href=\"https:\/\/www.instagram.com\/rondellipaolo_impianti\/#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2db05ae0 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"2db05ae0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-359\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"78685\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-359\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-359\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-359\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-359\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"359\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b2f1997 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"4b2f1997\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-248e69ea e-con-full e-flex e-con e-child\" data-id=\"248e69ea\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74cca5b9 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"74cca5b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-346\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"78685\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-346\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:600px;\"> <span id=\"gmw-resize-map-toggle-346\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-346\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-346\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"346\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24d9d2e2 e-flex e-con-boxed e-con e-child\" data-id=\"24d9d2e2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bb55fcc elementor-widget elementor-widget-text-editor\" data-id=\"2bb55fcc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate <br \/>agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9274655 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9274655\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-483053a4 elementor-widget elementor-widget-text-editor\" data-id=\"483053a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29dc732d elementor-widget elementor-widget-text-editor\" data-id=\"29dc732d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>RP DI RONDELLI PAOLO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aa8a309 elementor-widget elementor-widget-text-editor\" data-id=\"4aa8a309\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Flaminia Nord KM 191 &#8211; 06023 Gualdo Tardino (PG)<br \/><strong>Tel: <\/strong><a href=\"tel:+390756101510\">0756101510<\/a><strong><br \/>Cell: <\/strong><a href=\"tel:+393336157717\">3336157717<\/a> &#8211; <a href=\"tel:+393205719704\">3205719704<\/a><br \/><strong>Mail: <\/strong><a href=\"mailto:info@rp-impianti.com\">info@rp-impianti.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-385c750e elementor-widget elementor-widget-text-editor\" data-id=\"385c750e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.rp-impianti.com\/\">www.rp-impianti.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd5b129 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"6cd5b129\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-c6b0c59\" href=\"https:\/\/www.facebook.com\/impiantielettri?mibextid=wwXIfr&#038;rdid=ohru1UnISRUL2Oqh&#038;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F1GhzTksN8L%2F%3Fmibextid%3DwwXIfr#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-610e95e\" href=\"https:\/\/www.instagram.com\/rondellipaolo_impianti\/#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Siamo un&#8217;azienda leader nel settore degli impianti fotovoltaici, elettrici civili e industriali, sistemi di allarme, videosorveglianza e domotica. Con oltre 10 anni di esperienza alle spalle, la nostra azienda ha saputo crescere e innovarsi costantemente, diventando un punto di riferimento per l&#8217;Alto Chiascio, Gualdo Tadino, Nocera Umbra e oltre.<br \/>\nR.P. Impianti \u00e8 nata dal sogno di Paolo Rondelli, un artigiano e imprenditore che, sin da giovane, ha voluto guadagnarsi da vivere grazie alle proprie capacit\u00e0 e offrire opportunit\u00e0 di lavoro a chi lo circondava. Partendo da zero, con solo un furgoncino bianco pieno di attrezzi, Paolo ha costruito un&#8217;impresa solida che oggi conta 20 dipendenti<br \/>\nOgni giorno lavoriamo con passione e dedizione per garantire la massima qualit\u00e0 nei nostri servizi. Che si tratti di grandi appalti nazionali o di piccoli interventi locali, il nostro obiettivo \u00e8 sempre lo stesso: soddisfare le esigenze dei nostri clienti con soluzioni innovative e personalizzate.<br \/>\nIl nostro team \u00e8 composto da professionisti altamente qualificati, guidati dal capo-tecnico Maurizio, e un solido nucleo di personale amministrativo. Crediamo nella formazione continua e nell&#8217;innovazione, per questo siamo sempre alla ricerca di nuovi talenti da inserire nel nostro organico.<br \/>\nIl nostro percorso non \u00e8 stato privo di difficolt\u00e0, ma grazie alla determinazione e alla capacit\u00e0 di adattarsi ai cambiamenti, siamo riusciti a superare ogni sfida. Il periodo del Covid-19 \u00e8 stato un trampolino di lancio, permettendoci di raggiungere un fatturato di diversi milioni di euro.<br \/>\nGuardiamo al futuro con ottimismo, pronti a investire in nuove tecnologie e ad espandere la nostra presenza sul mercato. Siamo sempre aperti a nuove opportunit\u00e0 di lavoro e invitiamo i giovani motivati a unirsi a noi per costruire insieme un futuro migliore.<br \/>\nSiamo R.P. Impianti, e siamo qui per offrirvi il meglio della tecnologia e del servizio nel nostro settore. Contattateci per scoprire come possiamo aiutarvi a realizzare i vostri progetti.<\/p>\n<p>fotovoltaico, progettazione impianti fotovoltaici, installazione impianti fotovoltaici, manutenzione impianti fotovoltaici, progettazione impianti elettrici, installazione impianti elettrici, manutenzione impianti elettrici, progettazione sistemi di videosorveglianza, installazione sistemi di videosorveglianza, manutenzione sistemi di videosorveglianza, progettazione allarmi, installazione allarmi, manutenzione allarmi, sistemi di allarme, efficienza energetica, risparmio energia, sicurezza, allarme di sicurezza,<\/p>\n<p>progettazione impianti fotovoltaici a Gualdo Tadino, installazione impianti fotovoltaici a Gualdo Tadino, manutenzione impianti fotovoltaici a Gualdo Tadino, sistemi di allarme a Gualdo Tadino, progettazione impianti elettrici a Gualdo Tadino, installazione impianti elettrici a Gualdo Tadino, manutenzione impianti elettrici a Gualdo Tadino, progettazione sistemi di videosorveglianza a Gualdo Tadino, installazione sistemi di videosorveglianza a Gualdo Tadino, manutenzione sistemi di videosorveglianza a Gualdo Tadino, progettazione allarmi a Gualdo Tadino, installazione allarmi a Gualdo Tadino, manutenzione allarmi a Gualdo Tadino,<br \/>\nPerugia, Ancona,<br \/>\nfotovoltaico Perugia, fotovoltaico Ancona, fotovoltaico Gualdo Tadino, fotovoltaico a Perugia, fotovoltaico a Ancona, fotovoltaico ad Ancona, fotovoltaico a Gualdo Tadino,<br \/>\nfotovoltaici Perugia, fotovoltaici Ancona, fotovoltaici Gualdo Tadino, fotovoltaici a Perugia, fotovoltaici a Ancona, fotovoltaici a Gualdo Tadino,<\/p>\n<\/div>\n","protected":false},"featured_media":78686,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[58,65,67,68,71],"product_tag":[13904,10904,759,13902,13897,8999,13899,13903,13337,9406,13900,13901,11506,9419,13898,9875,3164,1790],"class_list":{"0":"post-78685","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-casa","7":"product_cat-fotovoltaico","8":"product_cat-impianti","9":"product_cat-impianti-di-allarme","10":"product_cat-impianti-elettrici","11":"product_tag-allarme-di-sicurezza","12":"product_tag-efficienza-energetica","13":"product_tag-fotovoltaico","14":"product_tag-installazione-allarmi","15":"product_tag-installazione-impianti-elettrici","16":"product_tag-installazione-impianti-fotovoltaici","17":"product_tag-installazione-sistemi-di-videosorveglianza","18":"product_tag-manutenzione-allarmi","19":"product_tag-manutenzione-impianti-elettrici","20":"product_tag-manutenzione-impianti-fotovoltaici","21":"product_tag-manutenzione-sistemi-di-videosorveglianza","22":"product_tag-progettazione-allarmi","23":"product_tag-progettazione-impianti-elettrici","24":"product_tag-progettazione-impianti-fotovoltaici","25":"product_tag-progettazione-sistemi-di-videosorveglianza","26":"product_tag-risparmio-energia","27":"product_tag-sicurezza","28":"product_tag-sistemi-di-allarme","30":"first","31":"instock","32":"shipping-taxable","33":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RP di Rondelli Paolo - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RP di Rondelli Paolo - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Siamo un&#039;azienda leader nel settore degli impianti fotovoltaici, elettrici civili e industriali, sistemi di allarme, videosorveglianza e domotica. Con oltre 10 anni di esperienza alle spalle, la nostra azienda ha saputo crescere e innovarsi costantemente, diventando un punto di riferimento per l&#039;Alto Chiascio, Gualdo Tadino, Nocera Umbra e oltre. R.P. Impianti \u00e8 nata dal sogno di Paolo Rondelli, un artigiano e imprenditore che, sin da giovane, ha voluto guadagnarsi da vivere grazie alle proprie capacit\u00e0 e offrire opportunit\u00e0 di lavoro a chi lo circondava. Partendo da zero, con solo un furgoncino bianco pieno di attrezzi, Paolo ha costruito un&#039;impresa solida che oggi conta 20 dipendenti Ogni giorno lavoriamo con passione e dedizione per garantire la massima qualit\u00e0 nei nostri servizi. Che si tratti di grandi appalti nazionali o di piccoli interventi locali, il nostro obiettivo \u00e8 sempre lo stesso: soddisfare le esigenze dei nostri clienti con soluzioni innovative e personalizzate. Il nostro team \u00e8 composto da professionisti altamente qualificati, guidati dal capo-tecnico Maurizio, e un solido nucleo di personale amministrativo. Crediamo nella formazione continua e nell&#039;innovazione, per questo siamo sempre alla ricerca di nuovi talenti da inserire nel nostro organico. Il nostro percorso non \u00e8 stato privo di difficolt\u00e0, ma grazie alla determinazione e alla capacit\u00e0 di adattarsi ai cambiamenti, siamo riusciti a superare ogni sfida. Il periodo del Covid-19 \u00e8 stato un trampolino di lancio, permettendoci di raggiungere un fatturato di diversi milioni di euro. Guardiamo al futuro con ottimismo, pronti a investire in nuove tecnologie e ad espandere la nostra presenza sul mercato. Siamo sempre aperti a nuove opportunit\u00e0 di lavoro e invitiamo i giovani motivati a unirsi a noi per costruire insieme un futuro migliore. Siamo R.P. Impianti, e siamo qui per offrirvi il meglio della tecnologia e del servizio nel nostro settore. Contattateci per scoprire come possiamo aiutarvi a realizzare i vostri progetti.    fotovoltaico, progettazione impianti fotovoltaici, installazione impianti fotovoltaici, manutenzione impianti fotovoltaici, progettazione impianti elettrici, installazione impianti elettrici, manutenzione impianti elettrici, progettazione sistemi di videosorveglianza, installazione sistemi di videosorveglianza, manutenzione sistemi di videosorveglianza, progettazione allarmi, installazione allarmi, manutenzione allarmi, sistemi di allarme, efficienza energetica, risparmio energia, sicurezza, allarme di sicurezza,    progettazione impianti fotovoltaici a Gualdo Tadino, installazione impianti fotovoltaici a Gualdo Tadino, manutenzione impianti fotovoltaici a Gualdo Tadino, sistemi di allarme a Gualdo Tadino, progettazione impianti elettrici a Gualdo Tadino, installazione impianti elettrici a Gualdo Tadino, manutenzione impianti elettrici a Gualdo Tadino, progettazione sistemi di videosorveglianza a Gualdo Tadino, installazione sistemi di videosorveglianza a Gualdo Tadino, manutenzione sistemi di videosorveglianza a Gualdo Tadino, progettazione allarmi a Gualdo Tadino, installazione allarmi a Gualdo Tadino, manutenzione allarmi a Gualdo Tadino, Perugia, Ancona, fotovoltaico Perugia, fotovoltaico Ancona, fotovoltaico Gualdo Tadino, fotovoltaico a Perugia, fotovoltaico a Ancona, fotovoltaico ad Ancona, fotovoltaico a Gualdo Tadino, fotovoltaici Perugia, fotovoltaici Ancona, fotovoltaici Gualdo Tadino, fotovoltaici a Perugia, fotovoltaici a Ancona, fotovoltaici a Gualdo Tadino,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T10:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/\",\"name\":\"RP di Rondelli Paolo - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg\",\"datePublished\":\"2025-10-22T08:59:15+00:00\",\"dateModified\":\"2025-10-22T10:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RP di Rondelli Paolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RP di Rondelli Paolo - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/","og_locale":"it_IT","og_type":"article","og_title":"RP di Rondelli Paolo - UIL Polizia","og_description":"Siamo un'azienda leader nel settore degli impianti fotovoltaici, elettrici civili e industriali, sistemi di allarme, videosorveglianza e domotica. Con oltre 10 anni di esperienza alle spalle, la nostra azienda ha saputo crescere e innovarsi costantemente, diventando un punto di riferimento per l'Alto Chiascio, Gualdo Tadino, Nocera Umbra e oltre. R.P. Impianti \u00e8 nata dal sogno di Paolo Rondelli, un artigiano e imprenditore che, sin da giovane, ha voluto guadagnarsi da vivere grazie alle proprie capacit\u00e0 e offrire opportunit\u00e0 di lavoro a chi lo circondava. Partendo da zero, con solo un furgoncino bianco pieno di attrezzi, Paolo ha costruito un'impresa solida che oggi conta 20 dipendenti Ogni giorno lavoriamo con passione e dedizione per garantire la massima qualit\u00e0 nei nostri servizi. Che si tratti di grandi appalti nazionali o di piccoli interventi locali, il nostro obiettivo \u00e8 sempre lo stesso: soddisfare le esigenze dei nostri clienti con soluzioni innovative e personalizzate. Il nostro team \u00e8 composto da professionisti altamente qualificati, guidati dal capo-tecnico Maurizio, e un solido nucleo di personale amministrativo. Crediamo nella formazione continua e nell'innovazione, per questo siamo sempre alla ricerca di nuovi talenti da inserire nel nostro organico. Il nostro percorso non \u00e8 stato privo di difficolt\u00e0, ma grazie alla determinazione e alla capacit\u00e0 di adattarsi ai cambiamenti, siamo riusciti a superare ogni sfida. Il periodo del Covid-19 \u00e8 stato un trampolino di lancio, permettendoci di raggiungere un fatturato di diversi milioni di euro. Guardiamo al futuro con ottimismo, pronti a investire in nuove tecnologie e ad espandere la nostra presenza sul mercato. Siamo sempre aperti a nuove opportunit\u00e0 di lavoro e invitiamo i giovani motivati a unirsi a noi per costruire insieme un futuro migliore. Siamo R.P. Impianti, e siamo qui per offrirvi il meglio della tecnologia e del servizio nel nostro settore. Contattateci per scoprire come possiamo aiutarvi a realizzare i vostri progetti.    fotovoltaico, progettazione impianti fotovoltaici, installazione impianti fotovoltaici, manutenzione impianti fotovoltaici, progettazione impianti elettrici, installazione impianti elettrici, manutenzione impianti elettrici, progettazione sistemi di videosorveglianza, installazione sistemi di videosorveglianza, manutenzione sistemi di videosorveglianza, progettazione allarmi, installazione allarmi, manutenzione allarmi, sistemi di allarme, efficienza energetica, risparmio energia, sicurezza, allarme di sicurezza,    progettazione impianti fotovoltaici a Gualdo Tadino, installazione impianti fotovoltaici a Gualdo Tadino, manutenzione impianti fotovoltaici a Gualdo Tadino, sistemi di allarme a Gualdo Tadino, progettazione impianti elettrici a Gualdo Tadino, installazione impianti elettrici a Gualdo Tadino, manutenzione impianti elettrici a Gualdo Tadino, progettazione sistemi di videosorveglianza a Gualdo Tadino, installazione sistemi di videosorveglianza a Gualdo Tadino, manutenzione sistemi di videosorveglianza a Gualdo Tadino, progettazione allarmi a Gualdo Tadino, installazione allarmi a Gualdo Tadino, manutenzione allarmi a Gualdo Tadino, Perugia, Ancona, fotovoltaico Perugia, fotovoltaico Ancona, fotovoltaico Gualdo Tadino, fotovoltaico a Perugia, fotovoltaico a Ancona, fotovoltaico ad Ancona, fotovoltaico a Gualdo Tadino, fotovoltaici Perugia, fotovoltaici Ancona, fotovoltaici Gualdo Tadino, fotovoltaici a Perugia, fotovoltaici a Ancona, fotovoltaici a Gualdo Tadino,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/","og_site_name":"UIL Polizia","article_modified_time":"2025-10-22T10:03:44+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/","name":"RP di Rondelli Paolo - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg","datePublished":"2025-10-22T08:59:15+00:00","dateModified":"2025-10-22T10:03:44+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/10\/logo_RP-di-Rondelli-Paolo.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/rp-di-rondelli-paolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"RP di Rondelli Paolo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/78685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=78685"}],"version-history":[{"count":4,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/78685\/revisions"}],"predecessor-version":[{"id":78813,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/78685\/revisions\/78813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/78686"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=78685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=78685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=78685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=78685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}