{"id":73553,"date":"2025-06-16T17:08:44","date_gmt":"2025-06-16T15:08:44","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=73553"},"modified":"2025-06-16T17:41:51","modified_gmt":"2025-06-16T15:41:51","slug":"la-piana-mattia-salvatore-agente-immobiliare","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/","title":{"rendered":"La Piana Mattia Salvatore &#8211; Agente Immobiliare"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"73553\" class=\"elementor elementor-73553\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fa5032 e-flex e-con-boxed e-con e-parent\" data-id=\"5fa5032\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-508c8e8 e-con-full e-flex e-con e-child\" data-id=\"508c8e8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c6c1ad elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1c6c1ad\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"993\" height=\"543\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare.jpg\" class=\"attachment-large size-large wp-image-73560\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare.jpg 993w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare-980x536.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare-480x262.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 993px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4846135 e-con-full e-flex e-con e-child\" data-id=\"4846135\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-118c366 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"118c366\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"663\" height=\"962\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-mattia-la-piana-ag-immobiliare.png\" class=\"attachment-large size-large wp-image-73557\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-mattia-la-piana-ag-immobiliare.png 663w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-mattia-la-piana-ag-immobiliare-480x696.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 663px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55e1173 e-flex e-con-boxed e-con e-parent\" data-id=\"55e1173\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c7f99d8 e-flex e-con-boxed e-con e-child\" data-id=\"c7f99d8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37b943b elementor-widget elementor-widget-text-editor\" data-id=\"37b943b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PRESENTAZIONE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd45d21 elementor-widget elementor-widget-text-editor\" data-id=\"bd45d21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mi chiamo Mattia Salvatore La Piana e sono il fondatore della mia agenzia immobiliare attiva su Catania e Provincia, ma operativa anche nelle zone di Siracusa, Augusta e Messina.<\/p><p>Dopo anni di gavetta in un noto franchising immobiliare, a fine settembre 2023 ho deciso di mettermi in proprio per costruire qualcosa di mio.<\/p><p>Nato come musicista, pianista laureato al Conservatorio e insegnante di musica, ho scelto di trasformare la mia passione per le persone e la cura nei dettagli in una nuova professione.<\/p><p>Oggi offro ai miei clienti trasparenza, seriet\u00e0, attenzione e passione, aiutandoli a vendere, acquistare o affittare con fiducia e serenit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d322fb0 e-flex e-con-boxed e-con e-parent\" data-id=\"d322fb0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1569bc6 e-con-full e-flex e-con e-child\" data-id=\"1569bc6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f688006 e-con-full e-flex e-con e-child\" data-id=\"f688006\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f19c77 elementor-widget elementor-widget-text-editor\" data-id=\"5f19c77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>servizi offerti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99efb46 e-con-full e-flex e-con e-child\" data-id=\"99efb46\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b871c15 e-con-full e-flex e-con e-child\" data-id=\"b871c15\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f22322 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1f22322\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Analisi di mercato immobiliare<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Redazione contratti di locazione e comodato<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Compravendite e locazioni<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Analisi della documentazione<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-208171d e-con-full e-flex e-con e-child\" data-id=\"208171d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c8f0c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b9c8f0c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Consulenze giuridiche, legali e finanziarie tramite professionisti indipendenti<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Assistenza fino al rogito notarile<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Inserzioni pubblicitarie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Collaborazioni con altre agenzie immobiliari<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bc67ed e-con-full e-flex e-con e-child\" data-id=\"2bc67ed\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-95b0de8 e-con-full e-flex e-con e-child\" data-id=\"95b0de8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ddc63c elementor-align-right elementor-tablet-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"5ddc63c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#contatti\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contattami<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32afe1f e-con-full e-flex e-con e-child\" data-id=\"32afe1f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4dec4c4 e-con-full e-flex e-con e-child\" data-id=\"4dec4c4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-51139a5 e-con-full e-flex e-con e-child\" data-id=\"51139a5\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-99fd43e e-flex e-con-boxed e-con e-child\" data-id=\"99fd43e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a07e2bd elementor-widget elementor-widget-text-editor\" data-id=\"a07e2bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>portali immobiliari<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1539fd elementor-widget elementor-widget-text-editor\" data-id=\"c1539fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 PortaleAgenzieImmobiliari.it<br \/>\u2022 Immobiliare.it<br \/>\u2022 Casa.it<br \/>\u2022 Subito.it<br \/>\u2022 Risorseimmobiliari.it<br \/>\u2022 Commerciali.it<br \/>\u2022 Idealista<br \/>\u2022 TrovaCasa<br \/>\u2022 Wikicasa<br \/>\u2022 Agestanet<br \/>\u2022 Marketplace<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bef997 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2bef997\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0758b44\" data-id=\"0758b44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f1a86a elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7f1a86a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-366fbbe e-flex e-con-boxed e-con e-parent\" data-id=\"366fbbe\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd96d74 e-con-full e-flex e-con e-child\" data-id=\"dd96d74\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7f2dc52 e-con-full e-flex e-con e-child\" data-id=\"7f2dc52\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-37e4812 e-con-full e-flex e-con e-child\" data-id=\"37e4812\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dabad88 elementor-widget elementor-widget-image\" data-id=\"dabad88\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"993\" height=\"543\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare.jpg\" class=\"attachment-large size-large wp-image-73560\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare.jpg 993w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare-980x536.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/img-logo-la-piana-ag-immobiliare-480x262.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 993px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc208b9 e-con-full e-flex e-con e-child\" data-id=\"bc208b9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02f6b49 elementor-widget elementor-widget-text-editor\" data-id=\"02f6b49\" data-element_type=\"widget\" id=\"contatti\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-919bdab elementor-widget elementor-widget-text-editor\" data-id=\"919bdab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Ingegnere, 31 &#8211; 95128 Catania (CT)<br \/>Cell: <a style=\"color: #444444;\" href=\"tel:+393802635077\" target=\"_blank\" rel=\"noopener\">380 2635077<\/a><br \/>Mail: <a style=\"color: #444444;\" href=\"mailto:mattialap98@gmail.com\" target=\"_blank\" rel=\"noopener\">mattialap98@gmail.com<\/a><br \/>Sito: <a style=\"color: #444444;\" href=\"https:\/\/lapianaagente.it\/\" target=\"_blank\" rel=\"noopener\">www.lapianaagente.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73baa92 elementor-widget elementor-widget-text-editor\" data-id=\"73baa92\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i>Si riceve previo appuntamento telefonico<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c83a3 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"32c83a3\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-phone-alt elementor-animation-shrink elementor-repeater-item-bf072c9\" href=\"tel:+393802635077\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Phone-alt<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-link elementor-animation-shrink elementor-repeater-item-fbfac9b\" href=\"https:\/\/lapianaagente.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Link<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-link\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M326.612 185.391c59.747 59.809 58.927 155.698.36 214.59-.11.12-.24.25-.36.37l-67.2 67.2c-59.27 59.27-155.699 59.262-214.96 0-59.27-59.26-59.27-155.7 0-214.96l37.106-37.106c9.84-9.84 26.786-3.3 27.294 10.606.648 17.722 3.826 35.527 9.69 52.721 1.986 5.822.567 12.262-3.783 16.612l-13.087 13.087c-28.026 28.026-28.905 73.66-1.155 101.96 28.024 28.579 74.086 28.749 102.325.51l67.2-67.19c28.191-28.191 28.073-73.757 0-101.83-3.701-3.694-7.429-6.564-10.341-8.569a16.037 16.037 0 0 1-6.947-12.606c-.396-10.567 3.348-21.456 11.698-29.806l21.054-21.055c5.521-5.521 14.182-6.199 20.584-1.731a152.482 152.482 0 0 1 20.522 17.197zM467.547 44.449c-59.261-59.262-155.69-59.27-214.96 0l-67.2 67.2c-.12.12-.25.25-.36.37-58.566 58.892-59.387 154.781.36 214.59a152.454 152.454 0 0 0 20.521 17.196c6.402 4.468 15.064 3.789 20.584-1.731l21.054-21.055c8.35-8.35 12.094-19.239 11.698-29.806a16.037 16.037 0 0 0-6.947-12.606c-2.912-2.005-6.64-4.875-10.341-8.569-28.073-28.073-28.191-73.639 0-101.83l67.2-67.19c28.239-28.239 74.3-28.069 102.325.51 27.75 28.3 26.872 73.934-1.155 101.96l-13.087 13.087c-4.35 4.35-5.769 10.79-3.783 16.612 5.864 17.194 9.042 34.999 9.69 52.721.509 13.906 17.454 20.446 27.294 10.606l37.106-37.106c59.271-59.259 59.271-155.699.001-214.959z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-shrink elementor-repeater-item-d06e700\" href=\"https:\/\/www.facebook.com\/lapiana.mattiasalvatore.agente\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-shrink elementor-repeater-item-4e496fc\" href=\"https:\/\/www.instagram.com\/lapiana.agente\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-shrink elementor-repeater-item-adc542a\" href=\"https:\/\/www.linkedin.com\/in\/mattia-s-la-piana-13b77329b\/?originalSubdomain=it\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7095eca e-con-full e-flex e-con e-child\" data-id=\"7095eca\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c273d88 elementor-widget elementor-widget-text-editor\" data-id=\"c273d88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-119\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-119\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:200px;\"> <span id=\"gmw-resize-map-toggle-119\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-119\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-119\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"119\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Mi chiamo Mattia Salvatore La Piana e sono il fondatore della mia agenzia immobiliare attiva su Catania e Provincia, ma operativa anche nelle zone di Siracusa, Augusta e Messina. Dopo anni di gavetta in un noto franchising immobiliare, a fine settembre 2023 ho deciso di mettermi in proprio per costruire qualcosa di mio.<br \/>\nNato come musicista, pianista laureato al Conservatorio e insegnante di musica, ho scelto di trasformare la mia passione per le persone e la cura nei dettagli in una nuova professione. Oggi offro ai miei clienti trasparenza, seriet\u00e0, attenzione e passione, aiutandoli a vendere, acquistare o affittare con fiducia e serenit\u00e0.agente immobiliare, agenzia immobiliare, agente immobiliare, agenti immobiliari, consulente immobiliare, consulenti immobiliari, immobili, immobili in vendita, case in vendita, casa, appartamenti, appartamenti in vendita, Analisi di mercato immobiliare, Redazione contratti di locazione e comodato, Compravendite, locazioni, compravendita, locazione, Analisi della documentazione, Consulenze giuridiche, legali e finanziarie tramite professionisti indipendenti, Assistenza fino al rogito notarile, Inserzioni pubblicitarie, Catania,<br \/>\nagente immobiliare Catania, agenzia immobiliare Catania, agente immobiliare Catania, agenti immobiliari Catania, consulente immobiliare Catania, consulenti immobiliari Catania, immobili Catania, immobili in vendita Catania, case in vendita Catania, casa Catania, appartamenti Catania, appartamenti in vendita Catania, Analisi di mercato immobiliare Catania, Redazione contratti di locazione e comodato Catania, Compravendite Catania, locazioni Catania, compravendita Catania, locazione Catania, Analisi della documentazione Catania, Consulenze giuridiche Catania, legali e finanziarie tramite professionisti indipendenti Catania, Assistenza fino al rogito notarile Catania, Inserzioni pubblicitarie Catania, agente immobiliare a Catania, agenzia immobiliare a Catania, agente immobiliare a Catania, agenti immobiliari a Catania, consulente immobiliare a Catania, consulenti immobiliari a Catania, immobili a Catania, immobili in vendita a Catania, case in vendita a Catania, casa a Catania, appartamenti a Catania, appartamenti in vendita a Catania, Analisi di mercato immobiliare a Catania, Redazione contratti di locazione e comodato a Catania, Compravendite a Catania, locazioni a Catania, compravendita a Catania, locazione a Catania, Analisi della documentazione a Catania, Consulenze giuridiche a Catania, legali e finanziarie tramite professionisti indipendenti a Catania, Assistenza fino al rogito notarile a Catania, Inserzioni pubblicitarie a Catania,<\/p>\n<\/div>\n","protected":false},"featured_media":73554,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[59,58],"product_tag":[12598,699,1197,873,12597,12602,12600,4172,12322,12605,12596,698,911,381,1192,3085,2941,2436,12603,12594,2067,12599,12606,12604,751,1915,12592,12593,12601,12595],"class_list":{"0":"post-73553","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agenzie-immobiliari","7":"product_cat-casa","8":"product_tag-acquistare-o-affittare-con-fiducia-e-serenita-agente-immobiliare","9":"product_tag-agente-immobiliare","10":"product_tag-agenti-immobiliari","11":"product_tag-agenzia-immobiliare","12":"product_tag-aiutandoli-a-vendere","13":"product_tag-analisi-della-documentazione","14":"product_tag-analisi-di-mercato-immobiliare","15":"product_tag-appartamenti","16":"product_tag-appartamenti-in-vendita","17":"product_tag-assistenza-fino-al-rogito-notarile","18":"product_tag-attenzione-e-passione","19":"product_tag-casa","20":"product_tag-case-in-vendita","21":"product_tag-catania","22":"product_tag-compravendita","23":"product_tag-compravendite","24":"product_tag-consulente-immobiliare","25":"product_tag-consulenti-immobiliari","26":"product_tag-consulenze-giuridiche","27":"product_tag-ho-scelto-di-trasformare-la-mia-passione-per-le-persone-e-la-cura-nei-dettagli-in-una-nuova-professione-oggi-offro-ai-miei-clienti-trasparenza","28":"product_tag-immobili","29":"product_tag-immobili-in-vendita","30":"product_tag-inserzioni-pubblicitarie","31":"product_tag-legali-e-finanziarie-tramite-professionisti-indipendenti","32":"product_tag-locazione","33":"product_tag-locazioni","34":"product_tag-nato-come-musicista","35":"product_tag-pianista-laureato-al-conservatorio-e-insegnante-di-musica","36":"product_tag-redazione-contratti-di-locazione-e-comodato","37":"product_tag-serieta","39":"first","40":"instock","41":"shipping-taxable","42":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Piana Mattia Salvatore - Agente Immobiliare - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Piana Mattia Salvatore - Agente Immobiliare - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Mi chiamo Mattia Salvatore La Piana e sono il fondatore della mia agenzia immobiliare attiva su Catania e Provincia, ma operativa anche nelle zone di Siracusa, Augusta e Messina. Dopo anni di gavetta in un noto franchising immobiliare, a fine settembre 2023 ho deciso di mettermi in proprio per costruire qualcosa di mio. Nato come musicista, pianista laureato al Conservatorio e insegnante di musica, ho scelto di trasformare la mia passione per le persone e la cura nei dettagli in una nuova professione. Oggi offro ai miei clienti trasparenza, seriet\u00e0, attenzione e passione, aiutandoli a vendere, acquistare o affittare con fiducia e serenit\u00e0.agente immobiliare, agenzia immobiliare, agente immobiliare, agenti immobiliari, consulente immobiliare, consulenti immobiliari, immobili, immobili in vendita, case in vendita, casa, appartamenti, appartamenti in vendita, Analisi di mercato immobiliare, Redazione contratti di locazione e comodato, Compravendite, locazioni, compravendita, locazione, Analisi della documentazione, Consulenze giuridiche, legali e finanziarie tramite professionisti indipendenti, Assistenza fino al rogito notarile, Inserzioni pubblicitarie, Catania, agente immobiliare Catania, agenzia immobiliare Catania, agente immobiliare Catania, agenti immobiliari Catania, consulente immobiliare Catania, consulenti immobiliari Catania, immobili Catania, immobili in vendita Catania, case in vendita Catania, casa Catania, appartamenti Catania, appartamenti in vendita Catania, Analisi di mercato immobiliare Catania, Redazione contratti di locazione e comodato Catania, Compravendite Catania, locazioni Catania, compravendita Catania, locazione Catania, Analisi della documentazione Catania, Consulenze giuridiche Catania, legali e finanziarie tramite professionisti indipendenti Catania, Assistenza fino al rogito notarile Catania, Inserzioni pubblicitarie Catania, agente immobiliare a Catania, agenzia immobiliare a Catania, agente immobiliare a Catania, agenti immobiliari a Catania, consulente immobiliare a Catania, consulenti immobiliari a Catania, immobili a Catania, immobili in vendita a Catania, case in vendita a Catania, casa a Catania, appartamenti a Catania, appartamenti in vendita a Catania, Analisi di mercato immobiliare a Catania, Redazione contratti di locazione e comodato a Catania, Compravendite a Catania, locazioni a Catania, compravendita a Catania, locazione a Catania, Analisi della documentazione a Catania, Consulenze giuridiche a Catania, legali e finanziarie tramite professionisti indipendenti a Catania, Assistenza fino al rogito notarile a Catania, Inserzioni pubblicitarie a Catania,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T15:41:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/\",\"name\":\"La Piana Mattia Salvatore - Agente Immobiliare - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png\",\"datePublished\":\"2025-06-16T15:08:44+00:00\",\"dateModified\":\"2025-06-16T15:41:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Piana Mattia Salvatore &#8211; Agente Immobiliare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Piana Mattia Salvatore - Agente Immobiliare - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/","og_locale":"it_IT","og_type":"article","og_title":"La Piana Mattia Salvatore - Agente Immobiliare - UIL Polizia","og_description":"Mi chiamo Mattia Salvatore La Piana e sono il fondatore della mia agenzia immobiliare attiva su Catania e Provincia, ma operativa anche nelle zone di Siracusa, Augusta e Messina. Dopo anni di gavetta in un noto franchising immobiliare, a fine settembre 2023 ho deciso di mettermi in proprio per costruire qualcosa di mio. Nato come musicista, pianista laureato al Conservatorio e insegnante di musica, ho scelto di trasformare la mia passione per le persone e la cura nei dettagli in una nuova professione. Oggi offro ai miei clienti trasparenza, seriet\u00e0, attenzione e passione, aiutandoli a vendere, acquistare o affittare con fiducia e serenit\u00e0.agente immobiliare, agenzia immobiliare, agente immobiliare, agenti immobiliari, consulente immobiliare, consulenti immobiliari, immobili, immobili in vendita, case in vendita, casa, appartamenti, appartamenti in vendita, Analisi di mercato immobiliare, Redazione contratti di locazione e comodato, Compravendite, locazioni, compravendita, locazione, Analisi della documentazione, Consulenze giuridiche, legali e finanziarie tramite professionisti indipendenti, Assistenza fino al rogito notarile, Inserzioni pubblicitarie, Catania, agente immobiliare Catania, agenzia immobiliare Catania, agente immobiliare Catania, agenti immobiliari Catania, consulente immobiliare Catania, consulenti immobiliari Catania, immobili Catania, immobili in vendita Catania, case in vendita Catania, casa Catania, appartamenti Catania, appartamenti in vendita Catania, Analisi di mercato immobiliare Catania, Redazione contratti di locazione e comodato Catania, Compravendite Catania, locazioni Catania, compravendita Catania, locazione Catania, Analisi della documentazione Catania, Consulenze giuridiche Catania, legali e finanziarie tramite professionisti indipendenti Catania, Assistenza fino al rogito notarile Catania, Inserzioni pubblicitarie Catania, agente immobiliare a Catania, agenzia immobiliare a Catania, agente immobiliare a Catania, agenti immobiliari a Catania, consulente immobiliare a Catania, consulenti immobiliari a Catania, immobili a Catania, immobili in vendita a Catania, case in vendita a Catania, casa a Catania, appartamenti a Catania, appartamenti in vendita a Catania, Analisi di mercato immobiliare a Catania, Redazione contratti di locazione e comodato a Catania, Compravendite a Catania, locazioni a Catania, compravendita a Catania, locazione a Catania, Analisi della documentazione a Catania, Consulenze giuridiche a Catania, legali e finanziarie tramite professionisti indipendenti a Catania, Assistenza fino al rogito notarile a Catania, Inserzioni pubblicitarie a Catania,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/","og_site_name":"UIL Polizia","article_modified_time":"2025-06-16T15:41:51+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/","name":"La Piana Mattia Salvatore - Agente Immobiliare - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png","datePublished":"2025-06-16T15:08:44+00:00","dateModified":"2025-06-16T15:41:51+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/06\/Logo-siti-la-piana-mattia-salvatore-ag-immobiliare.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/la-piana-mattia-salvatore-agente-immobiliare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"La Piana Mattia Salvatore &#8211; Agente Immobiliare"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/73553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=73553"}],"version-history":[{"count":15,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/73553\/revisions"}],"predecessor-version":[{"id":73619,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/73553\/revisions\/73619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/73554"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=73553"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=73553"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=73553"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=73553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}