{"id":73022,"date":"2025-05-16T11:22:49","date_gmt":"2025-05-16T09:22:49","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=73022"},"modified":"2025-05-21T09:41:58","modified_gmt":"2025-05-21T07:41:58","slug":"dott-ssa-corrado-francesca-ostetrica","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/","title":{"rendered":"Dott.ssa Corrado Francesca &#8211; Ostetrica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"73022\" class=\"elementor elementor-73022\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a03378b e-flex e-con-boxed e-con e-parent\" data-id=\"5a03378b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-382e7976 e-con-full e-flex e-con e-child\" data-id=\"382e7976\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6bf10877 e-con-full e-flex e-con e-child\" data-id=\"6bf10877\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-715a3df5 e-con-full e-flex e-con e-child\" data-id=\"715a3df5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c88126c elementor-widget elementor-widget-image\" data-id=\"5c88126c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"204\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-dott-ssa-francesca-corrado-1024x204.png\" class=\"attachment-large size-large wp-image-73027\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-dott-ssa-francesca-corrado-980x196.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-dott-ssa-francesca-corrado-480x96.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1163a64 e-con-full e-flex e-con e-child\" data-id=\"1163a64\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7608cc19 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7608cc19\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Sono Francesca Corrado, un&#8217;ostetrica specializzata nella prevenzione rieducazione e riabilitazione del pavimento pelvico.<\/b><\/p><p>Nel corso degli anni ho preso varie specializzazioni nel trattamento di disfunzioni pelviche, urologiche e colon-proctologiche.<\/p><p>Faccio parte dell\u2019AIO (Associazione Italiana Ostetricia) e del GOIPP (Gruppo Ostetriche Italiane Pavimento Pelvico).<\/p><p>Sono parte attiva dello Screening Oncologico Regionale per la prevenzione dei tumori della sfera sessuale della Donna nella Regione Basilicata.<\/p><p>Sono insegnante di Ginnastica Ipoopressiva (un valido aiuto nella risoluzione della diastasi dei retti addominali e dei prolassi uro-genitali).<\/p><p>Faccio parte dell&#8217;equipe Igea &#8211; Centro Salute Donne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdcd690 elementor-align-left elementor-tablet-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"cdcd690\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contatti\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattami<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48c51a99 e-con-full e-flex e-con e-child\" data-id=\"48c51a99\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93d41d3 elementor-widget elementor-widget-image\" data-id=\"93d41d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/img-drssa-corradp-francesca-ostetrica-724x1024.png\" class=\"attachment-large size-large wp-image-73054\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/img-drssa-corradp-francesca-ostetrica-724x1024.png 724w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/img-drssa-corradp-francesca-ostetrica-480x679.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 724px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5729cd9 e-flex e-con-boxed e-con e-parent\" data-id=\"5729cd9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-98da927 e-con-full e-flex e-con e-child\" data-id=\"98da927\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ab9292c e-con-full e-flex e-con e-child\" data-id=\"ab9292c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dccb49d e-con-full e-flex e-con e-child\" data-id=\"dccb49d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a0c5b3f e-con-full e-flex e-con e-child\" data-id=\"a0c5b3f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27ae10a elementor-widget elementor-widget-text-editor\" data-id=\"27ae10a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>la mia esperienza<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a718150 e-con-full e-flex e-con e-child\" data-id=\"a718150\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9306673 e-con-full e-flex e-con e-child\" data-id=\"9306673\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-615b637 elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"615b637\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRoma 10 Novembre 2018\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPerineo - La porta del tempio femminile \u2013 Preparare il pavimento pelvico al parto, proteggerlo durante il periodo espansivo, rieducarlo dopo il parto\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d56f5ac elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"d56f5ac\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCernusco sul Naviglio 22-23 Marzo 2019\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tL\u2019ostetrica e le disfunzioni del pavimento pelvico \u2013 Riabilitazione con inquadramento diagnostico, terapie e follow-up\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc5e23 elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"4bc5e23\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRimini 9 Giugno 2019 \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tL\u2019Ostetrica e la riabilitazione delle disfunzioni colon-proctologiche\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e82c50e elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e82c50e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRoma 2020 \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMaster in salute pelvica della donna\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a955c33 e-con-full e-flex e-con e-child\" data-id=\"a955c33\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a7384a elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7a7384a\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMilano 2022 \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOstetrica esperta in assistenza e conduzione di casi in climaterio e menopausa\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-016f94f elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"016f94f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMatera 24-25 Marzo 2023\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDolore pelvico cronico\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3a79f5 elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e3a79f5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMilano 19-20 Maggio 2023\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDolore pelvi-perineale \u2013 Patogenesi, classificazione e valutazione. Terapia chinesiterapia e strumentale\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-432e291 elementor-position-left elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"432e291\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPotenza 2023 \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBenessere vulvare: Nuove prospettive terapeutiche\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52bd19a e-flex e-con-boxed e-con e-parent\" data-id=\"52bd19a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-63fab80 e-con-full e-flex e-con e-child\" data-id=\"63fab80\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-77d46fb e-con-full e-flex e-con e-child\" data-id=\"77d46fb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-542790e elementor-widget elementor-widget-text-editor\" data-id=\"542790e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>mi occupo di<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dab9ad2 e-con-full e-flex e-con e-child\" data-id=\"dab9ad2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-75292d8 e-con-full e-flex e-con e-child\" data-id=\"75292d8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8f450 elementor-widget elementor-widget-icon-box\" data-id=\"6b8f450\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTrattamento del dolore pelvico della donna\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMigliora la coordinazione dei muscoli pelvici\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85b7d89 e-con-full e-flex e-con e-child\" data-id=\"85b7d89\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cc2db2 elementor-widget elementor-widget-icon-box\" data-id=\"6cc2db2\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTrattamento delle disfunzioni urologiche\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUn beneficio concreto per la tua qualit\u00e0 di vita\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12c5659 e-con-full e-flex e-con e-child\" data-id=\"12c5659\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb2ddf8 elementor-widget elementor-widget-icon-box\" data-id=\"fb2ddf8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTrattamento delle disfunzioni colon-proctologiche\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMigliora il tuo confort e la tua privacy\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-775be45 e-con-full e-flex e-con e-child\" data-id=\"775be45\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1957fe0 e-con-full e-flex e-con e-child\" data-id=\"1957fe0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-edf31f0 e-con-full e-flex e-con e-child\" data-id=\"edf31f0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1a79e4 elementor-widget elementor-widget-text-editor\" data-id=\"d1a79e4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Benefici terapeutici<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc80720 elementor-position-left elementor-tablet-position-top elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"dc80720\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-heart\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M458.4 64.3C400.6 15.7 311.3 23 256 79.3 200.7 23 111.4 15.6 53.6 64.3-21.6 127.6-10.6 230.8 43 285.5l175.4 178.7c10 10.2 23.4 15.9 37.6 15.9 14.3 0 27.6-5.6 37.6-15.8L469 285.6c53.5-54.7 64.7-157.9-10.6-221.3zm-23.6 187.5L259.4 430.5c-2.4 2.4-4.4 2.4-6.8 0L77.2 251.8c-36.5-37.2-43.9-107.6 7.3-150.7 38.9-32.7 98.9-27.8 136.5 10.5l35 35.7 35-35.7c37.8-38.5 97.8-43.2 136.5-10.6 51.1 43.1 43.5 113.9 7.3 150.8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRipristino attivit\u00e0 sfinteri\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed39f8 elementor-position-left elementor-tablet-position-top elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5ed39f8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-heart\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M458.4 64.3C400.6 15.7 311.3 23 256 79.3 200.7 23 111.4 15.6 53.6 64.3-21.6 127.6-10.6 230.8 43 285.5l175.4 178.7c10 10.2 23.4 15.9 37.6 15.9 14.3 0 27.6-5.6 37.6-15.8L469 285.6c53.5-54.7 64.7-157.9-10.6-221.3zm-23.6 187.5L259.4 430.5c-2.4 2.4-4.4 2.4-6.8 0L77.2 251.8c-36.5-37.2-43.9-107.6 7.3-150.7 38.9-32.7 98.9-27.8 136.5 10.5l35 35.7 35-35.7c37.8-38.5 97.8-43.2 136.5-10.6 51.1 43.1 43.5 113.9 7.3 150.8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Correggere attivit\u00e0 respiratoria\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87a1e7b elementor-position-left elementor-tablet-position-top elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"87a1e7b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-heart\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M458.4 64.3C400.6 15.7 311.3 23 256 79.3 200.7 23 111.4 15.6 53.6 64.3-21.6 127.6-10.6 230.8 43 285.5l175.4 178.7c10 10.2 23.4 15.9 37.6 15.9 14.3 0 27.6-5.6 37.6-15.8L469 285.6c53.5-54.7 64.7-157.9-10.6-221.3zm-23.6 187.5L259.4 430.5c-2.4 2.4-4.4 2.4-6.8 0L77.2 251.8c-36.5-37.2-43.9-107.6 7.3-150.7 38.9-32.7 98.9-27.8 136.5 10.5l35 35.7 35-35.7c37.8-38.5 97.8-43.2 136.5-10.6 51.1 43.1 43.5 113.9 7.3 150.8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Ripristino coordinazione muscoli pelvici\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c852a8a elementor-position-left elementor-tablet-position-top elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"c852a8a\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-heart\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M458.4 64.3C400.6 15.7 311.3 23 256 79.3 200.7 23 111.4 15.6 53.6 64.3-21.6 127.6-10.6 230.8 43 285.5l175.4 178.7c10 10.2 23.4 15.9 37.6 15.9 14.3 0 27.6-5.6 37.6-15.8L469 285.6c53.5-54.7 64.7-157.9-10.6-221.3zm-23.6 187.5L259.4 430.5c-2.4 2.4-4.4 2.4-6.8 0L77.2 251.8c-36.5-37.2-43.9-107.6 7.3-150.7 38.9-32.7 98.9-27.8 136.5 10.5l35 35.7 35-35.7c37.8-38.5 97.8-43.2 136.5-10.6 51.1 43.1 43.5 113.9 7.3 150.8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNormalizzare tono muscolare perineo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0454ea3 elementor-position-left elementor-tablet-position-top elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"0454ea3\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-heart\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M458.4 64.3C400.6 15.7 311.3 23 256 79.3 200.7 23 111.4 15.6 53.6 64.3-21.6 127.6-10.6 230.8 43 285.5l175.4 178.7c10 10.2 23.4 15.9 37.6 15.9 14.3 0 27.6-5.6 37.6-15.8L469 285.6c53.5-54.7 64.7-157.9-10.6-221.3zm-23.6 187.5L259.4 430.5c-2.4 2.4-4.4 2.4-6.8 0L77.2 251.8c-36.5-37.2-43.9-107.6 7.3-150.7 38.9-32.7 98.9-27.8 136.5 10.5l35 35.7 35-35.7c37.8-38.5 97.8-43.2 136.5-10.6 51.1 43.1 43.5 113.9 7.3 150.8z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConsapevolezza Parto\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d80444 elementor-align-left elementor-tablet-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"0d80444\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contatti\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prenota un appuntamento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c63ae5 e-con-full e-flex e-con e-child\" data-id=\"4c63ae5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db0318e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"db0318e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-628067c4 e-con-full e-flex e-con e-parent\" data-id=\"628067c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-17945352 e-con-full e-flex e-con e-child\" data-id=\"17945352\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-194009c5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"194009c5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb8612d e-flex e-con-boxed e-con e-parent\" data-id=\"bb8612d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-40e0d570 e-con-full e-flex e-con e-child\" data-id=\"40e0d570\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4c9f1d31 e-con-full e-flex e-con e-child\" data-id=\"4c9f1d31\" data-element_type=\"container\" id=\"contatti\">\n\t\t<div class=\"elementor-element elementor-element-4e6576f e-con-full e-flex e-con e-child\" data-id=\"4e6576f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71b1e4df elementor-widget elementor-widget-text-editor\" data-id=\"71b1e4df\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>sedi &amp; contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10d98fd5 elementor-widget elementor-widget-text-editor\" data-id=\"10d98fd5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dr.ssa Francesca Corrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d15670 elementor-widget elementor-widget-text-editor\" data-id=\"3d15670\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ostetrica e Riabilitazione del Pavimento pelvico<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba4f868 e-con-full e-flex e-con e-child\" data-id=\"ba4f868\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd4720 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1fd4720\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Studio Potenza<\/b><br \/>Via M. Gandhi, 53 &#8211; 85100 Potenza<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6e00eb elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c6e00eb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Studio Venosa<\/b><br \/>Via R. di Poppa, 25 &#8211; 85029 Venosa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2646d59 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2646d59\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Polomedico Matera<\/b><br \/>Via A. Olivetti, 155 &#8211; 75100 Matera<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad35ec6 e-con-full e-flex e-con e-child\" data-id=\"ad35ec6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d8ef52 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4d8ef52\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Tel:<\/b> <a style=\"color: #666666;\" href=\"tel:+393450785825\" target=\"_blank\" rel=\"noopener\">+39 345 0785825 <\/a><br \/><b>Mail:<\/b> <a style=\"color: #666666;\" href=\"mailto:info@ostetricacorrado.it\" target=\"_blank\" rel=\"noopener\">info@ostetricacorrado.it<\/a><br \/><b>Sito: <\/b><a style=\"color: #666666;\" href=\"https:\/\/ostetricacorrado.it\/\" target=\"_blank\" rel=\"noopener\">ostetricacorrado.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a80ab61 elementor-shape-circle e-grid-align-left e-grid-align-tablet-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7a80ab61\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-a4c2d7d\" href=\"https:\/\/www.facebook.com\/Dottoressa-Francesca-Corrado-106717152080286\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f976262\" href=\"https:\/\/www.instagram.com\/explore\/tags\/francy4corrado\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e2f3339 e-con-full e-flex e-con e-child\" data-id=\"4e2f3339\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3e959 elementor-widget elementor-widget-image\" data-id=\"2c3e959\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"950\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/studio-dott-ssa-francesca-corrado.png\" class=\"attachment-large size-large wp-image-73028\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/studio-dott-ssa-francesca-corrado.png 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/studio-dott-ssa-francesca-corrado-480x570.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47f82a36 e-con-full e-flex e-con e-child\" data-id=\"47f82a36\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e26043e e-con-full e-flex e-con e-child\" data-id=\"4e26043e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44c35813 elementor-widget elementor-widget-text-editor\" data-id=\"44c35813\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-135\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-135\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-135\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-135\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-135\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"135\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Sono il Dr. Edoardo Squintone, fisioterapista ed osteopata.<br \/>\nNel mio lavoro metto al primo posto il benessere a tutto tondo della persona, con la quale stabilisco un rapporto di empatia.Contattami per comprendere e risolvere il tuo problema<br \/>\nDI COSA MI OCCUPOHo dedicato tutta la mia carriera professionale e la mia vita personale alla cura delle patologie e delle disfunzioni del sistema muscolo-scheletrico.<\/p>\n<p>Mi occupo di fisioterapia, osteopatia, rieducazione posturale e terapie fisiche strumentali (elettromedicali).<\/p>\n<p>PRESTAZIONI EROGATE<\/p>\n<p>Terapie manuali fisioterapiche<br \/>\nTrattamenti osteopatici<br \/>\nTerapie fisiche strumentali: tecar, ultrasuoni, laser, onde d&#8217;urto, tens<br \/>\nRieducazione posturale e funzionale<br \/>\nVisita posturale<br \/>\nRiabilitazioni post-trauma e post-operatorie<br \/>\nFISIOTERAPIA<\/p>\n<p>La fisioterapia \u00e8 una branca della medicina che si occupa della cura, prevenzione e riabilitazione di pazienti affetti da patologie e disfunzioni congenite o acquisite in ambito muscolo schelettrico, neorologico, ginecologico, cardiovascolare e respiratorio.<br \/>\nOSTEOPATIA<\/p>\n<p>L\u2019osteopatia \u00e8 una terapia che ha lo scopo di supportare la funzionalit\u00e0 fisiologica del corpo tramite l\u2019utilizzo di una variet\u00e0 di tecniche manuali.<\/p>\n<p>L\u2019osteopatia si occupa principalmente di problemi strutturali e meccanici di tipo muscolo-schelettrico.<br \/>\n\u00c9 consigliata a scopo preventivo per normalizzare disfunzioni.<\/p>\n<p>RIABILITAZIONE<\/p>\n<p>La fisioterapia svolge un ruolo fondamentale nella riabilitazione motoria e funzionale, sia nel post-operatorio, sia in seguito a un trauma fisico o a una patologia.<\/p>\n<p>Soprattutto in ambito posturale, la fisioterapia svolge anche una funzione correttiva grazie a esercizi mirati e personalizzati in base al caso specifico che possano rinforzare la muscolatura prevendone e correggendone l\u2019insorgere di patologie o disfunzioni.<\/p>\n<p>ONDE D\u2019URTO<\/p>\n<p>La terapia ad onde d\u2019urto \u00e8 un dispositivo multidisciplinare che viene utilizzato in ortopedia, fisioterapia, medicina sportiva ed urologia.<br \/>\n\u00c8 una terapia biofisica non invasiva e possono rappresentare una valida strategia terapeutica.<br \/>\nHanno un\u2019azione meccanica su cellule e tessuti in grado di stimolare alcune reazioni biologiche che si esplicano con un effetto antinfiammatorio, antiedemigeno, antidolorifico e rigenerante per i tessuti.<\/p>\n<p>Questa terapia \u00e8 ideale per accelerare il recupero e curare svariate patologie in fase acuta e cronica come tendinopatie, disturbi della rigenerazione ossea e disfunzioni muscolari.<\/p>\n<p>TECAR<br \/>\nLa Tecarterapia (Terapia Capacitiva Resistiva), o pi\u00f9 semplicemente Tecar consiste nell\u2019applicazione su un\u2019area corporea dolente per patologia articolare o muscolare di radiofrequenze con frequenza nell\u2019ordine di quelle per le radiotrasmissioni a onde medie (fra 0.45 e 1.2 MHz).<\/p>\n<p>La Tecar consente di variare la modalit\u00e0 di applicazione cos\u00ec da consentire stimolazione a diverse profondit\u00e0 (inferiore nella modalit\u00e0 \u201ccapacitiva\u201d; superiore nella modalit\u00e0 \u201cresistiva\u201d).<\/p>\n<p>Questo permette di personalizzare il trattamento.<\/p>\n<p>Oltre che l\u2019effetto analgesico-antiinfiammatorio del riscaldamento profondo la Tecar produce effetti di riparazione biologica che possono rivelarsi utili nel caso di lesioni osteoarticolari, legamentose e muscolotendinee.<\/p>\n<p>ULTRASUONI<br \/>\nLa terapia con ultrasuoni utilizza le onde acustiche ad alta frequenza (non percepibili all\u2019orecchio umano) per stimolare il riassorbimento dei liquidi provocati da un\u2019infiammazione e per un effetto antalgico.<\/p>\n<p>Gli ultrasuoni consistono in vibrazioni acustiche a frequenza cos\u00ec elevata che le strutture intercellulari e cellulari si urtano e generano calore.<\/p>\n<p>La terapia con ultrasuoni pu\u00f2 essere somministrata in due modi diversi: per contatto (con testina mobile o fissa) o a immersione.<\/p>\n<p>osteopata, osteopati, osteopatia, studio osteopatico, studi osteopatici, trattamento osteopatico, trattamenti osteopatici, seduta osteopatica, consulenza osteopatica,<br \/>\nfisioterapista, fisioterapisti, fisioterapia, studio fisioterapico, studi fisioterapici, trattamento fisioterapico, trattamenti fisioterapici, seduta fisioterapica, consulenza fisioterapica, onde d&#8217;urto, riabilitazione, tecar terapia, tecarterapia, terapia manuale, rieducazione posturale, terapie fisiche strumentali, elettromedicali, Terapie manuali fisioterapiche, Trattamenti osteopatici, Terapie fisiche strumentali, tecar, ultrasuoni, laser, onde d&#8217;urto, tens, Rieducazione posturale e funzionale, Rieducazione posturale, rieducazione funzionale, Visita posturale, Riabilitazioni post-trauma, Riabilitazioni post-operatorie, riabilitazione post operazione, riabilitazione post trauma, Ghemme, Novara,<br \/>\nosteopata Ghemme, osteopati Ghemme, osteopatia Ghemme, studio osteopatico Ghemme, studi osteopatici Ghemme, trattamento osteopatico Ghemme, trattamenti osteopatici Ghemme, seduta osteopatica Ghemme, consulenza osteopatica Ghemme,<br \/>\nfisioterapista Ghemme, fisioterapisti Ghemme, fisioterapia Ghemme, studio fisioterapico Ghemme, studi fisioterapici Ghemme, trattamento fisioterapico Ghemme, trattamenti fisioterapici Ghemme, seduta fisioterapica Ghemme, consulenza fisioterapica Ghemme, onde d&#8217;urto Ghemme, riabilitazione Ghemme, tecar terapia Ghemme, tecarterapia Ghemme, terapia manuale Ghemme, rieducazione posturale Ghemme, terapie fisiche strumentali Ghemme, elettromedicali Ghemme, Terapie manuali fisioterapiche Ghemme, Trattamenti osteopatici Ghemme, Terapie fisiche strumentali Ghemme, tecar Ghemme, ultrasuoni Ghemme, laser Ghemme, onde d&#8217;urto Ghemme, tens Ghemme, Rieducazione posturale e funzionale Ghemme, Rieducazione posturale Ghemme, rieducazione funzionale Ghemme, Visita posturale Ghemme, Riabilitazioni post-trauma Ghemme, Riabilitazioni post-operatorie Ghemme, riabilitazione post operazione Ghemme, riabilitazione post trauma Ghemme,<br \/>\nosteopata a Ghemme, osteopati a Ghemme, osteopatia a Ghemme, studio osteopatico a Ghemme, studi osteopatici a Ghemme, trattamento osteopatico a Ghemme, trattamenti osteopatici a Ghemme, seduta osteopatica a Ghemme, consulenza osteopatica a Ghemme,<br \/>\nfisioterapista a Ghemme, fisioterapisti a Ghemme, fisioterapia a Ghemme, studio fisioterapico a Ghemme, studi fisioterapici a Ghemme, trattamento fisioterapico a Ghemme, trattamenti fisioterapici a Ghemme, seduta fisioterapica a Ghemme, consulenza fisioterapica a Ghemme, onde d&#8217;urto a Ghemme, riabilitazione a Ghemme, tecar terapia a Ghemme, tecarterapia a Ghemme, terapia manuale a Ghemme, rieducazione posturale a Ghemme, terapie fisiche strumentali a Ghemme, elettromedicali a Ghemme, Terapie manuali fisioterapiche a Ghemme, Trattamenti osteopatici a Ghemme, Terapie fisiche strumentali a Ghemme, tecar a Ghemme, ultrasuoni a Ghemme, laser a Ghemme, onde d&#8217;urto a Ghemme, tens a Ghemme, Rieducazione posturale e funzionale a Ghemme, Rieducazione posturale a Ghemme, rieducazione funzionale a Ghemme, Visita posturale a Ghemme, Riabilitazioni post-trauma a Ghemme, Riabilitazioni post-operatorie a Ghemme, riabilitazione post operazione a Ghemme, riabilitazione post trauma a Ghemme,<\/p>\n<\/div>\n","protected":false},"featured_media":73130,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[243,4145,163],"product_tag":[],"class_list":{"0":"post-73022","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ostetricia","7":"product_cat-riabilitazione-del-pavimento-pelvico","8":"product_cat-salute","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Corrado Francesca - Ostetrica - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Corrado Francesca - Ostetrica - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono il Dr. Edoardo Squintone, fisioterapista ed osteopata. Nel mio lavoro metto al primo posto il benessere a tutto tondo della persona, con la quale stabilisco un rapporto di empatia.Contattami per comprendere e risolvere il tuo problema DI COSA MI OCCUPOHo dedicato tutta la mia carriera professionale e la mia vita personale alla cura delle patologie e delle disfunzioni del sistema muscolo-scheletrico.  Mi occupo di fisioterapia, osteopatia, rieducazione posturale e terapie fisiche strumentali (elettromedicali).  PRESTAZIONI EROGATE  Terapie manuali fisioterapiche Trattamenti osteopatici Terapie fisiche strumentali: tecar, ultrasuoni, laser, onde d&#039;urto, tens Rieducazione posturale e funzionale Visita posturale Riabilitazioni post-trauma e post-operatorie FISIOTERAPIA  La fisioterapia \u00e8 una branca della medicina che si occupa della cura, prevenzione e riabilitazione di pazienti affetti da patologie e disfunzioni congenite o acquisite in ambito muscolo schelettrico, neorologico, ginecologico, cardiovascolare e respiratorio. OSTEOPATIA  L\u2019osteopatia \u00e8 una terapia che ha lo scopo di supportare la funzionalit\u00e0 fisiologica del corpo tramite l\u2019utilizzo di una variet\u00e0 di tecniche manuali.  L\u2019osteopatia si occupa principalmente di problemi strutturali e meccanici di tipo muscolo-schelettrico. \u00c9 consigliata a scopo preventivo per normalizzare disfunzioni.  RIABILITAZIONE  La fisioterapia svolge un ruolo fondamentale nella riabilitazione motoria e funzionale, sia nel post-operatorio, sia in seguito a un trauma fisico o a una patologia.  Soprattutto in ambito posturale, la fisioterapia svolge anche una funzione correttiva grazie a esercizi mirati e personalizzati in base al caso specifico che possano rinforzare la muscolatura prevendone e correggendone l\u2019insorgere di patologie o disfunzioni.  ONDE D\u2019URTO  La terapia ad onde d\u2019urto \u00e8 un dispositivo multidisciplinare che viene utilizzato in ortopedia, fisioterapia, medicina sportiva ed urologia. \u00c8 una terapia biofisica non invasiva e possono rappresentare una valida strategia terapeutica. Hanno un\u2019azione meccanica su cellule e tessuti in grado di stimolare alcune reazioni biologiche che si esplicano con un effetto antinfiammatorio, antiedemigeno, antidolorifico e rigenerante per i tessuti.  Questa terapia \u00e8 ideale per accelerare il recupero e curare svariate patologie in fase acuta e cronica come tendinopatie, disturbi della rigenerazione ossea e disfunzioni muscolari.  TECAR La Tecarterapia (Terapia Capacitiva Resistiva), o pi\u00f9 semplicemente Tecar consiste nell\u2019applicazione su un\u2019area corporea dolente per patologia articolare o muscolare di radiofrequenze con frequenza nell\u2019ordine di quelle per le radiotrasmissioni a onde medie (fra 0.45 e 1.2 MHz).  La Tecar consente di variare la modalit\u00e0 di applicazione cos\u00ec da consentire stimolazione a diverse profondit\u00e0 (inferiore nella modalit\u00e0 \u201ccapacitiva\u201d; superiore nella modalit\u00e0 \u201cresistiva\u201d).  Questo permette di personalizzare il trattamento.  Oltre che l\u2019effetto analgesico-antiinfiammatorio del riscaldamento profondo la Tecar produce effetti di riparazione biologica che possono rivelarsi utili nel caso di lesioni osteoarticolari, legamentose e muscolotendinee.  ULTRASUONI La terapia con ultrasuoni utilizza le onde acustiche ad alta frequenza (non percepibili all\u2019orecchio umano) per stimolare il riassorbimento dei liquidi provocati da un\u2019infiammazione e per un effetto antalgico.  Gli ultrasuoni consistono in vibrazioni acustiche a frequenza cos\u00ec elevata che le strutture intercellulari e cellulari si urtano e generano calore.  La terapia con ultrasuoni pu\u00f2 essere somministrata in due modi diversi: per contatto (con testina mobile o fissa) o a immersione.  osteopata, osteopati, osteopatia, studio osteopatico, studi osteopatici, trattamento osteopatico, trattamenti osteopatici, seduta osteopatica, consulenza osteopatica, fisioterapista, fisioterapisti, fisioterapia, studio fisioterapico, studi fisioterapici, trattamento fisioterapico, trattamenti fisioterapici, seduta fisioterapica, consulenza fisioterapica, onde d&#039;urto, riabilitazione, tecar terapia, tecarterapia, terapia manuale, rieducazione posturale, terapie fisiche strumentali, elettromedicali, Terapie manuali fisioterapiche, Trattamenti osteopatici, Terapie fisiche strumentali, tecar, ultrasuoni, laser, onde d&#039;urto, tens, Rieducazione posturale e funzionale, Rieducazione posturale, rieducazione funzionale, Visita posturale, Riabilitazioni post-trauma, Riabilitazioni post-operatorie, riabilitazione post operazione, riabilitazione post trauma, Ghemme, Novara, osteopata Ghemme, osteopati Ghemme, osteopatia Ghemme, studio osteopatico Ghemme, studi osteopatici Ghemme, trattamento osteopatico Ghemme, trattamenti osteopatici Ghemme, seduta osteopatica Ghemme, consulenza osteopatica Ghemme, fisioterapista Ghemme, fisioterapisti Ghemme, fisioterapia Ghemme, studio fisioterapico Ghemme, studi fisioterapici Ghemme, trattamento fisioterapico Ghemme, trattamenti fisioterapici Ghemme, seduta fisioterapica Ghemme, consulenza fisioterapica Ghemme, onde d&#039;urto Ghemme, riabilitazione Ghemme, tecar terapia Ghemme, tecarterapia Ghemme, terapia manuale Ghemme, rieducazione posturale Ghemme, terapie fisiche strumentali Ghemme, elettromedicali Ghemme, Terapie manuali fisioterapiche Ghemme, Trattamenti osteopatici Ghemme, Terapie fisiche strumentali Ghemme, tecar Ghemme, ultrasuoni Ghemme, laser Ghemme, onde d&#039;urto Ghemme, tens Ghemme, Rieducazione posturale e funzionale Ghemme, Rieducazione posturale Ghemme, rieducazione funzionale Ghemme, Visita posturale Ghemme, Riabilitazioni post-trauma Ghemme, Riabilitazioni post-operatorie Ghemme, riabilitazione post operazione Ghemme, riabilitazione post trauma Ghemme, osteopata a Ghemme, osteopati a Ghemme, osteopatia a Ghemme, studio osteopatico a Ghemme, studi osteopatici a Ghemme, trattamento osteopatico a Ghemme, trattamenti osteopatici a Ghemme, seduta osteopatica a Ghemme, consulenza osteopatica a Ghemme, fisioterapista a Ghemme, fisioterapisti a Ghemme, fisioterapia a Ghemme, studio fisioterapico a Ghemme, studi fisioterapici a Ghemme, trattamento fisioterapico a Ghemme, trattamenti fisioterapici a Ghemme, seduta fisioterapica a Ghemme, consulenza fisioterapica a Ghemme, onde d&#039;urto a Ghemme, riabilitazione a Ghemme, tecar terapia a Ghemme, tecarterapia a Ghemme, terapia manuale a Ghemme, rieducazione posturale a Ghemme, terapie fisiche strumentali a Ghemme, elettromedicali a Ghemme, Terapie manuali fisioterapiche a Ghemme, Trattamenti osteopatici a Ghemme, Terapie fisiche strumentali a Ghemme, tecar a Ghemme, ultrasuoni a Ghemme, laser a Ghemme, onde d&#039;urto a Ghemme, tens a Ghemme, Rieducazione posturale e funzionale a Ghemme, Rieducazione posturale a Ghemme, rieducazione funzionale a Ghemme, Visita posturale a Ghemme, Riabilitazioni post-trauma a Ghemme, Riabilitazioni post-operatorie a Ghemme, riabilitazione post operazione a Ghemme, riabilitazione post trauma a Ghemme,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T07:41:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/\",\"name\":\"Dott.ssa Corrado Francesca - Ostetrica - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png\",\"datePublished\":\"2025-05-16T09:22:49+00:00\",\"dateModified\":\"2025-05-21T07:41:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Corrado Francesca &#8211; Ostetrica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Corrado Francesca - Ostetrica - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Corrado Francesca - Ostetrica - UIL Polizia","og_description":"Sono il Dr. Edoardo Squintone, fisioterapista ed osteopata. Nel mio lavoro metto al primo posto il benessere a tutto tondo della persona, con la quale stabilisco un rapporto di empatia.Contattami per comprendere e risolvere il tuo problema DI COSA MI OCCUPOHo dedicato tutta la mia carriera professionale e la mia vita personale alla cura delle patologie e delle disfunzioni del sistema muscolo-scheletrico.  Mi occupo di fisioterapia, osteopatia, rieducazione posturale e terapie fisiche strumentali (elettromedicali).  PRESTAZIONI EROGATE  Terapie manuali fisioterapiche Trattamenti osteopatici Terapie fisiche strumentali: tecar, ultrasuoni, laser, onde d'urto, tens Rieducazione posturale e funzionale Visita posturale Riabilitazioni post-trauma e post-operatorie FISIOTERAPIA  La fisioterapia \u00e8 una branca della medicina che si occupa della cura, prevenzione e riabilitazione di pazienti affetti da patologie e disfunzioni congenite o acquisite in ambito muscolo schelettrico, neorologico, ginecologico, cardiovascolare e respiratorio. OSTEOPATIA  L\u2019osteopatia \u00e8 una terapia che ha lo scopo di supportare la funzionalit\u00e0 fisiologica del corpo tramite l\u2019utilizzo di una variet\u00e0 di tecniche manuali.  L\u2019osteopatia si occupa principalmente di problemi strutturali e meccanici di tipo muscolo-schelettrico. \u00c9 consigliata a scopo preventivo per normalizzare disfunzioni.  RIABILITAZIONE  La fisioterapia svolge un ruolo fondamentale nella riabilitazione motoria e funzionale, sia nel post-operatorio, sia in seguito a un trauma fisico o a una patologia.  Soprattutto in ambito posturale, la fisioterapia svolge anche una funzione correttiva grazie a esercizi mirati e personalizzati in base al caso specifico che possano rinforzare la muscolatura prevendone e correggendone l\u2019insorgere di patologie o disfunzioni.  ONDE D\u2019URTO  La terapia ad onde d\u2019urto \u00e8 un dispositivo multidisciplinare che viene utilizzato in ortopedia, fisioterapia, medicina sportiva ed urologia. \u00c8 una terapia biofisica non invasiva e possono rappresentare una valida strategia terapeutica. Hanno un\u2019azione meccanica su cellule e tessuti in grado di stimolare alcune reazioni biologiche che si esplicano con un effetto antinfiammatorio, antiedemigeno, antidolorifico e rigenerante per i tessuti.  Questa terapia \u00e8 ideale per accelerare il recupero e curare svariate patologie in fase acuta e cronica come tendinopatie, disturbi della rigenerazione ossea e disfunzioni muscolari.  TECAR La Tecarterapia (Terapia Capacitiva Resistiva), o pi\u00f9 semplicemente Tecar consiste nell\u2019applicazione su un\u2019area corporea dolente per patologia articolare o muscolare di radiofrequenze con frequenza nell\u2019ordine di quelle per le radiotrasmissioni a onde medie (fra 0.45 e 1.2 MHz).  La Tecar consente di variare la modalit\u00e0 di applicazione cos\u00ec da consentire stimolazione a diverse profondit\u00e0 (inferiore nella modalit\u00e0 \u201ccapacitiva\u201d; superiore nella modalit\u00e0 \u201cresistiva\u201d).  Questo permette di personalizzare il trattamento.  Oltre che l\u2019effetto analgesico-antiinfiammatorio del riscaldamento profondo la Tecar produce effetti di riparazione biologica che possono rivelarsi utili nel caso di lesioni osteoarticolari, legamentose e muscolotendinee.  ULTRASUONI La terapia con ultrasuoni utilizza le onde acustiche ad alta frequenza (non percepibili all\u2019orecchio umano) per stimolare il riassorbimento dei liquidi provocati da un\u2019infiammazione e per un effetto antalgico.  Gli ultrasuoni consistono in vibrazioni acustiche a frequenza cos\u00ec elevata che le strutture intercellulari e cellulari si urtano e generano calore.  La terapia con ultrasuoni pu\u00f2 essere somministrata in due modi diversi: per contatto (con testina mobile o fissa) o a immersione.  osteopata, osteopati, osteopatia, studio osteopatico, studi osteopatici, trattamento osteopatico, trattamenti osteopatici, seduta osteopatica, consulenza osteopatica, fisioterapista, fisioterapisti, fisioterapia, studio fisioterapico, studi fisioterapici, trattamento fisioterapico, trattamenti fisioterapici, seduta fisioterapica, consulenza fisioterapica, onde d'urto, riabilitazione, tecar terapia, tecarterapia, terapia manuale, rieducazione posturale, terapie fisiche strumentali, elettromedicali, Terapie manuali fisioterapiche, Trattamenti osteopatici, Terapie fisiche strumentali, tecar, ultrasuoni, laser, onde d'urto, tens, Rieducazione posturale e funzionale, Rieducazione posturale, rieducazione funzionale, Visita posturale, Riabilitazioni post-trauma, Riabilitazioni post-operatorie, riabilitazione post operazione, riabilitazione post trauma, Ghemme, Novara, osteopata Ghemme, osteopati Ghemme, osteopatia Ghemme, studio osteopatico Ghemme, studi osteopatici Ghemme, trattamento osteopatico Ghemme, trattamenti osteopatici Ghemme, seduta osteopatica Ghemme, consulenza osteopatica Ghemme, fisioterapista Ghemme, fisioterapisti Ghemme, fisioterapia Ghemme, studio fisioterapico Ghemme, studi fisioterapici Ghemme, trattamento fisioterapico Ghemme, trattamenti fisioterapici Ghemme, seduta fisioterapica Ghemme, consulenza fisioterapica Ghemme, onde d'urto Ghemme, riabilitazione Ghemme, tecar terapia Ghemme, tecarterapia Ghemme, terapia manuale Ghemme, rieducazione posturale Ghemme, terapie fisiche strumentali Ghemme, elettromedicali Ghemme, Terapie manuali fisioterapiche Ghemme, Trattamenti osteopatici Ghemme, Terapie fisiche strumentali Ghemme, tecar Ghemme, ultrasuoni Ghemme, laser Ghemme, onde d'urto Ghemme, tens Ghemme, Rieducazione posturale e funzionale Ghemme, Rieducazione posturale Ghemme, rieducazione funzionale Ghemme, Visita posturale Ghemme, Riabilitazioni post-trauma Ghemme, Riabilitazioni post-operatorie Ghemme, riabilitazione post operazione Ghemme, riabilitazione post trauma Ghemme, osteopata a Ghemme, osteopati a Ghemme, osteopatia a Ghemme, studio osteopatico a Ghemme, studi osteopatici a Ghemme, trattamento osteopatico a Ghemme, trattamenti osteopatici a Ghemme, seduta osteopatica a Ghemme, consulenza osteopatica a Ghemme, fisioterapista a Ghemme, fisioterapisti a Ghemme, fisioterapia a Ghemme, studio fisioterapico a Ghemme, studi fisioterapici a Ghemme, trattamento fisioterapico a Ghemme, trattamenti fisioterapici a Ghemme, seduta fisioterapica a Ghemme, consulenza fisioterapica a Ghemme, onde d'urto a Ghemme, riabilitazione a Ghemme, tecar terapia a Ghemme, tecarterapia a Ghemme, terapia manuale a Ghemme, rieducazione posturale a Ghemme, terapie fisiche strumentali a Ghemme, elettromedicali a Ghemme, Terapie manuali fisioterapiche a Ghemme, Trattamenti osteopatici a Ghemme, Terapie fisiche strumentali a Ghemme, tecar a Ghemme, ultrasuoni a Ghemme, laser a Ghemme, onde d'urto a Ghemme, tens a Ghemme, Rieducazione posturale e funzionale a Ghemme, Rieducazione posturale a Ghemme, rieducazione funzionale a Ghemme, Visita posturale a Ghemme, Riabilitazioni post-trauma a Ghemme, Riabilitazioni post-operatorie a Ghemme, riabilitazione post operazione a Ghemme, riabilitazione post trauma a Ghemme,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/","og_site_name":"UIL Polizia","article_modified_time":"2025-05-21T07:41:58+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/","name":"Dott.ssa Corrado Francesca - Ostetrica - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png","datePublished":"2025-05-16T09:22:49+00:00","dateModified":"2025-05-21T07:41:58+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2025\/05\/logo-siti-dottoressa-corrado-francesca.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-corrado-francesca-ostetrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Corrado Francesca &#8211; Ostetrica"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/73022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=73022"}],"version-history":[{"count":22,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/73022\/revisions"}],"predecessor-version":[{"id":73138,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/73022\/revisions\/73138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/73130"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=73022"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=73022"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=73022"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=73022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}