{"id":63390,"date":"2024-05-16T11:44:10","date_gmt":"2024-05-16T09:44:10","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=63390"},"modified":"2024-09-04T11:47:56","modified_gmt":"2024-09-04T09:47:56","slug":"dott-gabriele-malagoli-fisioterapista-e-osteopata","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/","title":{"rendered":"Dott. Gabriele Malagoli &#8211; Fisioterapista e Osteopata"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"63390\" class=\"elementor elementor-63390\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2194d6e elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"2194d6e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16d9357 e-con-full e-flex e-con e-child\" data-id=\"16d9357\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d52fd4 elementor-widget elementor-widget-text-editor\" data-id=\"7d52fd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. <br \/>Gabriele Malagoli<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-119132b elementor-widget elementor-widget-text-editor\" data-id=\"119132b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFisioterapista e Osteopata a Nonantola (MO)\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4213fc e-con-full e-flex e-con e-child\" data-id=\"d4213fc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56ef1c7 elementor-widget elementor-widget-image\" data-id=\"56ef1c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"998\" height=\"1320\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono.png\" class=\"attachment-full size-full wp-image-68198\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono.png 998w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-980x1296.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-480x635.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 998px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9beb00 e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"a9beb00\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0600ea4 e-con-full e-flex e-con e-child\" data-id=\"0600ea4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9c5d4a elementor-widget elementor-widget-text-editor\" data-id=\"f9c5d4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. <br \/>Gabriele Malagoli<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35fc839 elementor-widget elementor-widget-text-editor\" data-id=\"35fc839\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFisioterapista e Osteopata a Nonantola (MO)\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8392f09 e-con-full e-flex e-con e-child\" data-id=\"8392f09\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a38df22 elementor-widget elementor-widget-image\" data-id=\"a38df22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"998\" height=\"1320\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono.png\" class=\"attachment-full size-full wp-image-68198\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono.png 998w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-980x1296.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-480x635.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 998px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f762d01 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"f762d01\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-93ca38d e-con-full e-flex e-con e-child\" data-id=\"93ca38d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd9e151 elementor-widget elementor-widget-image\" data-id=\"dd9e151\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1456\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png\" class=\"attachment-full size-full wp-image-68193\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7-480x874.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd0fb07 elementor-widget elementor-widget-text-editor\" data-id=\"cd0fb07\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFornire la massima cura e attenzione al paziente\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94a1b3d elementor-widget elementor-widget-text-editor\" data-id=\"94a1b3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono laureato in FISIOTERAPIA presso l\u2019Universit\u00e0 di Modena e Reggio Emilia, dove ho approfondito la tematica della RIABILITAZIONE CARDIO RESPIRATORIA tramite tirocinio facoltativo in una struttura specializzata a Gaiato \u201cVilla Pineta\u201d.<\/p><p>Ammaliato da questo tipo di riabilitazione ho concluso il mio percorso universitario costruendo la mia tesi su un progetto inerente la telemedicina del paziente allettato \u201cFisiochinesiterapia respiratoria associata a telemonitoraggio domiciliare per la prevenzione delle riacutizzazione da intasamento bronchiale nelle malattie neuromuscolari\u201d.<\/p><p>Ho proseguito gli studi specializzandomi su riabilitazione e trattamento conservativo sia della spalla che del rachide cervicale e, dopo aver fatto un periodo di tirocinio in un centro specializzato sulla spalla, mi sono addentrato nel mondo della RIABILITAZIONE IN ACQUA frequentando il corso dell\u2019associazione ANIK (Associazione Nazionale IdroKinesiterapia).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28d2b9e elementor-widget elementor-widget-image\" data-id=\"28d2b9e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-home-page.png\" class=\"attachment-full size-full wp-image-68190\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-home-page.png 666w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-home-page-480x721.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 666px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec9e94 elementor-widget elementor-widget-text-editor\" data-id=\"3ec9e94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ho continuato la formazione frequentando il corso McKENZIE, ma lavorando con il paziente, la mia esigenza \u00e8 stata proiettata verso un ulteriore passo sposando l\u2019idea di T.Still \u201cLa struttura governa la funzione.\u201d<\/p><p>Mi sono iscritto cosi al corso di Osteopatia alla Escuela di Osteopatia de Madrid dove mi sono diplomato al Master dei disordini muscoloscheletrici all\u2019universit\u00e0 di Taragona e concludendo i miei sei anni sono diventato Osteopata.<\/p><p>Curioso di avere una prospettiva di valutazione sulla postura ho frequentando il corso di posturologia metodo Mezieres riconosciuto dall\u2019AIFiMM.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7254d8d elementor-widget elementor-widget-image\" data-id=\"7254d8d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"798\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2.png\" class=\"attachment-full size-full wp-image-68189\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2.png 1200w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2-980x652.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2-480x319.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df46b47 e-con-full e-flex e-con e-child\" data-id=\"df46b47\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-57038a6 e-flex e-con-boxed e-con e-child\" data-id=\"57038a6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de96c8e elementor-widget elementor-widget-text-editor\" data-id=\"de96c8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tI miei Servizi\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54d9537 elementor-widget elementor-widget-text-editor\" data-id=\"54d9537\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Osteopatia<br \/>\u2022 Osteopatia Pediatrica<br \/><strong>\u2022\u00a0<\/strong>Fisioterapia Ortopedica<br \/>\u2022 Fisioterapia Cardio Respiratoria<br \/>\u2022 Posturologia e Approccio SEAS<br \/>\u2022 Massoterapia<br \/>\u2022 Taping Neuromuscolare<br \/>\u2022 Shiatsu<br \/>\u2022 McKenze<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2d2eb2 elementor-widget elementor-widget-button\" data-id=\"b2d2eb2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/malagoligabriele.it\/servizi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3d505 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4f3d505\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1065\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web.png\" class=\"attachment-full size-full wp-image-68196\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web.png 1600w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web-1280x852.png 1280w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web-980x652.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web-480x320.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1600px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c34882 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"3c34882\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d871d63 e-con-full e-flex e-con e-child\" data-id=\"d871d63\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-359339a elementor-widget elementor-widget-image\" data-id=\"359339a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1456\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png\" class=\"attachment-full size-full wp-image-68193\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7-480x874.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fcdc38 elementor-widget elementor-widget-text-editor\" data-id=\"2fcdc38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFornire la massima cura e attenzione al paziente\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a2f00e elementor-widget elementor-widget-text-editor\" data-id=\"6a2f00e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono laureato in FISIOTERAPIA presso l\u2019Universit\u00e0 di Modena e Reggio Emilia, dove ho approfondito la tematica della RIABILITAZIONE CARDIO RESPIRATORIA tramite tirocinio facoltativo in una struttura specializzata a Gaiato \u201cVilla Pineta\u201d.<\/p><p>Ammaliato da questo tipo di riabilitazione ho concluso il mio percorso universitario costruendo la mia tesi su un progetto inerente la telemedicina del paziente allettato \u201cFisiochinesiterapia respiratoria associata a telemonitoraggio domiciliare per la prevenzione delle riacutizzazione da intasamento bronchiale nelle malattie neuromuscolari\u201d.<\/p><p>Ho proseguito gli studi specializzandomi su riabilitazione e trattamento conservativo sia della spalla che del rachide cervicale e, dopo aver fatto un periodo di tirocinio in un centro specializzato sulla spalla, mi sono addentrato nel mondo della RIABILITAZIONE IN ACQUA frequentando il corso dell\u2019associazione ANIK (Associazione Nazionale IdroKinesiterapia).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6decf4 e-con-full e-flex e-con e-child\" data-id=\"e6decf4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e32ff0d elementor-widget elementor-widget-image\" data-id=\"e32ff0d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-home-page.png\" class=\"attachment-full size-full wp-image-68190\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-home-page.png 666w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-home-page-480x721.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 666px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e48c2d e-con-full e-flex e-con e-child\" data-id=\"6e48c2d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d5427 elementor-widget elementor-widget-image\" data-id=\"b7d5427\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"798\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2.png\" class=\"attachment-full size-full wp-image-68189\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2.png 1200w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2-980x652.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-chi-sono-2-480x319.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-516d1d1 e-con-full e-flex e-con e-child\" data-id=\"516d1d1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a62833 elementor-widget elementor-widget-text-editor\" data-id=\"7a62833\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ho continuato la formazione frequentando il corso McKENZIE, ma lavorando con il paziente, la mia esigenza \u00e8 stata proiettata verso un ulteriore passo sposando l\u2019idea di T.Still \u201cLa struttura governa la funzione.\u201d<\/p><p>Mi sono iscritto cosi al corso di Osteopatia alla Escuela di Osteopatia de Madrid dove mi sono diplomato al Master dei disordini muscoloscheletrici all\u2019universit\u00e0 di Taragona e concludendo i miei sei anni sono diventato Osteopata.<\/p><p>Curioso di avere una prospettiva di valutazione sulla postura ho frequentando il corso di posturologia metodo Mezieres riconosciuto dall\u2019AIFiMM.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3ece9d e-con-full e-flex e-con e-child\" data-id=\"c3ece9d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-63f721b e-flex e-con-boxed e-con e-child\" data-id=\"63f721b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5f3f1 elementor-widget elementor-widget-text-editor\" data-id=\"3e5f3f1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tI miei Servizi\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e20029c elementor-widget elementor-widget-text-editor\" data-id=\"e20029c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Osteopatia<br \/>\u2022 Osteopatia Pediatrica<br \/><strong>\u2022\u00a0<\/strong>Fisioterapia Ortopedica<br \/>\u2022 Fisioterapia Cardio Respiratoria<br \/>\u2022 Posturologia e Approccio SEAS<br \/>\u2022 Massoterapia<br \/>\u2022 Taping Neuromuscolare<br \/>\u2022 Shiatsu<br \/>\u2022 McKenze<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-356c29d elementor-widget elementor-widget-button\" data-id=\"356c29d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/malagoligabriele.it\/servizi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6b6a6e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a6b6a6e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1065\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web.png\" class=\"attachment-full size-full wp-image-68196\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web.png 1600w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web-1280x852.png 1280w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web-980x652.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gabriele-malagoli-posturologia-web-480x320.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1600px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3b64c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3b64c3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c05232e\" data-id=\"c05232e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2747362 elementor-widget elementor-widget-text-editor\" data-id=\"2747362\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-192b0f7 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"192b0f7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81bec85\" data-id=\"81bec85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8c6d24 elementor-widget elementor-widget-text-editor\" data-id=\"b8c6d24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-651e215 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"651e215\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d049f29 e-con-full e-flex e-con e-child\" data-id=\"d049f29\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e32db5b elementor-widget elementor-widget-image\" data-id=\"e32db5b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1456\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png\" class=\"attachment-full size-full wp-image-68193\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7-480x874.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb21899 elementor-widget elementor-widget-text-editor\" data-id=\"fb21899\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ba85e2 elementor-widget elementor-widget-text-editor\" data-id=\"0ba85e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #06847b;\"><strong>Dott. Gabriele Malagoli<\/strong><\/span><\/p><p>Via Guglielmo Marconi, 26 &#8211; 41015 Nonantola (MO)<br \/><strong>Tel:<\/strong> 340 266 8026<br \/><strong>Mail:<\/strong> <span style=\"color: #06847b;\"><a style=\"color: #06847b;\" href=\"mailto:gamalago.fisio@yahoo.it\">gamalago.fisio@yahoo.it<\/a><\/span><br \/><strong>Sito web: <\/strong><span style=\"color: #06847b;\"><a style=\"color: #06847b;\" href=\"https:\/\/malagoligabriele.it\/\">malagoligabriele.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03b56cf elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"03b56cf\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-3255c55\" href=\"https:\/\/wa.me\/393402668026?text=Vorrei%20prenotare%20un%20appuntamento%20,%20grazie\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a3037d elementor-widget elementor-widget-text-editor\" data-id=\"4a3037d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-112\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"63390\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-112\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-112\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-112\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-112\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"112\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d0d489 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"4d0d489\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-438ee38 e-con-full e-flex e-con e-child\" data-id=\"438ee38\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4778369 elementor-widget elementor-widget-image\" data-id=\"4778369\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1456\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png\" class=\"attachment-full size-full wp-image-68193\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7.png 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/health-clinic-7-480x874.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbb9e59 elementor-widget elementor-widget-text-editor\" data-id=\"cbb9e59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bfd160 elementor-widget elementor-widget-text-editor\" data-id=\"8bfd160\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #06847b;\"><strong>Dott. Gabriele Malagoli<\/strong><\/span><\/p><p>Via Guglielmo Marconi, 26 &#8211; 41015 Nonantola (MO)<br \/><strong>Tel:<\/strong> 340 266 8026<br \/><strong>Mail:<\/strong> <span style=\"color: #06847b;\"><a style=\"color: #06847b;\" href=\"mailto:gamalago.fisio@yahoo.it\">gamalago.fisio@yahoo.it<\/a><\/span><br \/><strong>Sito web: <\/strong><span style=\"color: #06847b;\"><a style=\"color: #06847b;\" href=\"https:\/\/malagoligabriele.it\/\">malagoligabriele.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c3b24f elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3c3b24f\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-3255c55\" href=\"https:\/\/wa.me\/393402668026?text=Vorrei%20prenotare%20un%20appuntamento%20,%20grazie\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a294453 e-con-full e-flex e-con e-child\" data-id=\"a294453\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55031a2 elementor-widget elementor-widget-text-editor\" data-id=\"55031a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-386\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"63390\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-386\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-386\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-386\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-386\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"386\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e4222d4 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e4222d4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1615e05a\" data-id=\"1615e05a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3306c2 elementor-widget elementor-widget-text-editor\" data-id=\"7d3306c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-608e2d07 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"608e2d07\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-637d595f\" data-id=\"637d595f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d6e2504 elementor-widget elementor-widget-text-editor\" data-id=\"3d6e2504\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-356\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"63390\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-356\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-356\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-356\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-356\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"356\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5d888a elementor-widget elementor-widget-text-editor\" data-id=\"2f5d888a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-468\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-468\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-468\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-468\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-468\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"468\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Fornire la massima cura e attenzione al paziente<br \/>\nSono laureato in FISIOTERAPIA presso l\u2019Universit\u00e0 di Modena e Reggio Emilia, dove ho approfondito la tematica della RIABILITAZIONE CARDIO RESPIRATORIA tramite tirocinio facoltativo in una struttura specializzata a Gaiato \u201cVilla Pineta\u201d.<br \/>\nAmmaliato da questo tipo di riabilitazione ho concluso il mio percorso universitario costruendo la mia tesi su un progetto inerente la telemedicina del paziente allettato \u201cFisiochinesiterapia respiratoria associata a telemonitoraggio domiciliare per la prevenzione delle riacutizzazione da intasamento bronchiale nelle malattie neuromuscolari\u201d.<br \/>\nHo proseguito gli studi specializzandomi su riabilitazione e trattamento conservativo sia della spalla che del rachide cervicale e, dopo aver fatto un periodo di tirocinio in un centro specializzato sulla spalla, mi sono addentrato nel mondo della RIABILITAZIONE IN ACQUA frequentando il corso dell\u2019associazione ANIK (Associazione Nazionale IdroKinesiterapia).<br \/>\nHo continuato la formazione frequentando il corso McKENZIE, ma lavorando con il paziente, la mia esigenza \u00e8 stata proiettata verso un ulteriore passo sposando l\u2019idea di T.Still \u201cLa struttura governa la funzione.\u201d<br \/>\nMi sono iscritto cosi al corso di Osteopatia alla Escuela di Osteopatia de Madrid dove mi sono diplomato al Master dei disordini muscoloscheletrici all\u2019universit\u00e0 di Taragona e concludendo i miei sei anni sono diventato Osteopata.<br \/>\nCurioso di avere una prospettiva di valutazione sulla postura ho frequentando il corso di posturologia metodo Mezieres riconosciuto dall\u2019AIFiMM.<br \/>\nCredo che sia di fondamentale importanza condividere le mie conoscenze con i fisioterapisti tirocinanti universitari che mi affiancano, avendo portato a termine il percorso da TUTOR con Unife.<br \/>\nHo frequentato il Master ISICO (Istituto Scientifico Italiano Colonna Vertebrale di Milano), che verte sulla \u201cRiabilitazione dei pazienti affetti da patologie vertebrali\u201d e sulle \u201cDeformit\u00e0 vertebrali in et\u00e0 evolutiva e nell\u2019adulto\u201c.<br \/>\nMi sono specializzato ulteriormente in ambito pediatrico frequentando il corso EOM di VALUTAZIONE OSTEOPATICA PEDIATRICA.<br \/>\nAttualmente svolgo la mia attivit\u00e0 nel mio studio (via Marconi 26 Nonantola) e in un centro privato\/convenzionato (collaborando con diverse figure mediche tra cui fisiatri, ortopedici, odontoiatri, cardiologi, internisti e oculisti).<\/p>\n<p>Osteopatia, Osteopatia Pediatrica, Fisioterapia Ortopedica, Fisioterapia Cardio Respiratoria, Posturologia e Approccio SEAS, Massoterapia, Taping Neuromuscolare, Shiatsu, McKenzie, <\/p>\n<p>Osteopatia, Osteopatia Pediatrica, Fisioterapia Ortopedica, Fisioterapia Cardio Respiratoria, Posturologia, Massoterapia, Taping Neuromuscolare, riabilitazione , fisioterapisti, fisioterapista, Osteopati, Osteopata, <\/p>\n<p>Osteopatia a Nonantola , Osteopatia Pediatrica a Nonantola , Fisioterapia Ortopedica a Nonantola , Fisioterapia Cardio Respiratoria a Nonantola , Posturologia a Nonantola , Massoterapia a Nonantola , Taping Neuromuscolare a Nonantola , riabilitazione a Nonantola  , fisioterapisti a Nonantola , fisioterapista a Nonantola , Osteopati a Nonantola , Osteopata a Nonantola , <\/p>\n<\/div>\n","protected":false},"featured_media":68185,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,242,163],"product_tag":[12204,1667,365,448,611,383,1109,384,996,971,387,1838],"class_list":{"0":"post-63390","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-osteopatia","8":"product_cat-salute","9":"product_tag-fisioterapia-cardio-respiratoria","10":"product_tag-fisioterapia-ortopedica","11":"product_tag-fisioterapista","12":"product_tag-fisioterapisti","13":"product_tag-massoterapia","14":"product_tag-osteopata","15":"product_tag-osteopati","16":"product_tag-osteopatia","17":"product_tag-osteopatia-pediatrica","18":"product_tag-posturologia","19":"product_tag-riabilitazione","20":"product_tag-taping-neuromuscolare","22":"first","23":"instock","24":"shipping-taxable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Gabriele Malagoli - Fisioterapista e Osteopata - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Gabriele Malagoli - Fisioterapista e Osteopata - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Fornire la massima cura e attenzione al paziente Sono laureato in FISIOTERAPIA presso l\u2019Universit\u00e0 di Modena e Reggio Emilia, dove ho approfondito la tematica della RIABILITAZIONE CARDIO RESPIRATORIA tramite tirocinio facoltativo in una struttura specializzata a Gaiato \u201cVilla Pineta\u201d. Ammaliato da questo tipo di riabilitazione ho concluso il mio percorso universitario costruendo la mia tesi su un progetto inerente la telemedicina del paziente allettato \u201cFisiochinesiterapia respiratoria associata a telemonitoraggio domiciliare per la prevenzione delle riacutizzazione da intasamento bronchiale nelle malattie neuromuscolari\u201d. Ho proseguito gli studi specializzandomi su riabilitazione e trattamento conservativo sia della spalla che del rachide cervicale e, dopo aver fatto un periodo di tirocinio in un centro specializzato sulla spalla, mi sono addentrato nel mondo della RIABILITAZIONE IN ACQUA frequentando il corso dell\u2019associazione ANIK (Associazione Nazionale IdroKinesiterapia). Ho continuato la formazione frequentando il corso McKENZIE, ma lavorando con il paziente, la mia esigenza \u00e8 stata proiettata verso un ulteriore passo sposando l\u2019idea di T.Still \u201cLa struttura governa la funzione.\u201d  Mi sono iscritto cosi al corso di Osteopatia alla Escuela di Osteopatia de Madrid dove mi sono diplomato al Master dei disordini muscoloscheletrici all\u2019universit\u00e0 di Taragona e concludendo i miei sei anni sono diventato Osteopata. Curioso di avere una prospettiva di valutazione sulla postura ho frequentando il corso di posturologia metodo Mezieres riconosciuto dall\u2019AIFiMM. Credo che sia di fondamentale importanza condividere le mie conoscenze con i fisioterapisti tirocinanti universitari che mi affiancano, avendo portato a termine il percorso da TUTOR con Unife. Ho frequentato il Master ISICO (Istituto Scientifico Italiano Colonna Vertebrale di Milano), che verte sulla \u201cRiabilitazione dei pazienti affetti da patologie vertebrali\u201d e sulle \u201cDeformit\u00e0 vertebrali in et\u00e0 evolutiva e nell\u2019adulto\u201c. Mi sono specializzato ulteriormente in ambito pediatrico frequentando il corso EOM di VALUTAZIONE OSTEOPATICA PEDIATRICA. Attualmente svolgo la mia attivit\u00e0 nel mio studio (via Marconi 26 Nonantola) e in un centro privato\/convenzionato (collaborando con diverse figure mediche tra cui fisiatri, ortopedici, odontoiatri, cardiologi, internisti e oculisti).  Osteopatia, Osteopatia Pediatrica, Fisioterapia Ortopedica, Fisioterapia Cardio Respiratoria, Posturologia e Approccio SEAS, Massoterapia, Taping Neuromuscolare, Shiatsu, McKenzie,      Osteopatia, Osteopatia Pediatrica, Fisioterapia Ortopedica, Fisioterapia Cardio Respiratoria, Posturologia, Massoterapia, Taping Neuromuscolare, riabilitazione , fisioterapisti, fisioterapista, Osteopati, Osteopata,    Osteopatia a Nonantola , Osteopatia Pediatrica a Nonantola , Fisioterapia Ortopedica a Nonantola , Fisioterapia Cardio Respiratoria a Nonantola , Posturologia a Nonantola , Massoterapia a Nonantola , Taping Neuromuscolare a Nonantola , riabilitazione a Nonantola , fisioterapisti a Nonantola , fisioterapista a Nonantola , Osteopati a Nonantola , Osteopata a Nonantola ,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T09:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/\",\"name\":\"Dott. Gabriele Malagoli - Fisioterapista e Osteopata - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg\",\"datePublished\":\"2024-05-16T09:44:10+00:00\",\"dateModified\":\"2024-09-04T09:47:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Gabriele Malagoli &#8211; Fisioterapista e Osteopata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Gabriele Malagoli - Fisioterapista e Osteopata - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Gabriele Malagoli - Fisioterapista e Osteopata - UIL Polizia","og_description":"Fornire la massima cura e attenzione al paziente Sono laureato in FISIOTERAPIA presso l\u2019Universit\u00e0 di Modena e Reggio Emilia, dove ho approfondito la tematica della RIABILITAZIONE CARDIO RESPIRATORIA tramite tirocinio facoltativo in una struttura specializzata a Gaiato \u201cVilla Pineta\u201d. Ammaliato da questo tipo di riabilitazione ho concluso il mio percorso universitario costruendo la mia tesi su un progetto inerente la telemedicina del paziente allettato \u201cFisiochinesiterapia respiratoria associata a telemonitoraggio domiciliare per la prevenzione delle riacutizzazione da intasamento bronchiale nelle malattie neuromuscolari\u201d. Ho proseguito gli studi specializzandomi su riabilitazione e trattamento conservativo sia della spalla che del rachide cervicale e, dopo aver fatto un periodo di tirocinio in un centro specializzato sulla spalla, mi sono addentrato nel mondo della RIABILITAZIONE IN ACQUA frequentando il corso dell\u2019associazione ANIK (Associazione Nazionale IdroKinesiterapia). Ho continuato la formazione frequentando il corso McKENZIE, ma lavorando con il paziente, la mia esigenza \u00e8 stata proiettata verso un ulteriore passo sposando l\u2019idea di T.Still \u201cLa struttura governa la funzione.\u201d  Mi sono iscritto cosi al corso di Osteopatia alla Escuela di Osteopatia de Madrid dove mi sono diplomato al Master dei disordini muscoloscheletrici all\u2019universit\u00e0 di Taragona e concludendo i miei sei anni sono diventato Osteopata. Curioso di avere una prospettiva di valutazione sulla postura ho frequentando il corso di posturologia metodo Mezieres riconosciuto dall\u2019AIFiMM. Credo che sia di fondamentale importanza condividere le mie conoscenze con i fisioterapisti tirocinanti universitari che mi affiancano, avendo portato a termine il percorso da TUTOR con Unife. Ho frequentato il Master ISICO (Istituto Scientifico Italiano Colonna Vertebrale di Milano), che verte sulla \u201cRiabilitazione dei pazienti affetti da patologie vertebrali\u201d e sulle \u201cDeformit\u00e0 vertebrali in et\u00e0 evolutiva e nell\u2019adulto\u201c. Mi sono specializzato ulteriormente in ambito pediatrico frequentando il corso EOM di VALUTAZIONE OSTEOPATICA PEDIATRICA. Attualmente svolgo la mia attivit\u00e0 nel mio studio (via Marconi 26 Nonantola) e in un centro privato\/convenzionato (collaborando con diverse figure mediche tra cui fisiatri, ortopedici, odontoiatri, cardiologi, internisti e oculisti).  Osteopatia, Osteopatia Pediatrica, Fisioterapia Ortopedica, Fisioterapia Cardio Respiratoria, Posturologia e Approccio SEAS, Massoterapia, Taping Neuromuscolare, Shiatsu, McKenzie,      Osteopatia, Osteopatia Pediatrica, Fisioterapia Ortopedica, Fisioterapia Cardio Respiratoria, Posturologia, Massoterapia, Taping Neuromuscolare, riabilitazione , fisioterapisti, fisioterapista, Osteopati, Osteopata,    Osteopatia a Nonantola , Osteopatia Pediatrica a Nonantola , Fisioterapia Ortopedica a Nonantola , Fisioterapia Cardio Respiratoria a Nonantola , Posturologia a Nonantola , Massoterapia a Nonantola , Taping Neuromuscolare a Nonantola , riabilitazione a Nonantola , fisioterapisti a Nonantola , fisioterapista a Nonantola , Osteopati a Nonantola , Osteopata a Nonantola ,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/","og_site_name":"UIL Polizia","article_modified_time":"2024-09-04T09:47:56+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/","name":"Dott. Gabriele Malagoli - Fisioterapista e Osteopata - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg","datePublished":"2024-05-16T09:44:10+00:00","dateModified":"2024-09-04T09:47:56+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/logo_Gabriele-Malagoli.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-gabriele-malagoli-fisioterapista-e-osteopata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Gabriele Malagoli &#8211; Fisioterapista e Osteopata"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/63390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=63390"}],"version-history":[{"count":31,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/63390\/revisions"}],"predecessor-version":[{"id":68225,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/63390\/revisions\/68225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/68185"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=63390"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=63390"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=63390"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=63390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}