{"id":59639,"date":"2024-03-25T17:24:53","date_gmt":"2024-03-25T16:24:53","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=59639"},"modified":"2024-06-24T16:45:07","modified_gmt":"2024-06-24T14:45:07","slug":"concessionaria-eco-liri-spa","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/","title":{"rendered":"Concessionaria Eco Liri Spa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"59639\" class=\"elementor elementor-59639\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3eea98db e-flex e-con-boxed e-con e-parent\" data-id=\"3eea98db\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-944b5c3 elementor-widget elementor-widget-heading\" data-id=\"944b5c3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gruppo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70d23604 elementor-widget elementor-widget-heading\" data-id=\"70d23604\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eco Liri<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-419259c4 elementor-widget elementor-widget-heading\" data-id=\"419259c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le concessionarie del cuore<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-122f4868 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"122f4868\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a2595d0\" data-id=\"4a2595d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-149b8fe2 elementor-widget elementor-widget-text-editor\" data-id=\"149b8fe2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChi Siamo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d8f25fd elementor-widget elementor-widget-text-editor\" data-id=\"6d8f25fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da 40 anni&#8230; sempre in movimento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7410410d elementor-widget elementor-widget-text-editor\" data-id=\"7410410d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il <strong>Gruppo Eco Liri<\/strong>, da quarant&#8217;anni attivo sul territorio, \u00e8 diventato nel tempo, uno dei pi\u00f9 importanti operatori commerciali in Italia per i marchi <strong>FIAT, ALFA ROMEO, LANCIA, ABARTH, JEEP, FIAT PROFESSIONAL, DS, OPEL, DR, PEUGEOT e CITROEN<\/strong>.<\/p><p>La <strong>vendita di auto nuove, usate e km 0<\/strong> sono il nostro core business. Siamo, inoltre, diretti fornitori di tutti i servizi legati alla mobilit\u00e0: <strong>noleggio a breve e lungo termine, noleggio supercar, finanziamenti, assicurazioni, manutenzione<\/strong> e tanto altro.<\/p><p>Siamo proprietari dei brand <strong>Usato Store (usato), Dream Rent (noleggio supercar)<\/strong> ed <strong>Eco Lease (noleggio a lungo termine).<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-473a8124 elementor-widget elementor-widget-image\" data-id=\"473a8124\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1203\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg.jpg\" class=\"attachment-full size-full wp-image-63450\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg.jpg 1500w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg-1280x1027.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg-980x786.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg-480x385.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4912e0d4 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4912e0d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79c66dc8\" data-id=\"79c66dc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-700ad3a8 elementor-widget elementor-widget-text-editor\" data-id=\"700ad3a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChi Siamo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe67538 elementor-widget elementor-widget-text-editor\" data-id=\"2fe67538\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da 40 anni&#8230; sempre in movimento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5373c99f elementor-widget elementor-widget-text-editor\" data-id=\"5373c99f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il <strong>Gruppo Eco Liri<\/strong>, da quarant&#8217;anni attivo sul territorio, \u00e8 diventato nel tempo, uno dei pi\u00f9 importanti operatori commerciali in Italia per i marchi <strong>FIAT, ALFA ROMEO, LANCIA, ABARTH, JEEP, FIAT PROFESSIONAL, DS, OPEL, DR, PEUGEOT e CITROEN<\/strong>.<\/p><p>La <strong>vendita di auto nuove, usate e km 0<\/strong> sono il nostro core business. Siamo, inoltre, diretti fornitori di tutti i servizi legati alla mobilit\u00e0: <strong>noleggio a breve e lungo termine, noleggio supercar, finanziamenti, assicurazioni, manutenzione<\/strong> e tanto altro.<\/p><p>Siamo proprietari dei brand <strong>Usato Store (usato), Dream Rent (noleggio supercar)<\/strong> ed <strong>Eco Lease (noleggio a lungo termine).<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36e762d0\" data-id=\"36e762d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b813671 elementor-widget elementor-widget-image\" data-id=\"b813671\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1203\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg.jpg\" class=\"attachment-full size-full wp-image-63450\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg.jpg 1500w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg-1280x1027.jpg 1280w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg-980x786.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/gruppo_MAT1123-web.jpg-480x385.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-257ee2fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"257ee2fd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e6836d3\" data-id=\"1e6836d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6aa14996 elementor-widget elementor-widget-text-editor\" data-id=\"6aa14996\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcc0baf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bcc0baf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/File-convenzioni-GRUPPO-ECO-LIRI.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">guarda le condizioni<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-642e1b7d elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"642e1b7d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-31209a6e e-con-full e-flex e-con e-child\" data-id=\"31209a6e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ea88bd3 elementor-widget elementor-widget-text-editor\" data-id=\"7ea88bd3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CONTATTI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f758fbd elementor-widget elementor-widget-text-editor\" data-id=\"3f758fbd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tConcessionaria Eco Liri Spa\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43ad81ea elementor-widget elementor-widget-text-editor\" data-id=\"43ad81ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chiamaci al <span style=\"color: #085d00;\"><a style=\"color: #085d00;\" href=\"tel:+3907769149313\"><strong>07769149313<\/strong><\/a><\/span><br \/>Scrivici alla mail <span style=\"color: #085d00;\"><a style=\"color: #085d00;\" href=\"mailto:servizioclienti@gruppoecolirispa.com\"><strong>servizioclienti@gruppoecolirispa.com<\/strong><\/a><\/span><br \/>Visita il nostro sito <span style=\"color: #085d00;\"><a style=\"color: #085d00;\" href=\"https:\/\/www.gruppoecolirispa.com\/\"><strong>www.gruppoecolirispa.com<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3088a9 e-con-full e-flex e-con e-child\" data-id=\"2e3088a9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-483c112b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"483c112b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/latina.jpg\" class=\"attachment-full size-full wp-image-63463\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/latina.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/latina-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di Latina (LT)<\/h3><p class=\"elementor-image-box-description\">Casa Stellantis<br>\nVia Amerigo Vespucci, SNC - 04100 Latina<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701dd2b7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"701dd2b7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/sangiorgio.jpg\" class=\"attachment-full size-full wp-image-63465\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/sangiorgio.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/sangiorgio-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di San Giorgio a Liri (FR)<\/h3><p class=\"elementor-image-box-description\">Casa Stellantis<br>\nVia Ausonia, Km 10,200 - 03047 San Giorgio a Liri (FR)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cce730b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5cce730b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/tivoli.jpg\" class=\"attachment-full size-full wp-image-63467\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/tivoli.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/tivoli-480x360.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di Tivoli (RM)<\/h3><p class=\"elementor-image-box-description\">Via Maremmana Inf. km 0.500 - 00010 Tivoli (RM)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-324eacd2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"324eacd2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/terracina.jpg\" class=\"attachment-full size-full wp-image-63469\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/terracina.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/terracina-480x360.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di Terracina (LT)<\/h3><p class=\"elementor-image-box-description\">Via Pontina, Km 101.200 - 04019 Terracina (LT)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4cdf3376 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"4cdf3376\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6770a533 e-con-full e-flex e-con e-child\" data-id=\"6770a533\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36e518f3 elementor-widget elementor-widget-text-editor\" data-id=\"36e518f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CONTATTI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a76bf97 elementor-widget elementor-widget-text-editor\" data-id=\"7a76bf97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tConcessionaria Eco Liri Spa\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d38643 elementor-widget elementor-widget-text-editor\" data-id=\"32d38643\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chiamaci al <span style=\"color: #085d00;\"><a style=\"color: #085d00;\" href=\"tel:+3907769149313\"><strong>07769149313<\/strong><\/a><\/span><br \/>Scrivici alla mail <span style=\"color: #085d00;\"><a style=\"color: #085d00;\" href=\"mailto:servizioclienti@gruppoecolirispa.com\"><strong>servizioclienti@gruppoecolirispa.com<\/strong><\/a><\/span><br \/>Visita il nostro sito <span style=\"color: #085d00;\"><a style=\"color: #085d00;\" href=\"https:\/\/www.gruppoecolirispa.com\/\"><strong>www.gruppoecolirispa.com<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5159a664 e-con-full e-flex e-con e-child\" data-id=\"5159a664\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38a4271c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"38a4271c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/latina.jpg\" class=\"attachment-full size-full wp-image-63463\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/latina.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/latina-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di Latina (LT)<\/h3><p class=\"elementor-image-box-description\">Casa Stellantis<br>\nVia Amerigo Vespucci, SNC - 04100 Latina<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-208ee886 e-con-full e-flex e-con e-child\" data-id=\"208ee886\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24ffce08 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"24ffce08\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/sangiorgio.jpg\" class=\"attachment-full size-full wp-image-63465\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/sangiorgio.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/sangiorgio-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di San Giorgio a Liri (FR)<\/h3><p class=\"elementor-image-box-description\">Casa Stellantis<br>\nVia Ausonia, Km 10,200 - 03047 San Giorgio a Liri (FR)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1605d677 e-con-full e-flex e-con e-child\" data-id=\"1605d677\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37c37d69 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"37c37d69\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/tivoli.jpg\" class=\"attachment-full size-full wp-image-63467\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/tivoli.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/tivoli-480x360.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di Tivoli (RM)<\/h3><p class=\"elementor-image-box-description\">Via Maremmana Inf. km 0.500 - 00010 Tivoli (RM)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-581da8a e-con-full e-flex e-con e-child\" data-id=\"581da8a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d4fb7a3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1d4fb7a3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/terracina.jpg\" class=\"attachment-full size-full wp-image-63469\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/terracina.jpg 800w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/05\/terracina-480x360.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sede di Terracina (LT)<\/h3><p class=\"elementor-image-box-description\">Via Pontina, Km 101.200 - 04019 Terracina (LT)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-611fb166 e-con-full e-flex e-con e-parent\" data-id=\"611fb166\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69375aca elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"69375aca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-219\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-219\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:450px;\"> <span id=\"gmw-resize-map-toggle-219\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-219\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-219\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"219\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75dca43a elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75dca43a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38405a86\" data-id=\"38405a86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ffae879 elementor-widget elementor-widget-text-editor\" data-id=\"1ffae879\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68299738 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"68299738\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d10df37\" data-id=\"4d10df37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36d283e6 elementor-widget elementor-widget-text-editor\" data-id=\"36d283e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-327\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"59639\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-327\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-327\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-327\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-327\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"327\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ddb6cd9 elementor-widget elementor-widget-text-editor\" data-id=\"2ddb6cd9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-355\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-355\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-355\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-355\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-355\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"355\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>\u201cIl Gruppo Eco Liri, da quarant&#8217;anni attivo sul territorio, \u00e8 diventato nel tempo, uno dei pi\u00f9 importanti operatori commerciali in Italia per i marchi FIAT, ALFA ROMEO, LANCIA, ABARTH, JEEP, FIAT PROFESSIONAL, DS, OPEL, DR, PEUGEOT e CITROEN. La vendita di auto nuove, usate e km 0 sono il nostro core business. Siamo, inoltre, diretti fornitori di tutti i servizi legati alla mobilit\u00e0: noleggio a breve e lungo termine, noleggio supercar, finanziamenti, assicurazioni, manutenzione e tanto altro. Siamo proprietari dei brand Usato Store (usato), Dream Rent (noleggio supercar) ed Eco Lease (noleggio a lungo termine).\u201d<\/p>\n<p>noleggio a breve termine, noleggio a lungo termine, noleggio supercar, finanziamenti auto , assicurazioni auto , manutenzione auto, vendita di auto nuove, vendita di auto usate, vendita di auto km 0, Concessionaria, Concessionarie,<\/p>\n<p>noleggio a breve termine a Roma, noleggio a lungo termine a Roma, noleggio supercar a Roma, finanziamenti auto a Roma , assicurazioni auto a Roma , manutenzione auto a Roma, vendita di auto nuove a Roma, vendita di auto usate a Roma, vendita di auto km 0 a Roma, Concessionaria a Roma, Concessionarie a Roma,<\/p>\n<\/div>\n","protected":false},"featured_media":61549,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[18,29],"product_tag":[11911,2290,5376,11910,11912,6062,2447,11909,11913,9143,9140],"class_list":{"0":"post-59639","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-auto-moto","7":"product_cat-concessionari","8":"product_tag-assicurazioni-auto","9":"product_tag-concessionaria","10":"product_tag-concessionarie","11":"product_tag-finanziamenti-auto","12":"product_tag-manutenzione-auto","13":"product_tag-noleggio-a-breve-termine","14":"product_tag-noleggio-a-lungo-termine","15":"product_tag-noleggio-supercar","16":"product_tag-vendita-di-auto-km-0","17":"product_tag-vendita-di-auto-nuove","18":"product_tag-vendita-di-auto-usate","20":"first","21":"instock","22":"shipping-taxable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concessionaria Eco Liri Spa - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concessionaria Eco Liri Spa - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"\u201cIl Gruppo Eco Liri, da quarant&#039;anni attivo sul territorio, \u00e8 diventato nel tempo, uno dei pi\u00f9 importanti operatori commerciali in Italia per i marchi FIAT, ALFA ROMEO, LANCIA, ABARTH, JEEP, FIAT PROFESSIONAL, DS, OPEL, DR, PEUGEOT e CITROEN. La vendita di auto nuove, usate e km 0 sono il nostro core business. Siamo, inoltre, diretti fornitori di tutti i servizi legati alla mobilit\u00e0: noleggio a breve e lungo termine, noleggio supercar, finanziamenti, assicurazioni, manutenzione e tanto altro. Siamo proprietari dei brand Usato Store (usato), Dream Rent (noleggio supercar) ed Eco Lease (noleggio a lungo termine).\u201d  noleggio a breve termine, noleggio a lungo termine, noleggio supercar, finanziamenti auto , assicurazioni auto , manutenzione auto, vendita di auto nuove, vendita di auto usate, vendita di auto km 0, Concessionaria, Concessionarie,  noleggio a breve termine a Roma, noleggio a lungo termine a Roma, noleggio supercar a Roma, finanziamenti auto a Roma , assicurazioni auto a Roma , manutenzione auto a Roma, vendita di auto nuove a Roma, vendita di auto usate a Roma, vendita di auto km 0 a Roma, Concessionaria a Roma, Concessionarie a Roma,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T14:45:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/\",\"name\":\"Concessionaria Eco Liri Spa - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg\",\"datePublished\":\"2024-03-25T16:24:53+00:00\",\"dateModified\":\"2024-06-24T14:45:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Concessionaria Eco Liri Spa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concessionaria Eco Liri Spa - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/","og_locale":"it_IT","og_type":"article","og_title":"Concessionaria Eco Liri Spa - UIL Polizia","og_description":"\u201cIl Gruppo Eco Liri, da quarant'anni attivo sul territorio, \u00e8 diventato nel tempo, uno dei pi\u00f9 importanti operatori commerciali in Italia per i marchi FIAT, ALFA ROMEO, LANCIA, ABARTH, JEEP, FIAT PROFESSIONAL, DS, OPEL, DR, PEUGEOT e CITROEN. La vendita di auto nuove, usate e km 0 sono il nostro core business. Siamo, inoltre, diretti fornitori di tutti i servizi legati alla mobilit\u00e0: noleggio a breve e lungo termine, noleggio supercar, finanziamenti, assicurazioni, manutenzione e tanto altro. Siamo proprietari dei brand Usato Store (usato), Dream Rent (noleggio supercar) ed Eco Lease (noleggio a lungo termine).\u201d  noleggio a breve termine, noleggio a lungo termine, noleggio supercar, finanziamenti auto , assicurazioni auto , manutenzione auto, vendita di auto nuove, vendita di auto usate, vendita di auto km 0, Concessionaria, Concessionarie,  noleggio a breve termine a Roma, noleggio a lungo termine a Roma, noleggio supercar a Roma, finanziamenti auto a Roma , assicurazioni auto a Roma , manutenzione auto a Roma, vendita di auto nuove a Roma, vendita di auto usate a Roma, vendita di auto km 0 a Roma, Concessionaria a Roma, Concessionarie a Roma,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/","og_site_name":"UIL Polizia","article_modified_time":"2024-06-24T14:45:07+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/","name":"Concessionaria Eco Liri Spa - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg","datePublished":"2024-03-25T16:24:53+00:00","dateModified":"2024-06-24T14:45:07+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/03\/logo_Eco-Liri_.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/concessionaria-eco-liri-spa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Concessionaria Eco Liri Spa"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/59639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=59639"}],"version-history":[{"count":10,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/59639\/revisions"}],"predecessor-version":[{"id":65975,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/59639\/revisions\/65975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/61549"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=59639"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=59639"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=59639"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=59639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}