{"id":55236,"date":"2024-02-19T11:54:53","date_gmt":"2024-02-19T10:54:53","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=55236"},"modified":"2024-02-19T11:54:54","modified_gmt":"2024-02-19T10:54:54","slug":"dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/","title":{"rendered":"Dott.ssa Cristina Fanciullacci &#8211; Dietista e Nutrizionista"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"55236\" class=\"elementor elementor-55236\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ed6ac80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ed6ac80\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b7d57b0\" data-id=\"1b7d57b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-562ee181 elementor-widget elementor-widget-text-editor\" data-id=\"562ee181\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott.ssa Cristina Fanciullacci<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00bc62e elementor-widget elementor-widget-text-editor\" data-id=\"00bc62e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dietista e Nutrizionista<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79526333 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79526333\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78f16824\" data-id=\"78f16824\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-295ea2d3 elementor-widget elementor-widget-text-editor\" data-id=\"295ea2d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mia formazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5daf0e elementor-widget elementor-widget-text-editor\" data-id=\"e5daf0e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dopo la laurea in Dietistica ho conseguito il Master in \u201cDisturbi del comportamento alimentare in et\u00e0 evolutiva\u201d presso la Facolt\u00e0 di Medicina e Chirurgia dell&#8217;Universit\u00e0 degli Studi di Firenze &#8211; Cattedra di Neuropsichiatria Infantile &#8211; Dipartimento di Scienze Neurologiche e Psichiatriche Azienda Ospedaliera Universitaria di Careggi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe570a elementor-widget elementor-widget-text-editor\" data-id=\"4fe570a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con formazione permanente all&#8217;ascolto ad orientamento psicoanalitico, mi occupo della terapia dietetico &#8211; nutrizionale, effettuando valutazioni nutrizionali nelle persone sane di tutte le et\u00e0, in particolari stati fisiologici, gravidanza, allattamento, divezzamento, con particolari stili alimentari, vegetariani, vegani, sportivi, persone con patologie, obesit\u00e0, diabete, ipertensione, con allergie o intolleranze alimentari, e collaborando con le altre figure sanitarie in particolare nel trattamento dei disturbi alimentare in et\u00e0 evolutiva e adulta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764cd34 elementor-widget elementor-widget-text-editor\" data-id=\"764cd34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partire dall&#8217;ascolto della persona e dei suoi familiari quando necessario, sar\u00e0 fatta la valutazione dello stato nutrizionale attraverso un&#8217;anamnesi completa e raccolta dati come: stile di vita, abitudini alimentari, esami biochimici, misure antropometriche e composizione corporea; dopo essere state individuate e formulate le diagnosi nutrizionali e identificati i problemi e le relative cause, sar\u00e0 elaborato un piano dietetico personalizzato supportato dal counseling nutrizionale per la risoluzione del problema rilevato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c39fa2 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"0c39fa2\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/20240205_164000-FOTO-DR.SSA-CRISTINA-FANCIULLACCI-scaled.jpg\" alt=\"20240205_164000 FOTO DR.SSA CRISTINA FANCIULLACCI\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/IMG_20240122_195337-AMBULATORIO-DI-RIMAGGIO-SESTO-FIORENTINO-scaled.jpg\" alt=\"IMG_20240122_195337 AMBULATORIO DI RIMAGGIO SESTO FIORENTINO\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/IMG_20240123_170826-AMBULATORIO-STUDI-IAMA-PRATO-scaled.jpg\" alt=\"IMG_20240123_170826 AMBULATORIO STUDI IAMA PRATO\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-032888e elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"032888e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b53794\" data-id=\"7b53794\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ead4032 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"ead4032\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/20240205_164000-FOTO-DR.SSA-CRISTINA-FANCIULLACCI-scaled.jpg\" alt=\"20240205_164000 FOTO DR.SSA CRISTINA FANCIULLACCI\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/IMG_20240122_195337-AMBULATORIO-DI-RIMAGGIO-SESTO-FIORENTINO-scaled.jpg\" alt=\"IMG_20240122_195337 AMBULATORIO DI RIMAGGIO SESTO FIORENTINO\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/IMG_20240123_170826-AMBULATORIO-STUDI-IAMA-PRATO-scaled.jpg\" alt=\"IMG_20240123_170826 AMBULATORIO STUDI IAMA PRATO\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-99e19e1\" data-id=\"99e19e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e6972 elementor-widget elementor-widget-text-editor\" data-id=\"e5e6972\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mia formazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec2b3b2 elementor-widget elementor-widget-text-editor\" data-id=\"ec2b3b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dopo la laurea in Dietistica ho conseguito il Master in \u201cDisturbi del comportamento alimentare in et\u00e0 evolutiva\u201d presso la Facolt\u00e0 di Medicina e Chirurgia dell&#8217;Universit\u00e0 degli Studi di Firenze &#8211; Cattedra di Neuropsichiatria Infantile &#8211; Dipartimento di Scienze Neurologiche e Psichiatriche Azienda Ospedaliera Universitaria di Careggi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1664843 elementor-widget elementor-widget-text-editor\" data-id=\"1664843\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con formazione permanente all&#8217;ascolto ad orientamento psicoanalitico, mi occupo della terapia dietetico &#8211; nutrizionale, effettuando valutazioni nutrizionali nelle persone sane di tutte le et\u00e0, in particolari stati fisiologici, gravidanza, allattamento, divezzamento, con particolari stili alimentari, vegetariani, vegani, sportivi, persone con patologie, obesit\u00e0, diabete, ipertensione, con allergie o intolleranze alimentari, e collaborando con le altre figure sanitarie in particolare nel trattamento dei disturbi alimentare in et\u00e0 evolutiva e adulta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d1dfd2 elementor-widget elementor-widget-text-editor\" data-id=\"6d1dfd2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partire dall&#8217;ascolto della persona e dei suoi familiari quando necessario, sar\u00e0 fatta la valutazione dello stato nutrizionale attraverso un&#8217;anamnesi completa e raccolta dati come: stile di vita, abitudini alimentari, esami biochimici, misure antropometriche e composizione corporea; dopo essere state individuate e formulate le diagnosi nutrizionali e identificati i problemi e le relative cause, sar\u00e0 elaborato un piano dietetico personalizzato supportato dal counseling nutrizionale per la risoluzione del problema rilevato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34df6d14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34df6d14\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c297a14\" data-id=\"5c297a14\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4140dcd1 elementor-widget elementor-widget-text-editor\" data-id=\"4140dcd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce6c39c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"ce6c39c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b37cdc0 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b37cdc0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdad886\" data-id=\"cdad886\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c0d61 elementor-widget elementor-widget-text-editor\" data-id=\"61c0d61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d221bee elementor-widget elementor-widget-text-editor\" data-id=\"d221bee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #59a15b;\"><strong>Ambulatori di Rimaggio <\/strong><\/span><br \/>Via di Rimaggio, 19 &#8211; 50019 Sesto Fiorentino (FI)<\/p><p><span style=\"color: #59a15b;\"><strong>Centro Medico IAMA<\/strong><\/span><br \/>Via Pistoiese, 613\/2 &#8211; 59100 Prato<\/p><p><strong>Cell:<\/strong> 348 3390316<br \/><strong>Mail: <\/strong><span style=\"color: #59a15b;\"><a style=\"color: #59a15b;\" href=\"mailto:cri.fanciullacci@tiscali.it\">cri.fanciullacci@tiscali.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f26ec01 elementor-widget elementor-widget-text-editor\" data-id=\"f26ec01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-211\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-211\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-211\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-211\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-211\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"211\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f044fa elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f044fa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a7a9ae\" data-id=\"5a7a9ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d804e3 elementor-widget elementor-widget-text-editor\" data-id=\"7d804e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-914a036 elementor-widget elementor-widget-text-editor\" data-id=\"914a036\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #59a15b;\"><strong>Ambulatori di Rimaggio <\/strong><\/span><br \/>Via di Rimaggio, 19 &#8211; 50019 Sesto Fiorentino (FI)<\/p><p><span style=\"color: #59a15b;\"><strong>Centro Medico IAMA<\/strong><\/span><br \/>Via Pistoiese, 613\/2 &#8211; 59100 Prato<\/p><p><strong>Cell:<\/strong> 348 3390316<br \/><strong>Mail: <\/strong><span style=\"color: #59a15b;\"><a style=\"color: #59a15b;\" href=\"mailto:cri.fanciullacci@tiscali.it\">cri.fanciullacci@tiscali.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ecc918\" data-id=\"2ecc918\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-614a79b elementor-widget elementor-widget-text-editor\" data-id=\"614a79b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-162\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-162\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-162\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-162\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-162\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"162\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-202ab5bc elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"202ab5bc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1aca5448\" data-id=\"1aca5448\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66851957 elementor-widget elementor-widget-text-editor\" data-id=\"66851957\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7add20e2 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7add20e2\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7faea113\" data-id=\"7faea113\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b225739 elementor-widget elementor-widget-text-editor\" data-id=\"4b225739\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-278\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"55236\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-278\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-278\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-278\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-278\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"278\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c38c05 elementor-widget elementor-widget-text-editor\" data-id=\"50c38c05\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-535\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-535\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-535\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-535\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-535\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"535\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Dopo la laurea in Dietistica ho conseguito il Master in \u201cDisturbi del comportamento alimentare in et\u00e0 evolutiva\u201d presso la Facolt\u00e0 di Medicina e Chirurgia dell&#8217;Universit\u00e0 degli Studi di Firenze &#8211; Cattedra di Neuropsichiatria Infantile &#8211; Dipartimento di Scienze Neurologiche e Psichiatriche Azienda Ospedaliera Universitaria di Careggi.<br \/>\nCon formazione permanente all&#8217;ascolto ad orientamento psicoanalitico, mi occupo della terapia dietetico &#8211; nutrizionale, effettuando valutazioni nutrizionali nelle persone sane di tutte le et\u00e0, in particolari stati fisiologici, gravidanza, allattamento, divezzamento, con particolari stili alimentari, vegetariani, vegani, sportivi, persone con patologie, obesit\u00e0, diabete, ipertensione, con allergie o intolleranze alimentari, e collaborando con le altre figure sanitarie in particolare nel trattamento dei disturbi alimentare in et\u00e0 evolutiva e adulta.<br \/>\nA partire dall&#8217;ascolto della persona e dei suoi familiari quando necessario, sar\u00e0 fatta la valutazione dello stato nutrizionale attraverso un&#8217;anamnesi completa e raccolta dati come: stile di vita, abitudini alimentari, esami biochimici, misure antropometriche e composizione corporea; dopo essere state individuate e formulate le diagnosi nutrizionali e identificati i problemi e le relative cause, sar\u00e0 elaborato un piano dietetico personalizzato supportato dal counseling nutrizionale per la risoluzione del problema rilevato.<\/p>\n<p>Dietistica, Disturbi del comportamento alimentare, nutrizione in gravidanza, nutrizione in allattamento, nutrizione per vegetariani,  nutrizione per vegani,  nutrizione per sportivi, nutrizione per allergie, nutrizione per intolleranze alimentari, abitudini alimentari, diagnosi nutrizionali, counseling nutrizionale, consulenza nutrizionale, dieta, dietista, Nutrizionista, Nutrizionisti, dietisti, disturbi alimentari, <\/p>\n<p>diagnosi nutrizionali a Sesto Fiorentino, counseling nutrizionale a Sesto Fiorentino, consulenza nutrizionale a Sesto Fiorentino, dieta a Sesto Fiorentino, dietista a Sesto Fiorentino, Nutrizionista a Sesto Fiorentino, Nutrizionisti a Sesto Fiorentino, dietisti a Sesto Fiorentino,<\/p>\n<p>diagnosi nutrizionali a Prato, counseling nutrizionale a Prato, consulenza nutrizionale a Prato, dieta a Prato, dietista a Prato, Nutrizionista a Prato, Nutrizionisti a Prato, dietisti a Prato,<\/p>\n<\/div>\n","protected":false},"featured_media":55237,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[198,234,163],"product_tag":[3750,2829,11240,11233,2421,11239,11232,11230,11238,11231,1142,11241,10401,1102,11242,11234,1186,11245,11237,1514,1462,6939,5072,11229,7785,7501,11228,7628,459,11243,11235,1049,11244,11236],"class_list":{"0":"post-55236","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dietisti","7":"product_cat-nutrizionisti","8":"product_cat-salute","9":"product_tag-abitudini-alimentari","10":"product_tag-consulenza-nutrizionale","11":"product_tag-consulenza-nutrizionale-a-prato","12":"product_tag-consulenza-nutrizionale-a-sesto-fiorentino","13":"product_tag-counseling-nutrizionale","14":"product_tag-counseling-nutrizionale-a-prato","15":"product_tag-counseling-nutrizionale-a-sesto-fiorentino","16":"product_tag-diagnosi-nutrizionali","17":"product_tag-diagnosi-nutrizionali-a-prato","18":"product_tag-diagnosi-nutrizionali-a-sesto-fiorentino","19":"product_tag-dieta","20":"product_tag-dieta-a-prato","21":"product_tag-dieta-a-sesto-fiorentino","22":"product_tag-dietista","23":"product_tag-dietista-a-prato","24":"product_tag-dietista-a-sesto-fiorentino","25":"product_tag-dietisti","26":"product_tag-dietisti-a-prato","27":"product_tag-dietisti-a-sesto-fiorentino","28":"product_tag-disturbi-alimentari","29":"product_tag-disturbi-del-comportamento-alimentare","30":"product_tag-nutrizione-in-allattamento","31":"product_tag-nutrizione-in-gravidanza","32":"product_tag-nutrizione-per-allergie","33":"product_tag-nutrizione-per-intolleranze-alimentari","34":"product_tag-nutrizione-per-sportivi","35":"product_tag-nutrizione-per-vegani","36":"product_tag-nutrizione-per-vegetariani","37":"product_tag-nutrizionista","38":"product_tag-nutrizionista-a-prato","39":"product_tag-nutrizionista-a-sesto-fiorentino","40":"product_tag-nutrizionisti","41":"product_tag-nutrizionisti-a-prato","42":"product_tag-nutrizionisti-a-sesto-fiorentino","44":"first","45":"instock","46":"shipping-taxable","47":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Cristina Fanciullacci - Dietista e Nutrizionista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Cristina Fanciullacci - Dietista e Nutrizionista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dopo la laurea in Dietistica ho conseguito il Master in \u201cDisturbi del comportamento alimentare in et\u00e0 evolutiva\u201d presso la Facolt\u00e0 di Medicina e Chirurgia dell&#039;Universit\u00e0 degli Studi di Firenze - Cattedra di Neuropsichiatria Infantile - Dipartimento di Scienze Neurologiche e Psichiatriche Azienda Ospedaliera Universitaria di Careggi. Con formazione permanente all&#039;ascolto ad orientamento psicoanalitico, mi occupo della terapia dietetico - nutrizionale, effettuando valutazioni nutrizionali nelle persone sane di tutte le et\u00e0, in particolari stati fisiologici, gravidanza, allattamento, divezzamento, con particolari stili alimentari, vegetariani, vegani, sportivi, persone con patologie, obesit\u00e0, diabete, ipertensione, con allergie o intolleranze alimentari, e collaborando con le altre figure sanitarie in particolare nel trattamento dei disturbi alimentare in et\u00e0 evolutiva e adulta. A partire dall&#039;ascolto della persona e dei suoi familiari quando necessario, sar\u00e0 fatta la valutazione dello stato nutrizionale attraverso un&#039;anamnesi completa e raccolta dati come: stile di vita, abitudini alimentari, esami biochimici, misure antropometriche e composizione corporea; dopo essere state individuate e formulate le diagnosi nutrizionali e identificati i problemi e le relative cause, sar\u00e0 elaborato un piano dietetico personalizzato supportato dal counseling nutrizionale per la risoluzione del problema rilevato.    Dietistica, Disturbi del comportamento alimentare, nutrizione in gravidanza, nutrizione in allattamento, nutrizione per vegetariani, nutrizione per vegani, nutrizione per sportivi, nutrizione per allergie, nutrizione per intolleranze alimentari, abitudini alimentari, diagnosi nutrizionali, counseling nutrizionale, consulenza nutrizionale, dieta, dietista, Nutrizionista, Nutrizionisti, dietisti, disturbi alimentari,     diagnosi nutrizionali a Sesto Fiorentino, counseling nutrizionale a Sesto Fiorentino, consulenza nutrizionale a Sesto Fiorentino, dieta a Sesto Fiorentino, dietista a Sesto Fiorentino, Nutrizionista a Sesto Fiorentino, Nutrizionisti a Sesto Fiorentino, dietisti a Sesto Fiorentino,   diagnosi nutrizionali a Prato, counseling nutrizionale a Prato, consulenza nutrizionale a Prato, dieta a Prato, dietista a Prato, Nutrizionista a Prato, Nutrizionisti a Prato, dietisti a Prato,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T10:54:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/\",\"name\":\"Dott.ssa Cristina Fanciullacci - Dietista e Nutrizionista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg\",\"datePublished\":\"2024-02-19T10:54:53+00:00\",\"dateModified\":\"2024-02-19T10:54:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Cristina Fanciullacci &#8211; Dietista e Nutrizionista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Cristina Fanciullacci - Dietista e Nutrizionista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Cristina Fanciullacci - Dietista e Nutrizionista - UIL Polizia","og_description":"Dopo la laurea in Dietistica ho conseguito il Master in \u201cDisturbi del comportamento alimentare in et\u00e0 evolutiva\u201d presso la Facolt\u00e0 di Medicina e Chirurgia dell'Universit\u00e0 degli Studi di Firenze - Cattedra di Neuropsichiatria Infantile - Dipartimento di Scienze Neurologiche e Psichiatriche Azienda Ospedaliera Universitaria di Careggi. Con formazione permanente all'ascolto ad orientamento psicoanalitico, mi occupo della terapia dietetico - nutrizionale, effettuando valutazioni nutrizionali nelle persone sane di tutte le et\u00e0, in particolari stati fisiologici, gravidanza, allattamento, divezzamento, con particolari stili alimentari, vegetariani, vegani, sportivi, persone con patologie, obesit\u00e0, diabete, ipertensione, con allergie o intolleranze alimentari, e collaborando con le altre figure sanitarie in particolare nel trattamento dei disturbi alimentare in et\u00e0 evolutiva e adulta. A partire dall'ascolto della persona e dei suoi familiari quando necessario, sar\u00e0 fatta la valutazione dello stato nutrizionale attraverso un'anamnesi completa e raccolta dati come: stile di vita, abitudini alimentari, esami biochimici, misure antropometriche e composizione corporea; dopo essere state individuate e formulate le diagnosi nutrizionali e identificati i problemi e le relative cause, sar\u00e0 elaborato un piano dietetico personalizzato supportato dal counseling nutrizionale per la risoluzione del problema rilevato.    Dietistica, Disturbi del comportamento alimentare, nutrizione in gravidanza, nutrizione in allattamento, nutrizione per vegetariani, nutrizione per vegani, nutrizione per sportivi, nutrizione per allergie, nutrizione per intolleranze alimentari, abitudini alimentari, diagnosi nutrizionali, counseling nutrizionale, consulenza nutrizionale, dieta, dietista, Nutrizionista, Nutrizionisti, dietisti, disturbi alimentari,     diagnosi nutrizionali a Sesto Fiorentino, counseling nutrizionale a Sesto Fiorentino, consulenza nutrizionale a Sesto Fiorentino, dieta a Sesto Fiorentino, dietista a Sesto Fiorentino, Nutrizionista a Sesto Fiorentino, Nutrizionisti a Sesto Fiorentino, dietisti a Sesto Fiorentino,   diagnosi nutrizionali a Prato, counseling nutrizionale a Prato, consulenza nutrizionale a Prato, dieta a Prato, dietista a Prato, Nutrizionista a Prato, Nutrizionisti a Prato, dietisti a Prato,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/","og_site_name":"UIL Polizia","article_modified_time":"2024-02-19T10:54:54+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/","name":"Dott.ssa Cristina Fanciullacci - Dietista e Nutrizionista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg","datePublished":"2024-02-19T10:54:53+00:00","dateModified":"2024-02-19T10:54:54+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/Logo_Cristina-Fanciullacci.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-fanciullacci-dietista-e-nutrizionista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Cristina Fanciullacci &#8211; Dietista e Nutrizionista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/55236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=55236"}],"version-history":[{"count":29,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/55236\/revisions"}],"predecessor-version":[{"id":55333,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/55236\/revisions\/55333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/55237"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=55236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=55236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=55236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=55236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}