{"id":54488,"date":"2024-02-06T10:15:55","date_gmt":"2024-02-06T09:15:55","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=54488"},"modified":"2024-02-06T11:19:57","modified_gmt":"2024-02-06T10:19:57","slug":"dott-ssa-elisa-morelli-biologa-nutrizionista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/","title":{"rendered":"Dott.ssa Elisa Morelli &#8211; Biologa Nutrizionista"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/mainslider-bg003.jpg&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; custom_padding_tablet=&#8221;8vw||8vw||true|false&#8221; custom_padding_phone=&#8221;10vw||10vw||true|false&#8221; background_last_edited=&#8221;on|desktop&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; background_color_gradient_direction_tablet=&#8221;90deg&#8221; background_color_gradient_stops_tablet=&#8221;#ffffff 17%|rgba(255, 255, 255, 0.71) 58%|rgba(255,255,255,0) 100%&#8221; background_color_gradient_overlays_image_tablet=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1800px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo-elisa-1.png&#8221; title_text=&#8221;logo-elisa-1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;45%&#8221; width_tablet=&#8221;60%&#8221; width_phone=&#8221;72%&#8221; width_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#555555&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;Prata||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.4em&#8221; header_2_font=&#8221;Poppins|600||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#9dca00&#8243; header_2_font_size=&#8221;18px&#8221; header_2_letter_spacing=&#8221;5px&#8221; header_2_line_height=&#8221;1.8em&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;16px&#8221; header_2_font_size_phone=&#8221;14px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>\u2014 Dott.ssa Morelli<\/h2>\n<h1>&#8220;Non devi mangiare di meno, devi solo mangiare bene&#8221;<\/h1>\n<p><strong>Dott.ssa abilitata<\/strong> nello sviluppo di <strong>piani alimentari<\/strong> volti a migliorare lo stato di salute e di benessere o trovare nella giusta dieta il supporto nutrizionale fondamentale per numerose patologie ancorch\u00e9 gi\u00e0 in trattamento terapeutico\/farmacologico.<\/p>\n<p>Esperta in<strong> nutrizione sportiva<\/strong> e di integrazione personalizzata.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/elisa-hp.jpg&#8221; title_text=&#8221;elisa-hp&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#555555&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Prata||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.4em&#8221; header_2_font=&#8221;Poppins|600||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#9dca00&#8243; header_2_font_size=&#8221;18px&#8221; header_2_letter_spacing=&#8221;5px&#8221; header_2_line_height=&#8221;1.8em&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;|-15px||-15px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_tablet=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_phone=&#8221;40px|15px|40px|15px|true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;16px&#8221; header_2_font_size_phone=&#8221;14px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_letter_spacing_tablet=&#8221;5px&#8221; header_2_letter_spacing_phone=&#8221;3px&#8221; header_2_letter_spacing_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;20px&#8221; box_shadow_spread=&#8221;-5px&#8221; box_shadow_color=&#8221;#def58f&#8221; box_shadow_blur_tablet=&#8221;20px&#8221; box_shadow_blur_phone=&#8221;15px&#8221; box_shadow_blur_last_edited=&#8221;on|phone&#8221; box_shadow_spread_tablet=&#8221;-5px&#8221; box_shadow_spread_phone=&#8221;-5px&#8221; box_shadow_spread_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>\u2014 Durata: Circa 45 Min<\/h2>\n<h1>&#8220;Prima visita nutrizionale<\/h1>\n<p><strong>Cosa portare:<\/strong><br \/>\u2022 Diario alimentare di una settimana (ci\u00f2 che mangi e a che ora)<br \/>\u2022 Rilevazioni della temperatura corporea (misurare la mattina appena svegli per 4 giorni consecutivi)<br \/>\u2022 Gli esami del sangue recenti (non oltre 12 mesi)<\/p>\n<p><strong>Valutazione generale<\/strong><br \/>Valutazione di anamnesi fisiopatologica, del diario alimentare, e di eventuali documentazioni cliniche<\/p>\n<p><strong>Misure antropometriche<\/strong><br \/>Rilevamento delle misure antropometriche e studio della composizione corporea<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/tm-col-bg-five.jpg&#8221; title_text=&#8221;tm-col-bg-five&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#9dca00&#8243; custom_padding=&#8221;70px|70px|70px|70px|true|true&#8221; custom_padding_tablet=&#8221;50px|50px|50px|50px|true|true&#8221; custom_padding_phone=&#8221;30px|30px|30px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_type=&#8221;circle&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; ul_font=&#8221;Poppins||||||||&#8221; ul_text_color=&#8221;#ffffff&#8221; ul_font_size=&#8221;16px&#8221; ul_line_height=&#8221;2em&#8221; header_font=&#8221;Prata||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;45px&#8221; ul_font_size_tablet=&#8221;14px&#8221; ul_font_size_phone=&#8221;14px&#8221; ul_font_size_last_edited=&#8221;on|desktop&#8221; ul_line_height_tablet=&#8221;2em&#8221; ul_line_height_phone=&#8221;1.8em&#8221; ul_line_height_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Servizi offerti<\/h1>\n<ul>\n<li>Piani nutrizionali personalizzati<\/li>\n<li>Alimentazione pediatrica<\/li>\n<li>Alimentazione geriatrica<\/li>\n<li>Allenamento e alimentazione in gravidanza e nel post parto<\/li>\n<li>Pesata gratuita del tuo neonato<\/li>\n<li>Diete Sportive<\/li>\n<li>Esperta in nutrizione clinica e funzionale<\/li>\n<li>Riabilitazione ed educazione alimentare nei disturbi del comportamento alimentare<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.elisanutrizionista.it\/servizi\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Maggiori informzazioni&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#ffffff&#8221; button_border_width=&#8221;1px&#8221; button_border_radius=&#8221;10px&#8221; button_font=&#8221;Poppins||||||||&#8221; button_icon=&#8221;&#xf56b;||fa||900&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.21.0&#8243; background_enable_color=&#8221;off&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/row-img-seven.jpg&#8221; custom_padding=&#8221;||||true&#8221; custom_padding_tablet=&#8221;20px||20px||true|false&#8221; custom_padding_phone=&#8221;||||true&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_type=&#8221;circle&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; ul_font=&#8221;Poppins||||||||&#8221; ul_text_color=&#8221;#ffffff&#8221; ul_font_size=&#8221;16px&#8221; ul_line_height=&#8221;2em&#8221; header_font=&#8221;Prata||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; ul_font_size_tablet=&#8221;16px&#8221; ul_font_size_phone=&#8221;16px&#8221; ul_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;34px&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][et_pb_text ul_type=&#8221;circle&#8221; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; ul_font=&#8221;Poppins||||||||&#8221; ul_text_color=&#8221;#ffffff&#8221; ul_font_size=&#8221;16px&#8221; ul_line_height=&#8221;2em&#8221; header_font=&#8221;Prata||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.5em&#8221; ul_font_size_tablet=&#8221;16px&#8221; ul_font_size_phone=&#8221;16px&#8221; ul_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;27px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#555555&#8243; text_line_height=&#8221;1.9em&#8221; link_text_color=&#8221;#9dca00&#8243; header_font=&#8221;Prata||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|600||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#9dca00&#8243; header_2_font_size=&#8221;18px&#8221; header_2_letter_spacing=&#8221;5px&#8221; header_2_line_height=&#8221;1.4em&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;16px&#8221; header_2_font_size_phone=&#8221;14px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#333333&#8243;]<\/p>\n<h2>\u2014 Contatti<\/h2>\n<h1>Lo studio<\/h1>\n<p>Piazza Tarantelli, 5\/a &#8211; 20005 Pogliano (MI)<br \/><strong>Cell: <\/strong>3487602207<br \/><strong>Mail: <\/strong><a href=\"mailto:info@elisanutrizionista.it\">info@elisanutrizionista.it<\/a><br \/><strong>Sito web: <\/strong><a href=\"https:\/\/www.elisanutrizionista.it\/\">www.elisanutrizionista.it<\/a><br \/><strong>Lun &#8211; Ven: <\/strong>9:00 &#8211; 12:00 \/ 14:30 &#8211; 19:00<br \/><strong>Sab:<\/strong> 9:00 &#8211; 12:30<\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-10px||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/elisa.morelli.nutrizionista&#8221; icon_color=&#8221;#9dca00&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#9dca00&#8243; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;#9dca00&#8243; background__hover_enabled=&#8221;on|desktop&#8221; background_enable_color__hover=&#8221;on&#8221; icon_color__hover=&#8221;#ffffff&#8221; icon_color__hover_enabled=&#8221;on|desktop&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;http:\/\/instagram.com\/elisa.morelli.nutrizionista&#8221; icon_color=&#8221;#9dca00&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#9dca00&#8243; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;#9dca00&#8243; background__hover_enabled=&#8221;on|desktop&#8221; background_enable_color__hover=&#8221;on&#8221; icon_color__hover=&#8221;#ffffff&#8221; icon_color__hover_enabled=&#8221;on|desktop&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;whatsapp&#8221; url=&#8221;https:\/\/wa.me\/393487602207&#8243; icon_color=&#8221;#9dca00&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#9dca00&#8243; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|desktop&#8221; background_color__hover=&#8221;#9dca00&#8243; background_enable_color__hover=&#8221;on&#8221; icon_color__hover_enabled=&#8221;on|desktop&#8221; icon_color__hover=&#8221;#ffffff&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]whatsapp[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-303\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"54488\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-303\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-303\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-303\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-303\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"303\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e7f3fd&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Piazza Enzo Tarantelli, 5A, 20005 Pogliano Milanese MI, Italia <br>\n<strong>Telefono:<\/strong> 3487602207 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.elisanutrizionista.it\">www.elisanutrizionista.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:info@elisanutrizionista.it\">info@elisanutrizionista.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-175\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"54488\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-175\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-175\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-175\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-175\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"175\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-116\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-116\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-116\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-116\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-116\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"116\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Non devi mangiare di meno, devi solo mangiare bene<br \/>\nDott.ssa abilitata nello sviluppo di piani alimentari volti a migliorare lo stato di salute e di benessere o trovare nella giusta dieta il supporto nutrizionale fondamentale per numerose patologie ancorch\u00e9 gi\u00e0 in trattamento terapeutico\/farmacologico.<\/p>\n<p>Esperta in nutrizione sportiva e di integrazione personalizzata.<\/p>\n<p>Piani nutrizionali personalizzati<br \/>\nPiani alimentari funzionali ed efficaci, per rispondere a obiettivi specifici in base al proprio corpo, adatti a pazienti in stato fisiologico e\/o in stato patologico (gi\u00e0 diagnosticate).<\/p>\n<p>Alimentazione pediatrica<br \/>\nUna corretta alimentazione permette di sviluppare al meglio il potenziale di crescita del bambino e di diminuire lo sviluppo di malattie cronico-degenerative da adulti.<\/p>\n<p>Alimentazione geriatrica<br \/>\nIl principale problema nutrizionale nell\u2019anziano \u00e8 rappresentato dalla malnutrizione per difetto spesso secondaria a riduzione dell\u2019introito alimentare ed alla perdita di motivazione all\u2019assunzione di cibo.<\/p>\n<p>Allenamento e alimentazione in gravidanza e nel post parto<br \/>\nNel corso della gestazione l\u2019organismo va incontro a una serie di adattamenti fisiologici e il realizzarsi di questi in maniera ottimale \u00e8 il punto di partenza per un buon esito della gravidanza. Un\u2019alimentazione corretta \u00e8 condizione indispensabile a garantire il benessere materno (riducendo le complicanze come reflusso, stipsi, nausea e vomito, diabete gestazionale) e fetale.<\/p>\n<p>Pesata gratuita del tuo neonato<br \/>\nPuoi effettuare una pesata gratuita del tuo neonato, tutte le volte che vuoi, in modo da tenere monitorata la crescita settimana per settimana.<\/p>\n<p>E\u2019 necessario prendere un appuntamento.<\/p>\n<p>Diete Sportive<br \/>\nLa dieta ha un ruolo importante anche nello sport: pur non esistendo alimenti miracolosi in grado da soli di migliorare le prestazioni fisiche, si pu\u00f2 affermare che, associata ad un allenamento adeguato, consente il massimo rendimento agonistico.<\/p>\n<p>Esperta in nutrizione clinica e funzionale<br \/>\nservizi-disturbi alimentari<br \/>\nRiabilitazione ed educazione alimentare nei disturbi del comportamento alimentare<br \/>\nservizi-alimentazione-patologie<br \/>\nGestione dietetica delle patologie pi\u00f9 frequenti<br \/>\nLa Sindrome Metabolica<br \/>\nDislipidemia e Ipertensione<br \/>\nL\u2019Obesit\u00e0 Grave<br \/>\nPatologie Epatiche: focus on NAFLD, NASH<br \/>\nPatologie Pancreatiche: focus on diabete, insulino-resistenza<br \/>\nPatologie Renali: focus on IRC, IRA<br \/>\nPatologie Intestinali Infiammatorie: Celiachia, RCU, Chron Disease, Colon irritabile<\/p>\n<p>mangiare bene, piani alimentari, dieta, supporto nutrizionale, nutrizione sportiva, Piani nutrizionali personalizzati, Alimentazione pediatrica, corretta alimentazione, Alimentazione geriatrica, alimentazione in gravidanza, alimentazione in Allenamento , alimentazione corretta, Diete Sportive, nutrizione clinica, disturbi alimentari, educazione alimentare, Biologa Nutrizionista, Biologi Nutrizionisti,<\/p>\n<p>piani alimentari a Pogliano Milanese, dieta a Pogliano Milanese, supporto nutrizionale a Pogliano Milanese, nutrizione sportiva a Pogliano Milanese, Piani nutrizionali personalizzati a Pogliano Milanese, Alimentazione pediatrica a Pogliano Milanese, corretta alimentazione a Pogliano Milanese, Alimentazione geriatrica a Pogliano Milanese, alimentazione in gravidanza a Pogliano Milanese, alimentazione in Allenamento a Pogliano Milanese , alimentazione corretta a Pogliano Milanese, Diete Sportive a Pogliano Milanese, nutrizione clinica a Pogliano Milanese, educazione alimentare a Pogliano Milanese, Biologa Nutrizionista a Pogliano Milanese, Biologi Nutrizionisti a Pogliano Milanese,<\/p>\n<\/div>\n","protected":false},"featured_media":54489,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[175,163],"product_tag":[5690,11039,11026,11036,11027,11038,3250,11037,3251,11034,1235,11043,4050,11044,3748,11035,1142,11030,11028,11040,1514,3147,11042,5756,5432,11041,5344,11032,4412,11029,5691,11033,7212,11031],"class_list":{"0":"post-54488","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biologo-nutrizionista","7":"product_cat-salute","8":"product_tag-alimentazione-corretta","9":"product_tag-alimentazione-corretta-a-pogliano-milanese","10":"product_tag-alimentazione-geriatrica","11":"product_tag-alimentazione-geriatrica-a-pogliano-milanese","12":"product_tag-alimentazione-in-allenamento","13":"product_tag-alimentazione-in-allenamento-a-pogliano-milanese","14":"product_tag-alimentazione-in-gravidanza","15":"product_tag-alimentazione-in-gravidanza-a-pogliano-milanese","16":"product_tag-alimentazione-pediatrica","17":"product_tag-alimentazione-pediatrica-a-pogliano-milanese","18":"product_tag-biologa-nutrizionista","19":"product_tag-biologa-nutrizionista-a-pogliano-milanese","20":"product_tag-biologi-nutrizionisti","21":"product_tag-biologi-nutrizionisti-a-pogliano-milanese","22":"product_tag-corretta-alimentazione","23":"product_tag-corretta-alimentazione-a-pogliano-milanese","24":"product_tag-dieta","25":"product_tag-dieta-a-pogliano-milanese","26":"product_tag-diete-sportive","27":"product_tag-diete-sportive-a-pogliano-milanese","28":"product_tag-disturbi-alimentari","29":"product_tag-educazione-alimentare","30":"product_tag-educazione-alimentare-a-pogliano-milanese","31":"product_tag-mangiare-bene","32":"product_tag-nutrizione-clinica","33":"product_tag-nutrizione-clinica-a-pogliano-milanese","34":"product_tag-nutrizione-sportiva","35":"product_tag-nutrizione-sportiva-a-pogliano-milanese","36":"product_tag-piani-alimentari","37":"product_tag-piani-alimentari-a-pogliano-milanese","38":"product_tag-piani-nutrizionali-personalizzati","39":"product_tag-piani-nutrizionali-personalizzati-a-pogliano-milanese","40":"product_tag-supporto-nutrizionale","41":"product_tag-supporto-nutrizionale-a-pogliano-milanese","43":"first","44":"instock","45":"shipping-taxable","46":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Elisa Morelli - Biologa Nutrizionista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Elisa Morelli - Biologa Nutrizionista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Non devi mangiare di meno, devi solo mangiare bene Dott.ssa abilitata nello sviluppo di piani alimentari volti a migliorare lo stato di salute e di benessere o trovare nella giusta dieta il supporto nutrizionale fondamentale per numerose patologie ancorch\u00e9 gi\u00e0 in trattamento terapeutico\/farmacologico.  Esperta in nutrizione sportiva e di integrazione personalizzata.  Piani nutrizionali personalizzati Piani alimentari funzionali ed efficaci, per rispondere a obiettivi specifici in base al proprio corpo, adatti a pazienti in stato fisiologico e\/o in stato patologico (gi\u00e0 diagnosticate).  Alimentazione pediatrica Una corretta alimentazione permette di sviluppare al meglio il potenziale di crescita del bambino e di diminuire lo sviluppo di malattie cronico-degenerative da adulti.  Alimentazione geriatrica Il principale problema nutrizionale nell\u2019anziano \u00e8 rappresentato dalla malnutrizione per difetto spesso secondaria a riduzione dell\u2019introito alimentare ed alla perdita di motivazione all\u2019assunzione di cibo.  Allenamento e alimentazione in gravidanza e nel post parto Nel corso della gestazione l\u2019organismo va incontro a una serie di adattamenti fisiologici e il realizzarsi di questi in maniera ottimale \u00e8 il punto di partenza per un buon esito della gravidanza. Un\u2019alimentazione corretta \u00e8 condizione indispensabile a garantire il benessere materno (riducendo le complicanze come reflusso, stipsi, nausea e vomito, diabete gestazionale) e fetale.  Pesata gratuita del tuo neonato Puoi effettuare una pesata gratuita del tuo neonato, tutte le volte che vuoi, in modo da tenere monitorata la crescita settimana per settimana.  E\u2019 necessario prendere un appuntamento.  Diete Sportive La dieta ha un ruolo importante anche nello sport: pur non esistendo alimenti miracolosi in grado da soli di migliorare le prestazioni fisiche, si pu\u00f2 affermare che, associata ad un allenamento adeguato, consente il massimo rendimento agonistico.  Esperta in nutrizione clinica e funzionale servizi-disturbi alimentari Riabilitazione ed educazione alimentare nei disturbi del comportamento alimentare servizi-alimentazione-patologie Gestione dietetica delle patologie pi\u00f9 frequenti La Sindrome Metabolica Dislipidemia e Ipertensione L\u2019Obesit\u00e0 Grave Patologie Epatiche: focus on NAFLD, NASH Patologie Pancreatiche: focus on diabete, insulino-resistenza Patologie Renali: focus on IRC, IRA Patologie Intestinali Infiammatorie: Celiachia, RCU, Chron Disease, Colon irritabile  mangiare bene, piani alimentari, dieta, supporto nutrizionale, nutrizione sportiva, Piani nutrizionali personalizzati, Alimentazione pediatrica, corretta alimentazione, Alimentazione geriatrica, alimentazione in gravidanza, alimentazione in Allenamento , alimentazione corretta, Diete Sportive, nutrizione clinica, disturbi alimentari, educazione alimentare, Biologa Nutrizionista, Biologi Nutrizionisti,  piani alimentari a Pogliano Milanese, dieta a Pogliano Milanese, supporto nutrizionale a Pogliano Milanese, nutrizione sportiva a Pogliano Milanese, Piani nutrizionali personalizzati a Pogliano Milanese, Alimentazione pediatrica a Pogliano Milanese, corretta alimentazione a Pogliano Milanese, Alimentazione geriatrica a Pogliano Milanese, alimentazione in gravidanza a Pogliano Milanese, alimentazione in Allenamento a Pogliano Milanese , alimentazione corretta a Pogliano Milanese, Diete Sportive a Pogliano Milanese, nutrizione clinica a Pogliano Milanese, educazione alimentare a Pogliano Milanese, Biologa Nutrizionista a Pogliano Milanese, Biologi Nutrizionisti a Pogliano Milanese,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T10:19:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/\",\"name\":\"Dott.ssa Elisa Morelli - Biologa Nutrizionista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg\",\"datePublished\":\"2024-02-06T09:15:55+00:00\",\"dateModified\":\"2024-02-06T10:19:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Elisa Morelli &#8211; Biologa Nutrizionista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Elisa Morelli - Biologa Nutrizionista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Elisa Morelli - Biologa Nutrizionista - UIL Polizia","og_description":"Non devi mangiare di meno, devi solo mangiare bene Dott.ssa abilitata nello sviluppo di piani alimentari volti a migliorare lo stato di salute e di benessere o trovare nella giusta dieta il supporto nutrizionale fondamentale per numerose patologie ancorch\u00e9 gi\u00e0 in trattamento terapeutico\/farmacologico.  Esperta in nutrizione sportiva e di integrazione personalizzata.  Piani nutrizionali personalizzati Piani alimentari funzionali ed efficaci, per rispondere a obiettivi specifici in base al proprio corpo, adatti a pazienti in stato fisiologico e\/o in stato patologico (gi\u00e0 diagnosticate).  Alimentazione pediatrica Una corretta alimentazione permette di sviluppare al meglio il potenziale di crescita del bambino e di diminuire lo sviluppo di malattie cronico-degenerative da adulti.  Alimentazione geriatrica Il principale problema nutrizionale nell\u2019anziano \u00e8 rappresentato dalla malnutrizione per difetto spesso secondaria a riduzione dell\u2019introito alimentare ed alla perdita di motivazione all\u2019assunzione di cibo.  Allenamento e alimentazione in gravidanza e nel post parto Nel corso della gestazione l\u2019organismo va incontro a una serie di adattamenti fisiologici e il realizzarsi di questi in maniera ottimale \u00e8 il punto di partenza per un buon esito della gravidanza. Un\u2019alimentazione corretta \u00e8 condizione indispensabile a garantire il benessere materno (riducendo le complicanze come reflusso, stipsi, nausea e vomito, diabete gestazionale) e fetale.  Pesata gratuita del tuo neonato Puoi effettuare una pesata gratuita del tuo neonato, tutte le volte che vuoi, in modo da tenere monitorata la crescita settimana per settimana.  E\u2019 necessario prendere un appuntamento.  Diete Sportive La dieta ha un ruolo importante anche nello sport: pur non esistendo alimenti miracolosi in grado da soli di migliorare le prestazioni fisiche, si pu\u00f2 affermare che, associata ad un allenamento adeguato, consente il massimo rendimento agonistico.  Esperta in nutrizione clinica e funzionale servizi-disturbi alimentari Riabilitazione ed educazione alimentare nei disturbi del comportamento alimentare servizi-alimentazione-patologie Gestione dietetica delle patologie pi\u00f9 frequenti La Sindrome Metabolica Dislipidemia e Ipertensione L\u2019Obesit\u00e0 Grave Patologie Epatiche: focus on NAFLD, NASH Patologie Pancreatiche: focus on diabete, insulino-resistenza Patologie Renali: focus on IRC, IRA Patologie Intestinali Infiammatorie: Celiachia, RCU, Chron Disease, Colon irritabile  mangiare bene, piani alimentari, dieta, supporto nutrizionale, nutrizione sportiva, Piani nutrizionali personalizzati, Alimentazione pediatrica, corretta alimentazione, Alimentazione geriatrica, alimentazione in gravidanza, alimentazione in Allenamento , alimentazione corretta, Diete Sportive, nutrizione clinica, disturbi alimentari, educazione alimentare, Biologa Nutrizionista, Biologi Nutrizionisti,  piani alimentari a Pogliano Milanese, dieta a Pogliano Milanese, supporto nutrizionale a Pogliano Milanese, nutrizione sportiva a Pogliano Milanese, Piani nutrizionali personalizzati a Pogliano Milanese, Alimentazione pediatrica a Pogliano Milanese, corretta alimentazione a Pogliano Milanese, Alimentazione geriatrica a Pogliano Milanese, alimentazione in gravidanza a Pogliano Milanese, alimentazione in Allenamento a Pogliano Milanese , alimentazione corretta a Pogliano Milanese, Diete Sportive a Pogliano Milanese, nutrizione clinica a Pogliano Milanese, educazione alimentare a Pogliano Milanese, Biologa Nutrizionista a Pogliano Milanese, Biologi Nutrizionisti a Pogliano Milanese,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/","og_site_name":"UIL Polizia","article_modified_time":"2024-02-06T10:19:57+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/","name":"Dott.ssa Elisa Morelli - Biologa Nutrizionista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg","datePublished":"2024-02-06T09:15:55+00:00","dateModified":"2024-02-06T10:19:57+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/logo_Elisa-Morelli.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-elisa-morelli-biologa-nutrizionista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Elisa Morelli &#8211; Biologa Nutrizionista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/54488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=54488"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/54488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/54489"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=54488"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=54488"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=54488"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=54488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}