{"id":54237,"date":"2024-01-30T15:12:33","date_gmt":"2024-01-30T14:12:33","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=54237"},"modified":"2024-01-31T16:39:31","modified_gmt":"2024-01-31T15:39:31","slug":"avvocato-giuseppe-novembre","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/","title":{"rendered":"Avvocato Giuseppe Novembre"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;4%&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#004c76&#8243; background_enable_image=&#8221;off&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;3%&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;10%|8%|10%|8%&#8221; custom_padding_tablet=&#8221;10%|8%|10%|8%&#8221; custom_padding_phone=&#8221;20%|5%|20%|5%|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|200||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#f7f7f7&#8243; header_font_size=&#8221;35px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Avvocato<\/h1>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#f7f7f7&#8243; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Giuseppe Novembre<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/giuseppe_novembre_avvocato_1.jpg&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/giuseppe_novembre_avvocato_1.jpg&#8221; title_text=&#8221;giuseppe_novembre_avvocato_1&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1140px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/giuseppe_novembre_avvocato_2.jpg&#8221; title_text=&#8221;giuseppe_novembre_avvocato_2&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|700|||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.6em&#8221; text_font_size_tablet=&#8221;27px&#8221; text_font_size_phone=&#8221;25px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Avvocato Civilista per Consulenze Legali<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;-10px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Piacere, sono Giuseppe Novembre.<\/p>\n<p>Sono un avvocato civilista esperto in consulenza per aziende, professionisti e privati.<\/p>\n<p>Ho conseguito la Laurea in Giurisprudenza presso l\u2019Universit\u00e0 di Modena nel 2014, nel 2016 ho superato il percorso biennale di Studi di Specializzazione delle professioni legali a Bologna e nel 2018 mi sono abilitato come avvocato.<\/p>\n<p>Nello stesso anno ho aperto il mio studio, con un obiettivo preciso: offrire ai miei clienti una consulenza personalizzata e orientata alle soluzioni.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/giuseppe_novembre_avvocato_2.jpg&#8221; title_text=&#8221;giuseppe_novembre_avvocato_2&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f9f9fb&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1140px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|700|||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.6em&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;27px&#8221; text_font_size_phone=&#8221;25px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Cosa mi distingue come avvocato civilista?<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; text_orientation=&#8221;center&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sono due i principali elementi che mi differenziano.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1140px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;23px&#8221; text_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La mia filosofia di lavoro<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ho un approccio conciliativo, orientato a prevenire le controversie legali.<\/p>\n<p>Nel caso in cui questo non sia possibile, consiglio ai miei clienti di intraprendere le soluzioni stragiudiziarie pi\u00f9 adatte alle loro esigenze.<\/p>\n<p>Davanti ai contenziosi, invece, mi piace optare per soluzioni rapide e vantaggiose, volte a minimizzare il pi\u00f9 possibile la durata delle cause.<\/p>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-professionisti&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;23px&#8221; text_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il mio sguardo verso il futuro<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Come avvocato civilista, so bene che la normativa cambia continuamente. Per questo motivo, mi tengo costantemente aggiornato.<\/p>\n<p>Ogni anno seguo master e corsi di alta formazione su tematiche importanti come il tema della privacy e del GDPR per le aziende, corsi in materia di contrattualistica commerciale, diritto immobiliare, contenziosi legati al super bonus 110%, e molto altro, come attestano i titoli a seguire!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1140px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|700|||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.6em&#8221; text_font_size_tablet=&#8221;27px&#8221; text_font_size_phone=&#8221;25px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Servizi e consulenza legale per imprese e privati<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;-15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La mia esperienza, sempre al tuo servizio!<\/p>\n<p>Contrattualistica, consulenza stragiudiziale, mediazioni e negoziazioni assistite, contenziosi\u2026 c\u2019\u00e8 sempre una buona ragione per affidarsi alla mia consulenza legale personalizzata.<\/p>\n<p>Infatti, quando si tratta di proteggere e valorizzare i tuoi interessi o quelli della tua azienda, la giusta esperienza pu\u00f2 fare la differenza.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.avvgiuseppenovembre.it\/i-servizi-che-offro\/servizi-per-aziende-e-professionisti\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Per aziende e professionisti&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#004c76&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Poppins||||||||&#8221; custom_margin=&#8221;-10px||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.avvgiuseppenovembre.it\/i-servizi-che-offro\/servizi-per-le-persone\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Per le persone&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#004c76&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Poppins||||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/giuseppe_novembre_avvocato_3.jpg&#8221; title_text=&#8221;giuseppe_novembre_avvocato_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#004c76&#8243; background_enable_image=&#8221;off&#8221; background_enable_pattern_style=&#8221;on&#8221; background_pattern_style=&#8221;cubes&#8221; background_pattern_color=&#8221;rgba(0,0,0,0.1)&#8221; background_pattern_size=&#8221;custom&#8221; background_pattern_width=&#8221;282px&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Lora||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Poppins|200|||||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#ffffff&#8221; header_3_font_size=&#8221;40px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_5_text_color=&#8221;rgba(0,0,0,0.4)&#8221; header_5_font_size=&#8221;20px&#8221; header_5_letter_spacing=&#8221;3px&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;left&#8221; custom_margin_tablet=&#8221;|70px||70px&#8221; custom_margin_phone=&#8221;|50px||50px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221; header_3_font_size_tablet=&#8221;34px&#8221; header_3_font_size_phone=&#8221;27px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Trattamento riservato su presentazione tessera<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|700|||||||&#8221; text_text_color=&#8221;#004c76&#8243; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.6em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Contatti<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;2em&#8221; link_text_color=&#8221;#004c76&#8243; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Indirizzo:<\/strong> Via Bellucci, 3 &#8211; 41058 Vignola (MO)<br \/><strong>Telefono:<\/strong> +39 392 1611 514<br \/><strong>Mail:<\/strong> <a href=\"mailto:info@avvgiuseppenovembre.it\">info@avvgiuseppenovembre.it<\/a><br \/><strong>Sito web:<\/strong> <a href=\"https:\/\/www.avvgiuseppenovembre.it\/\" target=\"_blank\" rel=\"noopener\">www.avvgiuseppenovembre.it<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-477\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"54237\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-477\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-477\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-477\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-477\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"477\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-388\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-388\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-388\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-388\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-388\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"388\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Giovan Battista Bellucci, 3, 41058 Vignola MO, Italia <br>\n<strong>Telefono:<\/strong> +39 392 1611 514 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.avvgiuseppenovembre.it\">www.avvgiuseppenovembre.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:info@avvgiuseppenovembre.it\">info@avvgiuseppenovembre.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Giuseppe Novembre, avvocato civilista per consulenze legaliPiacere, sono Giuseppe Novembre.<br \/>\nSono un avvocato civilista esperto in consulenza per aziende, professionisti e privati.<br \/>\nHo conseguito la Laurea in Giurisprudenza presso l\u2019Universit\u00e0 di Modena nel 2014, nel 2016 ho superato il percorso biennale di Studi di Specializzazione delle professioni legali a Bologna e nel 2018 mi sono abilitato come avvocato.<br \/>\nNello stesso anno ho aperto il mio studio, con un obiettivo preciso: offrire ai miei clienti una consulenza personalizzata e orientata alle soluzioni.Cosa mi distingue come avvocato civilista?<br \/>\nSono due i principali elementi che mi differenziano.<\/p>\n<p>La mia filosofia di lavoro<br \/>\nHo un approccio conciliativo, orientato a prevenire le controversie legali.<br \/>\nNel caso in cui questo non sia possibile, consiglio ai miei clienti di intraprendere le soluzioni stragiudiziarie pi\u00f9 adatte alle loro esigenze.<br \/>\nDavanti ai contenziosi, invece, mi piace optare per soluzioni rapide e vantaggiose, volte a minimizzare il pi\u00f9 possibile la durata delle cause.<\/p>\n<p>Il mio sguardo verso il futuro<br \/>\nCome avvocato civilista, so bene che la normativa cambia continuamente. Per questo motivo, mi tengo costantemente aggiornato.<br \/>\nOgni anno seguo master e corsi di alta formazione su tematiche importanti come il tema della privacy e del GDPR per le aziende, corsi in materia di contrattualistica commerciale, diritto immobiliare, contenziosi legati al super bonus 110%, e molto altro, come attestano i titoli a seguire!<\/p>\n<p>Servizi e consulenza legale per imprese e privati<br \/>\nLa mia esperienza, sempre al tuo servizio!<br \/>\nContrattualistica, consulenza stragiudiziale, mediazioni e negoziazioni assistite, contenziosi\u2026 c\u2019\u00e8 sempre una buona ragione per affidarsi alla mia consulenza legale personalizzata.<br \/>\nInfatti, quando si tratta di proteggere e valorizzare i tuoi interessi o quelli della tua azienda, la giusta esperienza pu\u00f2 fare la differenza.<\/p>\n<p>studio legale, studi legali, avv, avv., avvocato, avvocati, avvocato civilista, avvocati civilisti, avv civilista, avv. civilista, consulenza personalizzata, Contrattualistica, consulenza stragiudiziale, mediazioni, negoziazioni assistite, contenziosi<\/p>\n<p>studio legale a Vigola, studi legali a Vigola, avv a Vigola, avv. a Vigola, avvocato a Vigola, avvocati a Vigola, avvocato civilista a Vigola, avvocati civilisti a Vigola, avv civilista a Vigola, avv. civilista a Vigola, consulenza personalizzata a Vigola, Contrattualistica a Vigola, consulenza stragiudiziale a Vigola, mediazioni a Vigola, negoziazioni assistite a Vigola, contenziosi a Vigola<\/p>\n<p>studio legale Vigola, studi legali Vigola, avv Vigola, avv. Vigola, avvocato Vigola, avvocati Vigola, avvocato civilista Vigola, avvocati civilisti Vigola, avv civilista Vigola, avv. civilista Vigola, consulenza personalizzata Vigola, Contrattualistica Vigola, consulenza stragiudiziale Vigola, mediazioni Vigola, negoziazioni assistite Vigola, contenziosi Vigola<\/p>\n<\/div>\n","protected":false},"featured_media":54238,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[147,161],"product_tag":[7840,10884,371,9598,370,2800,10885,5762,10887,1924,6447,10886,906,374],"class_list":{"0":"post-54237","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-professionisti-studi-consulenze","7":"product_cat-studi-legali","8":"product_tag-avv","9":"product_tag-avv-civilista","10":"product_tag-avvocati","11":"product_tag-avvocati-civilisti","12":"product_tag-avvocato","13":"product_tag-avvocato-civilista","14":"product_tag-consulenza-personalizzata","15":"product_tag-consulenza-stragiudiziale","16":"product_tag-contenziosi","17":"product_tag-contrattualistica","18":"product_tag-mediazioni","19":"product_tag-negoziazioni-assistite","20":"product_tag-studi-legali","21":"product_tag-studio-legale","23":"first","24":"instock","25":"shipping-taxable","26":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avvocato Giuseppe Novembre - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avvocato Giuseppe Novembre - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Giuseppe Novembre, avvocato civilista per consulenze legaliPiacere, sono Giuseppe Novembre. Sono un avvocato civilista esperto in consulenza per aziende, professionisti e privati. Ho conseguito la Laurea in Giurisprudenza presso l\u2019Universit\u00e0 di Modena nel 2014, nel 2016 ho superato il percorso biennale di Studi di Specializzazione delle professioni legali a Bologna e nel 2018 mi sono abilitato come avvocato. Nello stesso anno ho aperto il mio studio, con un obiettivo preciso: offrire ai miei clienti una consulenza personalizzata e orientata alle soluzioni.Cosa mi distingue come avvocato civilista? Sono due i principali elementi che mi differenziano.  La mia filosofia di lavoro Ho un approccio conciliativo, orientato a prevenire le controversie legali. Nel caso in cui questo non sia possibile, consiglio ai miei clienti di intraprendere le soluzioni stragiudiziarie pi\u00f9 adatte alle loro esigenze. Davanti ai contenziosi, invece, mi piace optare per soluzioni rapide e vantaggiose, volte a minimizzare il pi\u00f9 possibile la durata delle cause.  Il mio sguardo verso il futuro Come avvocato civilista, so bene che la normativa cambia continuamente. Per questo motivo, mi tengo costantemente aggiornato. Ogni anno seguo master e corsi di alta formazione su tematiche importanti come il tema della privacy e del GDPR per le aziende, corsi in materia di contrattualistica commerciale, diritto immobiliare, contenziosi legati al super bonus 110%, e molto altro, come attestano i titoli a seguire!  Servizi e consulenza legale per imprese e privati La mia esperienza, sempre al tuo servizio! Contrattualistica, consulenza stragiudiziale, mediazioni e negoziazioni assistite, contenziosi\u2026 c\u2019\u00e8 sempre una buona ragione per affidarsi alla mia consulenza legale personalizzata. Infatti, quando si tratta di proteggere e valorizzare i tuoi interessi o quelli della tua azienda, la giusta esperienza pu\u00f2 fare la differenza.  studio legale, studi legali, avv, avv., avvocato, avvocati, avvocato civilista, avvocati civilisti, avv civilista, avv. civilista, consulenza personalizzata, Contrattualistica, consulenza stragiudiziale, mediazioni, negoziazioni assistite, contenziosi  studio legale a Vigola, studi legali a Vigola, avv a Vigola, avv. a Vigola, avvocato a Vigola, avvocati a Vigola, avvocato civilista a Vigola, avvocati civilisti a Vigola, avv civilista a Vigola, avv. civilista a Vigola, consulenza personalizzata a Vigola, Contrattualistica a Vigola, consulenza stragiudiziale a Vigola, mediazioni a Vigola, negoziazioni assistite a Vigola, contenziosi a Vigola  studio legale Vigola, studi legali Vigola, avv Vigola, avv. Vigola, avvocato Vigola, avvocati Vigola, avvocato civilista Vigola, avvocati civilisti Vigola, avv civilista Vigola, avv. civilista Vigola, consulenza personalizzata Vigola, Contrattualistica Vigola, consulenza stragiudiziale Vigola, mediazioni Vigola, negoziazioni assistite Vigola, contenziosi Vigola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T15:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/\",\"name\":\"Avvocato Giuseppe Novembre - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg\",\"datePublished\":\"2024-01-30T14:12:33+00:00\",\"dateModified\":\"2024-01-31T15:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avvocato Giuseppe Novembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avvocato Giuseppe Novembre - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/","og_locale":"it_IT","og_type":"article","og_title":"Avvocato Giuseppe Novembre - UIL Polizia","og_description":"Giuseppe Novembre, avvocato civilista per consulenze legaliPiacere, sono Giuseppe Novembre. Sono un avvocato civilista esperto in consulenza per aziende, professionisti e privati. Ho conseguito la Laurea in Giurisprudenza presso l\u2019Universit\u00e0 di Modena nel 2014, nel 2016 ho superato il percorso biennale di Studi di Specializzazione delle professioni legali a Bologna e nel 2018 mi sono abilitato come avvocato. Nello stesso anno ho aperto il mio studio, con un obiettivo preciso: offrire ai miei clienti una consulenza personalizzata e orientata alle soluzioni.Cosa mi distingue come avvocato civilista? Sono due i principali elementi che mi differenziano.  La mia filosofia di lavoro Ho un approccio conciliativo, orientato a prevenire le controversie legali. Nel caso in cui questo non sia possibile, consiglio ai miei clienti di intraprendere le soluzioni stragiudiziarie pi\u00f9 adatte alle loro esigenze. Davanti ai contenziosi, invece, mi piace optare per soluzioni rapide e vantaggiose, volte a minimizzare il pi\u00f9 possibile la durata delle cause.  Il mio sguardo verso il futuro Come avvocato civilista, so bene che la normativa cambia continuamente. Per questo motivo, mi tengo costantemente aggiornato. Ogni anno seguo master e corsi di alta formazione su tematiche importanti come il tema della privacy e del GDPR per le aziende, corsi in materia di contrattualistica commerciale, diritto immobiliare, contenziosi legati al super bonus 110%, e molto altro, come attestano i titoli a seguire!  Servizi e consulenza legale per imprese e privati La mia esperienza, sempre al tuo servizio! Contrattualistica, consulenza stragiudiziale, mediazioni e negoziazioni assistite, contenziosi\u2026 c\u2019\u00e8 sempre una buona ragione per affidarsi alla mia consulenza legale personalizzata. Infatti, quando si tratta di proteggere e valorizzare i tuoi interessi o quelli della tua azienda, la giusta esperienza pu\u00f2 fare la differenza.  studio legale, studi legali, avv, avv., avvocato, avvocati, avvocato civilista, avvocati civilisti, avv civilista, avv. civilista, consulenza personalizzata, Contrattualistica, consulenza stragiudiziale, mediazioni, negoziazioni assistite, contenziosi  studio legale a Vigola, studi legali a Vigola, avv a Vigola, avv. a Vigola, avvocato a Vigola, avvocati a Vigola, avvocato civilista a Vigola, avvocati civilisti a Vigola, avv civilista a Vigola, avv. civilista a Vigola, consulenza personalizzata a Vigola, Contrattualistica a Vigola, consulenza stragiudiziale a Vigola, mediazioni a Vigola, negoziazioni assistite a Vigola, contenziosi a Vigola  studio legale Vigola, studi legali Vigola, avv Vigola, avv. Vigola, avvocato Vigola, avvocati Vigola, avvocato civilista Vigola, avvocati civilisti Vigola, avv civilista Vigola, avv. civilista Vigola, consulenza personalizzata Vigola, Contrattualistica Vigola, consulenza stragiudiziale Vigola, mediazioni Vigola, negoziazioni assistite Vigola, contenziosi Vigola","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/","og_site_name":"UIL Polizia","article_modified_time":"2024-01-31T15:39:31+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/","name":"Avvocato Giuseppe Novembre - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg","datePublished":"2024-01-30T14:12:33+00:00","dateModified":"2024-01-31T15:39:31+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-avv-giuseppe-novembre.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/avvocato-giuseppe-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Avvocato Giuseppe Novembre"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/54237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=54237"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/54237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/54238"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=54237"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=54237"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=54237"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=54237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}