{"id":53857,"date":"2024-01-17T15:55:28","date_gmt":"2024-01-17T14:55:28","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=53857"},"modified":"2024-01-30T16:11:39","modified_gmt":"2024-01-30T15:11:39","slug":"studio-legale-convertini-giatti","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/","title":{"rendered":"Studio Legale Convertini Giatti"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(33,33,33,0.5) 1%|#242424 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/AdobeStock_290607746-1-scaled-1.jpeg&#8221; custom_padding=&#8221;200px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Playfair Display|||on|||||&#8221; text_text_color=&#8221;#ddac3f&#8221; text_font_size=&#8221;30px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.6em&#8221; text_font_size_tablet=&#8221;30px&#8221; text_font_size_phone=&#8221;28px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Studio Legale<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Playfair Display|700|||||||&#8221; text_text_color=&#8221;#ddac3f&#8221; text_font_size=&#8221;70px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-20px||||false|false&#8221; text_font_size_tablet=&#8221;60px&#8221; text_font_size_phone=&#8221;44px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Convertini Giatti<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#242424&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.8em&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;justified&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Il nostro studio legale si propone di fornire un&#8217;attivit\u00e0 completa sia in termini di consulenza Giudiziale, Stragiudiziale e Contrattualistica.<\/p>\n<p>Si adopera per difendere i nostri assistiti nelle pi\u00f9 opportune sedi Giudiziarie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;CONTRATTI&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x69;||divi||400&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Sviluppiamo ogni contratto per ogni vostra esigenza<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;DIFESA IN GIUDIZIO&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf515;||fa||900&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;CONSULENZA&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf2b5;||fa||400&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#242424&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ddac3f&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; custom_padding_tablet=&#8221;30px|40px||40px|false|true&#8221; custom_padding_phone=&#8221;30px|30px|30px|30px|true|true&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Lora||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Playfair Display|700|||||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#212121&#8243; header_3_font_size=&#8221;40px&#8221; header_3_line_height=&#8221;1.5em&#8221; header_5_text_color=&#8221;rgba(0,0,0,0.4)&#8221; header_5_font_size=&#8221;20px&#8221; header_5_letter_spacing=&#8221;3px&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;left&#8221; custom_margin_tablet=&#8221;|70px||70px&#8221; custom_margin_phone=&#8221;|50px||50px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221; header_3_font_size_tablet=&#8221;33px&#8221; header_3_font_size_phone=&#8221;25px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3>Trattamento riservato su presentazione tessera<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#242424&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Playfair Display||||||||&#8221; text_text_color=&#8221;#ddac3f&#8221; text_font_size=&#8221;30px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.6em&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Contattaci<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;30px&#8221; text_orientation=&#8221;center&#8221; link_option_url=&#8221;tel:+390376631224&#8243; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>+39 0376 631224<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;30px||||false|false&#8221; custom_padding=&#8221;60px||||false|false&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;rgba(221,172,63,0.15)&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;DOVE SIAMO&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf276;||fa||900&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]Via Bernardo Ordanino, 48<br \/>\n46043 Castiglione delle Stiviere (MN)[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;MAIL&#8221; url=&#8221;mailto:info@lexlegis.it&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf0e0;||fa||400&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; link_option_url=&#8221;mailto:info@lexlegis.it&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>info@lexlegis.it<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;VISITA IL SITO&#8221; url=&#8221;https:\/\/lexlegis.it\/&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0e3;||divi||400&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; link_option_url=&#8221;https:\/\/lexlegis.it\/&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>lexlegis.it<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;30px||||false|false&#8221; custom_padding=&#8221;60px||||false|false&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;rgba(221,172,63,0.15)&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;AVV. ANGELO CONVERTINI&#8221; url=&#8221;mailto:info@lexlegis.it&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf2bd;||fa||400&#8243; icon_color=&#8221;#ddac3f&#8221; image_icon_width=&#8221;35px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ddac3f&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.8em&#8221; body_link_text_color=&#8221;#FFFFFF&#8221; link_option_url=&#8221;mailto:info@lexlegis.it&#8221; link_option_url_new_window=&#8221;on&#8221; body_font_size_tablet=&#8221;16px&#8221; body_font_size_phone=&#8221;15px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><strong>Mail:<\/strong> <a href=\"mailto:con.ang70@virgilio.it\">con.ang70@virgilio.it<\/a><br \/><strong>PEC:<\/strong> <a href=\"mailto:angelo.convertini@mantova.pecavvocati.it\">angelo.convertini@mantova.pecavvocati.it<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_code admin_label=&#8221;mappa&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div id=\"gmw-single-location-wrapper-354\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"53857\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-354\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-354\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-354\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-354\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"354\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Bernardo Ordanino, 48, 46043 Castiglione delle Stiviere MN, Italia <br>\n<strong>Telefono:<\/strong> +39 0376 631224 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/lexlegis.it\">lexlegis.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:info@lexlegis.it\">info@lexlegis.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none\">\nIl nostro studio legale si propone di fornire un&#8217;attivit\u00e0 completa sia in termini di consulenza Giudiziale, Stragiudiziale e Contrattualistica. Si adopera per difendere i nostri assistiti nelle pi\u00f9 opportune sedi Giudiziarie.<\/p>\n<p>SERVIZI<br \/>\nCONTRATTI<br \/>\nSviluppiamo ogni contratto per ogni vostra esigenza<br \/>\nDIFESA IN GIUDIZIO<br \/>\nCONSULENZA<\/p>\n<p>studio legale, studi legali, avvocato, avvocati, avv, avv., contratti, difesa in giudizio, consulenza<\/p>\n<p>studio legale a Castiglione delle Stiviere, studi legali a Castiglione delle Stiviere, avvocato a Castiglione delle Stiviere, avvocati a Castiglione delle Stiviere, avv a Castiglione delle Stiviere, avv. a Castiglione delle Stiviere, contratti a Castiglione delle Stiviere, difesa in giudizio a Castiglione delle Stiviere, consulenza a Castiglione delle Stiviere<\/p>\n<p>studio legale Castiglione delle Stiviere, studi legali Castiglione delle Stiviere, avvocato Castiglione delle Stiviere, avvocati Castiglione delle Stiviere, avv Castiglione delle Stiviere, avv. Castiglione delle Stiviere, contratti Castiglione delle Stiviere, difesa in giudizio Castiglione delle Stiviere, consulenza Castiglione delle Stiviere\n<\/p><\/div>\n","protected":false},"featured_media":53858,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[147,161],"product_tag":[7840,371,370,653,1916,10678,906,374],"class_list":{"0":"post-53857","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-professionisti-studi-consulenze","7":"product_cat-studi-legali","8":"product_tag-avv","9":"product_tag-avvocati","10":"product_tag-avvocato","11":"product_tag-consulenza","12":"product_tag-contratti","13":"product_tag-difesa-in-giudizio","14":"product_tag-studi-legali","15":"product_tag-studio-legale","17":"first","18":"instock","19":"shipping-taxable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Studio Legale Convertini Giatti - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio Legale Convertini Giatti - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Il nostro studio legale si propone di fornire un&#039;attivit\u00e0 completa sia in termini di consulenza Giudiziale, Stragiudiziale e Contrattualistica. Si adopera per difendere i nostri assistiti nelle pi\u00f9 opportune sedi Giudiziarie.  SERVIZI CONTRATTI Sviluppiamo ogni contratto per ogni vostra esigenza DIFESA IN GIUDIZIO CONSULENZA  studio legale, studi legali, avvocato, avvocati, avv, avv., contratti, difesa in giudizio, consulenza  studio legale a Castiglione delle Stiviere, studi legali a Castiglione delle Stiviere, avvocato a Castiglione delle Stiviere, avvocati a Castiglione delle Stiviere, avv a Castiglione delle Stiviere, avv. a Castiglione delle Stiviere, contratti a Castiglione delle Stiviere, difesa in giudizio a Castiglione delle Stiviere, consulenza a Castiglione delle Stiviere  studio legale Castiglione delle Stiviere, studi legali Castiglione delle Stiviere, avvocato Castiglione delle Stiviere, avvocati Castiglione delle Stiviere, avv Castiglione delle Stiviere, avv. Castiglione delle Stiviere, contratti Castiglione delle Stiviere, difesa in giudizio Castiglione delle Stiviere, consulenza Castiglione delle Stiviere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T15:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/\",\"name\":\"Studio Legale Convertini Giatti - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg\",\"datePublished\":\"2024-01-17T14:55:28+00:00\",\"dateModified\":\"2024-01-30T15:11:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Studio Legale Convertini Giatti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio Legale Convertini Giatti - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/","og_locale":"it_IT","og_type":"article","og_title":"Studio Legale Convertini Giatti - UIL Polizia","og_description":"Il nostro studio legale si propone di fornire un'attivit\u00e0 completa sia in termini di consulenza Giudiziale, Stragiudiziale e Contrattualistica. Si adopera per difendere i nostri assistiti nelle pi\u00f9 opportune sedi Giudiziarie.  SERVIZI CONTRATTI Sviluppiamo ogni contratto per ogni vostra esigenza DIFESA IN GIUDIZIO CONSULENZA  studio legale, studi legali, avvocato, avvocati, avv, avv., contratti, difesa in giudizio, consulenza  studio legale a Castiglione delle Stiviere, studi legali a Castiglione delle Stiviere, avvocato a Castiglione delle Stiviere, avvocati a Castiglione delle Stiviere, avv a Castiglione delle Stiviere, avv. a Castiglione delle Stiviere, contratti a Castiglione delle Stiviere, difesa in giudizio a Castiglione delle Stiviere, consulenza a Castiglione delle Stiviere  studio legale Castiglione delle Stiviere, studi legali Castiglione delle Stiviere, avvocato Castiglione delle Stiviere, avvocati Castiglione delle Stiviere, avv Castiglione delle Stiviere, avv. Castiglione delle Stiviere, contratti Castiglione delle Stiviere, difesa in giudizio Castiglione delle Stiviere, consulenza Castiglione delle Stiviere","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/","og_site_name":"UIL Polizia","article_modified_time":"2024-01-30T15:11:39+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/","name":"Studio Legale Convertini Giatti - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg","datePublished":"2024-01-17T14:55:28+00:00","dateModified":"2024-01-30T15:11:39+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/Base-Logo-studio-legale-convertini-giatti.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-convertini-giatti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Studio Legale Convertini Giatti"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/53857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=53857"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/53857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/53858"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=53857"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=53857"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=53857"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=53857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}