{"id":53473,"date":"2024-01-09T11:50:17","date_gmt":"2024-01-09T10:50:17","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=53473"},"modified":"2024-02-28T11:40:28","modified_gmt":"2024-02-28T10:40:28","slug":"dott-diego-andretta-fisioterapista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/","title":{"rendered":"Dott. Diego Andretta &#8211; Fisioterapista"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"53473\" class=\"elementor elementor-53473\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3a4c0 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"4f3a4c0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6f8fce9 e-con-full e-flex e-con e-child\" data-id=\"6f8fce9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60edb6e elementor-widget elementor-widget-image\" data-id=\"60edb6e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"411\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/LOGO-GRANDE-1024x411.png\" class=\"attachment-large size-large wp-image-56190\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/LOGO-GRANDE-980x394.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/LOGO-GRANDE-480x193.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e215248 elementor-widget elementor-widget-text-editor\" data-id=\"e215248\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. Andretta Diego<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-752f44d elementor-widget elementor-widget-text-editor\" data-id=\"752f44d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FISIOTERAPIA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8207014 e-con-full e-flex e-con e-child\" data-id=\"8207014\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:56189,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/uilpolizia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/nl-febbraio-dr-diego-adretta-img1.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf6c8be elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"bf6c8be\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e87df0 elementor-widget elementor-widget-image\" data-id=\"2e87df0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"411\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/LOGO-GRANDE-1024x411.png\" class=\"attachment-large size-large wp-image-56190\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/LOGO-GRANDE-980x394.png 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/LOGO-GRANDE-480x193.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f2492 elementor-widget elementor-widget-text-editor\" data-id=\"18f2492\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dott. Andretta Diego<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19bbd5d elementor-widget elementor-widget-text-editor\" data-id=\"19bbd5d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FISIOTERAPIA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbb6a2c elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"bbb6a2c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dff7dc elementor-widget elementor-widget-image\" data-id=\"6dff7dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img1-1024x682.jpg\" class=\"attachment-large size-large wp-image-56189\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img1-1024x682.jpg 1024w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img1-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5789af e-flex e-con-boxed e-con e-parent\" data-id=\"a5789af\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c46e7b elementor-widget elementor-widget-text-editor\" data-id=\"3c46e7b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo studio<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8c726 elementor-widget elementor-widget-text-editor\" data-id=\"4b8c726\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo Studio Fisio+ \u00e8 un centro di fisioterapia specializzato in terapia manuale, riabilitazione muscoloscheletrica e fisioterapia applicata allo sport.<\/p><p><strong>Si effettuano trattamenti specialistici di:<\/strong><br \/>terapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterpia, laserterapia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-156ddad elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"156ddad\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43e2ca0 elementor-widget elementor-widget-text-editor\" data-id=\"43e2ca0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Formazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc2bfb6 elementor-widget elementor-widget-text-editor\" data-id=\"bc2bfb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il direttore del centro, il dott. Andretta Diego \u00e8 un esperto del settore laureato in Fisioterapia all\u2019Universit\u00e0 di Padova nel 2012 e in possesso di due Master Universitari, rispettivamente in:<br \/>\u2022 Fisioterapia applicata allo sport, conseguito presso l\u2019Universit\u00e0 di Siena nell\u2019anno 2013-2014;<br \/>\u2022 Terapia manuale e riabilitazione muscoloscheletrica, conseguito presso l\u2019Universit\u00e0 di Padova nell\u2019anno 2016-2017.<\/p><p>Grazie ai suoi studi gli \u00e8 stato possibile lavorare con sportivi riconosciuti a livello nazionale ed internazionale. In particolare:<br \/>\u2022 come fisioterapista della prima squadra di calcio \u201cBassano Virtus\u201d (Serie C) negli anni 2014-2016;<br \/>\u2022 come fisioterapista della Nazionale Italiana Nuoto per la squadra velocisti negli anni 2015-2018.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d3326 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"47d3326\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,21c3.3,0,8.3-0.9,15.7-7.1c6.6-5.4,4.4-9.3,2.4-10.3c-3.4-1.8-7.7,1.3-7.3,8.8C11.2,20,17.1,21,24,21&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-995857b elementor-widget elementor-widget-image\" data-id=\"995857b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img2-1024x682.jpg\" class=\"attachment-large size-large wp-image-56188\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img2-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img2-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f87ecd elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"0f87ecd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-886617e e-con-full e-flex e-con e-child\" data-id=\"886617e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8ae407 elementor-widget elementor-widget-image\" data-id=\"b8ae407\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img2-1024x682.jpg\" class=\"attachment-large size-large wp-image-56188\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img2-980x653.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/02\/nl-febbraio-dr-diego-adretta-img2-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d68aa3c e-con-full e-flex e-con e-child\" data-id=\"d68aa3c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0f6711 elementor-widget elementor-widget-text-editor\" data-id=\"e0f6711\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Formazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee913bb elementor-widget elementor-widget-text-editor\" data-id=\"ee913bb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il direttore del centro, il dott. Andretta Diego \u00e8 un esperto del settore laureato in Fisioterapia all\u2019Universit\u00e0 di Padova nel 2012 e in possesso di due Master Universitari, rispettivamente in:<br \/>\u2022 Fisioterapia applicata allo sport, conseguito presso l\u2019Universit\u00e0 di Siena nell\u2019anno 2013-2014;<br \/>\u2022 Terapia manuale e riabilitazione muscoloscheletrica, conseguito presso l\u2019Universit\u00e0 di Padova nell\u2019anno 2016-2017.<\/p><p>Grazie ai suoi studi gli \u00e8 stato possibile lavorare con sportivi riconosciuti a livello nazionale ed internazionale. In particolare:<br \/>\u2022 come fisioterapista della prima squadra di calcio \u201cBassano Virtus\u201d (Serie C) negli anni 2014-2016;<br \/>\u2022 come fisioterapista della Nazionale Italiana Nuoto per la squadra velocisti negli anni 2015-2018.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa8542 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1fa8542\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,21c3.3,0,8.3-0.9,15.7-7.1c6.6-5.4,4.4-9.3,2.4-10.3c-3.4-1.8-7.7,1.3-7.3,8.8C11.2,20,17.1,21,24,21&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3604aaf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3604aaf8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21fe2398\" data-id=\"21fe2398\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66f7f880 elementor-widget elementor-widget-text-editor\" data-id=\"66f7f880\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ab0dadf elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"ab0dadf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5988171 elementor-widget elementor-widget-text-editor\" data-id=\"5988171\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0632f elementor-widget elementor-widget-text-editor\" data-id=\"fb0632f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Indirizzo:<\/strong>\u00a0Via Casoni, 22 \u2013 35015 Galliera Veneta (PD)<br \/><strong>Telefono:<\/strong>\u00a0<a style=\"color: #333;\" href=\"tel:+393496247545\">+39 349 624 7545<\/a><br \/><strong>Mail:<\/strong>\u00a0<a style=\"color: #333;\" href=\"mailto:info@studiofisiopiu.com\">info@studiofisiopiu.com<\/a><br \/><strong>Sito web:<\/strong>\u00a0<a style=\"color: #333;\" href=\"https:\/\/www.studiofisiopiu.com\/\">www.studiofisiopiu.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c3ffa3 elementor-widget elementor-widget-button\" data-id=\"0c3ffa3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"tel:+393496247545\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRENOTA LA TUA VISITA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524a53f elementor-widget elementor-widget-text-editor\" data-id=\"524a53f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-514\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"53473\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-514\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-514\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-514\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-514\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"514\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fda1c4 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"2fda1c4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5ffb71a e-con-full e-flex e-con e-child\" data-id=\"5ffb71a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-410e1e6 elementor-widget elementor-widget-text-editor\" data-id=\"410e1e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa8d30 elementor-widget elementor-widget-text-editor\" data-id=\"9aa8d30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Indirizzo:<\/strong>\u00a0Via Casoni, 22 \u2013 35015 Galliera Veneta (PD)<br \/><strong>Telefono:<\/strong>\u00a0<a style=\"color: #333;\" href=\"tel:+393496247545\">+39 349 624 7545<\/a><br \/><strong>Mail:<\/strong>\u00a0<a style=\"color: #333;\" href=\"mailto:info@studiofisiopiu.com\">info@studiofisiopiu.com<\/a><br \/><strong>Sito web:<\/strong>\u00a0<a style=\"color: #333;\" href=\"https:\/\/www.studiofisiopiu.com\/\">www.studiofisiopiu.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-567be51 elementor-widget elementor-widget-button\" data-id=\"567be51\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"tel:+393496247545\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRENOTA LA TUA VISITA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-591e012 e-con-full e-flex e-con e-child\" data-id=\"591e012\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-255f525 elementor-widget elementor-widget-text-editor\" data-id=\"255f525\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"gmw-single-location-wrapper-180\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"53473\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-180\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-180\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-180\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-180\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"180\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Lo Studio Fisio+ \u00e8 un centro di fisioterapia specializzato in terapia manuale, riabilitazione muscoloscheletrica e fisioterapia applicata allo sport.Si effettuano trattamenti specialistici di:<br \/>\nterapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterpia, laserterapia.Il direttore del centro, il dott. Andretta Diego \u00e8 un esperto del settore laureato in Fisioterapia all\u2019Universit\u00e0 di Padova nel 2012 e in possesso di due Master Universitari, rispettivamente in:<br \/>\n\u2022 Fisioterapia applicata allo sport, conseguito presso l\u2019Universit\u00e0 di Siena nell\u2019anno 2013-2014;<br \/>\n\u2022 Terapia manuale e riabilitazione muscoloscheletrica, conseguito presso l\u2019Universit\u00e0 di Padova nell\u2019anno 2016-2017.Grazie ai suoi studi gli \u00e8 stato possibile lavorare con sportivi riconosciuti a livello nazionale ed internazionale. In particolare:<br \/>\n\u2022 come fisioterapista della prima squadra di calcio \u201cBassano Virtus\u201d (Serie C) negli anni 2014-2016;<br \/>\n\u2022 come fisioterapista della Nazionale Italiana Nuoto per la squadra velocisti negli anni 2015-2018.terapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterapia, laserterapia, centro di fisioterapia, centri di fisioterapia, fisioterapista, fisioterapisti<\/p>\n<p>terapia manuale a Galliera Veneta, manipolazione fasciale a Galliera Veneta, rieducazione sport-specifica a Galliera Veneta, riabilitazione post traumatica e chirurgica a Galliera Veneta, terapia del dolore a Galliera Veneta, rieducazione funzionale a Galliera Veneta, rieducazione posturale a Galliera Veneta, bendaggio funzionale a Galliera Veneta, kinesiotaping a Galliera Veneta, linfodrenaggio a Galliera Veneta, tecarterapia a Galliera Veneta, laserterapia a Galliera Veneta, centro di fisioterapia a Galliera Veneta, centri di fisioterapia a Galliera Veneta, fisioterapista a Galliera Veneta, fisioterapisti a Galliera Veneta<\/p>\n<p>terapia manuale Galliera Veneta, manipolazione fasciale Galliera Veneta, rieducazione sport-specifica Galliera Veneta, riabilitazione post traumatica e chirurgica Galliera Veneta, terapia del dolore Galliera Veneta, rieducazione funzionale Galliera Veneta, rieducazione posturale Galliera Veneta, bendaggio funzionale Galliera Veneta, kinesiotaping Galliera Veneta, linfodrenaggio Galliera Veneta, tecarterapia Galliera Veneta, laserterapia Galliera Veneta, centro di fisioterapia Galliera Veneta, centri di fisioterapia Galliera Veneta, fisioterapista Galliera Veneta, fisioterapisti Galliera Veneta<\/p>\n<\/div>\n","protected":false},"featured_media":55782,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,163],"product_tag":[3046,11345,3335,365,448,3045,610,2320,1776,11344,4130,608,11343,2418,1509,1551],"class_list":{"0":"post-53473","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-salute","8":"product_tag-bendaggio-funzionale","9":"product_tag-centri-di-fisioterapia","10":"product_tag-centro-di-fisioterapia","11":"product_tag-fisioterapista","12":"product_tag-fisioterapisti","13":"product_tag-kinesiotaping","14":"product_tag-laserterapia","15":"product_tag-linfodrenaggio","16":"product_tag-manipolazione-fasciale","17":"product_tag-riabilitazione-post-traumatica-e-chirurgica","18":"product_tag-rieducazione-funzionale","19":"product_tag-rieducazione-posturale","20":"product_tag-rieducazione-sport-specifica","21":"product_tag-tecarterapia","22":"product_tag-terapia-del-dolore","23":"product_tag-terapia-manuale","25":"first","26":"instock","27":"shipping-taxable","28":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Diego Andretta - Fisioterapista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Diego Andretta - Fisioterapista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Lo Studio Fisio+ \u00e8 un centro di fisioterapia specializzato in terapia manuale, riabilitazione muscoloscheletrica e fisioterapia applicata allo sport.Si effettuano trattamenti specialistici di: terapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterpia, laserterapia.Il direttore del centro, il dott. Andretta Diego \u00e8 un esperto del settore laureato in Fisioterapia all\u2019Universit\u00e0 di Padova nel 2012 e in possesso di due Master Universitari, rispettivamente in: \u2022 Fisioterapia applicata allo sport, conseguito presso l\u2019Universit\u00e0 di Siena nell\u2019anno 2013-2014; \u2022 Terapia manuale e riabilitazione muscoloscheletrica, conseguito presso l\u2019Universit\u00e0 di Padova nell\u2019anno 2016-2017.Grazie ai suoi studi gli \u00e8 stato possibile lavorare con sportivi riconosciuti a livello nazionale ed internazionale. In particolare: \u2022 come fisioterapista della prima squadra di calcio \u201cBassano Virtus\u201d (Serie C) negli anni 2014-2016; \u2022 come fisioterapista della Nazionale Italiana Nuoto per la squadra velocisti negli anni 2015-2018.terapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterapia, laserterapia, centro di fisioterapia, centri di fisioterapia, fisioterapista, fisioterapisti  terapia manuale a Galliera Veneta, manipolazione fasciale a Galliera Veneta, rieducazione sport-specifica a Galliera Veneta, riabilitazione post traumatica e chirurgica a Galliera Veneta, terapia del dolore a Galliera Veneta, rieducazione funzionale a Galliera Veneta, rieducazione posturale a Galliera Veneta, bendaggio funzionale a Galliera Veneta, kinesiotaping a Galliera Veneta, linfodrenaggio a Galliera Veneta, tecarterapia a Galliera Veneta, laserterapia a Galliera Veneta, centro di fisioterapia a Galliera Veneta, centri di fisioterapia a Galliera Veneta, fisioterapista a Galliera Veneta, fisioterapisti a Galliera Veneta  terapia manuale Galliera Veneta, manipolazione fasciale Galliera Veneta, rieducazione sport-specifica Galliera Veneta, riabilitazione post traumatica e chirurgica Galliera Veneta, terapia del dolore Galliera Veneta, rieducazione funzionale Galliera Veneta, rieducazione posturale Galliera Veneta, bendaggio funzionale Galliera Veneta, kinesiotaping Galliera Veneta, linfodrenaggio Galliera Veneta, tecarterapia Galliera Veneta, laserterapia Galliera Veneta, centro di fisioterapia Galliera Veneta, centri di fisioterapia Galliera Veneta, fisioterapista Galliera Veneta, fisioterapisti Galliera Veneta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T10:40:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/\",\"name\":\"Dott. Diego Andretta - Fisioterapista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg\",\"datePublished\":\"2024-01-09T10:50:17+00:00\",\"dateModified\":\"2024-02-28T10:40:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Diego Andretta &#8211; Fisioterapista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Diego Andretta - Fisioterapista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Diego Andretta - Fisioterapista - UIL Polizia","og_description":"Lo Studio Fisio+ \u00e8 un centro di fisioterapia specializzato in terapia manuale, riabilitazione muscoloscheletrica e fisioterapia applicata allo sport.Si effettuano trattamenti specialistici di: terapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterpia, laserterapia.Il direttore del centro, il dott. Andretta Diego \u00e8 un esperto del settore laureato in Fisioterapia all\u2019Universit\u00e0 di Padova nel 2012 e in possesso di due Master Universitari, rispettivamente in: \u2022 Fisioterapia applicata allo sport, conseguito presso l\u2019Universit\u00e0 di Siena nell\u2019anno 2013-2014; \u2022 Terapia manuale e riabilitazione muscoloscheletrica, conseguito presso l\u2019Universit\u00e0 di Padova nell\u2019anno 2016-2017.Grazie ai suoi studi gli \u00e8 stato possibile lavorare con sportivi riconosciuti a livello nazionale ed internazionale. In particolare: \u2022 come fisioterapista della prima squadra di calcio \u201cBassano Virtus\u201d (Serie C) negli anni 2014-2016; \u2022 come fisioterapista della Nazionale Italiana Nuoto per la squadra velocisti negli anni 2015-2018.terapia manuale, manipolazione fasciale, rieducazione sport-specifica, riabilitazione post traumatica e chirurgica, terapia del dolore, rieducazione funzionale, rieducazione posturale, bendaggio funzionale, kinesiotaping, linfodrenaggio, tecarterapia, laserterapia, centro di fisioterapia, centri di fisioterapia, fisioterapista, fisioterapisti  terapia manuale a Galliera Veneta, manipolazione fasciale a Galliera Veneta, rieducazione sport-specifica a Galliera Veneta, riabilitazione post traumatica e chirurgica a Galliera Veneta, terapia del dolore a Galliera Veneta, rieducazione funzionale a Galliera Veneta, rieducazione posturale a Galliera Veneta, bendaggio funzionale a Galliera Veneta, kinesiotaping a Galliera Veneta, linfodrenaggio a Galliera Veneta, tecarterapia a Galliera Veneta, laserterapia a Galliera Veneta, centro di fisioterapia a Galliera Veneta, centri di fisioterapia a Galliera Veneta, fisioterapista a Galliera Veneta, fisioterapisti a Galliera Veneta  terapia manuale Galliera Veneta, manipolazione fasciale Galliera Veneta, rieducazione sport-specifica Galliera Veneta, riabilitazione post traumatica e chirurgica Galliera Veneta, terapia del dolore Galliera Veneta, rieducazione funzionale Galliera Veneta, rieducazione posturale Galliera Veneta, bendaggio funzionale Galliera Veneta, kinesiotaping Galliera Veneta, linfodrenaggio Galliera Veneta, tecarterapia Galliera Veneta, laserterapia Galliera Veneta, centro di fisioterapia Galliera Veneta, centri di fisioterapia Galliera Veneta, fisioterapista Galliera Veneta, fisioterapisti Galliera Veneta","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/","og_site_name":"UIL Polizia","article_modified_time":"2024-02-28T10:40:28+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/","name":"Dott. Diego Andretta - Fisioterapista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg","datePublished":"2024-01-09T10:50:17+00:00","dateModified":"2024-02-28T10:40:28+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2024\/01\/logo_siti-Diego-Andretta-Fisio.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-diego-andretta-fisioterapista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Diego Andretta &#8211; Fisioterapista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/53473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=53473"}],"version-history":[{"count":27,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/53473\/revisions"}],"predecessor-version":[{"id":56223,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/53473\/revisions\/56223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/55782"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=53473"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=53473"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=53473"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=53473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}