{"id":52931,"date":"2023-12-20T12:21:17","date_gmt":"2023-12-20T11:21:17","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=52931"},"modified":"2023-12-20T12:21:24","modified_gmt":"2023-12-20T11:21:24","slug":"lalbero-degli-occhiali","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/","title":{"rendered":"L&#8217;albero degli occhiali"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#ffffff 12%|rgba(255,255,255,0) 61%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/albero-degli-occhiali-6.jpg&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;center_right&#8221; custom_padding=&#8221;11vw||11vw||true|false&#8221; custom_padding_tablet=&#8221;6vw||6vw||true|false&#8221; custom_padding_phone=&#8221;8vw||8vw||true|false&#8221; background_last_edited=&#8221;on|tablet&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; use_background_color_gradient_phone=&#8221;on&#8221; background_color_gradient_stops_tablet=&#8221;#ffffff 39%|rgba(255,255,255,0) 68%&#8221; background_color_gradient_stops_phone=&#8221;#ffffff 37%|rgba(255,255,255,0.3) 100%&#8221; background_size_tablet=&#8221;contain&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1920px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/logo-1-1.png&#8221; title_text=&#8221;logo (1)&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;35%&#8221; width_tablet=&#8221;60%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;4vw||4vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1400px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; ul_text_align=&#8221;left&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#128e83&#8243; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; hover_enabled=&#8221;0&#8243; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Chi siamo<\/h1>\n<p>Il negozio, situato in Corso Belgio 60 a Torino, si occupa di misurazione della vista, vendita occhiali da vista e da sole, centratura lenti progressive computerizzata per una massima precisione e personalizzazione dell\u2019occhiale, ampia scelta di brand e montature tra cui scegliere per ogni stile.<\/p>\n<p>Applicazioni lenti a contatto, controllo con lampada a fessura e topografo.<\/p>\n<p>Offriamo anche allenamento viso-posturale con il jet program.<\/p>\n<p>&nbsp;<\/p>\n<h1>Servizi<\/h1>\n<ul>\n<li>esame della vista<\/li>\n<li>servizi post vendita (riassetto occhiali, sostituzione naselli, pulizia ultrasuoni)<\/li>\n<li>visual training (allenamento con jet program)<\/li>\n<li>applicazione lenti a contatto<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card_carousel slide_to_show=&#8221;1&#8243; arrows=&#8221;off&#8221; dots_horizontal_placement=&#8221;-50px&#8221; dots_active_color=&#8221;#f6931d&#8221; dots_inactive_color=&#8221;#ffeace&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/albero-degli-occhiali-5-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/albero-degli-occhiali-1-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/albero-degli-occhiali-2-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/albero-degli-occhiali-3-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_card_carousel_child][\/dsm_card_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.21.0&#8243; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0.7) 0%|rgba(0,0,0,0.7) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;#e7f3fd&#8221; background_color_gradient_end=&#8221;#89c5f5&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/albero-degli-occhiali-4.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;4vw||4vw||true|false&#8221; custom_padding_tablet=&#8221;||||false|false&#8221; custom_padding_phone=&#8221;||||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;34px&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; link_text_color=&#8221;#f6931d&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#128e83&#8243; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#128e83&#8243;]<\/p>\n<h1>Contatti<\/h1>\n<p>Corso Belgio, 60\/D &#8211; 10153 Torino<br \/><strong>Tel: <\/strong>011 19712525<br \/><strong>Cell:<\/strong> 347 4175886<br \/><strong>Mail: <\/strong><a href=\"mailto:info@lalberodegliocchiali.com\">info@lalberodegliocchiali.com<\/a><br \/><strong>Sito web:<\/strong> <a href=\"https:\/\/lalberodegliocchiali.com\/\">lalberodegliocchiali.com<\/a><br \/><b>Lun e Sab: <\/b>09:30 &#8211; 13:00<br \/><b>Mar &#8211; Ven: <\/b>09:30 &#8211; 13:00 \/ 15:30 &#8211; 19:30<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-315\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"52931\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-315\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-315\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-315\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-315\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"315\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e7f3fd&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Corso Belgio 60\/D, 10153 Torino TO <br>\n<strong>Telefono:<\/strong> 347 4175886 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/lalberodegliocchiali.com\">lalberodegliocchiali.com<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:info@lalberodegliocchiali.com\">info@lalberodegliocchiali.com<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-357\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"52931\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-357\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-357\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-357\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-357\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"357\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-486\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-486\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-486\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-486\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-486\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"486\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>esame della vista<br \/>\nservizi post vendita (riassetto occhiali, sostituzione naselli, pulizia ultrasuoni)<br \/>\nvisual training (allenamento con jet program)<br \/>\napplicazione lenti a contatto<\/p>\n<p>Il negozio, situato in corso Belgio 60 a Torino, si occupa di misurazione della vista, vendita occhiali da vista e da sole, centratura lenti progressive computerizzata per una massima precisione e personalizzazione dell\u2019occhiale, ampia scelta di brand e montature tra cui scegliere per ogni stile.<br \/>\nApplicazioni lenti a contatto, controllo con lampada a fessura e topografo.<br \/>\nOffriamo anche allenamento viso-posturale con il jet program<\/p>\n<p>esame della vista, riassetto occhiali, sostituzione naselli, pulizia ultrasuoni, visual training, applicazione lenti a contatto, esame vista, applicazione di lenti a contatto, misurazione della vista, vendita occhiali da vista, vendita occhiali da sole, lenti progressive, allenamento viso-posturale, controllo della vista, ottico, ottici, ottica, <\/p>\n<p>esame della vista a Torino, riassetto occhiali a Torino, sostituzione naselli a Torino, pulizia ultrasuoni a Torino, visual training a Torino, applicazione lenti a contatto a Torino, esame vista a Torino, applicazione di lenti a contatto a Torino, misurazione della vista a Torino, vendita occhiali da vista a Torino, vendita occhiali da sole a Torino, lenti progressive a Torino, allenamento viso-posturale a Torino, controllo della vista a Torino, ottico a Torino, ottici a Torino, ottica a Torino, <\/p>\n<\/div>\n","protected":false},"featured_media":52940,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[245,163],"product_tag":[9935,9948,7431,9943,2923,9941,5126,9949,5037,9936,9934,9942,7204,9947,4801,9944,359,9952,358,9951,775,9950,9933,9939,9931,9937,9932,9938,5128,9946,5129,9945,5905,9940],"class_list":{"0":"post-52931","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ottici","7":"product_cat-salute","8":"product_tag-allenamento-viso-posturale","9":"product_tag-allenamento-viso-posturale-a-torino","10":"product_tag-applicazione-di-lenti-a-contatto","11":"product_tag-applicazione-di-lenti-a-contatto-a-torino","12":"product_tag-applicazione-lenti-a-contatto","13":"product_tag-applicazione-lenti-a-contatto-a-torino","14":"product_tag-controllo-della-vista","15":"product_tag-controllo-della-vista-a-torino","16":"product_tag-esame-della-vista","17":"product_tag-esame-della-vista-a-torino","18":"product_tag-esame-vista","19":"product_tag-esame-vista-a-torino","20":"product_tag-lenti-progressive","21":"product_tag-lenti-progressive-a-torino","22":"product_tag-misurazione-della-vista","23":"product_tag-misurazione-della-vista-a-torino","24":"product_tag-ottica","25":"product_tag-ottica-a-torino","26":"product_tag-ottici","27":"product_tag-ottici-a-torino","28":"product_tag-ottico","29":"product_tag-ottico-a-torino","30":"product_tag-pulizia-ultrasuoni","31":"product_tag-pulizia-ultrasuoni-a-torino","32":"product_tag-riassetto-occhiali","33":"product_tag-riassetto-occhiali-a-torino","34":"product_tag-sostituzione-naselli","35":"product_tag-sostituzione-naselli-a-torino","36":"product_tag-vendita-occhiali-da-sole","37":"product_tag-vendita-occhiali-da-sole-a-torino","38":"product_tag-vendita-occhiali-da-vista","39":"product_tag-vendita-occhiali-da-vista-a-torino","40":"product_tag-visual-training","41":"product_tag-visual-training-a-torino","43":"first","44":"instock","45":"shipping-taxable","46":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;albero degli occhiali - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;albero degli occhiali - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"esame della vista servizi post vendita (riassetto occhiali, sostituzione naselli, pulizia ultrasuoni) visual training (allenamento con jet program) applicazione lenti a contatto   Il negozio, situato in corso Belgio 60 a Torino, si occupa di misurazione della vista, vendita occhiali da vista e da sole, centratura lenti progressive computerizzata per una massima precisione e personalizzazione dell\u2019occhiale, ampia scelta di brand e montature tra cui scegliere per ogni stile. Applicazioni lenti a contatto, controllo con lampada a fessura e topografo. Offriamo anche allenamento viso-posturale con il jet program    esame della vista, riassetto occhiali, sostituzione naselli, pulizia ultrasuoni, visual training, applicazione lenti a contatto, esame vista, applicazione di lenti a contatto, misurazione della vista, vendita occhiali da vista, vendita occhiali da sole, lenti progressive, allenamento viso-posturale, controllo della vista, ottico, ottici, ottica,    esame della vista a Torino, riassetto occhiali a Torino, sostituzione naselli a Torino, pulizia ultrasuoni a Torino, visual training a Torino, applicazione lenti a contatto a Torino, esame vista a Torino, applicazione di lenti a contatto a Torino, misurazione della vista a Torino, vendita occhiali da vista a Torino, vendita occhiali da sole a Torino, lenti progressive a Torino, allenamento viso-posturale a Torino, controllo della vista a Torino, ottico a Torino, ottici a Torino, ottica a Torino,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T11:21:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/\",\"name\":\"L'albero degli occhiali - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg\",\"datePublished\":\"2023-12-20T11:21:17+00:00\",\"dateModified\":\"2023-12-20T11:21:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;albero degli occhiali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'albero degli occhiali - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/","og_locale":"it_IT","og_type":"article","og_title":"L'albero degli occhiali - UIL Polizia","og_description":"esame della vista servizi post vendita (riassetto occhiali, sostituzione naselli, pulizia ultrasuoni) visual training (allenamento con jet program) applicazione lenti a contatto   Il negozio, situato in corso Belgio 60 a Torino, si occupa di misurazione della vista, vendita occhiali da vista e da sole, centratura lenti progressive computerizzata per una massima precisione e personalizzazione dell\u2019occhiale, ampia scelta di brand e montature tra cui scegliere per ogni stile. Applicazioni lenti a contatto, controllo con lampada a fessura e topografo. Offriamo anche allenamento viso-posturale con il jet program    esame della vista, riassetto occhiali, sostituzione naselli, pulizia ultrasuoni, visual training, applicazione lenti a contatto, esame vista, applicazione di lenti a contatto, misurazione della vista, vendita occhiali da vista, vendita occhiali da sole, lenti progressive, allenamento viso-posturale, controllo della vista, ottico, ottici, ottica,    esame della vista a Torino, riassetto occhiali a Torino, sostituzione naselli a Torino, pulizia ultrasuoni a Torino, visual training a Torino, applicazione lenti a contatto a Torino, esame vista a Torino, applicazione di lenti a contatto a Torino, misurazione della vista a Torino, vendita occhiali da vista a Torino, vendita occhiali da sole a Torino, lenti progressive a Torino, allenamento viso-posturale a Torino, controllo della vista a Torino, ottico a Torino, ottici a Torino, ottica a Torino,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/","og_site_name":"UIL Polizia","article_modified_time":"2023-12-20T11:21:24+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/","name":"L'albero degli occhiali - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg","datePublished":"2023-12-20T11:21:17+00:00","dateModified":"2023-12-20T11:21:24+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo_Lalbero-degli-occhiali.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/lalbero-degli-occhiali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"L&#8217;albero degli occhiali"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/52931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=52931"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/52931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/52940"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=52931"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=52931"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=52931"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=52931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}