{"id":52581,"date":"2023-12-15T12:16:41","date_gmt":"2023-12-15T11:16:41","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=52581"},"modified":"2023-12-15T16:40:16","modified_gmt":"2023-12-15T15:40:16","slug":"travelsingle-viaggi-e-vacanze-per-single","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/","title":{"rendered":"Travelsingle &#8211; Viaggi e Vacanze per Single"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; make_equal=&#8221;on&#8221; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; specialty=&#8221;on&#8221; background_color_2=&#8221;#ffffff&#8221; bg_img_1=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/367699717_10226999734291145_7230344548954672776_n.jpg&#8221; background_position_1=&#8221;center&#8221; background_vertical_offset_1=&#8221;50%&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.21.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#0974a4 50%|#ffffff 50%&#8221; background_color_gradient_start=&#8221;#002d4c&#8221; background_color_gradient_start_position=&#8221;50%&#8221; background_color_gradient_end=&#8221;#ffffff&#8221; background_color_gradient_end_position=&#8221;0%&#8221; inner_width=&#8221;90%&#8221; inner_max_width=&#8221;none&#8221; inner_module_alignment=&#8221;right&#8221; custom_padding=&#8221;0px||0px|||&#8221; background_last_edited=&#8221;on|tablet&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; background_color_gradient_stops_tablet=&#8221;#0974a4 100%|#ffffff 100%&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.21.0&#8243; height=&#8221;0px&#8221; height_tablet=&#8221;45vw&#8221; height_phone=&#8221;50vw&#8221; height_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; background_enable_image=&#8221;off&#8221; z_index=&#8221;10&#8243; custom_padding=&#8221;|60px|8vw|60px|false|true&#8221; custom_padding_tablet=&#8221;|40px|8vw|40px|false|true&#8221; custom_padding_phone=&#8221;|20px||20px|false|true&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;32px&#8221; box_shadow_blur=&#8221;48px&#8221; box_shadow_spread=&#8221;-32px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.16)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Nome Attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Cabin||||||||&#8221; text_text_color=&#8221;rgba(85,101,112,0.8)&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_color=&#8221;#0974a4&#8243; header_font_size=&#8221;115px&#8221; header_2_font=&#8221;Raleway|||on|||||&#8221; header_2_font_size=&#8221;50px&#8221; header_3_font=&#8221;Cabin|700||on|||||&#8221; header_3_text_color=&#8221;#bd8f52&#8243; header_3_font_size=&#8221;13px&#8221; header_3_letter_spacing=&#8221;3px&#8221; header_3_line_height=&#8221;1.4em&#8221; max_width=&#8221;36vw&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;||25px||false|false&#8221; header_text_align_tablet=&#8221;&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;85px&#8221; header_font_size_phone=&#8221;85px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Travel<span style=\"color: #ec841e;\">single<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Viaggi e Vacanze per Single<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>Viaggi e Vacanze<br \/>\nper Single<\/h2>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Nome Attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Cabin||||||||&#8221; text_text_color=&#8221;rgba(85,101,112,0.8)&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_color=&#8221;#002d4c&#8221; header_font_size=&#8221;115px&#8221; header_2_font=&#8221;Raleway|||on|||||&#8221; header_2_font_size=&#8221;50px&#8221; header_3_font=&#8221;Cabin|700||on|||||&#8221; header_3_text_color=&#8221;#bd8f52&#8243; header_3_font_size=&#8221;13px&#8221; header_3_letter_spacing=&#8221;3px&#8221; header_3_line_height=&#8221;1.4em&#8221; max_width=&#8221;36vw&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;||2vw||false|false&#8221; header_2_text_align_tablet=&#8221;&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_2_line_height_tablet=&#8221;&#8221; header_2_line_height_phone=&#8221;1.2em&#8221; header_2_line_height_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Viaggi e Vacanze per Single<\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;rgba(85,101,112,0.08)&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;40px|20px|40px|20px|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;20px||20px||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Cabin|600|||||||&#8221; text_text_color=&#8221;#002d4c&#8221; header_4_font=&#8221;Cabin|700||on|||||&#8221; header_4_text_color=&#8221;#77848d&#8221; header_4_font_size=&#8221;12px&#8221; header_4_letter_spacing=&#8221;1px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px|||||&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;|||22%|false|false&#8221; custom_margin_tablet=&#8221;|||11%|false|false&#8221; custom_margin_phone=&#8221;|||11%|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;100px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Cabin||||||||&#8221; text_text_color=&#8221;rgba(85,101,112,0.8)&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_color=&#8221;#ec841e&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.1em&#8221; header_3_font=&#8221;Cabin|700||on|||||&#8221; header_3_text_color=&#8221;#bd8f52&#8243; header_3_font_size=&#8221;13px&#8221; header_3_letter_spacing=&#8221;3px&#8221; header_3_line_height=&#8221;1.4em&#8221; max_width=&#8221;36vw&#8221; max_width_tablet=&#8221;90%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;44px&#8221; header_2_font_size_phone=&#8221;32px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>\/\/ Chi siamo<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome Attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Raleway||||||||&#8221; text_text_color=&#8221;rgba(85,101,112,0.8)&#8221; text_font_size=&#8221;17px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_color=&#8221;#002d4c&#8221; header_font_size=&#8221;115px&#8221; header_2_font=&#8221;Raleway|||on|||||&#8221; header_2_font_size=&#8221;50px&#8221; header_3_font=&#8221;Cabin|700||on|||||&#8221; header_3_text_color=&#8221;#bd8f52&#8243; header_3_font_size=&#8221;13px&#8221; header_3_letter_spacing=&#8221;3px&#8221; header_3_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;justified&#8221; max_width=&#8221;36vw&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;||2vw||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Travelsingle \u00e8 un operatore Leader nel settore di<b>\u00a0weekend e viaggi per single<\/b>, per chi viaggia da solo e vuole scoprire nuove destinazioni facendo nuove amicizie da tutta Italia condividendo ricordi ed emozioni in allegria e spensieratezza.<br \/>Il nostro compito sar\u00e0 quello di creare<b>\u00a0occasioni di aggregazione\u00a0<\/b>divertendosi insieme, seguiti dai\u00a0<b>nostri accompagnatori<\/b>\u00a0che si prenderanno cura di voi durante tutto il viaggio assumendosi il compito di risolvere ogni eventuale problema ed assicurare il rilassamento e divertimento dei partecipanti.<\/p>\n<p>E\u2019 stato ideato da uno\u00a0<b>staff di persone<\/b>\u00a0con<b>\u00a0anni di esperienza<\/b>\u00a0nel settore dei viaggi e\u00a0<b>weekend per single<\/b>\u00a0ve che si avvale della collaborazione dei migliori\u00a0<b>Tour Operator<\/b>\u00a0nazionali ed internazionali, strutture selezionate e provati accompagnatori per garantire ai clienti una vacanza in pieno relax ad un\u00a0<b>costo accessibile a tutti.<\/b><\/p>\n<p>L\u2019Agenzia Travelsingle si impegna al massimo nella\u00a0<b>formazione di gruppi omogenei fra uomini e donne<\/b>\u00a0(non garantito nella fascia over 50) che varieranno ad ogni nuovo viaggio, facendo sconti e promozioni in base all\u2019andamento delle prenotazioni, cosi come cureremo le diverse\u00a0<b>fasce d\u2019et\u00e0<\/b>\u00a0per creare gruppi omogenei e compatibili anagraficamente (normalmente\u00a0<b>fascia 30\/50, over 50 o fascia mista<\/b>).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/369467392_10231417092278655_2006182239857269711_n.jpg&#8221; title_text=&#8221;369467392_10231417092278655_2006182239857269711_n&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;|-10vw|||false|false&#8221; custom_margin_tablet=&#8221;|0vw|||false|false&#8221; custom_margin_phone=&#8221;|0vw|||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;80px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-60px&#8221; box_shadow_color=&#8221;rgba(0,45,76,0.32)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|||22%|false|false&#8221; custom_margin_tablet=&#8221;|||11%|false|false&#8221; custom_margin_phone=&#8221;|||11%|false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/372894650_608045871411809_1077461117497744797_n.jpg&#8221; title_text=&#8221;372894650_608045871411809_1077461117497744797_n&#8221; _builder_version=&#8221;4.21.0&#8243; custom_margin=&#8221;||||false|false&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-40px&#8221; box_shadow_vertical=&#8221;80px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-32px&#8221; box_shadow_color=&#8221;rgba(0,45,76,0.32)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Nome Attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Raleway||||||||&#8221; text_text_color=&#8221;rgba(85,101,112,0.8)&#8221; text_font_size=&#8221;17px&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#ec841e&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_color=&#8221;#002d4c&#8221; header_font_size=&#8221;115px&#8221; header_2_font=&#8221;Raleway|||on|||||&#8221; header_2_font_size=&#8221;50px&#8221; header_3_font=&#8221;Cabin|700||on|||||&#8221; header_3_text_color=&#8221;#bd8f52&#8243; header_3_font_size=&#8221;13px&#8221; header_3_letter_spacing=&#8221;3px&#8221; header_3_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;justified&#8221; max_width=&#8221;36vw&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;|-10vw|2vw||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Chi non vorr\u00e0 pagare il supplemento singola potr\u00e0 condividere la camera con un altro partecipante oppure in alcuni casi potr\u00e0 trovare offerte in\u00a0<b>singola gratuita<\/b>, in genere soggette a disponibilit\u00e0.<\/p>\n<p>Travelsingle ti offrir\u00e0 un\u2019altra valida alternativa per chi ha gi\u00e0 provato i<b>\u00a0viaggi per single<\/b>\u00a0attraverso altre realt\u00e0 del settore, trovando la<b>\u00a0stessa esperienza<\/b>, cortesia ed efficienza a prezzi contenuti a<b>\u00a0parit\u00e0 di qualit\u00e0 e servizi<\/b>.<\/p>\n<p>Le strutture prescelte per i nostri<b>\u00a0weekend e vacanze per single<\/b>\u00a0sono sempre accuratamente selezionate tramite un primo screening su\u00a0<b>Tripadvisor\u00a0<\/b>a cui seguono sopralluoghi sul posto per assicurare al cliente servizi all\u2019altezza delle aspettative.<\/p>\n<p>Per ogni altra domanda puoi chiamare il nostro<b>\u00a0call-center<\/b>\u00a0disponile tutti i giorni o inviaci un email a <a href=\"mailto:info@travelsingle.it\">info@travelsingle.it<\/a>, ti risponderemo al pi\u00f9 presto!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(85,101,112,0.08)&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][dsm_masonry_gallery _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; gallery_ids=&#8221;52593,52604,52602,52601,52592,52599,52598,52600,52597,52595,52596,52594&#8243; columns=&#8221;4&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/dsm_masonry_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ec841e&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|800||on|||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;35px&#8221; text_letter_spacing=&#8221;2px&#8221; text_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Agevolazioni riservate agli associati<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Dove siamo&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf3c5;||fa||900&#8243; icon_color=&#8221;#0974a4&#8243; image_icon_width=&#8221;45px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;23px&#8221; body_font=&#8221;Raleway||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#77838d&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.9em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Via del Fontanile Arenato, 147<br \/>00163 Roma<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Telefono&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_color=&#8221;#0974a4&#8243; image_icon_width=&#8221;45px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;23px&#8221; body_font=&#8221;Raleway||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#77838d&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.9em&#8221; global_colors_info=&#8221;{}&#8221;]06 92593048[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Mail&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf0e0;||fa||900&#8243; icon_color=&#8221;#0974a4&#8243; image_icon_width=&#8221;45px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;23px&#8221; body_font=&#8221;Raleway||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#77838d&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.9em&#8221; body_link_text_color=&#8221;#77838d&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"mailto:info@%20travelsingle.it\">info@ travelsingle.it<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|800||on|||||&#8221; text_text_color=&#8221;#0974a4&#8243; text_font_size=&#8221;30px&#8221; text_letter_spacing=&#8221;2px&#8221; text_line_height=&#8221;1.4em&#8221; link_text_color=&#8221;#ec841e&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;30px&#8221; text_font_size_phone=&#8221;25px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_letter_spacing_tablet=&#8221;2px&#8221; text_letter_spacing_phone=&#8221;0px&#8221; text_letter_spacing_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Visita il nostro sito <a href=\"http:\/\/www.travelsingle.it\/\">www.travelsingle.it<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_code admin_label=&#8221;Mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-487\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"52581\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-487\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:500px;\"> <span id=\"gmw-resize-map-toggle-487\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-487\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-487\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"487\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_fullwidth_code][et_pb_fullwidth_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-140\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-140\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-140\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-140\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-140\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"140\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_fullwidth_code][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Travelsingle \u00e8 un operatore Leader nel settore di<b>\u00a0weekend e viaggi per single<\/b>, per chi viaggia da solo e vuole scoprire nuove destinazioni facendo nuove amicizie da tutta Italia condividendo ricordi ed emozioni in allegria e spensieratezza.<br \/>\nIl nostro compito sar\u00e0 quello di creare<b>\u00a0occasioni di aggregazione\u00a0<\/b>divertendosi insieme, seguiti dai\u00a0<b>nostri accompagnatori<\/b>\u00a0che si prenderanno cura di voi durante tutto il viaggio assumendosi il compito di risolvere ogni eventuale problema ed assicurare il rilassamento e divertimento dei partecipanti.<\/p>\n<p>E\u2019 stato ideato da uno\u00a0<b>staff di persone<\/b>\u00a0con<b>\u00a0anni di esperienza<\/b>\u00a0nel settore dei viaggi e\u00a0<b>weekend per single<\/b>\u00a0ve che si avvale della collaborazione dei migliori\u00a0<b>Tour Operator<\/b>\u00a0nazionali ed internazionali, strutture selezionate e provati accompagnatori per garantire ai clienti una vacanza in pieno relax ad un\u00a0<b>costo accessibile a tutti.<\/b><\/p>\n<p>L\u2019Agenzia Travelsingle si impegna al massimo nella\u00a0<b>formazione di gruppi omogenei fra uomini e donne<\/b>\u00a0(non garantito nella fascia over 50) che varieranno ad ogni nuovo viaggio, facendo sconti e promozioni in base all\u2019andamento delle prenotazioni, cosi come cureremo le diverse\u00a0<b>fasce d\u2019et\u00e0<\/b>\u00a0per creare gruppi omogenei e compatibili anagraficamente (normalmente\u00a0<b>fascia 30\/50, over 50 o fascia mista<\/b>).<\/p>\n<p>Chi non vorr\u00e0 pagare il supplemento singola potr\u00e0 condividere la camera con un altro partecipante oppure in alcuni casi potr\u00e0 trovare offerte in\u00a0<b>singola gratuita<\/b>, in genere soggette a disponibilit\u00e0.<\/p>\n<p>Travelsingle ti offrir\u00e0 un\u2019altra valida alternativa per chi ha gi\u00e0 provato i<b>\u00a0viaggi per single<\/b>\u00a0attraverso altre realt\u00e0 del settore, trovando la<b>\u00a0stessa esperienza<\/b>, cortesia ed efficienza a prezzi contenuti a<b>\u00a0parit\u00e0 di qualit\u00e0 e servizi<\/b>.<\/p>\n<p>Le strutture prescelte per i nostri<b>\u00a0weekend e vacanze per single<\/b>\u00a0sono sempre accuratamente selezionate tramite un primo screening su\u00a0<b>Tripadvisor\u00a0<\/b>a cui seguono sopralluoghi sul posto per assicurare al cliente servizi all\u2019altezza delle aspettative.<\/p>\n<p>Per ogni altra domanda puoi chiamare il nostro<b>\u00a0call-center<\/b>\u00a0disponile tutti i giorni o inviaci un email a info@travelsingle.it, ti risponderemo al pi\u00f9 presto!<\/p>\n","protected":false},"featured_media":52583,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[331,2325,330],"product_tag":[665,2761,9697,8745,1602,9702,9699,418,9701,2324,9698,2204,9700],"class_list":{"0":"post-52581","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agenzie-di-viaggi","7":"product_cat-tour-operator","8":"product_cat-turismo-e-viaggi","9":"product_tag-agenzia-di-viaggi","10":"product_tag-agenzia-viaggi","11":"product_tag-agenzie-di-viaggia","12":"product_tag-agenzie-viaggi","13":"product_tag-relax","14":"product_tag-single","15":"product_tag-vacanze-per-single","16":"product_tag-viaggi","17":"product_tag-viaggi-di-gruppi","18":"product_tag-viaggi-in-gruppi","19":"product_tag-viaggi-per-single","20":"product_tag-viaggio","21":"product_tag-weekend-e-vacanze-per-single","23":"first","24":"instock","25":"shipping-taxable","26":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Travelsingle - Viaggi e Vacanze per Single - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travelsingle - Viaggi e Vacanze per Single - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Travelsingle \u00e8 un operatore Leader nel settore di\u00a0weekend e viaggi per single, per chi viaggia da solo e vuole scoprire nuove destinazioni facendo nuove amicizie da tutta Italia condividendo ricordi ed emozioni in allegria e spensieratezza. Il nostro compito sar\u00e0 quello di creare\u00a0occasioni di aggregazione\u00a0divertendosi insieme, seguiti dai\u00a0nostri accompagnatori\u00a0che si prenderanno cura di voi durante tutto il viaggio assumendosi il compito di risolvere ogni eventuale problema ed assicurare il rilassamento e divertimento dei partecipanti.  E\u2019 stato ideato da uno\u00a0staff di persone\u00a0con\u00a0anni di esperienza\u00a0nel settore dei viaggi e\u00a0weekend per single\u00a0ve che si avvale della collaborazione dei migliori\u00a0Tour Operator\u00a0nazionali ed internazionali, strutture selezionate e provati accompagnatori per garantire ai clienti una vacanza in pieno relax ad un\u00a0costo accessibile a tutti.  L\u2019Agenzia Travelsingle si impegna al massimo nella\u00a0formazione di gruppi omogenei fra uomini e donne\u00a0(non garantito nella fascia over 50) che varieranno ad ogni nuovo viaggio, facendo sconti e promozioni in base all\u2019andamento delle prenotazioni, cosi come cureremo le diverse\u00a0fasce d\u2019et\u00e0\u00a0per creare gruppi omogenei e compatibili anagraficamente (normalmente\u00a0fascia 30\/50, over 50 o fascia mista).  Chi non vorr\u00e0 pagare il supplemento singola potr\u00e0 condividere la camera con un altro partecipante oppure in alcuni casi potr\u00e0 trovare offerte in\u00a0singola gratuita, in genere soggette a disponibilit\u00e0.  Travelsingle ti offrir\u00e0 un\u2019altra valida alternativa per chi ha gi\u00e0 provato i\u00a0viaggi per single\u00a0attraverso altre realt\u00e0 del settore, trovando la\u00a0stessa esperienza, cortesia ed efficienza a prezzi contenuti a\u00a0parit\u00e0 di qualit\u00e0 e servizi.  Le strutture prescelte per i nostri\u00a0weekend e vacanze per single\u00a0sono sempre accuratamente selezionate tramite un primo screening su\u00a0Tripadvisor\u00a0a cui seguono sopralluoghi sul posto per assicurare al cliente servizi all\u2019altezza delle aspettative.  Per ogni altra domanda puoi chiamare il nostro\u00a0call-center\u00a0disponile tutti i giorni o inviaci un email a info@travelsingle.it, ti risponderemo al pi\u00f9 presto!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T15:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/\",\"name\":\"Travelsingle - Viaggi e Vacanze per Single - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg\",\"datePublished\":\"2023-12-15T11:16:41+00:00\",\"dateModified\":\"2023-12-15T15:40:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Travelsingle &#8211; Viaggi e Vacanze per Single\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travelsingle - Viaggi e Vacanze per Single - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/","og_locale":"it_IT","og_type":"article","og_title":"Travelsingle - Viaggi e Vacanze per Single - UIL Polizia","og_description":"Travelsingle \u00e8 un operatore Leader nel settore di\u00a0weekend e viaggi per single, per chi viaggia da solo e vuole scoprire nuove destinazioni facendo nuove amicizie da tutta Italia condividendo ricordi ed emozioni in allegria e spensieratezza. Il nostro compito sar\u00e0 quello di creare\u00a0occasioni di aggregazione\u00a0divertendosi insieme, seguiti dai\u00a0nostri accompagnatori\u00a0che si prenderanno cura di voi durante tutto il viaggio assumendosi il compito di risolvere ogni eventuale problema ed assicurare il rilassamento e divertimento dei partecipanti.  E\u2019 stato ideato da uno\u00a0staff di persone\u00a0con\u00a0anni di esperienza\u00a0nel settore dei viaggi e\u00a0weekend per single\u00a0ve che si avvale della collaborazione dei migliori\u00a0Tour Operator\u00a0nazionali ed internazionali, strutture selezionate e provati accompagnatori per garantire ai clienti una vacanza in pieno relax ad un\u00a0costo accessibile a tutti.  L\u2019Agenzia Travelsingle si impegna al massimo nella\u00a0formazione di gruppi omogenei fra uomini e donne\u00a0(non garantito nella fascia over 50) che varieranno ad ogni nuovo viaggio, facendo sconti e promozioni in base all\u2019andamento delle prenotazioni, cosi come cureremo le diverse\u00a0fasce d\u2019et\u00e0\u00a0per creare gruppi omogenei e compatibili anagraficamente (normalmente\u00a0fascia 30\/50, over 50 o fascia mista).  Chi non vorr\u00e0 pagare il supplemento singola potr\u00e0 condividere la camera con un altro partecipante oppure in alcuni casi potr\u00e0 trovare offerte in\u00a0singola gratuita, in genere soggette a disponibilit\u00e0.  Travelsingle ti offrir\u00e0 un\u2019altra valida alternativa per chi ha gi\u00e0 provato i\u00a0viaggi per single\u00a0attraverso altre realt\u00e0 del settore, trovando la\u00a0stessa esperienza, cortesia ed efficienza a prezzi contenuti a\u00a0parit\u00e0 di qualit\u00e0 e servizi.  Le strutture prescelte per i nostri\u00a0weekend e vacanze per single\u00a0sono sempre accuratamente selezionate tramite un primo screening su\u00a0Tripadvisor\u00a0a cui seguono sopralluoghi sul posto per assicurare al cliente servizi all\u2019altezza delle aspettative.  Per ogni altra domanda puoi chiamare il nostro\u00a0call-center\u00a0disponile tutti i giorni o inviaci un email a info@travelsingle.it, ti risponderemo al pi\u00f9 presto!","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/","og_site_name":"UIL Polizia","article_modified_time":"2023-12-15T15:40:16+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/","name":"Travelsingle - Viaggi e Vacanze per Single - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg","datePublished":"2023-12-15T11:16:41+00:00","dateModified":"2023-12-15T15:40:16+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/12\/Logo-Travel-Single.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/travelsingle-viaggi-e-vacanze-per-single\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Travelsingle &#8211; Viaggi e Vacanze per Single"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/52581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=52581"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/52581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/52583"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=52581"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=52581"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=52581"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=52581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}