{"id":51739,"date":"2023-11-16T10:16:49","date_gmt":"2023-11-16T09:16:49","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=51739"},"modified":"2023-11-17T10:35:05","modified_gmt":"2023-11-17T09:35:05","slug":"solarys-team","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/","title":{"rendered":"Solarys Team"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0d3b00&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0) 0%|#000000 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/H2-background-img-01.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;12vw||12vw||true|false&#8221; custom_padding_tablet=&#8221;10vw||10vw||true|false&#8221; custom_padding_phone=&#8221;10vw||10vw||true|false&#8221; background_last_edited=&#8221;on|desktop&#8221; parallax_tablet=&#8221;off&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|800||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;120px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;Poppins|200|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;50px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;60px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;65px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Solarys Team<\/h1>\n<h2>Energia solare<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; _builder_version=&#8221;4.16&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; padding_top_bottom_link_2=&#8221;false&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|||&#8221; padding_last_edited=&#8221;off|desktop&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;20px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.6em&#8221; header_2_font=&#8221;Poppins|600|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#005247&#8243; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;17px&#8221; header_font_size_phone=&#8221;17px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>LA VIA ECOLOGICA<\/h1>\n<h2>Solarys Team<\/h2>\n<p>Solarys Team \u00e8 una societ\u00e0 di servizi energetici che si rivolge a cittadini ed aziende col fine di aumentare l&#8217;efficienza energetica, promuovere l&#8217;energia rinnovabile ed aiutare le famiglie a raggiungere l&#8217;indipendenza energetica per abbattere i costi delle bollette.<\/p>\n<p>Siamo un&#8217;azienda sostenibile, presente sul territorio per promuovere iniziative e strategie per aiutare il nostro pianeta.<\/p>\n<p>Le energie rinnovabili sono a tutti gli effetti il modo pi\u00f9 facile, veloce ed economico per combattere l&#8217;inquinamento, sfruttando al meglio la loro potenzialit\u00e0 ci ritroveremo con una maggiore stabilit\u00e0 climatica, economica, ambientale e sociale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/modern-house-with-photovoltaic-system-8NGJ8GU.jpg&#8221; title_text=&#8221;Modern House with Photovoltaic System&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;2%&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_color=&#8221;#005247&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/7c14b1d9-51db-4aae-bb40-0ecabe3ffa00.jpg&#8221; title_text=&#8221;7c14b1d9-51db-4aae-bb40-0ecabe3ffa00&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;2%&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_color=&#8221;#fde840&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; padding_top_bottom_link_2=&#8221;false&#8221; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;||60px||false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#005247&#8243; border_style_bottom=&#8221;dotted&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/02\/square-bg.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; custom_padding=&#8221;10%|||40px&#8221; custom_padding_tablet=&#8221;|||&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|||&#8221; padding_last_edited=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;20px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.6em&#8221; header_2_font=&#8221;Poppins|600|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#005247&#8243; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>LA VIA ECOLOGICA<\/h1>\n<h2>Solarys Team<\/h2>\n<p>Solarys Team \u00e8 una societ\u00e0 di servizi energetici che si rivolge a cittadini ed aziende col fine di aumentare l&#8217;efficienza energetica, promuovere l&#8217;energia rinnovabile ed aiutare le famiglie a raggiungere l&#8217;indipendenza energetica per abbattere i costi delle bollette.<\/p>\n<p>Siamo un&#8217;azienda sostenibile, presente sul territorio per promuovere iniziative e strategie per aiutare il nostro pianeta.<\/p>\n<p>Le energie rinnovabili sono a tutti gli effetti il modo pi\u00f9 facile, veloce ed economico per combattere l&#8217;inquinamento, sfruttando al meglio la loro potenzialit\u00e0 ci ritroveremo con una maggiore stabilit\u00e0 climatica, economica, ambientale e sociale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/modern-house-with-photovoltaic-system-8NGJ8GU.jpg&#8221; title_text=&#8221;Modern House with Photovoltaic System&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;2%&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_color=&#8221;#005247&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/7c14b1d9-51db-4aae-bb40-0ecabe3ffa00.jpg&#8221; title_text=&#8221;7c14b1d9-51db-4aae-bb40-0ecabe3ffa00&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;2%&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_color=&#8221;#fde840&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,3_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;60px||||false|false&#8221; custom_padding_tablet=&#8221;25px||||false|false&#8221; custom_padding_phone=&#8221;25px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Acquisisci-schermata-Web_27-10-2023_125729_solarysteam.com_.jpeg&#8221; title_text=&#8221;Acquisisci schermata Web_27-10-2023_125729_solarysteam.com&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;2%&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_color=&#8221;#005247&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/impianto-residenziale3.jpg&#8221; title_text=&#8221;impianto residenziale3&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;2%&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;5px&#8221; box_shadow_vertical=&#8221;5px&#8221; box_shadow_color=&#8221;#fde840&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_type=&#8221;circle&#8221; admin_label=&#8221;Servizi&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#005247&#8243; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.4em&#8221; custom_padding=&#8221;|||25px|false|false&#8221; custom_padding_tablet=&#8221;20px|||0px|false|false&#8221; custom_padding_phone=&#8221;20px|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Servizi offerti<\/h1>\n<ul>\n<li>Installazione chiavi in mano impianti fotovoltaici<\/li>\n<li>Sistemi di accumulo<\/li>\n<li>Pompe di calore<\/li>\n<li>Caldaie<\/li>\n<li>Climatizzatori; compresi di pratiche ENEA per detrazione fiscale, E-Distribuzione e GSE (residenziali ed aziendali)<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Stats&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#0d3b00&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0) 0%|#000000 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/fotovolatico_tris-scaled-1.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;7vw||7vw||true|false&#8221; custom_padding_tablet=&#8221;7vw||7vw||true|false&#8221; custom_padding_phone=&#8221;7vw||7vw||true|false&#8221; background_last_edited=&#8221;on|desktop&#8221; parallax_tablet=&#8221;off&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|800||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;70px&#8221; header_line_height=&#8221;1.4em&#8221; header_2_font=&#8221;Poppins|200|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;50px&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Contatti&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; link_text_color=&#8221;#005247&#8243; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#005247&#8243; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.4em&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#b6d638&#8243;]<\/p>\n<h1>Contatti<\/h1>\n<p>Piazzetta Giovanelli, 8 &#8211; 35027 Noventa Padovana (PD)<br \/><b>Tel: <\/b>0494907360<br \/><strong>Cell: <\/strong>3457189575<br \/><strong>Mail: <\/strong><a href=\"mailto:info@solarysteam.com\">info@solarysteam.com<\/a><br \/><strong>Pec: <\/strong><a href=\"mailto:solarys.team@pec.it\">solarys.team@pec.it<\/a><br \/><strong>Sito web: <\/strong><a href=\"https:\/\/solarysteam.com\/\">solarysteam.com<\/a><br \/><strong>Lun &#8211; Ven:<\/strong> 9:30 &#8211; 13:00 \/ 14:00 &#8211; 18:00<br \/>(reperibilit\u00e0 telefonica anche il sabato mattina)<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-148\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51739\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-148\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-148\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-148\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-148\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"148\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#f9f9fb&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_left&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-auto&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Piazzetta Giovanelli, 8, 35027 Noventa padovana PD, Italia <br>\n<strong>Telefono:<\/strong> +39 0494907360 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/solarysteam.com\">solarysteam.com<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:info@solarysteam.com\">info@solarysteam.com<\/a> \n<\/p><br \/>[\/et_pb_code][et_pb_social_media_follow _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|||-13px|false|false&#8221; custom_padding=&#8221;18px||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3b5998&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00aced&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ea2c59&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#007bb6&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-173\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51739\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-173\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-173\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-173\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-173\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"173\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-102\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-102\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-102\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-102\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-102\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"102\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>LA VIA ECOLOGICA<br \/>\nSolarys Team<\/p>\n<p>Solarys Team \u00e8 una societ\u00e0 di servizi energetici che si rivolge a cittadini ed aziende col fine di aumentare l&#8217;efficienza energetica, promuovere l&#8217;energia rinnovabile ed aiutare le famiglie a raggiungere l&#8217;indipendenza energetica per abbattere i costi delle bollette.<\/p>\n<p>Siamo un&#8217;azienda sostenibile, presente sul territorio per promuovere iniziative e strategie per aiutare il nostro pianeta.<\/p>\n<p>Le energie rinnovabili sono a tutti gli effetti il modo pi\u00f9 facile, veloce ed economico per combattere l&#8217;inquinamento, sfruttando al meglio la loro potenzialit\u00e0 ci ritroveremo con una maggiore stabilit\u00e0 climatica, economica, ambientale e sociale.<\/p>\n<p>installazione chiavi in mano impianti fotovoltaici, sistemi di accumulo, pompe di calore, caldaie, climatizzatori; compresi di pratiche ENEA per detrazione fiscale, E-Distribuzione e GSE (residenziali ed aziendali)<\/p>\n<p>servizi energetici, energia rinnovabile, energie rinnovabili, indipendenza energetica, installazione impianti fotovoltaici, installare impianti fotovoltaici, sistemi di accumulo, pompe di calore, caldaie, climatizzatori, installazione impianti sistemi di accumulo, installazione pompe di calore, installazione impianti caldaie, installazione impianti climatizzatori, installare impianti sistemi di accumulo, installare pompe di calore, installare impianti caldaie, installare impianti climatizzatori, installazione impianto sistema di accumulo, installazione impianto caldaia, installazione impianto climatizzatore, installare impianto sistema di accumulo, installare impianto caldaia, installare impianto climatizzatore, azienda di Impianti fotovoltaici, ditta di Impianti fotovoltaici, produzione di Impianti fotovoltaici, pannelli solari, installazione pannelli solari, installare pannelli solari,<\/p>\n<p>servizi energetici a Noventa Padovana, energia rinnovabile a Noventa Padovana, energie rinnovabili a Noventa Padovana, indipendenza energetica a Noventa Padovana, installazione impianti fotovoltaici a Noventa Padovana, installare impianti fotovoltaici a Noventa Padovana, sistemi di accumulo a Noventa Padovana, pompe di calore a Noventa Padovana, caldaie a Noventa Padovana, climatizzatori a Noventa Padovana, installazione impianti sistemi di accumulo a Noventa Padovana, installazione pompe di calore a Noventa Padovana, installazione impianti caldaie a Noventa Padovana, installazione impianti climatizzatori a Noventa Padovana, installare impianti sistemi di accumulo a Noventa Padovana, installare pompe di calore a Noventa Padovana, installare impianti caldaie a Noventa Padovana, installare impianti climatizzatori a Noventa Padovana, installazione impianto sistema di accumulo a Noventa Padovana, installazione impianto caldaia a Noventa Padovana, installazione impianto climatizzatore a Noventa Padovana, installare impianto sistema di accumulo a Noventa Padovana, installare impianto caldaia a Noventa Padovana, installare impianto climatizzatore a Noventa Padovana, azienda di Impianti fotovoltaici a Noventa Padovana, ditta di Impianti fotovoltaici a Noventa Padovana, produzione di Impianti fotovoltaici a Noventa Padovana, pannelli solari a Noventa Padovana, installazione pannelli solari a Noventa Padovana, installare pannelli solari a Noventa Padovana,<\/p>\n<\/div>\n","protected":false},"featured_media":51743,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[58,65,69,70,74],"product_tag":[9018,9024,9003,5797,9019,9025,8997,7675,9027,8998,9010,9011,9000,9008,9016,9017,9015,9023,9009,9006,9007,8999,9026,9004,9013,9014,9012,9022,9029,9005,9021,9028,9002,9020,8996,9001],"class_list":{"0":"post-51739","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-casa","7":"product_cat-fotovoltaico","8":"product_cat-impianti-di-climatizzazione","9":"product_cat-impianti-di-riscaldamento","10":"product_cat-infissi","11":"product_tag-azienda-di-impianti-fotovoltaici","12":"product_tag-azienda-di-impianti-fotovoltaici-a-noventa-padovana","13":"product_tag-caldaie","14":"product_tag-climatizzatori","15":"product_tag-ditta-di-impianti-fotovoltaici","16":"product_tag-ditta-di-impianti-fotovoltaici-a-noventa-padovana","17":"product_tag-energia-rinnovabile","18":"product_tag-energie-rinnovabili","19":"product_tag-impianti-fotovoltaici-a-noventa-padovana","20":"product_tag-indipendenza-energetica","21":"product_tag-installare-impianti-caldaie","22":"product_tag-installare-impianti-climatizzatori","23":"product_tag-installare-impianti-fotovoltaici","24":"product_tag-installare-impianti-sistemi-di-accumulo","25":"product_tag-installare-impianto-caldaia","26":"product_tag-installare-impianto-climatizzatore","27":"product_tag-installare-impianto-sistema-di-accumulo","28":"product_tag-installare-pannelli-solari","29":"product_tag-installare-pompe-di-calore","30":"product_tag-installazione-impianti-caldaie","31":"product_tag-installazione-impianti-climatizzatori","32":"product_tag-installazione-impianti-fotovoltaici","33":"product_tag-installazione-impianti-fotovoltaici-a-noventa-padovana","34":"product_tag-installazione-impianti-sistemi-di-accumulo","35":"product_tag-installazione-impianto-caldaia","36":"product_tag-installazione-impianto-climatizzatore","37":"product_tag-installazione-impianto-sistema-di-accumulo","38":"product_tag-installazione-pannelli-solari","39":"product_tag-installazione-pannelli-solari-a-noventa-padovana","40":"product_tag-installazione-pompe-di-calore","41":"product_tag-pannelli-solari","42":"product_tag-pannelli-solari-a-noventa-padovana","43":"product_tag-pompe-di-calore","44":"product_tag-produzione-di-impianti-fotovoltaici","45":"product_tag-servizi-energetici","46":"product_tag-sistemi-di-accumulo","48":"first","49":"instock","50":"shipping-taxable","51":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solarys Team - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solarys Team - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"LA VIA ECOLOGICA Solarys Team  Solarys Team \u00e8 una societ\u00e0 di servizi energetici che si rivolge a cittadini ed aziende col fine di aumentare l&#039;efficienza energetica, promuovere l&#039;energia rinnovabile ed aiutare le famiglie a raggiungere l&#039;indipendenza energetica per abbattere i costi delle bollette.  Siamo un&#039;azienda sostenibile, presente sul territorio per promuovere iniziative e strategie per aiutare il nostro pianeta.  Le energie rinnovabili sono a tutti gli effetti il modo pi\u00f9 facile, veloce ed economico per combattere l&#039;inquinamento, sfruttando al meglio la loro potenzialit\u00e0 ci ritroveremo con una maggiore stabilit\u00e0 climatica, economica, ambientale e sociale.  installazione chiavi in mano impianti fotovoltaici, sistemi di accumulo, pompe di calore, caldaie, climatizzatori; compresi di pratiche ENEA per detrazione fiscale, E-Distribuzione e GSE (residenziali ed aziendali)  servizi energetici, energia rinnovabile, energie rinnovabili, indipendenza energetica, installazione impianti fotovoltaici, installare impianti fotovoltaici, sistemi di accumulo, pompe di calore, caldaie, climatizzatori, installazione impianti sistemi di accumulo, installazione pompe di calore, installazione impianti caldaie, installazione impianti climatizzatori, installare impianti sistemi di accumulo, installare pompe di calore, installare impianti caldaie, installare impianti climatizzatori, installazione impianto sistema di accumulo, installazione impianto caldaia, installazione impianto climatizzatore, installare impianto sistema di accumulo, installare impianto caldaia, installare impianto climatizzatore, azienda di Impianti fotovoltaici, ditta di Impianti fotovoltaici, produzione di Impianti fotovoltaici, pannelli solari, installazione pannelli solari, installare pannelli solari,  servizi energetici a Noventa Padovana, energia rinnovabile a Noventa Padovana, energie rinnovabili a Noventa Padovana, indipendenza energetica a Noventa Padovana, installazione impianti fotovoltaici a Noventa Padovana, installare impianti fotovoltaici a Noventa Padovana, sistemi di accumulo a Noventa Padovana, pompe di calore a Noventa Padovana, caldaie a Noventa Padovana, climatizzatori a Noventa Padovana, installazione impianti sistemi di accumulo a Noventa Padovana, installazione pompe di calore a Noventa Padovana, installazione impianti caldaie a Noventa Padovana, installazione impianti climatizzatori a Noventa Padovana, installare impianti sistemi di accumulo a Noventa Padovana, installare pompe di calore a Noventa Padovana, installare impianti caldaie a Noventa Padovana, installare impianti climatizzatori a Noventa Padovana, installazione impianto sistema di accumulo a Noventa Padovana, installazione impianto caldaia a Noventa Padovana, installazione impianto climatizzatore a Noventa Padovana, installare impianto sistema di accumulo a Noventa Padovana, installare impianto caldaia a Noventa Padovana, installare impianto climatizzatore a Noventa Padovana, azienda di Impianti fotovoltaici a Noventa Padovana, ditta di Impianti fotovoltaici a Noventa Padovana, produzione di Impianti fotovoltaici a Noventa Padovana, pannelli solari a Noventa Padovana, installazione pannelli solari a Noventa Padovana, installare pannelli solari a Noventa Padovana,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T09:35:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/\",\"name\":\"Solarys Team - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg\",\"datePublished\":\"2023-11-16T09:16:49+00:00\",\"dateModified\":\"2023-11-17T09:35:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Solarys Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solarys Team - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/","og_locale":"it_IT","og_type":"article","og_title":"Solarys Team - UIL Polizia","og_description":"LA VIA ECOLOGICA Solarys Team  Solarys Team \u00e8 una societ\u00e0 di servizi energetici che si rivolge a cittadini ed aziende col fine di aumentare l'efficienza energetica, promuovere l'energia rinnovabile ed aiutare le famiglie a raggiungere l'indipendenza energetica per abbattere i costi delle bollette.  Siamo un'azienda sostenibile, presente sul territorio per promuovere iniziative e strategie per aiutare il nostro pianeta.  Le energie rinnovabili sono a tutti gli effetti il modo pi\u00f9 facile, veloce ed economico per combattere l'inquinamento, sfruttando al meglio la loro potenzialit\u00e0 ci ritroveremo con una maggiore stabilit\u00e0 climatica, economica, ambientale e sociale.  installazione chiavi in mano impianti fotovoltaici, sistemi di accumulo, pompe di calore, caldaie, climatizzatori; compresi di pratiche ENEA per detrazione fiscale, E-Distribuzione e GSE (residenziali ed aziendali)  servizi energetici, energia rinnovabile, energie rinnovabili, indipendenza energetica, installazione impianti fotovoltaici, installare impianti fotovoltaici, sistemi di accumulo, pompe di calore, caldaie, climatizzatori, installazione impianti sistemi di accumulo, installazione pompe di calore, installazione impianti caldaie, installazione impianti climatizzatori, installare impianti sistemi di accumulo, installare pompe di calore, installare impianti caldaie, installare impianti climatizzatori, installazione impianto sistema di accumulo, installazione impianto caldaia, installazione impianto climatizzatore, installare impianto sistema di accumulo, installare impianto caldaia, installare impianto climatizzatore, azienda di Impianti fotovoltaici, ditta di Impianti fotovoltaici, produzione di Impianti fotovoltaici, pannelli solari, installazione pannelli solari, installare pannelli solari,  servizi energetici a Noventa Padovana, energia rinnovabile a Noventa Padovana, energie rinnovabili a Noventa Padovana, indipendenza energetica a Noventa Padovana, installazione impianti fotovoltaici a Noventa Padovana, installare impianti fotovoltaici a Noventa Padovana, sistemi di accumulo a Noventa Padovana, pompe di calore a Noventa Padovana, caldaie a Noventa Padovana, climatizzatori a Noventa Padovana, installazione impianti sistemi di accumulo a Noventa Padovana, installazione pompe di calore a Noventa Padovana, installazione impianti caldaie a Noventa Padovana, installazione impianti climatizzatori a Noventa Padovana, installare impianti sistemi di accumulo a Noventa Padovana, installare pompe di calore a Noventa Padovana, installare impianti caldaie a Noventa Padovana, installare impianti climatizzatori a Noventa Padovana, installazione impianto sistema di accumulo a Noventa Padovana, installazione impianto caldaia a Noventa Padovana, installazione impianto climatizzatore a Noventa Padovana, installare impianto sistema di accumulo a Noventa Padovana, installare impianto caldaia a Noventa Padovana, installare impianto climatizzatore a Noventa Padovana, azienda di Impianti fotovoltaici a Noventa Padovana, ditta di Impianti fotovoltaici a Noventa Padovana, produzione di Impianti fotovoltaici a Noventa Padovana, pannelli solari a Noventa Padovana, installazione pannelli solari a Noventa Padovana, installare pannelli solari a Noventa Padovana,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/","og_site_name":"UIL Polizia","article_modified_time":"2023-11-17T09:35:05+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/","name":"Solarys Team - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg","datePublished":"2023-11-16T09:16:49+00:00","dateModified":"2023-11-17T09:35:05+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/Logo-siti-solarys-team-no-esc.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/solarys-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Solarys Team"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=51739"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/51743"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=51739"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=51739"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=51739"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=51739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}