{"id":51277,"date":"2023-11-02T11:01:49","date_gmt":"2023-11-02T10:01:49","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=51277"},"modified":"2023-11-07T16:13:00","modified_gmt":"2023-11-07T15:13:00","slug":"studio-legale-avv-gaspare-massimiliano-bonventre","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/","title":{"rendered":"Studio Legale Avv. Gaspare Massimiliano Bonventre"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;4%&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#004b70&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/02\/circle-background-pattern.png&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;3%&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.21.0&#8243; custom_padding=&#8221;10%|5%|10%|5%|true|true&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;25px&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;55px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;60px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;21px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Studio Legale<\/h1>\n<h2>Avv. Gaspare Massimiliano Bonventre<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.21.0&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/bonv-1-scaled.jpeg&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.21.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0.7) 0%|rgba(0,0,0,0.7) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/3-1-scaled.jpeg&#8221; custom_padding=&#8221;11vw||11vw||true|false&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;4%&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;25px&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;64px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;21px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Studio Legale<\/h1>\n<h2>Avv. Gaspare Massimiliano Bonventre<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1230px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;2em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#004b70&#8243; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;10px||10px|25px|true|false&#8221; custom_padding_tablet=&#8221;|||20px|false|false&#8221; custom_padding_phone=&#8221;|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; text_line_height_tablet=&#8221;1.8em&#8221; text_line_height_phone=&#8221;2em&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;22px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_left=&#8221;5px&#8221; border_color_left=&#8221;#004b70&#8243; border_style_left=&#8221;double&#8221; border_width_left_tablet=&#8221;7px&#8221; border_width_left_phone=&#8221;0px&#8221; border_width_left_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Lo Studio<\/h1>\n<p>Lo Studio legale Bonventre fornisce consulenza legale a persone fisiche e a persone giuridiche in materia di <strong>Diritto Civile, Diritto Amministrativo <\/strong>ed in particolar modo negli <strong>Appalti Pubblici, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari<\/strong>.<\/p>\n<p>Lo Studio si avvale inoltre di collaborazioni con professionisti che operano su tutto il territorio nazionale per eventuali domiciliazioni e per trattare materie non indicate in precedenza.<\/p>\n<p>Si riceve esclusivamente previo appuntamento dal Luned\u00ec al Venerd\u00ec.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/unnamed.jpg&#8221; title_text=&#8221;unnamed&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1230px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/unnamed.jpg&#8221; title_text=&#8221;unnamed&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;2em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#004b70&#8243; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;70px||||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;10px||10px|25px|true|false&#8221; custom_padding_tablet=&#8221;|||20px|false|false&#8221; custom_padding_phone=&#8221;|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; text_line_height_tablet=&#8221;1.8em&#8221; text_line_height_phone=&#8221;2em&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;22px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_left=&#8221;5px&#8221; border_color_left=&#8221;#004b70&#8243; border_style_left=&#8221;double&#8221; border_width_left_tablet=&#8221;7px&#8221; border_width_left_phone=&#8221;0px&#8221; border_width_left_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Lo Studio<\/h1>\n<p>Lo Studio legale Bonventre fornisce consulenza legale a persone fisiche e a persone giuridiche in materia di <strong>Diritto Civile, Diritto Amministrativo <\/strong>ed in particolar modo negli <strong>Appalti Pubblici, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari<\/strong>.<\/p>\n<p>Lo Studio si avvale inoltre di collaborazioni con professionisti che operano su tutto il territorio nazionale per eventuali domiciliazioni e per trattare materie non indicate in precedenza.<\/p>\n<p>Si riceve esclusivamente previo appuntamento dal Luned\u00ec al Venerd\u00ec.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#004b70&#8243; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; custom_padding=&#8221;10px||10px|25px|true|false&#8221; custom_padding_tablet=&#8221;|||20px|false|false&#8221; custom_padding_phone=&#8221;|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; text_line_height_tablet=&#8221;1.8em&#8221; text_line_height_phone=&#8221;2em&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;22px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_left=&#8221;7px&#8221; border_color_left=&#8221;#004b70&#8243; border_style_left=&#8221;double&#8221; border_width_left_tablet=&#8221;7px&#8221; border_width_left_phone=&#8221;0px&#8221; border_width_left_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Lo Studio<\/h1>\n<p>Lo Studio legale Bonventre fornisce consulenza legale a persone fisiche e a persone giuridiche in materia di <strong>Diritto Civile, Diritto Amministrativo <\/strong>ed in particolar modo negli <strong>Appalti Pubblici, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari<\/strong>.<\/p>\n<p>Lo Studio si avvale inoltre di collaborazioni con professionisti che operano su tutto il territorio nazionale per eventuali domiciliazioni e per trattare materie non indicate in precedenza.<\/p>\n<p>Si riceve esclusivamente previo appuntamento dal Luned\u00ec al Venerd\u00ec.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#004b70&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(94, 142, 165, 0.63) 0%|#004b70 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/bonv-2-scaled.jpeg&#8221; custom_padding=&#8221;6vw||6vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1500px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.6em&#8221; header_text_align_tablet=&#8221;center&#8221; header_text_align_phone=&#8221;left&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;33px&#8221; header_font_size_phone=&#8221;22px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Per gli associati e i loro familiari lo Studio applicher\u00e0 uno sconto del 20% sui compensi medi previsti<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.6em&#8221; header_text_align_tablet=&#8221;center&#8221; header_text_align_phone=&#8221;left&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;33px&#8221; header_font_size_phone=&#8221;22px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Per gli associati SIM Guardia di Finanza e i loro familiari lo Studio applicher\u00e0 uno sconto del 20% sui compensi medi previsti<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; link_text_color=&#8221;#004b70&#8243; header_font=&#8221;Poppins|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#004b70&#8243; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; custom_padding=&#8221;10px||10px|25px|true|false&#8221; custom_padding_tablet=&#8221;|||20px|false|false&#8221; custom_padding_phone=&#8221;|||0px|false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;22px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; border_width_left=&#8221;7px&#8221; border_color_left=&#8221;#004b70&#8243; border_style_left=&#8221;double&#8221; border_width_left_tablet=&#8221;7px&#8221; border_width_left_phone=&#8221;0px&#8221; border_width_left_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#00c6b4&#8243;]<\/p>\n<h1>Contatti<\/h1>\n<p>Via dei Colli della Farnesina, 72 &#8211; 00135 Roma<br \/><strong>Tel:<\/strong> 06 45474786<br \/><strong>Cell:<\/strong> 333 5221017<br \/><strong>Mail:<\/strong> <a href=\"mailto:gmbonventre@hotmail.com\">gmbonventre@hotmail.com<\/a><br \/><strong>Pec:<\/strong> <a href=\"mailto:gasparemassimilianobonventre@legalmail.it\">gasparemassimilianobonventre@legalmail.it<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-120\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51277\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-120\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-120\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-120\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-120\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"120\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#f9f9fb&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_left&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#eee6dd&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-professionisti&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via dei Colli della Farnesina n.72, 00135, Roma <br>\n<strong>Telefono:<\/strong> 06 45474786 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:gmbonventre@hotmail.com\">gmbonventre@hotmail.com<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-386\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51277\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-386\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-386\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-386\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-386\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"386\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-185\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-185\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-185\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-185\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-185\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"185\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div>\n<p>Lo Studio<\/p>\n<p>Lo Studio legale Bonventre fornisce consulenza legale a persone fisiche e a persone giuridiche in materia di Diritto Civile, Diritto Amministrativo ed in particolar modo negli Appalti Pubblici, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari.<\/p>\n<p>Lo Studio si avvale inoltre di collaborazioni con professionisti che operano su tutto il territorio nazionale per eventuali domiciliazioni e per trattare materie non indicate in precedenza.<\/p>\n<p>Si riceve esclusivamente previo appuntamento dal lunedi al venerdi.<\/p>\n<p>Studio legale, Studi legali, consulenza legale, aiuto legale , assistenza legale, Diritto Civile, Diritto Amministrativo, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari, avvocato, avvocati,<\/p>\n<p>Studio legale a Roma, Studi legali a Roma, consulenza legale a Roma, aiuto legale a Roma , assistenza legale a Roma, Diritto Civile a Roma, Diritto Amministrativo a Roma, Diritto del Lavoro a Roma, Recupero Crediti a Roma, Diritto di Famiglia a Roma, Diritto delle Successioni a Roma, Contrattualistica a Roma, Diritto delle Locazioni e Condominio a Roma, Infortunistica Stradale a Roma, Compravendite Immobiliari a Roma, avvocato a Roma, avvocati a Roma,<\/p>\n<\/div>\n","protected":false},"featured_media":51279,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[147,161],"product_tag":[6314,7728,599,8503,371,6688,370,6687,4365,8513,962,7729,1924,8510,478,8505,475,8504,1633,8506,8502,8511,2053,8509,639,8508,964,8512,1752,8507,906,6689,374,6690],"class_list":{"0":"post-51277","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-professionisti-studi-consulenze","7":"product_cat-studi-legali","8":"product_tag-aiuto-legale","9":"product_tag-aiuto-legale-a-roma","10":"product_tag-assistenza-legale","11":"product_tag-assistenza-legale-a-roma","12":"product_tag-avvocati","13":"product_tag-avvocati-a-roma","14":"product_tag-avvocato","15":"product_tag-avvocato-a-roma","16":"product_tag-compravendite-immobiliari","17":"product_tag-compravendite-immobiliari-a-roma","18":"product_tag-consulenza-legale","19":"product_tag-consulenza-legale-a-roma","20":"product_tag-contrattualistica","21":"product_tag-contrattualistica-a-roma","22":"product_tag-diritto-amministrativo","23":"product_tag-diritto-amministrativo-a-roma","24":"product_tag-diritto-civile","25":"product_tag-diritto-civile-a-roma","26":"product_tag-diritto-del-lavoro","27":"product_tag-diritto-del-lavoro-a-roma","28":"product_tag-diritto-delle-locazioni-e-condominio","29":"product_tag-diritto-delle-locazioni-e-condominio-a-roma","30":"product_tag-diritto-delle-successioni","31":"product_tag-diritto-delle-successioni-a-roma","32":"product_tag-diritto-di-famiglia","33":"product_tag-diritto-di-famiglia-a-roma","34":"product_tag-infortunistica-stradale","35":"product_tag-infortunistica-stradale-a-roma","36":"product_tag-recupero-crediti","37":"product_tag-recupero-crediti-a-roma","38":"product_tag-studi-legali","39":"product_tag-studi-legali-a-roma","40":"product_tag-studio-legale","41":"product_tag-studio-legale-a-roma","43":"first","44":"instock","45":"shipping-taxable","46":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Studio Legale Avv. Gaspare Massimiliano Bonventre - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio Legale Avv. Gaspare Massimiliano Bonventre - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Lo Studio  Lo Studio legale Bonventre fornisce consulenza legale a persone fisiche e a persone giuridiche in materia di Diritto Civile, Diritto Amministrativo ed in particolar modo negli Appalti Pubblici, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari.  Lo Studio si avvale inoltre di collaborazioni con professionisti che operano su tutto il territorio nazionale per eventuali domiciliazioni e per trattare materie non indicate in precedenza.  Si riceve esclusivamente previo appuntamento dal lunedi al venerdi.  Studio legale, Studi legali, consulenza legale, aiuto legale , assistenza legale, Diritto Civile, Diritto Amministrativo, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari, avvocato, avvocati,  Studio legale a Roma, Studi legali a Roma, consulenza legale a Roma, aiuto legale a Roma , assistenza legale a Roma, Diritto Civile a Roma, Diritto Amministrativo a Roma, Diritto del Lavoro a Roma, Recupero Crediti a Roma, Diritto di Famiglia a Roma, Diritto delle Successioni a Roma, Contrattualistica a Roma, Diritto delle Locazioni e Condominio a Roma, Infortunistica Stradale a Roma, Compravendite Immobiliari a Roma, avvocato a Roma, avvocati a Roma,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T15:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/\",\"name\":\"Studio Legale Avv. Gaspare Massimiliano Bonventre - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg\",\"datePublished\":\"2023-11-02T10:01:49+00:00\",\"dateModified\":\"2023-11-07T15:13:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Studio Legale Avv. Gaspare Massimiliano Bonventre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio Legale Avv. Gaspare Massimiliano Bonventre - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/","og_locale":"it_IT","og_type":"article","og_title":"Studio Legale Avv. Gaspare Massimiliano Bonventre - UIL Polizia","og_description":"Lo Studio  Lo Studio legale Bonventre fornisce consulenza legale a persone fisiche e a persone giuridiche in materia di Diritto Civile, Diritto Amministrativo ed in particolar modo negli Appalti Pubblici, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari.  Lo Studio si avvale inoltre di collaborazioni con professionisti che operano su tutto il territorio nazionale per eventuali domiciliazioni e per trattare materie non indicate in precedenza.  Si riceve esclusivamente previo appuntamento dal lunedi al venerdi.  Studio legale, Studi legali, consulenza legale, aiuto legale , assistenza legale, Diritto Civile, Diritto Amministrativo, Diritto del Lavoro, Recupero Crediti, Diritto di Famiglia, Diritto delle Successioni, Contrattualistica, Diritto delle Locazioni e Condominio, Infortunistica Stradale, Compravendite Immobiliari, avvocato, avvocati,  Studio legale a Roma, Studi legali a Roma, consulenza legale a Roma, aiuto legale a Roma , assistenza legale a Roma, Diritto Civile a Roma, Diritto Amministrativo a Roma, Diritto del Lavoro a Roma, Recupero Crediti a Roma, Diritto di Famiglia a Roma, Diritto delle Successioni a Roma, Contrattualistica a Roma, Diritto delle Locazioni e Condominio a Roma, Infortunistica Stradale a Roma, Compravendite Immobiliari a Roma, avvocato a Roma, avvocati a Roma,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/","og_site_name":"UIL Polizia","article_modified_time":"2023-11-07T15:13:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/","name":"Studio Legale Avv. Gaspare Massimiliano Bonventre - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg","datePublished":"2023-11-02T10:01:49+00:00","dateModified":"2023-11-07T15:13:00+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/11\/logo_Gaspare-Massimiliano-Bonventre.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-gaspare-massimiliano-bonventre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Studio Legale Avv. Gaspare Massimiliano Bonventre"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=51277"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/51279"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=51277"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=51277"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=51277"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=51277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}