{"id":51128,"date":"2023-10-27T12:28:56","date_gmt":"2023-10-27T10:28:56","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=51128"},"modified":"2023-10-27T17:26:50","modified_gmt":"2023-10-27T15:26:50","slug":"tecnocasa-studio-trezzano-99","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/","title":{"rendered":"Tecnocasa Studio Trezzano 99"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f9f9f9&#8243; custom_padding=&#8221;7%|6%|7%|6%|true|true&#8221; custom_padding_tablet=&#8221;10%|6%|10%|6%|true|true&#8221; custom_padding_phone=&#8221;15%||15%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/tecnocasa2.png&#8221; title_text=&#8221;tecnocasa2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;65%&#8221; max_width_tablet=&#8221;50%&#8221; max_width_phone=&#8221;80%&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#157638&#8243; header_2_font_size=&#8221;35px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;40px||||false|false&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>STUDIO TREZZANO 99<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/studio.jpeg&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/studio.jpeg&#8221; title_text=&#8221;studio&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|600|||||||&#8221; text_text_color=&#8221;#878787&#8243; text_font_size=&#8221;16px&#8221; text_letter_spacing=&#8221;5px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>CHI SIAMO<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#157638&#8243; text_font_size=&#8221;38px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;38px&#8221; text_font_size_phone=&#8221;30px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La nostra agenzia<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin_tablet=&#8221;-20px||||false|false&#8221; custom_margin_phone=&#8221;-20px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.9em&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il <strong>Quartiere Zingone<\/strong> nasce a partire dagli anni sessanta e si sviluppa nel territorio del comune si Trezzano S\/N, a cavallo della S.S. Nuova Vigevanese, a 4 Km dal Dazio di Lorenteggio.<br \/>Il <strong>quartiere Zingone<\/strong> interpreta razionalmente il bisogno di uscire dalla citt\u00e0 senza tuttavia staccarsene perch\u00e9 \u00e8 esso stesso un centro urbano alle porte di Milano, che rimane pur sempre il centro commerciale, politico e culturale della regione.<\/p>\n<p>Ampie zone del quartiere sono state riservate alla costruzione di ville e villette, dalle pi\u00f9 lussuose, dotate di campi da tennis e piscina, a quelle di minor costo, circondate da giardini, tutte comunque soddisfano le esigenze di chi vuole una casa indipendente che possa garantire quiete e tranquillit\u00e0.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.9em&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Nella zona pi\u00f9 centrale della citt\u00e0 sorge il &#8216;Centro Socio Culturale&#8217;, una palazzina circondata dal verde, dotata di campo di bocce a disposizione dei cittadini, accanto vi sono le aule della scuola di musica e una sala che ospita rassegne di pittura e fotografia.<\/p>\n<p>Al piano superiore c&#8217;\u00e8 una fornitissima biblioteca (17.000 volumi), una sala lettura e studio, alcune sale dove si svolgono corsi di lingua straniera e artigianato.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/trezzanosulnaviglio1.tecnocasa.it\/trezzano-sul-naviglio\/quartiere-zingone\/la-nostra-zona&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Maggiori informazioni&#8221; button_alignment=&#8221;right&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#157638&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Poppins|300||on|||||&#8221; custom_margin=&#8221;40px||||false|false&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(21,118,56,0.3)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_wc_description disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;descrizione convenzione&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(245,245,245,0.55) 0%|rgba(0,0,0,0) 45%&#8221; background_color_gradient_start=&#8221;rgba(245,245,245,0.55)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0)&#8221; background_color_gradient_end_position=&#8221;45%&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#333333&#8243; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>I vantaggi di vendere con il Gruppo Tecnocasa<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|600|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#157638&#8243; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;-20px||||false|false&#8221; header_2_font_size_tablet=&#8221;26px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Affidati a noi<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1475px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Conoscenza dettagliata&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_conoscenza-2.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>della zona e dell&#8217;andamento del mercato locale.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Assistenza&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_assistenza-2.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>in tutte le fasi della compravendita.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Valutazione gratuita&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_valutazione-2.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>e senza impegno.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1475px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;-30px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Disponibilit\u00e0&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_disponibilita-2.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>e selezione di numerosi acquirenti.<\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Appuntamenti e organizzazione&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_appuntamenti-2.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>e gestione delle visite all&#8217;immobile.<\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Promuovere l&#8217;immobile&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_promuovere.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>sui periodici e sui portali del Gruppo.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1475px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;-30px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_card title=&#8221;Nessun compenso \u00e8 dovuto&#8221; layout=&#8221;inline&#8221; layout_inline_image_width=&#8221;16%&#8221; image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/ico_nocompenso-1.png&#8221; image_as_background=&#8221;off&#8221; image_alignment=&#8221;center&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#157638&#8243; header_font_size=&#8221;16px&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_align=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>in caso di mancata conclusione dell&#8217;affare.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Stats&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#157638&#8243; background_enable_mask_style=&#8221;on&#8221; background_mask_style=&#8221;diagonal-pills&#8221; background_mask_color=&#8221;#0f5729&#8243; background_mask_aspect_ratio=&#8221;square&#8221; background_mask_size=&#8221;cover&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;50px||50px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Poppins|300|||||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;40px&#8221; header_3_line_height=&#8221;1.5em&#8221; header_3_font_size_tablet=&#8221;31px&#8221; header_3_font_size_phone=&#8221;27px&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Agevolazioni riservate agli associati<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;40px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;28px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||8px||false|false&#8221; header_2_font_size_tablet=&#8221;26px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.9em&#8221; link_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;-5px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Indirizzo:<\/strong> Viale L. da Vinci, 64 &#8211; 20090 Trezzano Sul Naviglio (MI)<br \/><strong>Telefono:<\/strong> +39 02 82307131<br \/><strong>Mail:<\/strong> <a href=\"mailto:mihj2@tecnocasa.it\">mihj2@tecnocasa.it<\/a><br \/><strong>Sito web:<\/strong> <a href=\"https:\/\/trezzanosulnaviglio1.tecnocasa.it\/\">trezzanosulnaviglio1.tecnocasa.it<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;24px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||8px||false|false&#8221; header_2_font_size_tablet=&#8221;26px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Orari<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.9em&#8221; link_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;-5px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Luned\u00ec &#8211; Venerd\u00ec:<\/strong> 9.00 &#8211; 12.30 \/ 14.30 &#8211; 19.30<br \/><strong>Sabato:<\/strong> 9.00 &#8211; 12.30<\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-10px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/trezzanosulnaviglio1.affiliato.tecnocasa&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/tecnocasa_trezzanozingone&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;dbdb-whatsapp&#8221; url=&#8221;https:\/\/api.whatsapp.com\/send?phone=393204677040&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]dbdb-whatsapp[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-170\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51128\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-170\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-170\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-170\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-170\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"170\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-auto&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Viale Leonardo da Vinci, 68, 20090 Trezzano sul Naviglio, MI, Italia <br>\n<strong>Telefono:<\/strong> +39 02 82307131 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/trezzanosulnaviglio1.tecnocasa.it\">trezzanosulnaviglio1.tecnocasa.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:mihj2@tecnocasa.it\">mihj2@tecnocasa.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div>\nIl Quartiere Zingone nasce a partire dagli anni sessanta e si sviluppa nel territorio del comune si Trezzano S\/N, a cavallo della S.S. Nuova Vigevanese, a 4 Km dal Dazio di Lorenteggio. Il quartiere Zingone interpreta razionalmente il bisogno di uscire dalla citt\u00e0 senza tuttavia staccarsene perch\u00e9 \u00e8 esso stesso un centro urbano alle porte di Milano, che rimane pur sempre il centro commerciale, politico e culturale della regione.<\/p>\n<p>Ampie zone del quartiere sono state riservate alla costruzione di ville e villette, dalle pi\u00f9 lussuose, dotate di campi da tennis e piscina, a quelle di minor costo, circondate da giardini, tutte comunque soddisfano le esigenze di chi vuole una casa indipendente che possa garantire quiete e tranquillit\u00e0. Nella zona pi\u00f9 centrale della citt\u00e0 sorge il &#8216;Centro Socio Culturale&#8217;, una palazzina circondata dal verde, dotata di campo di bocce a disposizione dei cittadini, accanto vi sono le aule della scuola di musica e una sala che ospita rassegne di pittura e fotografia. Al piano superiore c&#8217;\u00e8 una fornitissima biblioteca (17.000 volumi), una sala lettura e studio, alcune sale dove si svolgono corsi di lingua straniera e artigianato.<\/p>\n<p>agenzia immobiliare, agenzie immobiliari, agenti immobiliari, agente immobiliare, tecnocasa, immobili, vendita, affitto, compravendita, immobile<br \/>\nagenzia immobiliare a Trezzano sul Naviglio, agenzie immobiliari a Trezzano sul Naviglio, agenti immobiliari a Trezzano sul Naviglio, agente immobiliare a Trezzano sul Naviglio, tecnocasa a Trezzano sul Naviglio, immobili a Trezzano sul Naviglio, vendita a Trezzano sul Naviglio, affitto a Trezzano sul Naviglio, compravendita a Trezzano sul Naviglio, immobile a Trezzano sul Naviglio, agenzia immobiliare Trezzano sul Naviglio, agenzie immobiliari Trezzano sul Naviglio, agenti immobiliari Trezzano sul Naviglio, agente immobiliare Trezzano sul Naviglio, tecnocasa Trezzano sul Naviglio, immobili Trezzano sul Naviglio, vendita Trezzano sul Naviglio, affitto Trezzano sul Naviglio, compravendita Trezzano sul Naviglio, immobile Trezzano sul Naviglio\n<\/p><\/div>\n","protected":false},"featured_media":51129,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[59,58],"product_tag":[748,699,1197,873,1061,1192,8421,874,2067,4730,1120],"class_list":{"0":"post-51128","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agenzie-immobiliari","7":"product_cat-casa","8":"product_tag-affitto","9":"product_tag-agente-immobiliare","10":"product_tag-agenti-immobiliari","11":"product_tag-agenzia-immobiliare","12":"product_tag-agenzie-immobiliari","13":"product_tag-compravendita","14":"product_tag-gestione-immobili","15":"product_tag-immobile","16":"product_tag-immobili","17":"product_tag-tecnocasa","18":"product_tag-vendita","20":"first","21":"instock","22":"shipping-taxable","23":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tecnocasa Studio Trezzano 99 - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecnocasa Studio Trezzano 99 - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Il Quartiere Zingone nasce a partire dagli anni sessanta e si sviluppa nel territorio del comune si Trezzano S\/N, a cavallo della S.S. Nuova Vigevanese, a 4 Km dal Dazio di Lorenteggio. Il quartiere Zingone interpreta razionalmente il bisogno di uscire dalla citt\u00e0 senza tuttavia staccarsene perch\u00e9 \u00e8 esso stesso un centro urbano alle porte di Milano, che rimane pur sempre il centro commerciale, politico e culturale della regione.  Ampie zone del quartiere sono state riservate alla costruzione di ville e villette, dalle pi\u00f9 lussuose, dotate di campi da tennis e piscina, a quelle di minor costo, circondate da giardini, tutte comunque soddisfano le esigenze di chi vuole una casa indipendente che possa garantire quiete e tranquillit\u00e0. Nella zona pi\u00f9 centrale della citt\u00e0 sorge il &#039;Centro Socio Culturale&#039;, una palazzina circondata dal verde, dotata di campo di bocce a disposizione dei cittadini, accanto vi sono le aule della scuola di musica e una sala che ospita rassegne di pittura e fotografia. Al piano superiore c&#039;\u00e8 una fornitissima biblioteca (17.000 volumi), una sala lettura e studio, alcune sale dove si svolgono corsi di lingua straniera e artigianato.  agenzia immobiliare, agenzie immobiliari, agenti immobiliari, agente immobiliare, tecnocasa, immobili, vendita, affitto, compravendita, immobile agenzia immobiliare a Trezzano sul Naviglio, agenzie immobiliari a Trezzano sul Naviglio, agenti immobiliari a Trezzano sul Naviglio, agente immobiliare a Trezzano sul Naviglio, tecnocasa a Trezzano sul Naviglio, immobili a Trezzano sul Naviglio, vendita a Trezzano sul Naviglio, affitto a Trezzano sul Naviglio, compravendita a Trezzano sul Naviglio, immobile a Trezzano sul Naviglio, agenzia immobiliare Trezzano sul Naviglio, agenzie immobiliari Trezzano sul Naviglio, agenti immobiliari Trezzano sul Naviglio, agente immobiliare Trezzano sul Naviglio, tecnocasa Trezzano sul Naviglio, immobili Trezzano sul Naviglio, vendita Trezzano sul Naviglio, affitto Trezzano sul Naviglio, compravendita Trezzano sul Naviglio, immobile Trezzano sul Naviglio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-27T15:26:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/\",\"name\":\"Tecnocasa Studio Trezzano 99 - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg\",\"datePublished\":\"2023-10-27T10:28:56+00:00\",\"dateModified\":\"2023-10-27T15:26:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tecnocasa Studio Trezzano 99\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tecnocasa Studio Trezzano 99 - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/","og_locale":"it_IT","og_type":"article","og_title":"Tecnocasa Studio Trezzano 99 - UIL Polizia","og_description":"Il Quartiere Zingone nasce a partire dagli anni sessanta e si sviluppa nel territorio del comune si Trezzano S\/N, a cavallo della S.S. Nuova Vigevanese, a 4 Km dal Dazio di Lorenteggio. Il quartiere Zingone interpreta razionalmente il bisogno di uscire dalla citt\u00e0 senza tuttavia staccarsene perch\u00e9 \u00e8 esso stesso un centro urbano alle porte di Milano, che rimane pur sempre il centro commerciale, politico e culturale della regione.  Ampie zone del quartiere sono state riservate alla costruzione di ville e villette, dalle pi\u00f9 lussuose, dotate di campi da tennis e piscina, a quelle di minor costo, circondate da giardini, tutte comunque soddisfano le esigenze di chi vuole una casa indipendente che possa garantire quiete e tranquillit\u00e0. Nella zona pi\u00f9 centrale della citt\u00e0 sorge il 'Centro Socio Culturale', una palazzina circondata dal verde, dotata di campo di bocce a disposizione dei cittadini, accanto vi sono le aule della scuola di musica e una sala che ospita rassegne di pittura e fotografia. Al piano superiore c'\u00e8 una fornitissima biblioteca (17.000 volumi), una sala lettura e studio, alcune sale dove si svolgono corsi di lingua straniera e artigianato.  agenzia immobiliare, agenzie immobiliari, agenti immobiliari, agente immobiliare, tecnocasa, immobili, vendita, affitto, compravendita, immobile agenzia immobiliare a Trezzano sul Naviglio, agenzie immobiliari a Trezzano sul Naviglio, agenti immobiliari a Trezzano sul Naviglio, agente immobiliare a Trezzano sul Naviglio, tecnocasa a Trezzano sul Naviglio, immobili a Trezzano sul Naviglio, vendita a Trezzano sul Naviglio, affitto a Trezzano sul Naviglio, compravendita a Trezzano sul Naviglio, immobile a Trezzano sul Naviglio, agenzia immobiliare Trezzano sul Naviglio, agenzie immobiliari Trezzano sul Naviglio, agenti immobiliari Trezzano sul Naviglio, agente immobiliare Trezzano sul Naviglio, tecnocasa Trezzano sul Naviglio, immobili Trezzano sul Naviglio, vendita Trezzano sul Naviglio, affitto Trezzano sul Naviglio, compravendita Trezzano sul Naviglio, immobile Trezzano sul Naviglio","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/","og_site_name":"UIL Polizia","article_modified_time":"2023-10-27T15:26:50+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/","name":"Tecnocasa Studio Trezzano 99 - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg","datePublished":"2023-10-27T10:28:56+00:00","dateModified":"2023-10-27T15:26:50+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/Base-Logo-Tecnocasa-studio-trezzano.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/tecnocasa-studio-trezzano-99\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Tecnocasa Studio Trezzano 99"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=51128"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/51129"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=51128"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=51128"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=51128"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=51128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}