{"id":51021,"date":"2023-10-25T11:32:32","date_gmt":"2023-10-25T09:32:32","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=51021"},"modified":"2023-10-26T10:11:25","modified_gmt":"2023-10-26T08:11:25","slug":"studio-legale-avv-ilaria-del-carretto-di-saluzzo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/","title":{"rendered":"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3a591d&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/02\/circle-background-pattern.png&#8221; custom_padding=&#8221;8vw||8vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1700px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Arizonia|300|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;Poppins|600|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;65px&#8221; header_2_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;41px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Studio Legale<\/h1>\n<h2>Avv. Ilaria Del Carretto Di Saluzzo<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/lawyer-25-a-bo-13.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; custom_padding_tablet=&#8221;7vw||7vw||true|false&#8221; custom_padding_phone=&#8221;11vw||11vw||true|false&#8221; background_last_edited=&#8221;on|tablet&#8221; background_size_tablet=&#8221;contain&#8221; background_size_phone=&#8221;cover&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#3a591d&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>La mia esperienza professionale<\/h1>\n<p>Nell\u2019ambito della mia esperienza professionale venticinquennale, svolta stabilmente in Torino, ho maturato esperienza sia nel campo giudiziale sia stragiudiziale nei settori del diritto civile, fallimentare e delle assicurazioni, fideiussioni e cauzioni e della responsabilit\u00e0 civile. In particolare mi sono occupata di responsabilit\u00e0 professionale dei sindaci di societ\u00e0, commercialisti, avvocati e notai, ma anche di medici e di strutture sanitarie, nonch\u00e9 di responsabilit\u00e0 delle Pubbliche Amministrazioni e di contenzioso dinnanzi alla Corte dei Conti.<\/p>\n<p>Nel settore bancario e del credit management, mi sono occupata di contenzioso in genere, a partire dalla fase monitoria e di opposizione, sino alle controversie in materia di validit\u00e0 ed efficacia dei contratti e delle garanzie, l\u2019usura, l\u2019anatocismo bancario, la commissione di massimo scoperto, la segnalazione alla Centrale rischi della Banca d\u2019Italia, la responsabilit\u00e0 della Banca quale operatore finanziario e la gestione dell\u2019attivit\u00e0 esecutiva, sia mobiliare che immobiliare.<\/p>\n<p>Nell\u2019ambito della consulenza e della contrattualistica nazionale per conto di imprese individuali, imprese collettive ed istituti di credito, ho fornito assistenza in materia di appalto, mediazione, locazione.<\/p>\n<p>Ho maturato notevole esperienza nell\u2019ambito della gestione immobiliare per conto di clienti privati.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3a591d&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/02\/circle-background-pattern.png&#8221; custom_padding=&#8221;7vw||7vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1600px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_line_height=&#8221;1.9em&#8221; header_font=&#8221;Arizonia|300|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;90px&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Trattamento riservato su presentazione tessera<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpavigilidelfuoco\/wp-content\/uploads\/sites\/39\/2023\/10\/Avv.-Del-Carretto-Di-Saluzzo-Ilaria.jpg&#8221; title_text=&#8221;Avv. Del Carretto Di Saluzzo Ilaria&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h1>Contatti<\/h1>\n<p>Via Giambattista Viotti, 4 &#8211; 10121 Torino<br \/><strong>Tel:<\/strong> 011 18837932<br \/><strong>Mail:<\/strong> <a href=%22mailto:ilaria.delcarretto@faberlegal.it%22>ilaria.delcarretto@faberlegal.it<\/a><br \/><strong>Mail segreteria:<\/strong> <a href=%22mailto:segreteria@faberlegal.it%22>segreteria@faberlegal.it<\/a><br \/><strong>Pec: <\/strong><a href=%22mailto:ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it%22>ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it<\/a><\/p>\n<p>&#8221; content_last_edited=&#8221;off|tablet&#8221; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_font_size=&#8221;17px&#8221; text_line_height=&#8221;2.1em&#8221; link_text_color=&#8221;#3a591d&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#3a591d&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;|-30px|||false|false&#8221; custom_padding=&#8221;3vw||||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;13px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; link_letter_spacing_tablet=&#8221;&#8221; link_letter_spacing_phone=&#8221;-0.5px&#8221; link_letter_spacing_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#00a4b7&#8243; header_2_text_color=&#8221;#3a591d&#8221; header_2_font_size=&#8221;29px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; sticky_enabled=&#8221;0&#8243; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;23px&#8221; header_2_font_size_phone=&#8221;19px&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<h2>Avv. Ilaria Del Carretto Di Saluzzo<\/h2>\n<p>Via Giambattista Viotti, 4 &#8211; 10121 Torino<br \/>\n<strong>Tel:<\/strong> 011 18837932<br \/>\n<strong>Mail:<\/strong> <a href=\"mailto:ilaria.delcarretto@faberlegal.it\">ilaria.delcarretto@faberlegal.it<\/a><br \/>\n<strong>Mail segreteria:<\/strong> <a href=\"mailto:segreteria@faberlegal.it\">segreteria@faberlegal.it<\/a><br \/>\n<strong>Pec: <\/strong><a href=\"mailto:ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it\">ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it<\/a>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<h1>Contatti<\/h1>\n<p>Via Giambattista Viotti, 4 &#8211; 10121 Torino<br \/><strong>Tel:<\/strong> 011 18837932<br \/><strong>Mail:<\/strong> <a href=%22mailto:ilaria.delcarretto@faberlegal.it%22>ilaria.delcarretto@faberlegal.it<\/a><br \/><strong>Mail segreteria:<\/strong> <a href=%22mailto:segreteria@faberlegal.it%22>segreteria@faberlegal.it<\/a><br \/><strong>Pec: <\/strong><a href=%22mailto:ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it%22>ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it<\/a><\/p>\n<p>&#8221; content_last_edited=&#8221;off|tablet&#8221; disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;2em&#8221; link_text_color=&#8221;#3a591d&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#3a591d&#8221; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;|-30px|||false|false&#8221; custom_padding=&#8221;40px||||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;13px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; link_letter_spacing_tablet=&#8221;&#8221; link_letter_spacing_phone=&#8221;-0.5px&#8221; link_letter_spacing_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#00a4b7&#8243; header_2_text_color=&#8221;#3a591d&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_line_height=&#8221;1.8em&#8221; sticky_enabled=&#8221;0&#8243; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_phone=&#8221;20px&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<h2>Avv. Ilaria Del Carretto Di Saluzzo<\/h2>\n<p>Via Giambattista Viotti, 4 &#8211; 10121 Torino<br \/>\n<strong>Tel:<\/strong> 011 18837932<br \/>\n<strong>Mail:<\/strong> <a href=\"mailto:ilaria.delcarretto@faberlegal.it\">ilaria.delcarretto@faberlegal.it<\/a><br \/>\n<strong>Mail segreteria:<\/strong> <a href=\"mailto:segreteria@faberlegal.it\">segreteria@faberlegal.it<\/a><br \/>\n<strong>Pec: <\/strong><br \/>\n<a href=\"mailto:ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it\">ilariadelcarrettodisaluzzo@pec.ordineavvocatitorino.it<\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-542\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51021\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-542\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-542\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-542\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-542\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"542\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#f9f9fb&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_left&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#eee6dd&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|35px|35px|35px|35px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-professionisti&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Giambattista Viotti, 4 - 10121 Torino <br>\n<strong>Telefono:<\/strong> 011 18837932 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:ilaria.delcarretto@faberlegal.it\">ilaria.delcarretto@faberlegal.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-464\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"51021\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-464\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-464\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-464\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-464\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"464\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>La mia esperienza professionale<\/p>\n<p>Nell\u2019ambito della mia esperienza professionale venticinquennale, svolta stabilmente in Torino, ho maturato esperienza sia nel campo giudiziale sia stragiudiziale nei settori del diritto civile, fallimentare e delle assicurazioni, fideiussioni e cauzioni e della responsabilit\u00e0 civile. In particolare mi sono occupata di responsabilit\u00e0 professionale dei sindaci di societ\u00e0, commercialisti, avvocati e notai, ma anche di medici e di strutture sanitarie, nonch\u00e9 di responsabilit\u00e0 delle Pubbliche Amministrazioni e di contenzioso dinnanzi alla Corte dei Conti.<\/p>\n<p>Nel settore bancario e del credit management, mi sono occupata di contenzioso in genere, a partire dalla fase monitoria e di opposizione, sino alle controversie in materia di validit\u00e0 ed efficacia dei contratti e delle garanzie, l\u2019usura, l\u2019anatocismo bancario, la commissione di massimo scoperto, la segnalazione alla Centrale rischi della Banca d\u2019Italia, la responsabilit\u00e0 della Banca quale operatore finanziario e la gestione dell\u2019attivit\u00e0 esecutiva, sia mobiliare che immobiliare.<\/p>\n<p>Nell\u2019ambito della consulenza e della contrattualistica nazionale per conto di imprese individuali, imprese collettive ed istituti di credito, ho fornito assistenza in materia di appalto, mediazione, locazione.<\/p>\n<p>Ho maturato notevole esperienza nell\u2019ambito della gestione immobiliare per conto di clienti privati.<\/p>\n<p>Studio Legale, Studi Legali, diritto civile, diritto fallimentare, responsabilit\u00e0 civile, avvocati , avvocato , settore bancario, credit management , consulenza, contrattualistica, consulenza Legale, aiuto Legale, assistenza Legale, gestione immobiliare<\/p>\n<p>Studio Legale a Torino, Studi Legali a Torino, diritto civile a Torino, diritto fallimentare a Torino, responsabilit\u00e0 civile a Torino, avvocati a Torino , avvocato a Torino , settore bancario a Torino, credit management a Torino , consulenza a Torino, contrattualistica a Torino, consulenza Legale a Torino, aiuto Legale a Torino, assistenza Legale a Torino, gestione immobiliare a Torino<\/p>\n<\/div>\n","protected":false},"featured_media":51025,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[147,161],"product_tag":[6314,8284,599,8285,371,8286,370,3805,653,8287,962,8288,1924,8289,8290,8291,475,8292,1820,8293,8294,8295,8296,1821,8297,8298,906,8299,374],"class_list":{"0":"post-51021","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-professionisti-studi-consulenze","7":"product_cat-studi-legali","8":"product_tag-aiuto-legale","9":"product_tag-aiuto-legale-a-torino","10":"product_tag-assistenza-legale","11":"product_tag-assistenza-legale-a-torino","12":"product_tag-avvocati","13":"product_tag-avvocati-a-torino","14":"product_tag-avvocato","15":"product_tag-avvocato-a-torino","16":"product_tag-consulenza","17":"product_tag-consulenza-a-torino","18":"product_tag-consulenza-legale","19":"product_tag-consulenza-legale-a-torino","20":"product_tag-contrattualistica","21":"product_tag-contrattualistica-a-torino","22":"product_tag-credit-management","23":"product_tag-credit-management-a-torino","24":"product_tag-diritto-civile","25":"product_tag-diritto-civile-a-torino","26":"product_tag-diritto-fallimentare","27":"product_tag-diritto-fallimentare-a-torino","28":"product_tag-gestione-immobiliare-a-torino","29":"product_tag-gestione-immobiliare-studio-legale-a-torino","30":"product_tag-responsabilita-civile-a-torino","31":"product_tag-responsabilita-civile","32":"product_tag-settore-bancario","33":"product_tag-settore-bancario-a-torino","34":"product_tag-studi-legali","35":"product_tag-studi-legali-a-torino","36":"product_tag-studio-legale","38":"first","39":"instock","40":"shipping-taxable","41":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Studio Legale Avv. Ilaria Del Carretto Di Saluzzo - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"La mia esperienza professionale  Nell\u2019ambito della mia esperienza professionale venticinquennale, svolta stabilmente in Torino, ho maturato esperienza sia nel campo giudiziale sia stragiudiziale nei settori del diritto civile, fallimentare e delle assicurazioni, fideiussioni e cauzioni e della responsabilit\u00e0 civile. In particolare mi sono occupata di responsabilit\u00e0 professionale dei sindaci di societ\u00e0, commercialisti, avvocati e notai, ma anche di medici e di strutture sanitarie, nonch\u00e9 di responsabilit\u00e0 delle Pubbliche Amministrazioni e di contenzioso dinnanzi alla Corte dei Conti.  Nel settore bancario e del credit management, mi sono occupata di contenzioso in genere, a partire dalla fase monitoria e di opposizione, sino alle controversie in materia di validit\u00e0 ed efficacia dei contratti e delle garanzie, l\u2019usura, l\u2019anatocismo bancario, la commissione di massimo scoperto, la segnalazione alla Centrale rischi della Banca d\u2019Italia, la responsabilit\u00e0 della Banca quale operatore finanziario e la gestione dell\u2019attivit\u00e0 esecutiva, sia mobiliare che immobiliare.  Nell\u2019ambito della consulenza e della contrattualistica nazionale per conto di imprese individuali, imprese collettive ed istituti di credito, ho fornito assistenza in materia di appalto, mediazione, locazione.  Ho maturato notevole esperienza nell\u2019ambito della gestione immobiliare per conto di clienti privati.  Studio Legale, Studi Legali, diritto civile, diritto fallimentare, responsabilit\u00e0 civile, avvocati , avvocato , settore bancario, credit management , consulenza, contrattualistica, consulenza Legale, aiuto Legale, assistenza Legale, gestione immobiliare  Studio Legale a Torino, Studi Legali a Torino, diritto civile a Torino, diritto fallimentare a Torino, responsabilit\u00e0 civile a Torino, avvocati a Torino , avvocato a Torino , settore bancario a Torino, credit management a Torino , consulenza a Torino, contrattualistica a Torino, consulenza Legale a Torino, aiuto Legale a Torino, assistenza Legale a Torino, gestione immobiliare a Torino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T08:11:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/\",\"name\":\"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg\",\"datePublished\":\"2023-10-25T09:32:32+00:00\",\"dateModified\":\"2023-10-26T08:11:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/","og_locale":"it_IT","og_type":"article","og_title":"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo - UIL Polizia","og_description":"La mia esperienza professionale  Nell\u2019ambito della mia esperienza professionale venticinquennale, svolta stabilmente in Torino, ho maturato esperienza sia nel campo giudiziale sia stragiudiziale nei settori del diritto civile, fallimentare e delle assicurazioni, fideiussioni e cauzioni e della responsabilit\u00e0 civile. In particolare mi sono occupata di responsabilit\u00e0 professionale dei sindaci di societ\u00e0, commercialisti, avvocati e notai, ma anche di medici e di strutture sanitarie, nonch\u00e9 di responsabilit\u00e0 delle Pubbliche Amministrazioni e di contenzioso dinnanzi alla Corte dei Conti.  Nel settore bancario e del credit management, mi sono occupata di contenzioso in genere, a partire dalla fase monitoria e di opposizione, sino alle controversie in materia di validit\u00e0 ed efficacia dei contratti e delle garanzie, l\u2019usura, l\u2019anatocismo bancario, la commissione di massimo scoperto, la segnalazione alla Centrale rischi della Banca d\u2019Italia, la responsabilit\u00e0 della Banca quale operatore finanziario e la gestione dell\u2019attivit\u00e0 esecutiva, sia mobiliare che immobiliare.  Nell\u2019ambito della consulenza e della contrattualistica nazionale per conto di imprese individuali, imprese collettive ed istituti di credito, ho fornito assistenza in materia di appalto, mediazione, locazione.  Ho maturato notevole esperienza nell\u2019ambito della gestione immobiliare per conto di clienti privati.  Studio Legale, Studi Legali, diritto civile, diritto fallimentare, responsabilit\u00e0 civile, avvocati , avvocato , settore bancario, credit management , consulenza, contrattualistica, consulenza Legale, aiuto Legale, assistenza Legale, gestione immobiliare  Studio Legale a Torino, Studi Legali a Torino, diritto civile a Torino, diritto fallimentare a Torino, responsabilit\u00e0 civile a Torino, avvocati a Torino , avvocato a Torino , settore bancario a Torino, credit management a Torino , consulenza a Torino, contrattualistica a Torino, consulenza Legale a Torino, aiuto Legale a Torino, assistenza Legale a Torino, gestione immobiliare a Torino","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/","og_site_name":"UIL Polizia","article_modified_time":"2023-10-26T08:11:25+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/","name":"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg","datePublished":"2023-10-25T09:32:32+00:00","dateModified":"2023-10-26T08:11:25+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/logo_Avv.-ilaria-Del-Carretto-Di-saluzzo.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-ilaria-del-carretto-di-saluzzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Studio Legale Avv. Ilaria Del Carretto Di Saluzzo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=51021"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/51021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/51025"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=51021"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=51021"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=51021"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=51021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}