{"id":50077,"date":"2023-09-15T11:36:38","date_gmt":"2023-09-15T09:36:38","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=50077"},"modified":"2023-10-13T09:41:09","modified_gmt":"2023-10-13T07:41:09","slug":"dr-marco-riva-psicoterapeuta","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/","title":{"rendered":"Dr. Marco Riva &#8211; Psicoterapeuta"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#006d92&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;1deg&#8221; background_color_gradient_stops=&#8221;#006d92 0%|#008ea6 49%|#b1ebff 100%&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; custom_padding_tablet=&#8221;10vw||10vw||true|false&#8221; custom_padding_phone=&#8221;10vw||10vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Syne|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;90px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;Syne|||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;35px&#8221; header_2_letter_spacing=&#8221;20px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_font_size_tablet=&#8221;65px&#8221; header_font_size_phone=&#8221;33px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_letter_spacing_tablet=&#8221;17px&#8221; header_2_letter_spacing_phone=&#8221;10px&#8221; header_2_letter_spacing_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Dr. Marco Riva<\/h1>\n<h2>Psicoterapeuta<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1400px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_type=&#8221;circle&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; ul_font=&#8221;Poppins|300|||||||&#8221; ul_text_align=&#8221;justify&#8221; ul_text_color=&#8221;#333333&#8243; ul_line_height=&#8221;2em&#8221; header_font=&#8221;Syne|700||on|||||&#8221; header_text_color=&#8221;#006d92&#8243; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Formazione del Dr. Riva<\/h1>\n<ul>\n<li>Laureato in medicina e chirurgia, specialista in psichiatria e psicoterapia.<\/li>\n<li><strong>1999-2002<\/strong> Responsabile Servizio Diagnosi e Cura dell\u2019Ospedale Fatebenefratelli di Milano.<\/li>\n<li><strong>2002-2018<\/strong> Coordinatore dell\u2019Ambulatorio per la Diagnosi e la Cura dei disturbi dell\u2019umore e dell\u2019ansia dell\u2019Ospedale Fatebenefratelli di Milano.<\/li>\n<li><strong>2001-2007<\/strong> Responsabile Ambulatorio di Psiconcologia dell\u2019Ospedale Fatebenefratelli di Milano.<\/li>\n<li><strong>2006-2012<\/strong> Psichiatra dell\u2019ABA di Milano per la terapia dei disturbi della condotta alimentare.<\/li>\n<li><strong>2017 ad oggi<\/strong> psichiatra Opera San Francesco Milano Tutor di tirocinio per varie scuole di psicoterapia.<\/li>\n<li>Socio fondatore Associazione Culturale \u201cOttocentro\u201d.<\/li>\n<li>Si occupa di psicoterapia psicoanalitica e di terapia psicofarmacologica presso lo \u201cStudio 12\u201d di Milano.<\/li>\n<li>Membro IFPS-International Federation of Psychoanalytic Societies.<\/li>\n<li>\u00c8 autore di oltre 30 pubblicazioni pertinenti alla psicopatologia tra le quali: \u201cFalso S\u00e9 e psicopatologia mediale\u201d (1995), \u201cAppunti di fenomenologia virtuale\u201d (2004), \u201cNuova normalit\u00e0, nuovi casi\u201d (2006), \u201cAlcune note sulla Violenza Simbolica\u201d (2010), \u201cLegami Deliranti\u201d (2012), \u201cCronache di psicopatologia contemporanea\u201d (2020).<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/Marco-Riva-curriculum.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Curriculum Dr. Riva&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#006d92&#8243; button_border_width=&#8221;1px&#8221; button_border_radius=&#8221;5px&#8221; button_font=&#8221;Poppins|300|||||||&#8221; button_icon=&#8221;&#xe108;||divi||400&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/10\/foto-mr3.jpg&#8221; title_text=&#8221;foto mr3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#006d92&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#006d92 0%|#008ea6 49%|#b1ebff 100%&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Syne|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;60px&#8221; header_line_height=&#8221;1.4em&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;33px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Syne|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.4em&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati SIM GUARDIA DI FINANZA e i loro familiari<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#333333&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; link_text_color=&#8221;#006d92&#8243; header_font=&#8221;Syne|700||on|||||&#8221; header_text_color=&#8221;#006d92&#8243; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|hover&#8221; link_text_color__hover=&#8221;#00afa6&#8243;]<\/p>\n<h1>Contatti<\/h1>\n<p>Via Benedetto Marcello, 2 &#8211; 20154 Milano (MI)<br \/>\n<strong>Tel:<\/strong> 3334350174<br \/>\n<strong>Mail:<\/strong> <a href=\"mailto:rivamarco321@gmail.com\">rivamarco321@gmail.com<\/a><br \/>\n<strong>Sito web: <\/strong><a href=\"https:\/\/www.studio12-milano.it\/dott-marco-riva\/\">www.studio12-milano.it\/dott-marco-riva<\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-173\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"50077\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-173\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-173\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-173\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-173\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"173\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e7f3fd&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Benedetto Marcello, 2, 20124 Milano MI, Italia <br>\n<strong>Telefono:<\/strong> 3334350174 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.studio12-milano.it\/dott-marco-riva\/\">www.studio12-milano.it\/dott-marco-riva\/<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:rivamarco321@gmail.com\">rivamarco321@gmail.com<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-171\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"50077\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-171\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-171\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-171\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-171\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"171\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-139\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-139\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-139\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-139\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-139\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"139\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Formazione del Dr. Riva<br \/>\nLaureato in medicina e chirurgia, specialista in psichiatria e psicoterapia.<br \/>\n1999-2002 Responsabile Servizio Diagnosi e Cura dell\u2019Ospedale Fatebenefratelli di Milano.<br \/>\n2002-2018 Coordinatore dell\u2019Ambulatorio per la Diagnosi e la Cura dei disturbi dell\u2019umore e dell\u2019ansia dell\u2019Ospedale Fatebenefratelli di Milano.<br \/>\n2001-2007 Responsabile Ambulatorio di Psiconcologia dell\u2019Ospedale Fatebenefratelli di Milano.<br \/>\n2006-2012 Psichiatra dell\u2019ABA di Milano per la terapia dei disturbi della condotta alimentare.<br \/>\n2017 ad oggi psichiatra Opera San Francesco Milano Tutor di tirocinio per varie scuole di psicoterapia.<br \/>\nSocio fondatore Associazione Culturale \u201cOttocentro\u201d.<br \/>\nSi occupa di psicoterapia psicoanalitica e di terapia psicofarmacologica presso lo \u201cStudio 12\u201d di Milano.<br \/>\nMembro IFPS-International Federation of Psychoanalytic Societies.<br \/>\n\u00c8 autore di oltre 30 pubblicazioni pertinenti alla psicopatologia tra le quali: \u201cFalso S\u00e9 e psicopatologia mediale\u201d (1995), \u201cAppunti di fenomenologia virtuale\u201d (2004), \u201cNuova normalit\u00e0, nuovi casi\u201d (2006), \u201cAlcune note sulla Violenza Simbolica\u201d (2010), \u201cLegami Deliranti\u201d (2012), \u201cCronache di psicopatologia contemporanea\u201d (2020).<\/p>\n<p>Psicoterapeuta, Psicoterapia, psichiatria, psichiatra , disturbi dell\u2019umore, disturbi dell\u2019ansia, disturbi d\u2019ansia, disturbi della condotta alimentare, disturbi alimentari, psicoterapia psicoanalitica, terapia psicofarmacologica, consulenza psicoterapeutica, trattamento psicoterapico, disturbi psicologici, visita psichiatrica, visita psicoterapeutica,<\/p>\n<p>Psicoterapeuta a Milano, Psicoterapia a Milano, psichiatria a Milano, psichiatra a Milano , psicoterapia psicoanalitica a Milano, terapia psicofarmacologica a Milano, consulenza psicoterapeutica a Milano, trattamento psicoterapico a Milano, visita psichiatrica a Milano, visita psicoterapeutica a Milano<\/p>\n<\/div>\n","protected":false},"featured_media":50079,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[258,163],"product_tag":[7883,7911,1514,1463,2957,7904,7877,6326,1240,7908,587,7907,354,5892,818,7906,3282,7909,7905,7910,7882,7912,7884,7913,7885,7914],"class_list":{"0":"post-50077","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicoterapeuti","7":"product_cat-salute","8":"product_tag-consulenza-psicoterapeutica","9":"product_tag-consulenza-psicoterapeutica-a-milano","10":"product_tag-disturbi-alimentari","11":"product_tag-disturbi-dansia","12":"product_tag-disturbi-dellumore","13":"product_tag-disturbi-dellansia","14":"product_tag-disturbi-della-condotta-alimentare","15":"product_tag-disturbi-psicologici","16":"product_tag-psichiatra","17":"product_tag-psichiatra-a-milano","18":"product_tag-psichiatria","19":"product_tag-psichiatria-a-milano","20":"product_tag-psicoterapeuta","21":"product_tag-psicoterapeuta-a-milano","22":"product_tag-psicoterapia","23":"product_tag-psicoterapia-a-milano","24":"product_tag-psicoterapia-psicoanalitica","25":"product_tag-psicoterapia-psicoanalitica-a-milano","26":"product_tag-terapia-psicofarmacologica","27":"product_tag-terapia-psicofarmacologica-a-milano","28":"product_tag-trattamento-psicoterapico","29":"product_tag-trattamento-psicoterapico-a-milano","30":"product_tag-visita-psichiatrica","31":"product_tag-visita-psichiatrica-a-milano","32":"product_tag-visita-psicoterapeutica","33":"product_tag-visita-psicoterapeutica-a-milano","35":"first","36":"instock","37":"shipping-taxable","38":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dr. Marco Riva - Psicoterapeuta - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Marco Riva - Psicoterapeuta - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Formazione del Dr. Riva Laureato in medicina e chirurgia, specialista in psichiatria e psicoterapia. 1999-2002 Responsabile Servizio Diagnosi e Cura dell\u2019Ospedale Fatebenefratelli di Milano. 2002-2018 Coordinatore dell\u2019Ambulatorio per la Diagnosi e la Cura dei disturbi dell\u2019umore e dell\u2019ansia dell\u2019Ospedale Fatebenefratelli di Milano. 2001-2007 Responsabile Ambulatorio di Psiconcologia dell\u2019Ospedale Fatebenefratelli di Milano. 2006-2012 Psichiatra dell\u2019ABA di Milano per la terapia dei disturbi della condotta alimentare. 2017 ad oggi psichiatra Opera San Francesco Milano Tutor di tirocinio per varie scuole di psicoterapia. Socio fondatore Associazione Culturale \u201cOttocentro\u201d. Si occupa di psicoterapia psicoanalitica e di terapia psicofarmacologica presso lo \u201cStudio 12\u201d di Milano. Membro IFPS-International Federation of Psychoanalytic Societies. \u00c8 autore di oltre 30 pubblicazioni pertinenti alla psicopatologia tra le quali: \u201cFalso S\u00e9 e psicopatologia mediale\u201d (1995), \u201cAppunti di fenomenologia virtuale\u201d (2004), \u201cNuova normalit\u00e0, nuovi casi\u201d (2006), \u201cAlcune note sulla Violenza Simbolica\u201d (2010), \u201cLegami Deliranti\u201d (2012), \u201cCronache di psicopatologia contemporanea\u201d (2020).  Psicoterapeuta, Psicoterapia, psichiatria, psichiatra , disturbi dell\u2019umore, disturbi dell\u2019ansia, disturbi d\u2019ansia, disturbi della condotta alimentare, disturbi alimentari, psicoterapia psicoanalitica, terapia psicofarmacologica, consulenza psicoterapeutica, trattamento psicoterapico, disturbi psicologici, visita psichiatrica, visita psicoterapeutica,  Psicoterapeuta a Milano, Psicoterapia a Milano, psichiatria a Milano, psichiatra a Milano , psicoterapia psicoanalitica a Milano, terapia psicofarmacologica a Milano, consulenza psicoterapeutica a Milano, trattamento psicoterapico a Milano, visita psichiatrica a Milano, visita psicoterapeutica a Milano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-13T07:41:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/\",\"name\":\"Dr. Marco Riva - Psicoterapeuta - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg\",\"datePublished\":\"2023-09-15T09:36:38+00:00\",\"dateModified\":\"2023-10-13T07:41:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr. Marco Riva &#8211; Psicoterapeuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Marco Riva - Psicoterapeuta - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/","og_locale":"it_IT","og_type":"article","og_title":"Dr. Marco Riva - Psicoterapeuta - UIL Polizia","og_description":"Formazione del Dr. Riva Laureato in medicina e chirurgia, specialista in psichiatria e psicoterapia. 1999-2002 Responsabile Servizio Diagnosi e Cura dell\u2019Ospedale Fatebenefratelli di Milano. 2002-2018 Coordinatore dell\u2019Ambulatorio per la Diagnosi e la Cura dei disturbi dell\u2019umore e dell\u2019ansia dell\u2019Ospedale Fatebenefratelli di Milano. 2001-2007 Responsabile Ambulatorio di Psiconcologia dell\u2019Ospedale Fatebenefratelli di Milano. 2006-2012 Psichiatra dell\u2019ABA di Milano per la terapia dei disturbi della condotta alimentare. 2017 ad oggi psichiatra Opera San Francesco Milano Tutor di tirocinio per varie scuole di psicoterapia. Socio fondatore Associazione Culturale \u201cOttocentro\u201d. Si occupa di psicoterapia psicoanalitica e di terapia psicofarmacologica presso lo \u201cStudio 12\u201d di Milano. Membro IFPS-International Federation of Psychoanalytic Societies. \u00c8 autore di oltre 30 pubblicazioni pertinenti alla psicopatologia tra le quali: \u201cFalso S\u00e9 e psicopatologia mediale\u201d (1995), \u201cAppunti di fenomenologia virtuale\u201d (2004), \u201cNuova normalit\u00e0, nuovi casi\u201d (2006), \u201cAlcune note sulla Violenza Simbolica\u201d (2010), \u201cLegami Deliranti\u201d (2012), \u201cCronache di psicopatologia contemporanea\u201d (2020).  Psicoterapeuta, Psicoterapia, psichiatria, psichiatra , disturbi dell\u2019umore, disturbi dell\u2019ansia, disturbi d\u2019ansia, disturbi della condotta alimentare, disturbi alimentari, psicoterapia psicoanalitica, terapia psicofarmacologica, consulenza psicoterapeutica, trattamento psicoterapico, disturbi psicologici, visita psichiatrica, visita psicoterapeutica,  Psicoterapeuta a Milano, Psicoterapia a Milano, psichiatria a Milano, psichiatra a Milano , psicoterapia psicoanalitica a Milano, terapia psicofarmacologica a Milano, consulenza psicoterapeutica a Milano, trattamento psicoterapico a Milano, visita psichiatrica a Milano, visita psicoterapeutica a Milano","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/","og_site_name":"UIL Polizia","article_modified_time":"2023-10-13T07:41:09+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/","name":"Dr. Marco Riva - Psicoterapeuta - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg","datePublished":"2023-09-15T09:36:38+00:00","dateModified":"2023-10-13T07:41:09+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/09\/logo_Riva-Marco.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-marco-riva-psicoterapeuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dr. Marco Riva &#8211; Psicoterapeuta"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/50077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=50077"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/50077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/50079"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=50077"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=50077"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=50077"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=50077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}