{"id":48767,"date":"2023-07-18T16:45:46","date_gmt":"2023-07-18T14:45:46","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=48767"},"modified":"2023-07-18T16:45:54","modified_gmt":"2023-07-18T14:45:54","slug":"dott-ssa-sara-masiero-nutrizionista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/","title":{"rendered":"Dott.ssa Sara Masiero &#8211; Nutrizionista"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.21.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0.25) 21%|#ffffff 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/tomoko-uji-kxvn1ogpTtE-unsplash-scaled-1.jpg&#8221; custom_padding=&#8221;100px||100px||true|false&#8221; custom_padding_tablet=&#8221;100px||100px||true|false&#8221; custom_padding_phone=&#8221;70px||70px||true|false&#8221; bottom_divider_height=&#8221;60px&#8221; global_colors_info=&#8221;{}&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_stops__hover=&#8221;rgba(0,0,0,0.4) 0%|rgba(0,0,0,0.4) 100%&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Logo-Energiabenessere-color-transp.png&#8221; title_text=&#8221;Logo-Energiabenessere-color-transp&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#e71969&#8243; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||10px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Chi sono<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Sono Sara, biologa nutrizionista, per 15 anni ho lavorato con cellule e virus conseguendo un dottorato di Ricerca in Oncologia e una specializzazione in Microbiologia e Virologia per poi approdare nel settore nutrizione.<\/p>\n<p>Durante il mio percorso formativo nell\u2019ambito nutrizionale effettuato tramite differenti corsi di formazione specifici, ho cambiato personalmente molte delle mie abitudini quotidiane, sono la prima a dire che \u00e8 possibile con la giusta determinazione. In questa professione ritengo essenziale un continuo aggiornamento scientifico visto il repentino cambiamento.<\/p>\n<p>Inoltre, ho seguito il corso di Nutritional Sport Consultant a Padova e la mia tesi finale aveva come argomento finale le donne runner in post menopausa.<\/p>\n<p>Mi piace la divulgazione, per questo negli anni ho collaborato con diversi enti che mi hanno permesso di affiancare l\u2019informazione alla pratica.<\/p>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_description][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf5bb;||fa||900&#8243; icon_color=&#8221;#FFFFFF&#8221; image_icon_background_color=&#8221;RGBA(255,255,255,0)&#8221; image_icon_width=&#8221;35px&#8221; icon_alignment=&#8221;left&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; background_color=&#8221;#95b820&#8243; image_icon_custom_margin=&#8221;||-10px||false|false&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>La mia anima matura mi ha portato a lavorare bene con le persone.<br \/>La trasparenza \u00e8 uno dei miei valori pi\u00f9 elevati e grazie a questo le persone si fidano di me e mi seguono nei percorsi che propongo.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/image3.jpeg&#8221; title_text=&#8221;image3&#8243; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;-30px||||false|false&#8221; custom_margin_phone=&#8221;-30px||||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/image0.jpeg&#8221; title_text=&#8221;image0&#8243; align=&#8221;center&#8221; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#e71969&#8243; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||10px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Come lavoro<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><strong>Durante la visita nutrizionale<\/strong>, scaricabile nella dichiarazione dei redditi, parte del mio tempo lo dedico alla conoscenza della persona che ho di fronte e parte alle misure antropometriche e al test della bioimpedenza per valutare la composizione corporea, essenziale per qualsiasi obiettivo.<\/p>\n<p><strong>Mi occupo di<\/strong> stilare piani nutrizionali pi\u00f9 o meno dettagliati, principalmente per gestire problematiche di peso, gastriche, intestinali, dismetaboliche, femminili, per autoimmunit\u00e0, per allergie al nichel, per celiaci, nonch\u00e9 di gestire piani nutrizionali per sportivi.<\/p>\n<p>[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf5bb;||fa||900&#8243; icon_color=&#8221;#95b820&#8243; image_icon_background_color=&#8221;RGBA(255,255,255,0)&#8221; image_icon_width=&#8221;35px&#8221; icon_alignment=&#8221;right&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; background_enable_color=&#8221;off&#8221; image_icon_custom_margin=&#8221;||-10px||false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/image0.jpeg&#8221; title_text=&#8221;image0&#8243; align=&#8221;center&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#e7f3fd&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/tomoko-uji-kxvn1ogpTtE-unsplash-scaled-1.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;55px||35px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#e71969&#8243; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/image1.jpeg&#8221; title_text=&#8221;image1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#e71969&#8243; header_2_font_size=&#8221;35px&#8221; custom_margin=&#8221;23px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_code raw_content_tablet=&#8221;<\/p>\n<div style=%22font-family: Poppins, sans-serif; font-size: 15px; font-weight: 300; line-height: 28px%22>\n  %91info_cliente tipo=%22dati_azienda%22%93\n<\/div>\n<p>&#8221; raw_content_phone=&#8221;<\/p>\n<div style=%22font-family: Poppins, sans-serif; font-size: 15px; font-weight: 300; line-height: 28px%22>\n  %91info_cliente tipo=%22dati_azienda%22%93\n<\/div>\n<p>&#8221; raw_content_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-70px||0px||false|false&#8221; custom_margin_tablet=&#8221;-60px||||false|false&#8221; custom_margin_phone=&#8221;-60px||||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<div style=\"font-family: Poppins, sans-serif; font-size: 20px; font-weight: 300; line-height: 45px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Via Monteortone, 3, 35143 Padova, PD, Italia <br>\n<strong>Telefono:<\/strong> +39 393 316 9740 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:sara.masiero@energiabenessere.com\">sara.masiero@energiabenessere.com<\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div id=\"gmw-single-location-wrapper-200\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"48767\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-200\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-200\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-200\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-200\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"200\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Sono Sara, biologa nutrizionista, per 15 anni ho lavorato con cellule e virus conseguendo un dottorato di Ricerca in Oncologia e una specializzazione in Microbiologia e Virologia per poi approdare nel settore nutrizione.Durante il mio percorso formativo nell\u2019ambito nutrizionale effettuato tramite differenti corsi di formazione specifici, ho cambiato personalmente molte delle mie abitudini quotidiane, sono la prima a dire che \u00e8 possibile con la giusta determinazione. In questa professione ritengo essenziale un continuo aggiornamento scientifico visto il repentino cambiamento.<\/p>\n<p>Inoltre, ho seguito il corso di Nutritional Sport Consultant a Padova e la mia tesi finale aveva come argomento finale le donne runner in post menopausa.<\/p>\n<p>Mi piace la divulgazione, per questo negli anni ho collaborato con diversi enti che mi hanno permesso di affiancare l\u2019informazione alla pratica.<\/p>\n<p>La mia anima matura mi ha portato a lavorare bene con le persone. La trasparenza \u00e8 uno dei miei valori pi\u00f9 elevati e grazie a questo le persone si fidano di me e mi seguono nei percorsi che propongo.<\/p>\n<p>Durante la visita nutrizionale, scaricabile nella dichiarazione dei redditi, parte del mio tempo lo dedico alla conoscenza della persona che ho di fronte e parte alle misure antropometriche e al test della bioimpedenza per valutare la composizione corporea, essenziale per qualsiasi obiettivo.<\/p>\n<p>Mi occupo di stilare piani nutrizionali pi\u00f9 o meno dettagliati, principalmente per gestire problematiche di peso, gastriche, intestinali, dismetaboliche, femminili, per autoimmunit\u00e0, per allergie al nichel, per celiaci, nonch\u00e9 di gestire piani nutrizionali per sportivi.<\/p>\n<\/div>\n","protected":false},"featured_media":48768,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[234,163],"product_tag":[1143,6914,6915,1142,1167,6916,459,1049,4915,6917,5625,6918],"class_list":{"0":"post-48767","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-nutrizionisti","7":"product_cat-salute","8":"product_tag-alimentazione-sana","9":"product_tag-alimentazioni","10":"product_tag-celiaci","11":"product_tag-dieta","12":"product_tag-diete","13":"product_tag-mantenimemnto-peso","14":"product_tag-nutrizionista","15":"product_tag-nutrizionisti","16":"product_tag-perdita-peso","17":"product_tag-peso","18":"product_tag-piani-nutrizionali","19":"product_tag-piani-nutrizionali-sportivi","21":"first","22":"instock","23":"shipping-taxable","24":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Sara Masiero - Nutrizionista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Sara Masiero - Nutrizionista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono Sara, biologa nutrizionista, per 15 anni ho lavorato con cellule e virus conseguendo un dottorato di Ricerca in Oncologia e una specializzazione in Microbiologia e Virologia per poi approdare nel settore nutrizione.Durante il mio percorso formativo nell\u2019ambito nutrizionale effettuato tramite differenti corsi di formazione specifici, ho cambiato personalmente molte delle mie abitudini quotidiane, sono la prima a dire che \u00e8 possibile con la giusta determinazione. In questa professione ritengo essenziale un continuo aggiornamento scientifico visto il repentino cambiamento.  Inoltre, ho seguito il corso di Nutritional Sport Consultant a Padova e la mia tesi finale aveva come argomento finale le donne runner in post menopausa.  Mi piace la divulgazione, per questo negli anni ho collaborato con diversi enti che mi hanno permesso di affiancare l\u2019informazione alla pratica.  La mia anima matura mi ha portato a lavorare bene con le persone. La trasparenza \u00e8 uno dei miei valori pi\u00f9 elevati e grazie a questo le persone si fidano di me e mi seguono nei percorsi che propongo.  Durante la visita nutrizionale, scaricabile nella dichiarazione dei redditi, parte del mio tempo lo dedico alla conoscenza della persona che ho di fronte e parte alle misure antropometriche e al test della bioimpedenza per valutare la composizione corporea, essenziale per qualsiasi obiettivo.  Mi occupo di stilare piani nutrizionali pi\u00f9 o meno dettagliati, principalmente per gestire problematiche di peso, gastriche, intestinali, dismetaboliche, femminili, per autoimmunit\u00e0, per allergie al nichel, per celiaci, nonch\u00e9 di gestire piani nutrizionali per sportivi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-18T14:45:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/\",\"name\":\"Dott.ssa Sara Masiero - Nutrizionista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg\",\"datePublished\":\"2023-07-18T14:45:46+00:00\",\"dateModified\":\"2023-07-18T14:45:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Sara Masiero &#8211; Nutrizionista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Sara Masiero - Nutrizionista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Sara Masiero - Nutrizionista - UIL Polizia","og_description":"Sono Sara, biologa nutrizionista, per 15 anni ho lavorato con cellule e virus conseguendo un dottorato di Ricerca in Oncologia e una specializzazione in Microbiologia e Virologia per poi approdare nel settore nutrizione.Durante il mio percorso formativo nell\u2019ambito nutrizionale effettuato tramite differenti corsi di formazione specifici, ho cambiato personalmente molte delle mie abitudini quotidiane, sono la prima a dire che \u00e8 possibile con la giusta determinazione. In questa professione ritengo essenziale un continuo aggiornamento scientifico visto il repentino cambiamento.  Inoltre, ho seguito il corso di Nutritional Sport Consultant a Padova e la mia tesi finale aveva come argomento finale le donne runner in post menopausa.  Mi piace la divulgazione, per questo negli anni ho collaborato con diversi enti che mi hanno permesso di affiancare l\u2019informazione alla pratica.  La mia anima matura mi ha portato a lavorare bene con le persone. La trasparenza \u00e8 uno dei miei valori pi\u00f9 elevati e grazie a questo le persone si fidano di me e mi seguono nei percorsi che propongo.  Durante la visita nutrizionale, scaricabile nella dichiarazione dei redditi, parte del mio tempo lo dedico alla conoscenza della persona che ho di fronte e parte alle misure antropometriche e al test della bioimpedenza per valutare la composizione corporea, essenziale per qualsiasi obiettivo.  Mi occupo di stilare piani nutrizionali pi\u00f9 o meno dettagliati, principalmente per gestire problematiche di peso, gastriche, intestinali, dismetaboliche, femminili, per autoimmunit\u00e0, per allergie al nichel, per celiaci, nonch\u00e9 di gestire piani nutrizionali per sportivi.","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/","og_site_name":"UIL Polizia","article_modified_time":"2023-07-18T14:45:54+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/","name":"Dott.ssa Sara Masiero - Nutrizionista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg","datePublished":"2023-07-18T14:45:46+00:00","dateModified":"2023-07-18T14:45:54+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/Base-Logo-sara-masiero.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-masiero-nutrizionista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Sara Masiero &#8211; Nutrizionista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/48767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=48767"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/48767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/48768"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=48767"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=48767"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=48767"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=48767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}