{"id":48406,"date":"2023-07-07T10:20:04","date_gmt":"2023-07-07T08:20:04","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=48406"},"modified":"2023-07-07T10:21:18","modified_gmt":"2023-07-07T08:21:18","slug":"dott-ssa-gianna-esposito-biologa-nutrizionista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/","title":{"rendered":"Dott.ssa Gianna Esposito &#8211; Biologa Nutrizionista"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#000000 0%|rgba(0,0,0,0.37) 99%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/esp-scaled.jpg&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; custom_padding_tablet=&#8221;10vw||10vw||true|false&#8221; custom_padding_phone=&#8221;10vw||10vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1180px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;80px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|200||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Dott.ssa Gianna Esposito<\/h1>\n<h2>Biologa Nutrizionista<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1180px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#595959&#8243; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#00dfbd&#8221; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>La mia idea<\/h1>\n<p>Intraprendere un percorso con un nutrizionista significa essere disposti a mettersi in gioco, modificare le proprie abitudini e cambiare il proprio rapporto con il cibo.<\/p>\n<p>Il mio approccio si basa sull&#8217;accompagnarvi attraverso questo cambiamento, fornirvi le competenze per imparare a mangiare in maniera sana ed equilibrata ma comunque gustosa.<\/p>\n<p>I piani alimentari che elaboro non devono essere visti come rigide regole da seguire ad occhi chiusi ma indicazioni che messe in atto giorno dopo giorno creeranno nuove abitudini e vi insegneranno a creare in autonomia pasti equilibrati.<\/p>\n<p>Ogni paziente \u00e8 unico. Non mi limiter\u00f2 a darvi indicazioni standard ma dovremo cercare insieme di personalizzare il pi\u00f9 possibile i pasti e la loro distribuzione della giornata in base ai vostri gusti, orari e necessit\u00e0 varie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/foto-profilo-scaled.jpg&#8221; title_text=&#8221;foto profilo&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;40px||40px||true|false&#8221; custom_margin_tablet=&#8221;0px||0px||true|false&#8221; custom_margin_phone=&#8221;0px||0px||true|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding_tablet=&#8221;0px||0px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; ul_font=&#8221;Poppins|300|||||||&#8221; ul_text_color=&#8221;#FFFFFF&#8221; ul_line_height=&#8221;1.9em&#8221; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;241deg&#8221; background_color_gradient_stops=&#8221;#00dfbd 0%|#001989 100%&#8221; custom_margin_tablet=&#8221;0vw|||0vw|false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_tablet=&#8221;35px|35px|35px|35px|true|true&#8221; custom_padding_phone=&#8221;30px|30px|30px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Piani personalizzati per<\/h1>\n<ul>\n<li>Educazione ad un&#8217;alimentazione sana e consapevole<\/li>\n<li>Sovrappeso e obesit\u00e0<\/li>\n<li>Sportivi<\/li>\n<li>Vegetariani e Vegani<\/li>\n<li>Alterazioni cliniche e patologie come: Dislipidemie (colesterolo e trigliceridi alti), Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione&#8230;<\/li>\n<li>Patologie del tratto gastrointestinale come: Gastrite, Reflusso, Sindrome del colon irritabile&#8230;<\/li>\n<li>Allergie e Intolleranze alimentari<\/li>\n<li>Chiunque desideri sentirsi bene e restare in forma<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/IMAGE-2023-07-03-18_20_36.jpg&#8221; title_text=&#8221;IMAGE 2023-07-03 18_20_36&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1180px&#8221; custom_margin=&#8221;40px||40px||true|false&#8221; custom_margin_tablet=&#8221;40px||40px||true|false&#8221; custom_margin_phone=&#8221;40px||40px||true|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/IMAGE-2023-07-03-18_20_36.jpg&#8221; title_text=&#8221;IMAGE 2023-07-03 18_20_36&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; ul_font=&#8221;Poppins|300|||||||&#8221; ul_text_color=&#8221;#FFFFFF&#8221; ul_line_height=&#8221;1.9em&#8221; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.2em&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;241deg&#8221; background_color_gradient_stops=&#8221;#00dfbd 0%|#001989 100%&#8221; custom_margin=&#8221;4vw|||-4vw|false|false&#8221; custom_margin_tablet=&#8221;4vw|||-4vw|false|false&#8221; custom_margin_phone=&#8221;4vw|||-4vw|false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_tablet=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_phone=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;50px&#8221; header_font_size_phone=&#8221;50px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Piani personalizzati per<\/h1>\n<ul>\n<li>Educazione ad un&#8217;alimentazione sana e consapevole<\/li>\n<li>Sovrappeso e obesit\u00e0<\/li>\n<li>Sportivi<\/li>\n<li>Vegetariani e Vegani<\/li>\n<li>Alterazioni cliniche e patologie come: Dislipidemie (colesterolo e trigliceridi alti), Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione&#8230;<\/li>\n<li>Patologie del tratto gastrointestinale come: Gastrite, Reflusso, Sindrome del colon irritabile&#8230;<\/li>\n<li>Allergie e Intolleranze alimentari<\/li>\n<li>Chiunque desideri sentirsi bene e restare in forma<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1180px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#595959&#8243; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#00dfbd&#8221; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Come si svolge la visita<\/h1>\n<ul>\n<li><strong>primo incontro sar\u00e0 focalizzato sull\u2019analisi del vostro stile di vita:<\/strong>\n<ul>\n<li>orari e tipologia di lavoro<\/li>\n<li>eventuale grado e frequenza di attivit\u00e0 fisica<\/li>\n<li>dove e quando consumate i pasti<\/li>\n<li>i vostri gusti ed abitudini alimentari<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Questo mi permetter\u00e0 di elaborare un piano il pi\u00f9 personalizzato e sostenibile possibile.<\/p>\n<p>Verranno poi esaminati il peso e le circonferenze e verr\u00e0 effettuata l&#8217;analisi impedenziometrica per la valutazione della composizione corporea (stato di idratazione, massa magra e massa grassa).<\/p>\n<p>I controlli successivi avranno cadenza pi\u00f9 o meno mensile e prevedono l&#8217;analisi dei vari parametri corporei, valutazione dell&#8217;aderenza alle indicazioni fornite ed eventuali modifiche al piano alimentare.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.21.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;42deg&#8221; background_color_gradient_stops=&#8221;#00dfbd 24%|#001989 100%&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; custom_padding_tablet=&#8221;5vw||5vw||true|false&#8221; custom_padding_phone=&#8221;5vw||5vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;80px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|200||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|200||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati sim guardia di finanza e i loro familiari<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3vw||3vw||true|false&#8221; custom_padding_tablet=&#8221;3vw||3vw||true|false&#8221; custom_padding_phone=&#8221;3vw||3vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1200px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;2em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Playfair Display|||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.2em&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;241deg&#8221; background_color_gradient_stops=&#8221;#00dfbd 0%|#001989 100%&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_tablet=&#8221;35px|35px|35px|35px|true|true&#8221; custom_padding_phone=&#8221;30px|30px|30px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#0fffeb&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<p>Via 24 Maggio, 107 &#8211; 56123 Pisa<br \/>Galileo Centro Medico Via dell&#8217;edilizia, 21 &#8211; 58022 Follonica (GR)<br \/>Fisiopoint Viale risorgimento, 15 &#8211; 58024 Massa Marittima (GR)<\/p>\n<p><strong>Tel:<\/strong> 388 8329571<br \/><strong>Mail:<\/strong> <a href=\"mailto:gianna@espositonutrizionista.it\">gianna@espositonutrizionista.it<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-510\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-510\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-510\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-510\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-510\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"510\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e7f3fd&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via 24 Maggio, 107 - 56123 Pisa <br>\n<strong>Telefono:<\/strong> 388 8329571 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:gianna@espositonutrizionista.it\">gianna@espositonutrizionista.it<\/a> \n<\/p><br \/>[\/et_pb_code][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-391\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"48406\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-391\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-391\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-391\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-391\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"391\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-351\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-351\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-351\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-351\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-351\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"351\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>La mia idea<\/p>\n<p>Intraprendere un percorso con un nutrizionista significa essere disposti a mettersi in gioco, modificare le proprie abitudini e cambiare il proprio rapporto con il cibo.<\/p>\n<p>Il mio approccio si basa sull&#8217;accompagnarvi attraverso questo cambiamento, fornirvi le competenze per imparare a mangiare in maniera sana ed equilibrata ma comunque gustosa.<\/p>\n<p>I piani alimentari che elaboro non devono essere visti come rigide regole da seguire ad occhi chiusi ma indicazioni che messe in atto giorno dopo giorno creeranno nuove abitudini e vi insegneranno a creare in autonomia pasti equilibrati.<\/p>\n<p>Ogni paziente \u00e8 unico. Non mi limiter\u00f2 a darvi indicazioni standard ma dovremo cercare insieme di personalizzare il pi\u00f9 possibile i pasti e la loro distribuzione della giornata in base ai vostri gusti, orari e necessit\u00e0 varie.<\/p>\n<p>Piani personalizzati per<br \/>\nEducazione ad un&#8217;alimentazione sana e consapevole<br \/>\nSovrappeso e obesit\u00e0<br \/>\nSportivi<br \/>\nVegetariani e Vegani<br \/>\nAlterazioni cliniche e patologie come: Dislipidemie (colesterolo e trigliceridi alti), Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione&#8230;<br \/>\nPatologie del tratto gastrointestinale come: Gastrite, Reflusso, Sindrome del colon irritabile&#8230;<br \/>\nAllergie e Intolleranze alimentari<br \/>\nChiunque desideri sentirsi bene e restare in forma<\/p>\n<p>Come si svolge la visita<\/p>\n<p>primo incontro sar\u00e0 focalizzato sull&#8217;analisi del vostro stile di vita:<\/p>\n<p>orari e tipologia di lavoro<br \/>\neventuale grado e frequenza di attivit\u00e0 fisica<br \/>\ndove e quando consumate i pasti<br \/>\ni vostri gusti ed abitudini alimentari<\/p>\n<p>Questo mi permetter\u00e0 di elaborare un piano il pi\u00f9 personalizzato e sostenibile possibile.<\/p>\n<p>Verranno poi esaminati il peso e le circonferenze e verr\u00e0 effettuata l&#8217;analisi impedenziometrica per la valutazione della composizione corporea (stato di idratazione, massa magra e massa grassa).<\/p>\n<p>I controlli successivi avranno cadenza pi\u00f9 o meno mensile e prevedono l&#8217;analisi dei vari parametri corporei, valutazione dell&#8217;aderenza alle indicazioni fornite ed eventuali modifiche al piano alimentare.<\/p>\n<p>alimentazione, Biologa Nutrizionista, corretta alimentazione, corrette abitudini alimentari, Educazione alimentare, giusta alimentazione, mangiare bene, nutrizione, nutrizionista , piani alimentari, Piani personalizzati, Sovrappeso e obesit\u00e0, Sportivi, Vegetariani e Vegani, Alterazioni cliniche e patologie, Dislipidemie, colesterolo e trigliceridi alti, Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione, Patologie del tratto gastrointestinale, Gastrite, Reflusso, Sindrome del colon irritabile, Allergie e Intolleranze alimentari, restare in forma, Biologa Nutrizionista a Pisa, Biologa Nutrizionista a Follonica, Biologa Nutrizionista a Massa Marittima,<\/p>\n<\/div>\n","protected":false},"featured_media":48411,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[175,163],"product_tag":[847,5684,6749,1235,6755,6756,6754,6750,3748,6732,6751,5457,3147,3261,6741,4998,2355,5756,584,459,6752,4412,6748,2344,6753,2465,3895,5680,3200,5681],"class_list":{"0":"post-48406","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biologo-nutrizionista","7":"product_cat-salute","8":"product_tag-alimentazione","9":"product_tag-allergie-e-intolleranze-alimentari","10":"product_tag-alterazioni-cliniche-e-patologie","11":"product_tag-biologa-nutrizionista","12":"product_tag-biologa-nutrizionista-a-follonica","13":"product_tag-biologa-nutrizionista-a-massa-marittima","14":"product_tag-biologa-nutrizionista-a-pisa","15":"product_tag-colesterolo-e-trigliceridi-alti","16":"product_tag-corretta-alimentazione","17":"product_tag-corrette-abitudini-alimentari","18":"product_tag-diabete-di-tipo-2","19":"product_tag-dislipidemie","20":"product_tag-educazione-alimentare","21":"product_tag-gastrite","22":"product_tag-giusta-alimentazione","23":"product_tag-insulino-resistenza","24":"product_tag-ipertensione","25":"product_tag-mangiare-bene","26":"product_tag-nutrizione","27":"product_tag-nutrizionista","28":"product_tag-patologie-del-tratto-gastrointestinale","29":"product_tag-piani-alimentari","30":"product_tag-piani-personalizzati","31":"product_tag-reflusso","32":"product_tag-restare-in-forma","33":"product_tag-sindrome-del-colon-irritabile","34":"product_tag-sindrome-metabolica","35":"product_tag-sovrappeso-e-obesita","36":"product_tag-sportivi","37":"product_tag-vegetariani-e-vegani","39":"first","40":"instock","41":"shipping-taxable","42":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Gianna Esposito - Biologa Nutrizionista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Gianna Esposito - Biologa Nutrizionista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"La mia idea  Intraprendere un percorso con un nutrizionista significa essere disposti a mettersi in gioco, modificare le proprie abitudini e cambiare il proprio rapporto con il cibo.  Il mio approccio si basa sull&#039;accompagnarvi attraverso questo cambiamento, fornirvi le competenze per imparare a mangiare in maniera sana ed equilibrata ma comunque gustosa.  I piani alimentari che elaboro non devono essere visti come rigide regole da seguire ad occhi chiusi ma indicazioni che messe in atto giorno dopo giorno creeranno nuove abitudini e vi insegneranno a creare in autonomia pasti equilibrati.  Ogni paziente \u00e8 unico. Non mi limiter\u00f2 a darvi indicazioni standard ma dovremo cercare insieme di personalizzare il pi\u00f9 possibile i pasti e la loro distribuzione della giornata in base ai vostri gusti, orari e necessit\u00e0 varie.  Piani personalizzati per Educazione ad un&#039;alimentazione sana e consapevole Sovrappeso e obesit\u00e0 Sportivi Vegetariani e Vegani Alterazioni cliniche e patologie come: Dislipidemie (colesterolo e trigliceridi alti), Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione... Patologie del tratto gastrointestinale come: Gastrite, Reflusso, Sindrome del colon irritabile... Allergie e Intolleranze alimentari Chiunque desideri sentirsi bene e restare in forma  Come si svolge la visita  primo incontro sar\u00e0 focalizzato sull&#039;analisi del vostro stile di vita:  orari e tipologia di lavoro eventuale grado e frequenza di attivit\u00e0 fisica dove e quando consumate i pasti i vostri gusti ed abitudini alimentari  Questo mi permetter\u00e0 di elaborare un piano il pi\u00f9 personalizzato e sostenibile possibile.  Verranno poi esaminati il peso e le circonferenze e verr\u00e0 effettuata l&#039;analisi impedenziometrica per la valutazione della composizione corporea (stato di idratazione, massa magra e massa grassa).  I controlli successivi avranno cadenza pi\u00f9 o meno mensile e prevedono l&#039;analisi dei vari parametri corporei, valutazione dell&#039;aderenza alle indicazioni fornite ed eventuali modifiche al piano alimentare.  alimentazione, Biologa Nutrizionista, corretta alimentazione, corrette abitudini alimentari, Educazione alimentare, giusta alimentazione, mangiare bene, nutrizione, nutrizionista , piani alimentari, Piani personalizzati, Sovrappeso e obesit\u00e0, Sportivi, Vegetariani e Vegani, Alterazioni cliniche e patologie, Dislipidemie, colesterolo e trigliceridi alti, Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione, Patologie del tratto gastrointestinale, Gastrite, Reflusso, Sindrome del colon irritabile, Allergie e Intolleranze alimentari, restare in forma, Biologa Nutrizionista a Pisa, Biologa Nutrizionista a Follonica, Biologa Nutrizionista a Massa Marittima,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-07T08:21:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/\",\"name\":\"Dott.ssa Gianna Esposito - Biologa Nutrizionista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg\",\"datePublished\":\"2023-07-07T08:20:04+00:00\",\"dateModified\":\"2023-07-07T08:21:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Gianna Esposito &#8211; Biologa Nutrizionista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Gianna Esposito - Biologa Nutrizionista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Gianna Esposito - Biologa Nutrizionista - UIL Polizia","og_description":"La mia idea  Intraprendere un percorso con un nutrizionista significa essere disposti a mettersi in gioco, modificare le proprie abitudini e cambiare il proprio rapporto con il cibo.  Il mio approccio si basa sull'accompagnarvi attraverso questo cambiamento, fornirvi le competenze per imparare a mangiare in maniera sana ed equilibrata ma comunque gustosa.  I piani alimentari che elaboro non devono essere visti come rigide regole da seguire ad occhi chiusi ma indicazioni che messe in atto giorno dopo giorno creeranno nuove abitudini e vi insegneranno a creare in autonomia pasti equilibrati.  Ogni paziente \u00e8 unico. Non mi limiter\u00f2 a darvi indicazioni standard ma dovremo cercare insieme di personalizzare il pi\u00f9 possibile i pasti e la loro distribuzione della giornata in base ai vostri gusti, orari e necessit\u00e0 varie.  Piani personalizzati per Educazione ad un'alimentazione sana e consapevole Sovrappeso e obesit\u00e0 Sportivi Vegetariani e Vegani Alterazioni cliniche e patologie come: Dislipidemie (colesterolo e trigliceridi alti), Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione... Patologie del tratto gastrointestinale come: Gastrite, Reflusso, Sindrome del colon irritabile... Allergie e Intolleranze alimentari Chiunque desideri sentirsi bene e restare in forma  Come si svolge la visita  primo incontro sar\u00e0 focalizzato sull'analisi del vostro stile di vita:  orari e tipologia di lavoro eventuale grado e frequenza di attivit\u00e0 fisica dove e quando consumate i pasti i vostri gusti ed abitudini alimentari  Questo mi permetter\u00e0 di elaborare un piano il pi\u00f9 personalizzato e sostenibile possibile.  Verranno poi esaminati il peso e le circonferenze e verr\u00e0 effettuata l'analisi impedenziometrica per la valutazione della composizione corporea (stato di idratazione, massa magra e massa grassa).  I controlli successivi avranno cadenza pi\u00f9 o meno mensile e prevedono l'analisi dei vari parametri corporei, valutazione dell'aderenza alle indicazioni fornite ed eventuali modifiche al piano alimentare.  alimentazione, Biologa Nutrizionista, corretta alimentazione, corrette abitudini alimentari, Educazione alimentare, giusta alimentazione, mangiare bene, nutrizione, nutrizionista , piani alimentari, Piani personalizzati, Sovrappeso e obesit\u00e0, Sportivi, Vegetariani e Vegani, Alterazioni cliniche e patologie, Dislipidemie, colesterolo e trigliceridi alti, Diabete di tipo 2, Insulino resistenza, Sindrome metabolica, Ipertensione, Patologie del tratto gastrointestinale, Gastrite, Reflusso, Sindrome del colon irritabile, Allergie e Intolleranze alimentari, restare in forma, Biologa Nutrizionista a Pisa, Biologa Nutrizionista a Follonica, Biologa Nutrizionista a Massa Marittima,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/","og_site_name":"UIL Polizia","article_modified_time":"2023-07-07T08:21:18+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/","name":"Dott.ssa Gianna Esposito - Biologa Nutrizionista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg","datePublished":"2023-07-07T08:20:04+00:00","dateModified":"2023-07-07T08:21:18+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/07\/logo_Gianna-Esposito.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-gianna-esposito-biologa-nutrizionista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Gianna Esposito &#8211; Biologa Nutrizionista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/48406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=48406"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/48406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/48411"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=48406"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=48406"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=48406"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=48406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}