{"id":47943,"date":"2023-06-21T11:16:47","date_gmt":"2023-06-21T09:16:47","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=47943"},"modified":"2023-06-21T11:19:11","modified_gmt":"2023-06-21T09:19:11","slug":"dott-giacomo-belcari-psicologo-e-psicoterapeuta","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/","title":{"rendered":"Dott. Giacomo Belcari &#8211; Psicologo e Psicoterapeuta"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.21.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0.4) 0%|rgba(0,0,0,0.59) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.4)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0.4)&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/francesco-ungaro-RdELgb1bNz8-unsplash-1-scaled-1.jpg&#8221; background_position=&#8221;center_right&#8221; custom_padding=&#8221;130px||130px||true|false&#8221; custom_padding_tablet=&#8221;90px||90px||true|false&#8221; custom_padding_phone=&#8221;60px||60px||true|false&#8221; bottom_divider_height=&#8221;60px&#8221; global_colors_info=&#8221;{}&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_stops__hover=&#8221;rgba(0,0,0,0.4) 0%|rgba(0,0,0,0.4) 100%&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; header_font_size=&#8221;48px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;80px&#8221; header_2_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;55px&#8221; header_2_font_size_phone=&#8221;42px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Dott. Giacomo Belcari<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; header_font_size=&#8221;48px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;44px&#8221; header_2_letter_spacing=&#8221;5px&#8221; header_2_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;29px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>PSICOLOGO E PSICOTERAPEUTA<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;30px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.3em&#8221; background_color=&#8221;#004080&#8243; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;10px|||20px|false|false&#8221; custom_padding_tablet=&#8221;10px|||20px|false|false&#8221; custom_padding_phone=&#8221;10px||5px|20px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>CHI SonO<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Sono psicologo e psicoterapeuta, nella mia esperienza ho toccato vari ambiti professionali, dalle dipendenze all&#8217;educazione, passando per il disagio mentale di vario tipo, sia all&#8217;interno di enti pubblici che privati.<\/p>\n<p>Oggi svolgo prevalentemente attivit\u00e0 privata.<\/p>\n<p>Il cammino verso il benessere personale passa attraverso la conoscenza di s\u00e9 e nel dissolvimento di tutte le interferenze che ne rallentano o ne impediscono la realizzazione.<br \/>Molto spesso mi trovo a trattare problematiche legate ad ansia e attacchi di panico che sono le forme di disagio psichico pi\u00f9 comuni, ma che possono diventare fonte di grande conoscenza personale ed essere sciolte. Tutte le forme di sofferenza possono essere lette col fine di ricavarne l&#8217;antidoto per la guarigione.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/foto1.jpg&#8221; title_text=&#8221;foto1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/foto2-scaled-1.jpg&#8221; title_text=&#8221;foto2&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;30px&#8221; header_2_letter_spacing=&#8221;3px&#8221; header_2_line_height=&#8221;1.3em&#8221; background_color=&#8221;#0066cc&#8221; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;10px|||20px|false|false&#8221; custom_padding_tablet=&#8221;10px|||20px|false|false&#8221; custom_padding_phone=&#8221;10px||5px|20px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Come lavoro<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Mi avvalgo di tecniche comunemente conosciute come il classico colloquio psicoterapeutico, ma anche di strumenti pi\u00f9 specifici come la lettura del corpo e l&#8217;analisi posturale, la respirazione consapevole, il tremore neurogeno, l&#8217;arteterapia e altre forme di approccio alla cura.<br \/>L&#8217;accoglienza, l&#8217;ascolto e l&#8217;analisi dei punti di forza della persona rappresentano la base del primo colloquo con il paziente, ne segue la pianificazione degli obiettivi e poi inizia la costruzione di se stessi.<\/p>\n<p>Sono <strong>disponibile<\/strong> a svolgere anche psicoterapia <strong>online<\/strong>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|600|on||||||&#8221; text_text_color=&#8221;#0066cc&#8221; text_font_size=&#8221;18px&#8221; text_orientation=&#8221;right&#8221; custom_padding=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Contattami e prenota un appuntamento!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/foto2-scaled-1.jpg&#8221; title_text=&#8221;foto2&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_wc_description disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_description][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;#004080&#8243; background_enable_mask_style=&#8221;on&#8221; background_mask_color=&#8221;#004c93&#8243; background_mask_transform=&#8221;rotate_90_degree|flip_horizontal&#8221; background_mask_size=&#8221;cover&#8221; custom_padding=&#8221;45px||45px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|on||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#0066cc&#8221; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;23px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.9em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;-20px||||false|false&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;17px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><strong>Indirizzo:<\/strong> Via Luigi Tosti, 6 &#8211; 00179 Roma (RM)<br \/><strong>Telefono:<\/strong> +39 329 494 4317<br \/><strong>Mail:<\/strong> <a href=\"mailto:giacomo.belcari@yahoo.com\">giacomo.belcari@yahoo.com<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Luigi Tosti, 6, 00179 Roma, RM, Italia <br>\n<strong>Telefono:<\/strong> +39 329 494 4317 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:giacomo.belcari@yahoo.com\">giacomo.belcari@yahoo.com<\/a> \n<\/p><br \/>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div id=\"gmw-single-location-wrapper-385\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"47943\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-385\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-385\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-385\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-385\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"385\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Sono psicologo e psicoterapeuta, nella mia esperienza ho toccato vari ambiti professionali, dalle dipendenze all&#8217;educazione, passando per il disagio mentale di vario tipo, sia all&#8217;interno di enti pubblici che privati.<br \/>\nOggi svolgo prevalentemente attivit\u00e0 privata.<br \/>\nIl cammino verso il benessere personale passa attraverso la conoscenza di s\u00e9 e nel dissolvimento di tutte le interferenze che ne rallentano o ne impediscono la realizzazione. Molto spesso mi trovo a trattare problematiche legate ad ansia e attacchi di panico che sono le forme di disagio psichico pi\u00f9 comuni, ma che possono diventare fonte di grande conoscenza personale ed essere sciolte. Tutte le forme di sofferenza possono essere lette col fine di ricavarne l&#8217;antidoto per la guarigione. Mi avvalgo di tecniche comunemente conosciute come il classico colloquio psicoterapeutico, ma anche di strumenti pi\u00f9 specifici come la lettura del corpo e l&#8217;analisi posturale, la respirazione consapevole, il tremore neurogeno, l&#8217;arteterapia e altre forme di approccio alla cura. L&#8217;accoglienza, l&#8217;ascolto e l&#8217;analisi dei punti di forza della persona rappresentano la base del primo colloquio con il paziente, ne segue la pianificazione degli obiettivi e poi inizia la costruzione di se stessi. Sono disponibile a svolgere anche psicoterapia online.<\/p>\n<p>psicologo, psicoterapeuta, psicologi, psicoterapeuti, psicologia, psicoterapia, benessere mentale, benessere personale, terapia, sostegno psicologico, sostegno psicoterapeutico, psicologo a Roma, psicoterapeuta a Roma, psicologi a Roma, psicoterapeuti a Roma<\/p><\/div>\n","protected":false},"featured_media":47944,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,258,163],"product_tag":[2086,6581,3191,516,354,1499,6582,1557],"class_list":{"0":"post-47943","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-psicoterapeuti","8":"product_cat-salute","9":"product_tag-benessere-mentale","10":"product_tag-benessere-personale","11":"product_tag-colloqui","12":"product_tag-psicologo","13":"product_tag-psicoterapeuta","14":"product_tag-sostegno-psicologico","15":"product_tag-sostegno-psicoterapeutico","16":"product_tag-terapia","18":"first","19":"instock","20":"shipping-taxable","21":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Giacomo Belcari - Psicologo e Psicoterapeuta - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Giacomo Belcari - Psicologo e Psicoterapeuta - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono psicologo e psicoterapeuta, nella mia esperienza ho toccato vari ambiti professionali, dalle dipendenze all&#039;educazione, passando per il disagio mentale di vario tipo, sia all&#039;interno di enti pubblici che privati. Oggi svolgo prevalentemente attivit\u00e0 privata. Il cammino verso il benessere personale passa attraverso la conoscenza di s\u00e9 e nel dissolvimento di tutte le interferenze che ne rallentano o ne impediscono la realizzazione. Molto spesso mi trovo a trattare problematiche legate ad ansia e attacchi di panico che sono le forme di disagio psichico pi\u00f9 comuni, ma che possono diventare fonte di grande conoscenza personale ed essere sciolte. Tutte le forme di sofferenza possono essere lette col fine di ricavarne l&#039;antidoto per la guarigione. Mi avvalgo di tecniche comunemente conosciute come il classico colloquio psicoterapeutico, ma anche di strumenti pi\u00f9 specifici come la lettura del corpo e l&#039;analisi posturale, la respirazione consapevole, il tremore neurogeno, l&#039;arteterapia e altre forme di approccio alla cura. L&#039;accoglienza, l&#039;ascolto e l&#039;analisi dei punti di forza della persona rappresentano la base del primo colloquio con il paziente, ne segue la pianificazione degli obiettivi e poi inizia la costruzione di se stessi. Sono disponibile a svolgere anche psicoterapia online.  psicologo, psicoterapeuta, psicologi, psicoterapeuti, psicologia, psicoterapia, benessere mentale, benessere personale, terapia, sostegno psicologico, sostegno psicoterapeutico, psicologo a Roma, psicoterapeuta a Roma, psicologi a Roma, psicoterapeuti a Roma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T09:19:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/\",\"name\":\"Dott. Giacomo Belcari - Psicologo e Psicoterapeuta - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg\",\"datePublished\":\"2023-06-21T09:16:47+00:00\",\"dateModified\":\"2023-06-21T09:19:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Giacomo Belcari &#8211; Psicologo e Psicoterapeuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Giacomo Belcari - Psicologo e Psicoterapeuta - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Giacomo Belcari - Psicologo e Psicoterapeuta - UIL Polizia","og_description":"Sono psicologo e psicoterapeuta, nella mia esperienza ho toccato vari ambiti professionali, dalle dipendenze all'educazione, passando per il disagio mentale di vario tipo, sia all'interno di enti pubblici che privati. Oggi svolgo prevalentemente attivit\u00e0 privata. Il cammino verso il benessere personale passa attraverso la conoscenza di s\u00e9 e nel dissolvimento di tutte le interferenze che ne rallentano o ne impediscono la realizzazione. Molto spesso mi trovo a trattare problematiche legate ad ansia e attacchi di panico che sono le forme di disagio psichico pi\u00f9 comuni, ma che possono diventare fonte di grande conoscenza personale ed essere sciolte. Tutte le forme di sofferenza possono essere lette col fine di ricavarne l'antidoto per la guarigione. Mi avvalgo di tecniche comunemente conosciute come il classico colloquio psicoterapeutico, ma anche di strumenti pi\u00f9 specifici come la lettura del corpo e l'analisi posturale, la respirazione consapevole, il tremore neurogeno, l'arteterapia e altre forme di approccio alla cura. L'accoglienza, l'ascolto e l'analisi dei punti di forza della persona rappresentano la base del primo colloquio con il paziente, ne segue la pianificazione degli obiettivi e poi inizia la costruzione di se stessi. Sono disponibile a svolgere anche psicoterapia online.  psicologo, psicoterapeuta, psicologi, psicoterapeuti, psicologia, psicoterapia, benessere mentale, benessere personale, terapia, sostegno psicologico, sostegno psicoterapeutico, psicologo a Roma, psicoterapeuta a Roma, psicologi a Roma, psicoterapeuti a Roma","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/","og_site_name":"UIL Polizia","article_modified_time":"2023-06-21T09:19:11+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/","name":"Dott. Giacomo Belcari - Psicologo e Psicoterapeuta - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg","datePublished":"2023-06-21T09:16:47+00:00","dateModified":"2023-06-21T09:19:11+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/06\/Base-Logo-Giacomo-Belcari.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-giacomo-belcari-psicologo-e-psicoterapeuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Giacomo Belcari &#8211; Psicologo e Psicoterapeuta"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/47943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=47943"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/47943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/47944"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=47943"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=47943"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=47943"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=47943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}