{"id":45472,"date":"2023-04-26T12:08:05","date_gmt":"2023-04-26T10:08:05","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=45472"},"modified":"2023-05-02T16:07:23","modified_gmt":"2023-05-02T14:07:23","slug":"studio-legale-avv-antonino-santangelo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/","title":{"rendered":"Studio Legale Avv. Antonino Santangelo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/still-life-with-scales-justice-1-scaled-1.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;130px||130px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|300||on|||||&#8221; header_text_color=&#8221;#303649&#8243; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||7px||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Studio legale<\/h1>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_color=&#8221;#303649&#8243; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;31px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Avv. Antonino Santangelo<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/still-life-with-scales-justice-1-scaled-1.jpg&#8221; custom_padding=&#8221;130px||130px||true|false&#8221; background_last_edited=&#8221;on|phone&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|300||on|||||&#8221; header_text_color=&#8221;#303649&#8243; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||7px||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Studio legale<\/h1>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|600|||||||&#8221; header_text_color=&#8221;#303649&#8243; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;31px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Avv. Antonino<br \/>Santangelo<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; custom_padding=&#8221;80px|0px|80px|0px|true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; admin_label=&#8221;About Row&#8221; _builder_version=&#8221;3.25&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/WIN_20210223_15_46_09_Pro.jpg&#8221; title_text=&#8221;WIN_20210223_15_46_09_Pro&#8221; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/lawyer-16-featured-3-icons-3.png&#8221; title_text=&#8221;lawyer-16-featured-3-icons-3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;8%&#8221; max_width_tablet=&#8221;8%&#8221; max_width_phone=&#8221;12%&#8221; max_width_last_edited=&#8221;on|phone&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Lora|700|||||||&#8221; text_text_color=&#8221;#303649&#8243; text_font_size=&#8221;25px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#9e120f&#8221; header_3_font_size=&#8221;42px&#8221; header_3_line_height=&#8221;1.5em&#8221; header_5_text_color=&#8221;rgba(0,0,0,0.4)&#8221; header_5_font_size=&#8221;20px&#8221; header_5_letter_spacing=&#8221;3px&#8221; max_width=&#8221;600px&#8221; max_width_tablet=&#8221;&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;-7px||10px||false|false&#8221; custom_margin_tablet=&#8221;|70px||70px&#8221; custom_margin_phone=&#8221;|50px||50px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<p>Di cosa mi occupo<\/p>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-professionisti&#8221; _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; text_orientation=&#8221;justified&#8221;][\/et_pb_wc_description][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/WIN_20210223_15_46_09_Pro.jpg&#8221; title_text=&#8221;WIN_20210223_15_46_09_Pro&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(48,54,73,0.75)&#8221; background_color_gradient_end=&#8221;rgba(48,54,73,0.75)&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/business-people-working-using-laptop-min-scaled-1.jpg&#8221; custom_padding=&#8221;60px||60px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Nome attivit\u00e0&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#f7f7f7&#8243; header_font_size=&#8221;45px&#8221; header_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;38px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Trattamento riservato su presentazione tessera<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#f9f9fb&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_left&#8221; custom_padding=&#8221;70px||70px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1230px&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#303649&#8243; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(48,54,73,0.3)&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Source Sans Pro|700|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Poppins|600||on|||||&#8221; header_4_text_color=&#8221;#FFFFFF&#8221; header_4_font_size=&#8221;25px&#8221; header_4_letter_spacing=&#8221;1px&#8221; max_width=&#8221;600px&#8221; header_2_font_size_tablet=&#8221;50px&#8221; header_2_font_size_phone=&#8221;32px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h4>Contatti<\/h4>\n<p>[\/et_pb_text][et_pb_code disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-60px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style=\"font-family: Poppins, sans-serif; font-size: 15px; font-weight: 400; line-height: 25px; color: white; a: white\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Studio legale Avv. Antonino Santangelo, Via Pionieri dell\\'Aria, 32, 20025 Legnano, MI <br>\n<strong>Telefono:<\/strong> +39 0331405717 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:antonino_santangelo@hotmail.it\">antonino_santangelo@hotmail.it<\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div style=\"font-family: Poppins, sans-serif; font-size: 15px; font-weight: 400; line-height: 25px; color: white; margin-top: -25px\"><!-- [et_pb_line_break_holder] --><strong>Cellulare:<\/strong> +39 340 922 8111<!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Source Sans Pro|700|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Poppins|600||on|||||&#8221; header_4_text_color=&#8221;#FFFFFF&#8221; header_4_font_size=&#8221;25px&#8221; header_4_letter_spacing=&#8221;1px&#8221; max_width=&#8221;600px&#8221; custom_padding=&#8221;20px||||false|false&#8221; header_2_font_size_tablet=&#8221;50px&#8221; header_2_font_size_phone=&#8221;32px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h4>Orari<\/h4>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-25px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style=\"font-family: Poppins, sans-serif; font-size: 15px; font-weight: 400; line-height: 25px; color: white\"><!-- [et_pb_line_break_holder] --><strong>Lun &#8211; Ven:<\/strong> 9.00 &#8211; 13.00 \/ 15.00 &#8211; 19.30<!\u2013- [et_pb_br_holder] -\u2013><!-- [et_pb_line_break_holder] -->  <strong>Reperibilit\u00e0 sul cellulare:<\/strong> dal luned\u00ec al venerd\u00ec<!-- [et_pb_line_break_holder] -->dalle 09.00 alle 20.00<!\u2013- [et_pb_br_holder] -\u2013> il sabato dalle 09.00 alle 13.00.<!\u2013- [et_pb_br_holder] -\u2013><!-- [et_pb_line_break_holder] -->  <strong>Sabato:<\/strong> 9.00 &#8211; 13.00<!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221;]<div id=\"gmw-single-location-wrapper-337\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"45472\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-337\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:360px;\"> <span id=\"gmw-resize-map-toggle-337\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-337\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-337\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"337\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"font-family: Poppins, sans-serif; font-size: 16px; line-height: 25px; font-weight: 300\">Sono iscritto all&#8217;albo degli avvocati dal 1999, cassazionista dal 2012.<\/p>\n<p>Mi occupo di diritto penale (reati contro il patrimonio, in materia di stupefacenti, maltrattamenti in famiglia, immigrazione, diritto penale minorile, bancarotta) ed infortunistica (privata e stradale).<br \/>\nTratto separazioni e divorzi.<br \/>\nSvolgo attivit\u00e0 di recupero credito per conto di alcune societ\u00e0 private e di molti condomini.<br \/>\nTratto le materie condominiale e successoria.<\/p><\/div>\n","protected":false},"featured_media":45474,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[147,161],"product_tag":[371,370,3830,476,5855,1746,5856,1972,4876,5857,5478,1748,374],"class_list":{"0":"post-45472","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-professionisti-studi-consulenze","7":"product_cat-studi-legali","8":"product_tag-avvocati","9":"product_tag-avvocato","10":"product_tag-bancarotta","11":"product_tag-diritto-penale","12":"product_tag-diritto-penale-minorile","13":"product_tag-divorzi","14":"product_tag-immigrazione","15":"product_tag-infortunistica","16":"product_tag-maltrattamenti-in-famiglia","17":"product_tag-materia-di-stupefacenti","18":"product_tag-recupero-credito","19":"product_tag-separazioni","20":"product_tag-studio-legale","22":"first","23":"instock","24":"shipping-taxable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Studio Legale Avv. Antonino Santangelo - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio Legale Avv. Antonino Santangelo - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono iscritto all&#039;albo degli avvocati dal 1999, cassazionista dal 2012.  Mi occupo di diritto penale (reati contro il patrimonio, in materia di stupefacenti, maltrattamenti in famiglia, immigrazione, diritto penale minorile, bancarotta) ed infortunistica (privata e stradale). Tratto separazioni e divorzi. Svolgo attivit\u00e0 di recupero credito per conto di alcune societ\u00e0 private e di molti condomini. Tratto le materie condominiale e successoria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-02T14:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/\",\"name\":\"Studio Legale Avv. Antonino Santangelo - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg\",\"datePublished\":\"2023-04-26T10:08:05+00:00\",\"dateModified\":\"2023-05-02T14:07:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Studio Legale Avv. Antonino Santangelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio Legale Avv. Antonino Santangelo - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/","og_locale":"it_IT","og_type":"article","og_title":"Studio Legale Avv. Antonino Santangelo - UIL Polizia","og_description":"Sono iscritto all'albo degli avvocati dal 1999, cassazionista dal 2012.  Mi occupo di diritto penale (reati contro il patrimonio, in materia di stupefacenti, maltrattamenti in famiglia, immigrazione, diritto penale minorile, bancarotta) ed infortunistica (privata e stradale). Tratto separazioni e divorzi. Svolgo attivit\u00e0 di recupero credito per conto di alcune societ\u00e0 private e di molti condomini. Tratto le materie condominiale e successoria.","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/","og_site_name":"UIL Polizia","article_modified_time":"2023-05-02T14:07:23+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/","name":"Studio Legale Avv. Antonino Santangelo - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg","datePublished":"2023-04-26T10:08:05+00:00","dateModified":"2023-05-02T14:07:23+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logo-antonino-santangelo.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-avv-antonino-santangelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Studio Legale Avv. Antonino Santangelo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/45472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=45472"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/45472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/45474"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=45472"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=45472"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=45472"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=45472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}