{"id":44556,"date":"2023-04-13T16:47:39","date_gmt":"2023-04-13T14:47:39","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=44556"},"modified":"2023-04-13T17:24:17","modified_gmt":"2023-04-13T15:24:17","slug":"dott-ssa-valentina-catena-biologa-nutrizionista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/","title":{"rendered":"Dott.ssa Valentina Catena &#8211; Biologa Nutrizionista"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; next_background_color=&#8221;#ffffff&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.9.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.4)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0.4)&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/AdobeStock_197406958-1-scaled-1.jpeg&#8221; background_position=&#8221;bottom_center&#8221; custom_padding=&#8221;150px||200px||false|false&#8221; custom_padding_tablet=&#8221;100px||150px||false|false&#8221; custom_padding_phone=&#8221;50px||100px||false|false&#8221; bottom_divider_style=&#8221;wave&#8221; bottom_divider_height=&#8221;60px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; da_disable_devices=&#8221;off|off|off&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; header_font_size=&#8221;48px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;70px&#8221; header_2_line_height=&#8221;1.1em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;52px&#8221; header_2_font_size_phone=&#8221;34px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h2>Dott.ssa Valentina Catena<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; header_font_size=&#8221;48px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;35px&#8221; header_2_letter_spacing=&#8221;4px&#8221; header_2_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;20px||0px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;27px&#8221; header_2_font_size_phone=&#8221;21px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h2>BIOLOGA NUTRIZIONISTA<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;90px||90px|&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ff9933&#8243; header_2_font_size=&#8221;35px&#8221; custom_margin=&#8221;||5px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Chi sono<\/h2>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221;][\/et_pb_wc_description][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/IMG-2151-2-scaled-1.jpg&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;200px||200px||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|phone&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#e7f3fd&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#f2bb30&#8243; background_color_gradient_end=&#8221;#ff9933&#8243; background_color_gradient_direction=&#8221;213deg&#8221; custom_padding=&#8221;55px||35px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/photo1650971016.jpg&#8221; background_last_edited=&#8221;on|phone&#8221; background_enable_image_phone=&#8221;off&#8221; parallax_tablet=&#8221;on&#8221; parallax_phone=&#8221;off&#8221; background_position_tablet=&#8221;top_center&#8221;][et_pb_divider show_divider=&#8221;off&#8221; disabled_on=&#8221;on|off|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;200px||200px||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;190px||190px||true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221;][\/et_pb_divider][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/photo1650971016.jpg&#8221; title_text=&#8221;photo1650971016&#8243; disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ff9933&#8243; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;23px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;30px||25px||false|false&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div style=\"font-family: Poppins, sans-serif; font-size: 15px; font-weight: 400; line-height: 35px\"><!-- [et_pb_line_break_holder] -->  <strong><u>ROMA:<\/u><\/strong> Via Filippo Antonio Gualtiero, 70 &#8211; 00139 Roma<!\u2013- [et_pb_br_holder] -\u2013><!-- [et_pb_line_break_holder] --><strong><u>MONTEROTONDO:<\/u><\/strong> Viale Fausto Cecconi, 3 &#8211; 00015 Monterotondo (RM)<!\u2013- [et_pb_br_holder] -\u2013><!-- [et_pb_line_break_holder] --><strong>Telefono:<\/strong> +39 340 255 4498<!\u2013- [et_pb_br_holder] -\u2013><!-- [et_pb_line_break_holder] --><strong>Mail:<\/strong> <a href=\"mailto:catena_valentina@libero.it\">catena_valentina@libero.it<\/a><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-20px|||0px|false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;http:\/\/facebook.com\/dott.ssavalentinacatena&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ff9933&#8243; background_enable_color=&#8221;on&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;http:\/\/ig.com\/dott.ssavalentinacatena&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ff9933&#8243; background_enable_color=&#8221;on&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;dbdb-tiktok&#8221; url=&#8221;http:\/\/tiktok.com\/dott.ssavalentinacatena&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ff9933&#8243; background_enable_color=&#8221;on&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]dbdb-tiktok[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-object-locations-wrapper-454\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-454\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-454\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-454\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-454\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"454\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Dott.ssa Valentina Catena, Nutrizionista, Viale Fausto Cecconi, 3, 00015 Monterotondo, RM <br>\n<strong>Telefono:<\/strong> +39 340 255 4498 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:catena_valentina@libero.it\">catena_valentina@libero.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"font-family: Poppins, sans-serif; font-size: 15px; line-height: 25px; text-align: justify;\">\n<p>Benvenuto nella mia pagina, molto piacere sono Valentina e spero di poterti conoscere ed iniziare insieme un percorso ricco di soddisfazioni.<\/p>\n<p>Sono laureata in scienze biologiche e in scienze dell&#8217;alimentazione, ed ho svolto il tirocinio post laurea presso lo studio medico del prof. Migliaccio.<br \/>\nLa mia carriera lavorativa \u00e8 iniziata lavorando presso diversi polispecialistici, questo mi ha permesso di entrare in contatto con molte persone, pazienti e specialisti, e di fare molta sperienza.<br \/>\nLo scorso anno ho deciso di aprire il mio studio privato a Roma ed \u00e8 l\u00ec che attualmente lavoro.<br \/>\nMi potete trovare anche su Monterotondo presso il centro polispecialistico cappuccini.<\/p>\n<p>Mi occupo di alimentazione sia in condizione fisiologica che patologica, sia per l&#8217;incremento che per la perdita o l&#8217;eventuale mantenimento di peso.<br \/>\n<em>Ora non resta altro da fare che conoscerci dal vivo, a presto, Valentina.<\/em><\/p>\n<\/div>\n","protected":false},"featured_media":44562,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[175,163],"product_tag":[4911,1143,1235,1142,5433,5653,459,4915],"class_list":{"0":"post-44556","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biologo-nutrizionista","7":"product_cat-salute","8":"product_tag-alimentazione-equilibrata","9":"product_tag-alimentazione-sana","10":"product_tag-biologa-nutrizionista","11":"product_tag-dieta","12":"product_tag-dieta-personalizzata","13":"product_tag-mantenimento-di-peso","14":"product_tag-nutrizionista","15":"product_tag-perdita-peso","17":"first","18":"instock","19":"shipping-taxable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Valentina Catena - Biologa Nutrizionista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Valentina Catena - Biologa Nutrizionista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Benvenuto nella mia pagina, molto piacere sono Valentina e spero di poterti conoscere ed iniziare insieme un percorso ricco di soddisfazioni.  Sono laureata in scienze biologiche e in scienze dell&#039;alimentazione, ed ho svolto il tirocinio post laurea presso lo studio medico del prof. Migliaccio. La mia carriera lavorativa \u00e8 iniziata lavorando presso diversi polispecialistici, questo mi ha permesso di entrare in contatto con molte persone, pazienti e specialisti, e di fare molta sperienza. Lo scorso anno ho deciso di aprire il mio studio privato a Roma ed \u00e8 l\u00ec che attualmente lavoro. Mi potete trovare anche su Monterotondo presso il centro polispecialistico cappuccini.  Mi occupo di alimentazione sia in condizione fisiologica che patologica, sia per l&#039;incremento che per la perdita o l&#039;eventuale mantenimento di peso. Ora non resta altro da fare che conoscerci dal vivo, a presto, Valentina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-13T15:24:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/\",\"name\":\"Dott.ssa Valentina Catena - Biologa Nutrizionista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg\",\"datePublished\":\"2023-04-13T14:47:39+00:00\",\"dateModified\":\"2023-04-13T15:24:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Valentina Catena &#8211; Biologa Nutrizionista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Valentina Catena - Biologa Nutrizionista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Valentina Catena - Biologa Nutrizionista - UIL Polizia","og_description":"Benvenuto nella mia pagina, molto piacere sono Valentina e spero di poterti conoscere ed iniziare insieme un percorso ricco di soddisfazioni.  Sono laureata in scienze biologiche e in scienze dell'alimentazione, ed ho svolto il tirocinio post laurea presso lo studio medico del prof. Migliaccio. La mia carriera lavorativa \u00e8 iniziata lavorando presso diversi polispecialistici, questo mi ha permesso di entrare in contatto con molte persone, pazienti e specialisti, e di fare molta sperienza. Lo scorso anno ho deciso di aprire il mio studio privato a Roma ed \u00e8 l\u00ec che attualmente lavoro. Mi potete trovare anche su Monterotondo presso il centro polispecialistico cappuccini.  Mi occupo di alimentazione sia in condizione fisiologica che patologica, sia per l'incremento che per la perdita o l'eventuale mantenimento di peso. Ora non resta altro da fare che conoscerci dal vivo, a presto, Valentina.","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/","og_site_name":"UIL Polizia","article_modified_time":"2023-04-13T15:24:17+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/","name":"Dott.ssa Valentina Catena - Biologa Nutrizionista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg","datePublished":"2023-04-13T14:47:39+00:00","dateModified":"2023-04-13T15:24:17+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/04\/Base-Logovalentina-catena.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-valentina-catena-biologa-nutrizionista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Valentina Catena &#8211; Biologa Nutrizionista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/44556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=44556"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/44556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/44562"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=44556"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=44556"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=44556"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=44556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}