{"id":43688,"date":"2023-03-29T09:51:48","date_gmt":"2023-03-29T07:51:48","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=43688"},"modified":"2023-03-29T09:51:55","modified_gmt":"2023-03-29T07:51:55","slug":"studio-legale-c-14-avvocati","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/","title":{"rendered":"Studio Legale C-14 Avvocati"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.38)&#8221; background_color_gradient_end=&#8221;rgba(84,15,15,0.48)&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/aree.jpg&#8221; custom_padding=&#8221;9vw||9vw||true|false&#8221; custom_padding_tablet=&#8221;7vw||7vw||true|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/c14avvocati-.png&#8221; title_text=&#8221;c14avvocati-&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; width_tablet=&#8221;55%&#8221; width_phone=&#8221;70%&#8221; width_last_edited=&#8221;on|tablet&#8221; border_radii=&#8221;on|40px|40px|40px|40px&#8221; border_radii_tablet=&#8221;&#8221; border_radii_phone=&#8221;on|20px|20px|20px|20px&#8221; border_radii_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;20px&#8221; box_shadow_spread=&#8221;5px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.56)&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;4vw||4vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#871028&#8243; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>La nostra storia<\/h1>\n<p>C-14 Avvocati \u00e8 un progetto che nasce nel 2018 dall\u2019incontro e dall\u2019idea di condivisione e messa a disposizione, in una sede unitaria, delle differenti esperienze e della professionalit\u00e0 di tre Avvocati, maturate ed acquisite nel corso di una loro gi\u00e0 ultraventennale esperienza e collaborazione, finalizzato ad ampliare l\u2019offerta professionale e soddisfare al meglio i bisogni di assistenza legale, giudiziale e stragiudiziale, dei Clienti, nelle molteplici aree del diritto.<\/p>\n<p>La storia dei singoli Professionisti di C-14 Avvocati \u00e8 un percorso di esperienza che si snoda in centinaia di casi gestiti nell\u2019ambito del diritto civile \u2013 nelle sue molteplici aree di intervento \u2013 del diritto amministrativo \u2013 con particolare riguardo ai contratti pubblici ed all\u2019edilizia-urbanistica \u2013 e del diritto penale.<br \/>C-14 Avvocati \u00e8 un progetto aperto alla crescita, alla compartecipazione di altri Professionisti, non fisicamente collocati presso l\u2019attuale struttura, che gi\u00e0 collaborano, in via continuativa e stabile, ciascuno con la propria specifica capacit\u00e0 e competenza, con gli Avvocati Fondatori del progetto.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.76)&#8221; background_color_gradient_end=&#8221;#000000&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/avvocati-c14-slide-6.jpg&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;2vw||2vw||true|false&#8221; background_last_edited=&#8221;on|tablet&#8221; background_position_tablet=&#8221;top_left&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|200|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>I professionisti<\/h1>\n<p>Clicca le voci per scoprire di pi\u00f9<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/dario-galliani.jpg&#8221; title_text=&#8221;dario-galliani&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_blur=&#8221;7px&#8221; box_shadow_spread=&#8221;-5px&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;Poppins|300|||||||&#8221; link_text_align=&#8221;center&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;30px&#8221; link_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;-20px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; link_font_size_tablet=&#8221;25px&#8221; link_font_size_phone=&#8221;&#8221; link_font_size_last_edited=&#8221;on|tablet&#8221; text_text_color__hover_enabled=&#8221;off|desktop&#8221; text_text_color__hover=&#8221;#871028&#8243; link_text_color__hover=&#8221;#FFFFFF&#8221; link_text_color__hover_enabled=&#8221;off|hover&#8221; link_font_size__hover_enabled=&#8221;on|desktop&#8221; link_font_size__hover=&#8221;32px&#8221;]<\/p>\n<p><a href=\"http:\/\/www.c14avvocati.it\/dario-galliani\/\">Dario A. Galliani<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/luca-fontana.jpg&#8221; title_text=&#8221;luca-fontana&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_blur=&#8221;7px&#8221; box_shadow_spread=&#8221;-5px&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;Poppins|300|||||||&#8221; link_text_align=&#8221;center&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;30px&#8221; link_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;-20px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; link_font_size_tablet=&#8221;25px&#8221; link_font_size_phone=&#8221;&#8221; link_font_size_last_edited=&#8221;on|tablet&#8221; text_text_color__hover_enabled=&#8221;off|desktop&#8221; text_text_color__hover=&#8221;#871028&#8243; link_text_color__hover=&#8221;#47080e&#8221; link_text_color__hover_enabled=&#8221;off|desktop&#8221; link_font_size__hover=&#8221;32px&#8221; link_font_size__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p><a href=\"http:\/\/www.c14avvocati.it\/luca-fontana\/\">Luca Fontana<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/matteo-bianchini.jpg&#8221; title_text=&#8221;matteo-bianchini&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_blur=&#8221;7px&#8221; box_shadow_spread=&#8221;-5px&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;Poppins|300|||||||&#8221; link_text_align=&#8221;center&#8221; link_text_color=&#8221;#FFFFFF&#8221; link_font_size=&#8221;30px&#8221; link_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;-20px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; link_font_size_tablet=&#8221;25px&#8221; link_font_size_phone=&#8221;&#8221; link_font_size_last_edited=&#8221;on|tablet&#8221; text_text_color__hover_enabled=&#8221;off|desktop&#8221; text_text_color__hover=&#8221;#871028&#8243; link_text_color__hover=&#8221;#47080e&#8221; link_text_color__hover_enabled=&#8221;off|desktop&#8221; link_font_size__hover=&#8221;32px&#8221; link_font_size__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p><a href=\"http:\/\/www.c14avvocati.it\/matteo-bianchini\/\">Matteo Bianchini<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;4vw||4vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#871028&#8243; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Aree di Intervento<\/h1>\n<p>C-14 Avvocati si propone di offrire assistenza a Societ\u00e0, Professionisti, Privati per ogni loro esigenza legata al mondo del diritto, secondo criteri di eccellenza.<\/p>\n<p>I Professionisti di C-14 Avvocati prestano assistenza in tutte le aree del diritto civile, del diritto d\u2019impresa e commerciale, del diritto del lavoro, del diritto bancario, del diritto societario e industriale, del diritto della crisi di impresa e da sovraindebitamento, della volontaria giurisdizione e del diritto di famiglia, del diritto penale (con particolare riguardo ai reati informatici), del diritto amministrativo (dei contratti pubblici e dell\u2019edilizia-urbanistica), sia in ambito giudiziale che stragiudiziale.<\/p>\n<p>Il tutto, secondo l\u2019esperienza maturata da ciascun Professionista di C-14 Avvocati nelle differenti aree del diritto, come meglio esplicitato nei rispettivi e consultabili profili professionali.<\/p>\n<p>C-14 Avvocati \u00e8 in grado di operare sull\u2019intero territorio nazionale, direttamente tramite i Fondatori o tramite stabili e consolidate collaborazioni.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(86,10,19,0.72)&#8221; background_color_gradient_end=&#8221;#3a050a&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/6_1.jpg&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;60px&#8221; header_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Trattamento riservato su presentazione tessera<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;20px||||false|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#871028&#8243; header_font_size=&#8221;50px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-professionisti&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 14px; line-height: 26px\"><!-- [et_pb_line_break_holder] --><br \/><p><strong>Indirizzo:<\/strong> Via G. Carcano, 14, 22063 Cant\u00f9 CO, Italia <br>\n<strong>Telefono:<\/strong> 031 3517026 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.c14avvocati.it\">www.c14avvocati.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:segreteria@c14avvocati.it\">segreteria@c14avvocati.it<\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221;]<div id=\"gmw-single-location-wrapper-468\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"43688\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-468\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-468\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-468\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-468\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"468\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;15px||||false|false&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-197\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-197\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-197\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-197\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-197\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"197\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>La nostra storia<\/p>\n<p>C-14 Avvocati \u00e8 un progetto che nasce nel 2018 dall\u2019incontro e dall\u2019idea di condivisione e messa a disposizione, in una sede unitaria, delle differenti esperienze e della professionalit\u00e0 di tre Avvocati, maturate ed acquisite nel corso di una loro gi\u00e0 ultraventennale esperienza e collaborazione, finalizzato ad ampliare l\u2019offerta professionale e soddisfare al meglio i bisogni di assistenza legale, giudiziale e stragiudiziale, dei Clienti, nelle molteplici aree del diritto.<\/p>\n<p>La storia dei singoli Professionisti di C-14 Avvocati \u00e8 un percorso di esperienza che si snoda in centinaia di casi gestiti nell\u2019ambito del diritto civile \u2013 nelle sue molteplici aree di intervento \u2013 del diritto amministrativo \u2013 con particolare riguardo ai contratti pubblici ed all\u2019edilizia-urbanistica \u2013 e del diritto penale.<br \/>\nC-14 Avvocati \u00e8 un progetto aperto alla crescita, alla compartecipazione di altri Professionisti, non fisicamente collocati presso l\u2019attuale struttura, che gi\u00e0 collaborano, in via continuativa e stabile, ciascuno con la propria specifica capacit\u00e0 e competenza, con gli Avvocati Fondatori del progetto.<\/p>\n<p>C-14 Avvocati si propone di offrire assistenza a Societ\u00e0, Professionisti, Privati per ogni loro esigenza legata al mondo del diritto, secondo criteri di eccellenza.<\/p>\n<p>I Professionisti di C-14 Avvocati prestano assistenza in tutte le aree del diritto civile, del diritto d\u2019impresa e commerciale, del diritto del lavoro, del diritto bancario, del diritto societario e industriale, del diritto della crisi di impresa e da sovraindebitamento, della volontaria giurisdizione e del diritto di famiglia, del diritto penale (con particolare riguardo ai reati informatici), del diritto amministrativo (dei contratti pubblici e dell\u2019edilizia-urbanistica), sia in ambito giudiziale che stragiudiziale.<\/p>\n<p>Il tutto, secondo l\u2019esperienza maturata da ciascun Professionista di C-14 Avvocati nelle differenti aree del diritto, come meglio esplicitato nei rispettivi e consultabili profili professionali.<\/p>\n<p>C-14 Avvocati \u00e8 in grado di operare sull\u2019intero territorio nazionale, direttamente tramite i Fondatori o tramite stabili e consolidate collaborazioni.<\/p>\n<p>Avvocati , Avvocato, assistenza legale, assistenza giudiziale, assistenza stragiudiziale, diritto civile, diritto amministrativo, edilizia-urbanistica, diritto penale, diritto d\u2019impresa, diritto commerciale, diritto del lavoro, diritto bancario, diritto societario e industriale, diritto di famiglia, diritto penale, reati informatici, diritto amministrativo, studio legale, studi legali, <\/p>\n<\/div>\n","protected":false},"featured_media":43697,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[147,161],"product_tag":[5413,599,5414,371,370,478,5184,475,3076,5416,1633,639,476,5417,5415,5418,906,374],"class_list":{"0":"post-43688","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-professionisti-studi-consulenze","7":"product_cat-studi-legali","8":"product_tag-assistenza-giudiziale","9":"product_tag-assistenza-legale","10":"product_tag-assistenza-stragiudiziale","11":"product_tag-avvocati","12":"product_tag-avvocato","13":"product_tag-diritto-amministrativo","14":"product_tag-diritto-bancario","15":"product_tag-diritto-civile","16":"product_tag-diritto-commerciale","17":"product_tag-diritto-dimpresa","18":"product_tag-diritto-del-lavoro","19":"product_tag-diritto-di-famiglia","20":"product_tag-diritto-penale","21":"product_tag-diritto-societario-e-industriale","22":"product_tag-edilizia-urbanistica","23":"product_tag-reati-informatici","24":"product_tag-studi-legali","25":"product_tag-studio-legale","27":"first","28":"instock","29":"shipping-taxable","30":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Studio Legale C-14 Avvocati - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio Legale C-14 Avvocati - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"La nostra storia  C-14 Avvocati \u00e8 un progetto che nasce nel 2018 dall\u2019incontro e dall\u2019idea di condivisione e messa a disposizione, in una sede unitaria, delle differenti esperienze e della professionalit\u00e0 di tre Avvocati, maturate ed acquisite nel corso di una loro gi\u00e0 ultraventennale esperienza e collaborazione, finalizzato ad ampliare l\u2019offerta professionale e soddisfare al meglio i bisogni di assistenza legale, giudiziale e stragiudiziale, dei Clienti, nelle molteplici aree del diritto.  La storia dei singoli Professionisti di C-14 Avvocati \u00e8 un percorso di esperienza che si snoda in centinaia di casi gestiti nell\u2019ambito del diritto civile \u2013 nelle sue molteplici aree di intervento \u2013 del diritto amministrativo \u2013 con particolare riguardo ai contratti pubblici ed all\u2019edilizia-urbanistica \u2013 e del diritto penale. C-14 Avvocati \u00e8 un progetto aperto alla crescita, alla compartecipazione di altri Professionisti, non fisicamente collocati presso l\u2019attuale struttura, che gi\u00e0 collaborano, in via continuativa e stabile, ciascuno con la propria specifica capacit\u00e0 e competenza, con gli Avvocati Fondatori del progetto.   C-14 Avvocati si propone di offrire assistenza a Societ\u00e0, Professionisti, Privati per ogni loro esigenza legata al mondo del diritto, secondo criteri di eccellenza.  I Professionisti di C-14 Avvocati prestano assistenza in tutte le aree del diritto civile, del diritto d\u2019impresa e commerciale, del diritto del lavoro, del diritto bancario, del diritto societario e industriale, del diritto della crisi di impresa e da sovraindebitamento, della volontaria giurisdizione e del diritto di famiglia, del diritto penale (con particolare riguardo ai reati informatici), del diritto amministrativo (dei contratti pubblici e dell\u2019edilizia-urbanistica), sia in ambito giudiziale che stragiudiziale.  Il tutto, secondo l\u2019esperienza maturata da ciascun Professionista di C-14 Avvocati nelle differenti aree del diritto, come meglio esplicitato nei rispettivi e consultabili profili professionali.  C-14 Avvocati \u00e8 in grado di operare sull\u2019intero territorio nazionale, direttamente tramite i Fondatori o tramite stabili e consolidate collaborazioni.     Avvocati , Avvocato, assistenza legale, assistenza giudiziale, assistenza stragiudiziale, diritto civile, diritto amministrativo, edilizia-urbanistica, diritto penale, diritto d\u2019impresa, diritto commerciale, diritto del lavoro, diritto bancario, diritto societario e industriale, diritto di famiglia, diritto penale, reati informatici, diritto amministrativo, studio legale, studi legali,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-29T07:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/\",\"name\":\"Studio Legale C-14 Avvocati - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg\",\"datePublished\":\"2023-03-29T07:51:48+00:00\",\"dateModified\":\"2023-03-29T07:51:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Studio Legale C-14 Avvocati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio Legale C-14 Avvocati - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/","og_locale":"it_IT","og_type":"article","og_title":"Studio Legale C-14 Avvocati - UIL Polizia","og_description":"La nostra storia  C-14 Avvocati \u00e8 un progetto che nasce nel 2018 dall\u2019incontro e dall\u2019idea di condivisione e messa a disposizione, in una sede unitaria, delle differenti esperienze e della professionalit\u00e0 di tre Avvocati, maturate ed acquisite nel corso di una loro gi\u00e0 ultraventennale esperienza e collaborazione, finalizzato ad ampliare l\u2019offerta professionale e soddisfare al meglio i bisogni di assistenza legale, giudiziale e stragiudiziale, dei Clienti, nelle molteplici aree del diritto.  La storia dei singoli Professionisti di C-14 Avvocati \u00e8 un percorso di esperienza che si snoda in centinaia di casi gestiti nell\u2019ambito del diritto civile \u2013 nelle sue molteplici aree di intervento \u2013 del diritto amministrativo \u2013 con particolare riguardo ai contratti pubblici ed all\u2019edilizia-urbanistica \u2013 e del diritto penale. C-14 Avvocati \u00e8 un progetto aperto alla crescita, alla compartecipazione di altri Professionisti, non fisicamente collocati presso l\u2019attuale struttura, che gi\u00e0 collaborano, in via continuativa e stabile, ciascuno con la propria specifica capacit\u00e0 e competenza, con gli Avvocati Fondatori del progetto.   C-14 Avvocati si propone di offrire assistenza a Societ\u00e0, Professionisti, Privati per ogni loro esigenza legata al mondo del diritto, secondo criteri di eccellenza.  I Professionisti di C-14 Avvocati prestano assistenza in tutte le aree del diritto civile, del diritto d\u2019impresa e commerciale, del diritto del lavoro, del diritto bancario, del diritto societario e industriale, del diritto della crisi di impresa e da sovraindebitamento, della volontaria giurisdizione e del diritto di famiglia, del diritto penale (con particolare riguardo ai reati informatici), del diritto amministrativo (dei contratti pubblici e dell\u2019edilizia-urbanistica), sia in ambito giudiziale che stragiudiziale.  Il tutto, secondo l\u2019esperienza maturata da ciascun Professionista di C-14 Avvocati nelle differenti aree del diritto, come meglio esplicitato nei rispettivi e consultabili profili professionali.  C-14 Avvocati \u00e8 in grado di operare sull\u2019intero territorio nazionale, direttamente tramite i Fondatori o tramite stabili e consolidate collaborazioni.     Avvocati , Avvocato, assistenza legale, assistenza giudiziale, assistenza stragiudiziale, diritto civile, diritto amministrativo, edilizia-urbanistica, diritto penale, diritto d\u2019impresa, diritto commerciale, diritto del lavoro, diritto bancario, diritto societario e industriale, diritto di famiglia, diritto penale, reati informatici, diritto amministrativo, studio legale, studi legali,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/","og_site_name":"UIL Polizia","article_modified_time":"2023-03-29T07:51:55+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/","name":"Studio Legale C-14 Avvocati - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg","datePublished":"2023-03-29T07:51:48+00:00","dateModified":"2023-03-29T07:51:55+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_C-14-Avvocati-Galliani-Fontana-Bianchini.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/studio-legale-c-14-avvocati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Studio Legale C-14 Avvocati"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=43688"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/43697"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=43688"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=43688"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=43688"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=43688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}