{"id":43480,"date":"2023-03-23T09:31:21","date_gmt":"2023-03-23T08:31:21","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=43480"},"modified":"2023-03-27T15:31:11","modified_gmt":"2023-03-27T13:31:11","slug":"dott-ssa-cristina-moglie-fisioterapista","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/","title":{"rendered":"Dott.ssa Cristina Moglie &#8211; Fisioterapista"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; next_background_color=&#8221;#ffffff&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(12,170,206,0.34)&#8221; background_color_gradient_end=&#8221;#0caace&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/moglie-scaled.jpeg&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; custom_padding_tablet=&#8221;7vw||9vw||false|false&#8221; custom_padding_phone=&#8221;5vw||10vw||false|false&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_height=&#8221;70px&#8221; bottom_divider_height_tablet=&#8221;50px&#8221; bottom_divider_height_phone=&#8221;&#8221; bottom_divider_height_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|tablet&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; background_color_gradient_start_tablet=&#8221;rgba(12,170,206,0.61)&#8221; background_color_gradient_end_position_tablet=&#8221;88%&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;100px&#8221; header_2_font=&#8221;Work Sans|200|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;60px&#8221; header_font_size_tablet=&#8221;61px&#8221; header_font_size_phone=&#8221;45px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Dott.ssa Cristina Moglie<\/h1>\n<h2>Fisioterapista<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;10px||||false|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Work Sans||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_color=&#8221;#0caace&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h1>Chi sono<\/h1>\n<p>Mi chiamo Cristina Moglie, faccio la fisioterapista da 33 anni. In tutti questo anni ho frequentato corsi di formazione professionali fisioterapici e corsi di crescita personale e spirituale.<br \/>Mi sono sempre interessata al benessere non solo fisico ma anche pi\u00f9 profondo dell&#8217;essere umano.<\/p>\n<p>Il mio lavoro verte sul riequilibrio fisico ed energetico dell&#8217;essere umano visto nella sua globalit\u00e0.<\/p>\n<p>Durante i miei trattamenti fisioterapici utilizzo la musica rilassante e un diffusore con olii essenziali per la purificazione dell&#8217;aria.<\/p>\n<p>Ho frequentato questi corsi di specializzazione: terapia cranio sacrale, massaggio connettivale, terapia dei trigger pointer miofasciali, shiatsu, riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, pompages miofasciale, rieducazione ortopedica e neuromuscolare, tecnica aromatouch con olii essenziali.<\/p>\n<p>Effettuo anche trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/20230310_184203-scaled.jpg&#8221; title_text=&#8221;20230310_184203&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|40px|40px|40px|40px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_blur=&#8221;20px&#8221; box_shadow_spread=&#8221;-8px&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;80px|80px|80px|80px|true|true&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; custom_padding_phone=&#8221;50px|30px|50px|30px|true|true&#8221; custom_padding_tablet=&#8221;80px|80px|80px|80px|true|true&#8221; locked=&#8221;off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;1200px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][et_pb_column _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Work Sans||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_color=&#8221;#0caace&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Chi sono<\/h1>\n<p>Mi chiamo Cristina Moglie, faccio la fisioterapista da 33 anni. In tutti questo anni ho frequentato corsi di formazione professionali fisioterapici e corsi di crescita personale e spirituale.<br \/>Mi sono sempre interessata al benessere non solo fisico ma anche pi\u00f9 profondo dell&#8217;essere umano.<\/p>\n<p>Il mio lavoro verte sul riequilibrio fisico ed energetico dell&#8217;essere umano visto nella sua globalit\u00e0.<\/p>\n<p>Durante i miei trattamenti fisioterapici utilizzo la musica rilassante e un diffusore con olii essenziali per la purificazione dell&#8217;aria.<\/p>\n<p>Ho frequentato questi corsi di specializzazione: terapia cranio sacrale, massaggio connettivale, terapia dei trigger pointer miofasciali, shiatsu, riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, pompages miofasciale, rieducazione ortopedica e neuromuscolare, tecnica aromatouch con olii essenziali.<\/p>\n<p>Effettuo anche trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.<\/p>\n<p>Inoltre effettuo trattamento Bars sulla testa che va a sciogliere le cariche elettromagnetiche che si accumulano sulla testa a causa delle nostre preoccupazioni, ansie, distress..<\/p>\n<p>\u00c8 possibile prendere in affitto il macchinario dell&#8217;elettromagnetoterapia.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/123539313_579160926284631_2551562643983031209_n.jpg&#8221; title_text=&#8221;123539313_579160926284631_2551562643983031209_n&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|40px|40px|40px|40px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_blur=&#8221;20px&#8221; box_shadow_spread=&#8221;-8px&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#e7f3fd&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#d3e8e8&#8243; background_color_gradient_end=&#8221;#00a8ce&#8221; background_color_gradient_end_position=&#8221;71%&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; custom_padding_tablet=&#8221;6vw||6vw||true|false&#8221; custom_padding_phone=&#8221;8vw||8vw||true|false&#8221; top_divider_style=&#8221;wave2&#8243; top_divider_color=&#8221;#FFFFFF&#8221; top_divider_height=&#8221;70px&#8221; top_divider_height_tablet=&#8221;50px&#8221; top_divider_height_phone=&#8221;&#8221; top_divider_height_last_edited=&#8221;on|tablet&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_color=&#8221;#0096bc&#8221; bottom_divider_height=&#8221;70px&#8221; bottom_divider_height_tablet=&#8221;50px&#8221; bottom_divider_height_phone=&#8221;&#8221; bottom_divider_height_last_edited=&#8221;on|tablet&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;80px&#8221; header_line_height=&#8221;1.2em&#8221; header_font_size_tablet=&#8221;50px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.2em&#8221; header_font_size_tablet=&#8221;43px&#8221; header_font_size_phone=&#8221;33px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#0096bc&#8221; background_color_gradient_end=&#8221;#004366&#8243; custom_padding_tablet=&#8221;10px||||false|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Work Sans|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<p><strong><em>Effettuo anche trattamenti a domicilio.<\/em><\/strong><\/p>\n<p><strong>Indirizzo:<\/strong><span>\u00a0Via Jesi, 2, 60126 Ancona AN, Italia<\/span><br \/><strong>Telefono:<\/strong><span>\u00a0338 242 9478<\/span><br \/><strong>Mail:<\/strong><span>\u00a0<\/span><a href=\"mailto:cristina.moglie@virgilio.it\">cristina.moglie@virgilio.it<\/a><\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-15px||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/trattamentifisioterapici?locale=it_IT&#8221; icon_color=&#8221;#0b78b7&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_enable_color=&#8221;on&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; background__hover_enabled=&#8221;on|desktop&#8221; background_color__hover=&#8221;RGBA(0,0,0,0)&#8221; background_enable_color__hover=&#8221;on&#8221; icon_color__hover_enabled=&#8221;on|desktop&#8221; icon_color__hover=&#8221;#FFFFFF&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-100\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"43480\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-100\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-100\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-100\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-100\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"100\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-367\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-367\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-367\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-367\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-367\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"367\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Work Sans|300|||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Work Sans|200|||||||&#8221; header_text_color=&#8221;#0caace&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||45px||false|false&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style= \"font-family: 'Work sans', sans-serif; font-size: 15px; line-height: 25px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Via Jesi, 2, 60126 Ancona AN, Italia <br>\n<strong>Telefono:<\/strong> 338 242 9478 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:cristina.moglie@virgilio.it\">cristina.moglie@virgilio.it<\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/trattamentifisioterapici?locale=it_IT&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0caace&#8221; background_enable_color=&#8221;on&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#0caace&#8221; background__hover_enabled=&#8221;on|desktop&#8221; background_color__hover=&#8221;#FFFFFF&#8221; background_enable_color__hover=&#8221;on&#8221; icon_color__hover_enabled=&#8221;on|desktop&#8221; icon_color__hover=&#8221;#0caace&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-395\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"43480\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-395\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-395\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-395\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-395\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"395\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-321\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-321\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-321\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-321\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-321\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"321\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Chi sono<\/p>\n<p>Mi chiamo Cristina Moglie, faccio la fisioterapista da 33 anni. In tutti questo anni ho frequentato corsi di formazione professionali fisioterapici e corsi di crescita personale e spirituale.<br \/>\nMi sono sempre interessata al benessere non solo fisico ma anche pi\u00f9 profondo dell&#8217;essere umano.<\/p>\n<p>Il mio lavoro verte sul riequilibrio fisico ed energetico dell&#8217;essere umano visto nella sua globalit\u00e0.<\/p>\n<p>Durante i miei trattamenti fisioterapici utilizzo la musica rilassante e un diffusore con olii essenziali per la purificazione dell&#8217;aria.<\/p>\n<p>Ho frequentato questi corsi di specializzazione: terapia cranio sacrale, massaggio connettivale, terapia dei trigger pointer miofasciali, shiatsu riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, pompages miofasciale, rieducazione ortopedica e neuromuscolare, tecnica aromatouch con olii essenziali.<br \/>\nEffettuo anche trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.<\/p>\n<p>fisioterapista, fisioterapia, trattamenti fisioterapici, terapia cranio sacrale, massaggio connettivale, shiatsu, riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, rieducazione ortopedica e neuromuscolare, trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.<\/p>\n<\/div>\n","protected":false},"featured_media":43483,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,163],"product_tag":[5332,4268,447,365,610,1830,5329,4410,5330,4020,2916,1874,5331,3059,4266],"class_list":{"0":"post-43480","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-salute","8":"product_tag-elettromagnetoterapia","9":"product_tag-elettroterapia","10":"product_tag-fisioterapia","11":"product_tag-fisioterapista","12":"product_tag-laserterapia","13":"product_tag-linfodrenaggio-manuale","14":"product_tag-massaggio-connettivale","15":"product_tag-riabilitazione-respiratoria","16":"product_tag-rieducazione-ortopedica-e-neuromuscolare","17":"product_tag-riflessologia-plantare","18":"product_tag-shiatsu","19":"product_tag-terapia-cranio-sacrale","20":"product_tag-trattamenti-di-tecarterapia","21":"product_tag-trattamenti-fisioterapici","22":"product_tag-ultrasuonoterapia","24":"first","25":"instock","26":"shipping-taxable","27":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Cristina Moglie - Fisioterapista - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Cristina Moglie - Fisioterapista - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Chi sono  Mi chiamo Cristina Moglie, faccio la fisioterapista da 33 anni. In tutti questo anni ho frequentato corsi di formazione professionali fisioterapici e corsi di crescita personale e spirituale. Mi sono sempre interessata al benessere non solo fisico ma anche pi\u00f9 profondo dell&#039;essere umano.  Il mio lavoro verte sul riequilibrio fisico ed energetico dell&#039;essere umano visto nella sua globalit\u00e0.  Durante i miei trattamenti fisioterapici utilizzo la musica rilassante e un diffusore con olii essenziali per la purificazione dell&#039;aria.  Ho frequentato questi corsi di specializzazione: terapia cranio sacrale, massaggio connettivale, terapia dei trigger pointer miofasciali, shiatsu riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, pompages miofasciale, rieducazione ortopedica e neuromuscolare, tecnica aromatouch con olii essenziali. Effettuo anche trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.  fisioterapista, fisioterapia, trattamenti fisioterapici, terapia cranio sacrale, massaggio connettivale, shiatsu, riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, rieducazione ortopedica e neuromuscolare, trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T13:31:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/\",\"name\":\"Dott.ssa Cristina Moglie - Fisioterapista - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg\",\"datePublished\":\"2023-03-23T08:31:21+00:00\",\"dateModified\":\"2023-03-27T13:31:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Cristina Moglie &#8211; Fisioterapista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Cristina Moglie - Fisioterapista - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Cristina Moglie - Fisioterapista - UIL Polizia","og_description":"Chi sono  Mi chiamo Cristina Moglie, faccio la fisioterapista da 33 anni. In tutti questo anni ho frequentato corsi di formazione professionali fisioterapici e corsi di crescita personale e spirituale. Mi sono sempre interessata al benessere non solo fisico ma anche pi\u00f9 profondo dell'essere umano.  Il mio lavoro verte sul riequilibrio fisico ed energetico dell'essere umano visto nella sua globalit\u00e0.  Durante i miei trattamenti fisioterapici utilizzo la musica rilassante e un diffusore con olii essenziali per la purificazione dell'aria.  Ho frequentato questi corsi di specializzazione: terapia cranio sacrale, massaggio connettivale, terapia dei trigger pointer miofasciali, shiatsu riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, pompages miofasciale, rieducazione ortopedica e neuromuscolare, tecnica aromatouch con olii essenziali. Effettuo anche trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.  fisioterapista, fisioterapia, trattamenti fisioterapici, terapia cranio sacrale, massaggio connettivale, shiatsu, riflessologia plantare, riabilitazione respiratoria, linfodrenaggio manuale, rieducazione ortopedica e neuromuscolare, trattamenti di tecarterapia, laserterapia, elettromagnetoterapia, elettroterapia, ultrasuonoterapia.","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/","og_site_name":"UIL Polizia","article_modified_time":"2023-03-27T13:31:11+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/","name":"Dott.ssa Cristina Moglie - Fisioterapista - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg","datePublished":"2023-03-23T08:31:21+00:00","dateModified":"2023-03-27T13:31:11+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Cristina-Moglie.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-cristina-moglie-fisioterapista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Cristina Moglie &#8211; Fisioterapista"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=43480"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/43483"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=43480"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=43480"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=43480"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=43480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}