{"id":43312,"date":"2023-03-17T12:37:51","date_gmt":"2023-03-17T11:37:51","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=43312"},"modified":"2023-04-07T18:20:58","modified_gmt":"2023-04-07T16:20:58","slug":"c-p-s-s-centro-polidiagnostico-servizi-sanitari","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/","title":{"rendered":"C.P.S.S &#8211; Centro Polidiagnostico Servizi Sanitari"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#00660a&#8221; background_color_gradient_end=&#8221;#ffffff&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;50%&#8221; background_color_gradient_end_position=&#8221;0%&#8221; custom_padding=&#8221;||||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;20px||20px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/65df5038c8cc486aad538c48cb7c2c63mJSMB1spF5vdjcZw-0-scaled.jpg&#8221; title_text=&#8221;65df5038c8cc486aad538c48cb7c2c63mJSMB1spF5vdjcZw-0&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Chi siamo<\/h1>\n<p>Il <strong>CENTRO POLIDIAGNOSTICO<\/strong>, accreditato dal <strong>SSN<\/strong>, nasce nel 1968 come Laboratorio generale di base. Nel corso degli anni ha subito diversi cambiamenti, sia logistici che organizzativi, ma \u00e8 sempre stato all\u2019avanguardia in campo cittadino, attraverso una politica di aggiornamento scientifico del personale e tecnologico della strumentazione, con lo scopo di offrire il migliore servizio possibile al paziente.<\/p>\n<p>In quest\u2019ottica, l\u2019adesione, nel 2009, al Decreto Assessoriale di aggregazione dei laboratori privati convenzionati con il SSN ha portato alla riorganizzazione della struttura ed alla nascita del rinnovato <strong>CENTRO POLIDIAGNOSTICO SERVIZI SANITARI &#8211; CPSS<\/strong>, con l\u2019acquisizione di nuovi settori specialistici (<strong>Biologia Molecolare e Genetica &#8211; Ematologia<\/strong>) e l\u2019ammodernamento dei settori gi\u00e0 esistenti (<strong>Analisi Cliniche &#8211; Microbiologia<\/strong>).<\/p>\n<p>Il nostro laboratorio (certificato secondo la norma UNI EN ISO 9001 Ed. 2015) pone costante attenzione alla Qualit\u00e0, intesa come garanzia di una buona pratica di laboratorio, attenzione alle norme di sicurezza e realizzazione di un miglioramento continuo. A tale scopo il CPSS attua protocolli interni di controllo di qualit\u00e0, specifici per ogni settore, e aderisce annualmente a diversi programmi di Valutazione Esterna di Qualit\u00e0 (VEQ) organizzati in ambito regionale, nazionale ed internazionale.<\/p>\n<p>Accogliamo pazienti che giungono da ogni luogo della Sicilia per soddisfare le pi\u00f9 diverse esigenze in campo diagnostico: Informazione, accoglienza, ascolto e cortesia costituiscono le basi su cui costruire con loro un rapporto di fiducia duraturo.<\/p>\n<p>[\/et_pb_text][dsm_card_carousel slide_to_show=&#8221;2&#8243; arrows=&#8221;off&#8221; dots_active_color=&#8221;#13821a&#8221; dots_inactive_color=&#8221;rgba(19,130,26,0.33)&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221;][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/cpss-1.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/cpss-2-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/cpss-3-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/cpss-5-scaled.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/dsm_card_carousel_child][\/dsm_card_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|off|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; border_width_top=&#8221;3px&#8221; border_color_top=&#8221;#00ad11&#8243; border_color_bottom=&#8221;#00ad11&#8243; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;35px&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>I nostri settori<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#59cc55&#8243; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>CHIMICA CLINICA<\/strong><\/p>\n<p>La chimica clinica si occupa dello studio delle alterazioni biochimiche di natura patologica mediante l\u2019applicazione di tecniche analitiche, chimico-strumentali ed immunochimiche per effettuare determinazioni diagnostiche o di routine sui liquidi biologici (sangue, urine, ecc.).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00ad11&#8243; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>EMATOLOGIA<\/strong><\/p>\n<p>L\u2019Ematologia \u00e8 la branca della Medicina di Laboratorio che mediante lo studio del numero, della morfologia, della struttura chimica e della funzionalit\u00e0 delle cellule del sangue, permette di valutarne le alterazioni. Il laboratorio, inoltre, esegue i principali test della coagulazione per individuare possibili coagulopatie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00841a&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>IMMUNOLOGIA<\/strong><\/p>\n<p>L\u2019immunologia si occupa delle funzioni fisiologiche del sistema immunitario (e dei suoi componenti) sia durante una malattia che in condizioni di salute, cos\u00ec come del suo malfunzionamento come nelle malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie e trapianti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00540b&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>MICROBIOLOGIA<\/strong><\/p>\n<p>La Microbiologia \u00e8 una disciplina della Medicina di Laboratorio che studia le patologie correlate alle infezioni causate da microrganismi (batteri, virus o parassiti).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00330b&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>GENETICA<\/strong><\/p>\n<p>Il settore di Genetica comprende la Citogenetica, che studia i cromosomi, e la Biologia Molecolare che utilizza test genetici per la diagnosi molecolare di alcune malattie ereditarie e per lo studio di alcuni geni associati ad un aumentato rischio di sviluppare patologie (medicina preventiva).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;45px||45px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;25px&#8221; text_line_height=&#8221;1.5em&#8221; link_font=&#8221;Poppins|600|||||||&#8221; link_text_color=&#8221;#13821a&#8221; link_font_size=&#8221;25px&#8221; link_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; locked=&#8221;off&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#08440d&#8221;]<\/p>\n<p>Scopri di pi\u00f9 sul nostro sito <br \/><a href=\"https:\/\/www.cpss.it\/il-laboratorio\/settori-laboratorio\/\">www.cpss.it\/il-laboratorio\/settori-laboratorio\/<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|on|off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; border_width_top=&#8221;3px&#8221; border_color_top=&#8221;#00ad11&#8243; border_color_bottom=&#8221;#00ad11&#8243; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;35px&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>I nostri settori<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#59cc55&#8243; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>CHIMICA CLINICA<\/strong><\/p>\n<p>La chimica clinica si occupa dello studio delle alterazioni biochimiche di natura patologica mediante l\u2019applicazione di tecniche analitiche, chimico-strumentali ed immunochimiche per effettuare determinazioni diagnostiche o di routine sui liquidi biologici (sangue, urine, ecc.).[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00ad11&#8243; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>EMATOLOGIA<\/strong><\/p>\n<p>L\u2019Ematologia \u00e8 la branca della Medicina di Laboratorio che mediante lo studio del numero, della morfologia, della struttura chimica e della funzionalit\u00e0 delle cellule del sangue, permette di valutarne le alterazioni. Il laboratorio, inoltre, esegue i principali test della coagulazione per individuare possibili coagulopatie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00841a&#8221; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>IMMUNOLOGIA<\/strong><\/p>\n<p>L\u2019immunologia si occupa delle funzioni fisiologiche del sistema immunitario (e dei suoi componenti) sia durante una malattia che in condizioni di salute, cos\u00ec come del suo malfunzionamento come nelle malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie e trapianti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00540b&#8221; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>MICROBIOLOGIA<\/strong><\/p>\n<p>La Microbiologia \u00e8 una disciplina della Medicina di Laboratorio che studia le patologie correlate alle infezioni causate da microrganismi (batteri, virus o parassiti).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00330b&#8221; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>GENETICA<\/strong><\/p>\n<p>Il settore di Genetica comprende la Citogenetica, che studia i cromosomi, e la Biologia Molecolare che utilizza test genetici per la diagnosi molecolare di alcune malattie ereditarie e per lo studio di alcuni geni associati ad un aumentato rischio di sviluppare patologie (medicina preventiva).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;45px||45px||true|false&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;Poppins||||||||&#8221; link_text_color=&#8221;#13821a&#8221; link_font_size=&#8221;20px&#8221; link_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|-20px||-20px|false|true&#8221; locked=&#8221;off&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#08440d&#8221;]<\/p>\n<p>Scopri di pi\u00f9 sul nostro sito <a href=\"https:\/\/www.cpss.it\/il-laboratorio\/settori-laboratorio\/\">www.cpss.it\/il-laboratorio\/settori-laboratorio\/<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.57)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0.82)&#8221; background_color_gradient_direction=&#8221;0deg&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/cpss2222.jpg&#8221; background_position=&#8221;top_right&#8221; custom_padding=&#8221;6vw||6vw||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; header_font_size_tablet=&#8221;38px&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/h1>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.2em&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||3px||false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#1ca891&#8243; header_font_size=&#8221;35px&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>I nostri servizi<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;on|off|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#42ceb0&#8243; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; link_option_url=&#8221;https:\/\/www.cpss.it\/#prenota-prelievo&#8221; link_option_url_new_window=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>PRENOTAZIONE ON LINE<\/strong><\/p>\n<p>Per evitare inutili attese, il laboratorio offre la possibilit\u00e0 di prenotare il prelievo comodamente da casa fissando giorno ed ora.<\/p>\n<p><a href=\"https:\/\/www.cpss.it\/#prenota-prelievo\"><u>Clicca qui per maggiori informazioni<\/u><\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#1ca891&#8243; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; link_option_url=&#8221;https:\/\/www.cpss.it\/servizi-ed-orari\/prelievi-a-domicilio\/&#8221; link_option_url_new_window=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>PRELIEVI A DOMICILIO<\/strong><\/p>\n<p>Il laboratorio offre la possibilit\u00e0 di effettuare il prelievo a domicilio, nell\u2019area metropolitana di Catania, inviando personale abilitato, dopo aver concordato ora e luogo.<\/p>\n<p><a href=\"https:\/\/www.cpss.it\/servizi-ed-orari\/prelievi-a-domicilio\/\"><u>Clicca qui per maggiori informazioni<\/u><\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#148770&#8243; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>REFERTI ON LINE<\/strong><\/p>\n<p>Il laboratorio offre gratuitamente la possibilit\u00e0 di ricevere i referti comodamente a casa scaricandoli dalla pagina dedicata del sito.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0e5e54&#8243; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; link_option_url=&#8221;https:\/\/www.cpss.it\/shop\/&#8221; link_option_url_new_window=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>ACQUISTO PACCHETTI<\/strong><\/p>\n<p>Il laboratorio offre la possibilit\u00e0 di scegliere fra diversi pacchetti check-up salute dedicati alla prevenzione.<\/p>\n<p><a href=\"https:\/\/www.cpss.it\/shop\/\"><u>Clicca qui per maggiori informazioni<\/u><\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|on|off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#42ceb0&#8243; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221; link_option_url=&#8221;https:\/\/www.cpss.it\/#prenota-prelievo&#8221; link_option_url_new_window=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>PRENOTAZIONE ON LINE<\/strong><\/p>\n<p>Per evitare inutili attese, il laboratorio offre la possibilit\u00e0 di prenotare il prelievo comodamente da casa fissando giorno ed ora.<\/p>\n<p><a href=\"https:\/\/www.cpss.it\/#prenota-prelievo\"><u>Clicca qui per maggiori informazioni<\/u><\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#1ca891&#8243; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221; link_option_url=&#8221;https:\/\/www.cpss.it\/servizi-ed-orari\/prelievi-a-domicilio\/&#8221; link_option_url_new_window=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>PRELIEVI A DOMICILIO<\/strong><\/p>\n<p>Il laboratorio offre la possibilit\u00e0 di effettuare il prelievo a domicilio, nell\u2019area metropolitana di Catania, inviando personale abilitato, dopo aver concordato ora e luogo.<\/p>\n<p><a href=\"https:\/\/www.cpss.it\/servizi-ed-orari\/prelievi-a-domicilio\/\"><u>Clicca qui per maggiori informazioni<\/u><\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#148770&#8243; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>REFERTI ON LINE<\/strong><\/p>\n<p>Il laboratorio offre gratuitamente la possibilit\u00e0 di ricevere i referti comodamente a casa scaricandoli dalla pagina dedicata del sito.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0e5e54&#8243; custom_padding=&#8221;70px|40px|70px|40px|true|true&#8221; link_option_url=&#8221;https:\/\/www.cpss.it\/shop\/&#8221; link_option_url_new_window=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;45px&#8221; text_orientation=&#8221;justified&#8221; locked=&#8221;off&#8221;]<strong>ACQUISTO PACCHETTI<\/strong><\/p>\n<p>Il laboratorio offre la possibilit\u00e0 di scegliere fra diversi pacchetti check-up salute dedicati alla prevenzione.<\/p>\n<p><a href=\"https:\/\/www.cpss.it\/shop\/\"><u>Clicca qui per maggiori informazioni<\/u><\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;Poppins||||||||&#8221; link_text_color=&#8221;#13821a&#8221; link_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;28px&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_line_height_tablet=&#8221;&#8221; header_line_height_phone=&#8221;1.2em&#8221; header_line_height_last_edited=&#8221;on|phone&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221; link_text_color__hover=&#8221;#0c540d&#8221;]<\/p>\n<h1>Contatti <strong>Punto prelievi Ipogeo<\/strong><\/h1>\n<p><strong>Indirizzo:<\/strong> Via Ipogeo, 30 &#8211; Catania<br \/><strong>Telefono:<\/strong> 095431298 &#8211; 095430288 &#8211; 095509431<br \/><strong>Sito web:<\/strong> <a href=\"https:\/\/www.cpss.it\/\">www.cpss.it<\/a><br \/><strong>Mail:<\/strong> <a href=\"mailto:info@cpss.it\">info@cpss.it<\/a><\/p>\n<p><strong>Orari di apertura:<\/strong><br \/>Lun &#8211; Ven: 7.15 &#8211; 12.30 \/ 15.00 &#8211; 18.00<br \/>Sab: 9.00 &#8211; 11.00 solo consegna dei referti<br \/><strong>Prelievi del sangue:<\/strong><br \/>Lun &#8211; Ven: 7.15 &#8211; 11.00<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;Poppins||||||||&#8221; link_text_color=&#8221;#13821a&#8221; link_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_color=&#8221;#13821a&#8221; header_font_size=&#8221;28px&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_line_height_tablet=&#8221;&#8221; header_line_height_phone=&#8221;1.2em&#8221; header_line_height_last_edited=&#8221;on|phone&#8221; link_text_color__hover=&#8221;#0c540d&#8221; link_text_color__hover_enabled=&#8221;on|desktop&#8221;]<\/p>\n<h1>Contatti <strong>Punto prelievi Italia<\/strong><\/h1>\n<p><strong>Indirizzo:<\/strong> Corso Italia, 171 &#8211; Catania<br \/><strong>Telefono:<\/strong> 095374140<br \/><strong>Sito web:<\/strong> <a href=\"https:\/\/www.cpss.it\/\">www.cpss.it<\/a><br \/><strong>Mail:<\/strong> <a href=\"mailto:info@cpss.it\">info@cpss.it<\/a><\/p>\n<p><strong>Orari di apertura:<\/strong><br \/>Lun &#8211; Ven: 7.30 &#8211; 11.30<br \/>Sab: 9.00 &#8211; 11.00 solo consegna dei referti<br \/><strong>Prelievi del sangue:<\/strong><br \/>Lun &#8211; Ven: 7.30 &#8211; 10.30<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-object-locations-wrapper-102\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-102\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-102\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-102\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-102\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"102\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e7f3fd&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Ipogeo, 30, 95123 Catania CT, Italia <br>\n<strong>Telefono:<\/strong> 095431298 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.cpss.it\">www.cpss.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:info@cpss.it\">info@cpss.it<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-431\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"43312\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-431\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-431\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-431\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-431\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"431\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-object-locations-wrapper-106\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-106\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-106\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-106\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-106\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"106\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>CHIMICA CLINICA<br \/>\nLa chimica clinica si occupa dello studio delle alterazioni biochimiche di natura patologica<br \/>\nmediante l\u2019applicazione di tecniche analitiche, chimico-strumentali ed immunochimiche per<br \/>\neffettuare determinazioni diagnostiche o di routine sui liquidi biologici (sangue, urine, ecc.).<\/p>\n<p>EMATOLOGIA<br \/>\nL\u2019Ematologia \u00e8 la branca della Medicina di Laboratorio che mediante lo studio del numero, della<br \/>\nmorfologia, della struttura chimica e della funzionalit\u00e0 delle cellule del sangue, permette di<br \/>\nvalutarne le alterazioni. Il laboratorio, inoltre, esegue i principali test della coagulazione per<br \/>\nindividuare possibili coagulopatie.<\/p>\n<p>IMMUNOLOGIA E SIEROLOGIA<br \/>\nL\u2019immunologia si occupa delle funzioni fisiologiche del sistema immunitario (e dei suoi<br \/>\ncomponenti) sia durante una malattia che in condizioni di salute, cos\u00ec come del suo<br \/>\nmalfunzionamento come nelle malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie e<br \/>\ntrapianti.<\/p>\n<p>MICROBIOLOGIA<br \/>\nLa Microbiologia \u00e8 una disciplina della Medicina di Laboratorio che studia le patologie correlate<br \/>\nalle infezioni causate da microrganismi (batteri, virus o parassiti).<\/p>\n<p>GENETICA<br \/>\nIl settore di Genetica comprende la Citogenetica, che studia i cromosomi, e la Biologia<br \/>\nMolecolare che utilizza test genetici per la diagnosi molecolare di alcune malattie ereditarie e<br \/>\nper lo studio di alcuni geni associati ad un aumentato rischio di sviluppare patologie (medicina<br \/>\npreventiva).<\/p>\n<p>PRENOTAZIONE ON LINE<br \/>\nPer evitare inutili attese, il laboratorio offre la possibilit\u00e0 di prenotare il prelievo comodamente da<br \/>\ncasa fissando giorno ed ora.<\/p>\n<p>PRELIEVI A DOMICILIO<br \/>\nIl laboratorio offre la possibilit\u00e0 di effettuare il prelievo a domicilio, nell\u2019area metropolitana di<br \/>\nCatania, inviando personale abilitato, dopo aver concordato ora e luogo.<\/p>\n<p>REFERTI ON LINE<br \/>\nIl laboratorio offre gratuitamente la possibilit\u00e0 di ricevere i referti comodamente a casa<br \/>\nscaricandoli dalla pagina dedicata del sito<\/p>\n<p>ACQUISTO PACCHETTI<br \/>\nIl laboratorio offre la possibilit\u00e0 di scegliere fra diversi pacchetti check-up salute dedicati alla<br \/>\nprevenzione.<\/p>\n<p>Chi siamo<\/p>\n<p>Il CENTRO POLIDIAGNOSTICO, accreditato dal SSN, nasce nel 1968 come Laboratorio generale di base. Nel corso degli anni ha subito diversi cambiamenti, sia logistici che organizzativi, ma \u00e8 sempre stato all\u2019avanguardia in campo cittadino, attraverso una politica di aggiornamento scientifico del personale e tecnologico della strumentazione, con lo scopo di offrire il migliore servizio possibile al paziente.<\/p>\n<p>In quest\u2019ottica, l\u2019adesione, nel 2009, al Decreto Assessoriale di aggregazione dei laboratori privati convenzionati con il SSN ha portato alla riorganizzazione della struttura ed alla nascita del rinnovato CENTRO POLIDIAGNOSTICO SERVIZI SANITARI &#8211; CPSS, con l\u2019acquisizione di nuovi settori specialistici (Biologia Molecolare e Genetica &#8211; Ematologia) e l\u2019ammodernamento dei settori gi\u00e0 esistenti (Analisi Cliniche &#8211; Microbiologia).<\/p>\n<p>Il nostro laboratorio (certificato secondo la norma UNI EN ISO 9001 Ed. 2015) pone costante attenzione alla Qualit\u00e0, intesa come garanzia di una buona pratica di laboratorio, attenzione alle norme di sicurezza e realizzazione di un miglioramento continuo. A tale scopo il CPSS attua protocolli interni di controllo di qualit\u00e0, specifici per ogni settore, e aderisce annualmente a diversi programmi di Valutazione Esterna di Qualit\u00e0 (VEQ) organizzati in ambito regionale, nazionale ed internazionale.<\/p>\n<p>Accogliamo pazienti che giungono da ogni luogo della Sicilia per soddisfare le pi\u00f9 diverse esigenze in campo diagnostico: Informazione, accoglienza, ascolto e cortesia costituiscono le basi su cui costruire con loro un rapporto di fiducia duraturo.<\/p>\n<p>Ematologia, laboratorio, immunologia , sistema immunitario, malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie, trapianti, Microbiologia , patologie, infezioni, virus, parassiti, Genetica, Citogenetica,, test genetici, diagnosi molecolare, malattie ereditarie, Analisi Cliniche,<\/p>\n<\/div>\n","protected":false},"featured_media":43314,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[168,3203,216,163],"product_tag":[2612,5263,5259,5264,467,5262,4612,4611,5258,2745,4616,5265,5224,5261,4407,5257,3332,4618,5260],"class_list":{"0":"post-43312","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-analisi","7":"product_cat-laboratori","8":"product_cat-laboratorio-analisi-cliniche","9":"product_cat-salute","10":"product_tag-analisi-cliniche","11":"product_tag-citogenetica","12":"product_tag-deficienze-immunitarie","13":"product_tag-diagnosi-molecolare","14":"product_tag-ematologia","15":"product_tag-genetica","16":"product_tag-immunologia","17":"product_tag-infezioni","18":"product_tag-ipersensitivita","19":"product_tag-laboratorio","20":"product_tag-malattie-autoimmuni","21":"product_tag-malattie-ereditarie","22":"product_tag-microbiologia","23":"product_tag-parassiti","24":"product_tag-patologie","25":"product_tag-sistema-immunitario","26":"product_tag-test-genetici","27":"product_tag-trapianti","28":"product_tag-virus","30":"first","31":"instock","32":"shipping-taxable","33":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C.P.S.S - Centro Polidiagnostico Servizi Sanitari - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C.P.S.S - Centro Polidiagnostico Servizi Sanitari - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"CHIMICA CLINICA La chimica clinica si occupa dello studio delle alterazioni biochimiche di natura patologica mediante l\u2019applicazione di tecniche analitiche, chimico-strumentali ed immunochimiche per effettuare determinazioni diagnostiche o di routine sui liquidi biologici (sangue, urine, ecc.).  EMATOLOGIA L\u2019Ematologia \u00e8 la branca della Medicina di Laboratorio che mediante lo studio del numero, della morfologia, della struttura chimica e della funzionalit\u00e0 delle cellule del sangue, permette di valutarne le alterazioni. Il laboratorio, inoltre, esegue i principali test della coagulazione per individuare possibili coagulopatie.  IMMUNOLOGIA E SIEROLOGIA L\u2019immunologia si occupa delle funzioni fisiologiche del sistema immunitario (e dei suoi componenti) sia durante una malattia che in condizioni di salute, cos\u00ec come del suo malfunzionamento come nelle malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie e trapianti.  MICROBIOLOGIA La Microbiologia \u00e8 una disciplina della Medicina di Laboratorio che studia le patologie correlate alle infezioni causate da microrganismi (batteri, virus o parassiti).  GENETICA Il settore di Genetica comprende la Citogenetica, che studia i cromosomi, e la Biologia Molecolare che utilizza test genetici per la diagnosi molecolare di alcune malattie ereditarie e per lo studio di alcuni geni associati ad un aumentato rischio di sviluppare patologie (medicina preventiva).  PRENOTAZIONE ON LINE Per evitare inutili attese, il laboratorio offre la possibilit\u00e0 di prenotare il prelievo comodamente da casa fissando giorno ed ora.  PRELIEVI A DOMICILIO Il laboratorio offre la possibilit\u00e0 di effettuare il prelievo a domicilio, nell\u2019area metropolitana di Catania, inviando personale abilitato, dopo aver concordato ora e luogo.  REFERTI ON LINE Il laboratorio offre gratuitamente la possibilit\u00e0 di ricevere i referti comodamente a casa scaricandoli dalla pagina dedicata del sito  ACQUISTO PACCHETTI Il laboratorio offre la possibilit\u00e0 di scegliere fra diversi pacchetti check-up salute dedicati alla prevenzione.  Chi siamo  Il CENTRO POLIDIAGNOSTICO, accreditato dal SSN, nasce nel 1968 come Laboratorio generale di base. Nel corso degli anni ha subito diversi cambiamenti, sia logistici che organizzativi, ma \u00e8 sempre stato all\u2019avanguardia in campo cittadino, attraverso una politica di aggiornamento scientifico del personale e tecnologico della strumentazione, con lo scopo di offrire il migliore servizio possibile al paziente.  In quest\u2019ottica, l\u2019adesione, nel 2009, al Decreto Assessoriale di aggregazione dei laboratori privati convenzionati con il SSN ha portato alla riorganizzazione della struttura ed alla nascita del rinnovato CENTRO POLIDIAGNOSTICO SERVIZI SANITARI - CPSS, con l\u2019acquisizione di nuovi settori specialistici (Biologia Molecolare e Genetica - Ematologia) e l\u2019ammodernamento dei settori gi\u00e0 esistenti (Analisi Cliniche - Microbiologia).  Il nostro laboratorio (certificato secondo la norma UNI EN ISO 9001 Ed. 2015) pone costante attenzione alla Qualit\u00e0, intesa come garanzia di una buona pratica di laboratorio, attenzione alle norme di sicurezza e realizzazione di un miglioramento continuo. A tale scopo il CPSS attua protocolli interni di controllo di qualit\u00e0, specifici per ogni settore, e aderisce annualmente a diversi programmi di Valutazione Esterna di Qualit\u00e0 (VEQ) organizzati in ambito regionale, nazionale ed internazionale.  Accogliamo pazienti che giungono da ogni luogo della Sicilia per soddisfare le pi\u00f9 diverse esigenze in campo diagnostico: Informazione, accoglienza, ascolto e cortesia costituiscono le basi su cui costruire con loro un rapporto di fiducia duraturo.  Ematologia, laboratorio, immunologia , sistema immunitario, malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie, trapianti, Microbiologia , patologie, infezioni, virus, parassiti, Genetica, Citogenetica,, test genetici, diagnosi molecolare, malattie ereditarie, Analisi Cliniche,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-07T16:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/\",\"name\":\"C.P.S.S - Centro Polidiagnostico Servizi Sanitari - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg\",\"datePublished\":\"2023-03-17T11:37:51+00:00\",\"dateModified\":\"2023-04-07T16:20:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C.P.S.S &#8211; Centro Polidiagnostico Servizi Sanitari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C.P.S.S - Centro Polidiagnostico Servizi Sanitari - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/","og_locale":"it_IT","og_type":"article","og_title":"C.P.S.S - Centro Polidiagnostico Servizi Sanitari - UIL Polizia","og_description":"CHIMICA CLINICA La chimica clinica si occupa dello studio delle alterazioni biochimiche di natura patologica mediante l\u2019applicazione di tecniche analitiche, chimico-strumentali ed immunochimiche per effettuare determinazioni diagnostiche o di routine sui liquidi biologici (sangue, urine, ecc.).  EMATOLOGIA L\u2019Ematologia \u00e8 la branca della Medicina di Laboratorio che mediante lo studio del numero, della morfologia, della struttura chimica e della funzionalit\u00e0 delle cellule del sangue, permette di valutarne le alterazioni. Il laboratorio, inoltre, esegue i principali test della coagulazione per individuare possibili coagulopatie.  IMMUNOLOGIA E SIEROLOGIA L\u2019immunologia si occupa delle funzioni fisiologiche del sistema immunitario (e dei suoi componenti) sia durante una malattia che in condizioni di salute, cos\u00ec come del suo malfunzionamento come nelle malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie e trapianti.  MICROBIOLOGIA La Microbiologia \u00e8 una disciplina della Medicina di Laboratorio che studia le patologie correlate alle infezioni causate da microrganismi (batteri, virus o parassiti).  GENETICA Il settore di Genetica comprende la Citogenetica, che studia i cromosomi, e la Biologia Molecolare che utilizza test genetici per la diagnosi molecolare di alcune malattie ereditarie e per lo studio di alcuni geni associati ad un aumentato rischio di sviluppare patologie (medicina preventiva).  PRENOTAZIONE ON LINE Per evitare inutili attese, il laboratorio offre la possibilit\u00e0 di prenotare il prelievo comodamente da casa fissando giorno ed ora.  PRELIEVI A DOMICILIO Il laboratorio offre la possibilit\u00e0 di effettuare il prelievo a domicilio, nell\u2019area metropolitana di Catania, inviando personale abilitato, dopo aver concordato ora e luogo.  REFERTI ON LINE Il laboratorio offre gratuitamente la possibilit\u00e0 di ricevere i referti comodamente a casa scaricandoli dalla pagina dedicata del sito  ACQUISTO PACCHETTI Il laboratorio offre la possibilit\u00e0 di scegliere fra diversi pacchetti check-up salute dedicati alla prevenzione.  Chi siamo  Il CENTRO POLIDIAGNOSTICO, accreditato dal SSN, nasce nel 1968 come Laboratorio generale di base. Nel corso degli anni ha subito diversi cambiamenti, sia logistici che organizzativi, ma \u00e8 sempre stato all\u2019avanguardia in campo cittadino, attraverso una politica di aggiornamento scientifico del personale e tecnologico della strumentazione, con lo scopo di offrire il migliore servizio possibile al paziente.  In quest\u2019ottica, l\u2019adesione, nel 2009, al Decreto Assessoriale di aggregazione dei laboratori privati convenzionati con il SSN ha portato alla riorganizzazione della struttura ed alla nascita del rinnovato CENTRO POLIDIAGNOSTICO SERVIZI SANITARI - CPSS, con l\u2019acquisizione di nuovi settori specialistici (Biologia Molecolare e Genetica - Ematologia) e l\u2019ammodernamento dei settori gi\u00e0 esistenti (Analisi Cliniche - Microbiologia).  Il nostro laboratorio (certificato secondo la norma UNI EN ISO 9001 Ed. 2015) pone costante attenzione alla Qualit\u00e0, intesa come garanzia di una buona pratica di laboratorio, attenzione alle norme di sicurezza e realizzazione di un miglioramento continuo. A tale scopo il CPSS attua protocolli interni di controllo di qualit\u00e0, specifici per ogni settore, e aderisce annualmente a diversi programmi di Valutazione Esterna di Qualit\u00e0 (VEQ) organizzati in ambito regionale, nazionale ed internazionale.  Accogliamo pazienti che giungono da ogni luogo della Sicilia per soddisfare le pi\u00f9 diverse esigenze in campo diagnostico: Informazione, accoglienza, ascolto e cortesia costituiscono le basi su cui costruire con loro un rapporto di fiducia duraturo.  Ematologia, laboratorio, immunologia , sistema immunitario, malattie autoimmuni, ipersensitivit\u00e0, deficienze immunitarie, trapianti, Microbiologia , patologie, infezioni, virus, parassiti, Genetica, Citogenetica,, test genetici, diagnosi molecolare, malattie ereditarie, Analisi Cliniche,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/","og_site_name":"UIL Polizia","article_modified_time":"2023-04-07T16:20:58+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"21 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/","name":"C.P.S.S - Centro Polidiagnostico Servizi Sanitari - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg","datePublished":"2023-03-17T11:37:51+00:00","dateModified":"2023-04-07T16:20:58+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_cpss-Centro-Polidiagnostico-Servizi-Sanitari.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/c-p-s-s-centro-polidiagnostico-servizi-sanitari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"C.P.S.S &#8211; Centro Polidiagnostico Servizi Sanitari"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=43312"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/43314"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=43312"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=43312"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=43312"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=43312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}