{"id":43095,"date":"2023-03-14T10:01:31","date_gmt":"2023-03-14T09:01:31","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=43095"},"modified":"2023-05-05T10:27:06","modified_gmt":"2023-05-05T08:27:06","slug":"dott-ssa-sara-papadia-psicologa-e-psicoterapeuta","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/","title":{"rendered":"Dott.ssa Sara Papadia &#8211; Psicologa e Psicoterapeuta"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(101,165,135,0.35)&#8221; background_color_gradient_end=&#8221;#65a587&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/pp-scaled.jpeg&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; custom_padding_tablet=&#8221;7vw||11vw||false|false&#8221; custom_padding_phone=&#8221;5vw||17vw||false|false&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_color=&#8221;#FFFFFF&#8221; bottom_divider_height=&#8221;70px&#8221; bottom_divider_height_tablet=&#8221;&#8221; bottom_divider_height_phone=&#8221;&#8221; bottom_divider_height_last_edited=&#8221;on|desktop&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;80px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;Poppins|200||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;30px&#8221; header_2_letter_spacing=&#8221;9px&#8221; header_font_size_tablet=&#8221;76px&#8221; header_font_size_phone=&#8221;36px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;26px&#8221; header_2_font_size_phone=&#8221;15px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_2_letter_spacing_tablet=&#8221;8px&#8221; header_2_letter_spacing_phone=&#8221;4px&#8221; header_2_letter_spacing_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Dott.Ssa Sara Papadia<\/h1>\n<h2>Psicologa e Psicoterapeuta<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/DSC9995-scaled.jpeg&#8221; title_text=&#8221;_DSC9995&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;-10px&#8221; box_shadow_blur=&#8221;11px&#8221; box_shadow_spread=&#8221;-9px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.67)&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|300||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#65a587&#8243; header_font_size=&#8221;50px&#8221; header_letter_spacing=&#8221;7px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;4vw||||false|false&#8221;]<\/p>\n<h1>Chi sono<\/h1>\n<p>Sono una psicologa Clinica e psicoterapeuta sistemico relazionale.<\/p>\n<p>Dopo la laurea in Psicologia Clinica: Salute, Relazioni familiari e Interventi di comunit\u00e0 presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Milano, mi sono specializzata in Psicoterapia ad orientamento Individuale-Familiare, un approccio sistemico relazionale integrato, presso la Scuola di Specializzazione Mara Selvini Palazzoli di Milano.<\/p>\n<p>Opero nella convinzione che lo sguardo clinico debba rivolgersi, oltre che alla persona direttamente coinvolta nel percorso, anche alle sue relazioni, a partire da quelle in ambito familiare, nell\u2019assunto che la matrice del funzionamento individuale e le risorse utili al cambiamento siano da ricercare proprio in queste.<\/p>\n<p>Sono abilitata all\u2019utilizzo della tecnica dell\u2019E.M.D.R. a supporto e in integrazione al percorso terapeutico, in caso di eventi traumatici (es. lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0).<\/p>\n<p>Offro consulenza e percorsi di psicoterapia ad individui, coppie e famiglie per coloro che sperimentano difficolt\u00e0 esistenziali, problematiche di coppia (es. crisi, separazioni, tematiche procreative, sfide genitoriali), criticit\u00e0 legate al ciclo di vita.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|300||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#65a587&#8243; header_font_size=&#8221;40px&#8221; header_letter_spacing=&#8221;5px&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_letter_spacing_tablet=&#8221;&#8221; header_letter_spacing_phone=&#8221;3px&#8221; header_letter_spacing_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h1>Chi sono<\/h1>\n<p>Sono una psicologa Clinica e psicoterapeuta sistemico relazionale.<\/p>\n<p>Dopo la laurea in Psicologia Clinica: Salute, Relazioni familiari e Interventi di comunit\u00e0 presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Milano, mi sono specializzata in Psicoterapia ad orientamento Individuale-Familiare, un approccio sistemico relazionale integrato, presso la Scuola di Specializzazione Mara Selvini Palazzoli di Milano.<\/p>\n<p>Opero nella convinzione che lo sguardo clinico debba rivolgersi, oltre che alla persona direttamente coinvolta nel percorso, anche alle sue relazioni, a partire da quelle in ambito familiare, nell\u2019assunto che la matrice del funzionamento individuale e le risorse utili al cambiamento siano da ricercare proprio in queste.<\/p>\n<p>Sono abilitata all\u2019utilizzo della tecnica dell\u2019E.M.D.R. a supporto e in integrazione al percorso terapeutico, in caso di eventi traumatici (es. lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0).<\/p>\n<p>Offro consulenza e percorsi di psicoterapia ad individui, coppie e famiglie per coloro che sperimentano difficolt\u00e0 esistenziali, problematiche di coppia (es. crisi, separazioni, tematiche procreative, sfide genitoriali), criticit\u00e0 legate al ciclo di vita.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/DSC9995-scaled.jpeg&#8221; title_text=&#8221;_DSC9995&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_blur=&#8221;5px&#8221; box_shadow_spread=&#8221;-10px&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#e7f3fd&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(101,165,135,0.56)&#8221; background_color_gradient_end=&#8221;#65a587&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/pp2.jpg&#8221; custom_padding=&#8221;6vw||6vw||true|false&#8221; custom_padding_tablet=&#8221;9vw||9vw||true|false&#8221; custom_padding_phone=&#8221;12vw||12vw||true|false&#8221; top_divider_style=&#8221;mountains2&#8243; top_divider_color=&#8221;#FFFFFF&#8221; top_divider_height=&#8221;70px&#8221; top_divider_height_tablet=&#8221;&#8221; top_divider_height_phone=&#8221;&#8221; top_divider_height_last_edited=&#8221;on|desktop&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_color=&#8221;#FFFFFF&#8221; bottom_divider_height=&#8221;70px&#8221; bottom_divider_height_tablet=&#8221;&#8221; bottom_divider_height_phone=&#8221;&#8221; bottom_divider_height_last_edited=&#8221;on|desktop&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;80px&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_line_height_tablet=&#8221;1.2em&#8221; header_line_height_phone=&#8221;&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|200|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;66px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|300||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#65a587&#8243; header_font_size=&#8221;45px&#8221; header_letter_spacing=&#8221;5px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||45px||false|false&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_letter_spacing_tablet=&#8221;3px&#8221; header_letter_spacing_phone=&#8221;2px&#8221; header_letter_spacing_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 14px; line-height: 26px\"><!-- [et_pb_line_break_holder] --><br \/><p><strong>Indirizzo:<\/strong> Via Paracelso, 6, 20129 Milano MI, Italia <br>\n<strong>Telefono:<\/strong> 3388144358 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:sara.papadia@gmail.com\">sara.papadia@gmail.com<\/a> \n<\/p><br \/>  <!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-312\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"43095\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-312\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-312\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-312\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-312\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"312\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-304\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-304\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-304\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-304\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-304\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"304\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Chi sono<\/p>\n<p>Sono una psicologa Clinica e psicoterapeuta sistemico relazionale.<\/p>\n<p>Dopo la laurea in Psicologia Clinica: Salute, Relazioni familiari e Interventi di comunit\u00e0 presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Milano, mi sono specializzata in Psicoterapia ad orientamento Individuale-Familiare, un approccio sistemico relazionale integrato, presso la Scuola di Specializzazione Mara Selvini Palazzoli di Milano.<\/p>\n<p>Opero nella convinzione che lo sguardo clinico debba rivolgersi, oltre che alla persona direttamente coinvolta nel percorso, anche alle sue relazioni, a partire da quelle in ambito familiare, nell\u2019assunto che la matrice del funzionamento individuale e le risorse utili al cambiamento siano da ricercare proprio in queste.<\/p>\n<p>Sono abilitata all\u2019utilizzo della tecnica dell\u2019E.M.D.R. a supporto e in integrazione al percorso terapeutico, in caso di eventi traumatici (es. lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0).<\/p>\n<p>Offro consulenza e percorsi di psicoterapia ad individui, coppie e famiglie per coloro che sperimentano difficolt\u00e0 esistenziali, problematiche di coppia (es. crisi, separazioni, tematiche procreative, sfide genitoriali), criticit\u00e0 legate al ciclo di vita.<\/p>\n<p>psicologa Clinica, psicoterapeuta sistemico relazionale, Relazioni familiari, percorso terapeutico, eventi traumatici, lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0, consulenza, percorsi di psicoterapia ad individui, coppie, famiglie, difficolt\u00e0 esistenziali, problematiche di coppia, separazioni, tematiche procreative, sfide genitoriali, criticit\u00e0 legate al ciclo di vita<\/p>\n<\/div>\n","protected":false},"featured_media":43100,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,258,163],"product_tag":[653,4900,5210,5205,4357,5206,5203,3189,2581,5207,1583,4902,658,5202,2573,1748,5209,5208,5204],"class_list":{"0":"post-43095","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-psicoterapeuti","8":"product_cat-salute","9":"product_tag-consulenza","10":"product_tag-coppie","11":"product_tag-criticita-legate-al-ciclo-di-vita","12":"product_tag-diagnosi-infauste","13":"product_tag-difficolta-esistenziali","14":"product_tag-eventi-stravolgenti-la-quotidianita","15":"product_tag-eventi-traumatici","16":"product_tag-famiglie","17":"product_tag-lutti","18":"product_tag-percorsi-di-psicoterapia-ad-individui","19":"product_tag-percorso-terapeutico","20":"product_tag-problematiche-di-coppia","21":"product_tag-psicologa-clinica","22":"product_tag-psicoterapeuta-sistemico-relazionale","23":"product_tag-relazioni-familiari","24":"product_tag-separazioni","25":"product_tag-sfide-genitoriali","26":"product_tag-tematiche-procreative","27":"product_tag-violenze","29":"first","30":"instock","31":"shipping-taxable","32":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Sara Papadia - Psicologa e Psicoterapeuta - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Sara Papadia - Psicologa e Psicoterapeuta - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Chi sono  Sono una psicologa Clinica e psicoterapeuta sistemico relazionale.  Dopo la laurea in Psicologia Clinica: Salute, Relazioni familiari e Interventi di comunit\u00e0 presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Milano, mi sono specializzata in Psicoterapia ad orientamento Individuale-Familiare, un approccio sistemico relazionale integrato, presso la Scuola di Specializzazione Mara Selvini Palazzoli di Milano.  Opero nella convinzione che lo sguardo clinico debba rivolgersi, oltre che alla persona direttamente coinvolta nel percorso, anche alle sue relazioni, a partire da quelle in ambito familiare, nell\u2019assunto che la matrice del funzionamento individuale e le risorse utili al cambiamento siano da ricercare proprio in queste.  Sono abilitata all\u2019utilizzo della tecnica dell\u2019E.M.D.R. a supporto e in integrazione al percorso terapeutico, in caso di eventi traumatici (es. lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0).  Offro consulenza e percorsi di psicoterapia ad individui, coppie e famiglie per coloro che sperimentano difficolt\u00e0 esistenziali, problematiche di coppia (es. crisi, separazioni, tematiche procreative, sfide genitoriali), criticit\u00e0 legate al ciclo di vita.     psicologa Clinica, psicoterapeuta sistemico relazionale, Relazioni familiari, percorso terapeutico, eventi traumatici, lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0, consulenza, percorsi di psicoterapia ad individui, coppie, famiglie, difficolt\u00e0 esistenziali, problematiche di coppia, separazioni, tematiche procreative, sfide genitoriali, criticit\u00e0 legate al ciclo di vita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-05T08:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/\",\"name\":\"Dott.ssa Sara Papadia - Psicologa e Psicoterapeuta - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg\",\"datePublished\":\"2023-03-14T09:01:31+00:00\",\"dateModified\":\"2023-05-05T08:27:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Sara Papadia &#8211; Psicologa e Psicoterapeuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Sara Papadia - Psicologa e Psicoterapeuta - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Sara Papadia - Psicologa e Psicoterapeuta - UIL Polizia","og_description":"Chi sono  Sono una psicologa Clinica e psicoterapeuta sistemico relazionale.  Dopo la laurea in Psicologia Clinica: Salute, Relazioni familiari e Interventi di comunit\u00e0 presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Milano, mi sono specializzata in Psicoterapia ad orientamento Individuale-Familiare, un approccio sistemico relazionale integrato, presso la Scuola di Specializzazione Mara Selvini Palazzoli di Milano.  Opero nella convinzione che lo sguardo clinico debba rivolgersi, oltre che alla persona direttamente coinvolta nel percorso, anche alle sue relazioni, a partire da quelle in ambito familiare, nell\u2019assunto che la matrice del funzionamento individuale e le risorse utili al cambiamento siano da ricercare proprio in queste.  Sono abilitata all\u2019utilizzo della tecnica dell\u2019E.M.D.R. a supporto e in integrazione al percorso terapeutico, in caso di eventi traumatici (es. lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0).  Offro consulenza e percorsi di psicoterapia ad individui, coppie e famiglie per coloro che sperimentano difficolt\u00e0 esistenziali, problematiche di coppia (es. crisi, separazioni, tematiche procreative, sfide genitoriali), criticit\u00e0 legate al ciclo di vita.     psicologa Clinica, psicoterapeuta sistemico relazionale, Relazioni familiari, percorso terapeutico, eventi traumatici, lutti, violenze, diagnosi infauste, eventi stravolgenti la quotidianit\u00e0, consulenza, percorsi di psicoterapia ad individui, coppie, famiglie, difficolt\u00e0 esistenziali, problematiche di coppia, separazioni, tematiche procreative, sfide genitoriali, criticit\u00e0 legate al ciclo di vita","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/","og_site_name":"UIL Polizia","article_modified_time":"2023-05-05T08:27:06+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/","name":"Dott.ssa Sara Papadia - Psicologa e Psicoterapeuta - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg","datePublished":"2023-03-14T09:01:31+00:00","dateModified":"2023-05-05T08:27:06+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Sara-Papadia.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-sara-papadia-psicologa-e-psicoterapeuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Sara Papadia &#8211; Psicologa e Psicoterapeuta"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=43095"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/43095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/43100"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=43095"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=43095"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=43095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=43095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}