{"id":42723,"date":"2023-03-07T10:37:10","date_gmt":"2023-03-07T09:37:10","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=42723"},"modified":"2023-03-07T16:22:34","modified_gmt":"2023-03-07T15:22:34","slug":"dott-andrea-bellusci-otorino","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/","title":{"rendered":"Dott. Andrea Bellusci &#8211; Otorino"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; next_background_color=&#8221;#ffffff&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(39,135,198,0.26)&#8221; background_color_gradient_end=&#8221;#0091c1&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/Dott-Bellusci_2-scaled.jpeg&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; custom_padding_tablet=&#8221;9vw||13vw||false|false&#8221; custom_padding_phone=&#8221;10vw||16vw||false|false&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_height=&#8221;70px&#8221; background_last_edited=&#8221;on|phone&#8221; use_background_color_gradient_phone=&#8221;on&#8221; background_color_gradient_start_phone=&#8221;rgba(39,135,198,0.74)&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Playfair Display|900||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;75px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;Playfair Display|600|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;30px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Playfair Display||||||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;25px&#8221; header_3_letter_spacing=&#8221;1px&#8221; header_font_size_tablet=&#8221;49px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_letter_spacing_tablet=&#8221;0px&#8221; header_letter_spacing_phone=&#8221;&#8221; header_letter_spacing_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;25px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;20px&#8221; header_3_font_size_phone=&#8221;18px&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221; header_3_letter_spacing_tablet=&#8221;0px&#8221; header_3_letter_spacing_phone=&#8221;&#8221; header_3_letter_spacing_last_edited=&#8221;on|tablet&#8221; header_3_line_height_tablet=&#8221;&#8221; header_3_line_height_phone=&#8221;1.2em&#8221; header_3_line_height_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h1>Dott. Andrea Bellusci<\/h1>\n<h2>Medico Chirurgo<\/h2>\n<h3>Specialista in otorinolaringoiatria e chirurgia cervico-facciale<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;0px||0px||false|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; header_font=&#8221;Playfair Display|900||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#0091c1&#8243; header_font_size=&#8221;45px&#8221; header_letter_spacing=&#8221;1px&#8221; text_orientation=&#8221;justified&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Su di me<\/h1>\n<p>Sin dai primi anni del corso di laurea in medicina mi sono concentrato sullo studio del distretto testa e collo raffinando le mie conoscenze anatomiche grazie alla partecipazione ad una fellowship in \u201cgross anatomy\u201d c\\o new york university.<\/p>\n<p>Per tre anni (2008-2011) ho eseguito attivit\u00e0 di assistenza alla didattica c\/o dipartimento di anatomia normale dell\u2019universit\u00e0 di bologna e di tutoraggio agli studenti del cdl medicina e chirurgia.<\/p>\n<p>Ho conseguito la laurea in medicina e chirurgia nel luglio 2012 con la votazione di 110 su 110 e lode.<\/p>\n<p>Sin dall\u2019inizio della scuola di specialit\u00e0 in otorinolaringoiatria mi sono interessato a tutte le branche endoscopiche di questa disciplina e all\u2019oncologia testa e collo.<\/p>\n<p>In particolare mi sono dedicato allo studio della sindrome delle apnee ostruttive del sonno prendendo parte a tutta l\u2019attivit\u00e0 inerente c\/o la clinica otorinolaringologica dell\u2019universit\u00e0 di bologna, in particolare all\u2019ambulatorio endoscopico e alle sedute di drug induced sleep endoscopy.<br \/>Durante questo periodo ho acquisito ottima capacit\u00e0 di refertazione dei tracciati polisonnografici, questo percorso si \u00e8 concluso con la frequenza al master sio \u2013 aims \u201ceos-drs\u201d e con l\u2019acquisizione del titolo di \u201cmedico qualificato in disturbi respiratori ostruttivi in sonno\u201d.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Leggi di pi\u00f9&#8221; open_toggle_text_color=&#8221;#0091c1&#8243; open_toggle_background_color=&#8221;#FFFFFF&#8221; closed_toggle_background_color=&#8221;#FFFFFF&#8221; icon_color=&#8221;#0091c1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#0091c1&#8243; title_font=&#8221;Playfair Display|800||on|||||&#8221; title_text_align=&#8221;left&#8221; title_font_size=&#8221;20px&#8221; title_letter_spacing=&#8221;1px&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_color_all=&#8221;#0091c1&#8243; border_width_top=&#8221;8px&#8221; border_style_top=&#8221;double&#8221; border_width_right=&#8221;0px&#8221; border_width_bottom=&#8221;8px&#8221; border_style_bottom=&#8221;double&#8221; border_width_left=&#8221;0px&#8221;]<\/p>\n<p>Nei mesi della specialit\u00e0 passati presso l\u2019uoc orl area metropolitana di bologna e presso il centro di chirurgia ipofisaria dell\u2019ospedale bellaria ho approfondito la conoscenza della chirurgia endoscopica funzionale e oncologica del distretto rinosinusale e del basicranio anteriore. In particolare ho approfondito lo studio dei tumori dei seni paranasali e della basecranica partecipando attivamente a tutti gli incontri del team multidisciplinare, ai relativi ambulatori e alle sedute di sala operatoria, in questo ambito mi sono dedicato alla compilazione dei database di tutti i pz affetti da neoplasie della rinobase ed in particolare dei pz affetti da adenocarcinoma intestinal-type dell\u2019etmoide.<\/p>\n<p>Al fine di affinare la conoscenza in campo otologico e otoneurologico ho poi intrapreso una fellowship di 4 mesi presso il gruppo otologico del professor mario sanna, dove in qualit\u00e0 di medico specializzando ho partecipato attivamente a tutte le regolari attivit\u00e0 di sala, reparto e ambulatorio. Inoltre nello stesso periodo ho partecipato a molteplici corsi di dissezione in ambito otologico e sono stato co-organizzazione del primo corso di dissezione per soli specializzandi cui ho partecipato in qualit\u00e0 tutor, ruolo che ho mantenuto nei corsi a seguire.<\/p>\n<p>Ho conseguito la specializzazione in otorinolaringoiatria nell\u2019agosto 2018 con la votazione di 110 su 110 e lode.<\/p>\n<p>Fino a marzo 2019 ho prestato servizio come medico contrattista presso la clinica otorinolaringologica del policlinico sant\u2019orsola-malpighi.<\/p>\n<p>Attualmente sono in servizio come dirigente medico di i livello presso l\u2019uoc di otorinolaringoiatria dell\u2019ospedale maggiore di bologna dove partecipo attivamente a tutte le attivit\u00e0 ambulatoriali e di sala operatoria, attualmente ho all\u2019attivo oltre 1000 interventi come primo operatore su tutti i livelli del distretto otorinolaringoiatrico.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/Dott-Bellusci_.jpg&#8221; title_text=&#8221;Dott Bellusci_&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; ul_font=&#8221;Poppins||||||||&#8221; ul_line_height=&#8221;1.96em&#8221; header_font=&#8221;Playfair Display|800||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#0091c1&#8243; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;1.3em&#8221; hover_enabled=&#8221;0&#8243; header_font_size_tablet=&#8221;26px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; sticky_enabled=&#8221;0&#8243; header_line_height_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221;]<\/p>\n<h1>Prestazioni eseguite presso il mio studio<\/h1>\n<ul>\n<li>Visita otorinolaringoiatrica<\/li>\n<li>Visita audiologica<\/li>\n<li>Endoscopia nasale<\/li>\n<li>Fibrolaringoscopia<\/li>\n<li>Esame audiometrico e impedenziometrico<\/li>\n<li>Visita otorino con manovre vestibolari per vertigini<\/li>\n<li>Visita di medicina del sonno<\/li>\n<li>Polisonnogra<\/li>\n<\/ul>\n<h1>Interventi chirurgici (eseguiti presso la casa di cura madre fortunata toniolo o presso l\u2019ospedale maggiore)<\/h1>\n<ul>\n<li>Tonsillectomia<\/li>\n<li>Adenoidectomia<\/li>\n<li>Settoplastica funzionale<\/li>\n<li>Turbinoplastica con radiofrequenze<\/li>\n<li>Interventi di chirurgia endoscopica per polipi nasali e sinusite<\/li>\n<li>Interventi alle corde vocali in microlaringoscopia<\/li>\n<li>Chirurgia endoscopica dell\u2019orecchio<\/li>\n<li>Tiroidectomia<\/li>\n<li>Parotidectomia<\/li>\n<li>Interventi per oncologia testa e collo<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; prev_background_color=&#8221;#ffffff&#8221; next_background_color=&#8221;#FFFFFF&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#e7f3fd&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#8adbdb&#8221; background_color_gradient_end=&#8221;#0091c1&#8243; background_color_gradient_direction=&#8221;360deg&#8221; custom_padding=&#8221;6vw||6vw||true|false&#8221; custom_padding_tablet=&#8221;10vw||10vw||true|false&#8221; custom_padding_phone=&#8221;16vw||16vw||true|false&#8221; top_divider_style=&#8221;wave2&#8243; top_divider_height=&#8221;70px&#8221; top_divider_flip=&#8221;vertical&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_height=&#8221;70px&#8221; bottom_divider_flip=&#8221;vertical&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Playfair Display|900||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;65px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Playfair Display|900||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;45px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_font_size_tablet=&#8221;31px&#8221; header_font_size_phone=&#8221;23px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h1>Agevolazioni riservate agli associati SIM GUARDIA DI FINANZA e i loro familiari<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Playfair Display|900||on|||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#0091c1&#8243; header_font_size=&#8221;35px&#8221; header_letter_spacing=&#8221;1px&#8221; header_2_font=&#8221;Montserrat|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#084578&#8243; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||45px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Contatti<\/h1>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 14px; line-height: 26px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Studio medico Dialogo, Via Caselle, 7, San Lazzaro di Savena, BO <br>\n<strong>Telefono:<\/strong> 338 731 3286 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.miodottore.it\/andrea-bellusci\/otorino\/bologna#address-id=858952861218863339&filtersspecializations=42\">www.miodottore.it\/andrea-bellusci\/otorino\/bologna#address-id=858952861218863339&filtersspecializations=42<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:\"><\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-165\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"42723\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-165\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-165\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-165\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-165\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"165\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-388\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-388\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-388\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-388\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-388\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"388\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>dott andrea bellusci<br \/>\nmedico chirurgo<br \/>\nspecialista in otorinolaringoitria e chirurgia cervico-facciale<\/p>\n<p>su di me:<\/p>\n<p>sin dai primi anni del corso di laurea in medicina mi sono concentrato sullo studio del distretto testa e collo raffinando le mie conoscenze anatomiche grazie alla partecipazione ad una fellowship in \u201cgross anatomy\u201d c\\o new york university.<\/p>\n<p>per tre anni (2008-2011) ho eseguito attivit\u00e0 di assistenza alla didattica c\/o dipartimento di anatomia normale dell\u2019universit\u00e0 di bologna e di tutoraggio agli studenti del cdl medicina e chirurgia.<\/p>\n<p>ho conseguito la laurea in medicina e chirurgia nel luglio 2012 con la votazione di 110 su 110 e lode.<\/p>\n<p>sin dall\u2019inizio della scuola di specialit\u00e0 in otorinolaringoiatria mi sono interessato a tutte le branche endoscopiche di questa disciplina e all\u2019oncologia testa e collo.<\/p>\n<p>in particolare mi sono dedicato allo studio della sindrome delle apnee ostruttive del sonno prendendo parte a tutta l\u2019attivit\u00e0 inerente c\/o la clinica otorinolaringologica dell\u2019universit\u00e0 di bologna, in particolare all\u2019ambulatorio endoscopico e alle sedute di drug induced sleep endoscopy.<br \/>\ndurante questo periodo ho acquisito ottima capacit\u00e0 di refertazione dei tracciati polisonnografici, questo percorso si \u00e8 concluso con la frequenza al master sio \u2013 aims \u201ceos-drs\u201d e con l\u2019acquisizione del titolo di \u201cmedico qualificato in disturbi respiratori ostruttivi in sonno\u201d<\/p>\n<p>nei mesi della specialit\u00e0 passati presso l\u2019uoc orl area metropolitana di bologna e presso il centro di chirurgia ipofisaria dell\u2019ospedale bellaria ho approfondito la conoscenza della chirurgia endoscopica funzionale e oncologica del distretto rinosinusale e del basicranio anteriore. in particolare ho approfondito lo studio dei tumori dei seni paranasali e della basecranica partecipando attivamente a tutti gli incontri del team multidisciplinare, ai relativi ambulatori e alle sedute di sala operatoria, in questo ambito mi sono dedicato alla compilazione dei database di tutti i pz affetti da neoplasie della rinobase ed in particolare dei pz affetti da adenocarcinoma intestinal-type dell\u2019etmoide.<\/p>\n<p>al fine di affinare la conoscenza in campo otologico e otoneurologico ho poi intrapreso una fellowship di 4 mesi presso il gruppo otologico del professor mario sanna, dove in qualit\u00e0 di medico specializzando ho partecipato attivamente a tutte le regolari attivit\u00e0 di sala, reparto e ambulatorio. inoltre nello stesso periodo ho partecipato a molteplici corsi di dissezione in ambito otologico e sono stato co-organizzazione del primo corso di dissezione per soli specializzandi cui ho partecipato in qualit\u00e0 tutor, ruolo che ho mantenuto nei corsi a seguire.<\/p>\n<p>ho conseguito la specializzazione in otorinolaringoiatria nell\u2019agosto 2018 con la votazione di 110 su 110 e lode.<\/p>\n<p>fino a marzo 2019 ho prestato servizio come medico contrattista presso la clinica otorinolaringologica del policlinico sant\u2019orsola-malpighi.<\/p>\n<p>attualmente sono in servizio come dirigente medico di i livello presso l\u2019uoc di otorinolaringoiatria dell\u2019ospedale maggiore di bologna dove partecipo attivamente a tutte le attivit\u00e0 ambulatoriali e di sala operatoria, attualmente ho all\u2019attivo oltre 1000 interventi come primo operatore su tutti i livelli del distretto otorinolaringoiatrico.<\/p>\n<p>prestazioni eseguite presso il mio studio<\/p>\n<p>visita otorinolaringoiatrica, visita audiologica, endoscopia nasale , fibrolaringoscopia , esame audiometrico, esame impedenziometrico, visita otorino, vertigini , visita di medicina del sonno , polisonnogra , interventi chirugici , tonsillectomia , adenoidectomia , settoplastica funzionale , turbinoplastica con radiofrequenze , interventi di chirurgia endoscopica per polipi nasali e sinusite , interventi alle corde vocali in microlaringoscopia , chirurgia endoscopica dell\u2019orecchio , tiroidectomia , parotidectomia , interventi per oncologia testa e collo, otorinolaringoiatria, otorinolaringoiatra , chirurgia cervico-facciale<\/p>\n<\/div>\n","protected":false},"featured_media":42729,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[244,163],"product_tag":[2856,5113,5109,5097,5099,5100,5098,5108,5104,5107,5112,438,585,5111,5103,5105,5110,2857,5106,2340,5096,5102,5101,5095],"class_list":{"0":"post-42723","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-otorinolaringoiatra","7":"product_cat-salute","8":"product_tag-adenoidectomia","9":"product_tag-chirurgia-cervico-facciale","10":"product_tag-chirurgia-endoscopica-dellorecchio","11":"product_tag-endoscopia-nasale","12":"product_tag-esame-audiometrico","13":"product_tag-esame-impedenziometrico","14":"product_tag-fibrolaringoscopia","15":"product_tag-interventi-alle-corde-vocali-in-microlaringoscopia","16":"product_tag-interventi-chirugici","17":"product_tag-interventi-di-chirurgia-endoscopica-per-polipi-nasali-e-sinusite","18":"product_tag-interventi-per-oncologia-testa-e-collo","19":"product_tag-otorinolaringoiatra","20":"product_tag-otorinolaringoiatria","21":"product_tag-parotidectomia","22":"product_tag-polisonnogra","23":"product_tag-settoplastica-funzionale","24":"product_tag-tiroidectomia","25":"product_tag-tonsillectomia","26":"product_tag-turbinoplastica-con-radiofrequenze","27":"product_tag-vertigini","28":"product_tag-visita-audiologica","29":"product_tag-visita-di-medicina-del-sonno","30":"product_tag-visita-otorino","31":"product_tag-visita-otorinolaringoiatrica","33":"first","34":"instock","35":"shipping-taxable","36":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Andrea Bellusci - Otorino - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Andrea Bellusci - Otorino - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"dott andrea bellusci medico chirurgo specialista in otorinolaringoitria e chirurgia cervico-facciale  su di me:  sin dai primi anni del corso di laurea in medicina mi sono concentrato sullo studio del distretto testa e collo raffinando le mie conoscenze anatomiche grazie alla partecipazione ad una fellowship in \u201cgross anatomy\u201d co new york university.  per tre anni (2008-2011) ho eseguito attivit\u00e0 di assistenza alla didattica c\/o dipartimento di anatomia normale dell\u2019universit\u00e0 di bologna e di tutoraggio agli studenti del cdl medicina e chirurgia.  ho conseguito la laurea in medicina e chirurgia nel luglio 2012 con la votazione di 110 su 110 e lode.  sin dall\u2019inizio della scuola di specialit\u00e0 in otorinolaringoiatria mi sono interessato a tutte le branche endoscopiche di questa disciplina e all\u2019oncologia testa e collo.  in particolare mi sono dedicato allo studio della sindrome delle apnee ostruttive del sonno prendendo parte a tutta l\u2019attivit\u00e0 inerente c\/o la clinica otorinolaringologica dell\u2019universit\u00e0 di bologna, in particolare all\u2019ambulatorio endoscopico e alle sedute di drug induced sleep endoscopy. durante questo periodo ho acquisito ottima capacit\u00e0 di refertazione dei tracciati polisonnografici, questo percorso si \u00e8 concluso con la frequenza al master sio \u2013 aims \u201ceos-drs\u201d e con l\u2019acquisizione del titolo di \u201cmedico qualificato in disturbi respiratori ostruttivi in sonno\u201d  nei mesi della specialit\u00e0 passati presso l\u2019uoc orl area metropolitana di bologna e presso il centro di chirurgia ipofisaria dell\u2019ospedale bellaria ho approfondito la conoscenza della chirurgia endoscopica funzionale e oncologica del distretto rinosinusale e del basicranio anteriore. in particolare ho approfondito lo studio dei tumori dei seni paranasali e della basecranica partecipando attivamente a tutti gli incontri del team multidisciplinare, ai relativi ambulatori e alle sedute di sala operatoria, in questo ambito mi sono dedicato alla compilazione dei database di tutti i pz affetti da neoplasie della rinobase ed in particolare dei pz affetti da adenocarcinoma intestinal-type dell\u2019etmoide.  al fine di affinare la conoscenza in campo otologico e otoneurologico ho poi intrapreso una fellowship di 4 mesi presso il gruppo otologico del professor mario sanna, dove in qualit\u00e0 di medico specializzando ho partecipato attivamente a tutte le regolari attivit\u00e0 di sala, reparto e ambulatorio. inoltre nello stesso periodo ho partecipato a molteplici corsi di dissezione in ambito otologico e sono stato co-organizzazione del primo corso di dissezione per soli specializzandi cui ho partecipato in qualit\u00e0 tutor, ruolo che ho mantenuto nei corsi a seguire.  ho conseguito la specializzazione in otorinolaringoiatria nell\u2019agosto 2018 con la votazione di 110 su 110 e lode.  fino a marzo 2019 ho prestato servizio come medico contrattista presso la clinica otorinolaringologica del policlinico sant\u2019orsola-malpighi.  attualmente sono in servizio come dirigente medico di i livello presso l\u2019uoc di otorinolaringoiatria dell\u2019ospedale maggiore di bologna dove partecipo attivamente a tutte le attivit\u00e0 ambulatoriali e di sala operatoria, attualmente ho all\u2019attivo oltre 1000 interventi come primo operatore su tutti i livelli del distretto otorinolaringoiatrico.  prestazioni eseguite presso il mio studio  visita otorinolaringoiatrica, visita audiologica, endoscopia nasale , fibrolaringoscopia , esame audiometrico, esame impedenziometrico, visita otorino, vertigini , visita di medicina del sonno , polisonnogra , interventi chirugici , tonsillectomia , adenoidectomia , settoplastica funzionale , turbinoplastica con radiofrequenze , interventi di chirurgia endoscopica per polipi nasali e sinusite , interventi alle corde vocali in microlaringoscopia , chirurgia endoscopica dell\u2019orecchio , tiroidectomia , parotidectomia , interventi per oncologia testa e collo, otorinolaringoiatria, otorinolaringoiatra , chirurgia cervico-facciale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-07T15:22:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/\",\"name\":\"Dott. Andrea Bellusci - Otorino - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg\",\"datePublished\":\"2023-03-07T09:37:10+00:00\",\"dateModified\":\"2023-03-07T15:22:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Andrea Bellusci &#8211; Otorino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Andrea Bellusci - Otorino - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Andrea Bellusci - Otorino - UIL Polizia","og_description":"dott andrea bellusci medico chirurgo specialista in otorinolaringoitria e chirurgia cervico-facciale  su di me:  sin dai primi anni del corso di laurea in medicina mi sono concentrato sullo studio del distretto testa e collo raffinando le mie conoscenze anatomiche grazie alla partecipazione ad una fellowship in \u201cgross anatomy\u201d co new york university.  per tre anni (2008-2011) ho eseguito attivit\u00e0 di assistenza alla didattica c\/o dipartimento di anatomia normale dell\u2019universit\u00e0 di bologna e di tutoraggio agli studenti del cdl medicina e chirurgia.  ho conseguito la laurea in medicina e chirurgia nel luglio 2012 con la votazione di 110 su 110 e lode.  sin dall\u2019inizio della scuola di specialit\u00e0 in otorinolaringoiatria mi sono interessato a tutte le branche endoscopiche di questa disciplina e all\u2019oncologia testa e collo.  in particolare mi sono dedicato allo studio della sindrome delle apnee ostruttive del sonno prendendo parte a tutta l\u2019attivit\u00e0 inerente c\/o la clinica otorinolaringologica dell\u2019universit\u00e0 di bologna, in particolare all\u2019ambulatorio endoscopico e alle sedute di drug induced sleep endoscopy. durante questo periodo ho acquisito ottima capacit\u00e0 di refertazione dei tracciati polisonnografici, questo percorso si \u00e8 concluso con la frequenza al master sio \u2013 aims \u201ceos-drs\u201d e con l\u2019acquisizione del titolo di \u201cmedico qualificato in disturbi respiratori ostruttivi in sonno\u201d  nei mesi della specialit\u00e0 passati presso l\u2019uoc orl area metropolitana di bologna e presso il centro di chirurgia ipofisaria dell\u2019ospedale bellaria ho approfondito la conoscenza della chirurgia endoscopica funzionale e oncologica del distretto rinosinusale e del basicranio anteriore. in particolare ho approfondito lo studio dei tumori dei seni paranasali e della basecranica partecipando attivamente a tutti gli incontri del team multidisciplinare, ai relativi ambulatori e alle sedute di sala operatoria, in questo ambito mi sono dedicato alla compilazione dei database di tutti i pz affetti da neoplasie della rinobase ed in particolare dei pz affetti da adenocarcinoma intestinal-type dell\u2019etmoide.  al fine di affinare la conoscenza in campo otologico e otoneurologico ho poi intrapreso una fellowship di 4 mesi presso il gruppo otologico del professor mario sanna, dove in qualit\u00e0 di medico specializzando ho partecipato attivamente a tutte le regolari attivit\u00e0 di sala, reparto e ambulatorio. inoltre nello stesso periodo ho partecipato a molteplici corsi di dissezione in ambito otologico e sono stato co-organizzazione del primo corso di dissezione per soli specializzandi cui ho partecipato in qualit\u00e0 tutor, ruolo che ho mantenuto nei corsi a seguire.  ho conseguito la specializzazione in otorinolaringoiatria nell\u2019agosto 2018 con la votazione di 110 su 110 e lode.  fino a marzo 2019 ho prestato servizio come medico contrattista presso la clinica otorinolaringologica del policlinico sant\u2019orsola-malpighi.  attualmente sono in servizio come dirigente medico di i livello presso l\u2019uoc di otorinolaringoiatria dell\u2019ospedale maggiore di bologna dove partecipo attivamente a tutte le attivit\u00e0 ambulatoriali e di sala operatoria, attualmente ho all\u2019attivo oltre 1000 interventi come primo operatore su tutti i livelli del distretto otorinolaringoiatrico.  prestazioni eseguite presso il mio studio  visita otorinolaringoiatrica, visita audiologica, endoscopia nasale , fibrolaringoscopia , esame audiometrico, esame impedenziometrico, visita otorino, vertigini , visita di medicina del sonno , polisonnogra , interventi chirugici , tonsillectomia , adenoidectomia , settoplastica funzionale , turbinoplastica con radiofrequenze , interventi di chirurgia endoscopica per polipi nasali e sinusite , interventi alle corde vocali in microlaringoscopia , chirurgia endoscopica dell\u2019orecchio , tiroidectomia , parotidectomia , interventi per oncologia testa e collo, otorinolaringoiatria, otorinolaringoiatra , chirurgia cervico-facciale","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/","og_site_name":"UIL Polizia","article_modified_time":"2023-03-07T15:22:34+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/","name":"Dott. Andrea Bellusci - Otorino - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg","datePublished":"2023-03-07T09:37:10+00:00","dateModified":"2023-03-07T15:22:34+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2023\/03\/logo_Andrea-Bellusci_.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-andrea-bellusci-otorino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Andrea Bellusci &#8211; Otorino"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/42723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=42723"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/42723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/42729"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=42723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=42723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=42723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=42723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}