{"id":39133,"date":"2022-12-28T12:10:52","date_gmt":"2022-12-28T11:10:52","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=39133"},"modified":"2022-12-28T12:11:01","modified_gmt":"2022-12-28T11:11:01","slug":"dott-alberto-lescarini-fisioterapista-e-osteopata","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/","title":{"rendered":"Dott. Alberto Lescarini &#8211; Fisioterapista e Osteopata"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.9.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(13,34,226,0.35)&#8221; background_color_gradient_end=&#8221;#0090c5&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/sfondo-ALBERTO-LESCARINI-scaled.jpeg&#8221; background_position=&#8221;center_right&#8221; custom_padding=&#8221;11vw||11vw||true|false&#8221; bottom_divider_height=&#8221;90px&#8221; da_disable_devices=&#8221;off|off|off&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;80px&#8221; text_orientation=&#8221;center&#8221; custom_margin_tablet=&#8221;|-40px||-40px|false|true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; text_font_size_tablet=&#8221;27px&#8221; text_font_size_phone=&#8221;22px&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;58px&#8221; header_font_size_phone=&#8221;43px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Dott. Alberto Lescarini<\/h1>\n<p>Fisioterapista e Osteopata<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; custom_padding_tablet=&#8221;12vw||12vw||true|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; disabled_on=&#8221;off|off|on&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.9.4&#8243; custom_margin=&#8221;|||0px|false|false&#8221; custom_margin_tablet=&#8221;|||80px|false|false&#8221; custom_margin_phone=&#8221;|||35px|false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_color=&#8221;#0090c5&#8243; header_font_size=&#8221;35px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;||||false|true&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; text_font_size_tablet=&#8221;14px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Chi sono<\/h1>\n<p>Mi chiamo Alberto Lescarini e sono un Fisioterapista e un Osteopata. Ho conseguito la laurea in Fisioterapia presso la L.U.de.S di Lugano nel 2009, e ho seguito i corsi di osteopatia con metodi a BFD (biomeccanica funzionale dinamica) presso la sede di Torino prima e Milano poi.<br \/>Ora esercito in uno studio privato situato a Concordia Sagittaria in Via Claudia, 84\/A.<\/p>\n<p>Il mio servizio si rivolge a tutti coloro i quali soffrono per un dolore o hanno un problema muscolare o articolare di natura artrosica, posturale, traumatica.<br \/>Si rivolge inoltre a chi deve prepararsi ad un intervento chirurgico o, essendo gi\u00e0 stato operato, deve fare la riabilitazione.<br \/>Mi occupo prevalentemente di patologie neuro-muscolo-sceletriche, lombosciatalgie, cervicobrachialgie, riassetto posturale dell&#8217;arto superiore o di quello inferiore, Riabilitazione post-traumarica e post-chirurgica, massoterapia.<br \/>Le varie tecniche manuali sono supportate, quando necessario, da terapie fisiche strumentali come la Tecarterapia, TENS, corrente interferenziale, ultrasuonoterapia.<\/p>\n<p>Regolarmente iscritto all&#8217;albo dei Fisioterapisti.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/IMG_20221220_102651-scaled.jpg&#8221; title_text=&#8221;IMG_20221220_102651&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-3vw|-8vw|-6vw||false|false&#8221; custom_margin_tablet=&#8221;8vw|0vw|4vw||false|false&#8221; custom_margin_phone=&#8221;||5vw||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; filter_saturate=&#8221;116%&#8221; border_radii=&#8221;on|40px|40px|40px|40px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.54)&#8221; box_shadow_color_tablet=&#8221;rgba(12,113,195,0.25)&#8221; box_shadow_color_phone=&#8221;&#8221; box_shadow_color_last_edited=&#8221;on|tablet&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.9.4&#8243; custom_margin=&#8221;|||0px|false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/IMG_20221220_102651-scaled.jpg&#8221; title_text=&#8221;IMG_20221220_102651&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-3vw|-8vw|-6vw||false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; filter_saturate=&#8221;116%&#8221; border_radii=&#8221;on|40px|40px|40px|40px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_color=&#8221;rgba(12,113,195,0.54)&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins|700|||||||&#8221; header_text_color=&#8221;#0090c5&#8243; header_font_size=&#8221;35px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;8vw|-30vw||12vw|false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h1>Chi sono<\/h1>\n<p>Mi chiamo Alberto Lescarini e sono un Fisioterapista e un Osteopata. Ho conseguito la laurea in Fisioterapia presso la L.U.de.S di Lugano nel 2009, e ho seguito i corsi di osteopatia con metodi a BFD(biomeccanica funzionale dinamica) presso la sede di Torino prima e Milano poi.<br \/>Ora esercito in uno studio privato situato a Concordia Sagittaria in via Claudia 84\/A.<\/p>\n<p>Il mio servizio si rivolge a tutti coloro i quali soffrono per un dolore o hanno un problema muscolare o articolare di natura artrosica, posturale, traumatica.<br \/>Si rivolge inoltre a chi deve prepararsi ad un intervento chirurgico o, essendo gi\u00e0 stato operato, deve fare la riabilitazione.<br \/>Mi occupo prevalentemente di patologie neuro-muscolo-sceletriche, lombosciatalgie, cervicobrachialgie, riassetto posturale dell&#8217;arto superiore o di quello inferiore, Riabilitazione post-traumarica e post-chirurgica, massoterapia.<br \/>Le varie tecniche manuali sono supportate, quando necessario, da terapie fisiche strumentali come la Tecarterapia, TENS, corrente interferenziale, ultrasuonoterapia.<\/p>\n<p>Regolarmente iscritto all&#8217;albo dei Fisioterapisti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; prev_background_color=&#8221;#FFFFFF&#8221; next_background_color=&#8221;#FFFFFF&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#e7f3fd&#8221; background_color_gradient_end=&#8221;#0090c5&#8243; custom_padding=&#8221;7vw||6vw||false|false&#8221; custom_padding_tablet=&#8221;12vw||11vw||false|false&#8221; custom_padding_phone=&#8221;20vw||20vw||true|false&#8221; top_divider_style=&#8221;asymmetric2&#8243; top_divider_height=&#8221;70px&#8221; top_divider_flip=&#8221;vertical&#8221; bottom_divider_style=&#8221;asymmetric2&#8243; bottom_divider_height=&#8221;70px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;55px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;47px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;|50px||50px|false|true&#8221; custom_padding_tablet=&#8221;|0px||0px|false|true&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;38px&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h2>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;3vw||2vw||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#0090c5&#8243; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||45px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 15px; line-height: 28px\"><!-- [et_pb_line_break_holder] --><br \/><p><strong>Indirizzo:<\/strong> Studio Fisioterapico Dott. Lescarini, Via Claudia, 84 A, 30023 Concordia Sagittaria, VE <br>\n<strong>Telefono:<\/strong> 3474819264 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/\"><\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:alberto_lescarini@hotmail.it\">alberto_lescarini@hotmail.it<\/a> \n<\/p><br \/> <\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-294\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"39133\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-294\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-294\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-294\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-294\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"294\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-513\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-513\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-513\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-513\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-513\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"513\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Alberto Lescarini &#8211; Fisioterapista e OsteopataMi chiamo Alberto Lescarini e sono un Fisioterapista e un Osteopata. Ho conseguito la laurea in Fisioterapia presso la L.U.de.S di Lugano nel 2009, e ho seguito i corsi di osteopatia con metodi a BFD( biomeccanica funzionale dinamica) presso la sede di Torino prima e Milano poi.<br \/>\nOra esercito in uno studio privato situato a Concordia Sagittaria in via Claudia 84\/A.<br \/>\nIl mio servizio si rivolge a tutti coloro i quali soffrono per un dolore o hanno un problema muscolare o articolare di natura artrosica, posturale, traumatica.<br \/>\nSi rivolge inoltre a chi deve prepararsi ad un intervento chirurgico o, essendo gi\u00e0 stato operato, deve fare la riabilitazione.<br \/>\nMi occupo prevalentemente di patologie neuro-muscolo-sceletriche, lombosciatalgie, cervicobrachialgie, riassetto posturale dell&#8217;arto superiore o di quello inferiore, Riabilitazione post-traumarica e post-chirurgica, massoterapia.<br \/>\nLe varie tecniche manuali sono supportate, quando necessario, da terapie fisiche strumentali come la Tecarterapia, TENS, corrente interferenziale, ultrasuonoterapia.<br \/>\nRegolarmente iscritto all&#8217;albo dei Fisioterapisti.<\/p>\n<p>sede: via claudia 84\/a concordia sagittaria (ve) 30023<br \/>\ntel: 3474819264<br \/>\nmail: alberto_lescarini@hotmail.it<\/p>\n<p>Fisioterapista, Osteopata, Fisioterapia, Osteopatia, Fisioterapisti, Osteopati, Venezia, Veneto, Concordia Sagittaria, dolore muscolare, dolore articolare, problema muscolare, problema articolare, problema posturale,<br \/>\ndolori muscolari, dolori articolari, problemi muscolari, problemi articolari, problemi posturali, patologie neuro-muscolo-scheletriche, lombosciatalgie, riassetto posturale dell&#8217;arto superiore o inferiore, Riabilitazione post-traumatica, Riabilitazione post-chirurgica, massoterapia<\/p>\n<\/div>\n","protected":false},"featured_media":39136,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,242,163],"product_tag":[4178,4180,4179,4184,2394,447,365,448,3967,611,383,1109,384,4188,4182,4181,4186,4185,4187,1453,1454,4189,4183,473,622],"class_list":{"0":"post-39133","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-osteopatia","8":"product_cat-salute","9":"product_tag-concordia-sagittaria","10":"product_tag-dolore-articolare","11":"product_tag-dolore-muscolare","12":"product_tag-dolori-articolari","13":"product_tag-dolori-muscolari","14":"product_tag-fisioterapia","15":"product_tag-fisioterapista","16":"product_tag-fisioterapisti","17":"product_tag-lombosciatalgie","18":"product_tag-massoterapia","19":"product_tag-osteopata","20":"product_tag-osteopati","21":"product_tag-osteopatia","22":"product_tag-patologie-neuro-muscolo-scheletriche","23":"product_tag-problema-articolare","24":"product_tag-problema-muscolare","25":"product_tag-problemi-articolari","26":"product_tag-problemi-muscolari","27":"product_tag-problemi-posturali","28":"product_tag-riabilitazione-post-chirurgica","29":"product_tag-riabilitazione-post-traumatica","30":"product_tag-riassetto-posturale-dellarto-superiore-o-inferiore","31":"product_tag-roblema-posturale","32":"product_tag-veneto","33":"product_tag-venezia","35":"first","36":"instock","37":"shipping-taxable","38":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Alberto Lescarini - Fisioterapista e Osteopata - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Alberto Lescarini - Fisioterapista e Osteopata - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Alberto Lescarini - Fisioterapista e OsteopataMi chiamo Alberto Lescarini e sono un Fisioterapista e un Osteopata. Ho conseguito la laurea in Fisioterapia presso la L.U.de.S di Lugano nel 2009, e ho seguito i corsi di osteopatia con metodi a BFD( biomeccanica funzionale dinamica) presso la sede di Torino prima e Milano poi. Ora esercito in uno studio privato situato a Concordia Sagittaria in via Claudia 84\/A. Il mio servizio si rivolge a tutti coloro i quali soffrono per un dolore o hanno un problema muscolare o articolare di natura artrosica, posturale, traumatica. Si rivolge inoltre a chi deve prepararsi ad un intervento chirurgico o, essendo gi\u00e0 stato operato, deve fare la riabilitazione. Mi occupo prevalentemente di patologie neuro-muscolo-sceletriche, lombosciatalgie, cervicobrachialgie, riassetto posturale dell&#039;arto superiore o di quello inferiore, Riabilitazione post-traumarica e post-chirurgica, massoterapia. Le varie tecniche manuali sono supportate, quando necessario, da terapie fisiche strumentali come la Tecarterapia, TENS, corrente interferenziale, ultrasuonoterapia. Regolarmente iscritto all&#039;albo dei Fisioterapisti.  sede: via claudia 84\/a concordia sagittaria (ve) 30023 tel: 3474819264 mail: alberto_lescarini@hotmail.it  Fisioterapista, Osteopata, Fisioterapia, Osteopatia, Fisioterapisti, Osteopati, Venezia, Veneto, Concordia Sagittaria, dolore muscolare, dolore articolare, problema muscolare, problema articolare, problema posturale, dolori muscolari, dolori articolari, problemi muscolari, problemi articolari, problemi posturali, patologie neuro-muscolo-scheletriche, lombosciatalgie, riassetto posturale dell&#039;arto superiore o inferiore, Riabilitazione post-traumatica, Riabilitazione post-chirurgica, massoterapia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T11:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/\",\"name\":\"Dott. Alberto Lescarini - Fisioterapista e Osteopata - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg\",\"datePublished\":\"2022-12-28T11:10:52+00:00\",\"dateModified\":\"2022-12-28T11:11:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Alberto Lescarini &#8211; Fisioterapista e Osteopata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Alberto Lescarini - Fisioterapista e Osteopata - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Alberto Lescarini - Fisioterapista e Osteopata - UIL Polizia","og_description":"Alberto Lescarini - Fisioterapista e OsteopataMi chiamo Alberto Lescarini e sono un Fisioterapista e un Osteopata. Ho conseguito la laurea in Fisioterapia presso la L.U.de.S di Lugano nel 2009, e ho seguito i corsi di osteopatia con metodi a BFD( biomeccanica funzionale dinamica) presso la sede di Torino prima e Milano poi. Ora esercito in uno studio privato situato a Concordia Sagittaria in via Claudia 84\/A. Il mio servizio si rivolge a tutti coloro i quali soffrono per un dolore o hanno un problema muscolare o articolare di natura artrosica, posturale, traumatica. Si rivolge inoltre a chi deve prepararsi ad un intervento chirurgico o, essendo gi\u00e0 stato operato, deve fare la riabilitazione. Mi occupo prevalentemente di patologie neuro-muscolo-sceletriche, lombosciatalgie, cervicobrachialgie, riassetto posturale dell'arto superiore o di quello inferiore, Riabilitazione post-traumarica e post-chirurgica, massoterapia. Le varie tecniche manuali sono supportate, quando necessario, da terapie fisiche strumentali come la Tecarterapia, TENS, corrente interferenziale, ultrasuonoterapia. Regolarmente iscritto all'albo dei Fisioterapisti.  sede: via claudia 84\/a concordia sagittaria (ve) 30023 tel: 3474819264 mail: alberto_lescarini@hotmail.it  Fisioterapista, Osteopata, Fisioterapia, Osteopatia, Fisioterapisti, Osteopati, Venezia, Veneto, Concordia Sagittaria, dolore muscolare, dolore articolare, problema muscolare, problema articolare, problema posturale, dolori muscolari, dolori articolari, problemi muscolari, problemi articolari, problemi posturali, patologie neuro-muscolo-scheletriche, lombosciatalgie, riassetto posturale dell'arto superiore o inferiore, Riabilitazione post-traumatica, Riabilitazione post-chirurgica, massoterapia","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/","og_site_name":"UIL Polizia","article_modified_time":"2022-12-28T11:11:01+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/","name":"Dott. Alberto Lescarini - Fisioterapista e Osteopata - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg","datePublished":"2022-12-28T11:10:52+00:00","dateModified":"2022-12-28T11:11:01+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Dott.-Alberto-Lescarini.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-alberto-lescarini-fisioterapista-e-osteopata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Alberto Lescarini &#8211; Fisioterapista e Osteopata"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/39133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=39133"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/39133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/39136"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=39133"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=39133"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=39133"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=39133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}