{"id":38978,"date":"2022-12-21T10:19:16","date_gmt":"2022-12-21T09:19:16","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=38978"},"modified":"2022-12-22T09:48:53","modified_gmt":"2022-12-22T08:48:53","slug":"dott-ssa-manuela-di-girolamo-fisioterapista-osteopata","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/","title":{"rendered":"Dott.ssa Manuela Di Girolamo &#8211; Fisioterapista &#038; Osteopata"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.9.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0)&#8221; background_color_gradient_end=&#8221;#88b5dc&#8221; background_color_gradient_start_position=&#8221;21%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/monya-prinsloo-HZmRQsyvGHA-unsplash-1-scaled-1.jpg&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;300px||0px||false|false&#8221; custom_padding_tablet=&#8221;200px||0px||false|false&#8221; custom_padding_phone=&#8221;100px||||false|false&#8221; bottom_divider_height=&#8221;60px&#8221; background_last_edited=&#8221;on|phone&#8221; background_color_gradient_start_position_tablet=&#8221;0%&#8221; da_disable_devices=&#8221;off|off|off&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; header_font_size=&#8221;48px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Playfair Display|600|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;65px&#8221; header_2_line_height=&#8221;1.1em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;55px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h2>Dott.ssa Manuela Di Girolamo<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; header_font_size=&#8221;48px&#8221; header_letter_spacing=&#8221;3px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Playfair Display|||on|||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.1em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;25px&#8221; header_2_font_size_phone=&#8221;17px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h2>Fisioterapista &amp; Osteopata<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.9.4&#8243; width=&#8221;100%&#8221; max_width=&#8221;1525px&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Dott.ssa-Manuela-Di-Girolamo.jpg&#8221; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;300px||300px||true|false&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; custom_padding=&#8221;60px||60px|40px|true|false&#8221; custom_padding_tablet=&#8221;60px|50px|60px|50px|true|true&#8221; custom_padding_phone=&#8221;|40px||40px|true|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Playfair Display|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#216183&#8243; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||5px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Chi sono<\/h2>\n<p>[\/et_pb_text][et_pb_wc_description disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; disabled=&#8221;on&#8221;][\/et_pb_wc_description][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;17px&#8221; text_line_height=&#8221;1.9em&#8221; text_orientation=&#8221;justified&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<p>Sono la <strong>Dott.ssa Manuela Di Girolamo<\/strong>, fisioterapista osteopata specializzata in riabilitazione del pavimento pelvico.<\/p>\n<p>Tratto disfunzioni della colonna (cervicalgia, lombalgia, coccigodina, ecc.), disfunzioni degli arti (problemi di spalla, epicondilite, dita a scatto, problemi all\u2019anca, gonalgia, spina calcaneale, fascite plantare, ecc.).<\/p>\n<p>Tratto le disfunzioni del pavimento pelvico con kinesiterapia funzionale, terapia osteopatica, manipolazione fasciale e terapia fisica.<\/p>\n<p>Mi occupo di dolore pelvico e vulvodinia, disturbi della minzione (incontinenza urinaria, urgenza urinaria, cistiti ricorrenti), disturbi della defecazione (sindrome da defecazione ostruita, dissinergia puborettale, incontinenza fecale, ragadi anali), prolassi del comparto anteriore e\/o posteriore (cistocele, isterocele, rettocele, prolasso rettale, prolasso emorroidario) e diastasi dei retti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1470px&#8221; custom_padding=&#8221;70px||||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/IMG_20221204_174208_0056.jpg&#8221; title_text=&#8221;IMG_20221204_174208_0056&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#216183&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/IMG_20221204_174229_0865.jpg&#8221; title_text=&#8221;IMG_20221204_174229_0865&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#216183&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/IMG_20221204_180550.jpg&#8221; title_text=&#8221;IMG_20221204_180550&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-50px||||false|false&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#216183&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#e7f3fd&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#e7f3fd&#8221; background_color_gradient_end=&#8221;#89c5f5&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/monya-prinsloo-HZmRQsyvGHA-unsplash-1-scaled-1.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;rgba(0,0,0,0.6)&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;70px||70px||true|false&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Playfair Display|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;19px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/IMG_20221204_174218_0569.jpg&#8221; title_text=&#8221;IMG_20221204_174218_0569&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#216183&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Playfair Display|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#216183&#8243; header_2_font_size=&#8221;33px&#8221; custom_margin=&#8221;23px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-60px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<\/p>\n<div style=\"font-family: Poppins, sans-serif; font-size: 16px; line-height: 30px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Viale Praga, 11, 90146 Palermo, PA, Italia <br>\n<strong>Telefono:<\/strong> +39 328 268 3394 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.manueladigirolamo.it\">www.manueladigirolamo.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:\"><\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;]<div id=\"gmw-single-location-wrapper-335\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"38978\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-335\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-335\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-335\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-335\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"335\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-object-locations-wrapper-217\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-217\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-217\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-217\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-217\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"217\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"font-family: Poppins, sans-serif; font-size: 17px; text-align: justify\">Sono la Dott.ssa Manuela Di Girolamo, fisioterapista osteopata specializzata in riabilitazione del pavimento pelvico.<\/p>\n<p>Tratto disfunzioni della colonna (cervicalgia, lombalgia, coccigodina, ecc.), disfunzioni degli arti (problemi di spalla, epicondilite, dita a scatto, problemi all\u2019anca, gonalgia, spina calcaneale, fascite plantare, ecc.).<\/p><\/div>\n","protected":false},"featured_media":38979,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,242,4145,163],"product_tag":[2663,1727,4138,4139,4140,4141,4142,365,383,4143,4144],"class_list":{"0":"post-38978","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-osteopatia","8":"product_cat-riabilitazione-del-pavimento-pelvico","9":"product_cat-salute","10":"product_tag-benessere-corporeo","11":"product_tag-benessere-fisico","12":"product_tag-diastasi-dei-retti","13":"product_tag-disfunzioni-arti","14":"product_tag-disfunzioni-colonna","15":"product_tag-disturbi-defecazione","16":"product_tag-disturbi-minzione","17":"product_tag-fisioterapista","18":"product_tag-osteopata","19":"product_tag-prolassi-comparto-anteriore-esteriore","20":"product_tag-riabilitazione-del-pavimento-pelvico","22":"first","23":"instock","24":"shipping-taxable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Manuela Di Girolamo - Fisioterapista &amp; Osteopata - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Manuela Di Girolamo - Fisioterapista &amp; Osteopata - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Sono la Dott.ssa Manuela Di Girolamo, fisioterapista osteopata specializzata in riabilitazione del pavimento pelvico.  Tratto disfunzioni della colonna (cervicalgia, lombalgia, coccigodina, ecc.), disfunzioni degli arti (problemi di spalla, epicondilite, dita a scatto, problemi all\u2019anca, gonalgia, spina calcaneale, fascite plantare, ecc.).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-22T08:48:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/\",\"name\":\"Dott.ssa Manuela Di Girolamo - Fisioterapista & Osteopata - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg\",\"datePublished\":\"2022-12-21T09:19:16+00:00\",\"dateModified\":\"2022-12-22T08:48:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Manuela Di Girolamo &#8211; Fisioterapista &#038; Osteopata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Manuela Di Girolamo - Fisioterapista & Osteopata - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Manuela Di Girolamo - Fisioterapista & Osteopata - UIL Polizia","og_description":"Sono la Dott.ssa Manuela Di Girolamo, fisioterapista osteopata specializzata in riabilitazione del pavimento pelvico.  Tratto disfunzioni della colonna (cervicalgia, lombalgia, coccigodina, ecc.), disfunzioni degli arti (problemi di spalla, epicondilite, dita a scatto, problemi all\u2019anca, gonalgia, spina calcaneale, fascite plantare, ecc.).","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/","og_site_name":"UIL Polizia","article_modified_time":"2022-12-22T08:48:53+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/","name":"Dott.ssa Manuela Di Girolamo - Fisioterapista & Osteopata - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg","datePublished":"2022-12-21T09:19:16+00:00","dateModified":"2022-12-22T08:48:53+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Base-Logo-di-girolamo.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-manuela-di-girolamo-fisioterapista-osteopata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Manuela Di Girolamo &#8211; Fisioterapista &#038; Osteopata"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/38978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=38978"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/38978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/38979"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=38978"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=38978"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=38978"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=38978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}