{"id":38344,"date":"2022-12-01T16:30:23","date_gmt":"2022-12-01T15:30:23","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=38344"},"modified":"2023-09-15T16:45:16","modified_gmt":"2023-09-15T14:45:16","slug":"dott-claudio-pianura-otorinolaringoiatra","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/","title":{"rendered":"Dott. Claudio Pianura &#8211; Otorinolaringoiatra"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.16&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/nosy-curiosity-ear-young-interesting-small.jpg&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_left&#8221; custom_padding=&#8221;150px||150px||true|false&#8221; custom_padding_tablet=&#8221;70px||70px||true|false&#8221; custom_padding_phone=&#8221;60px||60px||true|false&#8221; bottom_divider_height=&#8221;60px&#8221; background_last_edited=&#8221;on|tablet&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; background_color_gradient_stops_tablet=&#8221;rgba(255,255,255,0.54) 0%|#ffffff 100%&#8221; background_color_gradient_overlays_image_tablet=&#8221;on&#8221; background_color_gradient_start_tablet=&#8221;rgba(255,255,255,0.54)&#8221; background_color_gradient_end_tablet=&#8221;#ffffff&#8221; background_size_phone=&#8221;cover&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/Logo-Claudio-Pianura-blu.png&#8221; title_text=&#8221;Logo-Claudio-Pianura-blu&#8221; align=&#8221;right&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|-15vw|||false|false&#8221; custom_margin_tablet=&#8221;|0vw|||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;off|off|on&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;90px||90px|&#8221; custom_padding_tablet=&#8221;40px||||false|false&#8221; custom_padding_phone=&#8221;40px||40px||true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#3298ba&#8221; border_style_top=&#8221;dotted&#8221; border_width_bottom=&#8221;5px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|700|||||||&#8221; text_text_color=&#8221;#3298ba&#8221; text_font_size=&#8221;35px&#8221; text_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;30px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Oltre alla normale patologia ORL in particolare mi occupo di:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Disturbi dell\u2019equilibrio<\/h1>\n<p>L\u2019equilibrio \u201c\u00e8 la capacit\u00e0 di regolare e mantenere il corpo con opportuni e rapidi aggiustamenti di posizione contro la forza di gravit\u00e0, in posizione stabile ed eretta e di camminare senza cadere o deviare dalla linea prefissata\u201d.<br \/>\u00c8 considerato il \u201cVI Senso\u201d (\u00e8 il senso della relazione con l\u2019ambiente).<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; content_tablet=&#8221;<\/p>\n<table border=%221%22 style=%22height: 5%; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 10%; height: 240px;%22>\n<p>L\u2019uomo nel processo evolutivo ha conquistato la stazione eretta ricavandone numerosi vantaggi! Ma mantenere l\u2019equilibrio \u00e8 quasi un miracolo!<br \/>Implica un perfetto coordinamento tra numerosi sistemi: se uno va in \u201ctilt\u201d possono venire le VERTIGINI<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg%22 width=%22325%22 height=%22325%22 alt=%22%22 class=%22wp-image-38352 alignnone size-full%22 style=%22font-family: inherit; font-size: inherit;%22 \/><\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr style=%22height: 10px;%22>\n<td style=%22width: 10%; height: 10px;%22>\n<p>Al mantenimento dell\u2019equilibrio partecipa tutto il corpo e basta che una di queste componenti vada in tilt che compare il disturbo dell\u2019equilibrio.<br \/>I disturbi dell&#8217;equilibrio rappresentano un SINTOMO di diverse condizioni patologiche.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg%22 width=%22359%22 height=%22359%22 alt=%22%22 class=%22wp-image-38356 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 10%;%22>\n<p>L\u2019iter diagnostico \u00e8 per sua natura complesso, ma, identificata la causa, la cura sar\u00e0 mirata e pi\u00f9 efficace.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg%22 width=%22336%22 height=%22336%22 alt=%22%22 class=%22wp-image-38357 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8221; content_phone=&#8221;<\/p>\n<table border=%221%22 style=%22height: 394px; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 5%; height: 240px;%22>\n<p>L\u2019uomo nel processo evolutivo ha conquistato la stazione eretta ricavandone numerosi vantaggi! Ma mantenere l\u2019equilibrio \u00e8 quasi un miracolo!<br \/>Implica un perfetto coordinamento tra numerosi sistemi: se uno va in \u201ctilt\u201d possono venire le VERTIGINI<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg%22 width=%22355%22 height=%22355%22 alt=%22%22 class=%22wp-image-38352 alignnone size-full%22 style=%22font-family: inherit; font-size: inherit;%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr style=%22height: 10px;%22>\n<td style=%22width: 5%; height: 10px;%22>\n<p>Al mantenimento dell\u2019equilibrio partecipa tutto il corpo e basta che una di queste componenti vada in tilt che compare il disturbo dell\u2019equilibrio.<br \/>I disturbi dell&#8217;equilibrio rappresentano un SINTOMO di diverse condizioni patologiche.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg%22 width=%22359%22 height=%22359%22 alt=%22%22 class=%22wp-image-38356 alignnone size-full%22 style=%22font-family: inherit; font-size: inherit;%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr style=%22height: 144px;%22>\n<td style=%22width: 5%; height: 144px;%22>\n<p>L\u2019iter diagnostico \u00e8 per sua natura complesso, ma, identificata la causa, la cura sar\u00e0 mirata e pi\u00f9 efficace.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg%22 width=%22336%22 height=%22336%22 alt=%22%22 class=%22wp-image-38357 alignnone size-full%22 style=%22font-family: inherit; font-size: inherit;%22 \/><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8221; content_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 5%; width: 80%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg\" width=\"325\" height=\"325\" alt=\"\" class=\"wp-image-38352 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg 355w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5-300x300.jpg 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5-100x100.jpg 100w\" sizes=\"(max-width: 325px) 100vw, 325px\" \/><\/td>\n<td style=\"width: 10%; height: 240px;\">L\u2019uomo nel processo evolutivo ha conquistato la stazione eretta ricavandone numerosi vantaggi! Ma mantenere l\u2019equilibrio \u00e8 quasi un miracolo!<br \/>Implica un perfetto coordinamento tra numerosi sistemi: se uno va in \u201ctilt\u201d possono venire le VERTIGINI<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td style=\"width: 50%; height: 10px;\"><img decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg\" width=\"359\" height=\"359\" alt=\"\" class=\"wp-image-38356 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg 359w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA-300x300.jpg 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA-100x100.jpg 100w\" sizes=\"(max-width: 359px) 100vw, 359px\" \/><\/td>\n<td style=\"width: 50%; height: 10px;\">Al mantenimento dell\u2019equilibrio partecipa tutto il corpo e basta che una di queste componenti vada in tilt che compare il disturbo dell\u2019equilibrio.<br \/>I disturbi dell&#8217;equilibrio rappresentano un SINTOMO di diverse condizioni patologiche.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><img decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg\" width=\"336\" height=\"336\" alt=\"\" class=\"wp-image-38357 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg 336w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B-300x300.jpg 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B-100x100.jpg 100w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/><\/td>\n<td style=\"width: 50%;\">L\u2019iter diagnostico \u00e8 per sua natura complesso, ma, identificata la causa, la cura sar\u00e0 mirata e pi\u00f9 efficace.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Acufeni<\/h1>\n<p>L\u2019acufene \u00e8 una sensazione uditiva percepita dal paziente non legata ad una sorgente sonora presente nell\u2019ambiente esterno.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; content_tablet=&#8221;<\/p>\n<table border=%221%22 style=%22height: 5%; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 10%; height: 240px;%22>\n<p>Un acufene \u00e8 un disturbo uditivo costituito da rumori di vario genere (fischi, sibili, ronzii, pulsazioni, ecc.) percepiti come fastidiosi; tale fastidio pu\u00f2 giungere ad influenzare la qualit\u00e0 di vita del soggetto che ne \u00e8 affetto.<br \/>Le cause alla base di questo disturbo possono essere molte.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png%22 width=%22305%22 height=%22305%22 alt=%22%22 class=%22wp-image-38359 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr style=%22height: 10px;%22>\n<td style=%22width: 10%; height: 10px;%22>\n<p><strong>Cosa si deve fare?<\/strong><br \/>Terapia sintomatica e cercare la causa scatenante per una eventuale terapia mirata.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg%22 width=%22292%22 height=%22292%22 alt=%22%22 class=%22wp-image-38360 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8221; content_phone=&#8221;<\/p>\n<table border=%221%22 style=%22height: 5%; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 10%; height: 240px;%22>\n<p>Un acufene \u00e8 un disturbo uditivo costituito da rumori di vario genere (fischi, sibili, ronzii, pulsazioni, ecc.) percepiti come fastidiosi; tale fastidio pu\u00f2 giungere ad influenzare la qualit\u00e0 di vita del soggetto che ne \u00e8 affetto.<br \/>Le cause alla base di questo disturbo possono essere molte.<\/p>\n<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png%22 width=%22305%22 height=%22305%22 alt=%22%22 class=%22wp-image-38359 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr style=%22height: 10px;%22>\n<td style=%22width: 10%; height: 10px;%22>\n<p><strong>Cosa si deve fare?<\/strong><br \/>Terapia sintomatica e cercare la causa scatenante per una eventuale terapia mirata.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg%22 width=%22292%22 height=%22292%22 alt=%22%22 class=%22wp-image-38360 alignnone size-full%22 style=%22font-family: inherit; font-size: inherit;%22 \/><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8221; content_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 5%; width: 80%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png\" width=\"305\" height=\"305\" alt=\"\" class=\"wp-image-38359 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png 305w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E-300x300.png 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E-150x150.png 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E-100x100.png 100w\" sizes=\"auto, (max-width: 305px) 100vw, 305px\" \/><\/td>\n<td style=\"width: 10%; height: 240px;\">Un acufene \u00e8 un disturbo uditivo costituito da rumori di vario genere (fischi, sibili, ronzii, pulsazioni, ecc.) percepiti come fastidiosi; tale fastidio pu\u00f2 giungere ad influenzare la qualit\u00e0 di vita del soggetto che ne \u00e8 affetto.<br \/>Le cause alla base di questo disturbo possono essere molte.<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td style=\"width: 50%; height: 10px;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg\" width=\"292\" height=\"292\" alt=\"\" class=\"wp-image-38360 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg 292w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F-100x100.jpg 100w\" sizes=\"auto, (max-width: 292px) 100vw, 292px\" \/><\/td>\n<td style=\"width: 50%; height: 10px;\"><strong>Cosa si deve fare?<\/strong><br \/>Terapia sintomatica e cercare la causa scatenante per una eventuale terapia mirata.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Ipoacusia<\/h1>\n<p>L&#8217;udito \u00e8 il senso che ci permette di stabilire relazioni interpersonali (caratteristica dell\u2019essere umano).<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; content_tablet=&#8221;<\/p>\n<table border=%221%22 style=%22height: 848px; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 50%; height: 240px;%22>\n<p>Difficolt\u00e0 nel seguire conversazioni soprattutto nei luoghi affollati, Necessit\u00e0 di alzare il volume della tv o della radio, Difficolt\u00e0 nel comunicare al telefono, Disturbi dell\u2019attenzione.<br \/>In et\u00e0 pediatrica: disturbi dell\u2019apprendimento (il bambino che va male a scuola potrebbe essere ipoacusico!).<br \/>L\u2019ipoacusia o sordit\u00e0, \u00e8 la riduzione della capacit\u00e0 uditiva conseguente a un danno di una o pi\u00f9 parti del sistema uditivo.<br \/><strong>Sentire meno comporta <\/strong><strong>problemi importanti<\/strong><\/p>\n<p>Localizzare la sede del danno consente una terapia mirata.<br \/>Il primo passo \u00e8 efettuare l\u2019esame audiometrico.<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png%22 width=%22581%22 height=%22581%22 alt=%22%22 class=%22wp-image-38363 alignnone size-full%22 style=%22font-family: inherit; font-size: inherit;%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 50%;%22><strong>DIAGNOSI<br \/><\/strong>Primo passo la visita specialistica con il medico<br \/><strong>Audiologo:<\/strong><br \/>\u25cf storia clinica<br \/>\u25cfvalutazione delle condizioni del condotto uditivo e della membrana timpanica.<br \/><strong>Esami otofunzionali<\/strong><br \/>Devono inquadrare con la massima precisione le caratteristiche della perdita uditiva e definirne la gravit\u00e0.<br \/>1. Esame audiometrico<br \/>2. Impedenzometria<br \/>3. Audiometria vocale<br \/>4. Rilievo dei potenziali evocati uditivi (ABR)<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 50%;%22>Esami ematologici<br \/>Esami Strumentali<br \/>Es. Doppler<br \/>RMN encefalo e basicranio con contrasto<br \/><em>TAC PER STUDIO DELLE ROCCHE PETROSE E DELLE MASTOIDI A STRATO SOTTILE<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong><\/strong><\/p>\n<p><strong>Come curare le diverse forme di ipoacusia?<br \/><\/strong>Le ipoacusie trasmissive sono spesso curabili e reversibili: si possono risolvere con un trattamento medico che curi l\u2019infiammazione oppure con interventi chirurgici utili a ripristinare la corretta funzione della membrana timpanica e degli ossicini (timpanoplastica, ossiculoplastica).<br \/>Nel caso in cui l\u2019ipoacusia sia determinata da otosclerosi, l\u2019intervento \u00e8 la stapedoplastica.<br \/>L\u2019ipoacusia neurosensoriale \u00e8 solitamente pi\u00f9 grave di quella trasmissiva ed ha meno possibilit\u00e0 di risoluzione con una cura farmacologica e\/o chirurgica rispetto all\u2019ipoacusia trasmissiva.<br \/>Vanno poste in atto terapie idonee a correggere i fattori di rischio (vascolari, immunitari, ecc.), se presenti, in particolare vanno poste in atto alcune terapie anche solo per evitare un peggioramento della situazione uditiva.<br \/>Fa eccezione la sordit\u00e0 improvvisa che si giovando nel 70% dei casi circa di una terapia medica adeguata (cortisonici, diuretici e ossigenoterapia iperbarica, infiltrazioni endotimpaniche di cortisone) necessita di un trattamento tempestivo (il tempo \u00e8 prezioso).<\/p>\n<p><strong>Perch\u00e9 tanta resistenza alla protesi acustica?<\/strong><br \/>Chi non vede bene non ha problemi ad indossare gli occhiali<br \/>Eppure gli occhiali sono molto pi\u00f9 vistosi di una protesi acustica!<strong><br \/><\/strong><\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<table border=%221%22 style=%22height: 848px; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 50%; height: 240px;%22>\n<p>Difficolt\u00e0 nel seguire conversazioni soprattutto nei luoghi affollati, Necessit\u00e0 di alzare il volume della tv o della radio, Difficolt\u00e0 nel comunicare al telefono, Disturbi dell\u2019attenzione.<br \/>In et\u00e0 pediatrica: disturbi dell\u2019apprendimento (il bambino che va male a scuola potrebbe essere ipoacusico!).<br \/>L\u2019ipoacusia o sordit\u00e0, \u00e8 la riduzione della capacit\u00e0 uditiva conseguente a un danno di una o pi\u00f9 parti del sistema uditivo.<br \/><strong>Sentire meno comporta <\/strong><strong>problemi importanti<\/strong><\/p>\n<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/ipoacusia-sagoma-1024x874-1.png%22 width=%221024%22 height=%22874%22 alt=%22%22 class=%22wp-image-38362 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr style=%22height: 176px;%22>\n<td style=%22width: 50%; height: 176px;%22>\n<p>Localizzare la sede del danno consente una terapia mirata.<br \/>Il primo passo \u00e8 efettuare l\u2019esame audiometrico.<\/p>\n<\/p>\n<p><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png%22 width=%22581%22 height=%22581%22 alt=%22%22 class=%22wp-image-38363 alignnone size-full%22 \/><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 50%;%22><strong>DIAGNOSI<br \/><\/strong>Primo passo la visita specialistica con il medico<br \/><strong>Audiologo:<\/strong><br \/>\u25cf storia clinica<br \/>\u25cfvalutazione delle condizioni del condotto uditivo e della membrana timpanica.<br \/><strong>Esami otofunzionali<\/strong><br \/>Devono inquadrare con la massima precisione le caratteristiche della perdita uditiva e definirne la gravit\u00e0.<br \/>1. Esame audiometrico<br \/>2. Impedenzometria<br \/>3. Audiometria vocale<br \/>4.Rilievo dei potenziali evocati uditivi (ABR)<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 50%;%22>Esami ematologici<br \/>Esami Strumentali<br \/>Es. Doppler<br \/>RMN encefalo e basicranio con contrasto<br \/><em>TAC PER STUDIO DELLE ROCCHE PETROSE E DELLE MASTOIDI A STRATO SOTTILE<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong><\/strong><\/p>\n<p><strong>Come curare le diverse forme di ipoacusia?<br \/><\/strong>Le ipoacusie trasmissive sono spesso curabili e reversibili: si possono risolvere con un trattamento medico che curi l\u2019infiammazione oppure con interventi chirurgici utili a ripristinare la corretta funzione della membrana timpanica e degli ossicini (timpanoplastica, ossiculoplastica).<br \/>Nel caso in cui l\u2019ipoacusia sia determinata da otosclerosi, l\u2019intervento \u00e8 la stapedoplastica.<br \/>L\u2019ipoacusia neurosensoriale \u00e8 solitamente pi\u00f9 grave di quella trasmissiva ed ha meno possibilit\u00e0 di risoluzione con una cura farmacologica e\/o chirurgica rispetto all\u2019ipoacusia trasmissiva.<br \/>Vanno poste in atto terapie idonee a correggere i fattori di rischio (vascolari, immunitari, ecc.), se presenti, in particolare vanno poste in atto alcune terapie anche solo per evitare un peggioramento della situazione uditiva.<br \/>Fa eccezione la sordit\u00e0 improvvisa che si giovando nel 70% dei casi circa di una terapia medica adeguata (cortisonici, diuretici e ossigenoterapia iperbarica, infiltrazioni endotimpaniche di cortisone) necessita di un trattamento tempestivo (il tempo \u00e8 prezioso).<\/p>\n<p><strong>Perch\u00e9 tanta resistenza alla protesi acustica?<\/strong><br \/>Chi non vede bene non ha problemi ad indossare gli occhiali<br \/>Eppure gli occhiali sono molto pi\u00f9 vistosi di una protesi acustica!<strong><br \/><\/strong><\/p>\n<p>&#8221; content_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 848px; width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\">\n<p>Difficolt\u00e0 nel seguire conversazioni soprattutto nei luoghi affollati, Necessit\u00e0 di alzare il volume della tv o della radio, Difficolt\u00e0 nel comunicare al telefono, Disturbi dell\u2019attenzione.<br \/>In et\u00e0 pediatrica: disturbi dell\u2019apprendimento (il bambino che va male a scuola potrebbe essere ipoacusico!).<br \/>L\u2019ipoacusia o sordit\u00e0, \u00e8 la riduzione della capacit\u00e0 uditiva conseguente a un danno di una o pi\u00f9 parti del sistema uditivo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sentire meno comporta <\/strong><strong>problemi importanti<\/strong><\/p>\n<p>Localizzare la sede del danno consente una terapia mirata.<br \/>Il primo passo \u00e8 efettuare l\u2019esame audiometrico.<\/p>\n<p><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png\" width=\"581\" height=\"581\" alt=\"\" class=\"wp-image-38363 alignnone size-full\" style=\"font-family: inherit; font-size: inherit;\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png 581w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A-480x480.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 581px, 100vw\" \/><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">\n<p><strong>DIAGNOSI<br \/><\/strong>Primo passo la visita specialistica con il medico<br \/><strong>Audiologo:<\/strong><br \/>\u25cf storia clinica<br \/>\u25cfvalutazione delle condizioni del condotto uditivo e della membrana timpanica.<br \/><strong>Esami otofunzionali<\/strong><br \/>Devono inquadrare con la massima precisione le caratteristiche della perdita uditiva e definirne la gravit\u00e0.<br \/>1. Esame audiometrico<br \/>2. Impedenzometria<br \/>3. Audiometria vocale<br \/>4. Rilievo dei potenziali evocati uditivi (ABR)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">\n<p>Esami ematologici<br \/>Esami Strumentali<br \/>Es. Doppler<br \/>RMN encefalo e basicranio con contrasto<\/p>\n<p><em>TAC PER STUDIO DELLE ROCCHE PETROSE E DELLE MASTOIDI A STRATO SOTTILE<\/em><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Come curare le diverse forme di ipoacusia?<br \/><\/strong>Le ipoacusie trasmissive sono spesso curabili e reversibili: si possono risolvere con un trattamento medico che curi l\u2019infiammazione oppure con interventi chirurgici utili a ripristinare la corretta funzione della membrana timpanica e degli ossicini (timpanoplastica, ossiculoplastica).<br \/>Nel caso in cui l\u2019ipoacusia sia determinata da otosclerosi, l\u2019intervento \u00e8 la stapedoplastica.<br \/>L\u2019ipoacusia neurosensoriale \u00e8 solitamente pi\u00f9 grave di quella trasmissiva ed ha meno possibilit\u00e0 di risoluzione con una cura farmacologica e\/o chirurgica rispetto all\u2019ipoacusia trasmissiva.<br \/>Vanno poste in atto terapie idonee a correggere i fattori di rischio (vascolari, immunitari, ecc.), se presenti, in particolare vanno poste in atto alcune terapie anche solo per evitare un peggioramento della situazione uditiva.<br \/>Fa eccezione la sordit\u00e0 improvvisa che si giovando nel 70% dei casi circa di una terapia medica adeguata (cortisonici, diuretici e ossigenoterapia iperbarica, infiltrazioni endotimpaniche di cortisone) necessita di un trattamento tempestivo (il tempo \u00e8 prezioso).<\/p>\n<p><strong>Perch\u00e9 tanta resistenza alla protesi acustica?<\/strong><br \/>Chi non vede bene non ha problemi ad indossare gli occhiali<br \/>Eppure gli occhiali sono molto pi\u00f9 vistosi di una protesi acustica!<strong><br \/><\/strong><\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Ipoacusia Improvvisa<\/h1>\n<p>Insorge improvvisamente (come un fulmine a ciel sereno), generalmente colpisce un solo orecchio ma ha un impatto devastante sulla qualit\u00e0 di vita; il quadro drammatico \u00e8 peggiorato anche dal fatto che spesso si accompagna a violenti acufeni e vertigini talora imponenti.<br \/>Quasi sempre interessa un solo orecchio; la forma bilaterale \u00e8 molto rara (2-3% dei casi).<br \/>L\u2019ipoacusia improvvisa bilaterale, fortunatamente molto pi\u00f9 rara, ha spesso cause vascolari, metaboliche, immunologiche, infettive, neoplastiche, tossiche chimiche o infiammatorie, anche se l\u2019occorrenza bilaterale non \u00e8 patognomonica per queste cause.<\/p>\n<p>Un concetto da tenere bene a mente \u00e8 che tanto pi\u00f9 passa il tempo dall\u2019esordio del sintomo tanto minori sono le probabilit\u00e0 di recupero.<br \/>Quindi se ti capita di incorrere in questo problema la visita \u00e8 urgente.<br \/>Se si tratta di una causa banale (es. tappo di cerume) il problema verr\u00e0 rapidamente risolto.<br \/>Se si tratta di ipoacusia improvvisa va iniziata rapidamente la terapia e l\u2019iter diagnostico!<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Cause<br \/><\/strong>Sono state ipotizzate pi\u00f9 di cento possibili cause capaci di determinare questo sintomo.<\/p>\n<p><strong>Infettiva<\/strong><br \/>\u201cVirus neurotropi\u201d: herpes zoster, herpes simplex, influenza, parainfluenza, mononucleosi, morbillo, parotite, citomegalovirus, Coxsackie, HIV, FSME, meningite batterica, HIV, febbre di Lassa, malattia di Lyme, parotite, micoplasma, sifilide, toxoplasmosi, Borreliosi, febbre delle Montagne Rocciose.<\/p>\n<p><strong>Autoimmune<\/strong><br \/>Malattia dell\u2019orecchio interno autoimmune, Malattia di Beh\u00e7et, Sindrome di Cogan, Lupus eritematoso sistemico.<\/p>\n<p><strong>Otologica<\/strong><br \/>Perdita dell\u2019udito fluttuante Malattia di M\u00e9ni\u00e8re, Otosclerosi, Acquedotto vestibolare ingrandito, Barotrauma e trauma cranico.<\/p>\n<p><strong>Tossica<\/strong><br \/>Antibiotici: aminoglicosidici, agenti chemioterapici, antinfiammatori non steroidei (es. salicilati)<\/p>\n<p><strong>Metabolica<\/strong><br \/>Diabete mellito, ipotiroidismo, tossiche (ad es. droghe, farmaci, veleni industriali), insufficienza renale che richiede dialisi.<\/p>\n<p><span style=\"color: #800000;\"><strong>Ma una causa si riesce ad identificare solo in un 20% di casi per cui viene definita \u201cIdiopatica\u201d.<\/strong><\/span><\/p>\n<p><strong>\\\\Iter diagnostico<\/strong><br \/>Proprio per questa complessit\u00e0 di cause \u00e8 necessario effettuare un percorso diagnostico complesso ed articolato. Se si riesce ad identificare una causa specifica si potr\u00e0 mettere in atto una terapia mirata con maggiori probabilit\u00e0 di successi.<\/p>\n<p><strong>Terapia si avvale di<\/strong><br \/>\u25cf Terapia medica (cortisonici e vasodilatatori)<br \/>\u25cf Iniezioni intratimpaniche di cortisone<br \/>\u25cf Terapia iperbarica<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Patologia acuta e cronica dell\u2019orecchio medio<\/h1>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 50px; width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 700px;\">\n<td style=\"width: 50%; height: 700px;\">\n<p>L\u2019otite \u00e8 il termine usato per descrivere una variet\u00e0 di segni, sintomi e reperti fisici che derivano dal sofferenza a breve (se acuta) o a lungo termine (se cronica) dell\u2019orecchio medio. Dolore, Secrezione, Ipoacusia, \u00e8 causata da infezione o infiammazione<strong><\/strong><\/p>\n<p><strong>Il pericolo principale \u00e8 dato dalle possibili Complicanze<\/strong><\/p>\n<p><strong>ATTENZIONE<br \/><\/strong>L\u2019infezione pu\u00f2 diffondersi alle strutture vicine determinando gravi conseguenze<\/p>\n<p><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4AEBD5F5-BCEE-4CF4-AA64-41664A453668.png\" width=\"407\" height=\"429\" alt=\"\" class=\"wp-image-38366 alignnone size-full\" style=\"font-family: inherit; font-size: inherit;\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4AEBD5F5-BCEE-4CF4-AA64-41664A453668.png 407w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4AEBD5F5-BCEE-4CF4-AA64-41664A453668-285x300.png 285w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Terapia<\/strong><br \/>Gestione medica da iniziare prima possibile<\/p>\n<table border=\"1\" style=\"width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\">1. Antibiotici<br \/>2. Decongestionanti nasali<br \/>3. Antistaminici H1<br \/>4. Analgesici + antipiretici<br \/>5. Buona pulizia dell\u2019orecchio dalle secrezioni<br \/>6. Fumenti caldi o aereosol<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">Controllo dopo 48 ore<br \/>Se il mal d\u2019orecchio e la febbre persistono: passare a un antibiotico a pi\u00f9 ampio spettro.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">Quando il dolore e la febbre diminuiscono: continuare lo stesso trattamento per 10-14 giorni<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">\n<p>Se la membrana timpanica \u00e8 gonfia va eseguita una miringotomia per scaricare l\u2019orecchio medio<\/p>\n<p><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/7B0EA063-E07E-4B50-A941-00F33F8B8CF5.png\" width=\"443\" height=\"208\" alt=\"\" class=\"wp-image-38367 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/7B0EA063-E07E-4B50-A941-00F33F8B8CF5.png 443w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/7B0EA063-E07E-4B50-A941-00F33F8B8CF5-300x141.png 300w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/A548BB41-EA01-4A31-9923-595E35B9B5D6.png\" width=\"146\" height=\"104\" alt=\"\" class=\"wp-image-38368 alignnone size-full\" style=\"font-family: inherit; font-size: inherit;\" \/><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Riesaminare dopo 3 mesi<\/strong><br \/>\u25cf Nessun versamento: nessun ulteriore trattamento<br \/>\u25cfSe il versamento persiste: trattare come Otite Media con effusione: una piccola incisione per aspirare il liquido contenuto nell\u2019orecchio medio eventualmente posizionando un tubicino che garantisce il drenaggio.<br \/>\u25cf Presenza di ascesso o mastoidite coalescente: va effettuato un intervento pi\u00f9 impegnativo, la mastoidectomia.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Colesteatoma<\/h1>\n<p>Il colesteatoma \u00e8 una cisti epiteliale all\u2019interno delle cavit\u00e0 dell\u2019orecchio medio. Si presenta come una cisti o come una tasca ripiena di squame e aumenta di volume progressivamente determinando infezioni ricorrenti e distruzione delle strutture ossee circostanti (facilitando la diffusione e la comparsa di complicanze).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;40px||||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; custom_padding_tablet=&#8221;0px|0px|0px|0px|true|false&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; link_text_color=&#8221;#3298ba&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;justify&#8221; header_font_size=&#8221;33px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;|-20px||-20px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; link_font_size_tablet=&#8221;&#8221; link_font_size_phone=&#8221;23px&#8221; link_font_size_last_edited=&#8221;on|phone&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;&#8221; header_text_align_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;34px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_line_height_tablet=&#8221;1.4em&#8221; header_line_height_phone=&#8221;&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Per saperne di pi\u00f9 consulta il sito: <strong><a href=\"https:\/\/www.dottorclaudiopianura.it\/\">www.dottorclaudiopianura.it<\/a><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;90px||90px|&#8221; da_disable_devices=&#8221;off|off|off&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#3298ba&#8221; border_style_top=&#8221;dotted&#8221; border_width_bottom=&#8221;5px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|700|||||||&#8221; text_text_color=&#8221;#3298ba&#8221; text_font_size=&#8221;35px&#8221; text_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;30px&#8221; text_font_size_phone=&#8221;&#8221; text_font_size_last_edited=&#8221;on|tablet&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Oltre alla normale patologia ORL in particolare mi occupo di:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Disturbi dell\u2019equilibrio<\/h1>\n<p>L\u2019equilibrio \u201c\u00e8 la capacit\u00e0 di regolare e mantenere il corpo con opportuni e rapidi aggiustamenti di posizione contro la forza di gravit\u00e0, in posizione stabile ed eretta e di camminare senza cadere o deviare dalla linea prefissata\u201d.<br \/>\u00c8 considerato il \u201cVI Senso\u201d (\u00e8 il senso della relazione con l\u2019ambiente).<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; content_tablet=&#8221;<\/p>\n<table border=%221%22 style=%22height: 5%; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 50%; height: 240px;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg%22 width=%22325%22 height=%22325%22 alt=%22%22 class=%22wp-image-38352 alignnone size-full%22 \/><\/td>\n<td style=%22width: 10%; height: 240px;%22>L\u2019uomo nel processo evolutivo ha conquistato la stazione eretta ricavandone numerosi vantaggi! Ma mantenere l\u2019equilibrio \u00e8 quasi un miracolo!<br \/>Implica un perfetto coordinamento tra numerosi sistemi: se uno va in \u201ctilt\u201d possono venire le VERTIGINI<\/td>\n<\/tr>\n<tr style=%22height: 10px;%22>\n<td style=%22width: 50%; height: 10px;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg%22 width=%22359%22 height=%22359%22 alt=%22%22 class=%22wp-image-38356 alignnone size-full%22 \/><\/td>\n<td style=%22width: 50%; height: 10px;%22>Al mantenimento dell\u2019equilibrio partecipa tutto il corpo e basta che una di queste componenti vada in tilt che compare il disturbo dell\u2019equilibrio.<br \/>I disturbi dell&#8217;equilibrio rappresentano un SINTOMO di diverse condizioni patologiche.<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 50%;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg%22 width=%22336%22 height=%22336%22 alt=%22%22 class=%22wp-image-38357 alignnone size-full%22 \/><\/td>\n<td style=%22width: 50%;%22>L\u2019iter diagnostico \u00e8 per sua natura complesso, ma, identificata la causa, la cura sar\u00e0 mirata e pi\u00f9 efficace.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 5%; width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg\" width=\"325\" height=\"325\" alt=\"\" class=\"wp-image-38352 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5.jpg 355w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5-300x300.jpg 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/512332FA-CEED-4F9B-9971-4E836A98E7D5-100x100.jpg 100w\" sizes=\"(max-width: 325px) 100vw, 325px\" \/><\/td>\n<td style=\"width: 10%; height: 240px;\">L\u2019uomo nel processo evolutivo ha conquistato la stazione eretta ricavandone numerosi vantaggi! Ma mantenere l\u2019equilibrio \u00e8 quasi un miracolo!<br \/>Implica un perfetto coordinamento tra numerosi sistemi: se uno va in \u201ctilt\u201d possono venire le VERTIGINI<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td style=\"width: 50%; height: 10px;\"><img decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg\" width=\"359\" height=\"359\" alt=\"\" class=\"wp-image-38356 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA.jpg 359w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA-300x300.jpg 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/66908DD5-9556-4295-BA5B-731EE3334CAA-100x100.jpg 100w\" sizes=\"(max-width: 359px) 100vw, 359px\" \/><\/td>\n<td style=\"width: 50%; height: 10px;\">Al mantenimento dell\u2019equilibrio partecipa tutto il corpo e basta che una di queste componenti vada in tilt che compare il disturbo dell\u2019equilibrio.<br \/>I disturbi dell&#8217;equilibrio rappresentano un SINTOMO di diverse condizioni patologiche.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><img decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg\" width=\"336\" height=\"336\" alt=\"\" class=\"wp-image-38357 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B.jpg 336w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B-300x300.jpg 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/0C61C928-BFDC-4600-BECD-BB280274DF3B-100x100.jpg 100w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/><\/td>\n<td style=\"width: 50%;\">L\u2019iter diagnostico \u00e8 per sua natura complesso, ma, identificata la causa, la cura sar\u00e0 mirata e pi\u00f9 efficace.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Acufeni<\/h1>\n<p>L\u2019acufene \u00e8 una sensazione uditiva percepita dal paziente non legata ad una sorgente sonora presente nell\u2019ambiente esterno.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; content_tablet=&#8221;<\/p>\n<table border=%221%22 style=%22height: 5%; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 50%; height: 240px;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png%22 width=%22305%22 height=%22305%22 alt=%22%22 class=%22wp-image-38359 alignnone size-full%22 \/><\/td>\n<td style=%22width: 10%; height: 240px;%22>Un acufene \u00e8 un disturbo uditivo costituito da rumori di vario genere (fischi, sibili, ronzii, pulsazioni, ecc.) percepiti come fastidiosi; tale fastidio pu\u00f2 giungere ad influenzare la qualit\u00e0 di vita del soggetto che ne \u00e8 affetto.<br \/>Le cause alla base di questo disturbo possono essere molte.<\/td>\n<\/tr>\n<tr style=%22height: 10px;%22>\n<td style=%22width: 50%; height: 10px;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg%22 width=%22292%22 height=%22292%22 alt=%22%22 class=%22wp-image-38360 alignnone size-full%22 \/><\/td>\n<td style=%22width: 50%; height: 10px;%22><strong>Cosa si deve fare?<\/strong><br \/>Terapia sintomatica e cercare la causa scatenante per una eventuale terapia mirata.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 5%; width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png\" width=\"305\" height=\"305\" alt=\"\" class=\"wp-image-38359 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E.png 305w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E-300x300.png 300w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E-150x150.png 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/51EF2FE5-E79E-4306-9299-1F864F75945E-100x100.png 100w\" sizes=\"auto, (max-width: 305px) 100vw, 305px\" \/><\/td>\n<td style=\"width: 10%; height: 240px;\">Un acufene \u00e8 un disturbo uditivo costituito da rumori di vario genere (fischi, sibili, ronzii, pulsazioni, ecc.) percepiti come fastidiosi; tale fastidio pu\u00f2 giungere ad influenzare la qualit\u00e0 di vita del soggetto che ne \u00e8 affetto.<br \/>Le cause alla base di questo disturbo possono essere molte.<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td style=\"width: 50%; height: 10px;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg\" width=\"292\" height=\"292\" alt=\"\" class=\"wp-image-38360 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F.jpg 292w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F-150x150.jpg 150w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4686EACD-8B80-46A5-9F1A-2D4C2FF6F25F-100x100.jpg 100w\" sizes=\"auto, (max-width: 292px) 100vw, 292px\" \/><\/td>\n<td style=\"width: 50%; height: 10px;\"><strong>Cosa si deve fare?<\/strong><br \/>Terapia sintomatica e cercare la causa scatenante per una eventuale terapia mirata.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Ipoacusia<\/h1>\n<p>L&#8217;udito \u00e8 il senso che ci permette di stabilire relazioni interpersonali (caratteristica dell\u2019essere umano).<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; content_tablet=&#8221;<\/p>\n<table border=%221%22 style=%22height: 848px; width: 100%; border-collapse: collapse;%22>\n<tbody>\n<tr style=%22height: 240px;%22>\n<td style=%22width: 50%; height: 240px;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/ipoacusia-sagoma-1024x874-1.png%22 width=%221024%22 height=%22874%22 alt=%22%22 class=%22wp-image-38362 alignnone size-full%22 \/><\/td>\n<td style=%22width: 50%; height: 240px;%22>Difficolt\u00e0 nel seguire conversazioni soprattutto nei luoghi affollati, Necessit\u00e0 di alzare il volume della tv o della radio, Difficolt\u00e0 nel comunicare al telefono, Disturbi dell\u2019attenzione.<br \/>\nIn et\u00e0 pediatrica: disturbi dell\u2019apprendimento (il bambino che va male a scuola potrebbe essere ipoacusico!).<br \/>\nL\u2019ipoacusia o sordit\u00e0, \u00e8 la riduzione della capacit\u00e0 uditiva conseguente a un danno di una o pi\u00f9 parti del sistema uditivo.<br \/>\n<strong>Sentire meno comporta <\/strong><strong>problemi importanti<\/strong><\/td>\n<\/tr>\n<tr style=%22height: 176px;%22>\n<td style=%22width: 50%; height: 176px;%22><img src=%22https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png%22 width=%22581%22 height=%22581%22 alt=%22%22 class=%22wp-image-38363 alignnone size-full%22 \/><\/td>\n<td style=%22width: 50%; height: 176px;%22>Localizzare la sede del danno consente una terapia mirata.<br \/>\nIl primo passo \u00e8 efettuare l\u2019esame audiometrico.<\/td>\n<\/tr>\n<tr>\n<td style=%22width: 50%;%22><strong>DIAGNOSI<\/strong><br \/>\nPrimo passo la visita specialistica con il medico<br \/>\n<strong>Audiologo:<\/strong><br \/>\n\u25cf storia clinica<br \/>\n\u25cfvalutazione delle condizioni del condotto uditivo e della membrana timpanica.<br \/>\n<strong>Esami otofunzionali<\/strong><br \/>\nDevono inquadrare con la massima precisione le caratteristiche della perdita uditiva e definirne la gravit\u00e0.<br \/>\n1. Esame audiometrico<br \/>\n2. Impedenzometria<br \/>\n3. Audiometria vocale<br \/>\n4. Rilievo dei potenziali evocati uditivi (ABR)<\/td>\n<td style=%22width: 50%;%22>Esami ematologici<br \/>\nEsami Strumentali<br \/>\nEs. Doppler<br \/>\nRMN encefalo e basicranio con contrasto<br \/>\n<em>TAC PER STUDIO DELLE ROCCHE PETROSE E DELLE MASTOIDI A STRATO SOTTILE<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<strong>Come curare le diverse forme di ipoacusia?<br \/>\n<\/strong>Le ipoacusie trasmissive sono spesso curabili e reversibili: si possono risolvere con un trattamento medico che curi l\u2019infiammazione oppure con interventi chirurgici utili a ripristinare la corretta funzione della membrana timpanica e degli ossicini (timpanoplastica, ossiculoplastica).<br \/>\nNel caso in cui l\u2019ipoacusia sia determinata da otosclerosi, l\u2019intervento \u00e8 la stapedoplastica.<br \/>\nL\u2019ipoacusia neurosensoriale \u00e8 solitamente pi\u00f9 grave di quella trasmissiva ed ha meno possibilit\u00e0 di risoluzione con una cura farmacologica e\/o chirurgica rispetto all\u2019ipoacusia trasmissiva.<br \/>\nVanno poste in atto terapie idonee a correggere i fattori di rischio (vascolari, immunitari, ecc.), se presenti, in particolare vanno poste in atto alcune terapie anche solo per evitare un peggioramento della situazione uditiva.<br \/>\nFa eccezione la sordit\u00e0 improvvisa che si giovando nel 70% dei casi circa di una terapia medica adeguata (cortisonici, diuretici e ossigenoterapia iperbarica, infiltrazioni endotimpaniche di cortisone) necessita di un trattamento tempestivo (il tempo \u00e8 prezioso).<\/p>\n<p><strong>Perch\u00e9 tanta resistenza alla protesi acustica?<\/strong><br \/>\nChi non vede bene non ha problemi ad indossare gli occhiali<br \/>\nEppure gli occhiali sono molto pi\u00f9 vistosi di una protesi acustica!<strong><br \/>\n<\/strong>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 848px; width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png\" width=\"581\" height=\"581\" alt=\"\" class=\"wp-image-38363 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A.png 581w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/9A0D59F1-9C92-441B-9430-D5CF2BA3E39A-480x480.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 581px, 100vw\" \/><\/td>\n<td style=\"width: 50%; height: 240px;\">\n<p>Difficolt\u00e0 nel seguire conversazioni soprattutto nei luoghi affollati, Necessit\u00e0 di alzare il volume della tv o della radio, Difficolt\u00e0 nel comunicare al telefono, Disturbi dell\u2019attenzione.<br \/>In et\u00e0 pediatrica: disturbi dell\u2019apprendimento (il bambino che va male a scuola potrebbe essere ipoacusico!).<br \/>L\u2019ipoacusia o sordit\u00e0, \u00e8 la riduzione della capacit\u00e0 uditiva conseguente a un danno di una o pi\u00f9 parti del sistema uditivo.<\/p>\n<p><strong>Sentire meno comporta <\/strong><strong>problemi importanti<\/strong><\/p>\n<p><strong><br \/><\/strong>Localizzare la sede del danno consente una terapia mirata.<br \/>Il primo passo \u00e8 efettuare l\u2019esame audiometrico.<strong><br \/><\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><strong>DIAGNOSI<\/strong><br \/>Primo passo la visita specialistica con il medico<br \/><strong>Audiologo:<\/strong><br \/>\u25cf storia clinica<br \/>\u25cfvalutazione delle condizioni del condotto uditivo e della membrana timpanica.<br \/><strong>Esami otofunzionali<\/strong><br \/>Devono inquadrare con la massima precisione le caratteristiche della perdita uditiva e definirne la gravit\u00e0.<br \/>1. Esame audiometrico<br \/>2. Impedenzometria<br \/>3. Audiometria vocale<br \/>4. Rilievo dei potenziali evocati uditivi (ABR)<\/td>\n<td style=\"width: 50%;\">\n<p>Esami ematologici<br \/>Esami Strumentali<br \/>Es. Doppler<br \/>RMN encefalo e basicranio con contrasto<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>TAC PER STUDIO DELLE ROCCHE PETROSE E DELLE MASTOIDI A STRATO SOTTILE<\/em><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Come curare le diverse forme di ipoacusia?<br \/><\/strong>Le ipoacusie trasmissive sono spesso curabili e reversibili: si possono risolvere con un trattamento medico che curi l\u2019infiammazione oppure con interventi chirurgici utili a ripristinare la corretta funzione della membrana timpanica e degli ossicini (timpanoplastica, ossiculoplastica).<br \/>Nel caso in cui l\u2019ipoacusia sia determinata da otosclerosi, l\u2019intervento \u00e8 la stapedoplastica.<br \/>L\u2019ipoacusia neurosensoriale \u00e8 solitamente pi\u00f9 grave di quella trasmissiva ed ha meno possibilit\u00e0 di risoluzione con una cura farmacologica e\/o chirurgica rispetto all\u2019ipoacusia trasmissiva.<br \/>Vanno poste in atto terapie idonee a correggere i fattori di rischio (vascolari, immunitari, ecc.), se presenti, in particolare vanno poste in atto alcune terapie anche solo per evitare un peggioramento della situazione uditiva.<br \/>Fa eccezione la sordit\u00e0 improvvisa che si giovando nel 70% dei casi circa di una terapia medica adeguata (cortisonici, diuretici e ossigenoterapia iperbarica, infiltrazioni endotimpaniche di cortisone) necessita di un trattamento tempestivo (il tempo \u00e8 prezioso).<\/p>\n<p><strong>Perch\u00e9 tanta resistenza alla protesi acustica?<\/strong><br \/>Chi non vede bene non ha problemi ad indossare gli occhiali<br \/>Eppure gli occhiali sono molto pi\u00f9 vistosi di una protesi acustica!<strong><br \/><\/strong><\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Ipoacusia Improvvisa<\/h1>\n<p>Insorge improvvisamente (come un fulmine a ciel sereno), generalmente colpisce un solo orecchio ma ha un impatto devastante sulla qualit\u00e0 di vita; il quadro drammatico \u00e8 peggiorato anche dal fatto che spesso si accompagna a violenti acufeni e vertigini talora imponenti.<br \/>Quasi sempre interessa un solo orecchio; la forma bilaterale \u00e8 molto rara (2-3% dei casi).<br \/>L\u2019ipoacusia improvvisa bilaterale, fortunatamente molto pi\u00f9 rara, ha spesso cause vascolari, metaboliche, immunologiche, infettive, neoplastiche, tossiche chimiche o infiammatorie, anche se l\u2019occorrenza bilaterale non \u00e8 patognomonica per queste cause.<\/p>\n<p>Un concetto da tenere bene a mente \u00e8 che tanto pi\u00f9 passa il tempo dall\u2019esordio del sintomo tanto minori sono le probabilit\u00e0 di recupero.<br \/>Quindi se ti capita di incorrere in questo problema la visita \u00e8 urgente.<br \/>Se si tratta di una causa banale (es. tappo di cerume) il problema verr\u00e0 rapidamente risolto.<br \/>Se si tratta di ipoacusia improvvisa va iniziata rapidamente la terapia e l\u2019iter diagnostico!<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Cause<br \/><\/strong>Sono state ipotizzate pi\u00f9 di cento possibili cause capaci di determinare questo sintomo.<\/p>\n<p><strong>Infettiva<\/strong><br \/>\u201cVirus neurotropi\u201d: herpes zoster, herpes simplex, influenza, parainfluenza, mononucleosi, morbillo, parotite, citomegalovirus, Coxsackie, HIV, FSME, meningite batterica, HIV, febbre di Lassa, malattia di Lyme, parotite, micoplasma, sifilide, toxoplasmosi, Borreliosi, febbre delle Montagne Rocciose.<\/p>\n<p><strong>Autoimmune<\/strong><br \/>Malattia dell\u2019orecchio interno autoimmune, Malattia di Beh\u00e7et, Sindrome di Cogan, Lupus eritematoso sistemico.<\/p>\n<p><strong>Otologica<\/strong><br \/>Perdita dell\u2019udito fluttuante Malattia di M\u00e9ni\u00e8re, Otosclerosi, Acquedotto vestibolare ingrandito, Barotrauma e trauma cranico.<\/p>\n<p><strong>Tossica<\/strong><br \/>Antibiotici: aminoglicosidici, agenti chemioterapici, antinfiammatori non steroidei (es. salicilati)<\/p>\n<p><strong>Metabolica<\/strong><br \/>Diabete mellito, ipotiroidismo, tossiche (ad es. droghe, farmaci, veleni industriali), insufficienza renale che richiede dialisi.<\/p>\n<p><span style=\"color: #800000;\"><strong>Ma una causa si riesce ad identificare solo in un 20% di casi per cui viene definita \u201cIdiopatica\u201d.<\/strong><\/span><\/p>\n<p><strong>\\\\Iter diagnostico<\/strong><br \/>Proprio per questa complessit\u00e0 di cause \u00e8 necessario effettuare un percorso diagnostico complesso ed articolato. Se si riesce ad identificare una causa specifica si potr\u00e0 mettere in atto una terapia mirata con maggiori probabilit\u00e0 di successi.<\/p>\n<p><strong>Terapia si avvale di<\/strong><br \/>\u25cf Terapia medica (cortisonici e vasodilatatori)<br \/>\u25cf Iniezioni intratimpaniche di cortisone<br \/>\u25cf Terapia iperbarica<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;||20px||false|false&#8221; custom_padding=&#8221;27px|0px|40px|0px|false|false&#8221; border_width_bottom=&#8221;4px&#8221; border_color_bottom=&#8221;#3298ba&#8221; border_style_bottom=&#8221;dotted&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Patologia acuta e cronica dell\u2019orecchio medio<\/h1>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;Clicca qui per leggere di pi\u00f9&#8221; open_toggle_text_color=&#8221;#3298ba&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#3298ba&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;17px&#8221; open_icon_color=&#8221;#3298ba&#8221; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;17px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#3298ba&#8221; title_font=&#8221;Poppins||||||||&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_align=&#8221;justify&#8221; body_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_color_all=&#8221;#3298ba&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"1\" style=\"height: 10px; width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr style=\"height: 240px;\">\n<td style=\"width: 50%; height: 240px;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4AEBD5F5-BCEE-4CF4-AA64-41664A453668.png\" width=\"407\" height=\"429\" alt=\"\" class=\"wp-image-38366 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4AEBD5F5-BCEE-4CF4-AA64-41664A453668.png 407w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/4AEBD5F5-BCEE-4CF4-AA64-41664A453668-285x300.png 285w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/td>\n<td style=\"width: 50%; height: 240px;\">\n<p>L\u2019otite \u00e8 il termine usato per descrivere una variet\u00e0 di segni, sintomi e reperti fisici che derivano dal sofferenza a breve (se acuta) o a lungo termine (se cronica) dell\u2019orecchio medio. Dolore, Secrezione, Ipoacusia, \u00e8 causata da infezione o infiammazione<\/p>\n<p><strong>Il pericolo principale \u00e8 dato dalle possibili Complicanze<\/strong><\/p>\n<p><strong>ATTENZIONE<br \/><\/strong>L\u2019infezione pu\u00f2 diffondersi alle strutture vicine determinando gravi conseguenze<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Terapia<\/strong><br \/>Gestione medica da iniziare prima possibile<\/p>\n<table border=\"1\" style=\"width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\">1. Antibiotici<br \/>2. Decongestionanti nasali<br \/>3. Antistaminici H1<br \/>4. Analgesici + antipiretici<br \/>5. Buona pulizia dell\u2019orecchio dalle secrezioni<br \/>6. Fumenti caldi o aereosol<\/td>\n<td style=\"width: 33.3333%;\">Controllo dopo 48 ore<br \/>Se il mal d\u2019orecchio e la febbre persistono: passare a un antibiotico a pi\u00f9 ampio spettro.<\/td>\n<td style=\"width: 33.3333%;\">Quando il dolore e la febbre diminuiscono: continuare lo stesso trattamento per 10-14 giorni<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">Se la membrana timpanica \u00e8 gonfia va eseguita una miringotomia per scaricare l\u2019orecchio medio<\/td>\n<td style=\"width: 33.3333%;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/7B0EA063-E07E-4B50-A941-00F33F8B8CF5.png\" width=\"443\" height=\"208\" alt=\"\" class=\"wp-image-38367 alignnone size-full\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/7B0EA063-E07E-4B50-A941-00F33F8B8CF5.png 443w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/7B0EA063-E07E-4B50-A941-00F33F8B8CF5-300x141.png 300w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><\/td>\n<td style=\"width: 33.3333%;\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/A548BB41-EA01-4A31-9923-595E35B9B5D6.png\" width=\"146\" height=\"104\" alt=\"\" class=\"wp-image-38368 alignnone size-full\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Riesaminare dopo 3 mesi<\/strong><br \/>\u25cf Nessun versamento: nessun ulteriore trattamento<br \/>\u25cfSe il versamento persiste: trattare come Otite Media con effusione: una piccola incisione per aspirare il liquido contenuto nell\u2019orecchio medio eventualmente posizionando un tubicino che garantisce il drenaggio.<br \/>\u25cf Presenza di ascesso o mastoidite coalescente: va effettuato un intervento pi\u00f9 impegnativo, la mastoidectomia.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; header_font=&#8221;Poppins||||||||&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Colesteatoma<\/h1>\n<p>Il colesteatoma \u00e8 una cisti epiteliale all\u2019interno delle cavit\u00e0 dell\u2019orecchio medio. Si presenta come una cisti o come una tasca ripiena di squame e aumenta di volume progressivamente determinando infezioni ricorrenti e distruzione delle strutture ossee circostanti (facilitando la diffusione e la comparsa di complicanze).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;40px||||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; custom_padding_tablet=&#8221;0px|0px|0px|0px|true|false&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; link_text_color=&#8221;#3298ba&#8221; header_font=&#8221;Poppins||||||||&#8221; header_text_align=&#8221;justify&#8221; header_font_size=&#8221;33px&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;&#8221; header_text_align_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;34px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_line_height_tablet=&#8221;1.4em&#8221; header_line_height_phone=&#8221;&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Per saperne di pi\u00f9 consulta il sito: <strong><a href=\"https:\/\/www.dottorclaudiopianura.it\/\">www.dottorclaudiopianura.it<\/a><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#e7f3fd&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;360deg&#8221; background_color_gradient_stops=&#8221;#3298ba 0%|#003870 100%&#8221; background_color_gradient_start=&#8221;#3298ba&#8221; background_color_gradient_end=&#8221;#003870&#8243; custom_padding=&#8221;70px||70px||true|false&#8221; custom_padding_tablet=&#8221;40px||40px||true|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;55px&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;50px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_2_line_height_tablet=&#8221;1.2em&#8221; header_2_line_height_phone=&#8221;&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/acufeni-sagoma-677&#215;1024-1.png&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_left&#8221; custom_padding=&#8221;||90px||false|false&#8221; custom_padding_tablet=&#8221;||40px||false|false&#8221; custom_padding_phone=&#8221;&#8221; background_last_edited=&#8221;on|tablet&#8221; background_enable_image_tablet=&#8221;off&#8221; da_disable_devices=&#8221;off|off|off&#8221; border_width_top=&#8221;70px&#8221; border_color_top=&#8221;#FFFFFF&#8221; border_width_top_tablet=&#8221;0px&#8221; border_width_top_phone=&#8221;&#8221; border_width_top_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3298ba&#8221; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||45px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|-30px|0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 15px; line-height: 28px\"><!-- [et_pb_line_break_holder] --><br \/><p><strong>Indirizzo:<\/strong> Via Barbiellini Amidei Bernardo, 28, 00168 Roma RM, Italia <br>\n<strong>Telefono:<\/strong> 06-35504049 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.dottorclaudiopianura.it\">www.dottorclaudiopianura.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:c.pianura@hotmail.it\">c.pianura@hotmail.it<\/a> \n<\/p><br \/><\/div>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 15px; line-height: 28px; margin-top: -28px\"> La segreteria risponde dalle 16 alle 17.30 dal Lun al Ven<\/div>\n<p>[\/et_pb_code][et_pb_social_media_follow _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;10px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;dbdb-whatsapp&#8221; url=&#8221;https:\/\/api.whatsapp.com\/send?phone=393482650755&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#20B038&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;255deg&#8221; background_color_gradient_stops=&#8221;#3298ba 0%|#236aa8 100%&#8221; background_color_gradient_start=&#8221;#3298ba&#8221; background_color_gradient_end=&#8221;#236aa8&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]dbdb-whatsapp[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-location-wrapper-324\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"38344\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-324\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-324\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-324\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-324\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"324\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"gmw-single-object-locations-wrapper-145\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-145\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-145\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-145\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-145\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"145\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221; disabled_on=&#8221;on|on|on&#8221; disabled=&#8221;on&#8221;][\/et_pb_wc_description][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Disturbi dell\u2019equilibrio<br \/>\nL\u2019equilibrio \u201c\u00e8 la capacit\u00e0 di regolare e mantenere il corpo con opportuni e rapidi aggiustamenti di posizione contro la forza di gravit\u00e0, in posizione stabile ed eretta e di camminare senza cadere o deviare dalla linea prefissata\u201d.<br \/>\n\u00c8 considerato il \u201cVI Senso\u201d (\u00e8 il senso della relazione con l\u2019ambiente).<\/p>\n<p>Acufeni<br \/>\nL\u2019acufene \u00e8 una sensazione uditiva percepita dal paziente non legata ad una sorgente sonora presente nell\u2019ambiente esterno.<\/p>\n<p>Ipoacusia<br \/>\nL\u2019udito \u00e8 il senso che ci permette di stabilire relazioni interpersonali (caratteristica dell\u2019essere umano).<\/p>\n<p>Ipoacusia Improvvisa<br \/>\nInsorge improvvisamente (come un fulmine a ciel sereno), generalmente colpisce un solo orecchio ma ha un impatto devastante sulla qualit\u00e0 di vita; il quadro drammatico \u00e8 peggiorato anche dal fatto che spesso si accompagna a violenti acufeni e vertigini talora imponenti.<br \/>\nQuasi sempre interessa un solo orecchio; la forma bilaterale \u00e8 molto rara (2-3% dei casi).<br \/>\nL\u2019ipoacusia improvvisa bilaterale, fortunatamente molto pi\u00f9 rara, ha spesso cause vascolari, metaboliche, immunologiche, infettive, neoplastiche, tossiche chimiche o infiammatorie, anche se l\u2019occorrenza bilaterale non \u00e8 patognomonica per queste cause.<\/p>\n<p>Un concetto da tenere bene a mente \u00e8 che tanto pi\u00f9 passa il tempo dall\u2019esordio del sintomo tanto minori sono le probabilit\u00e0 di recupero.<br \/>\nQuindi se ti capita di incorrere in questo problema la visita \u00e8 urgente.<br \/>\nSe si tratta di una causa banale (es. tappo di cerume) il problema verr\u00e0 rapidamente risolto.<br \/>\nSe si tratta di ipoacusia improvvisa va iniziata rapidamente la terapia e l\u2019iter diagnostico!<\/p>\n<p>Patologia acuta e cronica dell\u2019orecchio medio<br \/>\nColesteatoma<br \/>\nIl colesteatoma \u00e8 una cisti epiteliale all\u2019interno delle cavit\u00e0 dell\u2019orecchio medio. Si presenta come una cisti o come una tasca ripiena di squame e aumenta di volume progressivamente determinando infezioni ricorrenti e distruzione delle strutture ossee circostanti (facilitando la diffusione e la comparsa di complicanze).<\/p>\n<p>acufeni, Disturbi dell\u2019equilibrio, Ipoacusia, Ipoacusia improvvisa, otiti, otorinolaringoiatra, otorinolaringoiatria, sordit\u00e0, vertigini\t<\/p>\n<\/div>\n","protected":false},"featured_media":38348,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[244,163],"product_tag":[2341,3916,3914,3915,2407,438,585,3917,2340],"class_list":{"0":"post-38344","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-otorinolaringoiatra","7":"product_cat-salute","8":"product_tag-acufeni","9":"product_tag-disturbi-dellequilibrio","10":"product_tag-ipoacusia","11":"product_tag-ipoacusia-improvvisa","12":"product_tag-otiti","13":"product_tag-otorinolaringoiatra","14":"product_tag-otorinolaringoiatria","15":"product_tag-sordita","16":"product_tag-vertigini","18":"first","19":"instock","20":"shipping-taxable","21":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Claudio Pianura - Otorinolaringoiatra - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Claudio Pianura - Otorinolaringoiatra - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Disturbi dell\u2019equilibrio L\u2019equilibrio \u201c\u00e8 la capacit\u00e0 di regolare e mantenere il corpo con opportuni e rapidi aggiustamenti di posizione contro la forza di gravit\u00e0, in posizione stabile ed eretta e di camminare senza cadere o deviare dalla linea prefissata\u201d. \u00c8 considerato il \u201cVI Senso\u201d (\u00e8 il senso della relazione con l\u2019ambiente).  Acufeni L\u2019acufene \u00e8 una sensazione uditiva percepita dal paziente non legata ad una sorgente sonora presente nell\u2019ambiente esterno.  Ipoacusia L\u2019udito \u00e8 il senso che ci permette di stabilire relazioni interpersonali (caratteristica dell\u2019essere umano).  Ipoacusia Improvvisa Insorge improvvisamente (come un fulmine a ciel sereno), generalmente colpisce un solo orecchio ma ha un impatto devastante sulla qualit\u00e0 di vita; il quadro drammatico \u00e8 peggiorato anche dal fatto che spesso si accompagna a violenti acufeni e vertigini talora imponenti. Quasi sempre interessa un solo orecchio; la forma bilaterale \u00e8 molto rara (2-3% dei casi). L\u2019ipoacusia improvvisa bilaterale, fortunatamente molto pi\u00f9 rara, ha spesso cause vascolari, metaboliche, immunologiche, infettive, neoplastiche, tossiche chimiche o infiammatorie, anche se l\u2019occorrenza bilaterale non \u00e8 patognomonica per queste cause.  Un concetto da tenere bene a mente \u00e8 che tanto pi\u00f9 passa il tempo dall\u2019esordio del sintomo tanto minori sono le probabilit\u00e0 di recupero. Quindi se ti capita di incorrere in questo problema la visita \u00e8 urgente. Se si tratta di una causa banale (es. tappo di cerume) il problema verr\u00e0 rapidamente risolto. Se si tratta di ipoacusia improvvisa va iniziata rapidamente la terapia e l\u2019iter diagnostico!  Patologia acuta e cronica dell\u2019orecchio medio Colesteatoma Il colesteatoma \u00e8 una cisti epiteliale all\u2019interno delle cavit\u00e0 dell\u2019orecchio medio. Si presenta come una cisti o come una tasca ripiena di squame e aumenta di volume progressivamente determinando infezioni ricorrenti e distruzione delle strutture ossee circostanti (facilitando la diffusione e la comparsa di complicanze).   acufeni, Disturbi dell\u2019equilibrio, Ipoacusia, Ipoacusia improvvisa, otiti, otorinolaringoiatra, otorinolaringoiatria, sordit\u00e0, vertigini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-15T14:45:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"33 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/\",\"name\":\"Dott. Claudio Pianura - Otorinolaringoiatra - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg\",\"datePublished\":\"2022-12-01T15:30:23+00:00\",\"dateModified\":\"2023-09-15T14:45:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Claudio Pianura &#8211; Otorinolaringoiatra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Claudio Pianura - Otorinolaringoiatra - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Claudio Pianura - Otorinolaringoiatra - UIL Polizia","og_description":"Disturbi dell\u2019equilibrio L\u2019equilibrio \u201c\u00e8 la capacit\u00e0 di regolare e mantenere il corpo con opportuni e rapidi aggiustamenti di posizione contro la forza di gravit\u00e0, in posizione stabile ed eretta e di camminare senza cadere o deviare dalla linea prefissata\u201d. \u00c8 considerato il \u201cVI Senso\u201d (\u00e8 il senso della relazione con l\u2019ambiente).  Acufeni L\u2019acufene \u00e8 una sensazione uditiva percepita dal paziente non legata ad una sorgente sonora presente nell\u2019ambiente esterno.  Ipoacusia L\u2019udito \u00e8 il senso che ci permette di stabilire relazioni interpersonali (caratteristica dell\u2019essere umano).  Ipoacusia Improvvisa Insorge improvvisamente (come un fulmine a ciel sereno), generalmente colpisce un solo orecchio ma ha un impatto devastante sulla qualit\u00e0 di vita; il quadro drammatico \u00e8 peggiorato anche dal fatto che spesso si accompagna a violenti acufeni e vertigini talora imponenti. Quasi sempre interessa un solo orecchio; la forma bilaterale \u00e8 molto rara (2-3% dei casi). L\u2019ipoacusia improvvisa bilaterale, fortunatamente molto pi\u00f9 rara, ha spesso cause vascolari, metaboliche, immunologiche, infettive, neoplastiche, tossiche chimiche o infiammatorie, anche se l\u2019occorrenza bilaterale non \u00e8 patognomonica per queste cause.  Un concetto da tenere bene a mente \u00e8 che tanto pi\u00f9 passa il tempo dall\u2019esordio del sintomo tanto minori sono le probabilit\u00e0 di recupero. Quindi se ti capita di incorrere in questo problema la visita \u00e8 urgente. Se si tratta di una causa banale (es. tappo di cerume) il problema verr\u00e0 rapidamente risolto. Se si tratta di ipoacusia improvvisa va iniziata rapidamente la terapia e l\u2019iter diagnostico!  Patologia acuta e cronica dell\u2019orecchio medio Colesteatoma Il colesteatoma \u00e8 una cisti epiteliale all\u2019interno delle cavit\u00e0 dell\u2019orecchio medio. Si presenta come una cisti o come una tasca ripiena di squame e aumenta di volume progressivamente determinando infezioni ricorrenti e distruzione delle strutture ossee circostanti (facilitando la diffusione e la comparsa di complicanze).   acufeni, Disturbi dell\u2019equilibrio, Ipoacusia, Ipoacusia improvvisa, otiti, otorinolaringoiatra, otorinolaringoiatria, sordit\u00e0, vertigini","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/","og_site_name":"UIL Polizia","article_modified_time":"2023-09-15T14:45:16+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"33 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/","name":"Dott. Claudio Pianura - Otorinolaringoiatra - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg","datePublished":"2022-12-01T15:30:23+00:00","dateModified":"2023-09-15T14:45:16+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_Claudio-Pianura.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-claudio-pianura-otorinolaringoiatra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Claudio Pianura &#8211; Otorinolaringoiatra"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/38344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=38344"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/38344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/38348"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=38344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=38344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=38344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=38344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}