{"id":37711,"date":"2022-11-17T12:10:19","date_gmt":"2022-11-17T11:10:19","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=37711"},"modified":"2024-06-12T11:59:42","modified_gmt":"2024-06-12T09:59:42","slug":"dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/","title":{"rendered":"Dott.ssa Chiara Cardone &#8211; Psicologa e Psicoterapeuta"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; next_background_color=&#8221;#c3a7d6&#8243; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.9.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(255,255,255,0.29)&#8221; background_color_gradient_end=&#8221;#8a44af&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/Cardone-1-scaled.jpg&#8221; custom_padding=&#8221;10vw||10vw||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;10vw||20vw||false|false&#8221; bottom_divider_style=&#8221;waves2&#8243; bottom_divider_height=&#8221;50px&#8221; da_disable_devices=&#8221;off|off|off&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Nome azienda&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Shippori Mincho|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;85px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins|200|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;42px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Poppins|200|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_font_size_tablet=&#8221;70px&#8221; header_font_size_phone=&#8221;42px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1.3em&#8221; header_2_line_height_phone=&#8221;&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;21px&#8221; header_3_font_size_phone=&#8221;18px&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221; header_3_line_height_tablet=&#8221;1.4em&#8221; header_3_line_height_phone=&#8221;&#8221; header_3_line_height_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h1>Dott.ssa Chiara Cardone<\/h1>\n<h2>Psicologa Psicoterapeuta ad indirizzo Psicosintetico<\/h2>\n<h3>Iscritta nella sezione A dell\u2019Albo degli Psicologi del Lazio con il n. 20449<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.9.4&#8243; background_color=&#8221;#c3a7d6&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#c3a7d6&#8243; background_color_gradient_end=&#8221;#8a44af&#8221; custom_padding=&#8221;4vw||4vw||true|false&#8221; custom_padding_tablet=&#8221;6vw||9vw||false|false&#8221; custom_padding_phone=&#8221;&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.9.4&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Shippori Mincho|800|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;35px&#8221; custom_margin=&#8221;||5px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Chi sono<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;justified&#8221;]<\/p>\n<p>Sono una psicologa psicoterapeuta ad orientamento psicosintetico, la professione che svolgo mi appassiona perch\u00e9 mi permette di entrare in contatto con le risorse profonde del paziente, sempre esistenti, anche laddove ci sono vissuti di grande difficolt\u00e0.<br \/>Il mio approccio terapeutico consiste in un metodo di lavoro concreto per la conoscenza, la crescita, la trasformazione personale, in cui ognuno, partendo da s\u00e8, ha la possibilit\u00e0 di attuare e realizzare le sue potenzialit\u00e0 individuali.<br \/>Pertanto la mia attivit\u00e0 mira a sostenere e ad aiutare le persone nell\u2019affrontare disagi e sofferenze e, soprattutto si ripropone di far emergere, in ciascuno, le proprie potenzialit\u00e0 e risorse, in uno spazio terapeutico sicuro e protetto in cui il paziente pu\u00f2 trovare ascolto ed accoglienza, per il raggiungimento del proprio benessere psicologico, sia a livello personale che interpersonale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_toggle title=&#8221;Formazione Personale&#8221; open_toggle_text_color=&#8221;#FFFFFF&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#FFFFFF&#8221; title_font=&#8221;Shippori Mincho|800|||||||&#8221; title_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.6em&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221;]<\/p>\n<p><strong>Sono laureata in:<\/strong><br \/>Psicologia, Pedagogia, Lettere<\/p>\n<p><strong>Ho conseguito:<\/strong><br \/>La specializzazione in Psicoterapeuta ad indirizzo Psicosintetico, il I e II Livello di EMDR (Eye Movement Desensitization and Reprocessing. Training I e II livello), diploma di Costellatrice familiare<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Attivit\u00e0 professionale&#8221; open_toggle_text_color=&#8221;#FFFFFF&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#FFFFFF&#8221; title_font=&#8221;Shippori Mincho|800|||||||&#8221; title_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.6em&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221;]<\/p>\n<p>Mi occupo, come libera professionista, in presenza e on line, di psicoterapia, di consulenza e sostegno psicologico e pedagogico.<\/p>\n<ul>\n<li>Pratico la psicoterapia EMDR<\/li>\n<li>Esercito tecniche di Mindfulness, rilassamento e crescita personale individuale, di coppia e di gruppo<\/li>\n<li>Conduco corsi e laboratori, in presenza e on line, per l\u2019apprendimento di Tecniche di Rilassamento e Meditazione, di Fiabazione, di Scrittura Autobiografica e di Scrittura poetica creativa con Metodo Caviardage<\/li>\n<li>Effettuo Costellazioni familiari individuali e di gruppo<\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Le attivit\u00e0 che propongo sono diversificate in funzione della richiesta&#8221; open_toggle_text_color=&#8221;#FFFFFF&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#FFFFFF&#8221; title_font=&#8221;Shippori Mincho|800|||||||&#8221; title_font_size=&#8221;24px&#8221; title_line_height=&#8221;1.3em&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.6em&#8221; title_font_size_tablet=&#8221;&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_line_height_tablet=&#8221;&#8221; title_line_height_phone=&#8221;1.4em&#8221; title_line_height_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221;]<\/p>\n<ul>\n<li><strong>Consulenza:<\/strong> 3\/4 incontri tesi a comprendere il disagio emerso e il modo per affrontarlo<\/li>\n<li><strong>Psicoterapia individuale e familiare:<\/strong> un percorso strutturato per il raggiungimento della conoscenza di s\u00e8 e del cambiamento intrapersonale e interpersonale finalizzato al benessere<\/li>\n<li><strong>Attivit\u00e0 di gruppo:<\/strong> un lavoro di gruppo che permette a persone che necessitano di stesse esigenze, di confrontarsi<\/li>\n<li><strong>Corsi di Rilassamento e\/o Meditazione\/Fiabazione\/Scrittura autobiografica:<\/strong> efficaci per gestire l&#8217;ansia, lo stress, l&#8217;insonnia e disturbi psicosomatici<\/li>\n<li><strong>Corsi di informazione e formazione psicologica:<\/strong> per conoscere ed affrontare tematiche psicologiche<\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Target di utenza&#8221; open_toggle_text_color=&#8221;#FFFFFF&#8221; open_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; closed_toggle_background_color=&#8221;RGBA(0,0,0,0)&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#FFFFFF&#8221; title_font=&#8221;Shippori Mincho|800|||||||&#8221; title_font_size=&#8221;24px&#8221; title_line_height=&#8221;1.3em&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.6em&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221;]<\/p>\n<ul>\n<li>Adolescenti<\/li>\n<li>Adulti<\/li>\n<li>Anziani<\/li>\n<li>Coppie\/Famiglie<\/li>\n<li>Gruppi e Comunit\u00e0<\/li>\n<\/ul>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][dsm_masonry_gallery gallery_ids=&#8221;37722,37721,37720,37718&#8243; columns=&#8221;2&#8243; gutter=&#8221;5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|11px|||false|false&#8221; custom_margin_tablet=&#8221;|0px|||false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; hover_enabled=&#8221;0&#8243; border_radii_grid=&#8221;on|20px|20px|20px|20px&#8221; border_color_all_grid=&#8221;#FFFFFF&#8221; border_style_all_grid=&#8221;double&#8221; sticky_enabled=&#8221;0&#8243;][\/dsm_masonry_gallery][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/Foto-professionale-1.jpg&#8221; title_text=&#8221;Foto professionale 1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|||-30px|false|false&#8221; custom_margin_tablet=&#8221;|||0px|false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|40px|40px|40px|40px&#8221; border_color_right=&#8221;#FFFFFF&#8221; border_style_right=&#8221;double&#8221; border_width_left=&#8221;20px&#8221; border_color_left=&#8221;#FFFFFF&#8221; border_style_left=&#8221;double&#8221; locked=&#8221;off&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#550c7f&#8221; background_color_gradient_end=&#8221;rgba(138,68,175,0.12)&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/Cardone-2.jpg&#8221; custom_padding=&#8221;5vw||5vw||true|false&#8221; custom_padding_tablet=&#8221;10vw||5vw||false|false&#8221; custom_padding_phone=&#8221;15vw||6vw||false|false&#8221; top_divider_style=&#8221;waves2&#8243; top_divider_color=&#8221;#8a44af&#8221; top_divider_height=&#8221;50px&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;54px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||-30px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;38px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_2_line_height_tablet=&#8221;1.4em&#8221; header_2_line_height_phone=&#8221;1.3em&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221;]<\/p>\n<h2>Agevolazioni riservate agli associati SIM Guardia di Finanza e i loro familiari<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||-30px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;50px&#8221; header_2_font_size_phone=&#8221;45px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_2_line_height_tablet=&#8221;1.4em&#8221; header_2_line_height_phone=&#8221;1.5em&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h2>Agevolazioni<br \/>riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#bb93d6&#8243; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_color_right=&#8221;#FFFFFF&#8221; border_style_right=&#8221;double&#8221; border_width_left=&#8221;20px&#8221; border_color_left=&#8221;#FFFFFF&#8221; border_style_left=&#8221;double&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||5px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>Indirizzo:<\/strong> Via Quarto, 18 &#8211; 04100 Latina<br \/>Via Ninfa, 18 &#8211; 04100 Latina\u00a0 (doppio ingresso)<br \/><strong>Telefono: <\/strong>3349636121<br \/><strong>Sito web: <\/strong><a href=\"https:\/\/dottssa-chiara-cardone-psicologa.business.site\/\">dottssa-chiara-cardone-psicologa.business.site<\/a><br \/><strong>Mail: <\/strong><a href=\"mailto:chiaracardonepsi@gmail.com\">chiaracardonepsi@gmail.com<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 15px; line-height: 28px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Via Quarto, 18 \u2013 Latina 04100 <br>\n<strong>Telefono:<\/strong> 3349636121 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/dottssa-chiara-cardone-psicologa.business.site\">dottssa-chiara-cardone-psicologa.business.site<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:chiaracardonepsi@gmail.com\">chiaracardonepsi@gmail.com<\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/it-it.facebook.com\/dott.ssaChiaraCardone&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#FFFFFF&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;skype&#8221; skype_url=&#8221;kiara_card1&#8243; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#FFFFFF&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]skype[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-297\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"37711\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-297\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-297\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-297\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-297\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"297\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-410\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-410\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-410\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-410\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-410\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"410\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(0,0,0,0.55)&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_color_right=&#8221;#FFFFFF&#8221; border_style_right=&#8221;double&#8221; border_width_left=&#8221;20px&#8221; border_color_left=&#8221;#FFFFFF&#8221; border_style_left=&#8221;double&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;||5px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; link_text_color=&#8221;#d9c8f7&#8243; custom_margin=&#8221;||||false|false&#8221; locked=&#8221;off&#8221;]<\/p>\n<p><strong>Indirizzo:<\/strong> Via Quarto, 18 &#8211; 04100 Latina<br \/>Via Ninfa, 18 &#8211; 04100 Latina\u00a0 (doppio ingresso)<br \/><strong>Telefono: <\/strong>3349636121<br \/><strong>Sito web: <\/strong><a href=\"https:\/\/dottssa-chiara-cardone-psicologa.business.site\/\">dottssa-chiara-cardone-psicologa.business.site<\/a><br \/><strong>Mail: <\/strong><a href=\"mailto:chiaracardonepsi@gmail.com\">chiaracardonepsi@gmail.com<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221;]<\/p>\n<div style= \"font-family: 'Poppins', sans-serif; font-size: 15px; line-height: 28px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Via Quarto, 18 \u2013 Latina 04100 <br>\n<strong>Telefono:<\/strong> 3349636121 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/dottssa-chiara-cardone-psicologa.business.site\">dottssa-chiara-cardone-psicologa.business.site<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:chiaracardonepsi@gmail.com\">chiaracardonepsi@gmail.com<\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/it-it.facebook.com\/dott.ssaChiaraCardone&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#FFFFFF&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;skype&#8221; skype_url=&#8221;kiara_card1&#8243; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#FFFFFF&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]skype[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-532\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"37711\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-532\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-532\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-532\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-532\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"532\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;mappa multipla&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221;]<div id=\"gmw-single-object-locations-wrapper-343\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-343\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-343\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-343\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-343\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"343\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dott.ssa Chiara Cardone Psicologa Psicoterapeuta ad indirizzo Psicosintetico Iscritta nella sezione A dell\u2019Albo degli Psicologi del Lazio con il n. 20449Chi sonoSono una psicologa psicoterapeuta ad orientamento psicosintetico, la professione che svolgo mi appassiona perch\u00e9 mi permette di entrare in contatto con le risorse profonde del paziente, sempre esistenti, anche laddove ci sono vissuti di [&hellip;]<\/p>\n","protected":false},"featured_media":37713,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,258,163],"product_tag":[3430,3762,3032,3763,2509,1184,353,993,354,818,3504,1505],"class_list":{"0":"post-37711","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-psicoterapeuti","8":"product_cat-salute","9":"product_tag-benessere-psicologico","10":"product_tag-consulenza-e-sostegno-psicologico","11":"product_tag-crescita-personale","12":"product_tag-meditazione","13":"product_tag-mindfulness","14":"product_tag-pedagogia","15":"product_tag-psicologa","16":"product_tag-psicologia","17":"product_tag-psicoterapeuta","18":"product_tag-psicoterapia","19":"product_tag-psicoterapia-familiare","20":"product_tag-psicoterapia-individuale","22":"first","23":"instock","24":"shipping-taxable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Chiara Cardone - Psicologa e Psicoterapeuta - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Chiara Cardone - Psicologa e Psicoterapeuta - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dott.ssa Chiara Cardone Psicologa Psicoterapeuta ad indirizzo Psicosintetico Iscritta nella sezione A dell\u2019Albo degli Psicologi del Lazio con il n. 20449Chi sonoSono una psicologa psicoterapeuta ad orientamento psicosintetico, la professione che svolgo mi appassiona perch\u00e9 mi permette di entrare in contatto con le risorse profonde del paziente, sempre esistenti, anche laddove ci sono vissuti di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T09:59:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/\",\"name\":\"Dott.ssa Chiara Cardone - Psicologa e Psicoterapeuta - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg\",\"datePublished\":\"2022-11-17T11:10:19+00:00\",\"dateModified\":\"2024-06-12T09:59:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Chiara Cardone &#8211; Psicologa e Psicoterapeuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Chiara Cardone - Psicologa e Psicoterapeuta - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Chiara Cardone - Psicologa e Psicoterapeuta - UIL Polizia","og_description":"Dott.ssa Chiara Cardone Psicologa Psicoterapeuta ad indirizzo Psicosintetico Iscritta nella sezione A dell\u2019Albo degli Psicologi del Lazio con il n. 20449Chi sonoSono una psicologa psicoterapeuta ad orientamento psicosintetico, la professione che svolgo mi appassiona perch\u00e9 mi permette di entrare in contatto con le risorse profonde del paziente, sempre esistenti, anche laddove ci sono vissuti di [&hellip;]","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/","og_site_name":"UIL Polizia","article_modified_time":"2024-06-12T09:59:42+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/","name":"Dott.ssa Chiara Cardone - Psicologa e Psicoterapeuta - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg","datePublished":"2022-11-17T11:10:19+00:00","dateModified":"2024-06-12T09:59:42+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/11\/logo_Chiara-Cardone.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-chiara-cardone-psicologa-e-psicoterapeuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Chiara Cardone &#8211; Psicologa e Psicoterapeuta"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/37711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=37711"}],"version-history":[{"count":2,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/37711\/revisions"}],"predecessor-version":[{"id":65549,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/37711\/revisions\/65549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/37713"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=37711"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=37711"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=37711"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=37711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}