{"id":36366,"date":"2022-10-05T15:49:49","date_gmt":"2022-10-05T13:49:49","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=36366"},"modified":"2022-10-05T15:49:54","modified_gmt":"2022-10-05T13:49:54","slug":"dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/","title":{"rendered":"Dott.ssa Alessia Silvani &#8211; Psicologa e Psicoterapeuta"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;titolo&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-150px||||false|false&#8221; saved_tabs=&#8221;all&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_wc_breadcrumb _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;|500|||||||&#8221; body_font_size=&#8221;15px&#8221;][\/et_pb_wc_breadcrumb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;sezione principale&#8221; _builder_version=&#8221;4.9.4&#8243; custom_margin=&#8221;-40px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row admin_label=&#8221;riga locandina&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_wc_title admin_label=&#8221;titolo convenzione&#8221; _builder_version=&#8221;4.9.4&#8243; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#283371&#8243; header_font_size=&#8221;40px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;|||12px|false|false&#8221; border_width_left=&#8221;6px&#8221; border_color_left=&#8221;#283371&#8243;][\/et_pb_wc_title][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/locandina_Alessia-Silvani.jpg&#8221; title_text=&#8221;locandina_Alessia Silvani&#8221; admin_label=&#8221;Immagine locandina&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_divider color=&#8221;#bababa&#8221; divider_weight=&#8221;2px&#8221; admin_label=&#8221;separatore locandina&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;riga chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;titolo chi siamo&#8221; module_id=&#8221;chi_siamo_prodotti&#8221; module_class=&#8221;title_product&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Roboto|700|||||||&#8221; header_2_text_color=&#8221;#283371&#8243; header_2_font_size=&#8221;32px&#8221; custom_padding=&#8221;5px|||10px|false|false&#8221; hover_enabled=&#8221;0&#8243; border_width_left=&#8221;5px&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Chi sono<\/h2>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221;][\/et_pb_wc_description][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; admin_label=&#8221;sezione contatti&#8221; module_id=&#8221;special_contatti&#8221; module_class=&#8221;special_contacts&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; admin_label=&#8221;riga contatti&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221;][et_pb_text admin_label=&#8221;titolo contatti&#8221; module_class=&#8221;title_product&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Roboto||||||||&#8221; text_orientation_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;right&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_social_media_follow][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner admin_label=&#8221;riga info supplementari&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; saved_tabs=&#8221;all&#8221;][et_pb_column_inner _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;dati aziendali&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Viale Cesare Battisti, 15, 27100 Pavia PV, Italia <br>\n<strong>Telefono:<\/strong> 3497978685 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.alessiasilvanipsicologa.com\">www.alessiasilvanipsicologa.com<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:a.silvani02@gmail.com\">a.silvani02@gmail.com<\/a> \n<\/p><br \/>[\/et_pb_code][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code admin_label=&#8221;mappa&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-169\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"36366\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-169\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-169\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-169\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-169\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"169\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Dott.ssa Alessia Silvani &#8211; Psicologa e Psicoterapeuta<\/strong><\/p>\n<p>Siete bloccati da un ostacolo che non riuscite a superare?<br \/>\nA volte, rivolgersi a un esperto qualificato \u00e8 il miglior modo per iniziare a cambiare prospettiva.<br \/>\nMi chiamo Alessia Silvani, sono una psicologa e psicoterapeuta specializzata nel trattamento di psicopatologie dell\u2019et\u00e0 adulta, dell\u2019adolescenza e dell\u2019infanzia.<\/p>\n<p>Mi occupo di disturbi e problematiche relative alla sfera psicologica, quali ad esempio depressione, ansia, elaborazione del lutto, stress, attacchi di panico, disturbi di somatizzazione, problemi relazionali, disagi legati alla crescita.<\/p>\n<p>Ho un approccio Umanistico alla Psicologia, sono specializzata in qualit\u00e0 di Psicoterapeuta presso lo IACP (Istituto dell\u2019Approccio Centrato sulla Persona) di Milano.<\/p>\n<p>Dopo un iniziale colloquio conoscitivo gratuito, offro colloqui di consultazione psicologica in cui la persona pu\u00f2 esprimere la propria domanda, connessa alla circostanza che causa fatica o sofferenza.<\/p>\n<p>Dopo i colloqui iniziali, elaboro soluzioni individuali e personalizzate che vengono illustrate al cliente e con esso concordate. Il mio primo strumento di intervento \u00e8 l\u2019ascolto empatico, all\u2019interno di un clima relazionale caratterizzato da accettazione ed assenza di giudizio. Queste modalit\u00e0 risultano efficaci per il trattamento di disturbi e problematiche relative alla sfera psicologica, sia in et\u00e0 adulta che evolutiva.<\/p>\n","protected":false},"featured_media":36369,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,258,163],"product_tag":[1585,1560,1587,3212,3210,3181,3211,353,993,354,818,1675],"class_list":{"0":"post-36366","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-psicoterapeuti","8":"product_cat-salute","9":"product_tag-ansia","10":"product_tag-attacchi-di-panico","11":"product_tag-depressione","12":"product_tag-disagi-legati-alla-crescita","13":"product_tag-disturbi-di-somatizzazione","14":"product_tag-elaborazione-del-lutto","15":"product_tag-problemi-relazionali","16":"product_tag-psicologa","17":"product_tag-psicologia","18":"product_tag-psicoterapeuta","19":"product_tag-psicoterapia","20":"product_tag-stress","22":"first","23":"instock","24":"shipping-taxable","25":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta  Siete bloccati da un ostacolo che non riuscite a superare? A volte, rivolgersi a un esperto qualificato \u00e8 il miglior modo per iniziare a cambiare prospettiva. Mi chiamo Alessia Silvani, sono una psicologa e psicoterapeuta specializzata nel trattamento di psicopatologie dell\u2019et\u00e0 adulta, dell\u2019adolescenza e dell\u2019infanzia.  Mi occupo di disturbi e problematiche relative alla sfera psicologica, quali ad esempio depressione, ansia, elaborazione del lutto, stress, attacchi di panico, disturbi di somatizzazione, problemi relazionali, disagi legati alla crescita.  Ho un approccio Umanistico alla Psicologia, sono specializzata in qualit\u00e0 di Psicoterapeuta presso lo IACP (Istituto dell\u2019Approccio Centrato sulla Persona) di Milano.  Dopo un iniziale colloquio conoscitivo gratuito, offro colloqui di consultazione psicologica in cui la persona pu\u00f2 esprimere la propria domanda, connessa alla circostanza che causa fatica o sofferenza.  Dopo i colloqui iniziali, elaboro soluzioni individuali e personalizzate che vengono illustrate al cliente e con esso concordate. Il mio primo strumento di intervento \u00e8 l\u2019ascolto empatico, all\u2019interno di un clima relazionale caratterizzato da accettazione ed assenza di giudizio. Queste modalit\u00e0 risultano efficaci per il trattamento di disturbi e problematiche relative alla sfera psicologica, sia in et\u00e0 adulta che evolutiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T13:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/\",\"name\":\"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg\",\"datePublished\":\"2022-10-05T13:49:49+00:00\",\"dateModified\":\"2022-10-05T13:49:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott.ssa Alessia Silvani &#8211; Psicologa e Psicoterapeuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/","og_locale":"it_IT","og_type":"article","og_title":"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta - UIL Polizia","og_description":"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta  Siete bloccati da un ostacolo che non riuscite a superare? A volte, rivolgersi a un esperto qualificato \u00e8 il miglior modo per iniziare a cambiare prospettiva. Mi chiamo Alessia Silvani, sono una psicologa e psicoterapeuta specializzata nel trattamento di psicopatologie dell\u2019et\u00e0 adulta, dell\u2019adolescenza e dell\u2019infanzia.  Mi occupo di disturbi e problematiche relative alla sfera psicologica, quali ad esempio depressione, ansia, elaborazione del lutto, stress, attacchi di panico, disturbi di somatizzazione, problemi relazionali, disagi legati alla crescita.  Ho un approccio Umanistico alla Psicologia, sono specializzata in qualit\u00e0 di Psicoterapeuta presso lo IACP (Istituto dell\u2019Approccio Centrato sulla Persona) di Milano.  Dopo un iniziale colloquio conoscitivo gratuito, offro colloqui di consultazione psicologica in cui la persona pu\u00f2 esprimere la propria domanda, connessa alla circostanza che causa fatica o sofferenza.  Dopo i colloqui iniziali, elaboro soluzioni individuali e personalizzate che vengono illustrate al cliente e con esso concordate. Il mio primo strumento di intervento \u00e8 l\u2019ascolto empatico, all\u2019interno di un clima relazionale caratterizzato da accettazione ed assenza di giudizio. Queste modalit\u00e0 risultano efficaci per il trattamento di disturbi e problematiche relative alla sfera psicologica, sia in et\u00e0 adulta che evolutiva.","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/","og_site_name":"UIL Polizia","article_modified_time":"2022-10-05T13:49:54+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/","name":"Dott.ssa Alessia Silvani - Psicologa e Psicoterapeuta - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg","datePublished":"2022-10-05T13:49:49+00:00","dateModified":"2022-10-05T13:49:54+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/10\/logo_Alessia-Silvani.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-ssa-alessia-silvani-psicologa-e-psicoterapeuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott.ssa Alessia Silvani &#8211; Psicologa e Psicoterapeuta"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/36366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=36366"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/36366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/36369"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=36366"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=36366"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=36366"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=36366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}