{"id":34902,"date":"2022-07-15T16:57:04","date_gmt":"2022-07-15T14:57:04","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=34902"},"modified":"2022-09-13T15:10:24","modified_gmt":"2022-09-13T13:10:24","slug":"fisiolab-livorno","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/","title":{"rendered":"Fisiolab Livorno"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;titolo&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-150px||||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; saved_tabs=&#8221;all&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_wc_breadcrumb _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;|500|||||||&#8221; body_font_size=&#8221;15px&#8221;][\/et_pb_wc_breadcrumb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;sezione principale&#8221; _builder_version=&#8221;4.9.4&#8243; custom_margin=&#8221;-40px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row admin_label=&#8221;riga locandina&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_wc_title admin_label=&#8221;titolo convenzione&#8221; _builder_version=&#8221;4.9.4&#8243; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#283371&#8243; header_font_size=&#8221;40px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;|||12px|false|false&#8221; border_width_left=&#8221;6px&#8221; border_color_left=&#8221;#283371&#8243;][\/et_pb_wc_title][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/locandina_viti-massimiliano.jpg&#8221; title_text=&#8221;locandina_viti massimiliano&#8221; admin_label=&#8221;Immagine locandina&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][et_pb_divider color=&#8221;#bababa&#8221; divider_weight=&#8221;2px&#8221; admin_label=&#8221;separatore locandina&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;riga chi siamo&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text admin_label=&#8221;titolo chi siamo&#8221; module_id=&#8221;chi_siamo_prodotti&#8221; module_class=&#8221;title_product&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Roboto|700|||||||&#8221; header_2_text_color=&#8221;#283371&#8243; header_2_font_size=&#8221;32px&#8221; custom_padding=&#8221;5px|||10px|false|false&#8221; border_width_left=&#8221;5px&#8221;]<\/p>\n<h2>Chi siamo<\/h2>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; _builder_version=&#8221;4.9.4&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221;][\/et_pb_wc_description][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; admin_label=&#8221;sezione contatti&#8221; module_id=&#8221;special_contatti&#8221; module_class=&#8221;special_contacts&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; admin_label=&#8221;riga contatti&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221;][et_pb_text admin_label=&#8221;titolo contatti&#8221; module_class=&#8221;title_product&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Roboto||||||||&#8221; text_orientation_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_social_media_follow _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;right&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/FisioLabLivorno\/&#8221; icon_color=&#8221;#3b5998&#8243; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;22px&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; background_enable_color=&#8221;on&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner admin_label=&#8221;riga info supplementari&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; saved_tabs=&#8221;all&#8221;][et_pb_column_inner _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_code admin_label=&#8221;dati aziendali&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221;]<br \/><p><strong>Indirizzo:<\/strong> Via Adua, 6, 57126 Livorno LI, Italia <br>\n<strong>Telefono:<\/strong> 0586 887367 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.fisiolablivorno.it\">www.fisiolablivorno.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:fisiolablivorno@gmail.com\">fisiolablivorno@gmail.com<\/a> \n<\/p><br \/>[\/et_pb_code][et_pb_text admin_label=&#8221;titolo orari&#8221; module_class=&#8221;title_product&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Roboto||||||||&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; text_orientation_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2>Orari di apertura<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;orari apertura&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]    \n<table style=\"border-collapse: collapse; width: 100%; height: 183px;\" border=\"1\">\n<tbody><tr style=\"height: 23px;background-color: #efefef;\"><td style=\"width: 23.0998%; height: 23px;\"><strong>Luned\u00ec<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">8.00 - 19.00<\/td><\/tr><tr style=\"height: 23px;\"> <td style=\"width: 23.0998%; height: 23px;\"><strong>Marted\u00ec<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">8.00 - 19.00<\/td><\/tr><tr style=\"height: 23px;background-color: #efefef;\"><td style=\"width: 23.0998%; height: 23px;\"><strong>Mercoled\u00ec<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">8.00 - 19.00<\/td><\/tr><tr style=\"height: 23px;\"> <td style=\"width: 23.0998%; height: 23px;\"><strong>Gioved\u00ec<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">8.00 - 19.00<\/td><\/tr><tr style=\"height: 23px;background-color: #efefef;\"><td style=\"width: 23.0998%; height: 23px;\"><strong>Venerd\u00ec<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">8.00 - 19.00<\/td><\/tr><tr style=\"height: 23px;\"> <td style=\"width: 23.0998%; height: 23px;\"><strong>Sabato<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">Chiuso<\/td><\/tr><tr style=\"height: 23px;background-color: #efefef;\"><td style=\"width: 23.0998%; height: 23px;\"><strong>Domenica<\/strong><\/td>\n<td style=\"width: 76.9002%; height: 23px;\">Chiuso<\/td><\/tr><\/tbody><\/table>[\/et_pb_code][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code admin_label=&#8221;mappa&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<div id=\"gmw-single-location-wrapper-143\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"34902\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-143\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-143\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-143\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-143\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"143\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][et_pb_code admin_label=&#8221;allunga mappa&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<!-- [et_pb_line_break_holder] -->jQuery( document ).ready(function() {<!-- [et_pb_line_break_holder] -->    jQuery( &#8220;.single_location&#8221; ).height(&#8220;620px&#8221;);<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Fisiolab Livorno<\/strong><\/p>\n<p>Fisiolab Livorno \u00e8 un ambulatorio di fisioterapia specializzato in programmi di riabilitazione personalizzata e fisiokinesiterapia a Livorno. Una rete di specialisti della riabilitazione, della medicina e della prevenzione ti mettono a disposizione la loro esperienza e professionalit\u00e0 proponendoti terapie e trattamenti riabilitativi mirati. Fisiolab Livorno dispone di macchinari all\u2019avanguardia e strumentazione medica di alta qualit\u00e0 per garantirti trattamenti fisioterapici e programmi di riabilitazione personalizzati.<br \/>\nPresso l\u2019ambulatorio di Livorno potrai richiedere non solo percorsi di riabilitazione fisica, posturale e postoperatoria ma anche fisiokinesiterapia ortopedica, ginnastica riabilitativa, massofisioterapia e fisioterapia sportiva. L\u2019obiettivo del personale altamente specializzato \u00e8 quello di prendersi cura del tuo percorso di riabilitazione in via olistica per garantirti una condizione di completo benessere fisico, psichico e di corretto movimento. <\/p>\n<p><strong>Terapie<\/strong><br \/>\n&#8211; Laserterapia antalgica<br \/>\n&#8211; Ipertermia in fisioterapia<br \/>\n&#8211; Massofisioterapia e manipolazione decontratturante<br \/>\n&#8211; Tecarterapia<\/p>\n","protected":false},"featured_media":35833,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[207,163],"product_tag":[3057,3058,3063,447,3065,365,448,3064,3067,3066,1004,3068,387,3060,3062,3061,2418,3059],"class_list":{"0":"post-34902","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fisioterapisti","7":"product_cat-salute","8":"product_tag-ambulatorio-di-fisioterapia","9":"product_tag-fisiokinesiterapia","10":"product_tag-fisiokinesiterapia-ortopedica","11":"product_tag-fisioterapia","12":"product_tag-fisioterapia-sportiva","13":"product_tag-fisioterapista","14":"product_tag-fisioterapisti","15":"product_tag-ginnastica-riabilitativa","16":"product_tag-ipertermia-in-fisioterapia","17":"product_tag-laserterapia-antalgica","18":"product_tag-massofisioterapia","19":"product_tag-massofisioterapia-e-manipolazione-decontratturante","20":"product_tag-riabilitazione","21":"product_tag-riabilitazione-fisica","22":"product_tag-riabilitazione-postoperatoria","23":"product_tag-riabilitazione-posturale","24":"product_tag-tecarterapia","25":"product_tag-trattamenti-fisioterapici","27":"first","28":"instock","29":"shipping-taxable","30":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fisiolab Livorno - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fisiolab Livorno - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Fisiolab Livorno  Fisiolab Livorno \u00e8 un ambulatorio di fisioterapia specializzato in programmi di riabilitazione personalizzata e fisiokinesiterapia a Livorno. Una rete di specialisti della riabilitazione, della medicina e della prevenzione ti mettono a disposizione la loro esperienza e professionalit\u00e0 proponendoti terapie e trattamenti riabilitativi mirati. Fisiolab Livorno dispone di macchinari all\u2019avanguardia e strumentazione medica di alta qualit\u00e0 per garantirti trattamenti fisioterapici e programmi di riabilitazione personalizzati.  Presso l\u2019ambulatorio di Livorno potrai richiedere non solo percorsi di riabilitazione fisica, posturale e postoperatoria ma anche fisiokinesiterapia ortopedica, ginnastica riabilitativa, massofisioterapia e fisioterapia sportiva. L\u2019obiettivo del personale altamente specializzato \u00e8 quello di prendersi cura del tuo percorso di riabilitazione in via olistica per garantirti una condizione di completo benessere fisico, psichico e di corretto movimento.   Terapie - Laserterapia antalgica - Ipertermia in fisioterapia  - Massofisioterapia e manipolazione decontratturante - Tecarterapia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-13T13:10:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/\",\"name\":\"Fisiolab Livorno - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg\",\"datePublished\":\"2022-07-15T14:57:04+00:00\",\"dateModified\":\"2022-09-13T13:10:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fisiolab Livorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fisiolab Livorno - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/","og_locale":"it_IT","og_type":"article","og_title":"Fisiolab Livorno - UIL Polizia","og_description":"Fisiolab Livorno  Fisiolab Livorno \u00e8 un ambulatorio di fisioterapia specializzato in programmi di riabilitazione personalizzata e fisiokinesiterapia a Livorno. Una rete di specialisti della riabilitazione, della medicina e della prevenzione ti mettono a disposizione la loro esperienza e professionalit\u00e0 proponendoti terapie e trattamenti riabilitativi mirati. Fisiolab Livorno dispone di macchinari all\u2019avanguardia e strumentazione medica di alta qualit\u00e0 per garantirti trattamenti fisioterapici e programmi di riabilitazione personalizzati.  Presso l\u2019ambulatorio di Livorno potrai richiedere non solo percorsi di riabilitazione fisica, posturale e postoperatoria ma anche fisiokinesiterapia ortopedica, ginnastica riabilitativa, massofisioterapia e fisioterapia sportiva. L\u2019obiettivo del personale altamente specializzato \u00e8 quello di prendersi cura del tuo percorso di riabilitazione in via olistica per garantirti una condizione di completo benessere fisico, psichico e di corretto movimento.   Terapie - Laserterapia antalgica - Ipertermia in fisioterapia  - Massofisioterapia e manipolazione decontratturante - Tecarterapia","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/","og_site_name":"UIL Polizia","article_modified_time":"2022-09-13T13:10:24+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/","name":"Fisiolab Livorno - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg","datePublished":"2022-07-15T14:57:04+00:00","dateModified":"2022-09-13T13:10:24+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2022\/07\/logo_viti-massimiliano-1.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/fisiolab-livorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Fisiolab Livorno"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/34902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=34902"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/34902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/35833"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=34902"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=34902"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=34902"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=34902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}