{"id":103004,"date":"2026-06-16T11:30:56","date_gmt":"2026-06-16T09:30:56","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=103004"},"modified":"2026-06-30T16:32:53","modified_gmt":"2026-06-30T14:32:53","slug":"dortenzio-it","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/","title":{"rendered":"Dortenzio.it"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"103004\" class=\"elementor elementor-103004\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e681e57 e-con-full e-flex e-con e-parent\" data-id=\"e681e57\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-116bf0e e-flex e-con-boxed e-con e-child\" data-id=\"116bf0e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-57b6835 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"57b6835\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e45ab62 elementor-widget elementor-widget-image\" data-id=\"e45ab62\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"431\" height=\"178\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/DORTENZIO.IT_.png\" class=\"attachment-large size-large wp-image-104460\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/DORTENZIO.IT_.png 431w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/DORTENZIO.IT_-300x124.png 300w\" sizes=\"(max-width: 431px) 100vw, 431px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f4a66 elementor-widget elementor-widget-html\" data-id=\"84f4a66\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"it\">\r\n<head>\r\n    <meta charset=\"UTF-8\">\r\n    <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\r\n    <title>D'Ortenzio - Noleggio a Lungo Termine<\/title>\r\n    \r\n    <!-- Tailwind CSS -->\r\n    <script src=\"https:\/\/cdn.tailwindcss.com\"><\/script>\r\n    \r\n    <!-- Google Fonts -->\r\n    <link href=\"https:\/\/fonts.googleapis.com\/css2?family=Poppins:wght@300;400;600;800;900&display=swap\" rel=\"stylesheet\">\r\n    \r\n    <!-- FontAwesome for Icons -->\r\n    <link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.4.0\/css\/all.min.css\">\r\n\r\n    <style>\r\n        body {\r\n            font-family: 'Poppins', sans-serif;\r\n            scroll-behavior: smooth;\r\n        }\r\n    <\/style>\r\n<\/head>\r\n<body class=\"bg-gray-50 text-slate-800 antialiased selection:bg-blue-600 selection:text-white\">\r\n\r\n    <!-- Header \/ Hero Section (Sfondo scurito al 70% per massimo contrasto e leggibilit\u00e0) -->\r\n    \r\n\r\n    <!-- Sezione: Chi Siamo -->\r\n    <section class=\"py-16 md:py-24 bg-white px-6\">\r\n        <div class=\"container mx-auto max-w-4xl text-center\">\r\n            <div class=\"inline-flex items-center justify-center p-3 bg-blue-100 rounded-full mb-6 text-blue-600\">\r\n                <i class=\"fa-solid fa-users text-2xl\"><\/i>\r\n            <\/div>\r\n            <h2 class=\"text-3xl md:text-5xl font-extrabold mb-8 text-slate-900\">Chi Siamo<\/h2>\r\n            <p class=\"text-lg md:text-xl text-slate-600 leading-relaxed mb-6\">\r\n                Siamo professionisti esperti nel settore della mobilit\u00e0. Con <strong>Dortenzio.it<\/strong> ti garantiamo il massimo risparmio, zero imprevisti e un servizio \"tutto incluso\". \r\n            <\/p>\r\n            <p class=\"text-lg md:text-xl text-slate-600 leading-relaxed\">\r\n                Che tu sia un privato, un professionista, un'azienda o un neopatentato, ti mettiamo al volante di veicoli sicuri e moderni senza i pensieri legati all'acquisto. Siamo sempre al tuo fianco prima, durante e dopo il noleggio, offrendo soluzioni su misura che uniscono flessibilit\u00e0 economica e serenit\u00e0 totale.\r\n            <\/p>\r\n        <\/div>\r\n    <\/section>\r\n\r\n    <!-- Sezione: Servizi Offerti -->\r\n    <section class=\"py-16 md:py-24 bg-slate-50 px-6\">\r\n        <div class=\"container mx-auto max-w-6xl\">\r\n            <div class=\"text-center mb-16\">\r\n                <h2 class=\"text-3xl md:text-5xl font-extrabold mb-4 text-slate-900\">Servizi Offerti<\/h2>\r\n                <p class=\"text-slate-500 text-lg\">Scopri i vantaggi di viaggiare con noi<\/p>\r\n            <\/div>\r\n\r\n            <div class=\"grid grid-cols-1 md:grid-cols-2 lg:grid-cols-3 gap-8\">\r\n                <!-- Servizio 1 -->\r\n                <div class=\"bg-white p-8 rounded-2xl shadow-sm border border-gray-100 hover:shadow-xl hover:-translate-y-1 transition-all duration-300\">\r\n                    <div class=\"w-14 h-14 bg-blue-50 text-blue-600 rounded-xl flex items-center justify-center mb-6 text-2xl\">\r\n                        <i class=\"fa-solid fa-car\"><\/i>\r\n                    <\/div>\r\n                    <h3 class=\"text-xl font-bold mb-3 text-slate-900\">Privati e Aziende<\/h3>\r\n                    <p class=\"text-slate-600\">Soluzioni personalizzate per rispondere a ogni necessit\u00e0 di mobilit\u00e0, dalla city-car per la citt\u00e0 fino alle flotte aziendali per professionisti.<\/p>\r\n                <\/div>\r\n\r\n                <!-- Servizio 2 -->\r\n                <div class=\"bg-white p-8 rounded-2xl shadow-sm border border-gray-100 hover:shadow-xl hover:-translate-y-1 transition-all duration-300\">\r\n                    <div class=\"w-14 h-14 bg-blue-50 text-blue-600 rounded-xl flex items-center justify-center mb-6 text-2xl\">\r\n                        <i class=\"fa-solid fa-shield-halved\"><\/i>\r\n                    <\/div>\r\n                    <h3 class=\"text-xl font-bold mb-3 text-slate-900\">Tutto Incluso<\/h3>\r\n                    <p class=\"text-slate-600\">RCA, Kasko, furto e incendio sempre comprese. E la manutenzione ordinaria e straordinaria \u00e8 inclusa nel canone: zero spese impreviste.<\/p>\r\n                <\/div>\r\n\r\n                <!-- Servizio 3 -->\r\n                <div class=\"bg-white p-8 rounded-2xl shadow-sm border border-gray-100 hover:shadow-xl hover:-translate-y-1 transition-all duration-300\">\r\n                    <div class=\"w-14 h-14 bg-blue-50 text-blue-600 rounded-xl flex items-center justify-center mb-6 text-2xl\">\r\n                        <i class=\"fa-solid fa-piggy-bank\"><\/i>\r\n                    <\/div>\r\n                    <h3 class=\"text-xl font-bold mb-3 text-slate-900\">Zero Anticipo<\/h3>\r\n                    <p class=\"text-slate-600\">Scegli il tuo veicolo e paghi solo il canone mensile, senza maxi-rate iniziali. Flessibilit\u00e0 su durata contrattuale e chilometraggio.<\/p>\r\n                <\/div>\r\n\r\n                <!-- Servizio 4 -->\r\n                <div class=\"bg-white p-8 rounded-2xl shadow-sm border border-gray-100 hover:shadow-xl hover:-translate-y-1 transition-all duration-300\">\r\n                    <div class=\"w-14 h-14 bg-blue-50 text-blue-600 rounded-xl flex items-center justify-center mb-6 text-2xl\">\r\n                        <i class=\"fa-solid fa-id-card\"><\/i>\r\n                    <\/div>\r\n                    <h3 class=\"text-xl font-bold mb-3 text-slate-900\">Neopatentati<\/h3>\r\n                    <p class=\"text-slate-600\">Hai appena preso la patente? Guida l'auto dei tuoi sogni senza limits normativi, assicurazione a tuo carico o spese a sorpresa.<\/p>\r\n                <\/div>\r\n\r\n                <!-- Servizio 5 -->\r\n                <div class=\"bg-white p-8 rounded-2xl shadow-sm border border-gray-100 hover:shadow-xl hover:-translate-y-1 transition-all duration-300\">\r\n                    <div class=\"w-14 h-14 bg-blue-50 text-blue-600 rounded-xl flex items-center justify-center mb-6 text-2xl\">\r\n                        <i class=\"fa-solid fa-handshake\"><\/i>\r\n                    <\/div>\r\n                    <h3 class=\"text-xl font-bold mb-3 text-slate-900\">Auto Usate<\/h3>\r\n                    <p class=\"text-slate-600\">Selezioniamo per te veicoli usati o a KM illimitato in perfette condizioni. Le stesse garanzie del noleggio sul nuovo, a costi ridotti.<\/p>\r\n                <\/div>\r\n\r\n                <!-- Servizio 6 -->\r\n                <div class=\"bg-white p-8 rounded-2xl shadow-sm border border-gray-100 hover:shadow-xl hover:-translate-y-1 transition-all duration-300\">\r\n                    <div class=\"w-14 h-14 bg-blue-50 text-blue-600 rounded-xl flex items-center justify-center mb-6 text-2xl\">\r\n                        <i class=\"fa-solid fa-headset\"><\/i>\r\n                    <\/div>\r\n                    <h3 class=\"text-xl font-bold mb-3 text-slate-900\">Assistenza Dedicata<\/h3>\r\n                    <p class=\"text-slate-600\">Personale specializzato ti assister\u00e0 passo dopo passo. Scegli in serenit\u00e0 e viaggia tranquillo, gestiamo noi ogni incombenza burocratica.<\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n    <!-- SEZIONE EVIDENZIATA: AGEVOLAZIONI -->\r\n    <section class=\"w-full bg-blue-600 bg-gradient-to-br from-blue-700 to-blue-500 py-12 md:py-16 px-4 flex items-center justify-center shadow-inner\">\r\n        <h2 class=\"text-center text-2xl sm:text-3xl md:text-4xl lg:text-5xl font-extrabold text-white uppercase tracking-tight\" style=\"text-wrap: balance; line-height: 1.2;\">\r\n            Agevolazioni Riservate<br class=\"hidden md:block\"> agli Associati\r\n        <\/h2>\r\n    <\/section>\r\n\r\n    <!-- Sezione: Contatti e Social -->\r\n    <section class=\"py-16 md:py-24 bg-slate-900 text-white px-6\">\r\n        <div class=\"container mx-auto max-w-4xl text-center\">\r\n            \r\n            <div class=\"inline-flex items-center justify-center p-3 bg-slate-800 rounded-full mb-6 text-blue-400\">\r\n                <i class=\"fa-solid fa-envelope-open-text text-2xl\"><\/i>\r\n            <\/div>\r\n            <h2 class=\"text-2xl md:text-4xl font-extrabold mb-10 text-white\">Contatti<\/h2>\r\n\r\n            <!-- Griglia dei Dati di Contatto -->\r\n            <div class=\"grid grid-cols-1 md:grid-cols-2 gap-6 text-left max-w-2xl mx-auto mb-12 bg-slate-800 p-6 md:p-8 rounded-2xl border border-slate-700\">\r\n                \r\n                <div class=\"flex items-start gap-4\">\r\n                    <div class=\"text-blue-400 mt-1\"><i class=\"fa-solid fa-location-dot\"><\/i><\/div>\r\n                    <div>\r\n                        <h4 class=\"text-xs text-slate-400 font-bold uppercase tracking-wider mb-1\">Indirizzo<\/h4>\r\n                        <p class=\"text-base font-medium\">Via Michetti 20<br>Manoppello (PE) - 65024<\/p>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <div class=\"flex items-start gap-4\">\r\n                    <div class=\"text-blue-400 mt-1\"><i class=\"fa-solid fa-phone\"><\/i><\/div>\r\n                    <div>\r\n                        <h4 class=\"text-xs text-slate-400 font-bold uppercase tracking-wider mb-1\">Telefono<\/h4>\r\n                        <a href=\"tel:+393287020927\" class=\"text-base font-medium hover:text-blue-300 transition\">+39 328 702 0927<\/a>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <div class=\"flex items-start gap-4\">\r\n                    <div class=\"text-blue-400 mt-1\"><i class=\"fa-solid fa-envelope\"><\/i><\/div>\r\n                    <div>\r\n                        <h4 class=\"text-xs text-slate-400 font-bold uppercase tracking-wider mb-1\">Mail<\/h4>\r\n                        <a href=\"mailto:noleggioauto@dortenzio.it\" class=\"text-base font-medium hover:text-blue-300 transition break-all\">noleggioauto@dortenzio.it<\/a>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n                <div class=\"flex items-start gap-4\">\r\n                    <div class=\"text-blue-400 mt-1\"><i class=\"fa-solid fa-globe\"><\/i><\/div>\r\n                    <div>\r\n                        <h4 class=\"text-xs text-slate-400 font-bold uppercase tracking-wider mb-1\">Sito Web<\/h4>\r\n                        <a href=\"https:\/\/www.dortenzio.it\/\" target=\"_blank\" class=\"text-base font-medium hover:text-blue-300 transition\">www.dortenzio.it<\/a>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Media Buttons -->\r\n            <div class=\"flex flex-col items-center\">\r\n                <p class=\"text-slate-400 mb-4 font-medium tracking-wide uppercase text-xs\">Rimaniamo in contatto<\/p>\r\n                <div class=\"flex justify-center gap-4\">\r\n                    \r\n                    <!-- Facebook -->\r\n                    <a href=\"https:\/\/www.facebook.com\/dortenzio.it\" target=\"_blank\" aria-label=\"Facebook\" class=\"w-12 h-12 flex items-center justify-center rounded-full bg-[#1877F2] text-white hover:bg-opacity-80 hover:scale-105 transition-all shadow-md text-xl\">\r\n                        <i class=\"fa-brands fa-facebook-f\"><\/i>\r\n                    <\/a>\r\n\r\n                    <!-- Instagram -->\r\n                    <a href=\"https:\/\/www.instagram.com\/dortenzio.it\/\" target=\"_blank\" aria-label=\"Instagram\" class=\"w-12 h-12 flex items-center justify-center rounded-full bg-gradient-to-tr from-[#fd5949] via-[#d6249f] to-[#285AEB] text-white hover:bg-opacity-80 hover:scale-105 transition-all shadow-md text-xl\">\r\n                        <i class=\"fa-brands fa-instagram\"><\/i>\r\n                    <\/a>\r\n\r\n                    <!-- WhatsApp -->\r\n                    <a href=\"https:\/\/wa.link\/92gw6q\" target=\"_blank\" aria-label=\"WhatsApp\" class=\"w-12 h-12 flex items-center justify-center rounded-full bg-[#25D366] text-white hover:bg-opacity-80 hover:scale-105 transition-all shadow-md text-xl\">\r\n                        <i class=\"fa-brands fa-whatsapp\"><\/i>\r\n                    <\/a>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n        <\/div>\r\n    <\/section>\r\n\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-525e786 e-con-full e-flex e-con e-parent\" data-id=\"525e786\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ec581 elementor-widget elementor-widget-text-editor\" data-id=\"12ec581\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-506\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-506\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-506\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-506\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-506\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"506\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61832e3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"61832e3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4478a elementor-widget elementor-widget-text-editor\" data-id=\"3d4478a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dortenzio.it \u00e8 l&#8217;agenzia specializzata nel noleggio a lungo termine di auto, moto e veicoli commerciali, un punto di riferimento in Abruzzo e su tutto il territorio nazionale per chi cerca una mobilit\u00e0 senza pensieri. Grazie a formule flessibili e personalizzate per privati, aziende, professionisti con partita IVA e neopatentati, la nostra realt\u00e0 permette di guidare auto nuove o veicoli usati garantiti a chilometri illimitati senza l&#8217;obbligo di un acquisto definitivo. Tutti i nostri servizi di noleggio si basano su un conveniente canone mensile tutto incluso che azzera le spese impreviste, coprendo interamente i costi di assicurazione RCA, Kasko, furto e incendio, insieme alla manutenzione ordinaria e straordinaria. Con le nostre vantaggiose soluzioni a zero anticipo, l&#8217;accesso alla mobilit\u00e0 \u00e8 immediato e privo di maxi-rate iniziali, supportato da un servizio di assistenza dedicata sempre al tuo fianco. Inoltre, all&#8217;interno del nostro portale \u00e8 attiva una sezione esclusiva con agevolazioni riservate agli associati, pensata per offrire condizioni economiche ancora pi\u00f9 competitive. Per richiedere un preventivo gratuito e personalizzato, visita il nostro sito ufficiale www.dortenzio.it o contatta i nostri uffici in Via Michetti 20 a Manoppello (PE) chiamando il numero di telefono +39 328 702 0927 o scrivendo a noleggioauto@dortenzio.it, e resta sempre aggiornato sulle ultime promozioni seguendo i nostri canali ufficiali Facebook, Instagram e l&#8217;assistenza rapida tramite WhatsApp.<\/p><p>noleggio lungo termine, noleggio auto lungo termine, noleggio moto lungo termine, noleggio veicoli commerciali, noleggio senza pensieri, mobilit\u00e0 conveniente, noleggio auto nuove, noleggio veicoli usati garantiti, noleggio zero anticipo, noleggio senza maxi-rate, canone tutto incluso, noleggio auto Abruzzo, agenzia noleggio, formule personalizzate noleggio, auto chilometri illimitati, assicurazione auto inclusa, manutenzione auto inclusa, offerte noleggio auto, agevolazioni noleggio, preventivo noleggio gratuito, Dortenzio noleggio auto, servizi noleggio privati, noleggio aziende, noleggio professionisti partita IVA, noleggio per neopatentati, Manoppello,<\/p><p>noleggio lungo termine Manoppello, noleggio auto lungo termine Manoppello, noleggio moto lungo termine Manoppello, noleggio veicoli commerciali Manoppello, noleggio senza pensieri Manoppello, mobilit\u00e0 conveniente Manoppello, noleggio auto nuove Manoppello, noleggio veicoli usati garantiti Manoppello, noleggio zero anticipo Manoppello, noleggio senza maxi-rate Manoppello, canone tutto incluso Manoppello, noleggio auto Abruzzo Manoppello, agenzia noleggio Manoppello, formule personalizzate noleggio Manoppello, auto chilometri illimitati Manoppello, assicurazione auto inclusa Manoppello, manutenzione auto inclusa Manoppello, offerte noleggio auto Manoppello, agevolazioni noleggio Manoppello, preventivo noleggio gratuito Manoppello, Dortenzio noleggio auto Manoppello, servizi noleggio privati Manoppello, noleggio aziende Manoppello, noleggio professionisti partita IVA Manoppello, noleggio per neopatentati Manoppello,<\/p><p>noleggio lungo termine a Manoppello, noleggio auto lungo termine a Manoppello, noleggio moto lungo termine a Manoppello, noleggio veicoli commerciali a Manoppello, noleggio senza pensieri a Manoppello, mobilit\u00e0 conveniente a Manoppello, noleggio auto nuove a Manoppello, noleggio veicoli usati garantiti a Manoppello, noleggio zero anticipo a Manoppello, noleggio senza maxi-rate a Manoppello, canone tutto incluso a Manoppello, noleggio auto Abruzzo a Manoppello, agenzia noleggio a Manoppello, formule personalizzate noleggio a Manoppello, auto chilometri illimitati a Manoppello, assicurazione auto inclusa a Manoppello, manutenzione auto inclusa a Manoppello, offerte noleggio auto a Manoppello, agevolazioni noleggio a Manoppello, preventivo noleggio gratuito a Manoppello, Dortenzio noleggio auto a Manoppello, servizi noleggio privati a Manoppello, noleggio aziende a Manoppello, noleggio professionisti partita IVA a Manoppello, noleggio per neopatentati a Manoppello,<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display:none\">\n<p>Dortenzio.it \u00e8 l&#8217;agenzia specializzata nel noleggio a lungo termine di auto, moto e veicoli commerciali, un punto di riferimento in Abruzzo e su tutto il territorio nazionale per chi cerca una mobilit\u00e0 senza pensieri. Grazie a formule flessibili e personalizzate per privati, aziende, professionisti con partita IVA e neopatentati, la nostra realt\u00e0 permette di guidare auto nuove o veicoli usati garantiti a chilometri illimitati senza l&#8217;obbligo di un acquisto definitivo. Tutti i nostri servizi di noleggio si basano su un conveniente canone mensile tutto incluso che azzera le spese impreviste, coprendo interamente i costi di assicurazione RCA, Kasko, furto e incendio, insieme alla manutenzione ordinaria e straordinaria. Con le nostre vantaggiose soluzioni a zero anticipo, l&#8217;accesso alla mobilit\u00e0 \u00e8 immediato e privo di maxi-rate iniziali, supportato da un servizio di assistenza dedicata sempre al tuo fianco. Inoltre, all&#8217;interno del nostro portale \u00e8 attiva una sezione esclusiva con agevolazioni riservate agli associati, pensata per offrire condizioni economiche ancora pi\u00f9 competitive. Per richiedere un preventivo gratuito e personalizzato, visita il nostro sito ufficiale www.dortenzio.it o contatta i nostri uffici in Via Michetti 20 a Manoppello (PE) chiamando il numero di telefono +39 328 702 0927 o scrivendo a noleggioauto@dortenzio.it, e resta sempre aggiornato sulle ultime promozioni seguendo i nostri canali ufficiali Facebook, Instagram e l&#8217;assistenza rapida tramite WhatsApp.<\/p>\n<p>noleggio lungo termine, noleggio auto lungo termine, noleggio moto lungo termine, noleggio veicoli commerciali, noleggio senza pensieri, mobilit\u00e0 conveniente, noleggio auto nuove, noleggio veicoli usati garantiti, noleggio zero anticipo, noleggio senza maxi-rate, canone tutto incluso, noleggio auto Abruzzo, agenzia noleggio, formule personalizzate noleggio, auto chilometri illimitati, assicurazione auto inclusa, manutenzione auto inclusa, offerte noleggio auto, agevolazioni noleggio, preventivo noleggio gratuito, Dortenzio noleggio auto, servizi noleggio privati, noleggio aziende, noleggio professionisti partita IVA, noleggio per neopatentati, Manoppello,<\/p>\n<p>noleggio lungo termine Manoppello, noleggio auto lungo termine Manoppello, noleggio moto lungo termine Manoppello, noleggio veicoli commerciali Manoppello, noleggio senza pensieri Manoppello, mobilit\u00e0 conveniente Manoppello, noleggio auto nuove Manoppello, noleggio veicoli usati garantiti Manoppello, noleggio zero anticipo Manoppello, noleggio senza maxi-rate Manoppello, canone tutto incluso Manoppello, noleggio auto Abruzzo Manoppello, agenzia noleggio Manoppello, formule personalizzate noleggio Manoppello, auto chilometri illimitati Manoppello, assicurazione auto inclusa Manoppello, manutenzione auto inclusa Manoppello, offerte noleggio auto Manoppello, agevolazioni noleggio Manoppello, preventivo noleggio gratuito Manoppello, Dortenzio noleggio auto Manoppello, servizi noleggio privati Manoppello, noleggio aziende Manoppello, noleggio professionisti partita IVA Manoppello, noleggio per neopatentati Manoppello,<\/p>\n<p>noleggio lungo termine a Manoppello, noleggio auto lungo termine a Manoppello, noleggio moto lungo termine a Manoppello, noleggio veicoli commerciali a Manoppello, noleggio senza pensieri a Manoppello, mobilit\u00e0 conveniente a Manoppello, noleggio auto nuove a Manoppello, noleggio veicoli usati garantiti a Manoppello, noleggio zero anticipo a Manoppello, noleggio senza maxi-rate a Manoppello, canone tutto incluso a Manoppello, noleggio auto Abruzzo a Manoppello, agenzia noleggio a Manoppello, formule personalizzate noleggio a Manoppello, auto chilometri illimitati a Manoppello, assicurazione auto inclusa a Manoppello, manutenzione auto inclusa a Manoppello, offerte noleggio auto a Manoppello, agevolazioni noleggio a Manoppello, preventivo noleggio gratuito a Manoppello, Dortenzio noleggio auto a Manoppello, servizi noleggio privati a Manoppello, noleggio aziende a Manoppello, noleggio professionisti partita IVA a Manoppello, noleggio per neopatentati a Manoppello,\n<\/p><\/div>\n","protected":false},"featured_media":103005,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[18,31,32],"product_tag":[17917,22799,22796,22795,22792,22801,22794,22806,22797,22787,22793,17905,22788,22803,1523,22785,22805,22804,22791,22786,6508,22789,22790,22798,22800,22802],"class_list":{"0":"post-103004","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-auto-moto","7":"product_cat-noleggio","8":"product_cat-noleggio-lungo-termine","9":"product_tag-agenzia-noleggio","10":"product_tag-agevolazioni-noleggio","11":"product_tag-assicurazione-auto-inclusa","12":"product_tag-auto-chilometri-illimitati","13":"product_tag-canone-tutto-incluso","14":"product_tag-dortenzio-noleggio-auto","15":"product_tag-formule-personalizzate-noleggio","16":"product_tag-manoppello","17":"product_tag-manutenzione-auto-inclusa","18":"product_tag-mobilita-conveniente","19":"product_tag-noleggio-auto-abruzzo","20":"product_tag-noleggio-auto-lungo-termine","21":"product_tag-noleggio-auto-nuove","22":"product_tag-noleggio-aziende","23":"product_tag-noleggio-lungo-termine","24":"product_tag-noleggio-moto-lungo-termine","25":"product_tag-noleggio-per-neopatentati","26":"product_tag-noleggio-professionisti-partita-iva","27":"product_tag-noleggio-senza-maxi-rate","28":"product_tag-noleggio-senza-pensieri","29":"product_tag-noleggio-veicoli-commerciali","30":"product_tag-noleggio-veicoli-usati-garantiti","31":"product_tag-noleggio-zero-anticipo","32":"product_tag-offerte-noleggio-auto","33":"product_tag-preventivo-noleggio-gratuito","34":"product_tag-servizi-noleggio-privati","36":"first","37":"instock","38":"shipping-taxable","39":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dortenzio.it - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dortenzio.it - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dortenzio.it \u00e8 l&#039;agenzia specializzata nel noleggio a lungo termine di auto, moto e veicoli commerciali, un punto di riferimento in Abruzzo e su tutto il territorio nazionale per chi cerca una mobilit\u00e0 senza pensieri. Grazie a formule flessibili e personalizzate per privati, aziende, professionisti con partita IVA e neopatentati, la nostra realt\u00e0 permette di guidare auto nuove o veicoli usati garantiti a chilometri illimitati senza l&#039;obbligo di un acquisto definitivo. Tutti i nostri servizi di noleggio si basano su un conveniente canone mensile tutto incluso che azzera le spese impreviste, coprendo interamente i costi di assicurazione RCA, Kasko, furto e incendio, insieme alla manutenzione ordinaria e straordinaria. Con le nostre vantaggiose soluzioni a zero anticipo, l&#039;accesso alla mobilit\u00e0 \u00e8 immediato e privo di maxi-rate iniziali, supportato da un servizio di assistenza dedicata sempre al tuo fianco. Inoltre, all&#039;interno del nostro portale \u00e8 attiva una sezione esclusiva con agevolazioni riservate agli associati, pensata per offrire condizioni economiche ancora pi\u00f9 competitive. Per richiedere un preventivo gratuito e personalizzato, visita il nostro sito ufficiale www.dortenzio.it o contatta i nostri uffici in Via Michetti 20 a Manoppello (PE) chiamando il numero di telefono +39 328 702 0927 o scrivendo a noleggioauto@dortenzio.it, e resta sempre aggiornato sulle ultime promozioni seguendo i nostri canali ufficiali Facebook, Instagram e l&#039;assistenza rapida tramite WhatsApp.  noleggio lungo termine, noleggio auto lungo termine, noleggio moto lungo termine, noleggio veicoli commerciali, noleggio senza pensieri, mobilit\u00e0 conveniente, noleggio auto nuove, noleggio veicoli usati garantiti, noleggio zero anticipo, noleggio senza maxi-rate, canone tutto incluso, noleggio auto Abruzzo, agenzia noleggio, formule personalizzate noleggio, auto chilometri illimitati, assicurazione auto inclusa, manutenzione auto inclusa, offerte noleggio auto, agevolazioni noleggio, preventivo noleggio gratuito, Dortenzio noleggio auto, servizi noleggio privati, noleggio aziende, noleggio professionisti partita IVA, noleggio per neopatentati, Manoppello,  noleggio lungo termine Manoppello, noleggio auto lungo termine Manoppello, noleggio moto lungo termine Manoppello, noleggio veicoli commerciali Manoppello, noleggio senza pensieri Manoppello, mobilit\u00e0 conveniente Manoppello, noleggio auto nuove Manoppello, noleggio veicoli usati garantiti Manoppello, noleggio zero anticipo Manoppello, noleggio senza maxi-rate Manoppello, canone tutto incluso Manoppello, noleggio auto Abruzzo Manoppello, agenzia noleggio Manoppello, formule personalizzate noleggio Manoppello, auto chilometri illimitati Manoppello, assicurazione auto inclusa Manoppello, manutenzione auto inclusa Manoppello, offerte noleggio auto Manoppello, agevolazioni noleggio Manoppello, preventivo noleggio gratuito Manoppello, Dortenzio noleggio auto Manoppello, servizi noleggio privati Manoppello, noleggio aziende Manoppello, noleggio professionisti partita IVA Manoppello, noleggio per neopatentati Manoppello,  noleggio lungo termine a Manoppello, noleggio auto lungo termine a Manoppello, noleggio moto lungo termine a Manoppello, noleggio veicoli commerciali a Manoppello, noleggio senza pensieri a Manoppello, mobilit\u00e0 conveniente a Manoppello, noleggio auto nuove a Manoppello, noleggio veicoli usati garantiti a Manoppello, noleggio zero anticipo a Manoppello, noleggio senza maxi-rate a Manoppello, canone tutto incluso a Manoppello, noleggio auto Abruzzo a Manoppello, agenzia noleggio a Manoppello, formule personalizzate noleggio a Manoppello, auto chilometri illimitati a Manoppello, assicurazione auto inclusa a Manoppello, manutenzione auto inclusa a Manoppello, offerte noleggio auto a Manoppello, agevolazioni noleggio a Manoppello, preventivo noleggio gratuito a Manoppello, Dortenzio noleggio auto a Manoppello, servizi noleggio privati a Manoppello, noleggio aziende a Manoppello, noleggio professionisti partita IVA a Manoppello, noleggio per neopatentati a Manoppello,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T14:32:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/\",\"name\":\"Dortenzio.it - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png\",\"datePublished\":\"2026-06-16T09:30:56+00:00\",\"dateModified\":\"2026-06-30T14:32:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dortenzio.it\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dortenzio.it - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/","og_locale":"it_IT","og_type":"article","og_title":"Dortenzio.it - UIL Polizia","og_description":"Dortenzio.it \u00e8 l'agenzia specializzata nel noleggio a lungo termine di auto, moto e veicoli commerciali, un punto di riferimento in Abruzzo e su tutto il territorio nazionale per chi cerca una mobilit\u00e0 senza pensieri. Grazie a formule flessibili e personalizzate per privati, aziende, professionisti con partita IVA e neopatentati, la nostra realt\u00e0 permette di guidare auto nuove o veicoli usati garantiti a chilometri illimitati senza l'obbligo di un acquisto definitivo. Tutti i nostri servizi di noleggio si basano su un conveniente canone mensile tutto incluso che azzera le spese impreviste, coprendo interamente i costi di assicurazione RCA, Kasko, furto e incendio, insieme alla manutenzione ordinaria e straordinaria. Con le nostre vantaggiose soluzioni a zero anticipo, l'accesso alla mobilit\u00e0 \u00e8 immediato e privo di maxi-rate iniziali, supportato da un servizio di assistenza dedicata sempre al tuo fianco. Inoltre, all'interno del nostro portale \u00e8 attiva una sezione esclusiva con agevolazioni riservate agli associati, pensata per offrire condizioni economiche ancora pi\u00f9 competitive. Per richiedere un preventivo gratuito e personalizzato, visita il nostro sito ufficiale www.dortenzio.it o contatta i nostri uffici in Via Michetti 20 a Manoppello (PE) chiamando il numero di telefono +39 328 702 0927 o scrivendo a noleggioauto@dortenzio.it, e resta sempre aggiornato sulle ultime promozioni seguendo i nostri canali ufficiali Facebook, Instagram e l'assistenza rapida tramite WhatsApp.  noleggio lungo termine, noleggio auto lungo termine, noleggio moto lungo termine, noleggio veicoli commerciali, noleggio senza pensieri, mobilit\u00e0 conveniente, noleggio auto nuove, noleggio veicoli usati garantiti, noleggio zero anticipo, noleggio senza maxi-rate, canone tutto incluso, noleggio auto Abruzzo, agenzia noleggio, formule personalizzate noleggio, auto chilometri illimitati, assicurazione auto inclusa, manutenzione auto inclusa, offerte noleggio auto, agevolazioni noleggio, preventivo noleggio gratuito, Dortenzio noleggio auto, servizi noleggio privati, noleggio aziende, noleggio professionisti partita IVA, noleggio per neopatentati, Manoppello,  noleggio lungo termine Manoppello, noleggio auto lungo termine Manoppello, noleggio moto lungo termine Manoppello, noleggio veicoli commerciali Manoppello, noleggio senza pensieri Manoppello, mobilit\u00e0 conveniente Manoppello, noleggio auto nuove Manoppello, noleggio veicoli usati garantiti Manoppello, noleggio zero anticipo Manoppello, noleggio senza maxi-rate Manoppello, canone tutto incluso Manoppello, noleggio auto Abruzzo Manoppello, agenzia noleggio Manoppello, formule personalizzate noleggio Manoppello, auto chilometri illimitati Manoppello, assicurazione auto inclusa Manoppello, manutenzione auto inclusa Manoppello, offerte noleggio auto Manoppello, agevolazioni noleggio Manoppello, preventivo noleggio gratuito Manoppello, Dortenzio noleggio auto Manoppello, servizi noleggio privati Manoppello, noleggio aziende Manoppello, noleggio professionisti partita IVA Manoppello, noleggio per neopatentati Manoppello,  noleggio lungo termine a Manoppello, noleggio auto lungo termine a Manoppello, noleggio moto lungo termine a Manoppello, noleggio veicoli commerciali a Manoppello, noleggio senza pensieri a Manoppello, mobilit\u00e0 conveniente a Manoppello, noleggio auto nuove a Manoppello, noleggio veicoli usati garantiti a Manoppello, noleggio zero anticipo a Manoppello, noleggio senza maxi-rate a Manoppello, canone tutto incluso a Manoppello, noleggio auto Abruzzo a Manoppello, agenzia noleggio a Manoppello, formule personalizzate noleggio a Manoppello, auto chilometri illimitati a Manoppello, assicurazione auto inclusa a Manoppello, manutenzione auto inclusa a Manoppello, offerte noleggio auto a Manoppello, agevolazioni noleggio a Manoppello, preventivo noleggio gratuito a Manoppello, Dortenzio noleggio auto a Manoppello, servizi noleggio privati a Manoppello, noleggio aziende a Manoppello, noleggio professionisti partita IVA a Manoppello, noleggio per neopatentati a Manoppello,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/","og_site_name":"UIL Polizia","article_modified_time":"2026-06-30T14:32:53+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/","name":"Dortenzio.it - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png","datePublished":"2026-06-16T09:30:56+00:00","dateModified":"2026-06-30T14:32:53+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dortenzio.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dortenzio-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dortenzio.it"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/103004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=103004"}],"version-history":[{"count":44,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/103004\/revisions"}],"predecessor-version":[{"id":104468,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/103004\/revisions\/104468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/103005"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=103004"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=103004"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=103004"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=103004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}