{"id":102033,"date":"2026-06-05T14:29:16","date_gmt":"2026-06-05T12:29:16","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=102033"},"modified":"2026-06-08T17:00:32","modified_gmt":"2026-06-08T15:00:32","slug":"dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/","title":{"rendered":"Dr. Francesco Sorrentino &#8211; Psicologo, Psico-oncologo e specializzando in psicoterapia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"102033\" class=\"elementor elementor-102033\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7e0fee e-flex e-con-boxed e-con e-parent\" data-id=\"4b7e0fee\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d8a656e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"2d8a656e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c8dccb elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5c8dccb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1018\" height=\"1024\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-finito-sorrentino-1018x1024.jpeg\" class=\"attachment-large size-large wp-image-102126\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-finito-sorrentino-980x986.jpeg 980w, https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-finito-sorrentino-480x483.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1018px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a787917 e-flex e-con-boxed e-con e-parent\" data-id=\"4a787917\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-797ea6ba e-con-full e-flex e-con e-child\" data-id=\"797ea6ba\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7a881aad e-con-full e-flex e-con e-child\" data-id=\"7a881aad\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa4f007 elementor-widget elementor-widget-text-editor\" data-id=\"1fa4f007\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mi presento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-769bfad7 elementor-widget elementor-widget-text-editor\" data-id=\"769bfad7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono Francesco Sorrentino, <b>psicologo<\/b>, <b>psico-oncologo<\/b> e <b>psicoterapeuta in formazione<\/b>, iscritto all\u2019Ordine degli Psicologi del Veneto (N\u00b0 13311) e all&#8217;Ordine degli Psico-Oncologi certificati SIPO (N\u00b0 184).<\/p><p>Mi sono laureato in Psicologia Clinica e ho completato un Master di II livello in Psico-Oncologia presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Roma.<\/p><p>Attualmente mi sto specializzando in psicoterapia ad orientamento Analisi Transazionale con approccio integrato, che si focalizza sulle dinamiche relazionali per favorire consapevolezza e crescita personale.<\/p><p>In ambito professionale, ho maturato esperienza nelle dipendenze presso una comunit\u00e0 terapeutica veronese e in oncologia, collaborando con il reparto di oncoematologia pediatrica dell\u2019ospedale B. Trento di Verona.<\/p><p>Collaboro ancora con il reparto di oncoematologia e ricevo privati presso il mio <b>studio a Verona<\/b>, rivolgendomi a giovani e adulti in cerca di supporto psicologico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0043f3d e-con-full e-flex e-con e-child\" data-id=\"0043f3d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c14c87c elementor-widget elementor-widget-image\" data-id=\"c14c87c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/coverdr-francesco-sorrentino-psico-819x1024.jpg\" class=\"attachment-large size-large wp-image-102038\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d33d61 e-con-full e-flex e-con e-child\" data-id=\"4d33d61\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-65be93a e-con-full e-flex e-con e-child\" data-id=\"65be93a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d838063 elementor-widget elementor-widget-text-editor\" data-id=\"d838063\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mia missione \u00e8 aiutare le persone a superare momenti difficili ritrovando serenit\u00e0 e benessere emotivo. Sebbene iniziare un percorso terapeutico possa spaventare, ogni passo compiuto dimostra quanto sia importante non rimanere fermi.<\/p><p>La psicoterapia \u00e8 uno spazio sicuro, privo di giudizio, dove creare un\u2019Alleanza Terapeutica per comprendere meglio s\u00e9 stessi e trasformare vecchie dinamiche in strumenti funzionali al proprio equilibrio.<\/p><p><span style=\"color: #348d81;\"><b>Chiedere aiuto non \u00e8 debolezza, ma un atto di amore e coraggio verso s\u00e9 stessi.\u00a0<\/b><\/span><\/p><p><span style=\"color: #348d81;\"><b>\u00c8 l\u2019opportunit\u00e0 di analizzare situazioni intricate, conoscersi profondamente e tornare a sorridere, perch\u00e9 ognuno merita di star bene. <\/b><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-420b5e0 e-flex e-con-boxed e-con e-parent\" data-id=\"420b5e0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-58f5e5b e-con-full e-flex e-con e-child\" data-id=\"58f5e5b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-69ff03c e-con-full e-flex e-con e-child\" data-id=\"69ff03c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a00f2b0 elementor-widget elementor-widget-text-editor\" data-id=\"a00f2b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aree di intervento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7cc609 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"f7cc609\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDifficolt\u00e0 nella sfera affettiva, relazionale e familiare\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8abf09 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"f8abf09\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDisturbi dell\u2019umore Disturbi \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tdepressivi e disagi esistenziali\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f7139 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"a2f7139\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTrauma, malattia, elaborazione del lutto\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b1d819 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"6b1d819\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCrescita personale\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tpotenziamento di autostima, comunicazione, intelligenza emotiva\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e79c877 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"e79c877\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDisturbi ansia, attacchi di panico\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afbc1ce elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"afbc1ce\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDisturbi psicosomatici\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d59a77 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"9d59a77\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGestione dello stress, tecniche di rilassamento\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1919a6f elementor-position-left elementor-view-default elementor-mobile-position-top elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"1919a6f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-holding-heart\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M275.3 250.5c7 7.4 18.4 7.4 25.5 0l108.9-114.2c31.6-33.2 29.8-88.2-5.6-118.8-30.8-26.7-76.7-21.9-104.9 7.7L288 36.9l-11.1-11.6C248.7-4.4 202.8-9.2 172 17.5c-35.3 30.6-37.2 85.6-5.6 118.8l108.9 114.2zm290 77.6c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTerapia di coppia e familiare\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70ecd6c e-con-full e-flex e-con e-child\" data-id=\"70ecd6c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73f538f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"73f538f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c5ef071 e-flex e-con-boxed e-con e-parent\" data-id=\"2c5ef071\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b21eecf e-con-full e-flex e-con e-child\" data-id=\"b21eecf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3588339b elementor-widget elementor-widget-text-editor\" data-id=\"3588339b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-229d7b52 e-flex e-con-boxed e-con e-parent\" data-id=\"229d7b52\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-618374e2 e-con-full e-flex e-con e-child\" data-id=\"618374e2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-50e42f15 e-con-full e-flex e-con e-child\" data-id=\"50e42f15\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-574c9d90 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"574c9d90\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-316\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"102033\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-316\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:400px;\"> <span id=\"gmw-resize-map-toggle-316\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-316\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-316\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"316\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-345ed7c3 e-con-full e-flex e-con e-child\" data-id=\"345ed7c3\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3aac5a52 elementor-widget elementor-widget-text-editor\" data-id=\"3aac5a52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48a30ee3 elementor-widget elementor-widget-text-editor\" data-id=\"48a30ee3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Studio Privato:<\/b><br \/>Via Filippo Brunelleschi, 1 &#8211; 37138 Verona (VR)<\/p><p>Tel: <a href=\"tel:+393389823753\" target=\"_blank\" rel=\"noopener\">338 98 23 753<\/a><br \/>Mail: <a href=\"mailto:dr.sorrentinofrancesco@gmail.com\" target=\"_blank\" rel=\"noopener\">dr.sorrentinofrancesco@gmail.com<\/a><br \/>Sito: <a href=\"https:\/\/www.psicologo-sorrentino.it\/\" target=\"_blank\" rel=\"noopener\">www.psicologo-sorrentino.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-571276f7 elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"571276f7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/wa.me\/393389823753\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Whatsapp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7683f78c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7683f78c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66e04ba0\" data-id=\"66e04ba0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0868fd elementor-widget elementor-widget-text-editor\" data-id=\"1f0868fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b7b994b elementor-widget elementor-widget-text-editor\" data-id=\"3b7b994b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c97494c elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7c97494c\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-2136453\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-bbe8529\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-a831d86\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50b926e8\" data-id=\"50b926e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3833e4d3 elementor-widget elementor-widget-text-editor\" data-id=\"3833e4d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-298\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"102033\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-298\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-298\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-298\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-298\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"298\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-385a63a4 elementor-widget elementor-widget-text-editor\" data-id=\"385a63a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-280\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-280\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-280\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-280\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-280\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"280\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6c919742 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"6c919742\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63045bec elementor-widget elementor-widget-text-editor\" data-id=\"63045bec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDott. Francesco Degl&#8217;Innocenti\nPsichiatra e Neurologo\n\nPresentazione\n\nHo conseguito la laurea in Medicina presso l\u2019Universit\u00e0 di Firenze nel 1982. Successivamente, spinto dal fascino per la complessit\u00e0 del cervello e della mente umana, ho deciso di specializzarmi in neurologia.\n\nDopo aver completato la specializzazione nel 1987, ho iniziato immediatamente a lavorare come psichiatra, e dal 1991 ho ricoperto il ruolo di dirigente presso l\u2019ASL Toscana Centro nel reparto di Psichiatria.\n\nNel corso di oltre 30 anni di attivit\u00e0 professionale, ho avuto l\u2019opportunit\u00e0 di seguire e trattare una vasta variet\u00e0 di casi clinici. Oggi metto a frutto questa preziosa esperienza nel mio lavoro da libero professionista.\n\nPercorsi offerti\n\nClicca sulla voci per maggiori informazioni\n\nDiagnosi Psichiatrica\nLa diagnosi psichiatrica \u00e8 un atto medico che si basa su un colloquio approfondito, durante il quale la persona racconta di s\u00e9 e delle proprie difficolt\u00e0. Le malattie psichiatriche, spesso curabili, includono depressione, ansia, panico, disturbo borderline, dipendenze e disturbi della percezione corporea.\nSi va dalla malinconia agli stati di angoscia, fino alla perdita di libert\u00e0 nelle dipendenze o alla distorta percezione del proprio corpo.\n\nPsicoterapia\nEsistono molte forme di psicoterapia, ma sono pi\u00f9 simili tra loro di quanto si pensi. \u00c8 l\u2019interazione tra terapeuta e paziente a fare la differenza, pi\u00f9 che la teoria o tecnica utilizzata.\nLe terapie cognitivo-comportamentali sono le pi\u00f9 diffuse, con solide prove scientifiche della loro efficacia per depressione e ansia. La psicoanalisi di Freud, originaria dell\u2019Ottocento, ha influenzato profondamente la societ\u00e0 moderna, seppur oggi meno praticata nella sua forma originale.\n\nTerapia per la guarigione dei traumi\nLa terapia per la guarigione dei traumi psichici si occupa di eventi esterni che provocano forti reazioni emotive, superando le capacit\u00e0 dell&#8217;individuo di assimilarli. Esistono approcci specifici, come le psicoterapie focalizzate sui traumi o adattate al caso, con significativi benefici sulla qualit\u00e0 di vita.\nTra le terapie non psicologiche, la pi\u00f9 nota \u00e8 l\u2019EMDR, mentre in prospettiva futura non si esclude un possibile supporto farmacologico.\n\nNeuropsichiatria\nNeuropsichiatria non significa semplicemente unire psichiatria e neurologia, ma adottare un approccio medico che supera il dualismo mente-cervello-corpo. Nei disturbi neuropsichiatrici, come autismo, ADHD e disturbi cognitivi, i sintomi persistono spesso oltre i 18 anni.\nAnche nelle patologie neurologiche classiche, come demenze, epilessia e sclerosi multipla, emergono rilevanti manifestazioni psichiatriche.\n\nTerapia farmacologica\nLa terapia farmacologica entra in gioco dopo una diagnosi di malattia o disturbo, ma non sempre \u00e8 utile n\u00e9 del tutto efficace. Una psichiatria estetica, volta a inseguire una felicit\u00e0 fittizia o la bellezza, appare poco pertinente. In psichiatria, i farmaci non curano del tutto, ma modificano aspetti come il panico, insonnia o agitazione.\nTuttavia, tutti i farmaci, compresi il placebo, presentano effetti collaterali, aumentati dall\u2019uso simultaneo di pi\u00f9 medicinali.\n\nDisturbi del Neurosviluppo\nI disturbi del neurosviluppo si manifestano fin dall&#8217;infanzia, ma possono essere diagnosticati anche in et\u00e0 adulta. L&#8217;autismo, che ha origine nei primi anni di vita, si presenta in diverse forme, incluse quelle ad alto funzionamento spesso riconosciute solo negli adulti.\nAnche l&#8217;ADHD, tipico dell&#8217;et\u00e0 infantile, persiste nel 50% dei casi nel giovane adulto.\n\nDott. Francesco Degl&#8217;Innocenti, psichiatra, neurologo, diagnosi psichiatrica, depressione, ansia, panico, disturbo borderline, dipendenze, disturbi percezione corporea, psicoterapia, terapie cognitivo-comportamentali, psicoanalisi, Freud, terapia guarigione traumi, EMDR, neuropsichiatria, autismo, ADHD, disturbi cognitivi, demenze, epilessia, sclerosi multipla, terapia farmacologica, disturbi del neurosviluppo, psichiatra, supporto psichiatrico, sostegno psichiatrico, percorso psichiatrico, psichiatri, neuropsichiatri, neuropsichiatra, neurologi, percorso psicoterapeutico, percorsi psicoterapici, psicoterapeuta, psicoterapeuti, Firenze,\n\nDott. Francesco Degl&#8217;Innocenti Firenze, psichiatra Firenze, neurologo Firenze, diagnosi psichiatrica Firenze, depressione Firenze, ansia Firenze, panico Firenze, disturbo borderline Firenze, dipendenze Firenze, disturbi percezione corporea Firenze, psicoterapia Firenze, terapie cognitivo-comportamentali Firenze, psicoanalisi Firenze, Freud Firenze, terapia guarigione traumi Firenze, EMDR Firenze, neuropsichiatria Firenze, autismo Firenze, ADHD Firenze, disturbi cognitivi Firenze, demenze Firenze, epilessia Firenze, sclerosi multipla Firenze, terapia farmacologica Firenze, disturbi del neurosviluppo Firenze, psichiatra Firenze, supporto psichiatrico Firenze, sostegno psichiatrico Firenze, percorso psichiatrico Firenze, psichiatri Firenze, neuropsichiatri Firenze, neuropsichiatra Firenze, neurologi Firenze, percorso psicoterapeutico Firenze, percorsi psicoterapici Firenze, psicoterapeuta Firenze, psicoterapeuti Firenze,\n\nDott. Francesco Degl&#8217;Innocenti a Firenze, psichiatra a Firenze, neurologo a Firenze, diagnosi psichiatrica a Firenze, depressione a Firenze, ansia a Firenze, panico a Firenze, disturbo borderline a Firenze, dipendenze a Firenze, disturbi percezione corporea a Firenze, psicoterapia a Firenze, terapie cognitivo-comportamentali a Firenze, psicoanalisi a Firenze, Freud a Firenze, terapia guarigione traumi a Firenze, EMDR a Firenze, neuropsichiatria a Firenze, autismo a Firenze, ADHD a Firenze, disturbi cognitivi a Firenze, demenze a Firenze, epilessia a Firenze, sclerosi multipla a Firenze, terapia farmacologica a Firenze, disturbi del neurosviluppo a Firenze, psichiatra a Firenze, supporto psichiatrico a Firenze, sostegno psichiatrico a Firenze, percorso psichiatrico a Firenze, psichiatri a Firenze, neuropsichiatri a Firenze, neuropsichiatra a Firenze, neurologi a Firenze, percorso psicoterapeutico a Firenze, percorsi psicoterapici a Firenze, psicoterapeuta a Firenze, psicoterapeuti a Firenze,\n\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Dr. Francesco Sorrentino &#8211; Psicologo, Psico-oncologo e specializzando in psicoterapia<\/p>\n<p>Francesco Sorrentino, psicologo, psico-oncologo, psicoterapeuta, Ordine degli Psicologi del Veneto, Ordine degli Psico-Oncologi certificati SIPO, Laurea in Psicologia Clinica, Master in Psico-Oncologia, Universit\u00e0 Cattolica del Sacro Cuore di Roma, specializzazione psicoterapia, Analisi Transazionale, approccio integrato, dinamiche relazionali, consapevolezza, crescita personale, esperienza dipendenze, comunit\u00e0 terapeutica Verona, oncoematologia pediatrica, ospedale B. Trento Verona, studio psicologo Verona, supporto psicologico giovani e adulti, benessere emotivo, Alleanza Terapeutica, superare difficolt\u00e0 personali, ritrovare serenit\u00e0, difficolt\u00e0 affettive, difficolt\u00e0 relazionali, difficolt\u00e0 familiari, disturbi dell\u2019umore, disturbi depressivi, disagi esistenziali, trauma, malattia, elaborazione lutto, crescita personale, autostima, comunicazione efficace, intelligenza emotiva, disturbi d\u2019ansia, attacchi di panico, disturbi psicosomatici, gestione dello stress, tecniche rilassamento, terapia di coppia, terapia familiare, psicologo, psicologi, supporto psicologico, supporto psicologico per pazienti oncologici, percorso psicologico, percorso psicologico per pazienti oncologici, sostegno psicologico, sostegno psicologico per pazienti oncologici, Verona,<\/p>\n<p>Francesco Sorrentino Verona, psicologo Verona, psico-oncologo Verona, psicoterapeuta Verona, Ordine degli Psicologi del Veneto Verona, Ordine degli Psico-Oncologi certificati SIPO Verona, Laurea in Psicologia Clinica Verona, Master in Psico-Oncologia Verona, Universit\u00e0 Cattolica del Sacro Cuore di Roma Verona, specializzazione psicoterapia Verona, Analisi Transazionale Verona, approccio integrato Verona, dinamiche relazionali Verona, consapevolezza Verona, crescita personale Verona, esperienza dipendenze Verona, comunit\u00e0 terapeutica Verona Verona, oncoematologia pediatrica Verona, ospedale B. Trento Verona Verona, studio psicologo Verona Verona, supporto psicologico giovani e adulti Verona, benessere emotivo Verona, Alleanza Terapeutica Verona, superare difficolt\u00e0 personali Verona, ritrovare serenit\u00e0 Verona, difficolt\u00e0 affettive Verona, difficolt\u00e0 relazionali Verona, difficolt\u00e0 familiari Verona, disturbi dell\u2019umore Verona, disturbi depressivi Verona, disagi esistenziali Verona, trauma Verona, malattia Verona, elaborazione lutto Verona, crescita personale Verona, autostima Verona, comunicazione efficace Verona, intelligenza emotiva Verona, disturbi d\u2019ansia Verona, attacchi di panico Verona, disturbi psicosomatici Verona, gestione dello stress Verona, tecniche rilassamento Verona, terapia di coppia Verona, terapia familiare Verona, psicologo Verona, psicologi Verona, supporto psicologico Verona, supporto psicologico per pazienti oncologici Verona, percorso psicologico Verona, percorso psicologico per pazienti oncologici Verona, sostegno psicologico Verona, sostegno psicologico per pazienti oncologici Verona,<\/p>\n<p>Francesco Sorrentino a Verona, psicologo a Verona, psico-oncologo a Verona, psicoterapeuta a Verona, Ordine degli Psicologi del Veneto a Verona, Ordine degli Psico-Oncologi certificati SIPO a Verona, Laurea in Psicologia Clinica a Verona, Master in Psico-Oncologia a Verona, Universit\u00e0 Cattolica del Sacro Cuore di Roma a Verona, specializzazione psicoterapia a Verona, Analisi Transazionale a Verona, approccio integrato a Verona, dinamiche relazionali a Verona, consapevolezza a Verona, crescita personale a Verona, esperienza dipendenze a Verona, comunit\u00e0 terapeutica Verona a Verona, oncoematologia pediatrica a Verona, ospedale B. Trento Verona a Verona, studio psicologo Verona a Verona, supporto psicologico giovani e adulti a Verona, benessere emotivo a Verona, Alleanza Terapeutica a Verona, superare difficolt\u00e0 personali a Verona, ritrovare serenit\u00e0 a Verona, difficolt\u00e0 affettive a Verona, difficolt\u00e0 relazionali a Verona, difficolt\u00e0 familiari a Verona, disturbi dell\u2019umore a Verona, disturbi depressivi a Verona, disagi esistenziali a Verona, trauma a Verona, malattia a Verona, elaborazione lutto a Verona, crescita personale a Verona, autostima a Verona, comunicazione efficace a Verona, intelligenza emotiva a Verona, disturbi d\u2019ansia a Verona, attacchi di panico a Verona, disturbi psicosomatici a Verona, gestione dello stress a Verona, tecniche rilassamento a Verona, terapia di coppia a Verona, terapia familiare a Verona, psicologo a Verona, psicologi a Verona, supporto psicologico a Verona, supporto psicologico per pazienti oncologici a Verona, percorso psicologico a Verona, percorso psicologico per pazienti oncologici a Verona, sostegno psicologico a Verona, sostegno psicologico per pazienti oncologici a Verona,<\/p>\n<\/div>\n","protected":false},"featured_media":102127,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[256,163],"product_tag":[18179,2854,13709,1560,2632,13517,3030,22516,15233,3032,22522,6404,2705,22514,3920,1463,2957,3839,2746,5517,22515,22506,3034,3035,22510,6043,22511,16734,22509,22508,22517,5847,22525,22507,460,516,354,22521,1499,22526,22513,22518,22520,1123,22519,22524,22523,730,1363,2925,22512,566],"class_list":{"0":"post-102033","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-psicologi","7":"product_cat-salute","8":"product_tag-alleanza-terapeutica","9":"product_tag-analisi-transazionale","10":"product_tag-approccio-integrato","11":"product_tag-attacchi-di-panico","12":"product_tag-autostima","13":"product_tag-benessere-emotivo","14":"product_tag-comunicazione-efficace","15":"product_tag-comunita-terapeutica-verona","16":"product_tag-consapevolezza","17":"product_tag-crescita-personale","18":"product_tag-difficolta-affettive","19":"product_tag-difficolta-familiari","20":"product_tag-difficolta-relazionali","21":"product_tag-dinamiche-relazionali","22":"product_tag-disagi-esistenziali","23":"product_tag-disturbi-dansia","24":"product_tag-disturbi-dellumore","25":"product_tag-disturbi-depressivi","26":"product_tag-disturbi-psicosomatici","27":"product_tag-elaborazione-lutto","28":"product_tag-esperienza-dipendenze","29":"product_tag-francesco-sorrentino","30":"product_tag-gestione-dello-stress","31":"product_tag-intelligenza-emotiva","32":"product_tag-laurea-in-psicologia-clinica","33":"product_tag-malattia","34":"product_tag-master-in-psico-oncologia","35":"product_tag-oncoematologia-pediatrica","36":"product_tag-ordine-degli-psico-oncologi-certificati-sipo","37":"product_tag-ordine-degli-psicologi-del-veneto","38":"product_tag-ospedale-b-trento-verona","39":"product_tag-percorso-psicologico","40":"product_tag-percorso-psicologico-per-pazienti-oncologici","41":"product_tag-psico-oncologo","42":"product_tag-psicologi","43":"product_tag-psicologo","44":"product_tag-psicoterapeuta","45":"product_tag-ritrovare-serenita","46":"product_tag-sostegno-psicologico","47":"product_tag-sostegno-psicologico-per-pazienti-oncologici","48":"product_tag-specializzazione-psicoterapia","49":"product_tag-studio-psicologo-verona","50":"product_tag-superare-difficolta-personali","51":"product_tag-supporto-psicologico","52":"product_tag-supporto-psicologico-giovani-e-adulti","53":"product_tag-supporto-psicologico-per-pazienti-oncologici","54":"product_tag-tecniche-rilassamento","55":"product_tag-terapia-di-coppia","56":"product_tag-terapia-familiare","57":"product_tag-trauma","58":"product_tag-universita-cattolica-del-sacro-cuore-di-roma","59":"product_tag-verona","61":"first","62":"instock","63":"shipping-taxable","64":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia  Francesco Sorrentino, psicologo, psico-oncologo, psicoterapeuta, Ordine degli Psicologi del Veneto, Ordine degli Psico-Oncologi certificati SIPO, Laurea in Psicologia Clinica, Master in Psico-Oncologia, Universit\u00e0 Cattolica del Sacro Cuore di Roma, specializzazione psicoterapia, Analisi Transazionale, approccio integrato, dinamiche relazionali, consapevolezza, crescita personale, esperienza dipendenze, comunit\u00e0 terapeutica Verona, oncoematologia pediatrica, ospedale B. Trento Verona, studio psicologo Verona, supporto psicologico giovani e adulti, benessere emotivo, Alleanza Terapeutica, superare difficolt\u00e0 personali, ritrovare serenit\u00e0, difficolt\u00e0 affettive, difficolt\u00e0 relazionali, difficolt\u00e0 familiari, disturbi dell\u2019umore, disturbi depressivi, disagi esistenziali, trauma, malattia, elaborazione lutto, crescita personale, autostima, comunicazione efficace, intelligenza emotiva, disturbi d\u2019ansia, attacchi di panico, disturbi psicosomatici, gestione dello stress, tecniche rilassamento, terapia di coppia, terapia familiare, psicologo, psicologi, supporto psicologico, supporto psicologico per pazienti oncologici, percorso psicologico, percorso psicologico per pazienti oncologici, sostegno psicologico, sostegno psicologico per pazienti oncologici, Verona,  Francesco Sorrentino Verona, psicologo Verona, psico-oncologo Verona, psicoterapeuta Verona, Ordine degli Psicologi del Veneto Verona, Ordine degli Psico-Oncologi certificati SIPO Verona, Laurea in Psicologia Clinica Verona, Master in Psico-Oncologia Verona, Universit\u00e0 Cattolica del Sacro Cuore di Roma Verona, specializzazione psicoterapia Verona, Analisi Transazionale Verona, approccio integrato Verona, dinamiche relazionali Verona, consapevolezza Verona, crescita personale Verona, esperienza dipendenze Verona, comunit\u00e0 terapeutica Verona Verona, oncoematologia pediatrica Verona, ospedale B. Trento Verona Verona, studio psicologo Verona Verona, supporto psicologico giovani e adulti Verona, benessere emotivo Verona, Alleanza Terapeutica Verona, superare difficolt\u00e0 personali Verona, ritrovare serenit\u00e0 Verona, difficolt\u00e0 affettive Verona, difficolt\u00e0 relazionali Verona, difficolt\u00e0 familiari Verona, disturbi dell\u2019umore Verona, disturbi depressivi Verona, disagi esistenziali Verona, trauma Verona, malattia Verona, elaborazione lutto Verona, crescita personale Verona, autostima Verona, comunicazione efficace Verona, intelligenza emotiva Verona, disturbi d\u2019ansia Verona, attacchi di panico Verona, disturbi psicosomatici Verona, gestione dello stress Verona, tecniche rilassamento Verona, terapia di coppia Verona, terapia familiare Verona, psicologo Verona, psicologi Verona, supporto psicologico Verona, supporto psicologico per pazienti oncologici Verona, percorso psicologico Verona, percorso psicologico per pazienti oncologici Verona, sostegno psicologico Verona, sostegno psicologico per pazienti oncologici Verona,  Francesco Sorrentino a Verona, psicologo a Verona, psico-oncologo a Verona, psicoterapeuta a Verona, Ordine degli Psicologi del Veneto a Verona, Ordine degli Psico-Oncologi certificati SIPO a Verona, Laurea in Psicologia Clinica a Verona, Master in Psico-Oncologia a Verona, Universit\u00e0 Cattolica del Sacro Cuore di Roma a Verona, specializzazione psicoterapia a Verona, Analisi Transazionale a Verona, approccio integrato a Verona, dinamiche relazionali a Verona, consapevolezza a Verona, crescita personale a Verona, esperienza dipendenze a Verona, comunit\u00e0 terapeutica Verona a Verona, oncoematologia pediatrica a Verona, ospedale B. Trento Verona a Verona, studio psicologo Verona a Verona, supporto psicologico giovani e adulti a Verona, benessere emotivo a Verona, Alleanza Terapeutica a Verona, superare difficolt\u00e0 personali a Verona, ritrovare serenit\u00e0 a Verona, difficolt\u00e0 affettive a Verona, difficolt\u00e0 relazionali a Verona, difficolt\u00e0 familiari a Verona, disturbi dell\u2019umore a Verona, disturbi depressivi a Verona, disagi esistenziali a Verona, trauma a Verona, malattia a Verona, elaborazione lutto a Verona, crescita personale a Verona, autostima a Verona, comunicazione efficace a Verona, intelligenza emotiva a Verona, disturbi d\u2019ansia a Verona, attacchi di panico a Verona, disturbi psicosomatici a Verona, gestione dello stress a Verona, tecniche rilassamento a Verona, terapia di coppia a Verona, terapia familiare a Verona, psicologo a Verona, psicologi a Verona, supporto psicologico a Verona, supporto psicologico per pazienti oncologici a Verona, percorso psicologico a Verona, percorso psicologico per pazienti oncologici a Verona, sostegno psicologico a Verona, sostegno psicologico per pazienti oncologici a Verona,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T15:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/\",\"name\":\"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png\",\"datePublished\":\"2026-06-05T12:29:16+00:00\",\"dateModified\":\"2026-06-08T15:00:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr. Francesco Sorrentino &#8211; Psicologo, Psico-oncologo e specializzando in psicoterapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/","og_locale":"it_IT","og_type":"article","og_title":"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia - UIL Polizia","og_description":"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia  Francesco Sorrentino, psicologo, psico-oncologo, psicoterapeuta, Ordine degli Psicologi del Veneto, Ordine degli Psico-Oncologi certificati SIPO, Laurea in Psicologia Clinica, Master in Psico-Oncologia, Universit\u00e0 Cattolica del Sacro Cuore di Roma, specializzazione psicoterapia, Analisi Transazionale, approccio integrato, dinamiche relazionali, consapevolezza, crescita personale, esperienza dipendenze, comunit\u00e0 terapeutica Verona, oncoematologia pediatrica, ospedale B. Trento Verona, studio psicologo Verona, supporto psicologico giovani e adulti, benessere emotivo, Alleanza Terapeutica, superare difficolt\u00e0 personali, ritrovare serenit\u00e0, difficolt\u00e0 affettive, difficolt\u00e0 relazionali, difficolt\u00e0 familiari, disturbi dell\u2019umore, disturbi depressivi, disagi esistenziali, trauma, malattia, elaborazione lutto, crescita personale, autostima, comunicazione efficace, intelligenza emotiva, disturbi d\u2019ansia, attacchi di panico, disturbi psicosomatici, gestione dello stress, tecniche rilassamento, terapia di coppia, terapia familiare, psicologo, psicologi, supporto psicologico, supporto psicologico per pazienti oncologici, percorso psicologico, percorso psicologico per pazienti oncologici, sostegno psicologico, sostegno psicologico per pazienti oncologici, Verona,  Francesco Sorrentino Verona, psicologo Verona, psico-oncologo Verona, psicoterapeuta Verona, Ordine degli Psicologi del Veneto Verona, Ordine degli Psico-Oncologi certificati SIPO Verona, Laurea in Psicologia Clinica Verona, Master in Psico-Oncologia Verona, Universit\u00e0 Cattolica del Sacro Cuore di Roma Verona, specializzazione psicoterapia Verona, Analisi Transazionale Verona, approccio integrato Verona, dinamiche relazionali Verona, consapevolezza Verona, crescita personale Verona, esperienza dipendenze Verona, comunit\u00e0 terapeutica Verona Verona, oncoematologia pediatrica Verona, ospedale B. Trento Verona Verona, studio psicologo Verona Verona, supporto psicologico giovani e adulti Verona, benessere emotivo Verona, Alleanza Terapeutica Verona, superare difficolt\u00e0 personali Verona, ritrovare serenit\u00e0 Verona, difficolt\u00e0 affettive Verona, difficolt\u00e0 relazionali Verona, difficolt\u00e0 familiari Verona, disturbi dell\u2019umore Verona, disturbi depressivi Verona, disagi esistenziali Verona, trauma Verona, malattia Verona, elaborazione lutto Verona, crescita personale Verona, autostima Verona, comunicazione efficace Verona, intelligenza emotiva Verona, disturbi d\u2019ansia Verona, attacchi di panico Verona, disturbi psicosomatici Verona, gestione dello stress Verona, tecniche rilassamento Verona, terapia di coppia Verona, terapia familiare Verona, psicologo Verona, psicologi Verona, supporto psicologico Verona, supporto psicologico per pazienti oncologici Verona, percorso psicologico Verona, percorso psicologico per pazienti oncologici Verona, sostegno psicologico Verona, sostegno psicologico per pazienti oncologici Verona,  Francesco Sorrentino a Verona, psicologo a Verona, psico-oncologo a Verona, psicoterapeuta a Verona, Ordine degli Psicologi del Veneto a Verona, Ordine degli Psico-Oncologi certificati SIPO a Verona, Laurea in Psicologia Clinica a Verona, Master in Psico-Oncologia a Verona, Universit\u00e0 Cattolica del Sacro Cuore di Roma a Verona, specializzazione psicoterapia a Verona, Analisi Transazionale a Verona, approccio integrato a Verona, dinamiche relazionali a Verona, consapevolezza a Verona, crescita personale a Verona, esperienza dipendenze a Verona, comunit\u00e0 terapeutica Verona a Verona, oncoematologia pediatrica a Verona, ospedale B. Trento Verona a Verona, studio psicologo Verona a Verona, supporto psicologico giovani e adulti a Verona, benessere emotivo a Verona, Alleanza Terapeutica a Verona, superare difficolt\u00e0 personali a Verona, ritrovare serenit\u00e0 a Verona, difficolt\u00e0 affettive a Verona, difficolt\u00e0 relazionali a Verona, difficolt\u00e0 familiari a Verona, disturbi dell\u2019umore a Verona, disturbi depressivi a Verona, disagi esistenziali a Verona, trauma a Verona, malattia a Verona, elaborazione lutto a Verona, crescita personale a Verona, autostima a Verona, comunicazione efficace a Verona, intelligenza emotiva a Verona, disturbi d\u2019ansia a Verona, attacchi di panico a Verona, disturbi psicosomatici a Verona, gestione dello stress a Verona, tecniche rilassamento a Verona, terapia di coppia a Verona, terapia familiare a Verona, psicologo a Verona, psicologi a Verona, supporto psicologico a Verona, supporto psicologico per pazienti oncologici a Verona, percorso psicologico a Verona, percorso psicologico per pazienti oncologici a Verona, sostegno psicologico a Verona, sostegno psicologico per pazienti oncologici a Verona,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/","og_site_name":"UIL Polizia","article_modified_time":"2026-06-08T15:00:32+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/","name":"Dr. Francesco Sorrentino - Psicologo, Psico-oncologo e specializzando in psicoterapia - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png","datePublished":"2026-06-05T12:29:16+00:00","dateModified":"2026-06-08T15:00:32+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/06\/logo-siti-dr-francesco-sorrentino-.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dr-francesco-sorrentino-psicologo-psico-oncologo-e-specializzando-in-psicoterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dr. Francesco Sorrentino &#8211; Psicologo, Psico-oncologo e specializzando in psicoterapia"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/102033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=102033"}],"version-history":[{"count":29,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/102033\/revisions"}],"predecessor-version":[{"id":102134,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/102033\/revisions\/102134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/102127"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=102033"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=102033"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=102033"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=102033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}