{"id":100931,"date":"2026-05-22T12:24:58","date_gmt":"2026-05-22T10:24:58","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?post_type=product&#038;p=100931"},"modified":"2026-05-26T11:36:22","modified_gmt":"2026-05-26T09:36:22","slug":"dott-roberto-contieri-urologo-e-andrologo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/","title":{"rendered":"Dott. Roberto Contieri &#8211; Urologo e Andrologo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"100931\" class=\"elementor elementor-100931\">\n\t\t\t\t<div class=\"elementor-element elementor-element-526923ef e-flex e-con-boxed e-con e-parent\" data-id=\"526923ef\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-679d4ec7 elementor-widget elementor-widget-icon-box\" data-id=\"679d4ec7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDott. Roberto Contieri \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUrologo \u2022 Andrologo\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c62c99c e-flex e-con-boxed e-con e-parent\" data-id=\"3c62c99c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-569f3372 e-con-full e-flex e-con e-child\" data-id=\"569f3372\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d19b8ca e-con-full e-flex e-con e-child\" data-id=\"1d19b8ca\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c230d1b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1c230d1b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f9cd390 e-con-full e-flex e-con e-child\" data-id=\"2f9cd390\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dd30e70 elementor-widget elementor-widget-text-editor\" data-id=\"4dd30e70\" data-element_type=\"widget\" id=\"chisono\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>presentazione<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b483344 elementor-widget elementor-widget-text-editor\" data-id=\"3b483344\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono un urologo specializzato nella diagnosi e trattamento delle patologie urologiche, con particolare focus su chirurgia oncologica e mininvasiva.\u00a0<\/p><p>Dopo aver completato la specializzazione in Urologia presso Humanitas University di Milano, sono rientrato a Napoli per mettere a servizio dei pazienti l\u2019esperienza maturata in centri di eccellenza italiani ed esteri.\u00a0<\/p><p>Attualmente ricopro il ruolo di dirigente medico presso l\u2019IRCCS Istituto Nazionale Tumori Fondazione \u201cG. Pascale\u201d di Napoli.<\/p><p>Durante la mia formazione ho approfondito lo studio dei tumori urologici al MD Anderson Cancer Center di Houston e ho svolto una fellowship in chirurgia robotica presso il Netherlands Cancer Institute di Amsterdam, specializzandomi nei trattamenti mininvasivi di prostata, rene e vescica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-655c741 e-con-full e-flex e-con e-child\" data-id=\"655c741\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a01c779 e-con-full e-flex e-con e-child\" data-id=\"a01c779\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85cdfd6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"85cdfd6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5ed3c8 e-con-full e-flex e-con e-child\" data-id=\"a5ed3c8\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81f6dcc elementor-widget elementor-widget-text-editor\" data-id=\"81f6dcc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DI COSA MI OCCUPO:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55db311 elementor-widget elementor-widget-text-editor\" data-id=\"55db311\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tratto sia patologie oncologiche che problematiche benigne come cistiti, ipertrofia prostatica e disturbi andrologici.\u00a0<\/p><p>Sono membro di importanti gruppi scientifici nazionali e internazionali, grazie ai quali collaboro con esperti di rilievo per sviluppare cure sempre pi\u00f9 efficaci e personalizzate.<\/p><p>Oltre all\u2019attivit\u00e0 clinica, partecipo come relatore ai principali congressi scientifici internazionali.\u00a0<\/p><p>Il mio obiettivo \u00e8 costruire rapporti di fiducia con i pazienti, offrendo loro cure innovative e mirate, ascoltandone le esigenze e garantendo attenzione ai bisogni individuali.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c75c2ba e-con-full e-flex e-con e-child\" data-id=\"c75c2ba\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c503966 e-con-full e-flex e-con e-child\" data-id=\"c503966\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9822637 elementor-widget elementor-widget-text-editor\" data-id=\"9822637\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PATOLOGIE TRATTATE:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e73eee elementor-widget elementor-widget-text-editor\" data-id=\"6e73eee\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Carcinoma della prostata<br \/>\u2022 Tumore del testicolo<br \/>\u2022 Prostatite<br \/>\u2022 Ipertrofia prostatica<br \/>\u2022 Iperplasia prostatica benigna<br \/>\u2022 Tumori della vescica urinaria<br \/>\u2022 Tumore renale e dell\u2019alta via escretrice<br \/>\u2022 Resezione transuretrale della prostata (TURP)<br \/>\u2022 Dolore<br \/>\u2022 Malattia sessualmente trasmissibile<br \/>\u2022 Malattia cronica<br \/>\u2022 Infezione<br \/>\u2022 Ipogonadismo<br \/>\u2022 Disfunzione erettile<br \/>\u2022 Virus del papilloma umano<br \/>\u2022 Infezione delle vie urinarie<br \/>\u2022 Colica renale<br \/>\u2022 Ematuria<br \/>\u2022 Sterilit\u00e0<br \/>\u2022 Incontinenza urinaria<br \/>\u2022 Pielonefrite<br \/>\u2022 Ipospadia<br \/>\u2022 Fimosi<br \/>\u2022 Idrocele<br \/>\u2022 Idronefrosi<br \/>\u2022 Minzione<br \/>\u2022 Epididimite<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66207c5e e-flex e-con-boxed e-con e-parent\" data-id=\"66207c5e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7321bd3e elementor-widget elementor-widget-text-editor\" data-id=\"7321bd3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16465e54 e-flex e-con-boxed e-con e-parent\" data-id=\"16465e54\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3626167c e-con-full e-flex e-con e-child\" data-id=\"3626167c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1e00f8ee e-con-full e-flex e-con e-child\" data-id=\"1e00f8ee\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d37c7ca e-con-full e-flex e-con e-child\" data-id=\"3d37c7ca\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b7141c9 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7b7141c9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tsedi e Contatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b20bed4 elementor-widget elementor-widget-text-editor\" data-id=\"4b20bed4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Dott. Roberto Contieri<br \/><\/b>Urologo e Andrologo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21bc2546 e-con-full e-flex e-con e-child\" data-id=\"21bc2546\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3939521a e-con-full e-flex e-con e-child\" data-id=\"3939521a\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5b7e61ec e-con-full e-flex e-con e-child\" data-id=\"5b7e61ec\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2d1f0c1c e-grid e-con-full e-con e-child\" data-id=\"2d1f0c1c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34741d6e elementor-widget elementor-widget-text-editor\" data-id=\"34741d6e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Centro MTN &#8211; Medicina e Territorio Napoli<br \/><\/b>Via San Donato, 3 &#8211; 80126 Napoli<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5358f elementor-widget elementor-widget-text-editor\" data-id=\"6a5358f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Centro MTN &#8211; Medicina e Territorio Napoli<\/b><br \/>Corso Umberto I, 23 &#8211; 80133 Napoli<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64c732c3 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"64c732c3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ece194f elementor-widget elementor-widget-text-editor\" data-id=\"ece194f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-161\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-161\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:150px;\"> <span id=\"gmw-resize-map-toggle-161\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-161\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-161\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"161\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-165bdfca e-con-full e-flex e-con e-child\" data-id=\"165bdfca\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13ec87d elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"13ec87d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.miodottore.it\/roberto-contieri\/urologo\/napoli\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">prenota ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65430d3f elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65430d3f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63d78203\" data-id=\"63d78203\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76925ff0 elementor-widget elementor-widget-text-editor\" data-id=\"76925ff0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tContatti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f036aa2 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"f036aa2\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-1539373\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8913cb9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-3255c55\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7fb29d1a\" data-id=\"7fb29d1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4a001 elementor-widget elementor-widget-text-editor\" data-id=\"d4a001\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-246\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"100931\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-246\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-246\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-246\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-246\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"246\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66aca44d elementor-widget elementor-widget-text-editor\" data-id=\"66aca44d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-478\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-478\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:350px;\"> <span id=\"gmw-resize-map-toggle-478\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-478\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-478\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"478\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6da7403 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"6da7403\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3db71be1 elementor-widget elementor-widget-text-editor\" data-id=\"3db71be1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\nDott. Roberto Contieri &#8211; Urologo e Andrologo\n\npresentazione\n\nSono un urologo specializzato nella diagnosi e trattamento delle patologie urologiche, con particolare focus su chirurgia oncologica e mininvasiva. \n\nDopo aver completato la specializzazione in Urologia presso Humanitas University di Milano, sono rientrato a Napoli per mettere a servizio dei pazienti l\u2019esperienza maturata in centri di eccellenza italiani ed esteri. \n\nAttualmente ricopro il ruolo di dirigente medico presso l\u2019IRCCS Istituto Nazionale Tumori Fondazione \u201cG. Pascale\u201d di Napoli.\n\nDurante la mia formazione ho approfondito lo studio dei tumori urologici al MD Anderson Cancer Center di Houston e ho svolto una fellowship in chirurgia robotica presso il Netherlands Cancer Institute di Amsterdam, specializzandomi nei trattamenti mininvasivi di prostata, rene e vescica.\n\nDI COSA MI OCCUPO:\n\nTratto sia patologie oncologiche che problematiche benigne come cistiti, ipertrofia prostatica e disturbi andrologici. \n\nSono membro di importanti gruppi scientifici nazionali e internazionali, grazie ai quali collaboro con esperti di rilievo per sviluppare cure sempre pi\u00f9 efficaci e personalizzate.\n\nOltre all\u2019attivit\u00e0 clinica, partecipo come relatore ai principali congressi scientifici internazionali. \n\nIl mio obiettivo \u00e8 costruire rapporti di fiducia con i pazienti, offrendo loro cure innovative e mirate, ascoltandone le esigenze e garantendo attenzione ai bisogni individuali.\n\nPATOLOGIE TRATTATE:\n\n\u2022 Carcinoma della prostata\n\u2022 Tumore del testicolo\n\u2022 Prostatite\n\u2022 Ipertrofia prostatica\n\u2022 Iperplasia prostatica benigna\n\u2022 Tumori della vescica urinaria\n\u2022 Tumore renale e dell\u2019alta via escretrice\n\u2022 Resezione transuretrale della prostata (TURP)\n\u2022 Dolore\n\u2022 Malattia sessualmente trasmissibile\n\u2022 Malattia cronica\n\u2022 Infezione\n\u2022 Ipogonadismo\n\u2022 Disfunzione erettile\n\u2022 Virus del papilloma umano\n\u2022 Infezione delle vie urinarie\n\u2022 Colica renale\n\u2022 Ematuria\n\u2022 Sterilit\u00e0\n\u2022 Incontinenza urinaria\n\u2022 Pielonefrite\n\u2022 Ipospadia\n\u2022 Fimosi\n\u2022 Idrocele\n\u2022 Idronefrosi\n\u2022 Minzione\n\u2022 Epididimite\n\nurologo, diagnosi patologie urologiche, trattamento patologie urologiche, chirurgia oncologica, chirurgia mininvasiva, tumori urologici, carcinoma prostata, tumore testicolo, prostatite, ipertrofia prostatica, iperplasia prostatica benigna, tumori vescica urinaria, tumore renale, tumore alta via escretrice, TURP, malattia sessualmente trasmissibile, infezione vie urinarie, disfunzione erettile, ipogonadismo, colica renale, ematuria, sterilit\u00e0, incontinenza urinaria, pielonefrite, ipospadia, fimosi, idrocele, idronefrosi, minzione, epididimite, cistiti, disturbi andrologici, papilloma virus umano, urologo, urologi, urologia, andrologo, andrologi, andrologia, Napoli,\n\n\nurologo Napoli, diagnosi patologie urologiche Napoli, trattamento patologie urologiche Napoli, chirurgia oncologica Napoli, chirurgia mininvasiva Napoli, tumori urologici Napoli, carcinoma prostata Napoli, tumore testicolo Napoli, prostatite Napoli, ipertrofia prostatica Napoli, iperplasia prostatica benigna Napoli, tumori vescica urinaria Napoli, tumore renale Napoli, tumore alta via escretrice Napoli, TURP Napoli, malattia sessualmente trasmissibile Napoli, infezione vie urinarie Napoli, disfunzione erettile Napoli, ipogonadismo Napoli, colica renale Napoli, ematuria Napoli, sterilit\u00e0 Napoli, incontinenza urinaria Napoli, pielonefrite Napoli, ipospadia Napoli, fimosi Napoli, idrocele Napoli, idronefrosi Napoli, minzione Napoli, epididimite Napoli, cistiti Napoli, disturbi andrologici Napoli, papilloma virus umano Napoli, urologo Napoli, urologi Napoli, urologia Napoli, andrologo Napoli, andrologi Napoli, andrologia Napoli, \n\nurologo a Napoli, diagnosi patologie urologiche a Napoli, trattamento patologie urologiche a Napoli, chirurgia oncologica a Napoli, chirurgia mininvasiva a Napoli, tumori urologici a Napoli, carcinoma prostata a Napoli, tumore testicolo a Napoli, prostatite a Napoli, ipertrofia prostatica a Napoli, iperplasia prostatica benigna a Napoli, tumori vescica urinaria a Napoli, tumore renale a Napoli, tumore alta via escretrice a Napoli, TURP a Napoli, malattia sessualmente trasmissibile a Napoli, infezione vie urinarie a Napoli, disfunzione erettile a Napoli, ipogonadismo a Napoli, colica renale a Napoli, ematuria a Napoli, sterilit\u00e0 a Napoli, incontinenza urinaria a Napoli, pielonefrite a Napoli, ipospadia a Napoli, fimosi a Napoli, idrocele a Napoli, idronefrosi a Napoli, minzione a Napoli, epididimite a Napoli, cistiti a Napoli, disturbi andrologici a Napoli, papilloma virus umano a Napoli, urologo a Napoli, urologi a Napoli, urologia a Napoli, andrologo a Napoli, andrologi a Napoli, andrologia a Napoli, \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display:none\">\n<p>Dott. Roberto Contieri &#8211; Urologo e Andrologo<\/p>\n<p>presentazione<\/p>\n<p>Sono un urologo specializzato nella diagnosi e trattamento delle patologie urologiche, con particolare focus su chirurgia oncologica e mininvasiva. <\/p>\n<p>Dopo aver completato la specializzazione in Urologia presso Humanitas University di Milano, sono rientrato a Napoli per mettere a servizio dei pazienti l\u2019esperienza maturata in centri di eccellenza italiani ed esteri. <\/p>\n<p>Attualmente ricopro il ruolo di dirigente medico presso l\u2019IRCCS Istituto Nazionale Tumori Fondazione \u201cG. Pascale\u201d di Napoli.<\/p>\n<p>Durante la mia formazione ho approfondito lo studio dei tumori urologici al MD Anderson Cancer Center di Houston e ho svolto una fellowship in chirurgia robotica presso il Netherlands Cancer Institute di Amsterdam, specializzandomi nei trattamenti mininvasivi di prostata, rene e vescica.<\/p>\n<p>DI COSA MI OCCUPO:<\/p>\n<p>Tratto sia patologie oncologiche che problematiche benigne come cistiti, ipertrofia prostatica e disturbi andrologici. <\/p>\n<p>Sono membro di importanti gruppi scientifici nazionali e internazionali, grazie ai quali collaboro con esperti di rilievo per sviluppare cure sempre pi\u00f9 efficaci e personalizzate.<\/p>\n<p>Oltre all\u2019attivit\u00e0 clinica, partecipo come relatore ai principali congressi scientifici internazionali. <\/p>\n<p>Il mio obiettivo \u00e8 costruire rapporti di fiducia con i pazienti, offrendo loro cure innovative e mirate, ascoltandone le esigenze e garantendo attenzione ai bisogni individuali.<\/p>\n<p>PATOLOGIE TRATTATE:<\/p>\n<p>\u2022 Carcinoma della prostata<br \/>\n\u2022 Tumore del testicolo<br \/>\n\u2022 Prostatite<br \/>\n\u2022 Ipertrofia prostatica<br \/>\n\u2022 Iperplasia prostatica benigna<br \/>\n\u2022 Tumori della vescica urinaria<br \/>\n\u2022 Tumore renale e dell\u2019alta via escretrice<br \/>\n\u2022 Resezione transuretrale della prostata (TURP)<br \/>\n\u2022 Dolore<br \/>\n\u2022 Malattia sessualmente trasmissibile<br \/>\n\u2022 Malattia cronica<br \/>\n\u2022 Infezione<br \/>\n\u2022 Ipogonadismo<br \/>\n\u2022 Disfunzione erettile<br \/>\n\u2022 Virus del papilloma umano<br \/>\n\u2022 Infezione delle vie urinarie<br \/>\n\u2022 Colica renale<br \/>\n\u2022 Ematuria<br \/>\n\u2022 Sterilit\u00e0<br \/>\n\u2022 Incontinenza urinaria<br \/>\n\u2022 Pielonefrite<br \/>\n\u2022 Ipospadia<br \/>\n\u2022 Fimosi<br \/>\n\u2022 Idrocele<br \/>\n\u2022 Idronefrosi<br \/>\n\u2022 Minzione<br \/>\n\u2022 Epididimite<\/p>\n<p>urologo, diagnosi patologie urologiche, trattamento patologie urologiche, chirurgia oncologica, chirurgia mininvasiva, tumori urologici, carcinoma prostata, tumore testicolo, prostatite, ipertrofia prostatica, iperplasia prostatica benigna, tumori vescica urinaria, tumore renale, tumore alta via escretrice, TURP, malattia sessualmente trasmissibile, infezione vie urinarie, disfunzione erettile, ipogonadismo, colica renale, ematuria, sterilit\u00e0, incontinenza urinaria, pielonefrite, ipospadia, fimosi, idrocele, idronefrosi, minzione, epididimite, cistiti, disturbi andrologici, papilloma virus umano, urologo, urologi, urologia, andrologo, andrologi, andrologia, Napoli,<\/p>\n<p>urologo Napoli, diagnosi patologie urologiche Napoli, trattamento patologie urologiche Napoli, chirurgia oncologica Napoli, chirurgia mininvasiva Napoli, tumori urologici Napoli, carcinoma prostata Napoli, tumore testicolo Napoli, prostatite Napoli, ipertrofia prostatica Napoli, iperplasia prostatica benigna Napoli, tumori vescica urinaria Napoli, tumore renale Napoli, tumore alta via escretrice Napoli, TURP Napoli, malattia sessualmente trasmissibile Napoli, infezione vie urinarie Napoli, disfunzione erettile Napoli, ipogonadismo Napoli, colica renale Napoli, ematuria Napoli, sterilit\u00e0 Napoli, incontinenza urinaria Napoli, pielonefrite Napoli, ipospadia Napoli, fimosi Napoli, idrocele Napoli, idronefrosi Napoli, minzione Napoli, epididimite Napoli, cistiti Napoli, disturbi andrologici Napoli, papilloma virus umano Napoli, urologo Napoli, urologi Napoli, urologia Napoli, andrologo Napoli, andrologi Napoli, andrologia Napoli, <\/p>\n<p>urologo a Napoli, diagnosi patologie urologiche a Napoli, trattamento patologie urologiche a Napoli, chirurgia oncologica a Napoli, chirurgia mininvasiva a Napoli, tumori urologici a Napoli, carcinoma prostata a Napoli, tumore testicolo a Napoli, prostatite a Napoli, ipertrofia prostatica a Napoli, iperplasia prostatica benigna a Napoli, tumori vescica urinaria a Napoli, tumore renale a Napoli, tumore alta via escretrice a Napoli, TURP a Napoli, malattia sessualmente trasmissibile a Napoli, infezione vie urinarie a Napoli, disfunzione erettile a Napoli, ipogonadismo a Napoli, colica renale a Napoli, ematuria a Napoli, sterilit\u00e0 a Napoli, incontinenza urinaria a Napoli, pielonefrite a Napoli, ipospadia a Napoli, fimosi a Napoli, idrocele a Napoli, idronefrosi a Napoli, minzione a Napoli, epididimite a Napoli, cistiti a Napoli, disturbi andrologici a Napoli, papilloma virus umano a Napoli, urologo a Napoli, urologi a Napoli, urologia a Napoli, andrologo a Napoli, andrologi a Napoli, andrologia a Napoli, <\/p>\n<\/div>\n","protected":false},"featured_media":101019,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[169,163,271],"product_tag":[844,2240,770,18489,22148,3886,4808,18491,22146,18481,22160,18500,22159,18496,21286,21288,10942,18482,18492,22150,22155,22157,18604,22158,544,22161,22156,18483,18488,22147,22153,22152,18484,22149,22151,22154,839,1274,435],"class_list":{"0":"post-100931","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-andrologo","7":"product_cat-salute","8":"product_cat-urologi","9":"product_tag-andrologi","10":"product_tag-andrologia","11":"product_tag-andrologo","12":"product_tag-carcinoma-prostata","13":"product_tag-chirurgia-mininvasiva","14":"product_tag-chirurgia-oncologica","15":"product_tag-cistiti","16":"product_tag-colica-renale","17":"product_tag-diagnosi-patologie-urologiche","18":"product_tag-disfunzione-erettile","19":"product_tag-disturbi-andrologici","20":"product_tag-ematuria","21":"product_tag-epididimite","22":"product_tag-fimosi","23":"product_tag-idrocele","24":"product_tag-idronefrosi","25":"product_tag-incontinenza-urinaria","26":"product_tag-infezione-vie-urinarie","27":"product_tag-iperplasia-prostatica-benigna","28":"product_tag-ipertrofia-prostatica","29":"product_tag-ipogonadismo","30":"product_tag-ipospadia","31":"product_tag-malattia-sessualmente-trasmissibile","32":"product_tag-minzione","33":"product_tag-napoli","34":"product_tag-papilloma-virus-umano","35":"product_tag-pielonefrite","36":"product_tag-prostatite","37":"product_tag-sterilita","38":"product_tag-trattamento-patologie-urologiche","39":"product_tag-tumore-alta-via-escretrice","40":"product_tag-tumore-renale","41":"product_tag-tumore-testicolo","42":"product_tag-tumori-urologici","43":"product_tag-tumori-vescica-urinaria","44":"product_tag-turp","45":"product_tag-urologi","46":"product_tag-urologia","47":"product_tag-urologo","49":"first","50":"instock","51":"shipping-taxable","52":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dott. Roberto Contieri - Urologo e Andrologo - UIL Polizia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dott. Roberto Contieri - Urologo e Andrologo - UIL Polizia\" \/>\n<meta property=\"og:description\" content=\"Dott. Roberto Contieri - Urologo e Andrologo  presentazione  Sono un urologo specializzato nella diagnosi e trattamento delle patologie urologiche, con particolare focus su chirurgia oncologica e mininvasiva.   Dopo aver completato la specializzazione in Urologia presso Humanitas University di Milano, sono rientrato a Napoli per mettere a servizio dei pazienti l\u2019esperienza maturata in centri di eccellenza italiani ed esteri.   Attualmente ricopro il ruolo di dirigente medico presso l\u2019IRCCS Istituto Nazionale Tumori Fondazione \u201cG. Pascale\u201d di Napoli.  Durante la mia formazione ho approfondito lo studio dei tumori urologici al MD Anderson Cancer Center di Houston e ho svolto una fellowship in chirurgia robotica presso il Netherlands Cancer Institute di Amsterdam, specializzandomi nei trattamenti mininvasivi di prostata, rene e vescica.  DI COSA MI OCCUPO:  Tratto sia patologie oncologiche che problematiche benigne come cistiti, ipertrofia prostatica e disturbi andrologici.   Sono membro di importanti gruppi scientifici nazionali e internazionali, grazie ai quali collaboro con esperti di rilievo per sviluppare cure sempre pi\u00f9 efficaci e personalizzate.  Oltre all\u2019attivit\u00e0 clinica, partecipo come relatore ai principali congressi scientifici internazionali.   Il mio obiettivo \u00e8 costruire rapporti di fiducia con i pazienti, offrendo loro cure innovative e mirate, ascoltandone le esigenze e garantendo attenzione ai bisogni individuali.  PATOLOGIE TRATTATE:  \u2022 Carcinoma della prostata \u2022 Tumore del testicolo \u2022 Prostatite \u2022 Ipertrofia prostatica \u2022 Iperplasia prostatica benigna \u2022 Tumori della vescica urinaria \u2022 Tumore renale e dell\u2019alta via escretrice \u2022 Resezione transuretrale della prostata (TURP) \u2022 Dolore \u2022 Malattia sessualmente trasmissibile \u2022 Malattia cronica \u2022 Infezione \u2022 Ipogonadismo \u2022 Disfunzione erettile \u2022 Virus del papilloma umano \u2022 Infezione delle vie urinarie \u2022 Colica renale \u2022 Ematuria \u2022 Sterilit\u00e0 \u2022 Incontinenza urinaria \u2022 Pielonefrite \u2022 Ipospadia \u2022 Fimosi \u2022 Idrocele \u2022 Idronefrosi \u2022 Minzione \u2022 Epididimite  urologo, diagnosi patologie urologiche, trattamento patologie urologiche, chirurgia oncologica, chirurgia mininvasiva, tumori urologici, carcinoma prostata, tumore testicolo, prostatite, ipertrofia prostatica, iperplasia prostatica benigna, tumori vescica urinaria, tumore renale, tumore alta via escretrice, TURP, malattia sessualmente trasmissibile, infezione vie urinarie, disfunzione erettile, ipogonadismo, colica renale, ematuria, sterilit\u00e0, incontinenza urinaria, pielonefrite, ipospadia, fimosi, idrocele, idronefrosi, minzione, epididimite, cistiti, disturbi andrologici, papilloma virus umano, urologo, urologi, urologia, andrologo, andrologi, andrologia, Napoli,   urologo Napoli, diagnosi patologie urologiche Napoli, trattamento patologie urologiche Napoli, chirurgia oncologica Napoli, chirurgia mininvasiva Napoli, tumori urologici Napoli, carcinoma prostata Napoli, tumore testicolo Napoli, prostatite Napoli, ipertrofia prostatica Napoli, iperplasia prostatica benigna Napoli, tumori vescica urinaria Napoli, tumore renale Napoli, tumore alta via escretrice Napoli, TURP Napoli, malattia sessualmente trasmissibile Napoli, infezione vie urinarie Napoli, disfunzione erettile Napoli, ipogonadismo Napoli, colica renale Napoli, ematuria Napoli, sterilit\u00e0 Napoli, incontinenza urinaria Napoli, pielonefrite Napoli, ipospadia Napoli, fimosi Napoli, idrocele Napoli, idronefrosi Napoli, minzione Napoli, epididimite Napoli, cistiti Napoli, disturbi andrologici Napoli, papilloma virus umano Napoli, urologo Napoli, urologi Napoli, urologia Napoli, andrologo Napoli, andrologi Napoli, andrologia Napoli,   urologo a Napoli, diagnosi patologie urologiche a Napoli, trattamento patologie urologiche a Napoli, chirurgia oncologica a Napoli, chirurgia mininvasiva a Napoli, tumori urologici a Napoli, carcinoma prostata a Napoli, tumore testicolo a Napoli, prostatite a Napoli, ipertrofia prostatica a Napoli, iperplasia prostatica benigna a Napoli, tumori vescica urinaria a Napoli, tumore renale a Napoli, tumore alta via escretrice a Napoli, TURP a Napoli, malattia sessualmente trasmissibile a Napoli, infezione vie urinarie a Napoli, disfunzione erettile a Napoli, ipogonadismo a Napoli, colica renale a Napoli, ematuria a Napoli, sterilit\u00e0 a Napoli, incontinenza urinaria a Napoli, pielonefrite a Napoli, ipospadia a Napoli, fimosi a Napoli, idrocele a Napoli, idronefrosi a Napoli, minzione a Napoli, epididimite a Napoli, cistiti a Napoli, disturbi andrologici a Napoli, papilloma virus umano a Napoli, urologo a Napoli, urologi a Napoli, urologia a Napoli, andrologo a Napoli, andrologi a Napoli, andrologia a Napoli,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/\" \/>\n<meta property=\"og:site_name\" content=\"UIL Polizia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T09:36:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/\",\"name\":\"Dott. Roberto Contieri - Urologo e Andrologo - UIL Polizia\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png\",\"datePublished\":\"2026-05-22T10:24:58+00:00\",\"dateModified\":\"2026-05-26T09:36:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dott. Roberto Contieri &#8211; Urologo e Andrologo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/\",\"name\":\"UIL Polizia\",\"description\":\"Area convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dott. Roberto Contieri - Urologo e Andrologo - UIL Polizia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/","og_locale":"it_IT","og_type":"article","og_title":"Dott. Roberto Contieri - Urologo e Andrologo - UIL Polizia","og_description":"Dott. Roberto Contieri - Urologo e Andrologo  presentazione  Sono un urologo specializzato nella diagnosi e trattamento delle patologie urologiche, con particolare focus su chirurgia oncologica e mininvasiva.   Dopo aver completato la specializzazione in Urologia presso Humanitas University di Milano, sono rientrato a Napoli per mettere a servizio dei pazienti l\u2019esperienza maturata in centri di eccellenza italiani ed esteri.   Attualmente ricopro il ruolo di dirigente medico presso l\u2019IRCCS Istituto Nazionale Tumori Fondazione \u201cG. Pascale\u201d di Napoli.  Durante la mia formazione ho approfondito lo studio dei tumori urologici al MD Anderson Cancer Center di Houston e ho svolto una fellowship in chirurgia robotica presso il Netherlands Cancer Institute di Amsterdam, specializzandomi nei trattamenti mininvasivi di prostata, rene e vescica.  DI COSA MI OCCUPO:  Tratto sia patologie oncologiche che problematiche benigne come cistiti, ipertrofia prostatica e disturbi andrologici.   Sono membro di importanti gruppi scientifici nazionali e internazionali, grazie ai quali collaboro con esperti di rilievo per sviluppare cure sempre pi\u00f9 efficaci e personalizzate.  Oltre all\u2019attivit\u00e0 clinica, partecipo come relatore ai principali congressi scientifici internazionali.   Il mio obiettivo \u00e8 costruire rapporti di fiducia con i pazienti, offrendo loro cure innovative e mirate, ascoltandone le esigenze e garantendo attenzione ai bisogni individuali.  PATOLOGIE TRATTATE:  \u2022 Carcinoma della prostata \u2022 Tumore del testicolo \u2022 Prostatite \u2022 Ipertrofia prostatica \u2022 Iperplasia prostatica benigna \u2022 Tumori della vescica urinaria \u2022 Tumore renale e dell\u2019alta via escretrice \u2022 Resezione transuretrale della prostata (TURP) \u2022 Dolore \u2022 Malattia sessualmente trasmissibile \u2022 Malattia cronica \u2022 Infezione \u2022 Ipogonadismo \u2022 Disfunzione erettile \u2022 Virus del papilloma umano \u2022 Infezione delle vie urinarie \u2022 Colica renale \u2022 Ematuria \u2022 Sterilit\u00e0 \u2022 Incontinenza urinaria \u2022 Pielonefrite \u2022 Ipospadia \u2022 Fimosi \u2022 Idrocele \u2022 Idronefrosi \u2022 Minzione \u2022 Epididimite  urologo, diagnosi patologie urologiche, trattamento patologie urologiche, chirurgia oncologica, chirurgia mininvasiva, tumori urologici, carcinoma prostata, tumore testicolo, prostatite, ipertrofia prostatica, iperplasia prostatica benigna, tumori vescica urinaria, tumore renale, tumore alta via escretrice, TURP, malattia sessualmente trasmissibile, infezione vie urinarie, disfunzione erettile, ipogonadismo, colica renale, ematuria, sterilit\u00e0, incontinenza urinaria, pielonefrite, ipospadia, fimosi, idrocele, idronefrosi, minzione, epididimite, cistiti, disturbi andrologici, papilloma virus umano, urologo, urologi, urologia, andrologo, andrologi, andrologia, Napoli,   urologo Napoli, diagnosi patologie urologiche Napoli, trattamento patologie urologiche Napoli, chirurgia oncologica Napoli, chirurgia mininvasiva Napoli, tumori urologici Napoli, carcinoma prostata Napoli, tumore testicolo Napoli, prostatite Napoli, ipertrofia prostatica Napoli, iperplasia prostatica benigna Napoli, tumori vescica urinaria Napoli, tumore renale Napoli, tumore alta via escretrice Napoli, TURP Napoli, malattia sessualmente trasmissibile Napoli, infezione vie urinarie Napoli, disfunzione erettile Napoli, ipogonadismo Napoli, colica renale Napoli, ematuria Napoli, sterilit\u00e0 Napoli, incontinenza urinaria Napoli, pielonefrite Napoli, ipospadia Napoli, fimosi Napoli, idrocele Napoli, idronefrosi Napoli, minzione Napoli, epididimite Napoli, cistiti Napoli, disturbi andrologici Napoli, papilloma virus umano Napoli, urologo Napoli, urologi Napoli, urologia Napoli, andrologo Napoli, andrologi Napoli, andrologia Napoli,   urologo a Napoli, diagnosi patologie urologiche a Napoli, trattamento patologie urologiche a Napoli, chirurgia oncologica a Napoli, chirurgia mininvasiva a Napoli, tumori urologici a Napoli, carcinoma prostata a Napoli, tumore testicolo a Napoli, prostatite a Napoli, ipertrofia prostatica a Napoli, iperplasia prostatica benigna a Napoli, tumori vescica urinaria a Napoli, tumore renale a Napoli, tumore alta via escretrice a Napoli, TURP a Napoli, malattia sessualmente trasmissibile a Napoli, infezione vie urinarie a Napoli, disfunzione erettile a Napoli, ipogonadismo a Napoli, colica renale a Napoli, ematuria a Napoli, sterilit\u00e0 a Napoli, incontinenza urinaria a Napoli, pielonefrite a Napoli, ipospadia a Napoli, fimosi a Napoli, idrocele a Napoli, idronefrosi a Napoli, minzione a Napoli, epididimite a Napoli, cistiti a Napoli, disturbi andrologici a Napoli, papilloma virus umano a Napoli, urologo a Napoli, urologi a Napoli, urologia a Napoli, andrologo a Napoli, andrologi a Napoli, andrologia a Napoli,","og_url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/","og_site_name":"UIL Polizia","article_modified_time":"2026-05-26T09:36:22+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/","name":"Dott. Roberto Contieri - Urologo e Andrologo - UIL Polizia","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png","datePublished":"2026-05-22T10:24:58+00:00","dateModified":"2026-05-26T09:36:22+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-content\/uploads\/sites\/2\/2026\/05\/Logo-sito-dott-roberto-contieri.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/prodotto\/dott-roberto-contieri-urologo-e-andrologo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/negozio\/"},{"@type":"ListItem","position":3,"name":"Dott. Roberto Contieri &#8211; Urologo e Andrologo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/","name":"UIL Polizia","description":"Area convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/100931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/comments?post=100931"}],"version-history":[{"count":34,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/100931\/revisions"}],"predecessor-version":[{"id":101028,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product\/100931\/revisions\/101028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media\/101019"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/media?parent=100931"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_brand?post=100931"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_cat?post=100931"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/uilpolizia\/wp-json\/wp\/v2\/product_tag?post=100931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}