{"id":99,"count":0,"description":"istruzione-soggiorni-linguistici-allestero","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/","name":"Soggiorni Linguistici all'Estero","slug":"soggiorni-linguistici-allestero","taxonomy":"product_cat","parent":23,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soggiorni Linguistici all&#039;Estero Archivi - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soggiorni Linguistici all&#039;Estero Archivi - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"istruzione-soggiorni-linguistici-allestero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/\",\"name\":\"Soggiorni Linguistici all'Estero Archivi - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Istruzione\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soggiorni Linguistici all'Estero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soggiorni Linguistici all'Estero Archivi - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/","og_locale":"it_IT","og_type":"article","og_title":"Soggiorni Linguistici all'Estero Archivi - Cral Policlinico di Milano","og_description":"istruzione-soggiorni-linguistici-allestero","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/","og_site_name":"Cral Policlinico di Milano","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/","name":"Soggiorni Linguistici all'Estero Archivi - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/soggiorni-linguistici-allestero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Istruzione","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/categoria-convenzione\/istruzione\/"},{"@type":"ListItem","position":3,"name":"Soggiorni Linguistici all'Estero"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat\/23"}],"wp:post_type":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product?product_cat=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}