{"id":5583,"date":"2024-02-01T12:02:07","date_gmt":"2024-02-01T11:02:07","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=5583"},"modified":"2024-02-01T12:02:11","modified_gmt":"2024-02-01T11:02:11","slug":"luca-venturi-chinesiologo-e-massaggiatore-sportivo","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/","title":{"rendered":"Luca Venturi &#8211; Chinesiologo e Massaggiatore Sportivo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;5%|7%|5%|7%|true|true&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#8cd071&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/LOGO-LUCA-CHINESIOLOGO-e-MASSAGGIATORE-SPORTIVO-850&#215;346-1.jpeg&#8221; title_text=&#8221;LOGO-LUCA-CHINESIOLOGO-e-MASSAGGIATORE-SPORTIVO-850&#215;346&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Immagine-Luca-Venturi-Chinesiolgo-2.jpeg&#8221; background_position=&#8221;bottom_center&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_divider show_divider=&#8221;off&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;180px||180px||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;120px||120px||true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;RGBA(0,0,0,0)&#8221; custom_padding=&#8221;90px||90px|&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#66b3ff&#8221; header_2_font_size=&#8221;35px&#8221; custom_margin=&#8221;||5px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Chi sono<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#6B6B6B&#8221; header_2_font_size=&#8221;15px&#8221; header_2_line_height=&#8221;1.6em&#8221; custom_margin=&#8221;10px||20px||false|false&#8221; custom_padding=&#8221;20px|20px|12px|20px|false|true&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;rgba(51,204,51,0.34)&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>L\u2019evidenza scientifica consiglia di affidarsi ad un professionista del movimento per avere benefici nell\u2019attivit\u00e0 fisica.<br \/>Con me scoprirai come raggiungerli.<\/h2>\n<p>[\/et_pb_text][et_pb_wc_description admin_label=&#8221;descrizione convenzione&#8221; module_class=&#8221;descrizione-salute&#8221; _builder_version=&#8221;4.16&#8243; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_description][et_pb_image src=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Immagine-Luca-Venturi-Chinesiologo-7.png&#8221; title_text=&#8221;Immagine Luca Venturi Chinesiologo 7&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Immagine-Luca-Venturi-Chinesiologo-7.png&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;27px|0px|27px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; background_enable_image=&#8221;off&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][dsm_card_carousel slide_to_show=&#8221;1&#8243; equal_height=&#8221;on&#8221; arrows=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Immagine-Luca-Venturi-Chinesiologo-6-scaled-1.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/dsm_card_carousel_child][dsm_card_carousel_child image=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Immagine-Luca-Venturi-Chinesiologo-5-scaled-1.jpg&#8221; image_as_background=&#8221;off&#8221; button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/dsm_card_carousel_child][\/dsm_card_carousel][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Chi siamo&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#66b3ff&#8221; header_2_font_size=&#8221;35px&#8221; custom_margin=&#8221;||5px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Inoltre..<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|300|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.6em&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Il mio indirizzo di lavoro \u00e8 basato specificamente nell\u2019ambito della progettazione di protocolli di esercizio fisico adattato, per il miglioramento sia di problematiche osteo-articolari e muscolari (ad es.: attivit\u00e0 motoria per rachialgie, recupero post-riabilitativo protesizzati ecc.), sia di patologie croniche (ad es. cardiopatie, sindrome metabolica, diabete, tiroidismo ecc.).<br \/>Questo ambito ancora di pi\u00f9 mi ha fatto stringere rapporti di fiducia con esperti del settore medico e fisioterapico.<\/p>\n<p>Sono appassionato di ciclismo, escursionismo, corsa, meteorologia (avendo anche una qualifica come osservatore nivologico) e ricerca scientifica.<\/p>\n<p>Da tre anni riporto e scrivo nel mio sito internet articoli sugli ambiti dell&#8217;attivit\u00e0 e dell&#8217;esercizio fisico e collaboro con due piattaforme d&#8217;esercizio importanti, quali Universal Kinesiology e Performance Lab.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.lucaventurichinesiologo.it\/articolitematici\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;VISUALIZZA GLI ARTICOLI&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#66b3ff&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Poppins||||||||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;4px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0.7) 0%|rgba(255,255,255,0.7) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(255,255,255,0.7)&#8221; background_color_gradient_end=&#8221;rgba(255,255,255,0.7)&#8221; background_image=&#8221;https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/AdobeStock_370736357-1-scaled-1.jpeg&#8221; custom_padding=&#8221;55px||35px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Sconto&#8221; _builder_version=&#8221;4.21.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Poppins|300|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#0C71C3&#8243; header_2_font_size=&#8221;55px&#8221; header_2_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;27px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Agevolazioni riservate agli associati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Titolo Contatti&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#66b3ff&#8221; header_2_font_size=&#8221;32px&#8221; custom_margin=&#8221;23px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;20%&#8221; animation_starting_opacity=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Contatti<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;dati aziendali&#8221; module_class=&#8221;contatti-salute&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-60px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<div style=\"foont-family: Poppins, sans-serif; font-size: 15px; font-weight: 400; line-height: 25px\"><!-- [et_pb_line_break_holder] -->  <br \/><p><strong>Indirizzo:<\/strong> Localita\\' Rampeniga, 39n, 25085 Gavardo, BS, Italia <br>\n<strong>Telefono:<\/strong> +39 349 490 0681 <br><strong>Sito web:<\/strong> <a href=\"http:\/\/www.lucaventurichinesiologo.it\">www.lucaventurichinesiologo.it<\/a> <br> \n<strong>Mail:<\/strong> <a href=\"mailto:\"><\/a> \n<\/p><br \/><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_social_media_follow use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;15px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-20px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; border_radii=&#8221;on|25px|25px|25px|25px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/lucaventurichinesiologo\/&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#66b3ff&#8221; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/luca.venturi.chinesiologo\/?hl=it&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#66b3ff&#8221; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_code admin_label=&#8221;mappa singola&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div id=\"gmw-single-location-wrapper-109\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"5583\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-109\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-109\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-109\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-109\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"109\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"font-family: Poppins, sans-serif; font-weight: 300; text-align: justify; line-height: 25px; font-size: 15px\">\n<p>Sono Luca Venturi, Chinesiologo Professionista, Massaggiatore Sportivo, Maestro e Allenatore di Sci Alpino.<\/p>\n<p>Dopo l\u2019esperienza di sciatore ad ottimo livello, ho deciso d\u2019intraprendere la strada dell\u2019insegnamento di questo sport, diventando maestro di sci alpino e successivamente allenatore di III livello.<\/p>\n<p>Prediligo l\u2019attivit\u00e0 all\u2019aria aperta, principalmente svolgo l\u2019attivit\u00e0 di chinesiologo a domicilio e da tre anni anche di massaggiatore sportivo.<br \/>\nIn molti anni ho seguito soggetti di diverse et\u00e0, dai bambini agli adulti, dai bisogni diversi e variegati, dalla donna che vuole tonificarsi, al soggetto che deve recuperare dopo un infortunio, all\u2019atleta del settore sportivo.<\/p>\n<\/div>\n","protected":false},"featured_media":5584,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[189,1846,26],"product_tag":[],"class_list":{"0":"post-5583","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chinesiologi","7":"product_cat-massaggiatore-sportivo","8":"product_cat-salute","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luca Venturi - Chinesiologo e Massaggiatore Sportivo - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luca Venturi - Chinesiologo e Massaggiatore Sportivo - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Sono Luca Venturi, Chinesiologo Professionista, Massaggiatore Sportivo, Maestro e Allenatore di Sci Alpino.  Dopo l\u2019esperienza di sciatore ad ottimo livello, ho deciso d\u2019intraprendere la strada dell\u2019insegnamento di questo sport, diventando maestro di sci alpino e successivamente allenatore di III livello.  Prediligo l\u2019attivit\u00e0 all\u2019aria aperta, principalmente svolgo l\u2019attivit\u00e0 di chinesiologo a domicilio e da tre anni anche di massaggiatore sportivo. In molti anni ho seguito soggetti di diverse et\u00e0, dai bambini agli adulti, dai bisogni diversi e variegati, dalla donna che vuole tonificarsi, al soggetto che deve recuperare dopo un infortunio, all\u2019atleta del settore sportivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-01T11:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/\",\"name\":\"Luca Venturi - Chinesiologo e Massaggiatore Sportivo - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg\",\"datePublished\":\"2024-02-01T11:02:07+00:00\",\"dateModified\":\"2024-02-01T11:02:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luca Venturi &#8211; Chinesiologo e Massaggiatore Sportivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luca Venturi - Chinesiologo e Massaggiatore Sportivo - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/","og_locale":"it_IT","og_type":"article","og_title":"Luca Venturi - Chinesiologo e Massaggiatore Sportivo - Cral Policlinico di Milano","og_description":"Sono Luca Venturi, Chinesiologo Professionista, Massaggiatore Sportivo, Maestro e Allenatore di Sci Alpino.  Dopo l\u2019esperienza di sciatore ad ottimo livello, ho deciso d\u2019intraprendere la strada dell\u2019insegnamento di questo sport, diventando maestro di sci alpino e successivamente allenatore di III livello.  Prediligo l\u2019attivit\u00e0 all\u2019aria aperta, principalmente svolgo l\u2019attivit\u00e0 di chinesiologo a domicilio e da tre anni anche di massaggiatore sportivo. In molti anni ho seguito soggetti di diverse et\u00e0, dai bambini agli adulti, dai bisogni diversi e variegati, dalla donna che vuole tonificarsi, al soggetto che deve recuperare dopo un infortunio, all\u2019atleta del settore sportivo.","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2024-02-01T11:02:11+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/","name":"Luca Venturi - Chinesiologo e Massaggiatore Sportivo - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg","datePublished":"2024-02-01T11:02:07+00:00","dateModified":"2024-02-01T11:02:11+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2024\/02\/Base-Logo-Luca-Venturi.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/luca-venturi-chinesiologo-e-massaggiatore-sportivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Luca Venturi &#8211; Chinesiologo e Massaggiatore Sportivo"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/5583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=5583"}],"version-history":[{"count":0,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/5583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/5584"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=5583"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=5583"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=5583"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=5583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}