{"id":37355,"date":"2026-06-22T15:36:00","date_gmt":"2026-06-22T13:36:00","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=37355"},"modified":"2026-06-29T10:46:52","modified_gmt":"2026-06-29T08:46:52","slug":"mamme-con-tatto","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/","title":{"rendered":"Mamme Con-Tatto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"37355\" class=\"elementor elementor-37355\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ddd22 e-flex e-con-boxed e-con e-parent\" data-id=\"f5ddd22\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-090412b e-con-full e-flex e-con e-child\" data-id=\"090412b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9b24c elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"7a9b24c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1025\" height=\"1536\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/Lodo-e-Carolina-73-1025x1536-1.jpg\" class=\"attachment-full size-full wp-image-37361\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/Lodo-e-Carolina-73-1025x1536-1.jpg 1025w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/Lodo-e-Carolina-73-1025x1536-1-980x1469.jpg 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/Lodo-e-Carolina-73-1025x1536-1-480x719.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1025px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a0e9b8 e-con-full e-flex e-con e-child\" data-id=\"9a0e9b8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16f2586 elementor-widget elementor-widget-text-editor\" data-id=\"16f2586\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mamme Con-Tatto\u00ae<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2df0e01 elementor-widget elementor-widget-text-editor\" data-id=\"2df0e01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ci prendiamo cura e <strong>accompagniamo la famiglia dal pre concepimento<\/strong>, nel periodo della <strong>gravidanza<\/strong>, del post parto e durante tutto il periodo dell\u2019<strong>infanzia del bambino<\/strong>.<\/p><p><strong>Siamo il villaggio<\/strong> che abbraccia e sta vicino alla <strong>famiglia<\/strong> che inizia il suo cammino genitoriale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76893ba e-flex e-con-boxed e-con e-parent\" data-id=\"76893ba\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56d7df8 e-con-full e-flex e-con e-child\" data-id=\"56d7df8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85b5edc elementor-widget elementor-widget-text-editor\" data-id=\"85b5edc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPer ogni famiglia che vuole sentirsi accolta\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af242cf elementor-widget elementor-widget-text-editor\" data-id=\"af242cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ti stiamo accanto in ogni fase del viaggio: dal desiderio di una gravidanza fino ai primi anni di vita del tuo bambino.<br \/>Ti accompagniamo con ascolto, competenza e calore, perch\u00e9 ogni famiglia merita di sentirsi sostenuta, non giudicata.<\/p><p>Crediamo che crescere un bambino sia un\u2019esperienza che coinvolge l\u2019intera famiglia corpo, mente ed emozioni.<br \/>Per questo uniamo strumenti pratici, sostegno empatico e approccio scientifico per aiutarti a vivere la maternit\u00e0 e la genitorialit\u00e0 con maggiore serenit\u00e0 e consapevolezza.<\/p><p>Ogni famiglia \u00e8 unica, e noi siamo qui per accompagnarti passo dopo passo, con empatia, professionalit\u00e0 e tanto cuore.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06ceaf5 elementor-widget elementor-widget-button\" data-id=\"06ceaf5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mammecon-tatto.com\/chi-siamo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri il team<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab50eaf e-con-full e-flex e-con e-child\" data-id=\"ab50eaf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e88a107 elementor-widget elementor-widget-spacer\" data-id=\"e88a107\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b94ec8 e-con-full e-flex e-con e-child\" data-id=\"2b94ec8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54b39af elementor-widget elementor-widget-spacer\" data-id=\"54b39af\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d6fc9c e-con-full e-flex e-con e-child\" data-id=\"7d6fc9c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa4d05 elementor-widget elementor-widget-text-editor\" data-id=\"1aa4d05\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri servizi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fe9cff elementor-widget elementor-widget-text-editor\" data-id=\"9fe9cff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Consulenza Sonno personalizzata 0\/3 anni<br \/>\u2022 Consulenza Passaggio all\u2019alimentazione complementare a richiesta<br \/>\u2022 Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia<br \/>\u2022 Consulenza Allattamento<br \/>\u2022 Consulenza Babywearing: dal pancione alle braccia<br \/>\u2022 Massaggio Sobada<br \/>\u2022 Consulenza Abbandono consapevole del ciuccio<br \/>\u2022 Consulenza Abbandono consapevole del pannolino<br \/>\u2022 Eccomi: Percorso di accompagnamento alla nascita e al post-nascita<br \/>\u2022 Percorso Fertilit\u00e0 in ascolto<br \/>\u2022 Allattamento e lavoro: si pu\u00f2!<br \/>\u2022 Ginnastica in gravidanza e post parto<br \/>\u2022 Consulenze e Trattamenti Osteopatici per mamma e bambino<br \/>\u2022 Consulenza Pedagogica<br \/>\u2022 Incontri con Ostetrica<br \/>\u2022 Valutazioni ed Incontri con nutrizionista<br \/>\u2022 Consulenza Alta Sensibilit\u00e0<br \/>\u2022 Consulenza Neurodivergenze<br \/>\u2022 Yoga in Gravidanza<br \/>\u2022 Educazione e Consulenza sessuale personale e di coppia<br \/>\u2022 Consulenza naturopatica per mamma e bambino<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc14b71 elementor-widget elementor-widget-button\" data-id=\"fc14b71\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mammecon-tatto.com\/servizi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a12dab e-con-full e-flex e-con e-child\" data-id=\"4a12dab\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bac9b3 elementor-widget elementor-widget-text-editor\" data-id=\"0bac9b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Nostra Accademia<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40af5f0 elementor-widget elementor-widget-text-editor\" data-id=\"40af5f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019Academy Mamme Con-Tatto nasce per formare professionisti capaci di accompagnare le famiglie con competenza, ascolto e umanit\u00e0 dal pre-concepimento ai primi anni di vita del bambino.<\/p><p>Crediamo in una formazione che unisca teoria e pratica, scienza e cuore, perch\u00e9 sostenere una famiglia significa molto pi\u00f9 che fornire informazioni: significa esserci, davvero.<\/p><p><strong>\u2022 approfondire le competenze nell\u2019ambito della maternit\u00e0 e della prima infanzia.<\/strong><br \/><strong>\u2022 apprendere strumenti pratici di comunicazione empatica e sostegno genitoriale.<\/strong><\/p><p>Ogni percorso \u00e8 costruito per far crescere prima la persona, poi il professionista.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5bba5a elementor-widget elementor-widget-button\" data-id=\"f5bba5a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mammecon-tatto.com\/academy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri i nostri corsi<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a16c58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a16c58\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c33c20d\" data-id=\"c33c20d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51094dc elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"51094dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a2b1056 e-flex e-con-boxed e-con e-parent\" data-id=\"a2b1056\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b8f38ce e-con-full e-flex e-con e-child\" data-id=\"b8f38ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abe64ee elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"abe64ee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"175\" height=\"114\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/mamme-contatto.jpg\" class=\"attachment-full size-full wp-image-37371\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d0dedb elementor-widget elementor-widget-text-editor\" data-id=\"0d0dedb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contattaci<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1fdd0a elementor-widget elementor-widget-text-editor\" data-id=\"b1fdd0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0Maison Mamme Con-Tatto\u00ae<br \/>Via Adelasio, 4 &#8211; 24020 Scanzorosciate (BG)<\/p><p><strong>Presidente:<\/strong> <a href=\"tel:+393406130587\">340 6130587<\/a><br \/><strong>Vicepresidente:<\/strong> <a href=\"tel:+393474113178\">347 4113178<\/a><br \/><strong>Maison:<\/strong>\u00a0 <a href=\"tel:+3903519774939\">035 19774939<\/a><\/p><p><strong>Mail:<\/strong> <a href=\"mailto:mammecontatto2021@gmail.com\">mammecontatto2021@gmail.com<\/a> <br \/><strong>Mail academy:<\/strong> <a href=\"mailto:academymammecontatto@gmail.com\">academymammecontatto@gmail.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e18175a elementor-widget elementor-widget-text-editor\" data-id=\"e18175a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/mammecon-tatto.com\/\">www.mammecon-tatto.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aac8a0 elementor-widget elementor-widget-text-editor\" data-id=\"4aac8a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-object-locations-wrapper-519\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post gmw-sl-multiple-locations\" object_type=\"post\" object_id=\"\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper\"><div id=\"gmw-map-wrapper-519\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-519\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-519\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-519\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"519\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-568264e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"568264e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-216959f elementor-widget elementor-widget-text-editor\" data-id=\"216959f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&lt;div style= &#8220;display: none&#8221;&gt;<\/p><p>Mamme Con-Tatto\u00ae<br \/>Ci prendiamo cura e accompagniamo la famiglia dal pre concepimento, nel periodo della gravidanza, del post parto e durante tutto il periodo dell\u2019infanzia del bambino.<br \/>Siamo il villaggio che abbraccia e sta vicino alla famiglia che inizia il suo cammino genitoriale.<br \/>Consulenza a Domicilio<br \/>Consulenza Online<br \/>Consulenza presso il nostro centro Maison Mamme Con-Tatto\u00ae<br \/>Accademia per professionisti<br \/>image<br \/>PER LE FAMIGLIE<br \/>Per ogni famiglia che vuole sentirsi accolta<br \/>Ti stiamo accanto in ogni fase del viaggio: dal desiderio di una gravidanza fino ai primi anni di vita del tuo bambino.<br \/>Ti accompagniamo con ascolto, competenza e calore, perch\u00e9 ogni famiglia merita di sentirsi sostenuta, non giudicata.<br \/>Crediamo che crescere un bambino sia un\u2019esperienza che coinvolge l\u2019intera famiglia corpo, mente ed emozioni.<br \/>Per questo uniamo strumenti pratici, sostegno empatico e approccio scientifico per aiutarti a vivere la maternit\u00e0 e la genitorialit\u00e0 con maggiore serenit\u00e0 e consapevolezza.<br \/>Ogni famiglia \u00e8 unica, e noi siamo qui per accompagnarti passo dopo passo, con empatia, professionalit\u00e0 e tanto cuore.<br \/>Mamme Con-Tatto<br \/>PER I PROFESSIONISTI<br \/>La Nostra Accademia<br \/>L\u2019Academy Mamme Con-Tatto nasce per formare professionisti capaci di accompagnare le famiglie con competenza, ascolto e umanit\u00e0 dal pre-concepimento ai primi anni di vita del bambino.<br \/>Crediamo in una formazione che unisca teoria e pratica, scienza e cuore, perch\u00e9 sostenere una famiglia significa molto pi\u00f9 che fornire informazioni: significa esserci, davvero.<br \/>approfondire le competenze nell\u2019ambito della maternit\u00e0 e della prima infanzia<br \/>apprendere strumenti pratici di comunicazione empatica e sostegno genitoriale<br \/>Ogni percorso \u00e8 costruito per far crescere prima la persona, poi il professionista.<br \/>PER I GENITORI<br \/>I Nostri Servizi per i Genitori<br \/>Consulto Iniziale<br \/>Offriamo il primo consulto telefonico gratuito per conoscerci ed insieme, capire i tuoi bisogni per poterti offrire la consulenza pi\u00f9 adatta a te.<br \/>Consulenza a Domicilio<br \/>Su richiesta, siamo disponibili a raggiungerti presso il tuo domicilio per una consulenza ancora pi\u00f9 accurata.<br \/>Consulenza Online<br \/>Offriamo consulenze su tutto il territorio Italiano, online, comodamente dal tuo PC o dal tuo Smartphone, su appuntamento.Presso il nostro centro<br \/>Offriamo accompagnamento alla genitorialit\u00e0 consapevole dal pre concepimento fino all\u2019et\u00e0 scolare del\/la bambino\/a attraverso corsi.<br \/>Inizia con noi il viaggio verso il tuo cambiamento: vi accompagneremo mano nella mano.<br \/>PER I GENITORI<br \/>Consulenza Sonno personalizzata 0\/3 anni<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Sonno personalizzata 0\/3 anni<br \/>Consulenza Passaggio all\u2019alimentazione complementare a richiesta<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Passaggio all\u2019alimentazione complementare a richiesta<br \/>Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia<br \/>Consulenze e attivit\u00e0<br \/>Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia<br \/>Consulenza Allattamento<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Allattamento<br \/>Consulenza Babywearing: dal pancione alle braccia<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Babywearing: dal pancione alle braccia<br \/>Massaggio Sobada<br \/>Consulenze e attivit\u00e0<br \/>Massaggio Sobada<br \/>Consulenza Abbandono consapevole del ciuccio<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Abbandono consapevole del ciuccio<br \/>Consulenza Abbandono consapevole del pannolino<br \/>Eccomi: Percorso di accompagnamento alla nascita e al post-nascita<br \/>Percorso Fertilit\u00e0 in ascolto<br \/>Concepimento<br \/>Percorso Fertilit\u00e0 in ascolto<br \/>Allattamento e lavoro: si pu\u00f2!<br \/>Corsi<br \/>Allattamento e lavoro: si pu\u00f2!<br \/>Consulenze e attivit\u00e0<br \/>Ginnastica in gravidanza e post parto<br \/>Consulenze e Trattamenti Osteopatici per mamma e bambino<br \/>Consulenze e attivit\u00e0<br \/>Consulenze e Trattamenti Osteopatici per mamma e bambino<br \/>Consulenza Pedagogica<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Pedagogica<br \/>Incontri con Ostetrica<br \/>Consulenze e attivit\u00e0<br \/>Incontri con Ostetrica<br \/>Valutazioni ed Incontri con nutrizionista<br \/>Consulenze e attivit\u00e0<br \/>Valutazioni ed Incontri con nutrizionista<br \/>Consulenza Alta Sensibilit\u00e0<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Alta Sensibilit\u00e0<br \/>Consulenza Neurodivergenze<br \/>Consulenze e attivit\u00e0<br \/>Consulenza Neurodivergenze<br \/>Yoga in Gravidanza<br \/>Consulenze e attivit\u00e0<br \/>Yoga in Gravidanza<br \/>Educazione e Consulenza sessuale personale e di coppia<br \/>Consulenze e attivit\u00e0<br \/>Educazione e Consulenza sessuale personale e di coppia<br \/>Consulenza naturopatica per mamma e bambino<br \/>Consulenze e attivit\u00e0<br \/>Consulenza naturopatica per mamma e bambino<br \/>Scarica l\u2019ebook gratuito e inizia a prenderti cura di te e del tuo bambino.<br \/>Scopri un modo pi\u00f9 dolce e consapevole di vivere la maternit\u00e0.<br \/>Abbiamo creato per te un ebook gratuito ricco di strumenti pratici, riflessioni profonde e consigli utili per affrontare il tuo percorso da mamma con pi\u00f9 serenit\u00e0 e fiducia.<br \/>COMPILA IL FORM QUI SOTTO E INIZIA DA SUBITO A PRENDERTI CURA DI TE.<br \/>ACCADEMIA PER PROFESSIONISTI<br \/>La nostra Accademia per professionisti<br \/>Academy professionalizzante, secondo la Mission e l\u2019ideologia di Mamme Con-Tatto\u00ae.<br \/>Se sei un professionista che opera nel settore materno-infantile puoi arricchire il tuo curriculum e la tua esperienza lavorativa attraverso i nostri master altamente qualificati:<br \/>Master Consulenti del Sonno Infantile ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo<br \/>Master Educatrice ed Operatrice Perinatale promotrice dell\u2019Allattamento con attestazione riconosciuta a livello Europeo<br \/>Scuola di Alimentazione Complementare a Richiesta Ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo<br \/>Madrina del latte con attestazione riconosciuta a livello Europeo<br \/>Corso Educatrice di nido esperta in Babywearing con attestazione riconosciuta a livello Europeo<br \/>Scuola di Babywearing con attestazione riconosciuta a livello Europeo<br \/>Consulente del Tocco di Mamme di Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo<br \/>Pedagogia dell\u2019abbandono consapevole del ciuccio con attestazione riconosciuta a livello Europeo<br \/>Pedagogia dell\u2019abbandono consapevole del Pannolino con attestazione riconosciuta a livello Europeo<br \/>Master Tata con attestazione riconosciuta a livello Europeoconsulenza maternit\u00e0, gravidanza, post parto, infanzia, genitorialit\u00e0, pre concepimento, sostegno famiglie, consulenza a domicilio, consulenza online, centro per famiglie, accademia professionisti, formazione perinatale, consulenza sonno bambini, alimentazione complementare, svezzamento, bagno neonati, allattamento, babywearing, massaggio neonatale, ciuccio, pannolino, accompagnamento nascita, fertilit\u00e0, lavoro e allattamento, ginnastica gravidanza, osteopatia mamma bambino, consulenza pedagogica, ostetrica, nutrizionista, neurodivergenze, yoga gravidanza, educazione sessuale, naturopatia mamma bambino, corsi genitori, supporto genitoriale, crescita bambino, consulenze per famiglie, supporto neomamma, aiuto allattamento, difficolt\u00e0 allattamento, consulenza sonno neonato, neonato che non dorme, gestione pianto neonato, consigli neonati primi mesi, supporto post parto, depressione post parto aiuto, stanchezza neomamma, alimentazione neonato, portare in fascia neonato, genitorialit\u00e0 consapevole, ansia da neomamma, gravidanza e preparazione parto, dolore allattamento, mastite, crescita bambino primi anni, consulenza ostetrica online, aiuto per dormire neonato, routine neonato, pianto inconsolabile neonato, supporto famiglia neonatoconsulenza maternit\u00e0 a Scanzorosciate, gravidanza a Scanzorosciate, post parto a Scanzorosciate, infanzia a Scanzorosciate, genitorialit\u00e0 a Scanzorosciate, pre concepimento a Scanzorosciate, sostegno famiglie a Scanzorosciate, consulenza a domicilio a Scanzorosciate, consulenza online a Scanzorosciate, centro per famiglie a Scanzorosciate, accademia professionisti a Scanzorosciate, formazione perinatale a Scanzorosciate, consulenza sonno bambini a Scanzorosciate, alimentazione complementare a Scanzorosciate, svezzamento a Scanzorosciate, bagno neonati a Scanzorosciate, allattamento a Scanzorosciate, babywearing a Scanzorosciate, massaggio neonatale a Scanzorosciate, ciuccio a Scanzorosciate, pannolino a Scanzorosciate, accompagnamento nascita a Scanzorosciate, fertilit\u00e0 a Scanzorosciate, lavoro e allattamento a Scanzorosciate, ginnastica gravidanza a Scanzorosciate, osteopatia mamma bambino a Scanzorosciate, consulenza pedagogica a Scanzorosciate, ostetrica a Scanzorosciate, nutrizionista a Scanzorosciate, neurodivergenze a Scanzorosciate, yoga gravidanza a Scanzorosciate, educazione sessuale a Scanzorosciate, naturopatia mamma bambino a Scanzorosciate, corsi genitori a Scanzorosciate, supporto genitoriale a Scanzorosciate, crescita bambino a Scanzorosciate, consulenze per famiglie a Scanzorosciate, supporto neomamma a Scanzorosciate, aiuto allattamento a Scanzorosciate, difficolt\u00e0 allattamento a Scanzorosciate, consulenza sonno neonato a Scanzorosciate, neonato che non dorme a Scanzorosciate, gestione pianto neonato a Scanzorosciate, consigli neonati primi mesi a Scanzorosciate, supporto post parto a Scanzorosciate, depressione post parto aiuto a Scanzorosciate, stanchezza neomamma a Scanzorosciate, alimentazione neonato a Scanzorosciate, portare in fascia neonato a Scanzorosciate, genitorialit\u00e0 consapevole a Scanzorosciate, ansia da neomamma a Scanzorosciate, gravidanza e preparazione parto a Scanzorosciate, dolore allattamento a Scanzorosciate, mastite a Scanzorosciate, crescita bambino primi anni a Scanzorosciate, consulenza ostetrica online a Scanzorosciate, aiuto per dormire neonato a Scanzorosciate, routine neonato a Scanzorosciate, pianto inconsolabile neonato a Scanzorosciate, supporto famiglia neonato a Scanzorosciateconsulenza maternit\u00e0 a Bergamo, gravidanza a Bergamo, post parto a Bergamo, infanzia a Bergamo, genitorialit\u00e0 a Bergamo, pre concepimento a Bergamo, sostegno famiglie a Bergamo, consulenza a domicilio a Bergamo, consulenza online a Bergamo, centro per famiglie a Bergamo, accademia professionisti a Bergamo, formazione perinatale a Bergamo, consulenza sonno bambini a Bergamo, alimentazione complementare a Bergamo, svezzamento a Bergamo, bagno neonati a Bergamo, allattamento a Bergamo, babywearing a Bergamo, massaggio neonatale a Bergamo, ciuccio a Bergamo, pannolino a Bergamo, accompagnamento nascita a Bergamo, fertilit\u00e0 a Bergamo, lavoro e allattamento a Bergamo, ginnastica gravidanza a Bergamo, osteopatia mamma bambino a Bergamo, consulenza pedagogica a Bergamo, ostetrica a Bergamo, nutrizionista a Bergamo, neurodivergenze a Bergamo, yoga gravidanza a Bergamo, educazione sessuale a Bergamo, naturopatia mamma bambino a Bergamo, corsi genitori a Bergamo, supporto genitoriale a Bergamo, crescita bambino a Bergamo, consulenze per famiglie a Bergamo, supporto neomamma a Bergamo, aiuto allattamento a Bergamo, difficolt\u00e0 allattamento a Bergamo, consulenza sonno neonato a Bergamo, neonato che non dorme a Bergamo, gestione pianto neonato a Bergamo, consigli neonati primi mesi a Bergamo, supporto post parto a Bergamo, depressione post parto aiuto a Bergamo, stanchezza neomamma a Bergamo, alimentazione neonato a Bergamo, portare in fascia neonato a Bergamo, genitorialit\u00e0 consapevole a Bergamo, ansia da neomamma a Bergamo, gravidanza e preparazione parto a Bergamo, dolore allattamento a Bergamo, mastite a Bergamo, crescita bambino primi anni a Bergamo, consulenza ostetrica online a Bergamo, aiuto per dormire neonato a Bergamo, routine neonato a Bergamo, pianto inconsolabile neonato a Bergamo, supporto famiglia neonato a Bergamo&lt;\/div&gt;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>Mamme Con-Tatto\u00ae<br \/>\nCi prendiamo cura e accompagniamo la famiglia dal pre concepimento, nel periodo della gravidanza, del post parto e durante tutto il periodo dell\u2019infanzia del bambino.<br \/>\nSiamo il villaggio che abbraccia e sta vicino alla famiglia che inizia il suo cammino genitoriale.<br \/>\nConsulenza a Domicilio<br \/>\nConsulenza Online<br \/>\nConsulenza presso il nostro centro Maison Mamme Con-Tatto\u00ae<br \/>\nAccademia per professionisti<br \/>\nimage<br \/>\nPER LE FAMIGLIE<br \/>\nPer ogni famiglia che vuole sentirsi accolta<br \/>\nTi stiamo accanto in ogni fase del viaggio: dal desiderio di una gravidanza fino ai primi anni di vita del tuo bambino.<br \/>\nTi accompagniamo con ascolto, competenza e calore, perch\u00e9 ogni famiglia merita di sentirsi sostenuta, non giudicata.<br \/>\nCrediamo che crescere un bambino sia un\u2019esperienza che coinvolge l\u2019intera famiglia corpo, mente ed emozioni.<br \/>\nPer questo uniamo strumenti pratici, sostegno empatico e approccio scientifico per aiutarti a vivere la maternit\u00e0 e la genitorialit\u00e0 con maggiore serenit\u00e0 e consapevolezza.<br \/>\nOgni famiglia \u00e8 unica, e noi siamo qui per accompagnarti passo dopo passo, con empatia, professionalit\u00e0 e tanto cuore.<br \/>\nMamme Con-Tatto<br \/>\nPER I PROFESSIONISTI<br \/>\nLa Nostra Accademia<br \/>\nL\u2019Academy Mamme Con-Tatto nasce per formare professionisti capaci di accompagnare le famiglie con competenza, ascolto e umanit\u00e0 dal pre-concepimento ai primi anni di vita del bambino.<br \/>\nCrediamo in una formazione che unisca teoria e pratica, scienza e cuore, perch\u00e9 sostenere una famiglia significa molto pi\u00f9 che fornire informazioni: significa esserci, davvero.<br \/>\napprofondire le competenze nell\u2019ambito della maternit\u00e0 e della prima infanzia<br \/>\napprendere strumenti pratici di comunicazione empatica e sostegno genitoriale<br \/>\nOgni percorso \u00e8 costruito per far crescere prima la persona, poi il professionista.<br \/>\nPER I GENITORI<br \/>\nI Nostri Servizi per i Genitori<br \/>\nConsulto Iniziale<br \/>\nOffriamo il primo consulto telefonico gratuito per conoscerci ed insieme, capire i tuoi bisogni per poterti offrire la consulenza pi\u00f9 adatta a te.<br \/>\nConsulenza a Domicilio<br \/>\nSu richiesta, siamo disponibili a raggiungerti presso il tuo domicilio per una consulenza ancora pi\u00f9 accurata.<br \/>\nConsulenza Online<br \/>\nOffriamo consulenze su tutto il territorio Italiano, online, comodamente dal tuo PC o dal tuo Smartphone, su appuntamento.Presso il nostro centro<br \/>\nOffriamo accompagnamento alla genitorialit\u00e0 consapevole dal pre concepimento fino all\u2019et\u00e0 scolare del\/la bambino\/a attraverso corsi.<br \/>\nInizia con noi il viaggio verso il tuo cambiamento: vi accompagneremo mano nella mano.<br \/>\nPER I GENITORI<br \/>\nConsulenza Sonno personalizzata 0\/3 anni<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Sonno personalizzata 0\/3 anni<br \/>\nConsulenza Passaggio all\u2019alimentazione complementare a richiesta<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Passaggio all\u2019alimentazione complementare a richiesta<br \/>\nBagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia<br \/>\nConsulenze e attivit\u00e0<br \/>\nBagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia<br \/>\nConsulenza Allattamento<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Allattamento<br \/>\nConsulenza Babywearing: dal pancione alle braccia<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Babywearing: dal pancione alle braccia<br \/>\nMassaggio Sobada<br \/>\nConsulenze e attivit\u00e0<br \/>\nMassaggio Sobada<br \/>\nConsulenza Abbandono consapevole del ciuccio<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Abbandono consapevole del ciuccio<br \/>\nConsulenza Abbandono consapevole del pannolino<br \/>\nEccomi: Percorso di accompagnamento alla nascita e al post-nascita<br \/>\nPercorso Fertilit\u00e0 in ascolto<br \/>\nConcepimento<br \/>\nPercorso Fertilit\u00e0 in ascolto<br \/>\nAllattamento e lavoro: si pu\u00f2!<br \/>\nCorsi<br \/>\nAllattamento e lavoro: si pu\u00f2!<br \/>\nConsulenze e attivit\u00e0<br \/>\nGinnastica in gravidanza e post parto<br \/>\nConsulenze e Trattamenti Osteopatici per mamma e bambino<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenze e Trattamenti Osteopatici per mamma e bambino<br \/>\nConsulenza Pedagogica<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Pedagogica<br \/>\nIncontri con Ostetrica<br \/>\nConsulenze e attivit\u00e0<br \/>\nIncontri con Ostetrica<br \/>\nValutazioni ed Incontri con nutrizionista<br \/>\nConsulenze e attivit\u00e0<br \/>\nValutazioni ed Incontri con nutrizionista<br \/>\nConsulenza Alta Sensibilit\u00e0<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Alta Sensibilit\u00e0<br \/>\nConsulenza Neurodivergenze<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza Neurodivergenze<br \/>\nYoga in Gravidanza<br \/>\nConsulenze e attivit\u00e0<br \/>\nYoga in Gravidanza<br \/>\nEducazione e Consulenza sessuale personale e di coppia<br \/>\nConsulenze e attivit\u00e0<br \/>\nEducazione e Consulenza sessuale personale e di coppia<br \/>\nConsulenza naturopatica per mamma e bambino<br \/>\nConsulenze e attivit\u00e0<br \/>\nConsulenza naturopatica per mamma e bambino<br \/>\nScarica l\u2019ebook gratuito e inizia a prenderti cura di te e del tuo bambino.<br \/>\nScopri un modo pi\u00f9 dolce e consapevole di vivere la maternit\u00e0.<br \/>\nAbbiamo creato per te un ebook gratuito ricco di strumenti pratici, riflessioni profonde e consigli utili per affrontare il tuo percorso da mamma con pi\u00f9 serenit\u00e0 e fiducia.<br \/>\nCOMPILA IL FORM QUI SOTTO E INIZIA DA SUBITO A PRENDERTI CURA DI TE.<br \/>\nACCADEMIA PER PROFESSIONISTI<br \/>\nLa nostra Accademia per professionisti<br \/>\nAcademy professionalizzante, secondo la Mission e l\u2019ideologia di Mamme Con-Tatto\u00ae.<br \/>\nSe sei un professionista che opera nel settore materno-infantile puoi arricchire il tuo curriculum e la tua esperienza lavorativa attraverso i nostri master altamente qualificati:<br \/>\nMaster Consulenti del Sonno Infantile ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo<br \/>\nMaster Educatrice ed Operatrice Perinatale promotrice dell\u2019Allattamento con attestazione riconosciuta a livello Europeo<br \/>\nScuola di Alimentazione Complementare a Richiesta Ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo<br \/>\nMadrina del latte con attestazione riconosciuta a livello Europeo<br \/>\nCorso Educatrice di nido esperta in Babywearing con attestazione riconosciuta a livello Europeo<br \/>\nScuola di Babywearing con attestazione riconosciuta a livello Europeo<br \/>\nConsulente del Tocco di Mamme di Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo<br \/>\nPedagogia dell\u2019abbandono consapevole del ciuccio con attestazione riconosciuta a livello Europeo<br \/>\nPedagogia dell\u2019abbandono consapevole del Pannolino con attestazione riconosciuta a livello Europeo<br \/>\nMaster Tata con attestazione riconosciuta a livello Europeo<\/p>\n<p>consulenza maternit\u00e0, gravidanza, post parto, infanzia, genitorialit\u00e0, pre concepimento, sostegno famiglie, consulenza a domicilio, consulenza online, centro per famiglie, accademia professionisti, formazione perinatale, consulenza sonno bambini, alimentazione complementare, svezzamento, bagno neonati, allattamento, babywearing, massaggio neonatale, ciuccio, pannolino, accompagnamento nascita, fertilit\u00e0, lavoro e allattamento, ginnastica gravidanza, osteopatia mamma bambino, consulenza pedagogica, ostetrica, nutrizionista, neurodivergenze, yoga gravidanza, educazione sessuale, naturopatia mamma bambino, corsi genitori, supporto genitoriale, crescita bambino, consulenze per famiglie, supporto neomamma, aiuto allattamento, difficolt\u00e0 allattamento, consulenza sonno neonato, neonato che non dorme, gestione pianto neonato, consigli neonati primi mesi, supporto post parto, depressione post parto aiuto, stanchezza neomamma, alimentazione neonato, portare in fascia neonato, genitorialit\u00e0 consapevole, ansia da neomamma, gravidanza e preparazione parto, dolore allattamento, mastite, crescita bambino primi anni, consulenza ostetrica online, aiuto per dormire neonato, routine neonato, pianto inconsolabile neonato, supporto famiglia neonato<\/p>\n<p>consulenza maternit\u00e0 a Scanzorosciate, gravidanza a Scanzorosciate, post parto a Scanzorosciate, infanzia a Scanzorosciate, genitorialit\u00e0 a Scanzorosciate, pre concepimento a Scanzorosciate, sostegno famiglie a Scanzorosciate, consulenza a domicilio a Scanzorosciate, consulenza online a Scanzorosciate, centro per famiglie a Scanzorosciate, accademia professionisti a Scanzorosciate, formazione perinatale a Scanzorosciate, consulenza sonno bambini a Scanzorosciate, alimentazione complementare a Scanzorosciate, svezzamento a Scanzorosciate, bagno neonati a Scanzorosciate, allattamento a Scanzorosciate, babywearing a Scanzorosciate, massaggio neonatale a Scanzorosciate, ciuccio a Scanzorosciate, pannolino a Scanzorosciate, accompagnamento nascita a Scanzorosciate, fertilit\u00e0 a Scanzorosciate, lavoro e allattamento a Scanzorosciate, ginnastica gravidanza a Scanzorosciate, osteopatia mamma bambino a Scanzorosciate, consulenza pedagogica a Scanzorosciate, ostetrica a Scanzorosciate, nutrizionista a Scanzorosciate, neurodivergenze a Scanzorosciate, yoga gravidanza a Scanzorosciate, educazione sessuale a Scanzorosciate, naturopatia mamma bambino a Scanzorosciate, corsi genitori a Scanzorosciate, supporto genitoriale a Scanzorosciate, crescita bambino a Scanzorosciate, consulenze per famiglie a Scanzorosciate, supporto neomamma a Scanzorosciate, aiuto allattamento a Scanzorosciate, difficolt\u00e0 allattamento a Scanzorosciate, consulenza sonno neonato a Scanzorosciate, neonato che non dorme a Scanzorosciate, gestione pianto neonato a Scanzorosciate, consigli neonati primi mesi a Scanzorosciate, supporto post parto a Scanzorosciate, depressione post parto aiuto a Scanzorosciate, stanchezza neomamma a Scanzorosciate, alimentazione neonato a Scanzorosciate, portare in fascia neonato a Scanzorosciate, genitorialit\u00e0 consapevole a Scanzorosciate, ansia da neomamma a Scanzorosciate, gravidanza e preparazione parto a Scanzorosciate, dolore allattamento a Scanzorosciate, mastite a Scanzorosciate, crescita bambino primi anni a Scanzorosciate, consulenza ostetrica online a Scanzorosciate, aiuto per dormire neonato a Scanzorosciate, routine neonato a Scanzorosciate, pianto inconsolabile neonato a Scanzorosciate, supporto famiglia neonato a Scanzorosciate<\/p>\n<p>consulenza maternit\u00e0 a Bergamo, gravidanza a Bergamo, post parto a Bergamo, infanzia a Bergamo, genitorialit\u00e0 a Bergamo, pre concepimento a Bergamo, sostegno famiglie a Bergamo, consulenza a domicilio a Bergamo, consulenza online a Bergamo, centro per famiglie a Bergamo, accademia professionisti a Bergamo, formazione perinatale a Bergamo, consulenza sonno bambini a Bergamo, alimentazione complementare a Bergamo, svezzamento a Bergamo, bagno neonati a Bergamo, allattamento a Bergamo, babywearing a Bergamo, massaggio neonatale a Bergamo, ciuccio a Bergamo, pannolino a Bergamo, accompagnamento nascita a Bergamo, fertilit\u00e0 a Bergamo, lavoro e allattamento a Bergamo, ginnastica gravidanza a Bergamo, osteopatia mamma bambino a Bergamo, consulenza pedagogica a Bergamo, ostetrica a Bergamo, nutrizionista a Bergamo, neurodivergenze a Bergamo, yoga gravidanza a Bergamo, educazione sessuale a Bergamo, naturopatia mamma bambino a Bergamo, corsi genitori a Bergamo, supporto genitoriale a Bergamo, crescita bambino a Bergamo, consulenze per famiglie a Bergamo, supporto neomamma a Bergamo, aiuto allattamento a Bergamo, difficolt\u00e0 allattamento a Bergamo, consulenza sonno neonato a Bergamo, neonato che non dorme a Bergamo, gestione pianto neonato a Bergamo, consigli neonati primi mesi a Bergamo, supporto post parto a Bergamo, depressione post parto aiuto a Bergamo, stanchezza neomamma a Bergamo, alimentazione neonato a Bergamo, portare in fascia neonato a Bergamo, genitorialit\u00e0 consapevole a Bergamo, ansia da neomamma a Bergamo, gravidanza e preparazione parto a Bergamo, dolore allattamento a Bergamo, mastite a Bergamo, crescita bambino primi anni a Bergamo, consulenza ostetrica online a Bergamo, aiuto per dormire neonato a Bergamo, routine neonato a Bergamo, pianto inconsolabile neonato a Bergamo, supporto famiglia neonato a Bergamo<\/p>\n<\/div>\n","protected":false},"featured_media":37356,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[3688,3689,3584,27],"product_tag":[10762,10771,4408,10798,10765,10789,3779,10792,3319,10767,10761,10769,10786,10760,10757,4555,10797,3956,10764,10783,10781,10779,10780,10796,10787,10782,10794,10777,10772,10763,4841,10791,10785,10774,6006,10793,3140,10773,10768,10795,10778,10784,10776,367,10775,5834,10770,10800,10790,10096,10758,10799,10759,10788,10801,7957,3696,3694,10766,9798],"class_list":{"0":"post-37355","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-assistenza-alla-genitorialita","7":"product_cat-centri-assistenza-per-le-famiglie","8":"product_cat-coach-del-sonno-infantile","9":"product_cat-servizi","10":"product_tag-accademia-professionisti","11":"product_tag-accompagnamento-nascita","12":"product_tag-aiuto-allattamento","13":"product_tag-aiuto-per-dormire-neonato","14":"product_tag-alimentazione-complementare","15":"product_tag-alimentazione-neonato","16":"product_tag-allattamento","17":"product_tag-ansia-da-neomamma","18":"product_tag-babywearing","19":"product_tag-bagno-neonati","20":"product_tag-centro-per-famiglie","21":"product_tag-ciuccio","22":"product_tag-consigli-neonati-primi-mesi","23":"product_tag-consulenza-a-domicilio","24":"product_tag-consulenza-maternita","25":"product_tag-consulenza-online","26":"product_tag-consulenza-ostetrica-online","27":"product_tag-consulenza-pedagogica","28":"product_tag-consulenza-sonno-bambini","29":"product_tag-consulenza-sonno-neonato","30":"product_tag-consulenze-per-famiglie","31":"product_tag-corsi-genitori","32":"product_tag-crescita-bambino","33":"product_tag-crescita-bambino-primi-anni","34":"product_tag-depressione-post-parto-aiuto","35":"product_tag-difficolta-allattamento","36":"product_tag-dolore-allattamento","37":"product_tag-educazione-sessuale","38":"product_tag-fertilita","39":"product_tag-formazione-perinatale","40":"product_tag-genitorialita","41":"product_tag-genitorialita-consapevole","42":"product_tag-gestione-pianto-neonato","43":"product_tag-ginnastica-gravidanza","44":"product_tag-gravidanza","45":"product_tag-gravidanza-e-preparazione-parto","46":"product_tag-infanzia","47":"product_tag-lavoro-e-allattamento","48":"product_tag-massaggio-neonatale","49":"product_tag-mastite","50":"product_tag-naturopatia-mamma-bambino","51":"product_tag-neonato-che-non-dorme","52":"product_tag-neurodivergenze","53":"product_tag-nutrizionista","54":"product_tag-osteopatia-mamma-bambino","55":"product_tag-ostetrica","56":"product_tag-pannolino","57":"product_tag-pianto-inconsolabile-neonato","58":"product_tag-portare-in-fascia-neonato","59":"product_tag-post-parto","60":"product_tag-pre-concepimento","61":"product_tag-routine-neonato","62":"product_tag-sostegno-famiglie","63":"product_tag-stanchezza-neomamma","64":"product_tag-supporto-famiglia-neonato","65":"product_tag-supporto-genitoriale","66":"product_tag-supporto-neomamma","67":"product_tag-supporto-post-parto","68":"product_tag-svezzamento","69":"product_tag-yoga-gravidanza","71":"first","72":"instock","73":"shipping-taxable","74":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mamme Con-Tatto - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mamme Con-Tatto - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Mamme Con-Tatto\u00ae Ci prendiamo cura e accompagniamo la famiglia dal pre concepimento, nel periodo della gravidanza, del post parto e durante tutto il periodo dell\u2019infanzia del bambino. Siamo il villaggio che abbraccia e sta vicino alla famiglia che inizia il suo cammino genitoriale. Consulenza a Domicilio Consulenza Online Consulenza presso il nostro centro Maison Mamme Con-Tatto\u00ae Accademia per professionisti image PER LE FAMIGLIE Per ogni famiglia che vuole sentirsi accolta Ti stiamo accanto in ogni fase del viaggio: dal desiderio di una gravidanza fino ai primi anni di vita del tuo bambino. Ti accompagniamo con ascolto, competenza e calore, perch\u00e9 ogni famiglia merita di sentirsi sostenuta, non giudicata. Crediamo che crescere un bambino sia un\u2019esperienza che coinvolge l\u2019intera famiglia corpo, mente ed emozioni. Per questo uniamo strumenti pratici, sostegno empatico e approccio scientifico per aiutarti a vivere la maternit\u00e0 e la genitorialit\u00e0 con maggiore serenit\u00e0 e consapevolezza. Ogni famiglia \u00e8 unica, e noi siamo qui per accompagnarti passo dopo passo, con empatia, professionalit\u00e0 e tanto cuore. Mamme Con-Tatto PER I PROFESSIONISTI La Nostra Accademia L\u2019Academy Mamme Con-Tatto nasce per formare professionisti capaci di accompagnare le famiglie con competenza, ascolto e umanit\u00e0 dal pre-concepimento ai primi anni di vita del bambino. Crediamo in una formazione che unisca teoria e pratica, scienza e cuore, perch\u00e9 sostenere una famiglia significa molto pi\u00f9 che fornire informazioni: significa esserci, davvero. approfondire le competenze nell\u2019ambito della maternit\u00e0 e della prima infanzia apprendere strumenti pratici di comunicazione empatica e sostegno genitoriale Ogni percorso \u00e8 costruito per far crescere prima la persona, poi il professionista. PER I GENITORI I Nostri Servizi per i Genitori Consulto Iniziale Offriamo il primo consulto telefonico gratuito per conoscerci ed insieme, capire i tuoi bisogni per poterti offrire la consulenza pi\u00f9 adatta a te. Consulenza a Domicilio Su richiesta, siamo disponibili a raggiungerti presso il tuo domicilio per una consulenza ancora pi\u00f9 accurata. Consulenza Online Offriamo consulenze su tutto il territorio Italiano, online, comodamente dal tuo PC o dal tuo Smartphone, su appuntamento.Presso il nostro centro Offriamo accompagnamento alla genitorialit\u00e0 consapevole dal pre concepimento fino all\u2019et\u00e0 scolare del\/la bambino\/a attraverso corsi. Inizia con noi il viaggio verso il tuo cambiamento: vi accompagneremo mano nella mano. PER I GENITORI Consulenza Sonno personalizzata 0\/3 anni Consulenze e attivit\u00e0 Consulenza Sonno personalizzata 0\/3 anni Consulenza Passaggio all\u2019alimentazione complementare a richiesta Consulenze e attivit\u00e0 Consulenza Passaggio all\u2019alimentazione complementare a richiesta Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia Consulenze e attivit\u00e0 Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia Consulenza Allattamento Consulenze e attivit\u00e0 Consulenza Allattamento Consulenza Babywearing: dal pancione alle braccia Consulenze e attivit\u00e0 Consulenza Babywearing: dal pancione alle braccia Massaggio Sobada Consulenze e attivit\u00e0 Massaggio Sobada Consulenza Abbandono consapevole del ciuccio Consulenze e attivit\u00e0 Consulenza Abbandono consapevole del ciuccio Consulenza Abbandono consapevole del pannolino Eccomi: Percorso di accompagnamento alla nascita e al post-nascita Percorso Fertilit\u00e0 in ascolto Concepimento Percorso Fertilit\u00e0 in ascolto Allattamento e lavoro: si pu\u00f2! Corsi Allattamento e lavoro: si pu\u00f2! Consulenze e attivit\u00e0 Ginnastica in gravidanza e post parto Consulenze e Trattamenti Osteopatici per mamma e bambino Consulenze e attivit\u00e0 Consulenze e Trattamenti Osteopatici per mamma e bambino Consulenza Pedagogica Consulenze e attivit\u00e0 Consulenza Pedagogica Incontri con Ostetrica Consulenze e attivit\u00e0 Incontri con Ostetrica Valutazioni ed Incontri con nutrizionista Consulenze e attivit\u00e0 Valutazioni ed Incontri con nutrizionista Consulenza Alta Sensibilit\u00e0 Consulenze e attivit\u00e0 Consulenza Alta Sensibilit\u00e0 Consulenza Neurodivergenze Consulenze e attivit\u00e0 Consulenza Neurodivergenze Yoga in Gravidanza Consulenze e attivit\u00e0 Yoga in Gravidanza Educazione e Consulenza sessuale personale e di coppia Consulenze e attivit\u00e0 Educazione e Consulenza sessuale personale e di coppia Consulenza naturopatica per mamma e bambino Consulenze e attivit\u00e0 Consulenza naturopatica per mamma e bambino Scarica l\u2019ebook gratuito e inizia a prenderti cura di te e del tuo bambino. Scopri un modo pi\u00f9 dolce e consapevole di vivere la maternit\u00e0. Abbiamo creato per te un ebook gratuito ricco di strumenti pratici, riflessioni profonde e consigli utili per affrontare il tuo percorso da mamma con pi\u00f9 serenit\u00e0 e fiducia. COMPILA IL FORM QUI SOTTO E INIZIA DA SUBITO A PRENDERTI CURA DI TE. ACCADEMIA PER PROFESSIONISTI La nostra Accademia per professionisti Academy professionalizzante, secondo la Mission e l\u2019ideologia di Mamme Con-Tatto\u00ae. Se sei un professionista che opera nel settore materno-infantile puoi arricchire il tuo curriculum e la tua esperienza lavorativa attraverso i nostri master altamente qualificati: Master Consulenti del Sonno Infantile ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo Master Educatrice ed Operatrice Perinatale promotrice dell\u2019Allattamento con attestazione riconosciuta a livello Europeo Scuola di Alimentazione Complementare a Richiesta Ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo Madrina del latte con attestazione riconosciuta a livello Europeo Corso Educatrice di nido esperta in Babywearing con attestazione riconosciuta a livello Europeo Scuola di Babywearing con attestazione riconosciuta a livello Europeo Consulente del Tocco di Mamme di Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo Pedagogia dell\u2019abbandono consapevole del ciuccio con attestazione riconosciuta a livello Europeo Pedagogia dell\u2019abbandono consapevole del Pannolino con attestazione riconosciuta a livello Europeo Master Tata con attestazione riconosciuta a livello Europeo  consulenza maternit\u00e0, gravidanza, post parto, infanzia, genitorialit\u00e0, pre concepimento, sostegno famiglie, consulenza a domicilio, consulenza online, centro per famiglie, accademia professionisti, formazione perinatale, consulenza sonno bambini, alimentazione complementare, svezzamento, bagno neonati, allattamento, babywearing, massaggio neonatale, ciuccio, pannolino, accompagnamento nascita, fertilit\u00e0, lavoro e allattamento, ginnastica gravidanza, osteopatia mamma bambino, consulenza pedagogica, ostetrica, nutrizionista, neurodivergenze, yoga gravidanza, educazione sessuale, naturopatia mamma bambino, corsi genitori, supporto genitoriale, crescita bambino, consulenze per famiglie, supporto neomamma, aiuto allattamento, difficolt\u00e0 allattamento, consulenza sonno neonato, neonato che non dorme, gestione pianto neonato, consigli neonati primi mesi, supporto post parto, depressione post parto aiuto, stanchezza neomamma, alimentazione neonato, portare in fascia neonato, genitorialit\u00e0 consapevole, ansia da neomamma, gravidanza e preparazione parto, dolore allattamento, mastite, crescita bambino primi anni, consulenza ostetrica online, aiuto per dormire neonato, routine neonato, pianto inconsolabile neonato, supporto famiglia neonato  consulenza maternit\u00e0 a Scanzorosciate, gravidanza a Scanzorosciate, post parto a Scanzorosciate, infanzia a Scanzorosciate, genitorialit\u00e0 a Scanzorosciate, pre concepimento a Scanzorosciate, sostegno famiglie a Scanzorosciate, consulenza a domicilio a Scanzorosciate, consulenza online a Scanzorosciate, centro per famiglie a Scanzorosciate, accademia professionisti a Scanzorosciate, formazione perinatale a Scanzorosciate, consulenza sonno bambini a Scanzorosciate, alimentazione complementare a Scanzorosciate, svezzamento a Scanzorosciate, bagno neonati a Scanzorosciate, allattamento a Scanzorosciate, babywearing a Scanzorosciate, massaggio neonatale a Scanzorosciate, ciuccio a Scanzorosciate, pannolino a Scanzorosciate, accompagnamento nascita a Scanzorosciate, fertilit\u00e0 a Scanzorosciate, lavoro e allattamento a Scanzorosciate, ginnastica gravidanza a Scanzorosciate, osteopatia mamma bambino a Scanzorosciate, consulenza pedagogica a Scanzorosciate, ostetrica a Scanzorosciate, nutrizionista a Scanzorosciate, neurodivergenze a Scanzorosciate, yoga gravidanza a Scanzorosciate, educazione sessuale a Scanzorosciate, naturopatia mamma bambino a Scanzorosciate, corsi genitori a Scanzorosciate, supporto genitoriale a Scanzorosciate, crescita bambino a Scanzorosciate, consulenze per famiglie a Scanzorosciate, supporto neomamma a Scanzorosciate, aiuto allattamento a Scanzorosciate, difficolt\u00e0 allattamento a Scanzorosciate, consulenza sonno neonato a Scanzorosciate, neonato che non dorme a Scanzorosciate, gestione pianto neonato a Scanzorosciate, consigli neonati primi mesi a Scanzorosciate, supporto post parto a Scanzorosciate, depressione post parto aiuto a Scanzorosciate, stanchezza neomamma a Scanzorosciate, alimentazione neonato a Scanzorosciate, portare in fascia neonato a Scanzorosciate, genitorialit\u00e0 consapevole a Scanzorosciate, ansia da neomamma a Scanzorosciate, gravidanza e preparazione parto a Scanzorosciate, dolore allattamento a Scanzorosciate, mastite a Scanzorosciate, crescita bambino primi anni a Scanzorosciate, consulenza ostetrica online a Scanzorosciate, aiuto per dormire neonato a Scanzorosciate, routine neonato a Scanzorosciate, pianto inconsolabile neonato a Scanzorosciate, supporto famiglia neonato a Scanzorosciate  consulenza maternit\u00e0 a Bergamo, gravidanza a Bergamo, post parto a Bergamo, infanzia a Bergamo, genitorialit\u00e0 a Bergamo, pre concepimento a Bergamo, sostegno famiglie a Bergamo, consulenza a domicilio a Bergamo, consulenza online a Bergamo, centro per famiglie a Bergamo, accademia professionisti a Bergamo, formazione perinatale a Bergamo, consulenza sonno bambini a Bergamo, alimentazione complementare a Bergamo, svezzamento a Bergamo, bagno neonati a Bergamo, allattamento a Bergamo, babywearing a Bergamo, massaggio neonatale a Bergamo, ciuccio a Bergamo, pannolino a Bergamo, accompagnamento nascita a Bergamo, fertilit\u00e0 a Bergamo, lavoro e allattamento a Bergamo, ginnastica gravidanza a Bergamo, osteopatia mamma bambino a Bergamo, consulenza pedagogica a Bergamo, ostetrica a Bergamo, nutrizionista a Bergamo, neurodivergenze a Bergamo, yoga gravidanza a Bergamo, educazione sessuale a Bergamo, naturopatia mamma bambino a Bergamo, corsi genitori a Bergamo, supporto genitoriale a Bergamo, crescita bambino a Bergamo, consulenze per famiglie a Bergamo, supporto neomamma a Bergamo, aiuto allattamento a Bergamo, difficolt\u00e0 allattamento a Bergamo, consulenza sonno neonato a Bergamo, neonato che non dorme a Bergamo, gestione pianto neonato a Bergamo, consigli neonati primi mesi a Bergamo, supporto post parto a Bergamo, depressione post parto aiuto a Bergamo, stanchezza neomamma a Bergamo, alimentazione neonato a Bergamo, portare in fascia neonato a Bergamo, genitorialit\u00e0 consapevole a Bergamo, ansia da neomamma a Bergamo, gravidanza e preparazione parto a Bergamo, dolore allattamento a Bergamo, mastite a Bergamo, crescita bambino primi anni a Bergamo, consulenza ostetrica online a Bergamo, aiuto per dormire neonato a Bergamo, routine neonato a Bergamo, pianto inconsolabile neonato a Bergamo, supporto famiglia neonato a Bergamo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T08:46:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/\",\"name\":\"Mamme Con-Tatto - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png\",\"datePublished\":\"2026-06-22T13:36:00+00:00\",\"dateModified\":\"2026-06-29T08:46:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mamme Con-Tatto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mamme Con-Tatto - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/","og_locale":"it_IT","og_type":"article","og_title":"Mamme Con-Tatto - Cral Policlinico di Milano","og_description":"Mamme Con-Tatto\u00ae Ci prendiamo cura e accompagniamo la famiglia dal pre concepimento, nel periodo della gravidanza, del post parto e durante tutto il periodo dell\u2019infanzia del bambino. Siamo il villaggio che abbraccia e sta vicino alla famiglia che inizia il suo cammino genitoriale. Consulenza a Domicilio Consulenza Online Consulenza presso il nostro centro Maison Mamme Con-Tatto\u00ae Accademia per professionisti image PER LE FAMIGLIE Per ogni famiglia che vuole sentirsi accolta Ti stiamo accanto in ogni fase del viaggio: dal desiderio di una gravidanza fino ai primi anni di vita del tuo bambino. Ti accompagniamo con ascolto, competenza e calore, perch\u00e9 ogni famiglia merita di sentirsi sostenuta, non giudicata. Crediamo che crescere un bambino sia un\u2019esperienza che coinvolge l\u2019intera famiglia corpo, mente ed emozioni. Per questo uniamo strumenti pratici, sostegno empatico e approccio scientifico per aiutarti a vivere la maternit\u00e0 e la genitorialit\u00e0 con maggiore serenit\u00e0 e consapevolezza. Ogni famiglia \u00e8 unica, e noi siamo qui per accompagnarti passo dopo passo, con empatia, professionalit\u00e0 e tanto cuore. Mamme Con-Tatto PER I PROFESSIONISTI La Nostra Accademia L\u2019Academy Mamme Con-Tatto nasce per formare professionisti capaci di accompagnare le famiglie con competenza, ascolto e umanit\u00e0 dal pre-concepimento ai primi anni di vita del bambino. Crediamo in una formazione che unisca teoria e pratica, scienza e cuore, perch\u00e9 sostenere una famiglia significa molto pi\u00f9 che fornire informazioni: significa esserci, davvero. approfondire le competenze nell\u2019ambito della maternit\u00e0 e della prima infanzia apprendere strumenti pratici di comunicazione empatica e sostegno genitoriale Ogni percorso \u00e8 costruito per far crescere prima la persona, poi il professionista. PER I GENITORI I Nostri Servizi per i Genitori Consulto Iniziale Offriamo il primo consulto telefonico gratuito per conoscerci ed insieme, capire i tuoi bisogni per poterti offrire la consulenza pi\u00f9 adatta a te. Consulenza a Domicilio Su richiesta, siamo disponibili a raggiungerti presso il tuo domicilio per una consulenza ancora pi\u00f9 accurata. Consulenza Online Offriamo consulenze su tutto il territorio Italiano, online, comodamente dal tuo PC o dal tuo Smartphone, su appuntamento.Presso il nostro centro Offriamo accompagnamento alla genitorialit\u00e0 consapevole dal pre concepimento fino all\u2019et\u00e0 scolare del\/la bambino\/a attraverso corsi. Inizia con noi il viaggio verso il tuo cambiamento: vi accompagneremo mano nella mano. PER I GENITORI Consulenza Sonno personalizzata 0\/3 anni Consulenze e attivit\u00e0 Consulenza Sonno personalizzata 0\/3 anni Consulenza Passaggio all\u2019alimentazione complementare a richiesta Consulenze e attivit\u00e0 Consulenza Passaggio all\u2019alimentazione complementare a richiesta Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia Consulenze e attivit\u00e0 Bagno Con-Tatto\u00ae, rinascere dall\u2019acqua alle braccia Consulenza Allattamento Consulenze e attivit\u00e0 Consulenza Allattamento Consulenza Babywearing: dal pancione alle braccia Consulenze e attivit\u00e0 Consulenza Babywearing: dal pancione alle braccia Massaggio Sobada Consulenze e attivit\u00e0 Massaggio Sobada Consulenza Abbandono consapevole del ciuccio Consulenze e attivit\u00e0 Consulenza Abbandono consapevole del ciuccio Consulenza Abbandono consapevole del pannolino Eccomi: Percorso di accompagnamento alla nascita e al post-nascita Percorso Fertilit\u00e0 in ascolto Concepimento Percorso Fertilit\u00e0 in ascolto Allattamento e lavoro: si pu\u00f2! Corsi Allattamento e lavoro: si pu\u00f2! Consulenze e attivit\u00e0 Ginnastica in gravidanza e post parto Consulenze e Trattamenti Osteopatici per mamma e bambino Consulenze e attivit\u00e0 Consulenze e Trattamenti Osteopatici per mamma e bambino Consulenza Pedagogica Consulenze e attivit\u00e0 Consulenza Pedagogica Incontri con Ostetrica Consulenze e attivit\u00e0 Incontri con Ostetrica Valutazioni ed Incontri con nutrizionista Consulenze e attivit\u00e0 Valutazioni ed Incontri con nutrizionista Consulenza Alta Sensibilit\u00e0 Consulenze e attivit\u00e0 Consulenza Alta Sensibilit\u00e0 Consulenza Neurodivergenze Consulenze e attivit\u00e0 Consulenza Neurodivergenze Yoga in Gravidanza Consulenze e attivit\u00e0 Yoga in Gravidanza Educazione e Consulenza sessuale personale e di coppia Consulenze e attivit\u00e0 Educazione e Consulenza sessuale personale e di coppia Consulenza naturopatica per mamma e bambino Consulenze e attivit\u00e0 Consulenza naturopatica per mamma e bambino Scarica l\u2019ebook gratuito e inizia a prenderti cura di te e del tuo bambino. Scopri un modo pi\u00f9 dolce e consapevole di vivere la maternit\u00e0. Abbiamo creato per te un ebook gratuito ricco di strumenti pratici, riflessioni profonde e consigli utili per affrontare il tuo percorso da mamma con pi\u00f9 serenit\u00e0 e fiducia. COMPILA IL FORM QUI SOTTO E INIZIA DA SUBITO A PRENDERTI CURA DI TE. ACCADEMIA PER PROFESSIONISTI La nostra Accademia per professionisti Academy professionalizzante, secondo la Mission e l\u2019ideologia di Mamme Con-Tatto\u00ae. Se sei un professionista che opera nel settore materno-infantile puoi arricchire il tuo curriculum e la tua esperienza lavorativa attraverso i nostri master altamente qualificati: Master Consulenti del Sonno Infantile ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo Master Educatrice ed Operatrice Perinatale promotrice dell\u2019Allattamento con attestazione riconosciuta a livello Europeo Scuola di Alimentazione Complementare a Richiesta Ideologia Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo Madrina del latte con attestazione riconosciuta a livello Europeo Corso Educatrice di nido esperta in Babywearing con attestazione riconosciuta a livello Europeo Scuola di Babywearing con attestazione riconosciuta a livello Europeo Consulente del Tocco di Mamme di Mamme Con-Tatto\u00ae con attestazione riconosciuta a livello Europeo Pedagogia dell\u2019abbandono consapevole del ciuccio con attestazione riconosciuta a livello Europeo Pedagogia dell\u2019abbandono consapevole del Pannolino con attestazione riconosciuta a livello Europeo Master Tata con attestazione riconosciuta a livello Europeo  consulenza maternit\u00e0, gravidanza, post parto, infanzia, genitorialit\u00e0, pre concepimento, sostegno famiglie, consulenza a domicilio, consulenza online, centro per famiglie, accademia professionisti, formazione perinatale, consulenza sonno bambini, alimentazione complementare, svezzamento, bagno neonati, allattamento, babywearing, massaggio neonatale, ciuccio, pannolino, accompagnamento nascita, fertilit\u00e0, lavoro e allattamento, ginnastica gravidanza, osteopatia mamma bambino, consulenza pedagogica, ostetrica, nutrizionista, neurodivergenze, yoga gravidanza, educazione sessuale, naturopatia mamma bambino, corsi genitori, supporto genitoriale, crescita bambino, consulenze per famiglie, supporto neomamma, aiuto allattamento, difficolt\u00e0 allattamento, consulenza sonno neonato, neonato che non dorme, gestione pianto neonato, consigli neonati primi mesi, supporto post parto, depressione post parto aiuto, stanchezza neomamma, alimentazione neonato, portare in fascia neonato, genitorialit\u00e0 consapevole, ansia da neomamma, gravidanza e preparazione parto, dolore allattamento, mastite, crescita bambino primi anni, consulenza ostetrica online, aiuto per dormire neonato, routine neonato, pianto inconsolabile neonato, supporto famiglia neonato  consulenza maternit\u00e0 a Scanzorosciate, gravidanza a Scanzorosciate, post parto a Scanzorosciate, infanzia a Scanzorosciate, genitorialit\u00e0 a Scanzorosciate, pre concepimento a Scanzorosciate, sostegno famiglie a Scanzorosciate, consulenza a domicilio a Scanzorosciate, consulenza online a Scanzorosciate, centro per famiglie a Scanzorosciate, accademia professionisti a Scanzorosciate, formazione perinatale a Scanzorosciate, consulenza sonno bambini a Scanzorosciate, alimentazione complementare a Scanzorosciate, svezzamento a Scanzorosciate, bagno neonati a Scanzorosciate, allattamento a Scanzorosciate, babywearing a Scanzorosciate, massaggio neonatale a Scanzorosciate, ciuccio a Scanzorosciate, pannolino a Scanzorosciate, accompagnamento nascita a Scanzorosciate, fertilit\u00e0 a Scanzorosciate, lavoro e allattamento a Scanzorosciate, ginnastica gravidanza a Scanzorosciate, osteopatia mamma bambino a Scanzorosciate, consulenza pedagogica a Scanzorosciate, ostetrica a Scanzorosciate, nutrizionista a Scanzorosciate, neurodivergenze a Scanzorosciate, yoga gravidanza a Scanzorosciate, educazione sessuale a Scanzorosciate, naturopatia mamma bambino a Scanzorosciate, corsi genitori a Scanzorosciate, supporto genitoriale a Scanzorosciate, crescita bambino a Scanzorosciate, consulenze per famiglie a Scanzorosciate, supporto neomamma a Scanzorosciate, aiuto allattamento a Scanzorosciate, difficolt\u00e0 allattamento a Scanzorosciate, consulenza sonno neonato a Scanzorosciate, neonato che non dorme a Scanzorosciate, gestione pianto neonato a Scanzorosciate, consigli neonati primi mesi a Scanzorosciate, supporto post parto a Scanzorosciate, depressione post parto aiuto a Scanzorosciate, stanchezza neomamma a Scanzorosciate, alimentazione neonato a Scanzorosciate, portare in fascia neonato a Scanzorosciate, genitorialit\u00e0 consapevole a Scanzorosciate, ansia da neomamma a Scanzorosciate, gravidanza e preparazione parto a Scanzorosciate, dolore allattamento a Scanzorosciate, mastite a Scanzorosciate, crescita bambino primi anni a Scanzorosciate, consulenza ostetrica online a Scanzorosciate, aiuto per dormire neonato a Scanzorosciate, routine neonato a Scanzorosciate, pianto inconsolabile neonato a Scanzorosciate, supporto famiglia neonato a Scanzorosciate  consulenza maternit\u00e0 a Bergamo, gravidanza a Bergamo, post parto a Bergamo, infanzia a Bergamo, genitorialit\u00e0 a Bergamo, pre concepimento a Bergamo, sostegno famiglie a Bergamo, consulenza a domicilio a Bergamo, consulenza online a Bergamo, centro per famiglie a Bergamo, accademia professionisti a Bergamo, formazione perinatale a Bergamo, consulenza sonno bambini a Bergamo, alimentazione complementare a Bergamo, svezzamento a Bergamo, bagno neonati a Bergamo, allattamento a Bergamo, babywearing a Bergamo, massaggio neonatale a Bergamo, ciuccio a Bergamo, pannolino a Bergamo, accompagnamento nascita a Bergamo, fertilit\u00e0 a Bergamo, lavoro e allattamento a Bergamo, ginnastica gravidanza a Bergamo, osteopatia mamma bambino a Bergamo, consulenza pedagogica a Bergamo, ostetrica a Bergamo, nutrizionista a Bergamo, neurodivergenze a Bergamo, yoga gravidanza a Bergamo, educazione sessuale a Bergamo, naturopatia mamma bambino a Bergamo, corsi genitori a Bergamo, supporto genitoriale a Bergamo, crescita bambino a Bergamo, consulenze per famiglie a Bergamo, supporto neomamma a Bergamo, aiuto allattamento a Bergamo, difficolt\u00e0 allattamento a Bergamo, consulenza sonno neonato a Bergamo, neonato che non dorme a Bergamo, gestione pianto neonato a Bergamo, consigli neonati primi mesi a Bergamo, supporto post parto a Bergamo, depressione post parto aiuto a Bergamo, stanchezza neomamma a Bergamo, alimentazione neonato a Bergamo, portare in fascia neonato a Bergamo, genitorialit\u00e0 consapevole a Bergamo, ansia da neomamma a Bergamo, gravidanza e preparazione parto a Bergamo, dolore allattamento a Bergamo, mastite a Bergamo, crescita bambino primi anni a Bergamo, consulenza ostetrica online a Bergamo, aiuto per dormire neonato a Bergamo, routine neonato a Bergamo, pianto inconsolabile neonato a Bergamo, supporto famiglia neonato a Bergamo","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-06-29T08:46:52+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/","name":"Mamme Con-Tatto - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png","datePublished":"2026-06-22T13:36:00+00:00","dateModified":"2026-06-29T08:46:52+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/06\/logo_Mamme-Con-Tatto.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/mamme-con-tatto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Mamme Con-Tatto"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/37355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=37355"}],"version-history":[{"count":15,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/37355\/revisions"}],"predecessor-version":[{"id":37696,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/37355\/revisions\/37696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/37356"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=37355"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=37355"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=37355"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=37355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}