{"id":32431,"date":"2026-05-05T14:46:06","date_gmt":"2026-05-05T12:46:06","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=32431"},"modified":"2026-05-05T17:32:02","modified_gmt":"2026-05-05T15:32:02","slug":"carlo-ponzio-architetto-milano","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/","title":{"rendered":"Carlo Ponzio &#8211; Architetto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"32431\" class=\"elementor elementor-32431\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50977639 e-flex e-con-boxed e-con e-parent\" data-id=\"50977639\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0fdf3a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f0fdf3a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"378\" height=\"189\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/logo_architetto_carlo_ponzio.png\" class=\"attachment-large size-large wp-image-32443\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/logo_architetto_carlo_ponzio.png 378w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/logo_architetto_carlo_ponzio-300x150.png 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dac8808 e-flex e-con-boxed e-con e-parent\" data-id=\"dac8808\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec96c75 elementor-widget elementor-widget-text-editor\" data-id=\"3ec96c75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cL\u2019architettura non \u00e8 altro che l\u2019ordine, la disposizione, la bella apparenza, la proporzione delle parti fra loro, la convenienza e la distribuzione\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1e649 elementor-widget elementor-widget-text-editor\" data-id=\"df1e649\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMichelangelo Buonarroti\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45cd05a3 e-flex e-con-boxed e-con e-parent\" data-id=\"45cd05a3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f9aa010 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3f9aa010\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4091b7d1 e-con-full e-flex e-con e-child\" data-id=\"4091b7d1\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab2afbb elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4ab2afbb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tProgetto spazi residenziali e professionali dove estetica e fattibilit\u00e0 vanno d\u2019accordo.\u2028\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cec92ad elementor-widget elementor-widget-text-editor\" data-id=\"1cec92ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sono <b>Carlo Ponzio<\/b>, architetto (laurea in Architettura e Ingegneria Edile al Politecnico di Milano).<\/p><p>Dal 2006 seguo interventi in ambito residenziale e terziario: abitazioni, uffici, attivit\u00e0 commerciali e studi professionali.<\/p><p><b>Il mio approccio \u00e8 semplice:<\/b> ogni scelta deve essere bella, funzionale e cantierabile. Per questo lavoro in modo rigoroso su layout, dettagli costruttivi, materiali e finiture, coordinando arredi su misura, illuminazione e impianti.\u00a0<\/p><p>L\u2019obiettivo \u00e8 evitare soluzioni \u201cdi effetto\u201d che poi diventino problemi: preferisco risultati puliti, coerenti e duraturi, che funzionano davvero nella vita quotidiana.<\/p><p>Dall\u2019ideazione alla realizzazione, mi impegno a <b>curare ogni dettaglio<\/b>, ascoltando attentamente le vostre esigenze per creare spazi unici.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d9cb2d5 e-con-full e-flex e-con e-child\" data-id=\"6d9cb2d5\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb0e59 elementor-widget elementor-widget-image\" data-id=\"4bb0e59\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Immagine-del-profiloimg-architetto-ponzio.jpg-683x1024.jpg\" class=\"attachment-large size-large wp-image-32442\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad858b5 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"ad858b5\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02cad14 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"02cad14\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSe stai ristrutturando o vuoi valorizzare un immobile, posso affiancarti dalla progettazione alla direzione lavori, con un metodo chiaro e decisioni guidate da costi, tempi e qualit\u00e0.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1079ecb e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1079ecb\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7a3efd0e e-con-full e-flex e-con e-child\" data-id=\"7a3efd0e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-577cad1b e-con-full e-flex e-con e-child\" data-id=\"577cad1b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-521a7456 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"521a7456\" data-element_type=\"widget\" id=\"serviziofferti\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Servizi offerti:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72f5f72a elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"72f5f72a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Analisi tecnica dell\u2019immobile preliminare all\u2019acquisto per verifica criticit\u00e0, costi reali e potenziale di trasformazione<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Progettazione architettonica e interior design<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Direzione lavori e coordinamento imprese<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pratiche edilizie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Arredi su misura, materiali e illuminazione<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b57fefa elementor-align-left elementor-widget__width-inherit elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"2b57fefa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/architettocarloponzio.it\/progetti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Guarda i miei progetti<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bf317fd e-con-full e-flex e-con e-child\" data-id=\"1bf317fd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:32445,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2026\\\/05\\\/prima-dei-lavori-di-ristrutturazione-23img-architetto-ponzio.jpg.jpg&quot;},{&quot;id&quot;:32441,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2026\\\/05\\\/06-2-scaledimg-architetto-ponzio.jpg.jpg&quot;},{&quot;id&quot;:32440,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2026\\\/05\\\/05-3img-architetto-ponzio.jpg.jpg&quot;},{&quot;id&quot;:32439,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2026\\\/05\\\/03-3img-architetto-ponzio.jpg.jpg&quot;},{&quot;id&quot;:32438,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2026\\\/05\\\/02-2-scaledimg-architetto-ponzio.jpg.jpg&quot;},{&quot;id&quot;:32437,&quot;url&quot;:&quot;https:\\\/\\\/convenzioni.cralnetwork.it\\\/cralmangiagalli\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2026\\\/05\\\/1-scaledimg-architetto-ponzio.jpg.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-672e51c6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"672e51c6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7981a7d3 e-flex e-con-boxed e-con e-parent\" data-id=\"7981a7d3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-54961125 e-con-full e-flex e-con e-child\" data-id=\"54961125\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28113ddf elementor-widget elementor-widget-text-editor\" data-id=\"28113ddf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAgevolazioni riservate agli associati\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3baab0eb e-con-full e-flex e-con e-child\" data-id=\"3baab0eb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43f7b4f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"43f7b4f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3212424 elementor-widget elementor-widget-text-editor\" data-id=\"3212424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Meloria, 8 &#8211; 20148 Milano<br \/>Via Zanotti, 5 &#8211; 28010 Pella (NO)<\/p><p>Cell: <a href=\"tel:+393339578043\" target=\"_blank\" rel=\"noopener\">333 9578043<\/a><br \/>Mail <a href=\"mailto:ponzio.carlo@gmail.com\" target=\"_blank\" rel=\"noopener\">ponzio.carlo@gmail.com<\/a><br \/>Sito: <a href=\"https:\/\/architettocarloponzio.it\/\" target=\"_blank\" rel=\"noopener\">wwww.architettocarloponzio.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f2370a elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"24f2370a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/architettocarloponzio.it\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">visita il sito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60deb48b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"60deb48b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e832af8 elementor-widget elementor-widget-text-editor\" data-id=\"1e832af8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCarlo Ponzio &#8211; Architetto\nProgetto spazi residenziali e professionali dove estetica e fattibilit\u00e0 vanno d\u2019accordo.\u2028Sono Carlo Ponzio, architetto (laurea in Architettura e Ingegneria Edile al Politecnico di Milano). Dal 2006 seguo interventi in ambito residenziale e terziario: abitazioni, uffici, attivit\u00e0 commerciali e studi professionali.\n\nIl mio approccio \u00e8 semplice: ogni scelta deve essere bella, funzionale e cantierabile. Per questo lavoro in modo rigoroso su layout, dettagli costruttivi, materiali e finiture, coordinando arredi su misura, illuminazione e impianti. L\u2019obiettivo \u00e8 evitare soluzioni \u201cdi effetto\u201d che poi diventino problemi: preferisco risultati puliti, coerenti e duraturi, che funzionano davvero nella vita quotidiana.\nDall\u2019ideazione alla realizzazione, mi impegno a curare ogni dettaglio, ascoltando attentamente le vostre esigenze per creare spazi unici.\n\nSe stai ristrutturando o vuoi valorizzare un immobile, posso affiancarti dalla progettazione alla direzione lavori, con un metodo chiaro e decisioni guidate da costi, tempi e qualit\u00e0.\n\nServizi:\n\t\u2022\t\u2022\tAnalisi tecnica dell\u2019immobile preliminare all\u2019acquisto per verifica criticit\u00e0, costi reali e potenziale di trasformazione\n\t\u2022\t\u2022\tProgettazione architettonica e interior design\n\t\u2022\t\u2022\tDirezione lavori e coordinamento imprese\n\t\u2022\t\u2022\tPratiche edilizie\n\t\u2022\t\u2022\tArredi su misura, materiali e illuminazione\n\n\nProgettazione spazi residenziali e professionali, architetto Carlo Ponzio, architettura e ingegneria edile, interventi residenziali e terziari, abitazioni, uffici, attivit\u00e0 commerciali, studi professionali, estetica e funzionalit\u00e0, layout, dettagli costruttivi, materiali e finiture, arredi su misura, illuminazione, impianti, ristrutturazione immobili, valorizzazione immobili, progettazione, direzione lavori, analisi tecnica immobile, trasformazione immobili, progettazione architettonica, interior design, pratiche edilizie, architetto, architetti, ristrutturazione, ristrutturazioni, ristrutturare, studio architettura, studio di architetti, studio di architettura, Milano, Pella,\nProgettazione spazi residenziali e professionali Milano, architetto Carlo Ponzio Milano, architettura e ingegneria edile Milano, interventi residenziali e terziari Milano, abitazioni Milano, uffici Milano, attivit\u00e0 commerciali Milano, studi professionali Milano, estetica e funzionalit\u00e0 Milano, layout Milano, dettagli costruttivi Milano, materiali e finiture Milano, arredi su misura Milano, illuminazione Milano, impianti Milano, ristrutturazione immobili Milano, valorizzazione immobili Milano, progettazione Milano, direzione lavori Milano, analisi tecnica immobile Milano, trasformazione immobili Milano, progettazione architettonica Milano, interior design Milano, pratiche edilizie Milano, architetto Milano, architetti Milano, ristrutturazione Milano, ristrutturazioni Milano, ristrutturare Milano, studio architettura Milano, studio di architetti Milano, studio di architettura Milano, \n\nProgettazione spazi residenziali e professionali a Milano, architetto Carlo Ponzio a Milano, architettura e ingegneria edile a Milano, interventi residenziali e terziari a Milano, abitazioni a Milano, uffici a Milano, attivit\u00e0 commerciali a Milano, studi professionali a Milano, estetica e funzionalit\u00e0 a Milano, layout a Milano, dettagli costruttivi a Milano, materiali e finiture a Milano, arredi su misura a Milano, illuminazione a Milano, impianti a Milano, ristrutturazione immobili a Milano, valorizzazione immobili a Milano, progettazione a Milano, direzione lavori a Milano, analisi tecnica immobile a Milano, trasformazione immobili a Milano, progettazione architettonica a Milano, interior design a Milano, pratiche edilizie a Milano, architetto a Milano, architetti a Milano, ristrutturazione a Milano, ristrutturazioni a Milano, ristrutturare a Milano, studio architettura a Milano, studio di architetti a Milano, studio di architettura a Milano, \n\nProgettazione spazi residenziali e professionali Pella, architetto Carlo Ponzio Pella, architettura e ingegneria edile Pella, interventi residenziali e terziari Pella, abitazioni Pella, uffici Pella, attivit\u00e0 commerciali Pella, studi professionali Pella, estetica e funzionalit\u00e0 Pella, layout Pella, dettagli costruttivi Pella, materiali e finiture Pella, arredi su misura Pella, illuminazione Pella, impianti Pella, ristrutturazione immobili Pella, valorizzazione immobili Pella, progettazione Pella, direzione lavori Pella, analisi tecnica immobile Pella, trasformazione immobili Pella, progettazione architettonica Pella, interior design Pella, pratiche edilizie Pella, architetto Pella, architetti Pella, ristrutturazione Pella, ristrutturazioni Pella, ristrutturare Pella, studio architettura Pella, studio di architetti Pella, studio di architettura Pella, \n\nProgettazione spazi residenziali e professionali a Pella, architetto Carlo Ponzio a Pella, architettura e ingegneria edile a Pella, interventi residenziali e terziari a Pella, abitazioni a Pella, uffici a Pella, attivit\u00e0 commerciali a Pella, studi professionali a Pella, estetica e funzionalit\u00e0 a Pella, layout a Pella, dettagli costruttivi a Pella, materiali e finiture a Pella, arredi su misura a Pella, illuminazione a Pella, impianti a Pella, ristrutturazione immobili a Pella, valorizzazione immobili a Pella, progettazione a Pella, direzione lavori a Pella, analisi tecnica immobile a Pella, trasformazione immobili a Pella, progettazione architettonica a Pella, interior design a Pella, pratiche edilizie a Pella, architetto a Pella, architetti a Pella, ristrutturazione a Pella, ristrutturazioni a Pella, ristrutturare a Pella, studio architettura a Pella, studio di architetti a Pella, studio di architettura a Pella, \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">Carlo Ponzio &#8211; Architetto<br \/>\nProgetto spazi residenziali e professionali dove estetica e fattibilit\u00e0 vanno d\u2019accordo.\u2028Sono Carlo Ponzio, architetto (laurea in Architettura e Ingegneria Edile al Politecnico di Milano). Dal 2006 seguo interventi in ambito residenziale e terziario: abitazioni, uffici, attivit\u00e0 commerciali e studi professionali.Il mio approccio \u00e8 semplice: ogni scelta deve essere bella, funzionale e cantierabile. Per questo lavoro in modo rigoroso su layout, dettagli costruttivi, materiali e finiture, coordinando arredi su misura, illuminazione e impianti. L\u2019obiettivo \u00e8 evitare soluzioni \u201cdi effetto\u201d che poi diventino problemi: preferisco risultati puliti, coerenti e duraturi, che funzionano davvero nella vita quotidiana.<br \/>\nDall\u2019ideazione alla realizzazione, mi impegno a curare ogni dettaglio, ascoltando attentamente le vostre esigenze per creare spazi unici.<\/p>\n<p>Se stai ristrutturando o vuoi valorizzare un immobile, posso affiancarti dalla progettazione alla direzione lavori, con un metodo chiaro e decisioni guidate da costi, tempi e qualit\u00e0.<\/p>\n<p>Servizi:<br \/>\n\u2022 \u2022 Analisi tecnica dell\u2019immobile preliminare all\u2019acquisto per verifica criticit\u00e0, costi reali e potenziale di trasformazione<br \/>\n\u2022 \u2022 Progettazione architettonica e interior design<br \/>\n\u2022 \u2022 Direzione lavori e coordinamento imprese<br \/>\n\u2022 \u2022 Pratiche edilizie<br \/>\n\u2022 \u2022 Arredi su misura, materiali e illuminazione<\/p>\n<p>Progettazione spazi residenziali e professionali, architetto Carlo Ponzio, architettura e ingegneria edile, interventi residenziali e terziari, abitazioni, uffici, attivit\u00e0 commerciali, studi professionali, estetica e funzionalit\u00e0, layout, dettagli costruttivi, materiali e finiture, arredi su misura, illuminazione, impianti, ristrutturazione immobili, valorizzazione immobili, progettazione, direzione lavori, analisi tecnica immobile, trasformazione immobili, progettazione architettonica, interior design, pratiche edilizie, architetto, architetti, ristrutturazione, ristrutturazioni, ristrutturare, studio architettura, studio di architetti, studio di architettura, Milano, Pella,<br \/>\nProgettazione spazi residenziali e professionali Milano, architetto Carlo Ponzio Milano, architettura e ingegneria edile Milano, interventi residenziali e terziari Milano, abitazioni Milano, uffici Milano, attivit\u00e0 commerciali Milano, studi professionali Milano, estetica e funzionalit\u00e0 Milano, layout Milano, dettagli costruttivi Milano, materiali e finiture Milano, arredi su misura Milano, illuminazione Milano, impianti Milano, ristrutturazione immobili Milano, valorizzazione immobili Milano, progettazione Milano, direzione lavori Milano, analisi tecnica immobile Milano, trasformazione immobili Milano, progettazione architettonica Milano, interior design Milano, pratiche edilizie Milano, architetto Milano, architetti Milano, ristrutturazione Milano, ristrutturazioni Milano, ristrutturare Milano, studio architettura Milano, studio di architetti Milano, studio di architettura Milano,<\/p>\n<p>Progettazione spazi residenziali e professionali a Milano, architetto Carlo Ponzio a Milano, architettura e ingegneria edile a Milano, interventi residenziali e terziari a Milano, abitazioni a Milano, uffici a Milano, attivit\u00e0 commerciali a Milano, studi professionali a Milano, estetica e funzionalit\u00e0 a Milano, layout a Milano, dettagli costruttivi a Milano, materiali e finiture a Milano, arredi su misura a Milano, illuminazione a Milano, impianti a Milano, ristrutturazione immobili a Milano, valorizzazione immobili a Milano, progettazione a Milano, direzione lavori a Milano, analisi tecnica immobile a Milano, trasformazione immobili a Milano, progettazione architettonica a Milano, interior design a Milano, pratiche edilizie a Milano, architetto a Milano, architetti a Milano, ristrutturazione a Milano, ristrutturazioni a Milano, ristrutturare a Milano, studio architettura a Milano, studio di architetti a Milano, studio di architettura a Milano,<\/p>\n<p>Progettazione spazi residenziali e professionali Pella, architetto Carlo Ponzio Pella, architettura e ingegneria edile Pella, interventi residenziali e terziari Pella, abitazioni Pella, uffici Pella, attivit\u00e0 commerciali Pella, studi professionali Pella, estetica e funzionalit\u00e0 Pella, layout Pella, dettagli costruttivi Pella, materiali e finiture Pella, arredi su misura Pella, illuminazione Pella, impianti Pella, ristrutturazione immobili Pella, valorizzazione immobili Pella, progettazione Pella, direzione lavori Pella, analisi tecnica immobile Pella, trasformazione immobili Pella, progettazione architettonica Pella, interior design Pella, pratiche edilizie Pella, architetto Pella, architetti Pella, ristrutturazione Pella, ristrutturazioni Pella, ristrutturare Pella, studio architettura Pella, studio di architetti Pella, studio di architettura Pella,<\/p>\n<p>Progettazione spazi residenziali e professionali a Pella, architetto Carlo Ponzio a Pella, architettura e ingegneria edile a Pella, interventi residenziali e terziari a Pella, abitazioni a Pella, uffici a Pella, attivit\u00e0 commerciali a Pella, studi professionali a Pella, estetica e funzionalit\u00e0 a Pella, layout a Pella, dettagli costruttivi a Pella, materiali e finiture a Pella, arredi su misura a Pella, illuminazione a Pella, impianti a Pella, ristrutturazione immobili a Pella, valorizzazione immobili a Pella, progettazione a Pella, direzione lavori a Pella, analisi tecnica immobile a Pella, trasformazione immobili a Pella, progettazione architettonica a Pella, interior design a Pella, pratiche edilizie a Pella, architetto a Pella, architetti a Pella, ristrutturazione a Pella, ristrutturazioni a Pella, ristrutturare a Pella, studio architettura a Pella, studio di architetti a Pella, studio di architettura a Pella,<\/p>\n<\/div>\n","protected":false},"featured_media":32481,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[8791,68,21,1392,25],"product_tag":[8796,8805,636,8808,8793,8794,2661,8586,8814,8800,8804,8798,3104,689,534,8795,8799,8801,288,8813,2983,639,8807,8792,8809,932,8802,688,8724,8810,8811,8812,8806,8797,8803],"class_list":{"0":"post-32431","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-architetti","7":"product_cat-arredamenti","8":"product_cat-casa","9":"product_cat-interior-design","10":"product_cat-professionisti-studio-consulenze","11":"product_tag-abitazioni","12":"product_tag-analisi-tecnica-immobile","13":"product_tag-architetti","14":"product_tag-architetto","15":"product_tag-architetto-carlo-ponzio","16":"product_tag-architettura-e-ingegneria-edile","17":"product_tag-arredi-su-misura","18":"product_tag-attivita-commerciali","19":"product_tag-carlo-ponzio-architetto","20":"product_tag-dettagli-costruttivi","21":"product_tag-direzione-lavori","22":"product_tag-estetica-e-funzionalita","23":"product_tag-illuminazione","24":"product_tag-impianti","25":"product_tag-interior-design","26":"product_tag-interventi-residenziali-e-terziari","27":"product_tag-layout","28":"product_tag-materiali-e-finiture","29":"product_tag-milano","30":"product_tag-pella","31":"product_tag-pratiche-edilizie","32":"product_tag-progettazione","33":"product_tag-progettazione-architettonica","34":"product_tag-progettazione-spazi-residenziali-e-professionali","35":"product_tag-ristrutturare","36":"product_tag-ristrutturazione","37":"product_tag-ristrutturazione-immobili","38":"product_tag-ristrutturazioni","39":"product_tag-studi-professionali","40":"product_tag-studio-architettura","41":"product_tag-studio-di-architetti","42":"product_tag-studio-di-architettura","43":"product_tag-trasformazione-immobili","44":"product_tag-uffici","45":"product_tag-valorizzazione-immobili","47":"first","48":"instock","49":"shipping-taxable","50":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carlo Ponzio - Architetto - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlo Ponzio - Architetto - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Carlo Ponzio - Architetto Progetto spazi residenziali e professionali dove estetica e fattibilit\u00e0 vanno d\u2019accordo.\u2028Sono Carlo Ponzio, architetto (laurea in Architettura e Ingegneria Edile al Politecnico di Milano). Dal 2006 seguo interventi in ambito residenziale e terziario: abitazioni, uffici, attivit\u00e0 commerciali e studi professionali.Il mio approccio \u00e8 semplice: ogni scelta deve essere bella, funzionale e cantierabile. Per questo lavoro in modo rigoroso su layout, dettagli costruttivi, materiali e finiture, coordinando arredi su misura, illuminazione e impianti. L\u2019obiettivo \u00e8 evitare soluzioni \u201cdi effetto\u201d che poi diventino problemi: preferisco risultati puliti, coerenti e duraturi, che funzionano davvero nella vita quotidiana. Dall\u2019ideazione alla realizzazione, mi impegno a curare ogni dettaglio, ascoltando attentamente le vostre esigenze per creare spazi unici.  Se stai ristrutturando o vuoi valorizzare un immobile, posso affiancarti dalla progettazione alla direzione lavori, con un metodo chiaro e decisioni guidate da costi, tempi e qualit\u00e0.  Servizi: \u2022 \u2022 Analisi tecnica dell\u2019immobile preliminare all\u2019acquisto per verifica criticit\u00e0, costi reali e potenziale di trasformazione \u2022 \u2022 Progettazione architettonica e interior design \u2022 \u2022 Direzione lavori e coordinamento imprese \u2022 \u2022 Pratiche edilizie \u2022 \u2022 Arredi su misura, materiali e illuminazione  Progettazione spazi residenziali e professionali, architetto Carlo Ponzio, architettura e ingegneria edile, interventi residenziali e terziari, abitazioni, uffici, attivit\u00e0 commerciali, studi professionali, estetica e funzionalit\u00e0, layout, dettagli costruttivi, materiali e finiture, arredi su misura, illuminazione, impianti, ristrutturazione immobili, valorizzazione immobili, progettazione, direzione lavori, analisi tecnica immobile, trasformazione immobili, progettazione architettonica, interior design, pratiche edilizie, architetto, architetti, ristrutturazione, ristrutturazioni, ristrutturare, studio architettura, studio di architetti, studio di architettura, Milano, Pella, Progettazione spazi residenziali e professionali Milano, architetto Carlo Ponzio Milano, architettura e ingegneria edile Milano, interventi residenziali e terziari Milano, abitazioni Milano, uffici Milano, attivit\u00e0 commerciali Milano, studi professionali Milano, estetica e funzionalit\u00e0 Milano, layout Milano, dettagli costruttivi Milano, materiali e finiture Milano, arredi su misura Milano, illuminazione Milano, impianti Milano, ristrutturazione immobili Milano, valorizzazione immobili Milano, progettazione Milano, direzione lavori Milano, analisi tecnica immobile Milano, trasformazione immobili Milano, progettazione architettonica Milano, interior design Milano, pratiche edilizie Milano, architetto Milano, architetti Milano, ristrutturazione Milano, ristrutturazioni Milano, ristrutturare Milano, studio architettura Milano, studio di architetti Milano, studio di architettura Milano,  Progettazione spazi residenziali e professionali a Milano, architetto Carlo Ponzio a Milano, architettura e ingegneria edile a Milano, interventi residenziali e terziari a Milano, abitazioni a Milano, uffici a Milano, attivit\u00e0 commerciali a Milano, studi professionali a Milano, estetica e funzionalit\u00e0 a Milano, layout a Milano, dettagli costruttivi a Milano, materiali e finiture a Milano, arredi su misura a Milano, illuminazione a Milano, impianti a Milano, ristrutturazione immobili a Milano, valorizzazione immobili a Milano, progettazione a Milano, direzione lavori a Milano, analisi tecnica immobile a Milano, trasformazione immobili a Milano, progettazione architettonica a Milano, interior design a Milano, pratiche edilizie a Milano, architetto a Milano, architetti a Milano, ristrutturazione a Milano, ristrutturazioni a Milano, ristrutturare a Milano, studio architettura a Milano, studio di architetti a Milano, studio di architettura a Milano,  Progettazione spazi residenziali e professionali Pella, architetto Carlo Ponzio Pella, architettura e ingegneria edile Pella, interventi residenziali e terziari Pella, abitazioni Pella, uffici Pella, attivit\u00e0 commerciali Pella, studi professionali Pella, estetica e funzionalit\u00e0 Pella, layout Pella, dettagli costruttivi Pella, materiali e finiture Pella, arredi su misura Pella, illuminazione Pella, impianti Pella, ristrutturazione immobili Pella, valorizzazione immobili Pella, progettazione Pella, direzione lavori Pella, analisi tecnica immobile Pella, trasformazione immobili Pella, progettazione architettonica Pella, interior design Pella, pratiche edilizie Pella, architetto Pella, architetti Pella, ristrutturazione Pella, ristrutturazioni Pella, ristrutturare Pella, studio architettura Pella, studio di architetti Pella, studio di architettura Pella,  Progettazione spazi residenziali e professionali a Pella, architetto Carlo Ponzio a Pella, architettura e ingegneria edile a Pella, interventi residenziali e terziari a Pella, abitazioni a Pella, uffici a Pella, attivit\u00e0 commerciali a Pella, studi professionali a Pella, estetica e funzionalit\u00e0 a Pella, layout a Pella, dettagli costruttivi a Pella, materiali e finiture a Pella, arredi su misura a Pella, illuminazione a Pella, impianti a Pella, ristrutturazione immobili a Pella, valorizzazione immobili a Pella, progettazione a Pella, direzione lavori a Pella, analisi tecnica immobile a Pella, trasformazione immobili a Pella, progettazione architettonica a Pella, interior design a Pella, pratiche edilizie a Pella, architetto a Pella, architetti a Pella, ristrutturazione a Pella, ristrutturazioni a Pella, ristrutturare a Pella, studio architettura a Pella, studio di architetti a Pella, studio di architettura a Pella,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T15:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/\",\"name\":\"Carlo Ponzio - Architetto - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png\",\"datePublished\":\"2026-05-05T12:46:06+00:00\",\"dateModified\":\"2026-05-05T15:32:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carlo Ponzio &#8211; Architetto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlo Ponzio - Architetto - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/","og_locale":"it_IT","og_type":"article","og_title":"Carlo Ponzio - Architetto - Cral Policlinico di Milano","og_description":"Carlo Ponzio - Architetto Progetto spazi residenziali e professionali dove estetica e fattibilit\u00e0 vanno d\u2019accordo.\u2028Sono Carlo Ponzio, architetto (laurea in Architettura e Ingegneria Edile al Politecnico di Milano). Dal 2006 seguo interventi in ambito residenziale e terziario: abitazioni, uffici, attivit\u00e0 commerciali e studi professionali.Il mio approccio \u00e8 semplice: ogni scelta deve essere bella, funzionale e cantierabile. Per questo lavoro in modo rigoroso su layout, dettagli costruttivi, materiali e finiture, coordinando arredi su misura, illuminazione e impianti. L\u2019obiettivo \u00e8 evitare soluzioni \u201cdi effetto\u201d che poi diventino problemi: preferisco risultati puliti, coerenti e duraturi, che funzionano davvero nella vita quotidiana. Dall\u2019ideazione alla realizzazione, mi impegno a curare ogni dettaglio, ascoltando attentamente le vostre esigenze per creare spazi unici.  Se stai ristrutturando o vuoi valorizzare un immobile, posso affiancarti dalla progettazione alla direzione lavori, con un metodo chiaro e decisioni guidate da costi, tempi e qualit\u00e0.  Servizi: \u2022 \u2022 Analisi tecnica dell\u2019immobile preliminare all\u2019acquisto per verifica criticit\u00e0, costi reali e potenziale di trasformazione \u2022 \u2022 Progettazione architettonica e interior design \u2022 \u2022 Direzione lavori e coordinamento imprese \u2022 \u2022 Pratiche edilizie \u2022 \u2022 Arredi su misura, materiali e illuminazione  Progettazione spazi residenziali e professionali, architetto Carlo Ponzio, architettura e ingegneria edile, interventi residenziali e terziari, abitazioni, uffici, attivit\u00e0 commerciali, studi professionali, estetica e funzionalit\u00e0, layout, dettagli costruttivi, materiali e finiture, arredi su misura, illuminazione, impianti, ristrutturazione immobili, valorizzazione immobili, progettazione, direzione lavori, analisi tecnica immobile, trasformazione immobili, progettazione architettonica, interior design, pratiche edilizie, architetto, architetti, ristrutturazione, ristrutturazioni, ristrutturare, studio architettura, studio di architetti, studio di architettura, Milano, Pella, Progettazione spazi residenziali e professionali Milano, architetto Carlo Ponzio Milano, architettura e ingegneria edile Milano, interventi residenziali e terziari Milano, abitazioni Milano, uffici Milano, attivit\u00e0 commerciali Milano, studi professionali Milano, estetica e funzionalit\u00e0 Milano, layout Milano, dettagli costruttivi Milano, materiali e finiture Milano, arredi su misura Milano, illuminazione Milano, impianti Milano, ristrutturazione immobili Milano, valorizzazione immobili Milano, progettazione Milano, direzione lavori Milano, analisi tecnica immobile Milano, trasformazione immobili Milano, progettazione architettonica Milano, interior design Milano, pratiche edilizie Milano, architetto Milano, architetti Milano, ristrutturazione Milano, ristrutturazioni Milano, ristrutturare Milano, studio architettura Milano, studio di architetti Milano, studio di architettura Milano,  Progettazione spazi residenziali e professionali a Milano, architetto Carlo Ponzio a Milano, architettura e ingegneria edile a Milano, interventi residenziali e terziari a Milano, abitazioni a Milano, uffici a Milano, attivit\u00e0 commerciali a Milano, studi professionali a Milano, estetica e funzionalit\u00e0 a Milano, layout a Milano, dettagli costruttivi a Milano, materiali e finiture a Milano, arredi su misura a Milano, illuminazione a Milano, impianti a Milano, ristrutturazione immobili a Milano, valorizzazione immobili a Milano, progettazione a Milano, direzione lavori a Milano, analisi tecnica immobile a Milano, trasformazione immobili a Milano, progettazione architettonica a Milano, interior design a Milano, pratiche edilizie a Milano, architetto a Milano, architetti a Milano, ristrutturazione a Milano, ristrutturazioni a Milano, ristrutturare a Milano, studio architettura a Milano, studio di architetti a Milano, studio di architettura a Milano,  Progettazione spazi residenziali e professionali Pella, architetto Carlo Ponzio Pella, architettura e ingegneria edile Pella, interventi residenziali e terziari Pella, abitazioni Pella, uffici Pella, attivit\u00e0 commerciali Pella, studi professionali Pella, estetica e funzionalit\u00e0 Pella, layout Pella, dettagli costruttivi Pella, materiali e finiture Pella, arredi su misura Pella, illuminazione Pella, impianti Pella, ristrutturazione immobili Pella, valorizzazione immobili Pella, progettazione Pella, direzione lavori Pella, analisi tecnica immobile Pella, trasformazione immobili Pella, progettazione architettonica Pella, interior design Pella, pratiche edilizie Pella, architetto Pella, architetti Pella, ristrutturazione Pella, ristrutturazioni Pella, ristrutturare Pella, studio architettura Pella, studio di architetti Pella, studio di architettura Pella,  Progettazione spazi residenziali e professionali a Pella, architetto Carlo Ponzio a Pella, architettura e ingegneria edile a Pella, interventi residenziali e terziari a Pella, abitazioni a Pella, uffici a Pella, attivit\u00e0 commerciali a Pella, studi professionali a Pella, estetica e funzionalit\u00e0 a Pella, layout a Pella, dettagli costruttivi a Pella, materiali e finiture a Pella, arredi su misura a Pella, illuminazione a Pella, impianti a Pella, ristrutturazione immobili a Pella, valorizzazione immobili a Pella, progettazione a Pella, direzione lavori a Pella, analisi tecnica immobile a Pella, trasformazione immobili a Pella, progettazione architettonica a Pella, interior design a Pella, pratiche edilizie a Pella, architetto a Pella, architetti a Pella, ristrutturazione a Pella, ristrutturazioni a Pella, ristrutturare a Pella, studio architettura a Pella, studio di architetti a Pella, studio di architettura a Pella,","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-05-05T15:32:02+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/","name":"Carlo Ponzio - Architetto - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png","datePublished":"2026-05-05T12:46:06+00:00","dateModified":"2026-05-05T15:32:02+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/05\/Logo-siti-carlo-ponzio.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/carlo-ponzio-architetto-milano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Carlo Ponzio &#8211; Architetto"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/32431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=32431"}],"version-history":[{"count":77,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/32431\/revisions"}],"predecessor-version":[{"id":32634,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/32431\/revisions\/32634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/32481"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=32431"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=32431"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=32431"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=32431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}