{"id":30575,"date":"2026-04-03T10:17:38","date_gmt":"2026-04-03T08:17:38","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=30575"},"modified":"2026-04-08T15:05:18","modified_gmt":"2026-04-08T13:05:18","slug":"phidia-hub","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/","title":{"rendered":"Phidia Hub"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"30575\" class=\"elementor elementor-30575\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ae3b87 e-flex e-con-boxed e-con e-parent\" data-id=\"9ae3b87\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea91943 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"ea91943\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"326\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-scaled.png\" class=\"attachment-full size-full wp-image-30579\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-scaled.png 2560w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-1280x163.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-980x125.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-480x61.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-115d100 e-flex e-con-boxed e-con e-parent\" data-id=\"115d100\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b0bc4e1 e-con-full e-flex e-con e-child\" data-id=\"b0bc4e1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66923f9 elementor-widget elementor-widget-text-editor\" data-id=\"66923f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fac272 elementor-widget elementor-widget-text-editor\" data-id=\"1fac272\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Phidia Hub \u00e8 una piattaforma pensata per accompagnare le persone in un percorso di benessere completo, offrendo un supporto a 360 gradi grazie alla collaborazione di diversi professionisti specializzati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f50d4f elementor-widget elementor-widget-text-editor\" data-id=\"3f50d4f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>All&#8217;interno della piattaforma, il cliente pu\u00f2 accedere a diversi specialisti che lavorano singolarmente o collaborano tra loro: <b>nutrizionisti<\/b>, <b>psicologi<\/b>, <b>mental coach<\/b>, <b>fisioterapisti<\/b>, <b>personal trainer<\/b>, insegnanti di <b>yoga <\/b>e altri professionisti del benessere.&nbsp;<\/p>\n<p>Questo approccio permette di creare percorsi personalizzati e integrati. <br>La prenotazione \u00e8 facile e veloce e il cliente ricever\u00e0 delle email con i link di pagamento\/consenso informato\/collegamento alla videocall.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36a137f elementor-widget elementor-widget-button\" data-id=\"36a137f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.phidiahub.com\/prenota\/#book-now\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">prenota ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d1585 elementor-widget elementor-widget-text-editor\" data-id=\"17d1585\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri servizi per il tuo benessere<br \/>Un approccio integrato che unisce corpo, mente e nutrizione.<br \/>Professionisti qualificati, percorsi personalizzati, benessere accessibile.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ca9494 elementor-widget elementor-widget-text-editor\" data-id=\"8ca9494\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Uno dei grandi punti di forza di Phidia Hub \u00e8 la possibilit\u00e0 di essere seguiti completamente da remoto. <br \/><\/b>Attraverso videocall e strumenti digitali, il cliente pu\u00f2 fare allenamenti con un personal trainer direttamente da casa, partecipare a sessioni di yoga guidate, seguire programmi di recupero fisico o ricevere consulenze dedicate, senza la necessit\u00e0 di spostarsi.<br \/>Permettendo continuit\u00e0 ad ogni percorso personale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21ddc43 e-con-full e-flex e-con e-child\" data-id=\"21ddc43\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c56b38 elementor-widget elementor-widget-spacer\" data-id=\"3c56b38\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e84290a e-con-full e-flex e-con e-child\" data-id=\"e84290a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3427125 elementor-widget elementor-widget-text-editor\" data-id=\"3427125\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri servizi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2397260 elementor-widget elementor-widget-text-editor\" data-id=\"2397260\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 nutrizione<br \/>\u2022 psicologia e mindfulness<br \/>\u2022 mental coach<br \/>\u2022 valutazione biomeccanica della corsa<br \/>\u2022 allenamento funzionale e preparazione atletica<br \/>\u2022 fisioterapia<br \/>\u2022 yoga<br \/>\u2022 consulenza gestine cavo orale in et\u00e0 pediatrica e in gravidanza<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cc2356 elementor-widget elementor-widget-button\" data-id=\"3cc2356\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.phidiahub.com\/servizi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">scopri i professionisti<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-155b9ab e-con-full e-flex e-con e-parent\" data-id=\"155b9ab\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9883590 e-con-full e-flex e-con e-child\" data-id=\"9883590\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c1a5ef7 e-flex e-con-boxed e-con e-child\" data-id=\"c1a5ef7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0e7f50 elementor-widget elementor-widget-text-editor\" data-id=\"a0e7f50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SCONTO ESCLUSIVO <br \/>DEL 10% PER GLI ASSOCIATI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78b0f0d elementor-widget elementor-widget-text-editor\" data-id=\"78b0f0d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tutti i servizi a un prezzo speciale: subito il 10% di sconto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa23194 elementor-widget elementor-widget-text-editor\" data-id=\"fa23194\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dopo la prenotazione riceverai una mail con il <strong>Link to Pay<\/strong> e le indicazioni dedicate ai <strong>Soci CRAL<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31bbfaf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"31bbfaf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.phidiahub.com\/prenota\/#book-now\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">prenota ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-118b145 e-con-full e-flex e-con e-child\" data-id=\"118b145\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-064bdf2 elementor-widget elementor-widget-spacer\" data-id=\"064bdf2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eeb038e e-flex e-con-boxed e-con e-parent\" data-id=\"eeb038e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-593c3f8 e-con-full e-flex e-con e-child\" data-id=\"593c3f8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d755f6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3d755f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"326\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-scaled.png\" class=\"attachment-full size-full wp-image-30579\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-scaled.png 2560w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-1280x163.png 1280w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-980x125.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/Footer-Logo-480x61.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0eff50 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a0eff50\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97ed619 elementor-widget elementor-widget-text-editor\" data-id=\"97ed619\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Scopri il tuo percorso di benessere su Phidia Hub<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9a48c elementor-widget elementor-widget-text-editor\" data-id=\"1c9a48c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Su Phidia Hub trovi tutto ci\u00f2 che ti serve per il tuo benessere: corpo, mente e nutrizione in un unico percorso integrato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb62115 elementor-widget elementor-widget-text-editor\" data-id=\"fb62115\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.phidiahub.com\/\">www.phidiahub.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02abb57 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"02abb57\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91eceb8 elementor-widget elementor-widget-text-editor\" data-id=\"91eceb8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&lt;div style= &#8220;display: none&#8221;&gt;<\/p><p><br \/>Phidia Hub \u00e8 una piattaforma pensata per accompagnare le persone in un percorso di benessere completo, offrendo un supporto a 360 gradi grazie alla collaborazione di diversi professionisti specializzati<br \/>All&#8217;interno della piattaforma, il cliente pu\u00f2 accedere a diversi specialisti che lavorano singolarmente o collaborano tra loro: nutrizionisti, psicologi, mental coach, fisioterapisti, personal trainer, insegnanti di yoga e altri professionisti del benessere. Questo approccio permette di creare percorsi personalizzati e integrati. La prenotazione \u00e8 facile e veloce e il cliente ricever\u00e0 delle email con i link di pagamento\/consenso informato\/collegamento alla videocall<br \/>I nostri servizi per il tuo benessere<br \/>Un approccio integrato che unisce corpo, mente e nutrizione.<br \/>Professionisti qualificati, percorsi personalizzati, benessere accessibile.<br \/>Uno dei grandi punti di forza di Phidia Hub \u00e8 la possibilit\u00e0 di essere seguiti completamente da remoto. Attraverso videocall e strumenti digitali, il cliente pu\u00f2 fare allenamenti con un personal trainer direttamente da casa, partecipare a sessioni di yoga guidate, seguire programmi di recupero fisico o ricevere consulenze dedicate, senza la necessit\u00e0 di spostarsi.<br \/>Permettendo continuit\u00e0 ad ogni percorso personale<br \/>I NOSTRI SERVIZI<br \/>\u2022 NUTRIZIONE<br \/>\u2022 PSICOLOGIA E MINDFULNESS<br \/>\u2022 MENTAL COACH<br \/>VALUTAZIONE BIOMECCANICA DELLA CORSA<br \/>\u2022 ALLENAMENTO FUNZIONALE E PREPARAZIONE ATLETICA<br \/>\u2022 FISIOTERAPIA<br \/>\u2022 YOGA<br \/>\u2022 CONSULENZA GESTINE CAVO ORALE IN ET\u00c0 PEDIATRICA E IN GRAVIDANZA<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><br \/>piattaforma benessere, corpo mente nutrizione, professionisti del benessere online, nutrizionista online, psicologo online, mindfulness online, mental coach online, fisioterapia a distanza, personal trainer online, lezioni di yoga online, allenamento funzionale da casa, preparazione atletica personalizzata, valutazione biomeccanica della corsa, consulenza igiene orale pediatrica, consulenza gestione cavo orale in gravidanza, percorsi di benessere personalizzati, benessere accessibile da remoto, prenotazione specialisti benessere, videoconsulenza nutrizionale, supporto psicologico digitale, programmi di recupero fisico online, coaching per il benessere, continuit\u00e0 percorso benessere, specialisti della salute online, fitness coach personalizzato, consulenza multidisciplinare salute, portale servizi benessere, allenamento atletico remoto, salute olistica digitale<\/p><p><br \/>&lt;\/div&gt;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style= \"display: none\">\n<p>Phidia Hub \u00e8 una piattaforma pensata per accompagnare le persone in un percorso di benessere completo, offrendo un supporto a 360 gradi grazie alla collaborazione di diversi professionisti specializzati<br \/>\nAll&#8217;interno della piattaforma, il cliente pu\u00f2 accedere a diversi specialisti che lavorano singolarmente o collaborano tra loro: nutrizionisti, psicologi, mental coach, fisioterapisti, personal trainer, insegnanti di yoga e altri professionisti del benessere. Questo approccio permette di creare percorsi personalizzati e integrati. La prenotazione \u00e8 facile e veloce e il cliente ricever\u00e0 delle email con i link di pagamento\/consenso informato\/collegamento alla videocall<br \/>\nI nostri servizi per il tuo benessere<br \/>\nUn approccio integrato che unisce corpo, mente e nutrizione.<br \/>\nProfessionisti qualificati, percorsi personalizzati, benessere accessibile.<br \/>\nUno dei grandi punti di forza di Phidia Hub \u00e8 la possibilit\u00e0 di essere seguiti completamente da remoto. Attraverso videocall e strumenti digitali, il cliente pu\u00f2 fare allenamenti con un personal trainer direttamente da casa, partecipare a sessioni di yoga guidate, seguire programmi di recupero fisico o ricevere consulenze dedicate, senza la necessit\u00e0 di spostarsi.<br \/>\nPermettendo continuit\u00e0 ad ogni percorso personale<br \/>\nI NOSTRI SERVIZI<br \/>\n\u2022 NUTRIZIONE<br \/>\n\u2022 PSICOLOGIA E MINDFULNESS<br \/>\n\u2022 MENTAL COACH<br \/>\nVALUTAZIONE BIOMECCANICA DELLA CORSA<br \/>\n\u2022 ALLENAMENTO FUNZIONALE E PREPARAZIONE ATLETICA<br \/>\n\u2022 FISIOTERAPIA<br \/>\n\u2022 YOGA<br \/>\n\u2022 CONSULENZA GESTINE CAVO ORALE IN ET\u00c0 PEDIATRICA E IN GRAVIDANZA<\/p>\n<p>piattaforma benessere, corpo mente nutrizione, professionisti del benessere online, nutrizionista online, psicologo online, mindfulness online, mental coach online, fisioterapia a distanza, personal trainer online, lezioni di yoga online, allenamento funzionale da casa, preparazione atletica personalizzata, valutazione biomeccanica della corsa, consulenza igiene orale pediatrica, consulenza gestione cavo orale in gravidanza, percorsi di benessere personalizzati, benessere accessibile da remoto, prenotazione specialisti benessere, videoconsulenza nutrizionale, supporto psicologico digitale, programmi di recupero fisico online, coaching per il benessere, continuit\u00e0 percorso benessere, specialisti della salute online, fitness coach personalizzato, consulenza multidisciplinare salute, portale servizi benessere, allenamento atletico remoto, salute olistica digitale<\/p>\n<\/div>\n","protected":false},"featured_media":30576,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[267,652,143,718,148,273,161,26,29],"product_tag":[7734,7717,7723,7728,7721,7720,7732,7729,7709,7715,7731,7716,7714,7713,7711,7722,6062,7708,7733,7724,7718,7710,7727,7712,7735,7730,7726,7719,7725],"class_list":{"0":"post-30575","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-centri-yoga","7":"product_cat-coaching","8":"product_cat-fisioterapisti","9":"product_cat-life-coach-mindfulness","10":"product_cat-nutrizionisti","11":"product_cat-personal-trainer","12":"product_cat-psicologi","13":"product_cat-salute","14":"product_cat-sport-tempo-libero","15":"product_tag-allenamento-atletico-remoto","16":"product_tag-allenamento-funzionale-da-casa","17":"product_tag-benessere-accessibile-da-remoto","18":"product_tag-coaching-per-il-benessere","19":"product_tag-consulenza-gestione-cavo-orale-in-gravidanza","20":"product_tag-consulenza-igiene-orale-pediatrica","21":"product_tag-consulenza-multidisciplinare-salute","22":"product_tag-continuita-percorso-benessere","23":"product_tag-corpo-mente-nutrizione","24":"product_tag-fisioterapia-a-distanza","25":"product_tag-fitness-coach-personalizzato","26":"product_tag-lezioni-di-yoga-online","27":"product_tag-mental-coach-online","28":"product_tag-mindfulness-online","29":"product_tag-nutrizionista-online","30":"product_tag-percorsi-di-benessere-personalizzati","31":"product_tag-personal-trainer-online","32":"product_tag-piattaforma-benessere","33":"product_tag-portale-servizi-benessere","34":"product_tag-prenotazione-specialisti-benessere","35":"product_tag-preparazione-atletica-personalizzata","36":"product_tag-professionisti-del-benessere-online","37":"product_tag-programmi-di-recupero-fisico-online","38":"product_tag-psicologo-online","39":"product_tag-salute-olistica-digitale","40":"product_tag-specialisti-della-salute-online","41":"product_tag-supporto-psicologico-digitale","42":"product_tag-valutazione-biomeccanica-della-corsa","43":"product_tag-videoconsulenza-nutrizionale","45":"first","46":"instock","47":"shipping-taxable","48":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Phidia Hub - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Phidia Hub - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"Phidia Hub \u00e8 una piattaforma pensata per accompagnare le persone in un percorso di benessere completo, offrendo un supporto a 360 gradi grazie alla collaborazione di diversi professionisti specializzati All&#039;interno della piattaforma, il cliente pu\u00f2 accedere a diversi specialisti che lavorano singolarmente o collaborano tra loro: nutrizionisti, psicologi, mental coach, fisioterapisti, personal trainer, insegnanti di yoga e altri professionisti del benessere. Questo approccio permette di creare percorsi personalizzati e integrati. La prenotazione \u00e8 facile e veloce e il cliente ricever\u00e0 delle email con i link di pagamento\/consenso informato\/collegamento alla videocall I nostri servizi per il tuo benessere Un approccio integrato che unisce corpo, mente e nutrizione. Professionisti qualificati, percorsi personalizzati, benessere accessibile. Uno dei grandi punti di forza di Phidia Hub \u00e8 la possibilit\u00e0 di essere seguiti completamente da remoto. Attraverso videocall e strumenti digitali, il cliente pu\u00f2 fare allenamenti con un personal trainer direttamente da casa, partecipare a sessioni di yoga guidate, seguire programmi di recupero fisico o ricevere consulenze dedicate, senza la necessit\u00e0 di spostarsi. Permettendo continuit\u00e0 ad ogni percorso personale I NOSTRI SERVIZI \u2022 NUTRIZIONE \u2022 PSICOLOGIA E MINDFULNESS \u2022 MENTAL COACH VALUTAZIONE BIOMECCANICA DELLA CORSA \u2022 ALLENAMENTO FUNZIONALE E PREPARAZIONE ATLETICA \u2022 FISIOTERAPIA \u2022 YOGA \u2022 CONSULENZA GESTINE CAVO ORALE IN ET\u00c0 PEDIATRICA E IN GRAVIDANZA       piattaforma benessere, corpo mente nutrizione, professionisti del benessere online, nutrizionista online, psicologo online, mindfulness online, mental coach online, fisioterapia a distanza, personal trainer online, lezioni di yoga online, allenamento funzionale da casa, preparazione atletica personalizzata, valutazione biomeccanica della corsa, consulenza igiene orale pediatrica, consulenza gestione cavo orale in gravidanza, percorsi di benessere personalizzati, benessere accessibile da remoto, prenotazione specialisti benessere, videoconsulenza nutrizionale, supporto psicologico digitale, programmi di recupero fisico online, coaching per il benessere, continuit\u00e0 percorso benessere, specialisti della salute online, fitness coach personalizzato, consulenza multidisciplinare salute, portale servizi benessere, allenamento atletico remoto, salute olistica digitale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T13:05:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/\",\"name\":\"Phidia Hub - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg\",\"datePublished\":\"2026-04-03T08:17:38+00:00\",\"dateModified\":\"2026-04-08T13:05:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Phidia Hub\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Phidia Hub - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/","og_locale":"it_IT","og_type":"article","og_title":"Phidia Hub - Cral Policlinico di Milano","og_description":"Phidia Hub \u00e8 una piattaforma pensata per accompagnare le persone in un percorso di benessere completo, offrendo un supporto a 360 gradi grazie alla collaborazione di diversi professionisti specializzati All'interno della piattaforma, il cliente pu\u00f2 accedere a diversi specialisti che lavorano singolarmente o collaborano tra loro: nutrizionisti, psicologi, mental coach, fisioterapisti, personal trainer, insegnanti di yoga e altri professionisti del benessere. Questo approccio permette di creare percorsi personalizzati e integrati. La prenotazione \u00e8 facile e veloce e il cliente ricever\u00e0 delle email con i link di pagamento\/consenso informato\/collegamento alla videocall I nostri servizi per il tuo benessere Un approccio integrato che unisce corpo, mente e nutrizione. Professionisti qualificati, percorsi personalizzati, benessere accessibile. Uno dei grandi punti di forza di Phidia Hub \u00e8 la possibilit\u00e0 di essere seguiti completamente da remoto. Attraverso videocall e strumenti digitali, il cliente pu\u00f2 fare allenamenti con un personal trainer direttamente da casa, partecipare a sessioni di yoga guidate, seguire programmi di recupero fisico o ricevere consulenze dedicate, senza la necessit\u00e0 di spostarsi. Permettendo continuit\u00e0 ad ogni percorso personale I NOSTRI SERVIZI \u2022 NUTRIZIONE \u2022 PSICOLOGIA E MINDFULNESS \u2022 MENTAL COACH VALUTAZIONE BIOMECCANICA DELLA CORSA \u2022 ALLENAMENTO FUNZIONALE E PREPARAZIONE ATLETICA \u2022 FISIOTERAPIA \u2022 YOGA \u2022 CONSULENZA GESTINE CAVO ORALE IN ET\u00c0 PEDIATRICA E IN GRAVIDANZA       piattaforma benessere, corpo mente nutrizione, professionisti del benessere online, nutrizionista online, psicologo online, mindfulness online, mental coach online, fisioterapia a distanza, personal trainer online, lezioni di yoga online, allenamento funzionale da casa, preparazione atletica personalizzata, valutazione biomeccanica della corsa, consulenza igiene orale pediatrica, consulenza gestione cavo orale in gravidanza, percorsi di benessere personalizzati, benessere accessibile da remoto, prenotazione specialisti benessere, videoconsulenza nutrizionale, supporto psicologico digitale, programmi di recupero fisico online, coaching per il benessere, continuit\u00e0 percorso benessere, specialisti della salute online, fitness coach personalizzato, consulenza multidisciplinare salute, portale servizi benessere, allenamento atletico remoto, salute olistica digitale","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-04-08T13:05:18+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/","name":"Phidia Hub - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg","datePublished":"2026-04-03T08:17:38+00:00","dateModified":"2026-04-08T13:05:18+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/04\/logo_phidia-hub.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/phidia-hub\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Phidia Hub"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/30575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=30575"}],"version-history":[{"count":25,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/30575\/revisions"}],"predecessor-version":[{"id":30607,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/30575\/revisions\/30607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/30576"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=30575"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=30575"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=30575"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=30575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}