{"id":30260,"date":"2026-03-30T11:45:50","date_gmt":"2026-03-30T09:45:50","guid":{"rendered":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?post_type=product&#038;p=30260"},"modified":"2026-05-26T15:18:32","modified_gmt":"2026-05-26T13:18:32","slug":"farmacia-del-naviglio","status":"publish","type":"product","link":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/","title":{"rendered":"Farmacia del Naviglio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"30260\" class=\"elementor elementor-30260\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e83cf88 e-con-full e-flex e-con e-parent\" data-id=\"e83cf88\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c1349ae e-con-full e-flex e-con e-child\" data-id=\"c1349ae\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-576cba3 e-con-full e-flex e-con e-child\" data-id=\"576cba3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aaed555 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"aaed555\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1184\" height=\"211\" src=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_naviglio.png\" class=\"attachment-full size-full wp-image-30265\" alt=\"\" srcset=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_naviglio.png 1184w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_naviglio-980x175.png 980w, https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_naviglio-480x86.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1184px, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9defa46 e-con-full e-flex e-con e-child\" data-id=\"9defa46\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff500fe elementor-widget elementor-widget-spacer\" data-id=\"ff500fe\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14f870c e-flex e-con-boxed e-con e-parent\" data-id=\"14f870c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f2b6a99 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"f2b6a99\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe75df6 elementor-widget elementor-widget-text-editor\" data-id=\"fe75df6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29bb30a elementor-widget elementor-widget-text-editor\" data-id=\"29bb30a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Farmacia del Naviglio \u00e8 una realt\u00e0 milanese a pochi passi dal Naviglio, con un vasto assortimento di farmaci, parafarmaci, prodotti omeopatici, fitoterapici, veterinari e cosmetici.<\/p><p>La nostra squadra di professionisti \u00e8 al tuo servizio: uno staff qualificato \u00e8 pronto ad ascoltarti dispensando consigli e suggerimenti adatti alla scelta del rimedio pi\u00f9 opportuno.<\/p><p>Il nostro obiettivo quotidiano \u00e8 quello di ricercare la soluzione pi\u00f9 adatta per ogni cliente offrendo nel contempo una serie di servizi dedicati ed esclusivi.<\/p><p>Nella nostra farmacia troverai sempre un perfetto connubio tra professionalit\u00e0 e gentilezza con personale dedicato alla nutraceutica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fcc319 e-con-full e-flex e-con e-child\" data-id=\"7fcc319\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4364c6 elementor-widget elementor-widget-spacer\" data-id=\"e4364c6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa614f1 e-con-full e-flex e-con e-child\" data-id=\"aa614f1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92df744 elementor-widget elementor-widget-text-editor\" data-id=\"92df744\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi siamo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c81446 elementor-widget elementor-widget-text-editor\" data-id=\"3c81446\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La <strong>Farmacia Del Naviglio &#8211; Apoteca Natura<\/strong> fa parte di un Network internazionale di Farmacie capaci di ascoltare e guidare le persone nel proprio percorso di Salute Consapevole, grazie alla specializzazione sulle principali esigenze di cura e prevenzione, alla costante ricerca di una piena integrazione nella filiera sanitaria e all\u2019accurata selezione dell\u2019offerta con un particolare focus sui prodotti naturali.\u00a0<\/p><p>Al centro di questo percorso la Persona, il rispetto del suo organismo e dell\u2019ambiente in cui vive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28cefd1 elementor-widget elementor-widget-text-editor\" data-id=\"28cefd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.apotecanatura.it\/\">www.apotecanatura.it<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f401cf8 e-con-full e-flex e-con e-child\" data-id=\"f401cf8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e23e38 elementor-widget elementor-widget-text-editor\" data-id=\"8e23e38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tConsulta i servizi a te dedicati\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c3b3ba elementor-widget elementor-widget-button\" data-id=\"9c3b3ba\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.farmaciadelnaviglio.it\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri di pi\u00f9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-402b446 e-con-full e-flex e-con e-child\" data-id=\"402b446\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37e81ce elementor-widget elementor-widget-text-editor\" data-id=\"37e81ce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri Reparti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c533696 elementor-widget elementor-widget-text-editor\" data-id=\"c533696\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Prodotti farmaceutici<\/strong><br \/>In Farmacia si trovano tutti gli articoli farmaceutici, con o senza prescrizione medica di diversa forma farmaceutica.<\/p><p><strong>Prodotti omeopatici<\/strong><br \/>Farmaci omeopatici e preparazioni galeniche a base di principi attivi naturali, sicuri e privi di effetti collaterali.<\/p><p><strong>Prodotti Cosmetici<\/strong><br \/>Cosmetici delle migliori marche: linee di eccellente qualit\u00e0, altamente tollerabili, efficaci e clinicamente testate, con principi attivi innovativi e ad azione intensiva specifiche per viso e corpo.<\/p><p><strong>Prodotti sanitari<\/strong><br \/>Presidi medico-sanitari per riabilitazione, auto-medicazione e auto-misurazione, apparecchi elettromedicali, prodotti ortopedici e molto altro.<\/p><p><strong>Prodotti fitoterapici<\/strong><br \/>Disponiamo di una variet\u00e0 di linee di prodotti fitoterapici, contenenti i principi attivi delle erbe, estratti e titolati con le tecniche pi\u00f9 moderne per ottenere il meglio dalla natura.<\/p><p><strong>Prodotti per diabetici<\/strong><br \/>Prodotti senza zuccheri aggiunti e a basso indice glicemico, dedicati a persone di tutte le et\u00e0 che hanno la necessit\u00e0 di controllare i livelli di glicemia nel sangue.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1132705 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1132705\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66ff10e\" data-id=\"66ff10e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5c1990 elementor-widget elementor-widget-text-editor\" data-id=\"d5c1990\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agevolazioni riservate agli associati<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1ab9ad6 e-flex e-con-boxed e-con e-parent\" data-id=\"1ab9ad6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-61ce152 e-con-full e-flex e-con e-child\" data-id=\"61ce152\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4c3b12 elementor-widget elementor-widget-text-editor\" data-id=\"b4c3b12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Farmacia del Naviglio<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56086be elementor-widget elementor-widget-text-editor\" data-id=\"56086be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contatti<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c242223 elementor-widget elementor-widget-text-editor\" data-id=\"c242223\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Viale Carlo Troya, 11<br \/>20144 Milano (MI)<\/p><p><strong>Tel: <\/strong><a href=\"tel:+39024233779\">024233779<\/a><br \/><strong>Mail:<\/strong> <a href=\"mailto:farmacia.delnaviglio@apotecanatura.it\">farmacia.delnaviglio@apotecanatura.it<\/a><br \/><strong>Sito web: <\/strong><a href=\"https:\/\/www.farmaciadelnaviglio.it\/\">www.farmaciadelnaviglio.it<\/a><br \/><strong>Lun &#8211; Ven:<\/strong> 8:00 &#8211; 20:00<br \/><strong>Sab:<\/strong>\u00a09:00 &#8211; 13:00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7588721 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7588721\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-1539373\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=3500401106&#038;text&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-11d9277\" href=\"https:\/\/www.facebook.com\/farmaciadelnaviglio\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cc66f0 e-con-full e-flex e-con e-child\" data-id=\"2cc66f0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea93430 elementor-widget elementor-widget-text-editor\" data-id=\"ea93430\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div id=\"gmw-single-location-wrapper-189\" class=\"gmw-element-wrapper gmw-single-location-wrapper gmw-sl-wrapper gmw-sl-single-post-wrapper post \" object_type=\"post\" object_id=\"30260\"  style=\"width:100%\"><div class=\"gmw-sl-map-wrapper gmw-sl-element\"><div id=\"gmw-map-wrapper-189\" class=\"gmw-map-wrapper  sl single_location \" style=\"width:100%;height:300px;\"> <span id=\"gmw-resize-map-toggle-189\" class=\"gmw-resize-map-toggle gmw-icon-resize-full\" style=\"display:none;\" title=\"Resize map\"><\/span> <div id=\"gmw-map-loader-189\" class=\"gmw-map-loader\"><\/div> <div id=\"gmw-map-189\" class=\"gmw-map sl single_location\" style=\"width:100%; height:100%\" data-map_id=\"189\" data-prefix=\"sl\" data-map_type=\"single_location\" data-icons_usage=\"global\"><\/div> <\/div><\/div><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6df1a3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"c6df1a3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-530bfcb elementor-widget elementor-widget-text-editor\" data-id=\"530bfcb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&lt;div style= &#8220;display: none&#8221;&gt;<\/p><p>La Farmacia del Naviglio \u00e8 una realt\u00e0 milanese a pochi passi dal Naviglio, con un vasto assortimento di farmaci, parafarmaci, prodotti omeopatici, fitoterapici, veterinari e cosmetici.<br \/>La nostra squadra di professionisti \u00e8 al tuo servizio: uno staff qualificato \u00e8 pronto ad ascoltarti dispensando consigli e suggerimenti adatti alla scelta del rimedio pi\u00f9 opportuno.<br \/>Il nostro obiettivo quotidiano \u00e8 quello di ricercare la soluzione pi\u00f9 adatta per ogni cliente offrendo nel contempo una serie di servizi dedicati ed esclusivi.<br \/>Nella nostra farmacia troverai sempre un perfetto connubio tra professionalit\u00e0 e gentilezza con personale dedicato alla nutraceutica.<\/p><p>\u00a0<\/p><p><br \/>articoli farmaceutici, Farmaci omeopatici, preparazioni galeniche, Cosmetici , Presidi medico-sanitari per riabilitazione, Presidi medico-sanitari per auto-medicazione, Presidi medico-sanitari per auto-misurazione, apparecchi elettromedicali, prodotti ortopedici, prodotti fitoterapici, Prodotti senza zuccheri aggiunti, Prodotti a basso indice glicemico, Prodotti per diabetici, Farmacia , prodotti veterinari, consulenza nutraceutica, rimedi fitoterapici, parafarmacia,<\/p><p><br \/>Articoli farmaceutici a Milano Navigli, Farmaci omeopatici a Milano Navigli, preparazioni galeniche a Milano Navigli, Cosmetici a Milano Navigli, Presidi medico-sanitari per riabilitazione a Milano Navigli, Presidi medico-sanitari per auto-medicazione a Milano Navigli, Presidi medico-sanitari per auto-misurazione a Milano Navigli, apparecchi elettromedicali a Milano Navigli, prodotti ortopedici a Milano Navigli, prodotti fitoterapici a Milano Navigli, Prodotti senza zuccheri aggiunti a Milano Navigli, Prodotti a basso indice glicemico a Milano Navigli, Prodotti per diabetici a Milano Navigli, Farmacia a Milano Navigli, parafarmaci a Milano Navigli, prodotti veterinari a Milano Navigli, consulenza nutraceutica a Milano Navigli, farmacia vicino al Naviglio Milano, rimedi fitoterapici Milano Ticinese.<br \/>&lt;\/div&gt;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div style=\"display: none;\">\n<p>La Farmacia del Naviglio \u00e8 una realt\u00e0 milanese a pochi passi dal Naviglio, con un vasto assortimento di farmaci, parafarmaci, prodotti omeopatici, fitoterapici, veterinari e cosmetici.<br \/>\nLa nostra squadra di professionisti \u00e8 al tuo servizio: uno staff qualificato \u00e8 pronto ad ascoltarti dispensando consigli e suggerimenti adatti alla scelta del rimedio pi\u00f9 opportuno.<br \/>\nIl nostro obiettivo quotidiano \u00e8 quello di ricercare la soluzione pi\u00f9 adatta per ogni cliente offrendo nel contempo una serie di servizi dedicati ed esclusivi.<br \/>\nNella nostra farmacia troverai sempre un perfetto connubio tra professionalit\u00e0 e gentilezza con personale dedicato alla nutraceutica.<\/p>\n<p>articoli farmaceutici, Farmaci omeopatici, preparazioni galeniche, Cosmetici , Presidi medico-sanitari per riabilitazione, Presidi medico-sanitari per auto-medicazione, Presidi medico-sanitari per auto-misurazione, apparecchi elettromedicali, prodotti ortopedici, prodotti fitoterapici, Prodotti senza zuccheri aggiunti, Prodotti a basso indice glicemico, Prodotti per diabetici, Farmacia , prodotti veterinari, consulenza nutraceutica, rimedi fitoterapici, parafarmacia,<\/p>\n<p>Articoli farmaceutici a Milano Navigli, Farmaci omeopatici a Milano Navigli, preparazioni galeniche a Milano Navigli, Cosmetici a Milano Navigli, Presidi medico-sanitari per riabilitazione a Milano Navigli, Presidi medico-sanitari per auto-medicazione a Milano Navigli, Presidi medico-sanitari per auto-misurazione a Milano Navigli, apparecchi elettromedicali a Milano Navigli, prodotti ortopedici a Milano Navigli, prodotti fitoterapici a Milano Navigli, Prodotti senza zuccheri aggiunti a Milano Navigli, Prodotti a basso indice glicemico a Milano Navigli, Prodotti per diabetici a Milano Navigli, Farmacia a Milano Navigli, parafarmaci a Milano Navigli, prodotti veterinari a Milano Navigli, consulenza nutraceutica a Milano Navigli, farmacia vicino al Naviglio Milano, rimedi fitoterapici Milano Ticinese.<\/p>\n<\/div>\n","protected":false},"featured_media":30261,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[5681,190,26],"product_tag":[5758,7522,7533,373,7523,6605,7534,7524,7526,7527,7525,7530,4511,7528,7531,7529,7532,4515],"class_list":{"0":"post-30260","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-farmacia-online","7":"product_cat-parafarmacie","8":"product_cat-salute","9":"product_tag-apparecchi-elettromedicali","10":"product_tag-articoli-farmaceutici","11":"product_tag-consulenza-nutraceutica","12":"product_tag-cosmetici","13":"product_tag-farmaci-omeopatici","14":"product_tag-farmacia","15":"product_tag-parafarmacia","16":"product_tag-preparazioni-galeniche","17":"product_tag-presidi-medico-sanitari-per-auto-medicazione","18":"product_tag-presidi-medico-sanitari-per-auto-misurazione","19":"product_tag-presidi-medico-sanitari-per-riabilitazione","20":"product_tag-prodotti-a-basso-indice-glicemico","21":"product_tag-prodotti-fitoterapici","22":"product_tag-prodotti-ortopedici","23":"product_tag-prodotti-per-diabetici","24":"product_tag-prodotti-senza-zuccheri-aggiunti","25":"product_tag-prodotti-veterinari","26":"product_tag-rimedi-fitoterapici","28":"first","29":"instock","30":"shipping-taxable","31":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Farmacia del Naviglio - Cral Policlinico di Milano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farmacia del Naviglio - Cral Policlinico di Milano\" \/>\n<meta property=\"og:description\" content=\"La Farmacia del Naviglio \u00e8 una realt\u00e0 milanese a pochi passi dal Naviglio, con un vasto assortimento di farmaci, parafarmaci, prodotti omeopatici, fitoterapici, veterinari e cosmetici. La nostra squadra di professionisti \u00e8 al tuo servizio: uno staff qualificato \u00e8 pronto ad ascoltarti dispensando consigli e suggerimenti adatti alla scelta del rimedio pi\u00f9 opportuno. Il nostro obiettivo quotidiano \u00e8 quello di ricercare la soluzione pi\u00f9 adatta per ogni cliente offrendo nel contempo una serie di servizi dedicati ed esclusivi. Nella nostra farmacia troverai sempre un perfetto connubio tra professionalit\u00e0 e gentilezza con personale dedicato alla nutraceutica.  articoli farmaceutici, Farmaci omeopatici, preparazioni galeniche, Cosmetici , Presidi medico-sanitari per riabilitazione, Presidi medico-sanitari per auto-medicazione, Presidi medico-sanitari per auto-misurazione, apparecchi elettromedicali, prodotti ortopedici, prodotti fitoterapici, Prodotti senza zuccheri aggiunti, Prodotti a basso indice glicemico, Prodotti per diabetici, Farmacia , prodotti veterinari, consulenza nutraceutica, rimedi fitoterapici, parafarmacia,  Articoli farmaceutici a Milano Navigli, Farmaci omeopatici a Milano Navigli, preparazioni galeniche a Milano Navigli, Cosmetici a Milano Navigli, Presidi medico-sanitari per riabilitazione a Milano Navigli, Presidi medico-sanitari per auto-medicazione a Milano Navigli, Presidi medico-sanitari per auto-misurazione a Milano Navigli, apparecchi elettromedicali a Milano Navigli, prodotti ortopedici a Milano Navigli, prodotti fitoterapici a Milano Navigli, Prodotti senza zuccheri aggiunti a Milano Navigli, Prodotti a basso indice glicemico a Milano Navigli, Prodotti per diabetici a Milano Navigli, Farmacia a Milano Navigli, parafarmaci a Milano Navigli, prodotti veterinari a Milano Navigli, consulenza nutraceutica a Milano Navigli, farmacia vicino al Naviglio Milano, rimedi fitoterapici Milano Ticinese.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/\" \/>\n<meta property=\"og:site_name\" content=\"Cral Policlinico di Milano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T13:18:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/\",\"name\":\"Farmacia del Naviglio - Cral Policlinico di Milano\",\"isPartOf\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg\",\"datePublished\":\"2026-03-30T09:45:50+00:00\",\"dateModified\":\"2026-05-26T13:18:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#primaryimage\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg\",\"contentUrl\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Farmacia del Naviglio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website\",\"url\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/\",\"name\":\"Cral Policlinico di Milano\",\"description\":\"Area Convenzioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farmacia del Naviglio - Cral Policlinico di Milano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/","og_locale":"it_IT","og_type":"article","og_title":"Farmacia del Naviglio - Cral Policlinico di Milano","og_description":"La Farmacia del Naviglio \u00e8 una realt\u00e0 milanese a pochi passi dal Naviglio, con un vasto assortimento di farmaci, parafarmaci, prodotti omeopatici, fitoterapici, veterinari e cosmetici. La nostra squadra di professionisti \u00e8 al tuo servizio: uno staff qualificato \u00e8 pronto ad ascoltarti dispensando consigli e suggerimenti adatti alla scelta del rimedio pi\u00f9 opportuno. Il nostro obiettivo quotidiano \u00e8 quello di ricercare la soluzione pi\u00f9 adatta per ogni cliente offrendo nel contempo una serie di servizi dedicati ed esclusivi. Nella nostra farmacia troverai sempre un perfetto connubio tra professionalit\u00e0 e gentilezza con personale dedicato alla nutraceutica.  articoli farmaceutici, Farmaci omeopatici, preparazioni galeniche, Cosmetici , Presidi medico-sanitari per riabilitazione, Presidi medico-sanitari per auto-medicazione, Presidi medico-sanitari per auto-misurazione, apparecchi elettromedicali, prodotti ortopedici, prodotti fitoterapici, Prodotti senza zuccheri aggiunti, Prodotti a basso indice glicemico, Prodotti per diabetici, Farmacia , prodotti veterinari, consulenza nutraceutica, rimedi fitoterapici, parafarmacia,  Articoli farmaceutici a Milano Navigli, Farmaci omeopatici a Milano Navigli, preparazioni galeniche a Milano Navigli, Cosmetici a Milano Navigli, Presidi medico-sanitari per riabilitazione a Milano Navigli, Presidi medico-sanitari per auto-medicazione a Milano Navigli, Presidi medico-sanitari per auto-misurazione a Milano Navigli, apparecchi elettromedicali a Milano Navigli, prodotti ortopedici a Milano Navigli, prodotti fitoterapici a Milano Navigli, Prodotti senza zuccheri aggiunti a Milano Navigli, Prodotti a basso indice glicemico a Milano Navigli, Prodotti per diabetici a Milano Navigli, Farmacia a Milano Navigli, parafarmaci a Milano Navigli, prodotti veterinari a Milano Navigli, consulenza nutraceutica a Milano Navigli, farmacia vicino al Naviglio Milano, rimedi fitoterapici Milano Ticinese.","og_url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/","og_site_name":"Cral Policlinico di Milano","article_modified_time":"2026-05-26T13:18:32+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/","name":"Farmacia del Naviglio - Cral Policlinico di Milano","isPartOf":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#primaryimage"},"image":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#primaryimage"},"thumbnailUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg","datePublished":"2026-03-30T09:45:50+00:00","dateModified":"2026-05-26T13:18:32+00:00","breadcrumb":{"@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#primaryimage","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg","contentUrl":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-content\/uploads\/sites\/30\/2026\/03\/logo_Farmacia-del-Naviglio.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/convenzione\/farmacia-del-naviglio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/negozio\/"},{"@type":"ListItem","position":3,"name":"Farmacia del Naviglio"}]},{"@type":"WebSite","@id":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/#website","url":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/","name":"Cral Policlinico di Milano","description":"Area Convenzioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/30260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/comments?post=30260"}],"version-history":[{"count":31,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/30260\/revisions"}],"predecessor-version":[{"id":34809,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product\/30260\/revisions\/34809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media\/30261"}],"wp:attachment":[{"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/media?parent=30260"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_brand?post=30260"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_cat?post=30260"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/convenzioni.cralnetwork.it\/cralmangiagalli\/wp-json\/wp\/v2\/product_tag?post=30260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}